{"id":387599,"date":"2019-06-14T17:52:55","date_gmt":"2019-06-14T20:52:55","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=387599"},"modified":"2024-11-18T14:22:10","modified_gmt":"2024-11-18T17:22:10","slug":"redacao-pronta-sobre-racismo","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/redacao-pronta-sobre-racismo\/","title":{"rendered":"Reda\u00e7\u00e3o Pronta sobre racismo &#8211; ENEM, Vestibulares e Concursos"},"content":{"rendered":"\n<figure class=\"wp-block-image alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"4000\" height=\"4000\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/06\/17205427\/racismo.jpg\" alt=\"Reda\u00e7\u00e3o pronta sobre racismo\" class=\"wp-image-388914\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/06\/17205427\/racismo.jpg 4000w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/06\/17205427\/racismo.jpg 150w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/06\/17205427\/racismo.jpg 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/06\/17205427\/racismo.jpg 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/06\/17205427\/racismo.jpg 1024w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/06\/17205427\/racismo.jpg 610w\" sizes=\"auto, (max-width: 4000px) 100vw, 4000px\" \/><figcaption class=\"wp-element-caption\">Reda\u00e7\u00e3o pronta sobre racismo &#8211; Enem, vestibulares e concursos<\/figcaption><\/figure>\n\n\n\n<p>Uma d\u00favida comum entre os alunos \u00e9 como desenvolver um tema de reda\u00e7\u00e3o. Pensando nisso, preparamos este artigo com um modelo de texto dissertativo-argumentativo (g\u00eanero cobrado no ENEM). Mais do que isso: aqui voc\u00ea encontrar\u00e1 uma reda\u00e7\u00e3o pronta sobre racismo no Brasil.<\/p>\n\n\n\n<p>A ideia \u00e9 que voc\u00ea consiga compreender os principais aspectos de constru\u00e7\u00e3o de um texto &#8211; como estruturar as ideias, o que deve conter a introdu\u00e7\u00e3o, como escrever o desenvolvimento e como concluir a sua reda\u00e7\u00e3o do ENEM. Ent\u00e3o, vamos l\u00e1?<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-introducao-redacao-pronta-sobre-racismo\"><strong>Introdu\u00e7\u00e3o<\/strong> &#8211; Reda\u00e7\u00e3o Pronta sobre Racismo<\/h2>\n\n\n\n<p>Dizem que a primeira impress\u00e3o \u00e9 a que fica, certo? Claro que isso pode ser um exagero, mas \u00e9 importante ter em mente que a introdu\u00e7\u00e3o de uma reda\u00e7\u00e3o \u00e9 um cart\u00e3o de visitas. \u00c9 por ela que o examinador come\u00e7ar\u00e1 a avaliar o seu texto. <\/p>\n\n\n\n<p>A introdu\u00e7\u00e3o deve apresentar <strong>dois aspectos<\/strong> muito importantes: <\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>A) <\/strong>a sua tese sobre o tema proposto (neste caso, uma tese sobre o racismo no Brasil) e;<\/li>\n\n\n\n<li><strong>B)<\/strong> a apresenta\u00e7\u00e3o da sua l\u00f3gica de argumenta\u00e7\u00e3o, ou seja, quais argumentos voc\u00ea pretende desencadear ao longo do desenvolvimento do texto. <\/li>\n<\/ul>\n\n\n\n<p>Veja um exemplo de introdu\u00e7\u00e3o para a nossa reda\u00e7\u00e3o pronta sobre racismo no Brasil:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p> <em>O racismo \u00e9 uma chaga social no Brasil. Mesmo ap\u00f3s mais de um s\u00e9culo de aboli\u00e7\u00e3o da escravatura, a popula\u00e7\u00e3o negra permanece, na maioria das vezes, \u00e0 margem dos espa\u00e7os de prest\u00edgio. A rela\u00e7\u00e3o de exclus\u00e3o com base na cor da pele est\u00e1 presente nos ambientes de trabalho, nas universidades, nos h\u00e1bitos cotidianos. Compreender como o racismo opera no tecido social e como \u00e9 poss\u00edvel super\u00e1-lo \u00e9, dessa forma, confrontar uma ferida que marca o pa\u00eds.<\/em> <\/p>\n<\/blockquote>\n\n\n\n<p><strong>1.<\/strong> Perceba que, na introdu\u00e7\u00e3o acima, a <strong>tese est\u00e1 presente logo na primeira frase<\/strong>: \u201c<em>O racismo \u00e9 uma chaga social no Brasil<\/em>\u201d. <\/p>\n\n\n\n<p><strong>2.<\/strong> Depois, uma primeira contextualiza\u00e7\u00e3o sobre a tese \u00e9 apresentada: \u201c<em>A rela\u00e7\u00e3o de exclus\u00e3o com base na cor da pele est\u00e1 presente nos ambientes de trabalho, nas universidades, nos h\u00e1bitos cotidianos<\/em>\u201d.<\/p>\n\n\n\n<p><strong>3.<\/strong> A introdu\u00e7\u00e3o \u00e9, ent\u00e3o, finalizada com a <strong><em>apresenta\u00e7\u00e3o da l\u00f3gica de argumenta\u00e7\u00e3o<\/em><\/strong>, encaminhando o leitor para o desenvolvimento do texto: &#8220;<em>Compreender como o racismo opera no tecido social e como \u00e9 poss\u00edvel super\u00e1-lo \u00e9, dessa forma, confrontar uma ferida que marca o pa\u00eds<\/em>&#8220;.<\/p>\n\n\n\n<p><strong>4<\/strong>. Dessa forma, o leitor \u00e9 preparado para um desenvolvimento textual que discorrer\u00e1 sobre \u201c<em>como o racismo opera no tecido social e como \u00e9 poss\u00edvel super\u00e1-lo<\/em>\u201d.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-desenvolvimento-redacao-pronta-sobre-racismo\"><strong>Desenvolvimento<\/strong> &#8211; Reda\u00e7\u00e3o Pronta sobre Racismo<\/h2>\n\n\n\n<p> Agora \u00e9 hora de apresentar o que os organizadores do ENEM chamam de &#8220;<em><strong>estrat\u00e9gias argumentativas<\/strong><\/em>&#8220;. Nos par\u00e1grafos de desenvolvimento (geralmente, dois), devem ser utilizados argumentos para desenvolver a tese inicial, de modo a convencer o leitor. Podem ser utilizados: <\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li> exemplos;<\/li>\n\n\n\n<li> dados estat\u00edsticos; <\/li>\n\n\n\n<li> pesquisas; <\/li>\n\n\n\n<li> fatos comprov\u00e1veis; <\/li>\n\n\n\n<li> cita\u00e7\u00f5es ou depoimentos de pessoas especializadas no assunto; <\/li>\n\n\n\n<li> pequenas narrativas ilustrativas; <\/li>\n\n\n\n<li> alus\u00f5es hist\u00f3ricas;  <\/li>\n\n\n\n<li> compara\u00e7\u00f5es entre fatos, situa\u00e7\u00f5es, \u00e9pocas ou lugares distintos. <\/li>\n<\/ul>\n\n\n\n<p>\n\nVeja o exemplo de dois par\u00e1grafos de desenvolvimento para a nossa reda\u00e7\u00e3o pronta sobre racismo no Brasil:\n\n<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><em>\u00daltima na\u00e7\u00e3o ocidental a conceder liberdade aos escravos, com a Lei \u00c1urea, de 1888, o Brasil buscou construir, desde ent\u00e3o, uma autoimagem de territ\u00f3rio de respeito \u00e0s diferen\u00e7as e de conv\u00edvio racial pac\u00edfico. A Lei \u00c1urea, no entanto, foi conservadora em seu texto e n\u00e3o contou com qualquer ressarcimento ou pol\u00edtica de inclus\u00e3o para popula\u00e7\u00f5es que ficaram tanto tempo afastadas da cidadania, do direito \u00e0 educa\u00e7\u00e3o e da liberdade de ir e vir. O resultado, previs\u00edvel, foi a perpetua\u00e7\u00e3o de uma viol\u00eancia social herdada do passado, mas renovada no presente.<\/em><br \/><br \/><em>Se foi injustific\u00e1vel o descaso a que acabaram relegados milhares de ex-escravizados, foi tamb\u00e9m persistente a luta deles pela liberdade plena. Uma luta que ecoou em seus descendentes e que hoje se traduz em batalha por representatividade e mais espa\u00e7os de poder. Conquista bem conhecida dos brasileiros, a pol\u00edtica de cotas, por exemplo, vem legando uma mudan\u00e7a na fei\u00e7\u00e3o das universidades e das reparti\u00e7\u00f5es p\u00fablicas &#8211; hoje mais heterog\u00eaneas.<\/em><\/p>\n<\/blockquote>\n\n\n\n<p><strong>1.<\/strong> Observe que, no primeiro par\u00e1grafo de desenvolvimento, \u00e9 feita uma <strong>alus\u00e3o hist\u00f3rica \u00e0  Lei \u00c1urea<\/strong>. Isso atende a um requisito importante, exigido pelo ENEM, que \u00e9 a <strong>contextualiza\u00e7\u00e3o<\/strong>. Conforme elencado acima, essa contextualiza\u00e7\u00e3o pode vir de fatos hist\u00f3ricos, dados estat\u00edsticos, cita\u00e7\u00f5es, etc.<\/p>\n\n\n\n<p><strong>2.<\/strong> O desenvolvimento \u00e9 a hora de <strong>explicar o que voc\u00ea falou na introdu\u00e7\u00e3o<\/strong>, s\u00f3 que com detalhes. Ou seja, se na introdu\u00e7\u00e3o houve uma promessa, a hora de cumpri-la \u00e9 no desenvolvimento. O trecho seguinte faz, justamente, a liga\u00e7\u00e3o do passado com o momento atual, corroborando a tese apresentada l\u00e1 no in\u00edcio da introdu\u00e7\u00e3o (de que o racismo \u00e9 uma chaga social ainda presente no Brasil). Veja: &#8220;<em>A Lei \u00c1urea (\u2026) n\u00e3o contou com qualquer ressarcimento ou pol\u00edtica de inclus\u00e3o para popula\u00e7\u00f5es que ficaram tanto tempo afastadas da cidadania (\u2026). O resultado, previs\u00edvel, foi a perpetua\u00e7\u00e3o de uma viol\u00eancia social herdada do passado, mas renovada no presente&#8221;<\/em>.<\/p>\n\n\n\n<p><strong>3.<\/strong> Um dos pontos valorizados pelos examinadores do ENEM no desenvolvimento da reda\u00e7\u00e3o \u00e9 a <strong><em>capacidade de o candidato estabelecer paralelos e contrapontos<\/em><\/strong>. Observe que, ao final do desenvolvimento, o texto reconhece avan\u00e7os no combate ao racismo, trazendo uma vis\u00e3o de mundo atenta aos fatos atuais: &#8220;<em>Conquista bem conhecida dos brasileiros, a pol\u00edtica de cotas, por exemplo, vem legando uma mudan\u00e7a na fei\u00e7\u00e3o das universidades e reparti\u00e7\u00f5es p\u00fablicas &#8211; hoje mais heterog\u00eaneas<\/em>&#8220;.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-conclusao-redacao-pronta-sobre-racismo\"><strong>Conclus\u00e3o<\/strong> &#8211; Reda\u00e7\u00e3o pronta sobre racismo<\/h2>\n\n\n\n<p> Antes de detalharmos como concluir o texto, leia este <strong><em>exemplo de conclus\u00e3o<\/em><\/strong> para a nossa reda\u00e7\u00e3o pronta sobre racismo no Brasil: <\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p> <em>Os avan\u00e7os na pol\u00edtica de inclus\u00e3o racial no Brasil, entretanto, ainda continuam pontuais e resultam de press\u00f5es da sociedade organizada. O pa\u00eds permanece sem uma pol\u00edtica de Estado coordenada, ampla, que ultrapasse governos e esteja presente em diferentes pastas, como o Minist\u00e9rio da Justi\u00e7a &#8211; com pol\u00edticas mais precisas de ressocializa\u00e7\u00e3o da popula\u00e7\u00e3o carcer\u00e1ria, em sua maioria negra &#8211; e o Minist\u00e9rio da Educa\u00e7\u00e3o &#8211; com a\u00e7\u00f5es sistem\u00e1ticas de conscientiza\u00e7\u00e3o em eventos e materiais did\u00e1ticos. S\u00f3 assim, ultrapassando a\u00e7\u00f5es pontuais, ser\u00e1 poss\u00edvel minimizar de forma mais efetiva o abismo racial que ainda assola o pa\u00eds.<\/em><\/p>\n<\/blockquote>\n\n\n\n<p>O aspecto mais relevante na conclus\u00e3o de uma reda\u00e7\u00e3o para o ENEM \u00e9 a <strong><em>proposta de interven\u00e7\u00e3o<\/em><\/strong> para o problema abordado. Ou seja, a sua reda\u00e7\u00e3o deve, ao fim, apresentar uma solu\u00e7\u00e3o, uma forma de resolver a quest\u00e3o abordada. <\/p>\n\n\n\n<p>A proposta de interven\u00e7\u00e3o deve <strong><em>refletir os conhecimentos de mundo de quem a redige<\/em><\/strong> e, quando bem elaborada, deve conter n\u00e3o apenas a exposi\u00e7\u00e3o da a\u00e7\u00e3o interventiva sugerida, mas tamb\u00e9m o ator social competente para execut\u00e1-la. Al\u00e9m disso, a proposta de interven\u00e7\u00e3o deve conter o meio de execu\u00e7\u00e3o da a\u00e7\u00e3o e o seu poss\u00edvel efeito.<\/p>\n\n\n\n<p>Perceba que, no exemplo de conclus\u00e3o acima, os requisitos avaliados pelo ENEM s\u00e3o atendidos. A a\u00e7\u00e3o interventiva \u00e9 &#8220;<em>uma pol\u00edtica de Estado coordenada, ampla, que ultrapasse governos<\/em>&#8220;, os atores sociais competentes s\u00e3o as &#8220;<em>diferentes pastas governamentais, como o Minist\u00e9rio da Justi\u00e7a (\u2026) e o Minist\u00e9rio da Educa\u00e7\u00e3o<\/em>&#8221; e o poss\u00edvel efeito \u00e9 a minimiza\u00e7\u00e3o, &#8220;<em>de forma mais efetiva<\/em>&#8221; do &#8220;<em>abismo racial que ainda assola o pa\u00eds<\/em>&#8220;.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-redacao-pronta-sobre-racismo-texto-completo\"><strong>Reda\u00e7\u00e3o pronta sobre racismo: Texto completo<\/strong><\/h2>\n\n\n\n<p>Agora, confira a \u00edntegra da nossa reda\u00e7\u00e3o pronta sobre racismo no Brasil. Trata-se de um exemplo, de uma inspira\u00e7\u00e3o para voc\u00ea construir o seu pr\u00f3prio texto. <a rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/como-estudar-redacao-para-o-enem\/\" target=\"_blank\">Como sempre falamos aqui no Estrat\u00e9gia<\/a>: aprender reda\u00e7\u00e3o \u00e9, sobretudo, praticar!<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p> <em>O racismo \u00e9 uma chaga social no Brasil. Mesmo ap\u00f3s mais de um s\u00e9culo de aboli\u00e7\u00e3o da escravatura, a popula\u00e7\u00e3o negra permanece, na maioria das vezes, \u00e0 margem dos espa\u00e7os de prest\u00edgio. A rela\u00e7\u00e3o de exclus\u00e3o com base na cor da pele est\u00e1 presente nos ambientes de trabalho, nas universidades, nos h\u00e1bitos cotidianos. Compreender como o racismo opera no tecido social e como \u00e9 poss\u00edvel super\u00e1-lo \u00e9, dessa forma, confrontar uma ferida que marca o pa\u00eds.<\/em><br \/><br \/><em>\u00daltima na\u00e7\u00e3o ocidental a conceder liberdade aos escravos, com a Lei \u00c1urea, de 1888, o Brasil buscou construir, desde ent\u00e3o, uma autoimagem de territ\u00f3rio de respeito \u00e0s diferen\u00e7as e de conv\u00edvio racial pac\u00edfico. A Lei \u00c1urea, no entanto, foi conservadora em seu texto e n\u00e3o contou com qualquer ressarcimento ou pol\u00edtica de inclus\u00e3o para popula\u00e7\u00f5es que ficaram tanto tempo afastadas da cidadania, do direito ao letramento e da liberdade de ir e vir. O resultado, previs\u00edvel, foi a perpetua\u00e7\u00e3o de uma viol\u00eancia social herdada do passado, mas renovada no presente.<\/em><br \/><br \/><em>Se foi injustific\u00e1vel o descaso a que acabaram relegados milhares de ex-escravizados, foi tamb\u00e9m persistente a luta deles pela liberdade plena. Uma luta que ecoou em seus descendentes e que hoje se traduz em batalha por representatividade e mais espa\u00e7os de poder. Conquista bem conhecida dos brasileiros, a pol\u00edtica de cotas, por exemplo, vem legando uma mudan\u00e7a na fei\u00e7\u00e3o das universidades e das reparti\u00e7\u00f5es p\u00fablicas &#8211; hoje mais heterog\u00eaneas.<\/em><br \/><br \/><em>Os avan\u00e7os na pol\u00edtica de inclus\u00e3o racial no Brasil, entretanto, ainda continuam pontuais e resultam de press\u00f5es da sociedade organizada. O pa\u00eds permanece sem uma pol\u00edtica de Estado coordenada, ampla, que ultrapasse governos e esteja presente em diferentes pastas, como o Minist\u00e9rio da Justi\u00e7a &#8211; com pol\u00edticas mais precisas de ressocializa\u00e7\u00e3o da popula\u00e7\u00e3o carcer\u00e1ria, em sua maioria negra &#8211; e o Minist\u00e9rio da Educa\u00e7\u00e3o &#8211; com a\u00e7\u00f5es sistem\u00e1ticas de conscientiza\u00e7\u00e3o em eventos e materiais did\u00e1ticos. S\u00f3 assim, ultrapassando a\u00e7\u00f5es pontuais, ser\u00e1 poss\u00edvel minimizar de forma mais efetiva o abismo racial que ainda assola o pa\u00eds.<\/em><\/p>\n<\/blockquote>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size\"><em><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/como-estudar-para-o-enem\/\">Como estudar para o ENEM<\/a><\/em><\/p>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size\"><em><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/redacao-nota-1000\/\">Reda\u00e7\u00e3o Nota 1000<\/a><\/em><\/p>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size\"><em><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/como-estudar-redacao-para-o-enem\/\">Como estudar Reda\u00e7\u00e3o para o ENEM<\/a><\/em><\/p>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/nota-do-enem-saiba-como-e-calculada-e-melhore-a-sua-pontuacao-na-prova\/\"><em>Como calcular a Nota do ENEM<\/em><\/a><\/p>\n\n\n\n<p>Confira a lista de <a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2025\/\" target=\"_blank\" rel=\"noreferrer noopener\">concursos 2025<\/a>: Veja os principais <a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" target=\"_blank\" rel=\"noreferrer noopener\">concursos abertos<\/a> com altos sal\u00e1rios que oferecem oportunidades para todos os n\u00edveis de escolaridade!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uma d\u00favida comum entre os alunos \u00e9 como desenvolver um tema de reda\u00e7\u00e3o. Pensando nisso, preparamos este artigo com um modelo de texto dissertativo-argumentativo (g\u00eanero cobrado no ENEM). Mais do que isso: aqui voc\u00ea encontrar\u00e1 uma reda\u00e7\u00e3o pronta sobre racismo no Brasil. A ideia \u00e9 que voc\u00ea consiga compreender os principais aspectos de constru\u00e7\u00e3o de [&hellip;]<\/p>\n","protected":false},"author":263,"featured_media":388914,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1],"tags":[87271],"tax_estado":[],"class_list":["post-387599","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cursos-e-concursos","tag-redacao-pronta-sobre-racismo"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Reda\u00e7\u00e3o Pronta sobre racismo - ENEM, Vestibulares e Concursos<\/title>\n<meta name=\"description\" content=\"J\u00e1 teve d\u00favidas sobre como desenvolver um tema de reda\u00e7\u00e3o para o ENEM? Aqui voc\u00ea encontrar\u00e1 uma reda\u00e7\u00e3o pronta sobre racismo no Brasil.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/redacao-pronta-sobre-racismo\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Reda\u00e7\u00e3o Pronta sobre racismo - ENEM, Vestibulares e Concursos\" \/>\n<meta property=\"og:description\" content=\"J\u00e1 teve d\u00favidas sobre como desenvolver um tema de reda\u00e7\u00e3o para o ENEM? Aqui voc\u00ea encontrar\u00e1 uma reda\u00e7\u00e3o pronta sobre racismo no Brasil.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/redacao-pronta-sobre-racismo\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2019-06-14T20:52:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-18T17:22:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/06\/17205427\/racismo-1024x1024.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Daniel dos Reis Lopes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Daniel dos Reis Lopes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/redacao-pronta-sobre-racismo\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/redacao-pronta-sobre-racismo\/\"},\"author\":{\"name\":\"Daniel dos Reis Lopes\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/86e4af37234d422e94ca7e825b416814\"},\"headline\":\"Reda\u00e7\u00e3o Pronta sobre racismo &#8211; ENEM, Vestibulares e Concursos\",\"datePublished\":\"2019-06-14T20:52:55+00:00\",\"dateModified\":\"2024-11-18T17:22:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/redacao-pronta-sobre-racismo\/\"},\"wordCount\":1767,\"commentCount\":11,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/redacao-pronta-sobre-racismo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/06\/17205427\/racismo.jpg\",\"keywords\":[\"reda\u00e7\u00e3o pronta sobre racismo\"],\"articleSection\":[\"Concursos P\u00fablicos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/redacao-pronta-sobre-racismo\/#respond\"]}],\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/redacao-pronta-sobre-racismo\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/redacao-pronta-sobre-racismo\/\",\"name\":\"Reda\u00e7\u00e3o Pronta sobre racismo - ENEM, Vestibulares e Concursos\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/redacao-pronta-sobre-racismo\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/redacao-pronta-sobre-racismo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/06\/17205427\/racismo.jpg\",\"datePublished\":\"2019-06-14T20:52:55+00:00\",\"dateModified\":\"2024-11-18T17:22:10+00:00\",\"description\":\"J\u00e1 teve d\u00favidas sobre como desenvolver um tema de reda\u00e7\u00e3o para o ENEM? Aqui voc\u00ea encontrar\u00e1 uma reda\u00e7\u00e3o pronta sobre racismo no Brasil.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/redacao-pronta-sobre-racismo\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/redacao-pronta-sobre-racismo\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/redacao-pronta-sobre-racismo\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/06\/17205427\/racismo.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/06\/17205427\/racismo.jpg\",\"width\":4000,\"height\":4000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/redacao-pronta-sobre-racismo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Reda\u00e7\u00e3o Pronta sobre racismo &#8211; ENEM, Vestibulares e Concursos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/86e4af37234d422e94ca7e825b416814\",\"name\":\"Daniel dos Reis Lopes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/ea24ef981da4044d0a66f44402441129fdde22c4c8d87f39a45cae8d4f82075a?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ea24ef981da4044d0a66f44402441129fdde22c4c8d87f39a45cae8d4f82075a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ea24ef981da4044d0a66f44402441129fdde22c4c8d87f39a45cae8d4f82075a?s=96&d=mm&r=g\",\"caption\":\"Daniel dos Reis Lopes\"},\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/d-reislopesgmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Reda\u00e7\u00e3o Pronta sobre racismo - ENEM, Vestibulares e Concursos","description":"J\u00e1 teve d\u00favidas sobre como desenvolver um tema de reda\u00e7\u00e3o para o ENEM? Aqui voc\u00ea encontrar\u00e1 uma reda\u00e7\u00e3o pronta sobre racismo no Brasil.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/redacao-pronta-sobre-racismo\/","og_locale":"pt_BR","og_type":"article","og_title":"Reda\u00e7\u00e3o Pronta sobre racismo - ENEM, Vestibulares e Concursos","og_description":"J\u00e1 teve d\u00favidas sobre como desenvolver um tema de reda\u00e7\u00e3o para o ENEM? Aqui voc\u00ea encontrar\u00e1 uma reda\u00e7\u00e3o pronta sobre racismo no Brasil.","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/redacao-pronta-sobre-racismo\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2019-06-14T20:52:55+00:00","article_modified_time":"2024-11-18T17:22:10+00:00","og_image":[{"width":1024,"height":1024,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/06\/17205427\/racismo-1024x1024.jpg","type":"image\/jpeg"}],"author":"Daniel dos Reis Lopes","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Daniel dos Reis Lopes","Est. tempo de leitura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/redacao-pronta-sobre-racismo\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/redacao-pronta-sobre-racismo\/"},"author":{"name":"Daniel dos Reis Lopes","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/86e4af37234d422e94ca7e825b416814"},"headline":"Reda\u00e7\u00e3o Pronta sobre racismo &#8211; ENEM, Vestibulares e Concursos","datePublished":"2019-06-14T20:52:55+00:00","dateModified":"2024-11-18T17:22:10+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/redacao-pronta-sobre-racismo\/"},"wordCount":1767,"commentCount":11,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/redacao-pronta-sobre-racismo\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/06\/17205427\/racismo.jpg","keywords":["reda\u00e7\u00e3o pronta sobre racismo"],"articleSection":["Concursos P\u00fablicos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/redacao-pronta-sobre-racismo\/#respond"]}],"copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/redacao-pronta-sobre-racismo\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/redacao-pronta-sobre-racismo\/","name":"Reda\u00e7\u00e3o Pronta sobre racismo - ENEM, Vestibulares e Concursos","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/redacao-pronta-sobre-racismo\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/redacao-pronta-sobre-racismo\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/06\/17205427\/racismo.jpg","datePublished":"2019-06-14T20:52:55+00:00","dateModified":"2024-11-18T17:22:10+00:00","description":"J\u00e1 teve d\u00favidas sobre como desenvolver um tema de reda\u00e7\u00e3o para o ENEM? Aqui voc\u00ea encontrar\u00e1 uma reda\u00e7\u00e3o pronta sobre racismo no Brasil.","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/redacao-pronta-sobre-racismo\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/redacao-pronta-sobre-racismo\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/redacao-pronta-sobre-racismo\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/06\/17205427\/racismo.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/06\/17205427\/racismo.jpg","width":4000,"height":4000},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/redacao-pronta-sobre-racismo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Reda\u00e7\u00e3o Pronta sobre racismo &#8211; ENEM, Vestibulares e Concursos"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/86e4af37234d422e94ca7e825b416814","name":"Daniel dos Reis Lopes","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/ea24ef981da4044d0a66f44402441129fdde22c4c8d87f39a45cae8d4f82075a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ea24ef981da4044d0a66f44402441129fdde22c4c8d87f39a45cae8d4f82075a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ea24ef981da4044d0a66f44402441129fdde22c4c8d87f39a45cae8d4f82075a?s=96&d=mm&r=g","caption":"Daniel dos Reis Lopes"},"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/d-reislopesgmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/387599","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/263"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=387599"}],"version-history":[{"count":21,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/387599\/revisions"}],"predecessor-version":[{"id":1491303,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/387599\/revisions\/1491303"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/388914"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=387599"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=387599"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=387599"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=387599"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}