{"id":38056,"date":"2016-04-30T11:31:40","date_gmt":"2016-04-30T14:31:40","guid":{"rendered":"http:\/\/www.estrategiaconcursos.com.br\/blog\/?p=38056"},"modified":"2022-09-05T16:33:03","modified_gmt":"2022-09-05T19:33:03","slug":"jurisprudencia-voce-realmente-sabe-o-que-e","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/jurisprudencia-voce-realmente-sabe-o-que-e\/","title":{"rendered":"Jurisprud\u00eancia: voc\u00ea REALMENTE sabe o que \u00e9?"},"content":{"rendered":"<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-38059 size-medium\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/04\/30111547\/jurisprudencia.jpg\" alt=\"jurisprudencia\" width=\"300\" height=\"236\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/04\/30111547\/jurisprudencia.jpg 382w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/04\/30111547\/jurisprudencia.jpg 300w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Meu nome \u00e9 Fabr\u00edcio R\u00eago, sou professor do Estrat\u00e9gia Concursos e coautor do livro <strong><em>Lei do Processo Administrativo Federal Esquematizada<\/em><\/strong>, publicado pelo Grupo GEN\/ Editora M\u00e9todo.<\/p>\n<p style=\"text-align: justify;\">Venho falar de um assunto trivial: <strong>jurisprud\u00eancia<\/strong>. O objetivo \u00e9 simples: falar do <strong>conceito de jurisprud\u00eancia<\/strong>. <em>Mas professor, isso \u00e9 f\u00e1cil demais, tiro de letra!<\/em> Ser\u00e1 mesmo?! Infelizmente essa \u00e9 uma realidade que percebo hoje, inclusive entre experientes operadores do direito: a confus\u00e3o na hora de dizer que a \u201cjurisprud\u00eancia\u201d de um tribunal \u00e9 essa ou aquela.<\/p>\n<p style=\"text-align: justify;\">Quando trabalhei no STF como analista da \u00e1rea judici\u00e1ria, analisava processos. Acredite: n\u00e3o \u00e9 incomum encontrar operadores do direito se equivocando na terminologia. Ok, na vida pr\u00e1tica do profissional talvez esse equ\u00edvoco n\u00e3o tenha relev\u00e2ncia, \u00e9 s\u00f3 uma imperfei\u00e7\u00e3o, mas certamente se voc\u00ea estiver numa <strong>2\u00aa FASE DA OAB, numa DISCURSIVA ou at\u00e9 mesmo numa PROVA ORAL<\/strong>, esse deslize poder\u00e1 demonstrar uma imprecis\u00e3o t\u00e9cnica na terminologia utilizada.<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ff0000;\"><strong>AFINAL, PROFESSOR, O QUE \u00c9 ENT\u00c3O JURISPRUD\u00caNCIA?<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\">Vamos beber na fonte e tomar como base o que nos ensina o saudoso jurista Miguel Reale em seu cl\u00e1ssico Li\u00e7\u00f5es Preliminares de Direito:<\/p>\n<p style=\"text-align: justify; padding-left: 60px;\"><em>Pela palavra \u201cjurisprud\u00eancia\u201d (stricto sensu), devemos entender a forma de revela\u00e7\u00e3o do direito que se processa atrav\u00e9s do exerc\u00edcio da jurisdi\u00e7\u00e3o, em virtude de uma <strong><u>sucess\u00e3o harm\u00f4nica de decis\u00f5es dos tribunais<\/u><\/strong>.<\/em><\/p>\n<p style=\"text-align: justify; padding-left: 60px;\"><em>[&#8230;] o Direito jurisprudencial n\u00e3o se forma atrav\u00e9s <strong><u>de uma ou tr\u00eas senten\u00e7as<\/u><\/strong>, <strong>MAS EXIGE UMA S\u00c9RIE DE JULGADOS <\/strong>que guardem<strong>,<\/strong> entre si, uma linha essencial de continuidade e coer\u00eancia. Para que se possa falar em jurisprud\u00eancia de um Tribunal, \u00e9 necess\u00e1rio certo n\u00famero de decis\u00f5es que coincidam quanto \u00e0 subst\u00e2ncia das quest\u00f5es objeto de seu pronunciamento.<\/em><\/p>\n<p style=\"text-align: justify;\">Voc\u00ea j\u00e1 pegou o ponto onde quero chegar, n\u00e3o \u00e9? Gente, jurisprud\u00eancia n\u00e3o \u00e9 um julgado isolado de um tribunal, tampouco dois ou tr\u00eas, mas sim uma sucess\u00e3o de julgados, v\u00e1rios! Pode parecer simples conceitualmente, algo batido, mas infelizmente n\u00e3o \u00e9.<\/p>\n<p style=\"text-align: justify;\">\u00c9 comum o operador do direito ver uma decis\u00e3o de um tribunal e escrever, seja no seu artigo, seja na sua pe\u00e7a processual, que se trata de uma jurisprud\u00eancia. N\u00e3o \u00e9, pessoal!<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ff0000;\"><strong>T\u00c1, PROFESSOR, MAS COMO EU VOU SABER SE \u00c9 UMA JURISPRUD\u00caNCIA?<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\">Aqui nosso <strong>foco \u00e9 provas<\/strong>, n\u00e3o a pr\u00e1tica. Neste \u00faltimo caso, s\u00f3 te restaria pesquisar em livros ou nos sites dos pr\u00f3prios tribunais. Mas, enquanto estudante e se preparando para provas de concursos, n\u00e3o h\u00e1 tempo h\u00e1bil para isso, n\u00e3o \u00e9? Portanto, essa \u00e9 a tarefa do professor ou do livro que esteja utilizando, e voc\u00ea precisa confiar nele.<\/p>\n<p style=\"text-align: justify;\">Assim, se o professor fala que aquela \u00e9 a jurisprud\u00eancia ou jurisprud\u00eancia dominante do tribunal X, ele j\u00e1 sabe que \u00e9 de fato uma jurisprud\u00eancia.<\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"color: #008000;\">Conhe\u00e7a nosso curso de Regimento Interno do STF =&gt;<\/span>\u00a0<a href=\"https:\/\/www.estrategiaconcursos.com.br\/curso\/regimento-interno-p-stf-analista-judiciario-area-judiciaria\/\" target=\"_blank\" rel=\"noopener\">CLIQUE AQUI<\/a><\/strong><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ff0000;\"><strong>E QUANDO N\u00c3O FOR JURISPRUD\u00caNCIA, N\u00c3O POSSO UTILIZAR?<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\">Claro que pode. Caso seja um julgado \u00fanico ou julgados ainda divergentes entre \u00f3rg\u00e3os do tribunal (entre turmas, por exemplo), \u00e9 seguro falar em <strong>precedente ou julgado<\/strong> da turma X ou do tribunal Y.<\/p>\n<p style=\"text-align: justify;\">Em todo caso, por via das d\u00favidas, mesmo sendo jurisprud\u00eancia, utilizar o termo gen\u00e9rico \u201cjulgado\u201d nunca estar\u00e1 errado, assim como precedente. \u00c9 claro que se for mesmo uma jurisprud\u00eancia e voc\u00ea souber disso, utilizar esse termo demonstrar\u00e1 ao examinador que voc\u00ea conhece do assunto e tamb\u00e9m a forma com que julga o tribunal.<\/p>\n<p style=\"text-align: justify;\"><strong>Outro ponto de extrema import\u00e2ncia \u00e9 a proced\u00eancia do julgado<\/strong>. Um tribunal \u00e9 dividido em turmas, se\u00e7\u00f5es, c\u00e2maras, enfim, a depender de cada regimento. O STF, por exemplo, se divide em duas turmas: a Primeira e a Segunda Turma, cada uma com cinco ministros, j\u00e1 que o Presidente do STF n\u00e3o comp\u00f5e turmas.<\/p>\n<div id=\"attachment_38057\" style=\"width: 610px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-38057\" class=\"wp-image-38057 size-full\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/04\/30111538\/jurisprudencia-2.jpg\" alt=\"jurisprudencia \" width=\"600\" height=\"276\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/04\/30111538\/jurisprudencia-2.jpg 600w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/04\/30111538\/jurisprudencia-2.jpg 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/04\/30111538\/jurisprudencia-2.jpg 500w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><p id=\"caption-attachment-38057\" class=\"wp-caption-text\">Plen\u00e1rio do STF<\/p><\/div>\n<p style=\"text-align: justify;\">Pois bem, \u00e9 preciso ter muito cuidado ao dizer que o julgado de uma turma, que n\u00e3o \u00e9 ainda uma jurisprud\u00eancia, representa a posi\u00e7\u00e3o do STF. N\u00e3o! Representa a posi\u00e7\u00e3o de uma turma do STF, mas n\u00e3o do STF. Falar em posi\u00e7\u00e3o do STF somente\u00a0quando o julgamento for semelhante em ambas as turmas ou, <strong>mais preciso ainda<\/strong>, quando for julgamento do Plen\u00e1rio do STF!<\/p>\n<div id=\"attachment_38058\" style=\"width: 594px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-38058\" class=\"wp-image-38058 size-large\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/04\/30111545\/jurisprudencia-3.jpg\" alt=\"jurisprudencia \" width=\"584\" height=\"339\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/04\/30111545\/jurisprudencia-3.jpg 1500w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/04\/30111545\/jurisprudencia-3.jpg 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/04\/30111545\/jurisprudencia-3.jpg 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/04\/30111545\/jurisprudencia-3.jpg 1024w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/04\/30111545\/jurisprudencia-3.jpg 500w\" sizes=\"auto, (max-width: 584px) 100vw, 584px\" \/><p id=\"caption-attachment-38058\" class=\"wp-caption-text\">Segunda Turma do STF<\/p><\/div>\n<p style=\"text-align: justify;\">Seria uma imprecis\u00e3o se referir a julgado da Segunda Turma e dizer que \u201c<em>a posi\u00e7\u00e3o do STF em julgado recente foi xxxx<\/em>\u201d. No entanto, j\u00e1 n\u00e3o estaria errado se voc\u00ea falasse o seguinte: \u201c<em>O STF, atrav\u00e9s da Segunda Turma, se manifestou no sentido de xxxx<\/em>\u201d.<\/p>\n<p style=\"text-align: justify;\">Veja que s\u00e3o itens e conceitos triviais que as vezes passam batido, mas em tempos de concursos concorrid\u00edssimos, n\u00e3o vacile com eles!!!<\/p>\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>Meu nome \u00e9 Fabr\u00edcio R\u00eago, sou professor do Estrat\u00e9gia Concursos e coautor do livro Lei do Processo Administrativo Federal Esquematizada, publicado pelo Grupo GEN\/ Editora M\u00e9todo. Venho falar de um assunto trivial: jurisprud\u00eancia. O objetivo \u00e9 simples: falar do conceito de jurisprud\u00eancia. Mas professor, isso \u00e9 f\u00e1cil demais, tiro de letra! Ser\u00e1 mesmo?! Infelizmente essa [&hellip;]<\/p>\n","protected":false},"author":48,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1],"tags":[],"tax_estado":[],"class_list":["post-38056","post","type-post","status-publish","format-standard","hentry","category-cursos-e-concursos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Jurisprud\u00eancia: voc\u00ea REALMENTE sabe o que \u00e9?<\/title>\n<meta name=\"description\" content=\"Venho falar de um assunto trivial: jurisprud\u00eancia. Infelizmente essa \u00e9 uma realidade que percebo: a confus\u00e3o na hora de dizer o \u00e9 que a \u201cjurisprud\u00eancia\u201d.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/jurisprudencia-voce-realmente-sabe-o-que-e\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jurisprud\u00eancia: voc\u00ea REALMENTE sabe o que \u00e9?\" \/>\n<meta property=\"og:description\" content=\"Venho falar de um assunto trivial: jurisprud\u00eancia. Infelizmente essa \u00e9 uma realidade que percebo: a confus\u00e3o na hora de dizer o \u00e9 que a \u201cjurisprud\u00eancia\u201d.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/jurisprudencia-voce-realmente-sabe-o-que-e\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2016-04-30T14:31:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-05T19:33:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2016\/04\/jurisprudencia-300x236.jpg\" \/>\n<meta name=\"author\" content=\"Coordena\u00e7\u00e3o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Coordena\u00e7\u00e3o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/jurisprudencia-voce-realmente-sabe-o-que-e\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/jurisprudencia-voce-realmente-sabe-o-que-e\/\"},\"author\":{\"name\":\"Coordena\u00e7\u00e3o\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/cdad40b5818eb228a838461fcd656da7\"},\"headline\":\"Jurisprud\u00eancia: voc\u00ea REALMENTE sabe o que \u00e9?\",\"datePublished\":\"2016-04-30T14:31:40+00:00\",\"dateModified\":\"2022-09-05T19:33:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/jurisprudencia-voce-realmente-sabe-o-que-e\/\"},\"wordCount\":822,\"commentCount\":6,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/jurisprudencia-voce-realmente-sabe-o-que-e\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2016\/04\/jurisprudencia-300x236.jpg\",\"articleSection\":[\"Concursos P\u00fablicos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/jurisprudencia-voce-realmente-sabe-o-que-e\/#respond\"]}],\"copyrightYear\":\"2016\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/jurisprudencia-voce-realmente-sabe-o-que-e\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/jurisprudencia-voce-realmente-sabe-o-que-e\/\",\"name\":\"Jurisprud\u00eancia: voc\u00ea REALMENTE sabe o que \u00e9?\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/jurisprudencia-voce-realmente-sabe-o-que-e\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/jurisprudencia-voce-realmente-sabe-o-que-e\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2016\/04\/jurisprudencia-300x236.jpg\",\"datePublished\":\"2016-04-30T14:31:40+00:00\",\"dateModified\":\"2022-09-05T19:33:03+00:00\",\"description\":\"Venho falar de um assunto trivial: jurisprud\u00eancia. Infelizmente essa \u00e9 uma realidade que percebo: a confus\u00e3o na hora de dizer o \u00e9 que a \u201cjurisprud\u00eancia\u201d.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/jurisprudencia-voce-realmente-sabe-o-que-e\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/jurisprudencia-voce-realmente-sabe-o-que-e\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/jurisprudencia-voce-realmente-sabe-o-que-e\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/04\/30111547\/jurisprudencia.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/04\/30111547\/jurisprudencia.jpg\",\"width\":382,\"height\":300,\"caption\":\"Jurisprudencia ICMS na base de c\u00e1lculo do PIS\/Cofins\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/jurisprudencia-voce-realmente-sabe-o-que-e\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jurisprud\u00eancia: voc\u00ea REALMENTE sabe o que \u00e9?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/cdad40b5818eb228a838461fcd656da7\",\"name\":\"Coordena\u00e7\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/a413b22da0f5009c634f6c4586a2dbe5207074fd5becd88db5183b8069ef25e4?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a413b22da0f5009c634f6c4586a2dbe5207074fd5becd88db5183b8069ef25e4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a413b22da0f5009c634f6c4586a2dbe5207074fd5becd88db5183b8069ef25e4?s=96&d=mm&r=g\",\"caption\":\"Coordena\u00e7\u00e3o\"},\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/contatoestrategiaconcursos-com-br\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Jurisprud\u00eancia: voc\u00ea REALMENTE sabe o que \u00e9?","description":"Venho falar de um assunto trivial: jurisprud\u00eancia. Infelizmente essa \u00e9 uma realidade que percebo: a confus\u00e3o na hora de dizer o \u00e9 que a \u201cjurisprud\u00eancia\u201d.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/jurisprudencia-voce-realmente-sabe-o-que-e\/","og_locale":"pt_BR","og_type":"article","og_title":"Jurisprud\u00eancia: voc\u00ea REALMENTE sabe o que \u00e9?","og_description":"Venho falar de um assunto trivial: jurisprud\u00eancia. Infelizmente essa \u00e9 uma realidade que percebo: a confus\u00e3o na hora de dizer o \u00e9 que a \u201cjurisprud\u00eancia\u201d.","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/jurisprudencia-voce-realmente-sabe-o-que-e\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2016-04-30T14:31:40+00:00","article_modified_time":"2022-09-05T19:33:03+00:00","og_image":[{"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2016\/04\/jurisprudencia-300x236.jpg","type":"","width":"","height":""}],"author":"Coordena\u00e7\u00e3o","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Coordena\u00e7\u00e3o","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/jurisprudencia-voce-realmente-sabe-o-que-e\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/jurisprudencia-voce-realmente-sabe-o-que-e\/"},"author":{"name":"Coordena\u00e7\u00e3o","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/cdad40b5818eb228a838461fcd656da7"},"headline":"Jurisprud\u00eancia: voc\u00ea REALMENTE sabe o que \u00e9?","datePublished":"2016-04-30T14:31:40+00:00","dateModified":"2022-09-05T19:33:03+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/jurisprudencia-voce-realmente-sabe-o-que-e\/"},"wordCount":822,"commentCount":6,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/jurisprudencia-voce-realmente-sabe-o-que-e\/#primaryimage"},"thumbnailUrl":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2016\/04\/jurisprudencia-300x236.jpg","articleSection":["Concursos P\u00fablicos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/jurisprudencia-voce-realmente-sabe-o-que-e\/#respond"]}],"copyrightYear":"2016","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/jurisprudencia-voce-realmente-sabe-o-que-e\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/jurisprudencia-voce-realmente-sabe-o-que-e\/","name":"Jurisprud\u00eancia: voc\u00ea REALMENTE sabe o que \u00e9?","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/jurisprudencia-voce-realmente-sabe-o-que-e\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/jurisprudencia-voce-realmente-sabe-o-que-e\/#primaryimage"},"thumbnailUrl":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2016\/04\/jurisprudencia-300x236.jpg","datePublished":"2016-04-30T14:31:40+00:00","dateModified":"2022-09-05T19:33:03+00:00","description":"Venho falar de um assunto trivial: jurisprud\u00eancia. Infelizmente essa \u00e9 uma realidade que percebo: a confus\u00e3o na hora de dizer o \u00e9 que a \u201cjurisprud\u00eancia\u201d.","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/jurisprudencia-voce-realmente-sabe-o-que-e\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/jurisprudencia-voce-realmente-sabe-o-que-e\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/jurisprudencia-voce-realmente-sabe-o-que-e\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/04\/30111547\/jurisprudencia.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/04\/30111547\/jurisprudencia.jpg","width":382,"height":300,"caption":"Jurisprudencia ICMS na base de c\u00e1lculo do PIS\/Cofins"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/jurisprudencia-voce-realmente-sabe-o-que-e\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Jurisprud\u00eancia: voc\u00ea REALMENTE sabe o que \u00e9?"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/cdad40b5818eb228a838461fcd656da7","name":"Coordena\u00e7\u00e3o","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/a413b22da0f5009c634f6c4586a2dbe5207074fd5becd88db5183b8069ef25e4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a413b22da0f5009c634f6c4586a2dbe5207074fd5becd88db5183b8069ef25e4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a413b22da0f5009c634f6c4586a2dbe5207074fd5becd88db5183b8069ef25e4?s=96&d=mm&r=g","caption":"Coordena\u00e7\u00e3o"},"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/contatoestrategiaconcursos-com-br\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/38056","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/48"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=38056"}],"version-history":[{"count":7,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/38056\/revisions"}],"predecessor-version":[{"id":1089719,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/38056\/revisions\/1089719"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=38056"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=38056"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=38056"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=38056"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}