{"id":36840,"date":"2016-04-12T20:51:12","date_gmt":"2016-04-12T23:51:12","guid":{"rendered":"http:\/\/www.estrategiaconcursos.com.br\/blog\/?p=36840"},"modified":"2016-04-13T09:48:53","modified_gmt":"2016-04-13T12:48:53","slug":"portugues-ibge-comentario-da-prova","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/portugues-ibge-comentario-da-prova\/","title":{"rendered":"An\u00e1lise da prova de Portugu\u00eas do IBGE Analista"},"content":{"rendered":"<p>Ol\u00e1, pessoal!<\/p>\n<p>Fiz uma an\u00e1lise da prova de Portugu\u00eas do IBGE Analista, e resolvi gravar\u00a0um v\u00eddeo comentando-a\u00a0(<a href=\"https:\/\/www.youtube.com\/watch?v=hIQEOadUxw4\" target=\"_blank\">Clique aqui<\/a>), de forma a verificar o que o edital previu e o que efetivamente caiu. Assim, voc\u00ea j\u00e1 ter\u00e1 uma pr\u00e9via do que poder\u00e1 ocorrer na prova de T\u00e9cnico do IBGE.<\/p>\n<p>No v\u00eddeo mostro que h\u00e1 possibilidade de recurso na quest\u00e3o 5, haja vista que a alternativa (E), dada como correta no gabarito preliminar, afirma que\u00a0o cartaz \u201cgritava\u201d porque o giz branco se destacava no fundo <strong>preto<\/strong>. Por\u00e9m, o texto n\u00e3o apresenta elemento expl\u00edcito ou impl\u00edcito que leve a subentender que o fundo do cartaz seria preto. Se a banca tivesse empregado o adjetivo &#8220;escuro&#8221;, ainda haveria possibilidade, haja vista o contraste com o giz &#8220;branco&#8221;, mas isso n\u00e3o implica entender que o fundo seria preto.<\/p>\n<p>Assim, seria interessante entrar com recurso, mesmo sabendo que a banca FGV \u00e9 &#8220;dura na queda&#8221; e dificilmente muda gabarito ou anula quest\u00e3o.<\/p>\n<p>A prova trouxe elementos novos, pois normalmente as quest\u00f5es gramaticais eram todas extra\u00eddas do texto ou textos da prova.\u00a0Nesta, percebemos quest\u00f5es com frases \u00a0fora do texto.<\/p>\n<p>Esta prova carregou no valor sem\u00e2ntico dos voc\u00e1bulos, seja na substitui\u00e7\u00e3o de palavras, no conhecimento da polissemia ou na redund\u00e2ncia.<\/p>\n<p>Veja o que o edital previu:<\/p>\n<p><b>Edital IBGE (todos os cargos) \u2013 Banca FGV<\/b>:<\/p>\n<p>Elementos de constru\u00e7\u00e3o do texto e seu sentido: g\u00eanero do texto (liter\u00e1rio e n\u00e3o liter\u00e1rio, narrativo, descritivo e argumentativo); interpreta\u00e7\u00e3o e organiza\u00e7\u00e3o interna. Sem\u00e2ntica: sentido e emprego dos voc\u00e1bulos; campos sem\u00e2nticos; emprego de tempos e modos dos verbos em portugu\u00eas. Morfologia: reconhecimento, emprego e sentido das classes gramaticais; processos de forma\u00e7\u00e3o de palavras; mecanismos de flex\u00e3o dos nomes e verbos. Sintaxe: frase, ora\u00e7\u00e3o e per\u00edodo; termos da ora\u00e7\u00e3o; processos de coordena\u00e7\u00e3o e subordina\u00e7\u00e3o; concord\u00e2ncia nominal e verbal; transitividade e reg\u00eancia de nomes e verbos; padr\u00f5es gerais de coloca\u00e7\u00e3o pronominal no portugu\u00eas; mecanismos de coes\u00e3o textual. Ortografia. Acentua\u00e7\u00e3o gr\u00e1fica. Emprego do sinal indicativo de crase. Pontua\u00e7\u00e3o. Estil\u00edstica: figuras de linguagem. Reescrita de frases: substitui\u00e7\u00e3o, deslocamento, paralelismo; varia\u00e7\u00e3o lingu\u00edstica: norma culta.<\/p>\n<p><b>Observa\u00e7\u00e3o<\/b>: os itens deste programa ser\u00e3o considerados sob o ponto de vista textual, ou seja, dever\u00e3o ser estudados sob o ponto de vista de sua participa\u00e7\u00e3o na estrutura\u00e7\u00e3o significativa dos textos.<\/p>\n<p>Agora, veja o que cada quest\u00e3o cobrou:<\/p>\n<p><b>Quest\u00e3o 1: <\/b>Interpreta\u00e7\u00e3o de texto e organiza\u00e7\u00e3o interna.<\/p>\n<p><b>Quest\u00e3o 2: <\/b>Sem\u00e2ntica: sentido e emprego dos voc\u00e1bulos.<\/p>\n<p><b>Quest\u00e3o 3<\/b>: processos de coordena\u00e7\u00e3o e mecanismos de coes\u00e3o textual.<\/p>\n<p><b>Quest\u00e3o 4<\/b>: Morfologia: reconhecimento, emprego e sentido das classes gramaticais. Mecanismos de coes\u00e3o textual.<\/p>\n<p><b>Quest\u00e3o 5<\/b>: Interpreta\u00e7\u00e3o de texto e organiza\u00e7\u00e3o interna.<\/p>\n<p><b>Quest\u00e3o 6<\/b>: Sintaxe: frase, ora\u00e7\u00e3o e per\u00edodo; processos de subordina\u00e7\u00e3o. Reescrita de frases: substitui\u00e7\u00e3o, deslocamento, paralelismo; varia\u00e7\u00e3o lingu\u00edstica: norma culta.<\/p>\n<p><strong> Quest\u00e3o 7<\/strong>: Reescrita de frases: substitui\u00e7\u00e3o, deslocamento, paralelismo; varia\u00e7\u00e3o lingu\u00edstica: norma culta. Padr\u00f5es gerais de coloca\u00e7\u00e3o pronominal no portugu\u00eas. Emprego de tempos e modos dos verbos em portugu\u00eas.<\/p>\n<p><b>Quest\u00e3o 8<\/b>: Sintaxe: frase, ora\u00e7\u00e3o e per\u00edodo; processos de subordina\u00e7\u00e3o. Reescrita de frases: substitui\u00e7\u00e3o, deslocamento, paralelismo; varia\u00e7\u00e3o lingu\u00edstica: norma culta. Emprego de tempos e modos dos verbos em portugu\u00eas.<\/p>\n<p><b>Quest\u00e3o 9: <\/b>Interpreta\u00e7\u00e3o de texto e organiza\u00e7\u00e3o interna.<\/p>\n<p><b>Quest\u00e3o 10: <\/b>Pontua\u00e7\u00e3o.<\/p>\n<p><b>Quest\u00e3o 11 <\/b>e <b>12<\/b>: Sem\u00e2ntica: sentido e emprego dos voc\u00e1bulos.<\/p>\n<p><b>Quest\u00e3o 13<\/b>: Estil\u00edstica.<\/p>\n<p><b>Quest\u00e3o 14<\/b>: processos de coordena\u00e7\u00e3o e mecanismos de coes\u00e3o textual.<\/p>\n<p><b>Quest\u00e3o 15<\/b>: Sem\u00e2ntica: sentido e emprego dos voc\u00e1bulos.<\/p>\n<p>Assista ao v\u00eddeo <a href=\"https:\/\/www.youtube.com\/watch?v=hIQEOadUxw4\" target=\"_blank\">clicando aqui!!!!<\/a><\/p>\n<p>Ah, no dia 17\/04 (domingo, dia da prova de n\u00edvel t\u00e9cnico), faremos uma transmiss\u00e3o ao vivo \u00e0s 08:00h da manh\u00e3! Isso mesmo!<\/p>\n<p>Voc\u00ea vai acordar com o professor D\u00e9cio Terror falando na sua cabe\u00e7a, passando algumas dicas, um resumo do conte\u00fado e sanando d\u00favidas!<\/p>\n<p>Se voc\u00ea quiser participar, basta enviar e-mail para pedagogico@terrorportugues.com.br<\/p>\n<p>Ser\u00e1 o &#8220;Encontro com D\u00e9cio Terror&#8221; rsrsrsrsrs<\/p>\n<p>Abra\u00e7o a todos!<\/p>\n<p>D\u00e9cio Terror<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ol\u00e1, pessoal! Fiz uma an\u00e1lise da prova de Portugu\u00eas do IBGE Analista, e resolvi gravar\u00a0um v\u00eddeo comentando-a\u00a0(Clique aqui), de forma a verificar o que o edital previu e o que efetivamente caiu. Assim, voc\u00ea j\u00e1 ter\u00e1 uma pr\u00e9via do que poder\u00e1 ocorrer na prova de T\u00e9cnico do IBGE. No v\u00eddeo mostro que h\u00e1 possibilidade de [&hellip;]<\/p>\n","protected":false},"author":214,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1],"tags":[893,833,1416,1575,1580,1578,1577,1415],"tax_estado":[],"class_list":["post-36840","post","type-post","status-publish","format-standard","hentry","category-cursos-e-concursos","tag-concurso-ibge","tag-ibge","tag-portugues-ibge","tag-resumao-ibge","tag-resumao-portugues-ibge","tag-resumo-de-portugues-ibge","tag-resumo-ibge","tag-revisao-ibge"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>An\u00e1lise da prova de Portugu\u00eas do IBGE Analista<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/portugues-ibge-comentario-da-prova\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"An\u00e1lise da prova de Portugu\u00eas do IBGE Analista\" \/>\n<meta property=\"og:description\" content=\"Ol\u00e1, pessoal! Fiz uma an\u00e1lise da prova de Portugu\u00eas do IBGE Analista, e resolvi gravar\u00a0um v\u00eddeo comentando-a\u00a0(Clique aqui), de forma a verificar o que o edital previu e o que efetivamente caiu. Assim, voc\u00ea j\u00e1 ter\u00e1 uma pr\u00e9via do que poder\u00e1 ocorrer na prova de T\u00e9cnico do IBGE. No v\u00eddeo mostro que h\u00e1 possibilidade de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/portugues-ibge-comentario-da-prova\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2016-04-12T23:51:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-04-13T12:48:53+00:00\" \/>\n<meta name=\"author\" content=\"D\u00e9cio Terror Filho\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"D\u00e9cio Terror Filho\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/portugues-ibge-comentario-da-prova\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/portugues-ibge-comentario-da-prova\/\"},\"author\":{\"name\":\"D\u00e9cio Terror Filho\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/e8165364027a31208914fc77c3314727\"},\"headline\":\"An\u00e1lise da prova de Portugu\u00eas do IBGE Analista\",\"datePublished\":\"2016-04-12T23:51:12+00:00\",\"dateModified\":\"2016-04-13T12:48:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/portugues-ibge-comentario-da-prova\/\"},\"wordCount\":729,\"commentCount\":20,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"keywords\":[\"concurso ibge\",\"IBGE\",\"Portugu\u00eas IBGE\",\"Resum\u00e3o IBGE\",\"Resum\u00e3o Portugu\u00eas IBGE\",\"Resumo de Portugu\u00eas IBGE\",\"Resumo IBGE\",\"Revis\u00e3o IBGE\"],\"articleSection\":[\"Concursos P\u00fablicos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/portugues-ibge-comentario-da-prova\/#respond\"]}],\"copyrightYear\":\"2016\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/portugues-ibge-comentario-da-prova\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/portugues-ibge-comentario-da-prova\/\",\"name\":\"An\u00e1lise da prova de Portugu\u00eas do IBGE Analista\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"datePublished\":\"2016-04-12T23:51:12+00:00\",\"dateModified\":\"2016-04-13T12:48:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/portugues-ibge-comentario-da-prova\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/portugues-ibge-comentario-da-prova\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/portugues-ibge-comentario-da-prova\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"An\u00e1lise da prova de Portugu\u00eas do IBGE Analista\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/e8165364027a31208914fc77c3314727\",\"name\":\"D\u00e9cio Terror Filho\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/a5b78e734de7c6482e965926e78344deb81abbc34282a3c9536cbb1a59728a37?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a5b78e734de7c6482e965926e78344deb81abbc34282a3c9536cbb1a59728a37?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a5b78e734de7c6482e965926e78344deb81abbc34282a3c9536cbb1a59728a37?s=96&d=mm&r=g\",\"caption\":\"D\u00e9cio Terror Filho\"},\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/contatoterrorportugues-com-br\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"An\u00e1lise da prova de Portugu\u00eas do IBGE Analista","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/portugues-ibge-comentario-da-prova\/","og_locale":"pt_BR","og_type":"article","og_title":"An\u00e1lise da prova de Portugu\u00eas do IBGE Analista","og_description":"Ol\u00e1, pessoal! Fiz uma an\u00e1lise da prova de Portugu\u00eas do IBGE Analista, e resolvi gravar\u00a0um v\u00eddeo comentando-a\u00a0(Clique aqui), de forma a verificar o que o edital previu e o que efetivamente caiu. Assim, voc\u00ea j\u00e1 ter\u00e1 uma pr\u00e9via do que poder\u00e1 ocorrer na prova de T\u00e9cnico do IBGE. No v\u00eddeo mostro que h\u00e1 possibilidade de [&hellip;]","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/portugues-ibge-comentario-da-prova\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2016-04-12T23:51:12+00:00","article_modified_time":"2016-04-13T12:48:53+00:00","author":"D\u00e9cio Terror Filho","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"D\u00e9cio Terror Filho","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/portugues-ibge-comentario-da-prova\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/portugues-ibge-comentario-da-prova\/"},"author":{"name":"D\u00e9cio Terror Filho","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/e8165364027a31208914fc77c3314727"},"headline":"An\u00e1lise da prova de Portugu\u00eas do IBGE Analista","datePublished":"2016-04-12T23:51:12+00:00","dateModified":"2016-04-13T12:48:53+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/portugues-ibge-comentario-da-prova\/"},"wordCount":729,"commentCount":20,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"keywords":["concurso ibge","IBGE","Portugu\u00eas IBGE","Resum\u00e3o IBGE","Resum\u00e3o Portugu\u00eas IBGE","Resumo de Portugu\u00eas IBGE","Resumo IBGE","Revis\u00e3o IBGE"],"articleSection":["Concursos P\u00fablicos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/portugues-ibge-comentario-da-prova\/#respond"]}],"copyrightYear":"2016","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/portugues-ibge-comentario-da-prova\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/portugues-ibge-comentario-da-prova\/","name":"An\u00e1lise da prova de Portugu\u00eas do IBGE Analista","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"datePublished":"2016-04-12T23:51:12+00:00","dateModified":"2016-04-13T12:48:53+00:00","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/portugues-ibge-comentario-da-prova\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/portugues-ibge-comentario-da-prova\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/portugues-ibge-comentario-da-prova\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"An\u00e1lise da prova de Portugu\u00eas do IBGE Analista"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/e8165364027a31208914fc77c3314727","name":"D\u00e9cio Terror Filho","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/a5b78e734de7c6482e965926e78344deb81abbc34282a3c9536cbb1a59728a37?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a5b78e734de7c6482e965926e78344deb81abbc34282a3c9536cbb1a59728a37?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a5b78e734de7c6482e965926e78344deb81abbc34282a3c9536cbb1a59728a37?s=96&d=mm&r=g","caption":"D\u00e9cio Terror Filho"},"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/contatoterrorportugues-com-br\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/36840","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/214"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=36840"}],"version-history":[{"count":2,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/36840\/revisions"}],"predecessor-version":[{"id":36842,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/36840\/revisions\/36842"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=36840"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=36840"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=36840"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=36840"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}