{"id":35451,"date":"2016-03-20T18:42:27","date_gmt":"2016-03-20T21:42:27","guid":{"rendered":"http:\/\/www.estrategiaconcursos.com.br\/blog\/?p=35451"},"modified":"2016-03-20T18:42:27","modified_gmt":"2016-03-20T21:42:27","slug":"concurso-perito-r-17-00000","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-perito-r-17-00000\/","title":{"rendered":"Concurso Perito &#8211; R$ 17.000,00"},"content":{"rendered":"<p>Ol\u00e1 minhas amigas e meus amigos,<\/p>\n<p>Se voc\u00ea ainda n\u00e3o sabe, foi divulgado h\u00e1 alguns dias o edital do concurso perito da PCDF, para o\u00a0 qual o edital prev\u00ea uma remunera\u00e7\u00e3o de aproximadamente R$ 17.000,00! S\u00e3o 100 vagas entre provimento imediato e cadastro de reserva. Isso mesmo, um cargo com status federal, no qual voc\u00ea vai iniciar ganhando esse \u201ctroco\u201d a\u00ed, com essa quantidade enorme de vagas.<\/p>\n<p><a href=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/03\/19231934\/img.-1.jpg\" rel=\"attachment wp-att-35438\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-35438 aligncenter\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/03\/19231934\/img.-1-300x160.jpg\" alt=\"img. 1\" width=\"344\" height=\"188\" \/><\/a><\/p>\n<p>Gostou? Ficou com vontade de fazer concurso perito? Quer ganhar R$ 17.000,00 por m\u00eas e ainda ter a t\u00e3o sonhada estabilidade, trabalhando em um \u00f3rg\u00e3o de respeito dentro da atividade de persecu\u00e7\u00e3o penal exercida pelo DF? Ent\u00e3o vem comigo conhecer os melhores cursos para esse concurso perito.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.estrategiaconcursos.com.br\/curso\/pacote-completo-p-perito-criminal-pcdf-fisica-com-videoaulas\/\">https:\/\/www.estrategiaconcursos.com.br\/curso\/pacote-completo-p-perito-criminal-pcdf-fisica-com-videoaulas\/<\/a><\/p>\n<p>&nbsp;<\/p>\n<p><strong>APRESENTA\u00c7\u00c3O<\/strong><\/p>\n<p>Bom, primeiramente, deixe que eu me apresente para voc\u00ea conhecer melhor meu trabalho aqui no Estrat\u00e9gia Concursos.<\/p>\n<p><a href=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/03\/20183613\/caricatura-ondulatoria.jpg\" rel=\"attachment wp-att-35452\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-35452 aligncenter\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/03\/20183613\/caricatura-ondulatoria-300x288.jpg\" alt=\"caricatura ondulatoria\" width=\"300\" height=\"288\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/03\/20183613\/caricatura-ondulatoria.jpg 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/03\/20183613\/caricatura-ondulatoria.jpg 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/03\/20183613\/caricatura-ondulatoria.jpg 313w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/03\/20183613\/caricatura-ondulatoria.jpg 960w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Sou professor de F\u00edsica aqui no Estrat\u00e9gia Concursos desde 2013, oportunidade em que ministrei meu primeiro curso, para a carreira de Policial Rodovi\u00e1rio Federal, tendo obtido resultados muito expressivos, inclusive o 1\u00b0 lugar geral, o Matheus Ara\u00fajo, que foi nosso aluno.<\/p>\n<p>Da\u00ed para frente foram mais de 36 cursos, geralmente para concurso perito dos mais diversos estados, al\u00e9m de concursos para Papiloscopista, Petrobr\u00e1s, etc. Os estados para os quais ministrei aulas de F\u00edsica para concurso perito foram: <strong>DF, GO, SC, SP<\/strong>, ou seja, \u00a0conhe\u00e7o bem a realidade da sua prova e sei o que ser\u00e1 cobrado, pois em todos os casos acima tivemos alunos aprovados.<\/p>\n<p>Sobre a \u00e1rea policial, meu conhecimento vai al\u00e9m dos limites da F\u00edsica, pois al\u00e9m de ser professor de F\u00edsica, tamb\u00e9m sou bacharel em Direito e estudei muito para carreiras policiais at\u00e9 obter aprova\u00e7\u00e3o para o cargo de Delegado de Pol\u00edcia Civil do Cear\u00e1, cargo para o qual estou aguardando nomea\u00e7\u00e3o.<\/p>\n<p>Assim, conhe\u00e7o bem a realidade do concurso perito para o qual voc\u00ea est\u00e1 se preparando, al\u00e9m de conhecer a realidade da \u00e1rea policial e o que as bancas mais cobram nesses cargos.<\/p>\n<p><strong>CONCURSO PERITO<\/strong><\/p>\n<p><a href=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/03\/20183710\/img.-2.jpg\" rel=\"attachment wp-att-35453\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-35453 aligncenter\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/03\/20183710\/img.-2-300x201.jpg\" alt=\"img. 2\" width=\"300\" height=\"201\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/03\/20183710\/img.-2.jpg 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/03\/20183710\/img.-2.jpg 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/03\/20183710\/img.-2.jpg 448w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/03\/20183710\/img.-2.jpg 1000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Pessoal, o concurso perito para o qual voc\u00ea est\u00e1 tentando uma vaga ser\u00e1 um dos mais concorridos dos \u00faltimos tempos, at\u00e9 mais que concursos perito criminal federal, teremos muitos candidatos experientes em F\u00edsica que estar\u00e3o presentes na lista de inscritos. Peritos criminais que j\u00e1 foram aprovados em outro concurso perito, al\u00e9m de Papiloscopistas, e estudiosos de outras \u00e1reas. Mas n\u00e3o se assuste, a dica \u00e9 iniciar os seus estudos o quanto antes.<\/p>\n<p>O concurso, como todos sabem envolve uma parte de conhecimentos gerais, que n\u00e3o permite deslizes, ou seja, s\u00e3o mat\u00e9rias mais b\u00e1sicas, para as quais o esfor\u00e7o deve ser grande, mas com um pouco de estudo organizado voc\u00ea consegue obter uma boa pontua\u00e7\u00e3o nessa prova.<\/p>\n<p>Por outro lado, a prova espec\u00edfica assusta, pois s\u00e3o conte\u00fados de concurso perito bem espec\u00edficos da sua \u00e1rea de forma\u00e7\u00e3o. E que contemplam uma grande gama de informa\u00e7\u00f5es e conte\u00fados.<\/p>\n<p><strong>BANCA IADES<\/strong><\/p>\n<p>No entanto, a banca examinadora n\u00e3o \u00e9 uma banca tradicional em concursos para esse cargo. Fiz uma pesquisa em quest\u00f5es de F\u00edsica dessa banca e n\u00e3o consegui obter sequer nenhum resultado, ou seja, essa banca nunca aplicou uma prova de f\u00edsica em algum concurso, a n\u00e3o ser \u00e1reas bem espec\u00edficas de F\u00edsica M\u00e9dica para concursos na \u00e1rea de sa\u00fade, portanto, totalmente distintos da nossa realidade, que \u00e9 a de concurso perito.<\/p>\n<p>&nbsp;<\/p>\n<p>Isso \u00e9 bom Prof. Vin\u00edcius Silva?<\/p>\n<p>&nbsp;<\/p>\n<p>Por um lado, sim, pois a prova n\u00e3o ser\u00e1 muito aprofundada, a banca n\u00e3o possui experi\u00eancia em quest\u00f5es do assunto; por outro \u00e9 ruim, pois h\u00e1 uma chance grande de quest\u00f5es d\u00fabias e pass\u00edveis de anula\u00e7\u00e3o acabarem aparecendo no seu concurso perito, haja vista a inexperi\u00eancia da banca na elabora\u00e7\u00e3o de provas.<\/p>\n<p>&nbsp;<\/p>\n<p>Acredito muito em uma prova que ser\u00e1 resolvida em <strong>80% com conhecimentos de n\u00edvel m\u00e9dio<\/strong>. N\u00e3o teremos muitas surpresas, assuntos como f\u00edsica nuclear, f\u00edsica do estado s\u00f3lido e f\u00edsica moderna s\u00e3o assuntos sem grande relev\u00e2ncia para a sua prova e voc\u00ea, definitivamente, n\u00e3o deve ficar perdendo seu tempo com esses temas. Depois que o edital sai, voc\u00ea deve otimizar seu tempo, priorizando aquilo que mais cai em prova.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>ASSUNTOS MAIS IMPORTANTES<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong><a href=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/03\/20183830\/caricatura-eletricidade.jpg\" rel=\"attachment wp-att-35454\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-35454 alignleft\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/03\/20183830\/caricatura-eletricidade-300x293.jpg\" alt=\"caricatura eletricidade\" width=\"260\" height=\"254\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/03\/20183830\/caricatura-eletricidade.jpg 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/03\/20183830\/caricatura-eletricidade.jpg 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/03\/20183830\/caricatura-eletricidade.jpg 307w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/03\/20183830\/caricatura-eletricidade.jpg 960w\" sizes=\"auto, (max-width: 260px) 100vw, 260px\" \/><\/a><a href=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/03\/20183832\/caricatura-mecanica.jpg\" rel=\"attachment wp-att-35455\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-35455\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/03\/20183832\/caricatura-mecanica-296x300.jpg\" alt=\"caricatura mecanica\" width=\"251\" height=\"255\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/03\/20183832\/caricatura-mecanica.jpg 296w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/03\/20183832\/caricatura-mecanica.jpg 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/03\/20183832\/caricatura-mecanica.jpg 948w\" sizes=\"auto, (max-width: 251px) 100vw, 251px\" \/><\/a>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/strong><strong>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>Assuntos mais relevantes para a sua prova s\u00e3o: Mec\u00e2nica e Eletricidade. Em toda prova de F\u00edsica esses s\u00e3o os assuntos mais cobrados dos candidatos. S\u00e3o extremamente importantes sob o ponto de vista do n\u00famero de quest\u00f5es que ser\u00e3o cobradas de voc\u00ea. Acredito muito em 50% da prova versando sobre esses dois temas, portanto, s\u00e3o de suma import\u00e2ncia no seu planejamento de estudos.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>CURSO DE F\u00cdSICA PARA CONCURSO PERITO PCDF<\/strong><\/p>\n<p>Vamos agora conversar um pouco sobre o nosso curso de F\u00edsica voltado para o concurso perito da PCDF.<\/p>\n<p>Trata-se de um curso que vai focar, certamente, nos assuntos mais importantes para a sua prova. Assuntos como Mec\u00e2nica e Eletricidade estar\u00e3o presentes com muita intensidade e volume.<\/p>\n<p>O meu curso aqui no Estrat\u00e9gia Concursos \u00e9 um dos \u00fanicos do mercado, se n\u00e3o for o \u00fanico, a trabalhar com uma quantidade de quest\u00f5es de aproximadamente 500 quest\u00f5es. E s\u00e3o 500 quest\u00f5es de concurso perito e outros cargos correlatos, ou seja, vamos trabalhar apenas com quest\u00f5es de concursos p\u00fablicos anteriores para o mesmo cargo ou similares.<\/p>\n<p>&nbsp;<\/p>\n<p>Portanto, \u00e9 um curso completo em teoria e exerc\u00edcios, todos comentados e resolvidos para voc\u00ea n\u00e3o perder seu tempo, tampouco ficar em d\u00favidas em quest\u00f5es que n\u00e3o acertou ou acertou \u201cno chute\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>Al\u00e9m disso voc\u00ea ter\u00e1 ferramentas exclusivas como videoaulas que podem ser baixadas para o seu computador, f\u00f3rum de d\u00favidas e uma novidade, que ser\u00e1 um grupo exclusivo de whatsapp para os candidatos que comprarem o curso para concurso perito diretamente no site, de forma honesta, sem intermedi\u00e1rios ou grupos de rateio. Nesse grupo eu estarei dedicado a tirar as suas d\u00favidas, dar dicas de prova e diluir as principais ang\u00fastias de voc\u00eas at\u00e9 o dia da prova.<\/p>\n<p>Gostou do curso? Confira a aula demonstrativa totalmente gratuita no link abaixo e adquira j\u00e1 o melhor material. Inicie seus estudos para o concurso perito dos teus sonhos.<\/p>\n<p><a href=\"https:\/\/www.estrategiaconcursos.com.br\/curso\/pacote-completo-p-perito-criminal-pcdf-fisica-com-videoaulas\/\">https:\/\/www.estrategiaconcursos.com.br\/curso\/pacote-completo-p-perito-criminal-pcdf-fisica-com-videoaulas\/<\/a><\/p>\n<p>Acesse as redes sociais do Prof. Vin\u00edcius Silva.<\/p>\n<p>Instagram: @profvinciussilva<\/p>\n<p>Periscope: @profvinciussilva<\/p>\n<p>Facebook: Vin\u00edcius Silva.<\/p>\n<p>Forte abra\u00e7o.<\/p>\n<p>Bons estudos.<\/p>\n<p>Prof. Vin\u00edcius Silva.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ol\u00e1 minhas amigas e meus amigos, Se voc\u00ea ainda n\u00e3o sabe, foi divulgado h\u00e1 alguns dias o edital do concurso perito da PCDF, para o\u00a0 qual o edital prev\u00ea uma remunera\u00e7\u00e3o de aproximadamente R$ 17.000,00! S\u00e3o 100 vagas entre provimento imediato e cadastro de reserva. Isso mesmo, um cargo com status federal, no qual voc\u00ea [&hellip;]<\/p>\n","protected":false},"author":93,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1],"tags":[1481,1443,445,757,822,853],"tax_estado":[],"class_list":["post-35451","post","type-post","status-publish","format-standard","hentry","category-cursos-e-concursos","tag-concurso-perito","tag-concursos-policiais","tag-fisica","tag-pcdf","tag-perito","tag-perito-criminal"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Concurso Perito - R$ 17.000,00<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-perito-r-17-00000\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Concurso Perito - R$ 17.000,00\" \/>\n<meta property=\"og:description\" content=\"Ol\u00e1 minhas amigas e meus amigos, Se voc\u00ea ainda n\u00e3o sabe, foi divulgado h\u00e1 alguns dias o edital do concurso perito da PCDF, para o\u00a0 qual o edital prev\u00ea uma remunera\u00e7\u00e3o de aproximadamente R$ 17.000,00! S\u00e3o 100 vagas entre provimento imediato e cadastro de reserva. Isso mesmo, um cargo com status federal, no qual voc\u00ea [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-perito-r-17-00000\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2016-03-20T21:42:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/03\/19231934\/img.-1-300x160.jpg\" \/>\n<meta name=\"author\" content=\"Vinicius Silva\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Vinicius Silva\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-perito-r-17-00000\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-perito-r-17-00000\/\"},\"author\":{\"name\":\"Vinicius Silva\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/20030622a981f9a942ad6b3561fe4ca4\"},\"headline\":\"Concurso Perito &#8211; R$ 17.000,00\",\"datePublished\":\"2016-03-20T21:42:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-perito-r-17-00000\/\"},\"wordCount\":1124,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-perito-r-17-00000\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/03\/19231934\/img.-1-300x160.jpg\",\"keywords\":[\"concurso perito\",\"Concursos Policiais\",\"F\u00edsica\",\"PCDF\",\"Perito\",\"Perito criminal\"],\"articleSection\":[\"Concursos P\u00fablicos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-perito-r-17-00000\/#respond\"]}],\"copyrightYear\":\"2016\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-perito-r-17-00000\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-perito-r-17-00000\/\",\"name\":\"Concurso Perito - R$ 17.000,00\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-perito-r-17-00000\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-perito-r-17-00000\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/03\/19231934\/img.-1-300x160.jpg\",\"datePublished\":\"2016-03-20T21:42:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-perito-r-17-00000\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-perito-r-17-00000\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-perito-r-17-00000\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/03\/19231934\/img.-1-300x160.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/03\/19231934\/img.-1-300x160.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-perito-r-17-00000\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Concurso Perito &#8211; R$ 17.000,00\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/20030622a981f9a942ad6b3561fe4ca4\",\"name\":\"Vinicius Silva\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/604d9670a4c7eea71feaa4381f3ae97e148292ac402671c5944aa67a3d127663?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/604d9670a4c7eea71feaa4381f3ae97e148292ac402671c5944aa67a3d127663?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/604d9670a4c7eea71feaa4381f3ae97e148292ac402671c5944aa67a3d127663?s=96&d=mm&r=g\",\"caption\":\"Vinicius Silva\"},\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/viniciussilvaestrategiaconcursos-com-br\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Concurso Perito - R$ 17.000,00","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-perito-r-17-00000\/","og_locale":"pt_BR","og_type":"article","og_title":"Concurso Perito - R$ 17.000,00","og_description":"Ol\u00e1 minhas amigas e meus amigos, Se voc\u00ea ainda n\u00e3o sabe, foi divulgado h\u00e1 alguns dias o edital do concurso perito da PCDF, para o\u00a0 qual o edital prev\u00ea uma remunera\u00e7\u00e3o de aproximadamente R$ 17.000,00! S\u00e3o 100 vagas entre provimento imediato e cadastro de reserva. Isso mesmo, um cargo com status federal, no qual voc\u00ea [&hellip;]","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-perito-r-17-00000\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2016-03-20T21:42:27+00:00","og_image":[{"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/03\/19231934\/img.-1-300x160.jpg","type":"","width":"","height":""}],"author":"Vinicius Silva","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Vinicius Silva","Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-perito-r-17-00000\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-perito-r-17-00000\/"},"author":{"name":"Vinicius Silva","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/20030622a981f9a942ad6b3561fe4ca4"},"headline":"Concurso Perito &#8211; R$ 17.000,00","datePublished":"2016-03-20T21:42:27+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-perito-r-17-00000\/"},"wordCount":1124,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-perito-r-17-00000\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/03\/19231934\/img.-1-300x160.jpg","keywords":["concurso perito","Concursos Policiais","F\u00edsica","PCDF","Perito","Perito criminal"],"articleSection":["Concursos P\u00fablicos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-perito-r-17-00000\/#respond"]}],"copyrightYear":"2016","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-perito-r-17-00000\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-perito-r-17-00000\/","name":"Concurso Perito - R$ 17.000,00","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-perito-r-17-00000\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-perito-r-17-00000\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/03\/19231934\/img.-1-300x160.jpg","datePublished":"2016-03-20T21:42:27+00:00","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-perito-r-17-00000\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-perito-r-17-00000\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-perito-r-17-00000\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/03\/19231934\/img.-1-300x160.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/03\/19231934\/img.-1-300x160.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-perito-r-17-00000\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Concurso Perito &#8211; R$ 17.000,00"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/20030622a981f9a942ad6b3561fe4ca4","name":"Vinicius Silva","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/604d9670a4c7eea71feaa4381f3ae97e148292ac402671c5944aa67a3d127663?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/604d9670a4c7eea71feaa4381f3ae97e148292ac402671c5944aa67a3d127663?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/604d9670a4c7eea71feaa4381f3ae97e148292ac402671c5944aa67a3d127663?s=96&d=mm&r=g","caption":"Vinicius Silva"},"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/viniciussilvaestrategiaconcursos-com-br\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/35451","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/93"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=35451"}],"version-history":[{"count":1,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/35451\/revisions"}],"predecessor-version":[{"id":35456,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/35451\/revisions\/35456"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=35451"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=35451"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=35451"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=35451"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}