{"id":33065,"date":"2016-02-11T15:49:48","date_gmt":"2016-02-11T18:49:48","guid":{"rendered":"http:\/\/www.estrategiaconcursos.com.br\/blog\/?p=33065"},"modified":"2016-02-16T15:03:39","modified_gmt":"2016-02-16T18:03:39","slug":"mapeamento-do-modelo-entidade-relacionamento-para-modelo-conceitual","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/mapeamento-do-modelo-entidade-relacionamento-para-modelo-conceitual\/","title":{"rendered":"Mapeamento do Modelo Entidade Relacionamento (ER) para o Modelo Relacional"},"content":{"rendered":"<p>Quando estudamos os conceitos introdut\u00f3rios de banco de dados sempre falando do modelo conceitual entidade relacionamento (ER) e do modelo l\u00f3gico relacional. Explicamos que durante um projeto de banco de dados a evolu\u00e7\u00e3o natural leva voc\u00ea a construir os dois modelos a partir dos requisitos do cliente.<\/p>\n<p>Legal, ent\u00e3o voc\u00ea come\u00e7ou pelo mini mundo, juntou os requisitos e construiu seu modelo ER! Agora voc\u00ea est\u00e1 com dificuldade de passar esse modelo para o modelo relacional. Seus problema acabaram! Nas pr\u00f3ximas linhas vamos explicar o passo a passo da transforma\u00e7\u00e3o do seu diagrama ER em tabelas.<\/p>\n<p>O livro do Navathe sugere um algoritmo que nos ajuda no processo de transformar um esquema ER e um mapeamento relacional. Vamos utilizar o esquema abaixo para ilustrar o passo-a-passo do mapeamento.<\/p>\n<div id=\"attachment_33067\" style=\"width: 310px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/02\/11153453\/figura-01.png\" rel=\"attachment wp-att-33067\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-33067\" class=\"size-medium wp-image-33067\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/02\/11153453\/figura-01-300x266.png\" alt=\"Diagrama entidade relacionamento\" width=\"300\" height=\"266\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/02\/11153453\/figura-01.png 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/02\/11153453\/figura-01.png 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/02\/11153453\/figura-01.png 338w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/02\/11153453\/figura-01.png 849w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-33067\" class=\"wp-caption-text\">Diagrama entidade relacionamento<\/p><\/div>\n<p>&nbsp;<\/p>\n<p><strong>Passo 01:<\/strong> O mapeamento come\u00e7a com as entidades regulares do modelo ER. Para casa tipo de entidade forte E presente no diagrama, criamos uma rela\u00e7\u00e3o R que inclu\u00ed todos os atributos simples da entidade E. Escolha os atributos chaves da entidade para ser chave prim\u00e1ria da rela\u00e7\u00e3o. Se a chave da entidade for composta, o mesmo conjunto de atributos que formam a chave de E v\u00e3o fazer parte da chave prim\u00e1ria de R.<\/p>\n<p>Vejamos no exemplo temos as entidade fortes EMPLOYEE, DEPARTAMENT e PROJECT ser\u00e3o transformados em rela\u00e7\u00f5es. Os atributos SSN, DNUMBER e PNUMBER ser\u00e3o as chaves prim\u00e1rias das respectivas tabelas. Assim temos:<\/p>\n<p><strong>EMPLOYEE<\/strong><\/p>\n<table style=\"height: 42px\" width=\"584\">\n<tbody>\n<tr>\n<td width=\"78\">Fname<\/td>\n<td width=\"74\">Minit<\/td>\n<td width=\"78\">Lname<\/td>\n<td width=\"68\"><u>Ssn<\/u><\/td>\n<td width=\"75\">Bdate<\/td>\n<td width=\"78\">Adress<\/td>\n<td width=\"58\">Salary<\/td>\n<td width=\"58\">Sex<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><strong>DEPARTAMENT<\/strong><\/p>\n<table>\n<tbody>\n<tr>\n<td width=\"94\">Dname<\/td>\n<td width=\"94\"><u>Dnumber<\/u><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p><strong>PROJECT<\/strong><\/p>\n<table>\n<tbody>\n<tr>\n<td width=\"94\">Pname<\/td>\n<td width=\"94\"><u>Pnumber<\/u><\/td>\n<td width=\"94\">Plocation<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p><strong>Passo 02:<\/strong> A segunda etapa se concentra em mapear as entidades fracas. Para cada entidade fraca W no modelo ER com uma entidade pai ou propriet\u00e1ria E, voc\u00ea deve criar uma rela\u00e7\u00e3o R e incluir todos os atributos simples (ou os componentes simples de atributos compostos) de W como atributos de R. \u00c9 necess\u00e1rio ainda incluir como chave estrangeira os atributos que fazem parte da chave prim\u00e1ria da entidade propriet\u00e1ria E. Assim a chave prim\u00e1ria ser\u00e1 formada pela combina\u00e7\u00e3o da chave prim\u00e1ria da entidade pai mais a chave parcial da entidade fraca, caso exista.<\/p>\n<p>Vamos mais uma vez para o nosso diagrama ER. A entidade fraca DEPENDENT deve dar origem a uma rela\u00e7\u00e3o. Essa rela\u00e7\u00e3o ter\u00e1 os atributos da entidade, al\u00e9m da chave estrangeira que vem da entidade pai. Vejam, ent\u00e3o, que o Ssn far\u00e1 parte da rela\u00e7\u00e3o. Desta forma podemos construir a rela\u00e7\u00e3o dependente conforme descrito abaixo:<\/p>\n<p><strong>DEPENDENT<\/strong><\/p>\n<table>\n<tbody>\n<tr>\n<td width=\"67\"><u>Essn<\/u><\/td>\n<td width=\"126\"><u>Dependent_name<\/u><\/td>\n<td width=\"66\">Sex<\/td>\n<td width=\"68\">Bdate<\/td>\n<td width=\"68\">Relationship<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p><strong>Passo 03:<\/strong> Vamos agora come\u00e7ar a mapear os relacionamentos bin\u00e1rios 1:1 entre as entidades. Para cada relacionamento bin\u00e1rio 1:1 R no esquema ER, identificamos as rela\u00e7\u00f5es que correspondem as entidades S e T que participam do relacionamento R. A partir deste momento temos tr\u00eas a\u00e7\u00f5es poss\u00edveis.<\/p>\n<p>A primeira seria <strong>usar chave estrangeira<\/strong> para efetivar o relacionamento. Neste caso voc\u00ea escolhe uma das chaves prim\u00e1rias de S ou de T. Vamos supor que escolhemos a chave de S. Voc\u00ea vai usar a chave prim\u00e1ria de S e incluir ela como chave estrangeira da rela\u00e7\u00e3o T. A melhor op\u00e7\u00e3o \u00e9 escolher a entidade que tenha participa\u00e7\u00e3o total no relacionamento. Em outras palavras, voc\u00ea deve escolher a entidade que para cada inst\u00e2ncia existente da entidade ela tenha uma inst\u00e2ncia no relacionamento e incluir a chave prim\u00e1ria da outra entidade nela. Vejam que neste caso evitamos o uso valores nulos.<\/p>\n<p>Um exemplo desta op\u00e7\u00e3o \u00e9 colocar na rela\u00e7\u00e3o DEPARTAMENT a chave do funcion\u00e1rio que gerencia (MANAGES) o departamento. Vejam que todo departamento deve ter um funcion\u00e1rio como gerente. Agora nossa tabela de DEPARTAMENT aparece com os novos atributos: o id do gerente e a data de in\u00edcio da ger\u00eancia.<\/p>\n<p><strong>DEPARTAMENT<\/strong><\/p>\n<table>\n<tbody>\n<tr>\n<td width=\"94\">Dname<\/td>\n<td width=\"94\"><u>Dnumber<\/u><\/td>\n<td width=\"94\">Mgr_ssn<\/td>\n<td width=\"94\">Mgr_start_date<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>A segunda op\u00e7\u00e3o seria fazer uma <strong>merge ou fus\u00e3o das rela\u00e7\u00f5es<\/strong>. Vejam que se temos um relacionamento 1:1 podemos combinar os atributos das duas rela\u00e7\u00f5es e do relacionamento em uma \u00fanica rela\u00e7\u00e3o. Essa op\u00e7\u00e3o \u00e9 adequada quando a participa\u00e7\u00e3o das duas entidades no relacionamento \u00e9 total.<\/p>\n<p>A terceira op\u00e7\u00e3o seria por <strong>cross-reference ou cria\u00e7\u00e3o de uma rela\u00e7\u00e3o<\/strong> para o relacionamento. Essa alternativa basicamente cria uma nova rela\u00e7\u00e3o com a chave prim\u00e1ria das duas rela\u00e7\u00f5es participantes para prover o relacionamento entre elas. Conhecida como tabela de liga\u00e7\u00e3o.<\/p>\n<p><strong>Passo 04:<\/strong> Neste momento vamos nos preocupar com os relacionamentos bin\u00e1rios 1:N. Para cada relacionamento bin\u00e1rio 1:N, vamos identificar a rela\u00e7\u00e3o S que representa a participa\u00e7\u00e3o da entidade no lado N do relacionamento. Em seguida, devemos incluir a chave estrangeira da rela\u00e7\u00e3o T em S. Os atributos da rela\u00e7\u00e3o 1:N tamb\u00e9m devem aparecer na rela\u00e7\u00e3o S.<\/p>\n<p>Vejamos um exemplo, o relacionamentos WORKS_FOR, CONTROLS e SUPERVISION no diagrama ER acima. Para WORKS_FOR vamos incluir o n\u00famero do departamento como chave estrangeira na rela\u00e7\u00e3o EMPLOYEE, vamos chama-lo de DNO. Da mesma forma vamos incluir SUPER_SSN para implementar o relacionamento SUPERVION e o n\u00famero do departamento na tabela de projeto para implementar o relacionamento CONTROLS. Vejam como ficaram as rela\u00e7\u00f5es EMPLOYEE e PROJECT com essas mudan\u00e7as.<\/p>\n<p><strong>EMPLOYEE<\/strong><\/p>\n<table>\n<tbody>\n<tr>\n<td width=\"62\">Fname<\/td>\n<td width=\"55\">Minit<\/td>\n<td width=\"63\">Lname<\/td>\n<td width=\"44\"><u>Ssn<\/u><\/td>\n<td width=\"57\">Bdate<\/td>\n<td width=\"63\">Adress<\/td>\n<td width=\"56\">Salary<\/td>\n<td width=\"43\">Sex<\/td>\n<td width=\"80\">Super_ssn<\/td>\n<td width=\"43\">Dno<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p><strong>PROJECT<\/strong><\/p>\n<table>\n<tbody>\n<tr>\n<td width=\"94\">Pname<\/td>\n<td width=\"94\"><u>Pnumber<\/u><\/td>\n<td width=\"94\">Plocation<\/td>\n<td width=\"94\">Dnum<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p><strong>Passo 05:<\/strong> O pr\u00f3ximo mapeamento deve tomar conta dos relacionamento M:N. Para cada relacionamento M:N criar uma nova rela\u00e7\u00e3o para representar o relacionamento. Inclua como chaves estrangeiras da nova rela\u00e7\u00e3o as chaves prim\u00e1rias das entidades participantes. Inclua ainda os atributos simples do relacionamento na nova tabela.<\/p>\n<p>Observe o relacionamento WORKS_ON no diagrama ER. Ele \u00e9 mapeado pela cria\u00e7\u00e3o da entidade WORKS_ON no esquema relacional. A chave prim\u00e1ria \u00e9 formada pelas chaves estrangeiras de projeto e empregado, renomeadas respectivamente para PNO e ESSN, respectivamente. O atributo HOURS \u00e9 representado na rela\u00e7\u00e3o.<\/p>\n<p><strong>WORKS_ON<\/strong><\/p>\n<table>\n<tbody>\n<tr>\n<td width=\"94\"><u>Essn<\/u><\/td>\n<td width=\"94\"><u>Pno<\/u><\/td>\n<td width=\"94\">Hours<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p><strong>Passo 06<\/strong>: Vamos agora fazer o mapeamento dos atributos multivalorados. Para cada atributo multivalorado A, crie uma tabela R. Essa rela\u00e7\u00e3o R vai incluir qualquer atributo pertencente ao conjunto A, al\u00e9m da chave prim\u00e1ria da entidade K que tem A como atributo multivalorado sendo chave estrangeira em R. A chave prim\u00e1ria da rela\u00e7\u00e3o \u00e9 uma combina\u00e7\u00e3o de A e K.<\/p>\n<p>No nosso modelo temos o exemplo de DEPT_LOCATIONS que deve ser criado. O atributo DLOCATION representa um atributo multivalorado de departamento, que tem como chave prim\u00e1ria DNUMBER. A rela\u00e7\u00e3o DEPT_LOCATIONS fica com a seguinte configura\u00e7\u00e3o:<\/p>\n<p><strong>DEPT_LOCATIONS<\/strong><\/p>\n<table>\n<tbody>\n<tr>\n<td width=\"94\"><u>Dnumber<\/u><\/td>\n<td width=\"94\"><u>Dlocation<\/u><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>Antes de passar para o passo 07, vamos apresentar abaixo o esquema relacional completo derivado do diagrama ER apresentado acima. As setas indicam a exist\u00eancia de uma chave estrangeira que garante a integridade referencial.<\/p>\n<div id=\"attachment_33068\" style=\"width: 454px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/02\/11153456\/figura-02.png\" rel=\"attachment wp-att-33068\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-33068\" class=\" wp-image-33068\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/02\/11153456\/figura-02-1024x712.png\" alt=\"Modelo relacional\" width=\"444\" height=\"312\" \/><\/a><p id=\"caption-attachment-33068\" class=\"wp-caption-text\">Modelo relacional<\/p><\/div>\n<p><strong>Passo 07:<\/strong> A \u00faltima etapa \u00e9 o mapeamento de relacionamentos N-\u00e1rios. Devemos criar\u00a0uma nova rela\u00e7\u00e3o que inclua as chaves prim\u00e1ria de todas as entidades participantes do relacionamento quanto n&gt;2. Adicione tamb\u00e9m os atributos simples. Observe o diagrama abaixo o resultado do mapeamento do relacionamento SUPPLY em uma rela\u00e7\u00e3o.<\/p>\n<div id=\"attachment_33069\" style=\"width: 442px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/02\/11153457\/figura-03.png\" rel=\"attachment wp-att-33069\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-33069\" class=\" wp-image-33069\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/02\/11153457\/figura-03.png\" alt=\"Digrama ER de um relacionamento tern\u00e1rio\" width=\"432\" height=\"164\" \/><\/a><p id=\"caption-attachment-33069\" class=\"wp-caption-text\">Digrama ER de um relacionamento tern\u00e1rio<\/p><\/div>\n<div id=\"attachment_33070\" style=\"width: 516px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/02\/11153459\/figura-04.png\" rel=\"attachment wp-att-33070\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-33070\" class=\" wp-image-33070\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/02\/11153459\/figura-04.png\" alt=\"Modelo relacional derivado de um relacionamento tern\u00e1rio.\" width=\"506\" height=\"342\" \/><\/a><p id=\"caption-attachment-33070\" class=\"wp-caption-text\">Modelo relacional derivado de um relacionamento tern\u00e1rio.<\/p><\/div>\n<p>Acabamos aqui o nosso primeiro artigo de muitos que vamos publicar aqui no Blog do Estrat\u00e9gia Concursos. A partir desta semana, teremos um rod\u00edzio entre os professores de TI para publicar artigos de interesse dos concurseiros. N\u00e3o deixem de fazer coment\u00e1rios e sugerir temas.<\/p>\n<p>O pr\u00f3ximo artigo relacionado com banco de dados trar\u00e1 os detalhes de mapeamento do modelo entidade relacionamento estendido. Mostraremos como a generaliza\u00e7\u00e3o e a heran\u00e7a s\u00e3o mapeados no modelo relacional.<\/p>\n<p>Qualquer d\u00favidas estamos \u00e0s ordens,<\/p>\n<p>Thiago Cavalcanti<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quando estudamos os conceitos introdut\u00f3rios de banco de dados sempre falando do modelo conceitual entidade relacionamento (ER) e do modelo l\u00f3gico relacional. Explicamos que durante um projeto de banco de dados a evolu\u00e7\u00e3o natural leva voc\u00ea a construir os dois modelos a partir dos requisitos do cliente. Legal, ent\u00e3o voc\u00ea come\u00e7ou pelo mini mundo, juntou [&hellip;]<\/p>\n","protected":false},"author":215,"featured_media":33067,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[],"tags":[1193,1304,1306,1305,1323],"tax_estado":[],"class_list":["post-33065","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","tag-banco-de-dados","tag-entidade-relacionamento","tag-mapeamento","tag-modelo-relacional","tag-projetotoken"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Mapeamento do Modelo Entidade Relacionamento (ER) para o Modelo Relacional<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/mapeamento-do-modelo-entidade-relacionamento-para-modelo-conceitual\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mapeamento do Modelo Entidade Relacionamento (ER) para o Modelo Relacional\" \/>\n<meta property=\"og:description\" content=\"Quando estudamos os conceitos introdut\u00f3rios de banco de dados sempre falando do modelo conceitual entidade relacionamento (ER) e do modelo l\u00f3gico relacional. Explicamos que durante um projeto de banco de dados a evolu\u00e7\u00e3o natural leva voc\u00ea a construir os dois modelos a partir dos requisitos do cliente. Legal, ent\u00e3o voc\u00ea come\u00e7ou pelo mini mundo, juntou [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/mapeamento-do-modelo-entidade-relacionamento-para-modelo-conceitual\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2016-02-11T18:49:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-02-16T18:03:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/02\/11153453\/figura-01.png\" \/>\n\t<meta property=\"og:image:width\" content=\"849\" \/>\n\t<meta property=\"og:image:height\" content=\"754\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Thiago Rodrigues Cavalcanti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Thiago Rodrigues Cavalcanti\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/mapeamento-do-modelo-entidade-relacionamento-para-modelo-conceitual\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/mapeamento-do-modelo-entidade-relacionamento-para-modelo-conceitual\/\"},\"author\":{\"name\":\"Thiago Rodrigues Cavalcanti\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/fcaf7747a784c860b8a4feb3dd2c528e\"},\"headline\":\"Mapeamento do Modelo Entidade Relacionamento (ER) para o Modelo Relacional\",\"datePublished\":\"2016-02-11T18:49:48+00:00\",\"dateModified\":\"2016-02-16T18:03:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/mapeamento-do-modelo-entidade-relacionamento-para-modelo-conceitual\/\"},\"wordCount\":1357,\"commentCount\":4,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/mapeamento-do-modelo-entidade-relacionamento-para-modelo-conceitual\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/02\/11153453\/figura-01.png\",\"keywords\":[\"banco de dados\",\"entidade relacionamento\",\"mapeamento\",\"modelo relacional\",\"projetotoken\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/mapeamento-do-modelo-entidade-relacionamento-para-modelo-conceitual\/#respond\"]}],\"copyrightYear\":\"2016\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/mapeamento-do-modelo-entidade-relacionamento-para-modelo-conceitual\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/mapeamento-do-modelo-entidade-relacionamento-para-modelo-conceitual\/\",\"name\":\"Mapeamento do Modelo Entidade Relacionamento (ER) para o Modelo Relacional\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/mapeamento-do-modelo-entidade-relacionamento-para-modelo-conceitual\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/mapeamento-do-modelo-entidade-relacionamento-para-modelo-conceitual\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/02\/11153453\/figura-01.png\",\"datePublished\":\"2016-02-11T18:49:48+00:00\",\"dateModified\":\"2016-02-16T18:03:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/mapeamento-do-modelo-entidade-relacionamento-para-modelo-conceitual\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/mapeamento-do-modelo-entidade-relacionamento-para-modelo-conceitual\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/mapeamento-do-modelo-entidade-relacionamento-para-modelo-conceitual\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/02\/11153453\/figura-01.png\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/02\/11153453\/figura-01.png\",\"width\":849,\"height\":754,\"caption\":\"Diagrama entidade relacionamento\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/mapeamento-do-modelo-entidade-relacionamento-para-modelo-conceitual\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mapeamento do Modelo Entidade Relacionamento (ER) para o Modelo Relacional\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/fcaf7747a784c860b8a4feb3dd2c528e\",\"name\":\"Thiago Rodrigues Cavalcanti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/08e6c519fe84ceb0618b23307f2dee18afb2b5dce83a93b6a66dfdd007a08564?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/08e6c519fe84ceb0618b23307f2dee18afb2b5dce83a93b6a66dfdd007a08564?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/08e6c519fe84ceb0618b23307f2dee18afb2b5dce83a93b6a66dfdd007a08564?s=96&d=mm&r=g\",\"caption\":\"Thiago Rodrigues Cavalcanti\"},\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/rcthiagogmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Mapeamento do Modelo Entidade Relacionamento (ER) para o Modelo Relacional","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/mapeamento-do-modelo-entidade-relacionamento-para-modelo-conceitual\/","og_locale":"pt_BR","og_type":"article","og_title":"Mapeamento do Modelo Entidade Relacionamento (ER) para o Modelo Relacional","og_description":"Quando estudamos os conceitos introdut\u00f3rios de banco de dados sempre falando do modelo conceitual entidade relacionamento (ER) e do modelo l\u00f3gico relacional. Explicamos que durante um projeto de banco de dados a evolu\u00e7\u00e3o natural leva voc\u00ea a construir os dois modelos a partir dos requisitos do cliente. Legal, ent\u00e3o voc\u00ea come\u00e7ou pelo mini mundo, juntou [&hellip;]","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/mapeamento-do-modelo-entidade-relacionamento-para-modelo-conceitual\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2016-02-11T18:49:48+00:00","article_modified_time":"2016-02-16T18:03:39+00:00","og_image":[{"width":849,"height":754,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/02\/11153453\/figura-01.png","type":"image\/png"}],"author":"Thiago Rodrigues Cavalcanti","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Thiago Rodrigues Cavalcanti","Est. tempo de leitura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/mapeamento-do-modelo-entidade-relacionamento-para-modelo-conceitual\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/mapeamento-do-modelo-entidade-relacionamento-para-modelo-conceitual\/"},"author":{"name":"Thiago Rodrigues Cavalcanti","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/fcaf7747a784c860b8a4feb3dd2c528e"},"headline":"Mapeamento do Modelo Entidade Relacionamento (ER) para o Modelo Relacional","datePublished":"2016-02-11T18:49:48+00:00","dateModified":"2016-02-16T18:03:39+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/mapeamento-do-modelo-entidade-relacionamento-para-modelo-conceitual\/"},"wordCount":1357,"commentCount":4,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/mapeamento-do-modelo-entidade-relacionamento-para-modelo-conceitual\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/02\/11153453\/figura-01.png","keywords":["banco de dados","entidade relacionamento","mapeamento","modelo relacional","projetotoken"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/mapeamento-do-modelo-entidade-relacionamento-para-modelo-conceitual\/#respond"]}],"copyrightYear":"2016","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/mapeamento-do-modelo-entidade-relacionamento-para-modelo-conceitual\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/mapeamento-do-modelo-entidade-relacionamento-para-modelo-conceitual\/","name":"Mapeamento do Modelo Entidade Relacionamento (ER) para o Modelo Relacional","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/mapeamento-do-modelo-entidade-relacionamento-para-modelo-conceitual\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/mapeamento-do-modelo-entidade-relacionamento-para-modelo-conceitual\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/02\/11153453\/figura-01.png","datePublished":"2016-02-11T18:49:48+00:00","dateModified":"2016-02-16T18:03:39+00:00","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/mapeamento-do-modelo-entidade-relacionamento-para-modelo-conceitual\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/mapeamento-do-modelo-entidade-relacionamento-para-modelo-conceitual\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/mapeamento-do-modelo-entidade-relacionamento-para-modelo-conceitual\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/02\/11153453\/figura-01.png","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/02\/11153453\/figura-01.png","width":849,"height":754,"caption":"Diagrama entidade relacionamento"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/mapeamento-do-modelo-entidade-relacionamento-para-modelo-conceitual\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Mapeamento do Modelo Entidade Relacionamento (ER) para o Modelo Relacional"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/fcaf7747a784c860b8a4feb3dd2c528e","name":"Thiago Rodrigues Cavalcanti","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/08e6c519fe84ceb0618b23307f2dee18afb2b5dce83a93b6a66dfdd007a08564?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/08e6c519fe84ceb0618b23307f2dee18afb2b5dce83a93b6a66dfdd007a08564?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/08e6c519fe84ceb0618b23307f2dee18afb2b5dce83a93b6a66dfdd007a08564?s=96&d=mm&r=g","caption":"Thiago Rodrigues Cavalcanti"},"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/rcthiagogmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/33065","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/215"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=33065"}],"version-history":[{"count":4,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/33065\/revisions"}],"predecessor-version":[{"id":33076,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/33065\/revisions\/33076"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/33067"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=33065"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=33065"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=33065"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=33065"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}