{"id":27334,"date":"2015-09-22T02:56:02","date_gmt":"2015-09-22T05:56:02","guid":{"rendered":"http:\/\/www.estrategiaconcursos.com.br\/blog\/?p=27334"},"modified":"2015-09-22T11:42:56","modified_gmt":"2015-09-22T14:42:56","slug":"comentarios-a-prova-de-direito-constitucional-pgfn-2015","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-a-prova-de-direito-constitucional-pgfn-2015\/","title":{"rendered":"Coment\u00e1rios \u00e0 Prova de Direito Constitucional &#8211; PGFN 2015"},"content":{"rendered":"<p>Ol\u00e1, pessoal! Tudo bem?<\/p>\n<p>Aqui \u00e9 o <em><strong>Ricardo Vale<\/strong><\/em>, coordenador e professor do Estrat\u00e9gia Concursos.<\/p>\n<p>A prova de <em><strong>Direito Constitucional<\/strong><\/em>, do concurso PGFN 2015, teve <em><strong>20 quest\u00f5es de alt\u00edssimo n\u00edvel<\/strong><\/em>. Sem d\u00favida, uma das melhores provas de Direito Constitucional que a ESAF fez nos \u00faltimos tempos.<\/p>\n<p>Abaixo, comento detalhadamente todas elas!<\/p>\n<p>Abra\u00e7os,<\/p>\n<p>Ricardo Vale<\/p>\n<p><em><strong>&#8220;O segredo do sucesso \u00e9 a const\u00e2ncia no objetivo&#8221;<\/strong><\/em><\/p>\n<p><a href=\"https:\/\/www.facebook.com\/rvale01\">https:\/\/www.facebook.com\/rvale01<\/a><\/p>\n<p><a href=\"https:\/\/www.youtube.com\/channel\/UC32LlMyS96biplI715yzS9Q\">https:\/\/www.youtube.com\/channel\/UC32LlMyS96biplI715yzS9Q<\/a><\/p>\n<p><strong>41 &#8211; (PGFN \u2013 2015) Sobre o controle de constitucionalidade de leis no Brasil, assinale a op\u00e7\u00e3o incorreta.<\/strong><\/p>\n<p>a) Respeitadas as regras processuais de distribui\u00e7\u00e3o e compet\u00eancia, a qualquer juiz ou tribunal do pa\u00eds \u00e9 reconhecido o poder de controlar a conformidade dos atos normativos \u00e0 Constitui\u00e7\u00e3o, desde que a decis\u00e3o do lit\u00edgio reclame, como premissa l\u00f3gica, o exame do tema da inconstitucionalidade, configurando, portanto, como uma quest\u00e3o prejudicial.<\/p>\n<p>b) No controle difuso de constitucionalidade, a mat\u00e9ria da constitucionalidade \u00e9 pedido deduzido na a\u00e7\u00e3o e n\u00e3o na sua causa de pedir.<\/p>\n<p>c) O sistema brasileiro adota o controle misto de constitucionalidade, convivendo com o controle concentrado e o controle difuso de constitucionalidade, sendo o primeiro relacionado com o controle principal e abstrato e o segundo com o modelo incidental e concreto.<\/p>\n<p>d) No sistema brasileiro h\u00e1 o controle de constitucionalidade pol\u00edtico e o jurisdicional.<\/p>\n<p>e) No sistema brasileiro admite-se o controle judicial preventivo, nos casos de mandado de seguran\u00e7a impetrado por parlamentar com objetivo de impedir a tramita\u00e7\u00e3o de projeto de emenda constitucional lesiva \u00e0s cl\u00e1usulas p\u00e9treas.<\/p>\n<p><strong>Coment\u00e1rios: <\/strong><\/p>\n<p>Letra A: correta. Qualquer juiz ou tribunal do pa\u00eds pode apreciar a constitucionalidade de lei. \u00c9 o chamado <strong><em>controle difuso<\/em><\/strong>, no qual o exame de constitucionalidade \u00e9 apenas uma <strong><em>quest\u00e3o prejudicial<\/em><\/strong>, ou seja, um antecedente l\u00f3gico para a solu\u00e7\u00e3o do caso concreto.<\/p>\n<p>Letra B: errada. No controle difuso, a mat\u00e9ria da constitucionalidade \u00e9 uma quest\u00e3o incidental. Ela \u00e9 a <strong><em>causa de pedir<\/em><\/strong> (a fundamenta\u00e7\u00e3o jur\u00eddica do pedido!).<\/p>\n<p>Letra C: correta. No Brasil, convivem o <strong><em>controle concentrado<\/em><\/strong> e o <strong><em>controle difuso<\/em><\/strong> de constitucionalidade. O controle concentrado \u00e9 realizado pelo STF, mediante a aprecia\u00e7\u00e3o da constitucionalidade de lei em abstrato. Por sua vez, o controle difuso \u00e9 realizado por qualquer juiz ou tribunal do pa\u00eds e se d\u00e1 diante de casos concretos.<\/p>\n<p>Letra D: correta. De fato, no sistema brasileiro, h\u00e1 o controle de constitucionalidade <strong><em>pol\u00edtico<\/em><\/strong> (por exemplo, quando o Poder Executivo veta projeto de lei em raz\u00e3o de sua inconstitucionalidade) e o controle de constitucionalidade <strong><em>jurisdicional<\/em><\/strong>.<\/p>\n<p>Letra E: correta. O controle judicial preventivo ocorre quando \u00e9 <strong><em>impetrado mandado de seguran\u00e7a por parlamentar<\/em><\/strong> com o objetivo de impedir a tramita\u00e7\u00e3o de projeto de emenda constitucional lesiva a cl\u00e1usula p\u00e9trea. Nesse caso, considera-se que est\u00e1 sendo violado o direito ao devido processo legislativo, que \u00e9 um direito l\u00edquido e certo que tem o parlamentar como detentor.<\/p>\n<p>O gabarito \u00e9 a letra B<\/p>\n<p><strong>42 &#8211; (PGFN \u2013 2015) Assinale a op\u00e7\u00e3o correta.<\/strong><\/p>\n<p>a) Os v\u00edcios formais traduzem defeito de forma\u00e7\u00e3o do ato normativo, pela inobserv\u00e2ncia de princ\u00edpio de ordem t\u00e9cnica ou procedimental ou pela viola\u00e7\u00e3o de regras de compet\u00eancia. Nesses casos, viciado \u00e9 o ato nos seus pressupostos, no seu procedimento de forma\u00e7\u00e3o, na sua forma final, atingindo diretamente seu conte\u00fado.<\/p>\n<p>b) No direito brasileiro, a consolida\u00e7\u00e3o do sistema de controle com amplo poder de julgar as quest\u00f5es constitucionais inclui a mat\u00e9ria relativa \u00e0 interpreta\u00e7\u00e3o de normas de regimento legislativo, n\u00e3o circunscrevendo-se no dom\u00ednio <em>interna corporis<\/em>.<\/p>\n<p>c) A inconstitucionalidade material envolve n\u00e3o somente o contraste direto do ato legislativo com o par\u00e2metro constitucional, mas tamb\u00e9m a aferi\u00e7\u00e3o do desvio de poder ou do excesso de poder legislativo.<\/p>\n<p>d) O controle de convencionalidade passou a ser estudado no Brasil especialmente ap\u00f3s a entrada em vigor da Emenda Constitucional n. 45\/2004 e a partir das decis\u00f5es do Supremo Tribunal Federal que elevaram o <em>status<\/em> de todos os tratados de direitos humanos a patamar de emendas constitucionais, excluindo, consequentemente, o controle de constitucionalidade sobre as regras jur\u00eddicas de car\u00e1ter dom\u00e9stico.<\/p>\n<p>e) N\u00e3o h\u00e1 distin\u00e7\u00e3o entre inconstitucionalidade origin\u00e1ria e inconstitucionalidade superveniente.<\/p>\n<p><strong>Coment\u00e1rios: <\/strong><\/p>\n<p>Letra A: errada. A <strong><em>inconstitucionalidade formal<\/em><\/strong> pode ser de 3 (tr\u00eas) tipos: <strong>i)<\/strong> org\u00e2nica; <strong>ii)<\/strong> forma propriamente dita ou; <strong>iii)<\/strong> formal por viola\u00e7\u00e3o a pressupostos objetivos do ato. No entanto, em nenhum desses casos, \u00e9 atingido diretamente o conte\u00fado do ato. Se isso ocorresse, falar\u00edamos em inconstitucionalidade material.<\/p>\n<p>Letra B: errada. No sistema brasileiro, tem sido reconhecida a <strong><em>impossibilidade de se examinar<\/em><\/strong> <strong><em>judicialmente<\/em><\/strong> atos <strong><em>exclusivamente<\/em><\/strong> <em>interna corporis<\/em>, como \u00e9 o caso das normas de regimento legislativo. Destaque-se, por\u00e9m, que o STF entende que:<\/p>\n<p>&#8211; \u00e9 poss\u00edvel a discuss\u00e3o judicial caso a norma regimental seja ofensiva \u00e0 Constitui\u00e7\u00e3o;<\/p>\n<p>&#8211; \u00e9 poss\u00edvel o exame judicia caso a quest\u00e3o diga respeito ao processo legislativo constitucional, em especial ao tr\u00e2mite de emenda constitucional.<\/p>\n<p>Letra C: correta. Essa assertiva foi retirada \u201c<em>ipsis literis<\/em>\u201d da doutrina do Prof. Gilmar Mendes, para quem a inconstitucionalidade material tamb\u00e9m fica caracterizada quando ocorre \u201c<em>desvio de poder ou excesso de poder legislativo\u201d<\/em>.<\/p>\n<p>Trata-se de tema bastante complexo, que est\u00e1 relacionado aos <strong><em>limites da jurisdi\u00e7\u00e3o constitucional<\/em><\/strong>. A quest\u00e3o est\u00e1 em saber at\u00e9 que ponto o Poder Judici\u00e1rio est\u00e1 legitimado a intervir na liberdade de conforma\u00e7\u00e3o do legislador.<\/p>\n<p>Segundo Gilmar Mendes, o excesso de poder legislativo se manifesta quando h\u00e1 <strong><em>viola\u00e7\u00e3o ao princ\u00edpio da proporcionalidade<\/em><\/strong>, em suas duas facetas: proibi\u00e7\u00e3o de excesso e proibi\u00e7\u00e3o de prote\u00e7\u00e3o insuficiente.<\/p>\n<p>Letra D: errada. De fato, o controle de convencionalidade passou a ser estudado no Brasil ap\u00f3s a EC n\u00ba 45\/2004. Entretanto, segundo entendimento do STF, <strong><em>nem todos os tratados de direitos humanos possuem status constitucional<\/em><\/strong>, mas apenas aqueles aprovados pelo rito pr\u00f3prio das emendas constitucionais.<\/p>\n<p>Letra E: errada. A <strong><em>inconstitucionalidade origin\u00e1ria<\/em><\/strong> existe quando a norma-par\u00e2metro \u00e9 anterior \u00e0 norma objeto de impugna\u00e7\u00e3o. Nesse caso, a norma j\u00e1 nasce inconstitucional. Por outro lado, na <strong><em>inconstitucionalidade superveniente<\/em><\/strong>, a norma-par\u00e2metro \u00e9 posterior \u00e0 norma impugnada. Destaque-se que o STF n\u00e3o admite no Brasil a inconstitucionalidade superveniente.<\/p>\n<p>O gabarito \u00e9 a letra C.<\/p>\n<p><strong>43 &#8211; (PGFN \u2013 2015) Sobre as garantias constitucionais do devido processo legal, da ampla defesa e do contradit\u00f3rio, assinale a op\u00e7\u00e3o incorreta.<\/strong><\/p>\n<p>a) \u00c9 direito do defensor, no interesse do representado, ter acesso amplo aos elementos de prova que, j\u00e1 documentados em procedimento investigat\u00f3rio realizado por \u00f3rg\u00e3o com compet\u00eancia de pol\u00edcia judici\u00e1ria, digam respeito ao exerc\u00edcio do direito de defesa.<\/p>\n<p>b) Ao inqu\u00e9rito policial n\u00e3o se aplica o princ\u00edpio do contradit\u00f3rio e ampla defesa, uma vez que n\u00e3o h\u00e1 acusa\u00e7\u00e3o, logo, n\u00e3o se fala em defesa.<\/p>\n<p>c) A pretens\u00e3o \u00e0 tutela jur\u00eddica que corresponde \u00e0 garantia aos acusados do contradit\u00f3rio e ampla defesa, com os meios e recursos a ela inerentes, cont\u00e9m os direitos a: informa\u00e7\u00e3o, manifesta\u00e7\u00e3o, de ver seus argumentos considerados.<\/p>\n<p>d) Os poderes inquisitivos do juiz encontram limite no princ\u00edpio do contradit\u00f3rio que imp\u00f5e \u00e0 autoridade judici\u00e1ria o dever jur\u00eddico processual de assegurar \u00e0s partes o exerc\u00edcio das prerrogativas inerentes \u00e0 bilateralidade do ju\u00edzo.<\/p>\n<p>e) Tendo em vista a garantia constitucional do amplo direito de defesa e do contradit\u00f3rio, \u00e9 v\u00e1lida a den\u00fancia que n\u00e3o aponte, especificadamente e de forma adequada, a exposi\u00e7\u00e3o do fato delituoso com todas as suas circunst\u00e2ncias.<\/p>\n<p><strong>Coment\u00e1rios: <\/strong><\/p>\n<p>Letra A: correta. \u00c9 exatamente o que prev\u00ea a <strong><em>S\u00famula Vinculante n\u00ba 14:<\/em><\/strong> <em>&#8220;\u00c9 direito do defensor, no interesse do representado, ter acesso amplo aos elementos de prova que, j\u00e1 documentados em procedimento investigat\u00f3rio realizado por \u00f3rg\u00e3o com compet\u00eancia de pol\u00edcia judici\u00e1ria, digam respeito ao exerc\u00edcio do direito de defesa&#8221;. <\/em><\/p>\n<p>Letra B: correta. Segundo o STF, <strong><em>n\u00e3o se aplica<\/em><\/strong> o contradit\u00f3rio e a ampla defesa no inqu\u00e9rito policial. No inqu\u00e9rito policial, n\u00e3o h\u00e1 acusa\u00e7\u00e3o; logo, n\u00e3o h\u00e1 que se falar em defesa.<\/p>\n<p>Letra C: correta. Segundo o STF (MS 22.693, Rel. Min. Gilmar Mendes), \u201c<em>a pretens\u00e3o \u00e0 tutela jur\u00eddica, que corresponde exatamente \u00e0 garantia consagrada no art. 5\u00ba, LV, da Constitui\u00e7\u00e3o, cont\u00e9m os seguintes direitos: <strong>a) direito de informa\u00e7\u00e3o<\/strong> (Recht auf Information), que obriga o \u00f3rg\u00e3o julgador a informar a parte contr\u00e1ria dos atos praticados no processo e sobre os elementos dele constantes; <strong>b) direito de manifesta\u00e7\u00e3o<\/strong> (Recht auf \u00c4usserung), que assegura ao defendente a possibilidade de manifestar-se, oralmente ou por escrito, sobre os elementos f\u00e1ticos e jur\u00eddicos constantes do processo; <strong>c) direito de ver seus argumentos considerados <\/strong>(Recht auf Ber\u00fccksichtingung), que exige do julgador capacidade de apreens\u00e3o e isen\u00e7\u00e3o de \u00e2nimo (Aufnahmef\u00e4higkeit und Aufnahmebereitschaft) para contemplar as raz\u00f5es apresentadas<\/em>\u201d.<\/p>\n<p>Letra D: correta. Segundo o STF (HC 69.001, Rel. Min. Celso de Mello), \u201c<em>\u00e9 preciso ter presente que os <strong>poderes inquisitivos do juiz encontram limite no princ\u00edpio constitucional do contradit\u00f3rio<\/strong> que imp\u00f5e a autoridade judici\u00e1ria &#8211; qualquer que seja o grau de jurisdi\u00e7\u00e3o em que atue &#8211; o dever jur\u00eddico-processual de assegurar as partes o exerc\u00edcio das prerrogativas inerentes a bilateralidade do ju\u00edzo\u201d. <\/em><\/p>\n<p>Letra E: errada. O STF considera que <strong><em>a den\u00fancia gen\u00e9rica<\/em><\/strong>, que n\u00e3o descreve de maneira adequada os fatos delituosos imputados ao denunciado, atenta contra o direito ao contradit\u00f3rio e impede o direito de defesa. Portanto, <strong><em>ser\u00e1 inv\u00e1lida<\/em><\/strong>.<\/p>\n<p>O gabarito \u00e9 a letra E.<\/p>\n<p><strong>44 &#8211; <\/strong><strong>(PGFN \u2013 2015) <\/strong><strong>Assinale a op\u00e7\u00e3o incorreta.<\/strong><\/p>\n<p>a) A Justi\u00e7a do Trabalho det\u00e9m compet\u00eancia para julgar as a\u00e7\u00f5es de indeniza\u00e7\u00e3o por dano moral ou patrimonial, decorrentes da rela\u00e7\u00e3o de trabalho e as a\u00e7\u00f5es relativas \u00e0s penalidades administrativas impostas aos empregadores pelos \u00f3rg\u00e3os de fiscaliza\u00e7\u00e3o das rela\u00e7\u00f5es de trabalho.<\/p>\n<p>b) Compete \u00e0 Justi\u00e7a do Trabalho dirimir controv\u00e9rsias em torno de representa\u00e7\u00e3o sindical, transferida da Justi\u00e7a Comum para a do Trabalho, conforme previs\u00e3o na Emenda Constitucional n. 45, de 2004, mantendo, por decis\u00e3o do STF, a compet\u00eancia residual dos TJs e do STJ para apreciar os recursos nessa mat\u00e9ria, quando j\u00e1 proferidas decis\u00f5es na Justi\u00e7a Comum antes da promulga\u00e7\u00e3o da Emenda em comento.<\/p>\n<p>c) As decis\u00f5es tomadas pelo Tribunal Superior do Trabalho s\u00e3o irrecorr\u00edveis, salvo: as decis\u00f5es denegat\u00f3rias de mandado de seguran\u00e7a, <em>habeas corpus<\/em> ou <em>habeas data<\/em>, cabendo recurso ordin\u00e1rio para o Supremo Tribunal Federal e as decis\u00f5es que contrariarem a Constitui\u00e7\u00e3o ou declararem a inconstitucionalidade de lei federal ou tratado, quando caber\u00e1 recurso extraordin\u00e1rio para o Supremo Tribunal Federal.<\/p>\n<p>d) A Emenda Constitucional n. 45, de 2004, manteve o Poder Normativo da Justi\u00e7a do Trabalho como forma de solu\u00e7\u00e3o dos conflitos coletivos exigindo, previamente, ao ajuizamento do diss\u00eddio coletivo de natureza econ\u00f4mica, a comprova\u00e7\u00e3o do esgotamento do processo negocial entre empregados e empregadores.<\/p>\n<p>e) Com a reda\u00e7\u00e3o da Emenda Constitucional n. 45, de 2004, o Tribunal Superior do Trabalho passou a ser composto por vinte e sete Ministros, escolhidos entre brasileiros, com mais de 35 e menos de 65 anos, nomeados pelo Presidente da Rep\u00fablica, ap\u00f3s a aprova\u00e7\u00e3o pela maioria absoluta do Senado Federal, sendo 1\/5 entre advogados com mais de dez anos de efetiva atividade profissional e membros do Minist\u00e9rio P\u00fablico do Trabalho, com mais de dez anos de efetivo exerc\u00edcio, indicados em lista s\u00eaxtupla pelos \u00f3rg\u00e3os de representa\u00e7\u00e3o da respectiva classe.<\/p>\n<p><strong>Coment\u00e1rios: <\/strong><\/p>\n<p>Letra A: correta. Essas compet\u00eancias est\u00e3o previstas no art. 114, VI e VII, CF\/88.<\/p>\n<p>Letra B: correta. Segundo o art. 114, III, CF\/88, compete \u00e0 Justi\u00e7a do Trabalho processar e julgar \u201c<em>as <strong>a\u00e7\u00f5es sobre representa\u00e7\u00e3o sindical<\/strong>, entre sindicatos, entre sindicatos e trabalhadores, e entre sindicatos e empregadores\u201d<\/em>. Essa compet\u00eancia, antes da EC n\u00ba 45\/2004, <strong><em>era da Justi\u00e7a Comum<\/em><\/strong>. Segundo o STF, os recursos das decis\u00f5es proferidas pela Justi\u00e7a Comum antes da EC n\u00ba 45\/2004, no que diz respeito a essa mat\u00e9ria, ser\u00e3o processados e julgados pelos Tribunais de Justi\u00e7a e pelo STJ.<\/p>\n<p>Letra C: correta. Conforme ensina Gilmar Mendes, em regra, as decis\u00f5es do TST s\u00e3o irrecorr\u00edveis, com duas exce\u00e7\u00f5es: <strong>i) <\/strong>as decis\u00f5es denegat\u00f3rias de mandado de seguran\u00e7a, <em>habeas corpus<\/em> ou <em>habeas data<\/em>, cabendo recurso ordin\u00e1rio para o Supremo Tribunal Federal e; <strong>ii)<\/strong> as decis\u00f5es que contrariarem a Constitui\u00e7\u00e3o ou declararem a inconstitucionalidade de lei federal ou tratado, quando caber\u00e1 recurso extraordin\u00e1rio para o Supremo Tribunal Federal.<\/p>\n<p>Letra D: errada. <strong><em>N\u00e3o se exige<\/em><\/strong> comprova\u00e7\u00e3o do esgotamento do processo negocial entre empregados e empregadores como requisito para ajuizamento de diss\u00eddio coletivo.<\/p>\n<p>Letra E: correta. O TST \u00e9 composto de <strong><em>27 Ministros<\/em><\/strong>, escolhidos entre brasileiros, com <strong><em>mais de 35 e menos de 65 anos<\/em><\/strong>, nomeados pelo Presidente da Rep\u00fablica, ap\u00f3s a aprova\u00e7\u00e3o pela maioria absoluta do Senado Federal. Desses Ministros, 1\/5 (um quinto) ser\u00e1 escolhido entre advogados com mais de dez anos de efetiva atividade profissional e membros do Minist\u00e9rio P\u00fablico do Trabalho, com mais de dez anos de efetivo exerc\u00edcio, indicados em lista s\u00eaxtupla pelos \u00f3rg\u00e3os de representa\u00e7\u00e3o da respectiva classe.<\/p>\n<p>O gabarito \u00e9 a letra D.<\/p>\n<p><strong>45- <\/strong><strong>(PGFN \u2013 2015) <\/strong><strong>Sobre os servidores p\u00fablicos, assinale a op\u00e7\u00e3o incorreta.<\/strong><\/p>\n<p>a) Os vencimentos dos cargos do Poder Legislativo e do Poder Judici\u00e1rio n\u00e3o poder\u00e3o ser superiores aos pagos pelo Poder Executivo.<\/p>\n<p>b) O direito de greve ser\u00e1 exercido nos termos e nos limites definidos em lei complementar.<\/p>\n<p>c) \u00c9 vedada a vincula\u00e7\u00e3o ou equipara\u00e7\u00e3o de quaisquer esp\u00e9cies remunerat\u00f3rias para o efeito de remunera\u00e7\u00e3o de pessoal do servi\u00e7o p\u00fablico.<\/p>\n<p>d) A administra\u00e7\u00e3o fazend\u00e1ria e seus servidores fiscais ter\u00e3o, dentro de suas \u00e1reas de compet\u00eancia e jurisdi\u00e7\u00e3o, preced\u00eancia sobre os demais setores administrativos, na forma da lei.<\/p>\n<p>e) A lei estabelecer\u00e1 os casos de contrata\u00e7\u00e3o por tempo determinado para atender a necessidade tempor\u00e1ria de excepcional interesse p\u00fablico.<\/p>\n<p><strong>Coment\u00e1rios: <\/strong><\/p>\n<p>Letra A: correta. Segundo o art. 37, XII, CF\/88, \u201c<em>os vencimentos dos cargos do Poder Legislativo e do Poder Judici\u00e1rio n\u00e3o poder\u00e3o ser superiores aos pagos pelo Poder Executivo\u201d<\/em>.<\/p>\n<p>Letra B: errada. N\u00e3o \u00e9 necess\u00e1rio lei complementar para regular o direito de greve dos servidores p\u00fablicos. Basta uma <strong><em>lei ordin\u00e1ria<\/em><\/strong>.<\/p>\n<p>Letra C: correta. Segundo o art. 37, XIII, CF\/88, \u201c<em>\u00e9 vedada a vincula\u00e7\u00e3o ou equipara\u00e7\u00e3o de quaisquer esp\u00e9cies remunerat\u00f3rias para o efeito de remunera\u00e7\u00e3o de pessoal do servi\u00e7o p\u00fablico\u201d. <\/em><\/p>\n<p>Letra D: correta. Segundo o art. 37, XVIII, CF\/88, <em>\u201ca administra\u00e7\u00e3o fazend\u00e1ria e seus servidores fiscais ter\u00e3o, dentro de suas \u00e1reas de compet\u00eancia e jurisdi\u00e7\u00e3o, preced\u00eancia sobre os demais setores administrativos, na forma da lei\u201d. <\/em><\/p>\n<p>Letra E: correta. Segundo o art. 37, IX, CF\/88, \u201c<em>a lei estabelecer\u00e1 os casos de contrata\u00e7\u00e3o por tempo determinado para atender a necessidade tempor\u00e1ria de excepcional interesse p\u00fablico\u201d. <\/em><\/p>\n<p>O gabarito \u00e9 a letra B.<\/p>\n<p><strong>46- <\/strong><strong>(PGFN \u2013 2015) <\/strong><strong>A compet\u00eancia recursal da Suprema Corte dos Estados Unidos \u00e9 discricion\u00e1ria. Os ju\u00edzes (<em>Justices<\/em>) que a comp\u00f5em t\u00eam a prerrogativa de aceitar ou n\u00e3o recurso contra decis\u00f5es de \u00f3rg\u00e3os judici\u00e1rios inferiores. Elegem o tema que entendem merecer a aprecia\u00e7\u00e3o do, por assim dizer, \u201cpleno\u201d. Essa regra \u00e9 considerada salutar e respons\u00e1vel pelo n\u00famero relativamente pequeno de processos que a Suprema Corte norte-americana julga a cada ano, possibilitando mais tempo para julgar, para refletir, o que se traduz em votos mais densos e de melhor qualidade.<\/strong><\/p>\n<p><strong>Sobre esse tema, redu\u00e7\u00e3o do n\u00famero de processos julgados pela Corte M\u00e1xima, no caso brasileiro, \u00e9 correto afirmar que:<\/strong><\/p>\n<p>a) os ministros do Supremo Tribunal Federal, desde a Constitui\u00e7\u00e3o de 1946, t\u00eam essa prerrogativa, vale dizer, selecionar os recursos que v\u00e3o ou n\u00e3o julgar, constituindo-se um avan\u00e7o naquela que \u00e9 considerada umas das mais democr\u00e1ticas constitui\u00e7\u00f5es da nossa hist\u00f3ria.<\/p>\n<p>b) a Argui\u00e7\u00e3o de Preceito Fundamental \u00e9 o instrumento adequado para fazer esse filtro de recursos ao Supremo Tribunal Federal.<\/p>\n<p>c) o Brasil n\u00e3o adota esse sistema, todos os recursos interpostos para julgamento pelo Supremo Tribunal Federal ser\u00e3o analisados pelos Ministros daquela Corte, sem exce\u00e7\u00e3o.<\/p>\n<p>d) a Emenda Constitucional n. 45\/05 criou mecanismo que se assemelha ao filtro existente na Suprema Corte dos EUA, que, no Brasil, \u00e9 a repercuss\u00e3o geral, sem a qual o n\u00famero de recursos no Supremo Tribunal Federal seria ainda maior que o atual.<\/p>\n<p>e) a discricionariedade no sistema processual constitucional brasileiro verifica-se mediante instrumentos pr\u00f3prios que est\u00e3o presentes desde a promulga\u00e7\u00e3o da Constitui\u00e7\u00e3o Federal de 1988, especificamente para o Superior Tribunal de Justi\u00e7a e o Supremo Tribunal Federal, aos quais o texto constitucional outorgou a prerrogativa da discricionariedade recursal a cada um de seus ministros.<\/p>\n<p><strong>Coment\u00e1rios: <\/strong><\/p>\n<p>A <strong><em>repercuss\u00e3o geral<\/em><\/strong> foi inserida pela EC n\u00ba 45\/2004 como <strong><em>requisito de admissibilidade do recurso extraordin\u00e1rio<\/em><\/strong>. Consiste em verificar se determinada quest\u00e3o \u00e9 relevante do ponto de vista pol\u00edtico, econ\u00f4mico, social ou jur\u00eddico. Por meio do mecanismo da repercuss\u00e3o geral, h\u00e1 um \u201cfiltro\u201d daqueles recursos extraordin\u00e1rios que ser\u00e3o apreciados pelo STF. O gabarito \u00e9 a letra D.<\/p>\n<p><strong>47- (PGFN \u2013 2015) A Comiss\u00e3o Parlamentar de Inqu\u00e9rito (CPI) exerce importante papel no ordenamento jur\u00eddico brasileiro. A ela a vigente Constitui\u00e7\u00e3o Federal outorgou poderes que s\u00e3o pr\u00f3prios \u00e0queles historicamente outorgados ao Poder Judici\u00e1rio. Sobre a CPI, \u00e9 correto afirmar que:<\/strong><\/p>\n<p>a) possui todas as prerrogativas outorgadas ao Judici\u00e1rio, n\u00e3o se admitindo, por for\u00e7a do princ\u00edpio da Separa\u00e7\u00e3o dos Poderes, controle judicial dos seus atos.<\/p>\n<p>b) segundo entendimento do STF, \u00e9 ileg\u00edtima a rejei\u00e7\u00e3o de cria\u00e7\u00e3o de CPI pelo plen\u00e1rio da C\u00e2mara dos Deputados, ainda que por expressa vota\u00e7\u00e3o majorit\u00e1ria, porquanto a Constitui\u00e7\u00e3o protege a prerrogativa institucional de investigar, especialmente a dos grupos minorit\u00e1rios que atuam no \u00e2mbito dos corpos legislativos.<\/p>\n<p>c) a cria\u00e7\u00e3o de CPIs depende da assinatura de 1\/3 dos membros da C\u00e2mara dos Deputados, ou do Senado, ou da C\u00e2mara dos Deputados e do Senado, na hip\u00f3tese de CPI mista, ou, alternativamente, de ato do Presidente da C\u00e2mara ou do Senado.<\/p>\n<p>d) compete \u00e0 Justi\u00e7a Federal no Distrito Federal julgar as a\u00e7\u00f5es ajuizadas contra ato de Presidente de CPI, a exemplo de convoca\u00e7\u00e3o para depor como investigado ou testemunha.<\/p>\n<p>e) a apura\u00e7\u00e3o de fato determinado, tal qual estabelece o art. 58, \u00a7 3.\u00ba, da CF\/88, pode ser objeto de especifica\u00e7\u00e3o ap\u00f3s a cria\u00e7\u00e3o da CPI, vale dizer, ele n\u00e3o necessariamente deve preexistir \u00e0 cria\u00e7\u00e3o da Comiss\u00e3o.<\/p>\n<p><strong>Coment\u00e1rios: <\/strong><\/p>\n<p>Letra A: errada. Nem todas as prerrogativas atribu\u00eddas ao Poder Judici\u00e1rio s\u00e3o concedidas \u00e0s CPI`s. Como exemplo, as CPI`s n\u00e3o podem determinar a intercepta\u00e7\u00e3o telef\u00f4nica.<\/p>\n<p>Letra B: correta. A CPI \u00e9 um direito das minorias. Segundo o STF, \u00e9 inconstitucional que se submeta o requerimento de instaura\u00e7\u00e3o de CPI ao Plen\u00e1rio.<\/p>\n<p>Letra C: errada. As CPI`s n\u00e3o podem ser criadas por mero ato do Presidente da C\u00e2mara ou do Senado.<\/p>\n<p>Letra D: errada. O STF \u00e9 que julga as a\u00e7\u00f5es ajuizadas contra ato de Presidente de CPI.<\/p>\n<p>Letra E: errada. O <strong><em>ato que instaura<\/em><\/strong> uma CPI dever\u00e1 delimitar, precisamente, os fatos que ser\u00e3o objeto da investiga\u00e7\u00e3o parlamentar. N\u00e3o se admite a cria\u00e7\u00e3o de CPI para investiga\u00e7\u00e3o gen\u00e9rica.<\/p>\n<p>O gabarito \u00e9 a letra B.<\/p>\n<p><strong>48- (PGFN \u2013 2015) A Constitui\u00e7\u00e3o Federal de 1988 (CF\/88) atribui, em casos espec\u00edficos, a iniciativa legislativa a determinada autoridade, \u00f3rg\u00e3o ou Poder. Sobre ela (iniciativa para deflagrar o processo legislativo, para formalmente apresentar proposta legislativa), \u00e9 correto afirmar que:<\/strong><\/p>\n<p>a) compete privativamente ao Presidente da Rep\u00fablica e ao Procurador-Geral da Rep\u00fablica a iniciativa legislativa sobre a organiza\u00e7\u00e3o, estrutura e aumento salarial da Procuradoria-Geral da Rep\u00fablica.<\/p>\n<p>b) a Constitui\u00e7\u00e3o Federal de 1988 estabelece que compete concomitantemente ao governador de Estado, juntamente com o Procurador-Geral de Justi\u00e7a, a iniciativa legislativa sobre a Lei Org\u00e2nica do Minist\u00e9rio P\u00fablico estadual.<\/p>\n<p>c) a Emenda Constitucional n. 45\/04, entre outras modifica\u00e7\u00f5es, alterou o Ato das Disposi\u00e7\u00f5es Constitucionais Transit\u00f3rias (ADCT) para autorizar a cria\u00e7\u00e3o de Varas Municipais, nos munic\u00edpios com popula\u00e7\u00e3o superior a 500 mil habitantes.<\/p>\n<p>d) sobre cria\u00e7\u00e3o de Tribunais Regionais Federais, o Supremo Tribunal Federal (STF) decidiu, em 2013, em sede de medida cautelar em ADI, que sequer a utiliza\u00e7\u00e3o de emenda \u00e0 Constitui\u00e7\u00e3o pode atalhar a prerrogativa de iniciativa do Poder competente, de modo que a iniciativa para criar tribunais \u00e9 do Poder Judici\u00e1rio, via projeto de lei.<\/p>\n<p>e) sobre cria\u00e7\u00e3o de Varas no \u00e2mbito da Justi\u00e7a Estadual, o Supremo Tribunal Federal (STF) decidiu, em 2013, em sede de medida cautelar em ADI, que a Assembleia Legislativa do Estado pode propor a cria\u00e7\u00e3o dessas Varas, desde que devidamente autorizada pela Constitui\u00e7\u00e3o do Estado.<\/p>\n<p><strong>Coment\u00e1rios: <\/strong><\/p>\n<p>Letra A: errada. O aumento salarial dos membros do Minist\u00e9rio P\u00fablico \u00e9 de <strong><em>iniciativa legislativa do pr\u00f3prio Minist\u00e9rio P\u00fablico<\/em><\/strong>. \u00c9 o que se depreende a partir do art. 127, \u00a7 2\u00ba , CF\/88, que prev\u00ea que, \u201c<em>ao Minist\u00e9rio P\u00fablico \u00e9 assegurada autonomia funcional e administrativa, podendo, observado o disposto no art. 169, propor ao Poder Legislativo a cria\u00e7\u00e3o e extin\u00e7\u00e3o de seus cargos e servi\u00e7os auxiliares, provendo-os por concurso p\u00fablico de provas ou de provas e t\u00edtulos, a <strong>pol\u00edtica remunerat\u00f3ria<\/strong> <strong>e os planos de carreira<\/strong>; a lei dispor\u00e1 sobre sua organiza\u00e7\u00e3o e funcionamento.\u201d<\/em><\/p>\n<p>Letra B: errada. Pegadinha! Na CF\/88, <strong><em>n\u00e3o h\u00e1 atribui\u00e7\u00e3o expressa<\/em><\/strong> de iniciativa legislativa ao Governador e ao Procurador-Geral de Justi\u00e7a. Essa compet\u00eancia decorre da aplica\u00e7\u00e3o do <strong>princ\u00edpio da simetria<\/strong>, uma vez que \u00e9 iniciativa concorrente entre o Presidente da Rep\u00fablica e o Procurador-Geral da Rep\u00fablica a lei de organiza\u00e7\u00e3o do Minist\u00e9rio P\u00fablico da Uni\u00e3o.<\/p>\n<p>Letra C: errada. Na CF\/88, n\u00e3o h\u00e1 previs\u00e3o para a cria\u00e7\u00e3o de varas municipais.<\/p>\n<p>Letra D: correta. A iniciativa legislativa para a cria\u00e7\u00e3o de tribunais \u00e9 do Poder Judici\u00e1rio. Nem mesmo emenda constitucional poder\u00e1, ent\u00e3o, criar tribunais do Poder Judici\u00e1rio. Foi o que decidiu o STF em sede de medida cautelar em ADI, suspendendo os efeitos da Emenda Constitucional n\u00ba 73\/2013, em raz\u00e3o de <strong><em>v\u00edcio de iniciativa<\/em><\/strong> (inconstitucionalidade formal).<\/p>\n<p>Letra E: errada. A Assembleia Legislativa n\u00e3o pode criar Varas da Justi\u00e7a Estadual. A cria\u00e7\u00e3o de varas \u00e9 mat\u00e9ria de iniciativa privativa do Poder Judici\u00e1rio.<\/p>\n<p>O gabarito \u00e9 a letra D.<\/p>\n<p><strong>49- (PGFN \u2013 2015) Sobre a concess\u00e3o de medida cautelar em sede de A\u00e7\u00e3o Direta de Inconstitucionalidade (ADI), \u00e9 correto afirmar que:<\/strong><\/p>\n<p>a) a Constitui\u00e7\u00e3o Federal de 1988 estabelece que a medida cautelar somente ser\u00e1 concedida por maioria de 2\/3 dos membros do Supremo Tribunal Federal.<\/p>\n<p>b) a medida cautelar somente pode ser concedida depois da manifesta\u00e7\u00e3o do Procurador-Geral da Rep\u00fablica, que disp\u00f5e do prazo de 3 dias.<\/p>\n<p>c) admite-se, conforme jurisprud\u00eancia do STF, a concess\u00e3o monocr\u00e1tica de medida cautelar, em car\u00e1ter excepcional e ainda que fora do per\u00edodo de recesso da Corte.<\/p>\n<p>d) n\u00e3o cabe medida cautelar contra Emenda Constitucional promulgada.<\/p>\n<p>e) a medida cautelar ser\u00e1 concedida por decis\u00e3o de 2\/3 dos membros do Superior Tribunal de Justi\u00e7a.<\/p>\n<p><strong>Coment\u00e1rios: <\/strong><\/p>\n<p>Letra A: errada. A CF\/88 n\u00e3o trata da concess\u00e3o de medida cautelar em ADI. Isso \u00e9 mat\u00e9ria prevista na legisla\u00e7\u00e3o infraconstitucional. Ademais, a medida cautelar \u00e9 concedida por decis\u00e3o da <strong><em>maioria absoluta <\/em><\/strong>dos membros do STF (seis votos), devendo estar presentes na sess\u00e3o, pelo menos, oito Ministros (qu\u00f3rum de presen\u00e7a).<\/p>\n<p>Letra B: errada. No caso de medida cautelar em sede de ADI, o relator apenas ouvir\u00e1 o Advogado-Geral da Uni\u00e3o e o Procurador-Geral da Rep\u00fablica <strong><em>caso julgue indispens\u00e1vel<\/em><\/strong>.<\/p>\n<p>Letra C: correta. Essa \u00e9 uma possibilidade excepcional\u00edssima. Em regra, a concess\u00e3o de medida cautelar deve ser feita em <strong><em>sess\u00e3o plen\u00e1ria<\/em><\/strong>. No entanto, h\u00e1 algumas exce\u00e7\u00f5es:<\/p>\n<p>&#8211; No per\u00edodo de recesso, a medida cautelar poder\u00e1 ser concedida pelo Presidente do Tribunal, sujeita a referendo posterior do Tribunal Pleno.<\/p>\n<p>&#8211; O relator poder\u00e1 conceder monocraticamente a medida cautelar, <strong><em>ainda que fora do per\u00edodo de recesso<\/em><\/strong>, desde que a espera pelo julgamento da sess\u00e3o plen\u00e1ria seguinte ao pedido de medida cautelar leve \u00e0 completa perda de sua utilidade.<a href=\"#_ftn1\" name=\"_ftnref1\">[1]<\/a><\/p>\n<p>Letra D: errada. \u00c9 cab\u00edvel, sim, medida cautelar contra emenda constitucional. N\u00e3o h\u00e1 qualquer \u00f3bice a isso.<\/p>\n<p>Letra E: errada. A concess\u00e3o de medida cautelar em ADI compete ao STF (e n\u00e3o ao STJ!).<\/p>\n<p>O gabarito \u00e9 a letra C.<\/p>\n<p><strong>50- (PGFN \u2013 2015) \u00c9 de Rui Barbosa a seguinte li\u00e7\u00e3o: \u201cUma constitui\u00e7\u00e3o \u00e9 execut\u00e1vel por si mesma, quando, completa no que determina, lhe \u00e9 sup\u00e9rfluo aux\u00edlio supletivo da lei, para exprimir tudo o que intenta, e realizar tudo o que exprime\u201d (Coment\u00e1rios \u00e0 Constitui\u00e7\u00e3o, 1933, II). <\/strong><\/p>\n<p><strong>No que diz respeito \u00e0 efic\u00e1cia e aplicabilidade da norma constitucional, \u00e9 correto afirmar que:<\/strong><\/p>\n<p>a) as prescri\u00e7\u00f5es mandat\u00f3rias e as prescri\u00e7\u00f5es diret\u00f3rias t\u00eam o mesmo significado, alcance e validade.<\/p>\n<p>b) o Supremo Tribunal Federal considerou, logo ap\u00f3s a promulga\u00e7\u00e3o da Constitui\u00e7\u00e3o Federal de 1988, autoaplic\u00e1vel o dispositivo do mandado de injun\u00e7\u00e3o, o que dispensaria a necessidade de regulamenta\u00e7\u00e3o, n\u00e3o obstante tenha assinalado que a legisla\u00e7\u00e3o do mandado de seguran\u00e7a seria utilizada de empr\u00e9stimo.<\/p>\n<p>c) a concep\u00e7\u00e3o de normas constitucionais autoaplic\u00e1veis (<em>self-executing<\/em>) e n\u00e3o autoexecut\u00e1veis (<em>not self-executing<\/em>) tem origem na Inglaterra, resultado da lenta constru\u00e7\u00e3o do seu sistema constitucional consuetudin\u00e1rio.<\/p>\n<p>d) apesar da sua ineg\u00e1vel relev\u00e2ncia, o art. 196 da Constitui\u00e7\u00e3o Federal, que diz que a sa\u00fade \u00e9 direito de todos e dever do Estado, necessita de lei para produzir efeitos, conforme tem decidido o Supremo Tribunal Federal ao negar o prosseguimento de recursos que intentam compelir o Estado a arcar com a responsabilidade de tratamento de sa\u00fade.<\/p>\n<p>e) ap\u00f3s a promulga\u00e7\u00e3o da Emenda Constitucional n. 45\/04, n\u00e3o se considera program\u00e1tico o dispositivo da Constitui\u00e7\u00e3o que requer a aprova\u00e7\u00e3o de lei por maioria simples.<\/p>\n<p><strong>Coment\u00e1rios: <\/strong><\/p>\n<p>Letra A: errada. As <strong><em>prescri\u00e7\u00f5es mandat\u00f3rias<\/em><\/strong> e as <strong><em>prescri\u00e7\u00f5es diret\u00f3rias<\/em><\/strong>, termos cunhados pela jurisprud\u00eancia norte-americana, possuem sentidos diversos. As prescri\u00e7\u00f5es mandat\u00f3rias (<em>mandatory provisions<\/em>) s\u00e3o normas de cumprimento obrigat\u00f3rios e irrecus\u00e1vel; por outro lado, prescri\u00e7\u00f5es diret\u00f3rias (<em>directory provisions<\/em>) s\u00e3o normas que n\u00e3o vinculam o legislador, possuindo simples car\u00e1ter regulamentar. Registre-se que h\u00e1 fortes cr\u00edticas a essa doutrina.<\/p>\n<p>Letra B: correta. O mandado de injun\u00e7\u00e3o \u00e9, de fato, <strong><em>norma autoaplic\u00e1vel<\/em><\/strong>. Tendo em vista que n\u00e3o h\u00e1 lei espec\u00edfica que regulamente o mandado de injun\u00e7\u00e3o, <strong><em>aplica-se, naquilo que couber, o rito previsto para o mandado de seguran\u00e7a<\/em><\/strong>. Esse \u00e9 o entendimento do STF, que considera que a legisla\u00e7\u00e3o do mandado de seguran\u00e7a ser\u00e1 usada de \u201cempr\u00e9stimo\u201d.<\/p>\n<p>Letra C: errada. A concep\u00e7\u00e3o de normas constitucionais autoaplic\u00e1veis e n\u00e3o autoaplic\u00e1veis t\u00eam origem na <strong><em>doutrina norte-americana<\/em><\/strong>.<\/p>\n<p>Letra D: errada. Em diversas oportunidades, o STF se manifestou garantindo a concretiza\u00e7\u00e3o do direito \u00e0 sa\u00fade, imputando ao Estado o dever de criar condi\u00e7\u00f5es para que os indiv\u00edduos tenham acesso a esse direito social.<\/p>\n<p>Letra E: errada. Os dispositivos constitucionais que requerem a aprova\u00e7\u00e3o de lei ordin\u00e1ria regulamentadora s\u00e3o <strong><em>normas de efic\u00e1cia limitada<\/em><\/strong>, algumas das quais de conte\u00fado program\u00e1tico.<\/p>\n<p>O gabarito \u00e9 a letra B.<\/p>\n<p><strong>51- (PGFN \u2013 2015) Como resposta ao 11 de setembro, o governo dos Estados Unidos lan\u00e7ou ampla ofensiva contra o terrorismo, denominada de \u201cGuerra ao Terror\u201d. V\u00e1rios acusados de pr\u00e1ticas terroristas ou de apoio foram presos e levados \u00e0 pris\u00e3o de Guant\u00e1namo Bay, em Cuba. Durante largo espa\u00e7o de tempo, a condi\u00e7\u00e3o desses prisioneiros, nacionais ou estrangeiros, restou legalmente indefinida at\u00e9 que a Suprema Corte dos Estados Unidos decidiu que eles poderiam impetrar habeas corpus e impugnar judicialmente os motivos para a pris\u00e3o, ainda que alguns deles n\u00e3o possu\u00edssem nacionalidade norte-americana. <\/strong><\/p>\n<p><strong>A Constitui\u00e7\u00e3o Federal de 1988 se ocupa do tema, dispondo em alguns momentos sobre guerra e estabelecendo consequ\u00eancias. Tomando-se por base o direito constitucional brasileiro, \u00e9 correto afirmar que:<\/strong><\/p>\n<p>a) em caso de guerra somente o Supremo Tribunal Federal ret\u00e9m compet\u00eancia constitucional para julgar a\u00e7\u00f5es contra les\u00e3o a direito.<\/p>\n<p>b) na hip\u00f3tese de estado de beliger\u00e2ncia, a compet\u00eancia origin\u00e1ria para dirimir conflitos surgidos em raz\u00e3o desse estado \u00e9 do Tribunal Regional Federal que tiver jurisdi\u00e7\u00e3o sobre o \u00f3rg\u00e3o militar que tomou a decis\u00e3o.<\/p>\n<p>c) na hip\u00f3tese de les\u00e3o a direito individual praticado por ato administrativo de autoridade militar, o juiz natural \u00e9 o Tribunal Superior Militar, ainda que se trate de les\u00e3o a direito de civil.<\/p>\n<p>d) a Constitui\u00e7\u00e3o Federal de 1988 autoriza, no Ato das Disposi\u00e7\u00f5es Constitucionais Transit\u00f3rias, a cria\u00e7\u00e3o de Tribunal espec\u00edfico, formado por civis e militares na ativa em posi\u00e7\u00e3o equiparada ao generalato, com jurisdi\u00e7\u00e3o para tratar, entre outros temas, de les\u00e3o a direito individual ou coletivo, em caso de guerra.<\/p>\n<p>e) o princ\u00edpio da inafastabilidade da aprecia\u00e7\u00e3o pelo Judici\u00e1rio de les\u00e3o ou amea\u00e7a a direito autoriza que, mesmo em caso de guerra, o Judici\u00e1rio mantenha sua jurisdi\u00e7\u00e3o.<\/p>\n<p><strong>Coment\u00e1rios: <\/strong><\/p>\n<p>O princ\u00edpio da inafastabilidade de jurisdi\u00e7\u00e3o est\u00e1 previsto no art. 5\u00ba, XXXV, CF\/88, que disp\u00f5e que \u201c<em>a lei n\u00e3o excluir\u00e1 da aprecia\u00e7\u00e3o do Poder Judici\u00e1rio les\u00e3o ou amea\u00e7a a direito\u201d. <\/em>Esse \u00e9 um princ\u00edpio v\u00e1lido a qualquer tempo, seja em per\u00edodo de paz ou em per\u00edodo de guerra. O gabarito \u00e9 a letra E.<\/p>\n<p><strong>52- (PGFN \u2013 2015) O Congresso Nacional, por ambas as Casas, aprovou um projeto de lei, posteriormente sancionado, promulgado e publicado. Ap\u00f3s entrar em vigor, in\u00fameras a\u00e7\u00f5es foram ajuizadas contra o ato normativo (lei), todas elas sob o argumento de que a lei acolhia evidente excesso de poder legislativo (excesso de poder no exerc\u00edcio da fun\u00e7\u00e3o legislativa, ou simplesmente, como doravante, \u201cexcesso de poder legislativo\u201d), sendo incompat\u00edvel com os fins constitucionalmente previstos. Tomando-se por base esse argumento, assinale a op\u00e7\u00e3o correta.<\/strong><\/p>\n<p>a) O argumento de excesso de poder legislativo n\u00e3o pode ser objeto de aprecia\u00e7\u00e3o judicial.<\/p>\n<p>b) O excesso de poder legislativo deve ser aferido por decis\u00e3o do Supremo Tribunal Federal.<\/p>\n<p>c) A doutrina de excesso de poder legislativo n\u00e3o tem amparo no Supremo Tribunal Federal.<\/p>\n<p>d) Uma das formas de manifesta\u00e7\u00e3o de excesso de poder legislativo \u00e9 a inconstitucionalidade substancial.<\/p>\n<p>e) N\u00e3o se pode atribuir \u00e0 Lei Complementar excesso de poder legislativo.<\/p>\n<p><strong>Coment\u00e1rios: <\/strong><\/p>\n<p>Letra A: errada. O \u201cexcesso de poder legislativo\u201d resulta na inconstitucionalidade material da lei. Portanto, pode ser apreciado pelo Poder Judici\u00e1rio.<\/p>\n<p>Letra B: errada. Qualquer juiz ou Tribunal poder\u00e1 aferir a exist\u00eancia de \u201cexcesso de poder legislativo\u201d.<\/p>\n<p>Letra C: errada. O STF reconhece a possibilidade de \u201cexcesso de poder legislativo\u201d.<\/p>\n<p>Letra D: correta. A inconstitucionalidade substancial (material) \u00e9 uma consequ\u00eancia do \u201cexcesso de poder legislativo\u201d.<\/p>\n<p>Letra E: errada. Tamb\u00e9m poder\u00e1 estar evidenciado em lei complementar \u201cexcesso de poder legislativo\u201d.<\/p>\n<p>O gabarito \u00e9 a letra D.<\/p>\n<p><strong>53- (PGFN \u2013 2015) Sobre \u201ccompet\u00eancia\u201d, \u00e9 correto afirmar que compete:<\/strong><\/p>\n<p>a) \u00e0 Uni\u00e3o emitir moeda, manter o servi\u00e7o postal e o correio a\u00e9reo nacional; e aos Estados compete explorar, diretamente ou mediante autoriza\u00e7\u00e3o, concess\u00e3o ou permiss\u00e3o, os servi\u00e7os de transporte rodovi\u00e1rio interestadual de passageiros.<\/p>\n<p>b) privativamente \u00e0 Uni\u00e3o legislar sobre registros p\u00fablicos e compete \u00e0 Uni\u00e3o, aos Estados e ao Distrito Federal legislar concorrentemente sobre popula\u00e7\u00f5es ind\u00edgenas.<\/p>\n<p>c) \u00e0 Uni\u00e3o planejar e promover a defesa permanente contra as calamidades p\u00fablicas, especialmente as secas e as inunda\u00e7\u00f5es e compete \u00e0 Uni\u00e3o, aos Estados e ao Distrito Federal legislar concorrentemente sobre educa\u00e7\u00e3o, cultura, ensino e desporto.<\/p>\n<p>d) privativamente \u00e0 Uni\u00e3o legislar sobre propaganda comercial, e aos Estados legislar sobre emigra\u00e7\u00e3o e imigra\u00e7\u00e3o.<\/p>\n<p>e) \u00e0 Uni\u00e3o e aos Estados autorizar e fiscalizar a produ\u00e7\u00e3o e o com\u00e9rcio de material b\u00e9lico.<\/p>\n<p><strong>Coment\u00e1rios: <\/strong><\/p>\n<p>Letra A: errada. \u00c9 <strong><em>compet\u00eancia da Uni\u00e3o<\/em><\/strong> explorar, diretamente ou mediante autoriza\u00e7\u00e3o, concess\u00e3o ou permiss\u00e3o, os servi\u00e7os de transporte rodovi\u00e1rio interestadual e internacional de passageiros (art. 21, XII, al\u00ednea \u201ce\u201d).<\/p>\n<p>Letra B: errada. \u00c9 <strong><em>compet\u00eancia privativa da Uni\u00e3o<\/em><\/strong> legisla sobre registros p\u00fablicos (art. 22, XXV) e sobre popula\u00e7\u00f5es ind\u00edgenas (art. 22, XIV).<\/p>\n<p>Letra C: correta. \u00c9 <strong><em>compet\u00eancia da Uni\u00e3o<\/em><\/strong> planejar e promover a defesa permanente contra as calamidades p\u00fablicas, especialmente as secas e as inunda\u00e7\u00f5es (art. 21, XVIII). Por sua vez, \u00e9 <strong><em>compet\u00eancia concorrente<\/em><\/strong> da Uni\u00e3o, dos Estados e do Distrito Federal legislar sobre educa\u00e7\u00e3o, cultura, ensino e desporto (art. 24, IX).<\/p>\n<p>Letra D: errada. \u00c9 <strong><em>compet\u00eancia privativa da Uni\u00e3o<\/em><\/strong> legislar sobre propaganda comercial (art. 22, XXIX) e sobre emigra\u00e7\u00e3o e imigra\u00e7\u00e3o (art. 22, XV).<\/p>\n<p>Letra E: errada. \u00c9 <strong><em>compet\u00eancia da Uni\u00e3o<\/em><\/strong> autorizar e fiscalizar a produ\u00e7\u00e3o e o com\u00e9rcio de material b\u00e9lico (art. 21, VI, CF\/88).<\/p>\n<p>O gabarito \u00e9 a letra C.<\/p>\n<p><strong>54- (PGFN \u2013 2015) Sobre o processo legislativo escolha a op\u00e7\u00e3o correta.<\/strong><\/p>\n<p>a) O Presidente da Rep\u00fablica disp\u00f5e de prazo de 15 dias para sancionar ou vetar Proposta de Emenda \u00e0 Constitui\u00e7\u00e3o.<\/p>\n<p>b) As limita\u00e7\u00f5es de ordem material n\u00e3o atingem a medida provis\u00f3ria.<\/p>\n<p>c) Se o Presidente da Rep\u00fablica considerar o projeto, no todo ou em parte, inconstitucional ou contr\u00e1rio ao interesse p\u00fablico, vet\u00e1-lo-\u00e1 total ou parcialmente, no prazo de quinze dias \u00fateis, contados da data do recebimento, e comunicar\u00e1, dentro de quarenta e oito horas, ao Presidente da C\u00e2mara dos Deputados os motivos do veto.<\/p>\n<p>d) A medida provis\u00f3ria mant\u00e9m-se integral at\u00e9 que sancionado ou vetado o projeto de lei de convers\u00e3o que alterou o seu texto original.<\/p>\n<p>e) No \u00e2mbito do Poder Judici\u00e1rio, a compet\u00eancia para apresentar projeto de lei \u00e9 exclusiva do Supremo Tribunal Federal.<\/p>\n<p><strong>Coment\u00e1rios: <\/strong><\/p>\n<p>Letra A: errada. As emendas constitucionais <strong><em>n\u00e3o est\u00e3o sujeitas<\/em><\/strong> a san\u00e7\u00e3o ou veto do Presidente da Rep\u00fablica.<\/p>\n<p>Letra B: errada. H\u00e1 v\u00e1rias limita\u00e7\u00f5es materiais \u00e0 medida provis\u00f3ria. Como exemplo, n\u00e3o podem ser editadas medidas provis\u00f3rias sobre direito eleitoral e direito penal.<\/p>\n<p>Letra C: errada. Segundo o art. 66, \u00a71\u00ba, CF\/88, \u201c<em>se o Presidente da Rep\u00fablica considerar o projeto, no todo ou em parte, inconstitucional ou contr\u00e1rio ao interesse p\u00fablico, vet\u00e1-lo-\u00e1 total ou parcialmente, no prazo de quinze dias \u00fateis, contados da data do recebimento, e comunicar\u00e1, dentro de quarenta e oito horas, <strong>ao Presidente do Senado Federal <\/strong>os motivos do veto<\/em>\u201d.<\/p>\n<p>Letra D: correta. Mesmo ap\u00f3s decorrido o prazo de cento e vinte dias contados da sua edi\u00e7\u00e3o, uma <strong><em>medida provis\u00f3ria conserva integralmente a sua vig\u00eancia<\/em><\/strong> se, nesse per\u00edodo, <strong><em>tiver sido aprovado, pelo Congresso Nacional, um projeto de lei de convers\u00e3o<\/em><\/strong> e esse projeto esteja aguardando san\u00e7\u00e3o presidencial.<\/p>\n<p>Letra E: errada. N\u00e3o \u00e9 s\u00f3 o STF que apresenta projeto de lei. Os Tribunais Superiores e os Tribunais de Justi\u00e7a tamb\u00e9m poder\u00e3o faz\u00ea-lo.<\/p>\n<p>O gabarito \u00e9 a letra D.<\/p>\n<p><strong>55- (PGFN \u2013 2015) Escolha a op\u00e7\u00e3o correta.<\/strong><\/p>\n<p>a) Constitui crime inafian\u00e7\u00e1vel e imprescrit\u00edvel a a\u00e7\u00e3o de grupos armados, civis ou militares, contra a ordem constitucional e o Estado Democr\u00e1tico, bem como, depois de declaradas ilegais por decis\u00e3o judicial, as greves em setores essenciais para a sociedade, definidas como tal em lei complementar.<\/p>\n<p>b) A lei ordin\u00e1ria estabelecer\u00e1 casos de inelegibilidade e os prazos de sua cessa\u00e7\u00e3o, a fim de proteger a probidade administrativa.<\/p>\n<p>c) O prazo para impugna\u00e7\u00e3o do mandato eletivo \u00e9 de quinze dias contados da diploma\u00e7\u00e3o.<\/p>\n<p>d) A incapacidade civil absoluta n\u00e3o \u00e9 motivo para a perda ou suspens\u00e3o de direitos pol\u00edticos.<\/p>\n<p>e) O militar alist\u00e1vel \u00e9 eleg\u00edvel, se contar menos de dez anos de servi\u00e7o ser\u00e1 agregado pela autoridade superior e, se eleito, passar\u00e1 automaticamente, no ato da diploma\u00e7\u00e3o, para a inatividade.<\/p>\n<p><strong>Coment\u00e1rios: <\/strong><\/p>\n<p>Letra A: errada. As greves em setores essenciais para a sociedade <strong><em>n\u00e3o configuram<\/em><\/strong> crime inafian\u00e7\u00e1vel e imprescrit\u00edvel.<\/p>\n<p>Letra B: errada. A lei complementar \u00e9 estabelecer\u00e1 outros casos de inelegibilidade e os prazos de sua cessa\u00e7\u00e3o.<\/p>\n<p><em>Letra C: correta. <\/em>\u00c9 isso mesmo. Segundo o art. 14, \u00a7 10,<em> \u201co mandato eletivo poder\u00e1 ser impugnado ante a Justi\u00e7a Eleitoral no <strong>prazo de quinze dias contados da diploma\u00e7\u00e3o<\/strong>, instru\u00edda a a\u00e7\u00e3o com provas de abuso do poder econ\u00f4mico, corrup\u00e7\u00e3o ou fraude\u201d. <\/em><\/p>\n<p>Letra D: errada. O art. 15, II, prev\u00ea que a incapacidade civil absoluta \u00e9 uma hip\u00f3tese de perda ou suspens\u00e3o dos direitos pol\u00edticos.<\/p>\n<p>Letra E: errada. Se contar <strong><em>mais de dez anos de servi\u00e7o<\/em><\/strong>, o militar ser\u00e1 agregado pela autoridade superior e, se eleito, passar\u00e1 automaticamente, no ato da diploma\u00e7\u00e3o, para a inatividade.<\/p>\n<p>O gabarito \u00e9 a letra C.<\/p>\n<p><strong>56- (PGFN \u2013 2015) Sobre \u201cneoconstitucionalismo\u201d, \u00e9 correto afirmar que se trata:<\/strong><\/p>\n<p>a) de express\u00e3o doutrin\u00e1ria, de origem inglesa, desenvolvida com a s\u00e9rie de julgados da C\u00e2mara dos Lordes, que ret\u00e9m compet\u00eancia legislativa e judicante.<\/p>\n<p>b) de express\u00e3o doutrin\u00e1ria, que tem como marco hist\u00f3rico o direito constitucional europeu, com destaque para o alem\u00e3o e o italiano, ap\u00f3s o fim da Segunda Guerra mundial.<\/p>\n<p>c) do novo constitucionalismo de express\u00e3o doutrin\u00e1ria, que tem origem e marco hist\u00f3rico no direito brasileiro com a redemocratiza\u00e7\u00e3o e as inova\u00e7\u00f5es constantes da Constitui\u00e7\u00e3o de 1946.<\/p>\n<p>d) de express\u00e3o doutrin\u00e1ria, de origem anglo-sax\u00e3, desenvolvida na Suprema Corte dos Estados Unidos \u00e0 \u00e9poca em que John Marshall era seu presidente, caracterizada pelo amplo ativismo judicial.<\/p>\n<p>e) de express\u00e3o doutrin\u00e1ria atribu\u00edda ao constitucionalista argentino Bidart Campos e tem como marco hist\u00f3rico a reforma constitucional de 1957.<\/p>\n<p><strong>Coment\u00e1rios: <\/strong><\/p>\n<p>O neoconstitucionalismo tem suas origens no direito constitucional europeu, com destaque para o alem\u00e3o e o italiano, <strong><em>ap\u00f3s a Segunda Guerra Mundial<\/em><\/strong>. O gabarito \u00e9 a letra B.<\/p>\n<p><strong>57- (PGFN \u2013 2015) Considerando a hist\u00f3ria constitucional do Brasil, \u00e9 correto afirmar que:<\/strong><\/p>\n<p>a) a Constitui\u00e7\u00e3o de 1937 previu o Supremo Tribunal Federal, mas extinguiu a Justi\u00e7a Federal.<\/p>\n<p>b) ao ser promulgada, a Constitui\u00e7\u00e3o Federal de 1946 previu a a\u00e7\u00e3o direta de inconstitucionalidade.<\/p>\n<p>c) a Emenda Constitucional n. 03\/93, que instituiu a a\u00e7\u00e3o declarat\u00f3ria de constitucionalidade, estabeleceu como legitimados para prop\u00f4-la os mesmos da a\u00e7\u00e3o direta de inconstitucionalidade.<\/p>\n<p>d) o mandado de seguran\u00e7a foi introduzido no direito brasileiro pela Constitui\u00e7\u00e3o de 1946.<\/p>\n<p>e) a Constitui\u00e7\u00e3o de 1891 determinou o ensino religioso nas escolas mantidas ou subvencionadas pela Uni\u00e3o, Estados ou Munic\u00edpios.<\/p>\n<p><strong>Coment\u00e1rios: <\/strong><\/p>\n<p>Letra A: correta. A Constitui\u00e7\u00e3o de 1937 extinguiu a Justi\u00e7a Federal. Depois, ela foi institu\u00edda novamente (mas apenas em segunda inst\u00e2ncia) pela Constitui\u00e7\u00e3o de 1946, que criou o Tribunal Federal de Recursos.<\/p>\n<p>Letra B: errada. Foi a EC n\u00ba 16\/1965 que previu a representa\u00e7\u00e3o gen\u00e9rica de constitucionalidade.<\/p>\n<p>Letra C: errada. A ADC foi mesmo criada pela EC n\u00ba 03\/1993. Por\u00e9m, foi com a EC n\u00ba 45\/2004 que os legitimados a ingressar com ADC <strong><em>passaram a ser os mesmos legitimados da ADI<\/em><\/strong>.<\/p>\n<p>Letra D: errada. O mandado de seguran\u00e7a foi introduzido no direito brasileiro com a <strong><em>Constitui\u00e7\u00e3o de 1934<\/em><\/strong>.<\/p>\n<p>Letra E: errada. A <em><strong>Constitui\u00e7\u00e3o de 1946<\/strong><\/em> \u00e9 que determinou o ensino religioso nas escolas oficiais. Nas Constitui\u00e7\u00f5es de 1934 e 1937, o ensino religioso aparecia como disciplina facultativa.<\/p>\n<p>O gabarito \u00e9 a letra A.<\/p>\n<p><strong>58 &#8211; (PGFN \u2013 2015) A interpreta\u00e7\u00e3o constitucional experimentou ampla evolu\u00e7\u00e3o desde a primeira decis\u00e3o judicial que declarou a inconstitucionalidade de um ato normativo, primazia da Suprema Corte dos Estados Unidos, em 1803, no caso <em>Marbury v. Madison<\/em>. A respeito desse tema, princ\u00edpio da interpreta\u00e7\u00e3o constitucional, \u00e9 correto afirmar que:<\/strong><\/p>\n<p>a) denomina-se \u201cprinc\u00edpio da unidade da Constitui\u00e7\u00e3o\u201d aquele que possibilita separar a norma do conjunto e aplicar o texto da Constitui\u00e7\u00e3o mediante sua divis\u00e3o em diversos sistemas.<\/p>\n<p>b) por sua caracter\u00edstica de documento fundamental, fruto de soberana outorga popular a um poder especial que se denomina de Poder Constituinte Origin\u00e1rio, os dispositivos da Constitui\u00e7\u00e3o encerram, em sua grande e esmagadora maioria, um compromisso pol\u00edtico, desprovido de efic\u00e1cia normativa imediata.<\/p>\n<p>c) o princ\u00edpio da interpreta\u00e7\u00e3o conforme a constitui\u00e7\u00e3o tem como caracter\u00edstica fundamental a preval\u00eancia da s\u00famula vinculante na interpreta\u00e7\u00e3o de c\u00e2none constitucional de natureza fundamental.<\/p>\n<p>d) o princ\u00edpio da concord\u00e2ncia pr\u00e1tica manifesta sua utilidade nas hip\u00f3teses de conflito entre normas constitucionais, quando os seus programas normativos se abalroam.<\/p>\n<p>e) pelo princ\u00edpio da efic\u00e1cia integradora, os instrumentos de controle de constitucionalidade, especialmente a ADI, devem ser interpretados de modo a, tanto quanto poss\u00edvel, integrar o texto impugnado \u00e0 Constitui\u00e7\u00e3o.<\/p>\n<p><strong>Coment\u00e1rios: <\/strong><\/p>\n<p>Letra A: errada. Segundo o princ\u00edpio da unidade, a Constitui\u00e7\u00e3o deve ser <strong><em>interpretada como um todo<\/em><\/strong> \u00fanico. Suas normas n\u00e3o podem ser interpretadas de maneira isolada.<\/p>\n<p>Letra B: errada. As normas constitucionais s\u00e3o dotadas de grande <strong><em>for\u00e7a normativa<\/em><\/strong>. Elas n\u00e3o podem ser consideradas meros compromissos pol\u00edticos.<\/p>\n<p>Letra C: errada. N\u00e3o h\u00e1 qualquer rela\u00e7\u00e3o entre a \u201cinterpreta\u00e7\u00e3o conforme a Constitui\u00e7\u00e3o\u201d e as s\u00famulas vinculantes. A interpreta\u00e7\u00e3o conforme a Constitui\u00e7\u00e3o \u00e9 uma <strong><em>t\u00e9cnica aplic\u00e1vel a normas poliss\u00eamicas<\/em><\/strong> (plurissignificativas). Diante de uma norma com v\u00e1rias interpreta\u00e7\u00f5es poss\u00edveis, deve-se priorizar aquela que melhor a compatibilize com a Constitui\u00e7\u00e3o.<\/p>\n<p>Letra D: correta. O princ\u00edpio da concord\u00e2ncia pr\u00e1tica (ou harmoniza\u00e7\u00e3o) busca resolver o conflito entre normas constitucionais. Por meio desse princ\u00edpio, busca-se a <strong><em>harmoniza\u00e7\u00e3o dos bens jur\u00eddicos em conflito<\/em><\/strong>, <strong><em>evitando-se o sacrif\u00edcio total de uns em rela\u00e7\u00e3o aos outros<\/em><\/strong>.<\/p>\n<p>Letra E: errada. Segundo princ\u00edpio da efic\u00e1cia integradora, na interpreta\u00e7\u00e3o da Constitui\u00e7\u00e3o, deve ser dada prefer\u00eancia \u00e0s determina\u00e7\u00f5es que favore\u00e7am a integra\u00e7\u00e3o pol\u00edtica e social e o refor\u00e7o da unidade pol\u00edtica.<\/p>\n<p>O gabarito \u00e9 a letra D.<\/p>\n<p><strong>59 &#8211; (PGFN \u2013 2015) Sobre o sistema brasileiro de controle de constitucionalidade, assinale a op\u00e7\u00e3o incorreta.<\/strong><\/p>\n<p>a) A Constitui\u00e7\u00e3o de 1934, mantendo o sistema de controle difuso, introduziu a a\u00e7\u00e3o direta de inconstitucionalidade interventiva, a cl\u00e1usula de reserva de plen\u00e1rio e a atribui\u00e7\u00e3o ao Senado Federal de compet\u00eancia para suspender a execu\u00e7\u00e3o, no todo ou em parte, de lei ou ato declarado inconstitucional por decis\u00e3o definitiva.<\/p>\n<p>b) A ruptura do chamado \u201cmonop\u00f3lio da a\u00e7\u00e3o direta\u201d, outorgado ao Procurador-Geral da Rep\u00fablica para o exerc\u00edcio de controle de constitucionalidade de leis no Brasil, ocorreu com a Constitui\u00e7\u00e3o de 1946.<\/p>\n<p>c) A partir da Constitui\u00e7\u00e3o de 1891 consagrou-se, no direito brasileiro, a t\u00e9cnica do controle difuso de constitucionalidade, repressivo, posterior, pela via da exce\u00e7\u00e3o ou defesa, pela qual a declara\u00e7\u00e3o de inconstitucionalidade se implementa de modo incidental como prejudicial ao m\u00e9rito.<\/p>\n<p>d) A Constitui\u00e7\u00e3o de 1824 n\u00e3o contemplava qualquer modalidade de controle de constitucionalidade das leis. Era outorgada ao Poder Legislativo, sob influ\u00eancia francesa, a atribui\u00e7\u00e3o de fazer leis, interpret\u00e1-las, suspend\u00ea-las e revog\u00e1-las, bem como velar pela guarda da Constitui\u00e7\u00e3o.<\/p>\n<p>e) A Constitui\u00e7\u00e3o de 1937 vedou expressamente ao Poder Judici\u00e1rio conhecer das quest\u00f5es exclusivamente pol\u00edticas.<\/p>\n<p><strong>Coment\u00e1rios: <\/strong><\/p>\n<p>Letra A: correta. Todas essas foram inova\u00e7\u00f5es trazidas pela Constitui\u00e7\u00e3o de 1934.<\/p>\n<p>Letra B: errada. A <strong><em>Constitui\u00e7\u00e3o Federal de 1988<\/em><\/strong> \u00e9 que rompeu com o \u201cmonop\u00f3lio da a\u00e7\u00e3o direta\u201d. At\u00e9 a CF\/88, a compet\u00eancia para propor ADI era exclusiva do Procurador-Geral da Rep\u00fablica.<\/p>\n<p>Letra C: correta. A Constitui\u00e7\u00e3o de 1891 previu o controle difuso de constitucionalidade, por influ\u00eancia norte-americana.<\/p>\n<p>Letra D: correta. A Constitui\u00e7\u00e3o de 1824 n\u00e3o adotou <strong><em>nenhum sistema de controle da constitucionalidade<\/em><\/strong> dos atos ou omiss\u00f5es do Poder P\u00fablico<\/p>\n<p>Letra E: correta. De fato, a Constitui\u00e7\u00e3o de 1937 vedou expressamente ao Poder Judici\u00e1rio conhecer das quest\u00f5es exclusivamente pol\u00edticas.<\/p>\n<p>O gabarito \u00e9 a letra B.<\/p>\n<p><strong>60 &#8211; (PGFN \u2013 2015) Sobre os direitos sociais coletivos dos trabalhadores, assinale a op\u00e7\u00e3o correta.<\/strong><\/p>\n<p>a) \u00c9 livre a cria\u00e7\u00e3o de sindicatos, condicionados ao registro no \u00f3rg\u00e3o competente, cabendo aos trabalhadores ou empregadores interessados estabelecer a base territorial respectiva, n\u00e3o inferior \u00e0 \u00e1rea de um munic\u00edpio.<\/p>\n<p>b) Para a S\u00famula Vinculante n. 40, do Supremo Tribunal Federal, a contribui\u00e7\u00e3o assistencial s\u00f3 \u00e9 exig\u00edvel dos filiados ao sindicato.<\/p>\n<p>c) Cabe aos trabalhadores, diante do princ\u00edpio da liberdade e autonomia sindical, artigo 8\u00ba, caput, da Constitui\u00e7\u00e3o da Rep\u00fablica Federativa do Brasil de 1988, decidir pela participa\u00e7\u00e3o dos sindicatos nas negocia\u00e7\u00f5es coletivas de trabalho.<\/p>\n<p>d) Nas empresas com mais de 200 empregados, \u00e9 assegurada a elei\u00e7\u00e3o de um representante destes com a finalidade exclusiva de promover-lhes o entendimento direto com os empregadores, sendo vedada a dispensa do representante eleito, a partir do registro da candidatura e, se eleito, ainda que suplente, at\u00e9 um ano ap\u00f3s o t\u00e9rmino do mandato.<\/p>\n<p>e) A Constitui\u00e7\u00e3o da Rep\u00fablica Federativa do Brasil de 1988 confere, como direito fundamental coletivo, o exerc\u00edcio do direito de greve, sendo vedada regulamenta\u00e7\u00e3o por lei ordin\u00e1ria.<\/p>\n<p><strong>Coment\u00e1rios: <\/strong><\/p>\n<p>Letra A: correta. \u00c9 exatamente o que prev\u00ea o art. 8\u00ba, II, CF\/88, que versa sobre o <strong><em>princ\u00edpio da unicidade sindical<\/em><\/strong>: <em>\u201c\u00e9 vedada a cria\u00e7\u00e3o de mais de uma organiza\u00e7\u00e3o sindical, em qualquer grau, representativa de categoria profissional ou econ\u00f4mica, na mesma base territorial, que ser\u00e1 definida pelos trabalhadores ou empregadores interessados, n\u00e3o podendo ser inferior \u00e0 \u00e1rea de um Munic\u00edpio\u201d. <\/em><\/p>\n<p>Letra B: errada. A S\u00famula Vinculante n\u00ba 40 trata da <strong><em>contribui\u00e7\u00e3o confederativa<\/em><\/strong>, que s\u00f3 \u00e9 exigida dos filiados ao sindicato.<\/p>\n<p>Letra C: errada. Segundo o art. 8\u00ba, VI, \u201c<em>\u00e9 <strong>obrigat\u00f3ria<\/strong> a participa\u00e7\u00e3o dos sindicatos nas negocia\u00e7\u00f5es coletivas de trabalho<\/em>\u201d.<\/p>\n<p>Letra D: errada. De fato, nas <strong><em>empresas com mais de 200 empregados<\/em><\/strong>, \u00e9 assegurada a elei\u00e7\u00e3o de um representante destes com a finalidade exclusiva de promover-lhes o entendimento direto com os empregadores. Esse representante n\u00e3o goza, todavia, de estabilidade.<\/p>\n<p>A CF\/88 veda a dispensa do empregado sindicalizado a partir do registro da <strong><em>candidatura a cargo de dire\u00e7\u00e3o ou representa\u00e7\u00e3o sindical<\/em><\/strong> e, se eleito, ainda que suplente, at\u00e9 um ano ap\u00f3s o final do mandato, salvo se cometer falta grave nos termos da lei.<\/p>\n<p>Letra E: errada. O direito de greve pode ser, sim, regulamentado por lei ordin\u00e1ria. \u00c9 o que se depreende a partir do art. 9\u00ba, \u00a7 1\u00ba, que disp\u00f5e que \u201c<em>a <strong>lei definir\u00e1<\/strong> os servi\u00e7os ou atividades essenciais e dispor\u00e1 sobre o atendimento das necessidades inadi\u00e1veis da comunidade\u201d.<\/em><\/p>\n<p>O gabarito \u00e9 a letra A.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"#_ftnref1\" name=\"_ftn1\">[1]<\/a> MENDES, Gilmar Ferreira; BRANCO, Paulo Gustavo Gonet. <strong><em>Curso de Direito Constitucional<\/em><\/strong>. 10\u00aa edi\u00e7\u00e3o. Editora Saraiva, 2011, pp. 1181-1183.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ol\u00e1, pessoal! Tudo bem? Aqui \u00e9 o Ricardo Vale, coordenador e professor do Estrat\u00e9gia Concursos. A prova de Direito Constitucional, do concurso PGFN 2015, teve 20 quest\u00f5es de alt\u00edssimo n\u00edvel. Sem d\u00favida, uma das melhores provas de Direito Constitucional que a ESAF fez nos \u00faltimos tempos. Abaixo, comento detalhadamente todas elas! Abra\u00e7os, Ricardo Vale &#8220;O [&hellip;]<\/p>\n","protected":false},"author":26,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[],"tags":[506,644],"tax_estado":[],"class_list":["post-27334","post","type-post","status-publish","format-standard","hentry","tag-direito-constitucional","tag-pgfn"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Coment\u00e1rios \u00e0 Prova de Direito Constitucional - PGFN 2015<\/title>\n<meta name=\"description\" content=\"A prova de Direito Constitucional, do concurso PGFN 2015, 20 quest\u00f5es de alt\u00edssimo n\u00edvel. Uma das melhores provas de Direito Constitucional que a ESAF fez.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-a-prova-de-direito-constitucional-pgfn-2015\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Coment\u00e1rios \u00e0 Prova de Direito Constitucional - PGFN 2015\" \/>\n<meta property=\"og:description\" content=\"A prova de Direito Constitucional, do concurso PGFN 2015, 20 quest\u00f5es de alt\u00edssimo n\u00edvel. Uma das melhores provas de Direito Constitucional que a ESAF fez.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-a-prova-de-direito-constitucional-pgfn-2015\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/rvale01\" \/>\n<meta property=\"article:published_time\" content=\"2015-09-22T05:56:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-09-22T14:42:56+00:00\" \/>\n<meta name=\"author\" content=\"Ricardo Vale\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ricardo Vale\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"40 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-a-prova-de-direito-constitucional-pgfn-2015\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-a-prova-de-direito-constitucional-pgfn-2015\/\"},\"author\":{\"name\":\"Ricardo Vale\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/c32e47dba2159cafe7796a9569a6ff7e\"},\"headline\":\"Coment\u00e1rios \u00e0 Prova de Direito Constitucional &#8211; PGFN 2015\",\"datePublished\":\"2015-09-22T05:56:02+00:00\",\"dateModified\":\"2015-09-22T14:42:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-a-prova-de-direito-constitucional-pgfn-2015\/\"},\"wordCount\":7923,\"commentCount\":4,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"keywords\":[\"Direito Constitucional\",\"PGFN\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-a-prova-de-direito-constitucional-pgfn-2015\/#respond\"]}],\"copyrightYear\":\"2015\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-a-prova-de-direito-constitucional-pgfn-2015\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-a-prova-de-direito-constitucional-pgfn-2015\/\",\"name\":\"Coment\u00e1rios \u00e0 Prova de Direito Constitucional - PGFN 2015\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"datePublished\":\"2015-09-22T05:56:02+00:00\",\"dateModified\":\"2015-09-22T14:42:56+00:00\",\"description\":\"A prova de Direito Constitucional, do concurso PGFN 2015, 20 quest\u00f5es de alt\u00edssimo n\u00edvel. Uma das melhores provas de Direito Constitucional que a ESAF fez.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-a-prova-de-direito-constitucional-pgfn-2015\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-a-prova-de-direito-constitucional-pgfn-2015\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-a-prova-de-direito-constitucional-pgfn-2015\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Coment\u00e1rios \u00e0 Prova de Direito Constitucional &#8211; PGFN 2015\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/c32e47dba2159cafe7796a9569a6ff7e\",\"name\":\"Ricardo Vale\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/e5a5658c798bb49dd53314263f59f38c192d73370fb65839a372c2ae9027be74?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e5a5658c798bb49dd53314263f59f38c192d73370fb65839a372c2ae9027be74?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e5a5658c798bb49dd53314263f59f38c192d73370fb65839a372c2ae9027be74?s=96&d=mm&r=g\",\"caption\":\"Ricardo Vale\"},\"sameAs\":[\"https:\/\/www.facebook.com\/rvale01\",\"https:\/\/x.com\/https:\/\/twitter.com\/EstratConcursos\"],\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/ricardovaleestrategiaconcursos-com-br\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Coment\u00e1rios \u00e0 Prova de Direito Constitucional - PGFN 2015","description":"A prova de Direito Constitucional, do concurso PGFN 2015, 20 quest\u00f5es de alt\u00edssimo n\u00edvel. Uma das melhores provas de Direito Constitucional que a ESAF fez.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-a-prova-de-direito-constitucional-pgfn-2015\/","og_locale":"pt_BR","og_type":"article","og_title":"Coment\u00e1rios \u00e0 Prova de Direito Constitucional - PGFN 2015","og_description":"A prova de Direito Constitucional, do concurso PGFN 2015, 20 quest\u00f5es de alt\u00edssimo n\u00edvel. Uma das melhores provas de Direito Constitucional que a ESAF fez.","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-a-prova-de-direito-constitucional-pgfn-2015\/","og_site_name":"Estrat\u00e9gia Concursos","article_author":"https:\/\/www.facebook.com\/rvale01","article_published_time":"2015-09-22T05:56:02+00:00","article_modified_time":"2015-09-22T14:42:56+00:00","author":"Ricardo Vale","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Ricardo Vale","Est. tempo de leitura":"40 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-a-prova-de-direito-constitucional-pgfn-2015\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-a-prova-de-direito-constitucional-pgfn-2015\/"},"author":{"name":"Ricardo Vale","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/c32e47dba2159cafe7796a9569a6ff7e"},"headline":"Coment\u00e1rios \u00e0 Prova de Direito Constitucional &#8211; PGFN 2015","datePublished":"2015-09-22T05:56:02+00:00","dateModified":"2015-09-22T14:42:56+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-a-prova-de-direito-constitucional-pgfn-2015\/"},"wordCount":7923,"commentCount":4,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"keywords":["Direito Constitucional","PGFN"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-a-prova-de-direito-constitucional-pgfn-2015\/#respond"]}],"copyrightYear":"2015","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-a-prova-de-direito-constitucional-pgfn-2015\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-a-prova-de-direito-constitucional-pgfn-2015\/","name":"Coment\u00e1rios \u00e0 Prova de Direito Constitucional - PGFN 2015","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"datePublished":"2015-09-22T05:56:02+00:00","dateModified":"2015-09-22T14:42:56+00:00","description":"A prova de Direito Constitucional, do concurso PGFN 2015, 20 quest\u00f5es de alt\u00edssimo n\u00edvel. Uma das melhores provas de Direito Constitucional que a ESAF fez.","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-a-prova-de-direito-constitucional-pgfn-2015\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-a-prova-de-direito-constitucional-pgfn-2015\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-a-prova-de-direito-constitucional-pgfn-2015\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Coment\u00e1rios \u00e0 Prova de Direito Constitucional &#8211; PGFN 2015"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/c32e47dba2159cafe7796a9569a6ff7e","name":"Ricardo Vale","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/e5a5658c798bb49dd53314263f59f38c192d73370fb65839a372c2ae9027be74?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e5a5658c798bb49dd53314263f59f38c192d73370fb65839a372c2ae9027be74?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e5a5658c798bb49dd53314263f59f38c192d73370fb65839a372c2ae9027be74?s=96&d=mm&r=g","caption":"Ricardo Vale"},"sameAs":["https:\/\/www.facebook.com\/rvale01","https:\/\/x.com\/https:\/\/twitter.com\/EstratConcursos"],"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/ricardovaleestrategiaconcursos-com-br\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/27334","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=27334"}],"version-history":[{"count":1,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/27334\/revisions"}],"predecessor-version":[{"id":27335,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/27334\/revisions\/27335"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=27334"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=27334"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=27334"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=27334"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}