{"id":27248,"date":"2015-09-18T21:19:52","date_gmt":"2015-09-19T00:19:52","guid":{"rendered":"http:\/\/www.estrategiaconcursos.com.br\/blog\/?p=27248"},"modified":"2016-07-22T18:16:07","modified_gmt":"2016-07-22T21:16:07","slug":"um-pouco-sobre-cpmf-nao-nao-e-o-imposto-do-cheque","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/um-pouco-sobre-cpmf-nao-nao-e-o-imposto-do-cheque\/","title":{"rendered":"Um pouco sobre CPMF (n\u00e3o, n\u00e3o \u00e9 o imposto do cheque)"},"content":{"rendered":"<p style=\"text-align: left;\">Ol\u00e1, amigas e amigos concurseiros!<\/p>\n<p>E os estudos, como andam? Sei que o momento n\u00e3o \u00e9 dos melhores e muito menos animador para quem est\u00e1 nessa luta di\u00e1ria e, muitas vezes, desgastante. As medidas anunciadas pelo Governo parecem ser um balde de \u00e1gua fria na prepara\u00e7\u00e3o de todos, e que eu sei bem como \u00e9 isso. Vivi tal momento em 2008, na prepara\u00e7\u00e3o para a RFB. Se houvesse desanimado, talvez hoje n\u00e3o estivesse escrevendo esse <em>post<\/em>.<\/p>\n<p>Embora j\u00e1 tenha virado um clich\u00ea, digo, por experi\u00eancia pr\u00f3pria, que voc\u00ea n\u00e3o desanime e que n\u00e3o abandone seus sonhos. Not\u00edcias como essas sempre ocorreram e sempre ocorrer\u00e3o. \u00c9 hora, sim, de manter o foco enquanto muitos concorrentes, no caminho contr\u00e1rio, est\u00e3o desanimando e deixando de lado um tempo importante para aprender ainda mais e fixar na cabe\u00e7a conceitos que, por sua natureza, requerem mais dedica\u00e7\u00e3o do que outros, e que podem ser decisivos na sua aprova\u00e7\u00e3o (ou n\u00e3o). Veja pelo lado bom: \u201cGanhei mais tempo para se preparar melhor. Quando o concurso dos meus sonhos chegar, uma vaga ser\u00e1 minha\u201d. For\u00e7a e foco!<\/p>\n<p>Mas o post de hoje n\u00e3o \u00e9 para falar especificamente sobre isso. No <em>post<\/em> de hoje quero falar um pouco sobre o imposto do cheque. Ops! Um minuto, deixe-me apenas desligar a TV. Willian Bonner, o cara l\u00e1 de Rede Globo de Desinforma\u00e7\u00e3o, estava falando nesse momento sobre esse tal imposto e me tirou a concentra\u00e7\u00e3o. Pronto! Agora sim.<\/p>\n<p>O post de hoje \u00e9 para falarmos um pouco dessa tal CPFM, a Contribui\u00e7\u00e3o Provis\u00f3ria sobre Movimenta\u00e7\u00e3o Financeira, vulgo, imposto do cheque, tanto veiculada na m\u00eddia escrita e falada nesses \u00faltimos dias e um dos carros-chefes da pol\u00edtica a ser possivelmente adotada pelo Governo na busca pela estabiliza\u00e7\u00e3o das contas do nosso pa\u00eds.<\/p>\n<p>Antes de tudo, imposto sobre o cheque, ainda que fosse v\u00e1lida essa nomenclatura, como iremos mostrar mais adiante, \u00e9 um tanto restritiva. E bem restritiva eu diria. A CPMF incide sobre uma diversidade de opera\u00e7\u00f5es, e n\u00e3o apenas sobre opera\u00e7\u00f5es com cheque, que, imagino eu, j\u00e1 tenha entrado na lista dos \u201cbichos\u201d amea\u00e7ados de extin\u00e7\u00e3o.<\/p>\n<p>Ao menos na minha humilde realidade, \u00e9 mais f\u00e1cil eu ver um mico le\u00e3o-dourado vestido com roupa de baiana em pleno Parque do Taim do que uma folha de cheque. Se voc\u00eas costumam v\u00ea-lo, pe\u00e7o-lhes desculpas pela minha desinforma\u00e7\u00e3o.<\/p>\n<p>Inicialmente, CPMF significa contribui\u00e7\u00e3o provis\u00f3ria sobre movimenta\u00e7\u00e3o ou transmiss\u00e3o de valores e de cr\u00e9ditos e direitos de natureza financeira. \u00c9 (ou era) uma contribui\u00e7\u00e3o destinada especialmente, e em teoria, ao financiamento da seguridade social, conforme estabelece ao artigo 84, \u00a72\u00ba, do ADCT. Foi utilizada tamb\u00e9m para o financiamento da sa\u00fade e como uma das fontes de aporte de recursos ao Fundo de Combate \u00e0 Pobreza e Erradica\u00e7\u00e3o da Pobreza. Inicialmente, por\u00e9m, ela foi institu\u00edda para financiar apenas a sa\u00fade, sendo o produto da sua arrecada\u00e7\u00e3o integralmente destinada ao Fundo Nacional de Sa\u00fade, para financiamento das a\u00e7\u00f5es e servi\u00e7os de sa\u00fade, conforme o artigo 74 do ADCT.<\/p>\n<p>A institui\u00e7\u00e3o da CPMF foi autorizada em raz\u00e3o da publica\u00e7\u00e3o da Emenda Constitucional n\u00ba 12, de 1996, conferindo a compet\u00eancia tribut\u00e1ria \u00e0 Uni\u00e3o, \u00fanico ente pol\u00edtico competente para tanto, conforme o artigo 74, caput, do ADCT.<\/p>\n<p>A al\u00edquota inicial do tributo era de, no m\u00e1ximo, 0,25%, conforme viesse a ser estipulado pela Uni\u00e3o ao editar a lei respectiva, sendo facultado ao Poder Executivo reduzi-la ou restabelec\u00ea-la, total ou parcialmente, nas condi\u00e7\u00f5es e limites fixados em lei. Ou seja, o tributo era uma exce\u00e7\u00e3o ao princ\u00edpio da legalidade quanto \u00e0 redu\u00e7\u00e3o e reestabelecimento de suas al\u00edquotas, n\u00e3o podendo, entretanto, superar o limite de 0,25%. Essa \u00e9 a reda\u00e7\u00e3o do artigo 74, \u00a71\u00ba, do ADCT da CF\/88.<\/p>\n<p>E qual a lei a ser utilizada pela Uni\u00e3o ao instituir o novo tributo? Conforme o artigo 74, \u00a72\u00ba, do ADCT, essa lei poderia ser de natureza ordin\u00e1ria, n\u00e3o sendo exigida a utiliza\u00e7\u00e3o de lei complementar para tanto. Conforme esse par\u00e1grafo, \u00e0 CPMF n\u00e3o seria aplicado o disposto nos artigos 153, \u00a75\u00ba, e 154, I, da CF\/88.<\/p>\n<p>A n\u00e3o exig\u00eancia de lei complementar para a cria\u00e7\u00e3o do tributo se d\u00e1 em raz\u00e3o do que consta no artigo 154, I, da CF\/88, estabelecendo ainda que o tributo n\u00e3o precisar\u00e1 ser n\u00e3o-cumulativo (ou seja, poderia ser cumulativo), podendo ainda ser adotado pelo legislador federal fato gerador ou base de c\u00e1lculo j\u00e1 previstos para outro tributo presente no texto da CF\/88, em especial o IOF, tributo a que se refere o artigo 153, \u00a75\u00ba, da CF\/88, relativamente ao ouro na qualidade de ativo financeiro ou instrumento cambial.<\/p>\n<p>Logo, a CPMF a ser institu\u00edda pela Uni\u00e3o poderia incidir, normalmente, sobre as opera\u00e7\u00f5es com ouro definidas em lei como ativo financeiro ou instrumento cambial, n\u00e3o obstante a incid\u00eancia do IOF sobre a mesma opera\u00e7\u00e3o, sendo uma modalidade de bis in iden constitucionalmente permitida.<\/p>\n<p>Por sua vez, conforme o artigo 74, \u00a74\u00ba, do ADCT, a CPMF, ao ser institu\u00edda, estaria sujeita ao disposto no artigo 195, \u00a76\u00ba, da CF\/88, ou seja, ao princ\u00edpio da noventena, somente podendo ser cobrada depois de decorridos noventa dias da data da publica\u00e7\u00e3o da lei que a houver institu\u00eddo. Al\u00e9m disso, aquele normativo estabeleceu ainda que o prazo m\u00e1ximo de cobran\u00e7a do novo tributo seria de dois anos.<\/p>\n<p>Diante da sua nova compet\u00eancia tribut\u00e1ria, a Uni\u00e3o, por meio da lei ordin\u00e1ria n\u00ba 9.311, de 24 de outubro de 1996, instituiu a CPMF, com al\u00edquota inicial de 0,20%, tendo como fato gerador as seguintes situa\u00e7\u00f5es:<\/p>\n<ul>\n<li>o lan\u00e7amento a d\u00e9bito, por institui\u00e7\u00e3o financeira, em contas correntes de dep\u00f3sito, em contas correntes de empr\u00e9stimo, em contas de dep\u00f3sito de poupan\u00e7a, de dep\u00f3sito judicial e de dep\u00f3sitos em consigna\u00e7\u00e3o de pagamento de que tratam os par\u00e1grafos do art. 890 da Lei n\u00b0 5.869, de 11 de janeiro de 1973, introduzidos pelo art. 1\u00b0 da Lei n\u00b0 8.951, de 13 de dezembro de 1994, junto a ela mantidas;<\/li>\n<li>o lan\u00e7amento a cr\u00e9dito, por institui\u00e7\u00e3o financeira, em contas correntes que apresentem saldo negativo, at\u00e9 o limite de valor da redu\u00e7\u00e3o do saldo devedor;<\/li>\n<li>a liquida\u00e7\u00e3o ou pagamento, por institui\u00e7\u00e3o financeira, de quaisquer cr\u00e9ditos, direitos ou valores, por conta e ordem de terceiros, que n\u00e3o tenham sido creditados, em nome do benefici\u00e1rio, nas contas referidas nos incisos anteriores;<\/li>\n<li>o lan\u00e7amento, e qualquer outra forma de movimenta\u00e7\u00e3o ou transmiss\u00e3o de valores e de cr\u00e9ditos e direitos de natureza financeira, n\u00e3o relacionados nos incisos anteriores, efetuados pelos bancos comerciais, bancos m\u00faltiplos com carteira comercial e caixas econ\u00f4micas;<\/li>\n<li>a liquida\u00e7\u00e3o de opera\u00e7\u00e3o contratadas nos mercados organizados de liquida\u00e7\u00e3o futura;<\/li>\n<li>qualquer outra movimenta\u00e7\u00e3o ou transmiss\u00e3o de valores e de cr\u00e9ditos e direitos de natureza financeira que, por sua finalidade, reunindo caracter\u00edsticas que permitam presumir a exist\u00eancia de sistema organizado para efetiv\u00e1-la, produza os mesmos efeitos previstos nos incisos anteriores, independentemente da pessoa que a efetue, da denomina\u00e7\u00e3o que possa ter e da forma jur\u00eddica ou dos instrumentos utilizados para realiz\u00e1-la.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Em contrapartida, a CPMF n\u00e3o incidiria:<\/p>\n<ul>\n<li>no lan\u00e7amento nas contas da Uni\u00e3o, dos Estados, do Distrito Federal, dos Munic\u00edpios, de suas autarquias e funda\u00e7\u00f5es;<\/li>\n<li>no lan\u00e7amento errado e seu respectivo estorno, desde que n\u00e3o caracterizem a anula\u00e7\u00e3o de opera\u00e7\u00e3o efetivamente contratada, bem como no lan\u00e7amento de cheque e documento compens\u00e1vel, e seu respectivo estorno, devolvidos em conformidade com as normas do Banco Central do Brasil;<\/li>\n<li>no lan\u00e7amento para pagamento da pr\u00f3pria contribui\u00e7\u00e3o;<\/li>\n<li>nos saques efetuados diretamente nas contas vinculadas do Fundo de Garantia do Tempo de Servi\u00e7o &#8211; FGTS e do Fundo de Participa\u00e7\u00e3o PIS\/PASEP e no saque do valor do benef\u00edcio do seguro-desemprego, pago de acordo com os crit\u00e9rios previstos no art. 5\u00ba da Lei n\u00b0 7.998, de 11 de janeiro de 1990;<\/li>\n<li>sobre a movimenta\u00e7\u00e3o financeira ou transmiss\u00e3o de valores e de cr\u00e9ditos e direitos de natureza financeira das entidades beneficentes de assist\u00eancia social, nos termos do \u00a7 7\u00b0 do art. 195 da Constitui\u00e7\u00e3o Federal.<\/li>\n<li>nos lan\u00e7amentos a d\u00e9bito nas contas-correntes de dep\u00f3sito cujos titulares sejam: miss\u00f5es diplom\u00e1ticas; reparti\u00e7\u00f5es consulares de carreira; representa\u00e7\u00f5es de organismos internacionais e regionais de car\u00e1ter permanente, de que o Brasil seja membro; funcion\u00e1rio estrangeiro de miss\u00e3o diplom\u00e1tica ou representa\u00e7\u00e3o consular; funcion\u00e1rio estrangeiro de organismo internacional que goze de privil\u00e9gios ou isen\u00e7\u00f5es tribut\u00e1rias em virtude de acordo firmado com o Brasil.<\/li>\n<\/ul>\n<p>Como se observa em sua nomenclatura, a CPMF n\u00e3o incidia apenas sobre opera\u00e7\u00f5es com cheques, e sim sobre diversos tipos de movimenta\u00e7\u00f5es financeiras, exceto nos casos previstos expressamente nos artigos da mesma ADCT.<\/p>\n<p>Como base de c\u00e1lculo, a CPMF, conforme o caso, tinha como tais o valor do lan\u00e7amento e de qualquer outra forma de movimenta\u00e7\u00e3o ou\u00a0\u00a0\u00a0\u00a0 transmiss\u00e3o; o valor da liquida\u00e7\u00e3o ou do pagamento; o resultado, se negativo, da soma alg\u00e9brica dos ajustes di\u00e1rios ocorridos no per\u00edodo compreendido entre a contrata\u00e7\u00e3o inicial e a liquida\u00e7\u00e3o do contrato; ou o valor da movimenta\u00e7\u00e3o ou da transmiss\u00e3o.<\/p>\n<p>Conforme o artigo 18 da lei federal, o produto da arrecada\u00e7\u00e3o da CPMF deveria ser destinado integralmente ao Fundo Nacional de Sa\u00fade, para financiamento das a\u00e7\u00f5es e servi\u00e7os de sa\u00fade, sendo que sua entrega obedecer\u00e1 aos prazos e condi\u00e7\u00f5es estabelecidos para as transfer\u00eancias de que trata o artigo 159 da CF\/88, ficando vedada a utiliza\u00e7\u00e3o dos recursos arrecadados em pagamento de servi\u00e7os prestados pelas institui\u00e7\u00f5es hospitalares com finalidade lucrativa.<\/p>\n<p>Em outra linha, coube \u00e0 Receita Federal do Brasil, \u00e0 \u00e9poca ainda denominada de Secretaria da Receita Federal, a administra\u00e7\u00e3o da contribui\u00e7\u00e3o, inclu\u00eddas as atividades de tributa\u00e7\u00e3o, fiscaliza\u00e7\u00e3o e arrecada\u00e7\u00e3o do tributo, que poderia requisitar ou proceder ao exame de documentos, livros e registros, bem como estabelecer obriga\u00e7\u00f5es acess\u00f3rias.<\/p>\n<p>Uma vez que a dura\u00e7\u00e3o m\u00e1xima da cobran\u00e7a da CPMF era de dois anos, conforme afirmava o texto do caput do artigo 74 do ADCT, somente com outra altera\u00e7\u00e3o do texto constitucional o tributo poderia ser novamente cobrado. E foi o que aconteceu.<\/p>\n<p>Em 18 de mar\u00e7o de 1999 foi publicada a Emenda Constitucional n\u00ba 21, incluindo o artigo 75 ao ADCT e prorrogando a vig\u00eancia da lei federal n\u00ba 9.311, de 1996, por mais tr\u00eas anos. Esse novo artigo 75 estipulou ainda que a nova al\u00edquota m\u00e1xima da contribui\u00e7\u00e3o seria de 0,38%, nos primeiros doze meses, e de 0,30%, nos meses subsequentes, facultado ao Poder Executivo reduzi-la total ou parcialmente, nos limites definidos no texto da EC n\u00ba 21\/96. Ou seja, a CPMF seria cobrada, novamente, at\u00e9 o ano 2002.<\/p>\n<p>O \u00a72\u00ba do artigo 75 do ADCT estabelecia ainda que o resultado do aumento da arrecada\u00e7\u00e3o, decorrente da altera\u00e7\u00e3o da al\u00edquota, nos exerc\u00edcios financeiros de 1999, 2000 e 2001, seria destinado ao custeio da previd\u00eancia social.<\/p>\n<p>Ou seja, tudo aquilo que fosse arrecadado em raz\u00e3o da diferen\u00e7a entre os percentuais utilizados anteriormente, no montante de 0,20%, conforme a lei federal n\u00ba 9.311, de 1996, e o percentual atual, de 0,38% e 0,30%, conforme o per\u00edodo, seria destinado \u00e0 previd\u00eancia social. Assim, a CPMF passou a financiar tanto a sa\u00fade quanto a previd\u00eancia social, duas das tr\u00eas vertentes da seguridade social.<\/p>\n<p>Em 2002, findou-se novamente o prazo de cobran\u00e7a da CPMF. Entretanto, com a publica\u00e7\u00e3o da emenda constitucional n\u00ba 37, de 2002, a CPMF passou a ser cobrada at\u00e9 o dia 31 de dezembro de 2004, tendo em vista o artigo 84 do ADCT, acrescentado por esse EC ao texto da CF\/88. Na oportunidade, ficou prorrogada tamb\u00e9m a vig\u00eancia da lei federal n\u00ba 9.311, de 1996.<\/p>\n<p>Conforme o \u00a72\u00ba do artigo 84 do ADCT, do produto da arrecada\u00e7\u00e3o da contribui\u00e7\u00e3o social de que trata este artigo ser\u00e1 destinada a parcela correspondente \u00e0 al\u00edquota de:<\/p>\n<ul>\n<li>0,20% ao Fundo Nacional de Sa\u00fade, para financiamento das a\u00e7\u00f5es e servi\u00e7os de sa\u00fade;<\/li>\n<li>0,10% ao custeio da previd\u00eancia social;<\/li>\n<li>0,08% ao Fundo de Combate e Erradica\u00e7\u00e3o da Pobreza, de que tratam os artigos 80 e 81 deste Ato das Disposi\u00e7\u00f5es Constitucionais Transit\u00f3rias (mais uma destina\u00e7\u00e3o a ser dada ao produto da arrecada\u00e7\u00e3o da CPMF).<\/li>\n<\/ul>\n<p>A al\u00edquota, por sua vez, foi fixada em 0,38%, conforme o \u00a73\u00ba do mesmo artigo, cabendo ao \u00a74\u00ba estipular os casos em que a CPMF n\u00e3o poderia incidir, tendo como exemplo os lan\u00e7amentos em contas correntes de dep\u00f3sito, relativos a opera\u00e7\u00f5es de compra e venda de a\u00e7\u00f5es, realizadas em recintos ou sistemas de negocia\u00e7\u00e3o de bolsas de valores e no mercado de balc\u00e3o organizado; e a contratos referenciados em a\u00e7\u00f5es ou \u00edndices de a\u00e7\u00f5es, em suas diversas modalidades, negociados em bolsas de valores, de mercadorias e de futuros.<\/p>\n<p>Mais uma vez, findando o prazo estipulado na EC n\u00ba 37, de 2002, o Congresso Nacional editou outra EC, dessa vez a de n\u00ba 42, de 19 de dezembro de 2003, acrescentando o artigo 90 ao ADCT, autorizando a cobran\u00e7a do tributo at\u00e9 31 de dezembro de 2007 e prorrogando, por consequ\u00eancia, a vig\u00eancia da lei n\u00ba 9.311, de 1996. Na oportunidade, manteve a al\u00edquota do tributo em 0,38%. E n\u00e3o houve mais prorroga\u00e7\u00f5es. (UFA!!)<\/p>\n<p>N\u00e3o obstante o nosso \u201cquerido\u201d Bonner, bem como outros meios de comunica\u00e7\u00e3o, se referirem ao tributo como um imposto, a utiliza\u00e7\u00e3o desse termo tem um fundo hist\u00f3rico, uma vez que a CPMF substituiu o antigo imposto sobre provis\u00f3rio sobre movimenta\u00e7\u00e3o financeira (IPMF), o pai da CPMF, os quais guardam \u201cla\u00e7os tributo-sangu\u00edneos\u201d.<\/p>\n<p>O IPMF foi criado em 1993, tendo vigorado durante todo o ano-calend\u00e1rio 1994, \u00e9poca da implementa\u00e7\u00e3o do Plano Real e de vig\u00eancia da chamada URV (Unidade Real de Valor). Sua al\u00edquota era de 0,25%, e incidia, em s\u00edntese, sobre as opera\u00e7\u00f5es de lan\u00e7amento efetuadas em contas mantidas por institui\u00e7\u00f5es financeiras e sobre as transa\u00e7\u00f5es gerais efetuadas na economia utilizando essas institui\u00e7\u00f5es. O IPMF foi institu\u00eddo pela lei complementar n\u00ba 77, de 13 de julho de 1993.<\/p>\n<p><em>\u201cE \u00e9 verdade que a CPMF \u00e9 um bom instrumento para combater a corrup\u00e7\u00e3o, a lavagem de dinheiro e outros il\u00edcitos, tribut\u00e1rios ou n\u00e3o, como eu j\u00e1 li em alguns lugares?\u201d<\/em><\/p>\n<p>Mais ou menos. E essa parece ser tamb\u00e9m uma das principais bandeiras daqueles que apoiam a volta da cobran\u00e7a do tributo. Contudo, na minha opini\u00e3o a CPMF n\u00e3o vai acabar ou reduzir sobremaneira quaisquer tipos de il\u00edcitos praticados junto ao sistema financeiro, que continuar\u00e3o a existir e a necessitar da interven\u00e7\u00e3o do poder p\u00fablico para serem combatidas, especialmente conferindo prerrogativas e poderes \u00e0s autoridades, especialmente \u00e0s fiscais e \u00e0s policiais.<\/p>\n<p>Tributadas ou n\u00e3o, as movimenta\u00e7\u00f5es financeiras, atualmente, s\u00e3o efetuadas sob o manto de sistemas de inform\u00e1tica cada vez mais complexos, que registram e monitoram as opera\u00e7\u00f5es e movimenta\u00e7\u00e3o financeiras efetuadas no territ\u00f3rio nacional e aquelas praticadas com agentes financeiros situados no exterior.<\/p>\n<p>Ora, para que uma opera\u00e7\u00e3o financeira venha a ser realizada junto ao sistema financeiro, atualmente, em alguma parte dele (sen\u00e3o em todas as etapas) haver\u00e1 a interven\u00e7\u00e3o de um computador ou de um sistema computacional. Sendo identificada a opera\u00e7\u00e3o que se encaixa na base de incid\u00eancia da CPMF, e supondo-se que essa esteja em cobran\u00e7a novamente, haver\u00e1 normalmente a tributa\u00e7\u00e3o com o \u201cimposto\u201d, e de forma autom\u00e1tica.<\/p>\n<p>De um jeito ou de outro, a opera\u00e7\u00e3o ser\u00e1 monitorada, e, num sistema onde n\u00e3o haja manipula\u00e7\u00e3o dos dados e\/ou corrup\u00e7\u00e3o daqueles que o gerenciam, a opera\u00e7\u00e3o poder\u00e1 ser facilmente identificada. O fato de haver tributa\u00e7\u00e3o ou n\u00e3o, repito, n\u00e3o influencia em quase nada a pr\u00e1tica de il\u00edcitos, especialmente os tribut\u00e1rios.<\/p>\n<p>O que poderia garantir maior efetividade contra a pr\u00e1tica de il\u00edcitos, sim, repito, \u00e9 a exist\u00eancia de autoridades, fiscais ou n\u00e3o, monitorando essas atividades, inclusive sobre aquelas opera\u00e7\u00f5es que, em raz\u00e3o da sua natureza, n\u00e3o sofrem tributa\u00e7\u00e3o.<\/p>\n<p>Por\u00e9m, afirmar que a CPMF vai gravar ainda mais as grandes fortunas transacionadas nos sistemas financeiros, nisso eu concordo. Arrisco-me a dizer que, em certo ponto, com uma efici\u00eancia maior do que o imposto sobre a renda, uma vez que tributou (e poder\u00e1 vir a tributar novamente) a movimenta\u00e7\u00e3o de riqueza nos sistemas financeiros proporcionalmente ao seu montante. Quanto maior o valor transacionado, maior o aporte tribut\u00e1rio para os cofres p\u00fablicos, diga-se, aos da Uni\u00e3o.<\/p>\n<p>Contudo, muito se fala no aumento da carga tribut\u00e1ria. Claro que, uma nova imposi\u00e7\u00e3o tribut\u00e1ria, por obvio, aumenta a carga tribut\u00e1ria. Mas o que se quer vender \u00e9 que isso onerar\u00e1 sobremaneira toda a popula\u00e7\u00e3o, o que n\u00e3o \u00e9 verdade, j\u00e1 que uma maioria esmagadora sequer se utiliza do sistema financeiro, e quando participa, o faz em montantes individualmente pequenos ou irris\u00f3rios.<\/p>\n<p>Para fins de exemplo, uma transa\u00e7\u00e3o de R$ 100,00 iria gerar, de CPMF, o montante de R$ 0,38. Em uma de R$ 1.000,00, R$ 3,80. O que s\u00e3o R$ 380,00 num montante de R$ 1.000.000,00? Ou seja, a nova cobran\u00e7a da CPMF atinge em cheio as grandes fortunas transacionadas no sistema financeiro, e sobre as quais, via de regra, n\u00e3o h\u00e1 uma tributa\u00e7\u00e3o condizente.<\/p>\n<p>Concordo que a popula\u00e7\u00e3o n\u00e3o deve pagar pelos desajustes oriundos dos seus governantes, tendo por consequ\u00eancia a cobran\u00e7a de mais um tributo, n\u00e3o obstante o que comentei, mas justificar o n\u00e3o cobran\u00e7a com vi\u00e9s tamb\u00e9m n\u00e3o acho correto. A defesa n\u00e3o cobran\u00e7a \u00e9 oriunda, sobretudo, daqueles que mais possuem recursos e os transacionam no mercado financeiros, licitamente ou n\u00e3o. Isso \u00e9 apenas uma opini\u00e3o particular, sem qualquer inten\u00e7\u00e3o de estabelecer\u00a0 a verdade absoluta, ok? Na pior das hip\u00f3teses, fique apenas com aquilo que for ser realmente \u00fatil para a sua prova, caso esse tema venha a um dia ser cobrado.<\/p>\n<p>Por hoje \u00e9 \u201cs\u00f3\u201d, pessoal! At\u00e9 a pr\u00f3xima.<\/p>\n<p>Grande abra\u00e7o e bons estudos!<\/p>\n<p style=\"text-align: center;\"><a href=\"mailto:aluisioalneto@gmail.com\">aluisioalneto@gmail.com<\/a><\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.facebook.com\/aluisioalneto\">www.facebook.com\/aluisioalneto<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ol\u00e1, amigas e amigos concurseiros! E os estudos, como andam? Sei que o momento n\u00e3o \u00e9 dos melhores e muito menos animador para quem est\u00e1 nessa luta di\u00e1ria e, muitas vezes, desgastante. As medidas anunciadas pelo Governo parecem ser um balde de \u00e1gua fria na prepara\u00e7\u00e3o de todos, e que eu sei bem como \u00e9 [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1,1988],"tags":[1006],"tax_estado":[],"class_list":["post-27248","post","type-post","status-publish","format-standard","hentry","category-cursos-e-concursos","category-policia","tag-cpmf"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Um pouco sobre CPMF (n\u00e3o, n\u00e3o \u00e9 o imposto do cheque)<\/title>\n<meta name=\"description\" content=\"Um pouco dessa tal CPFM, a Contribui\u00e7\u00e3o Provis\u00f3ria sobre Movimenta\u00e7\u00e3o Financeira, vulgo, imposto do cheque, tanto veiculada na m\u00eddia escrita.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/um-pouco-sobre-cpmf-nao-nao-e-o-imposto-do-cheque\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Um pouco sobre CPMF (n\u00e3o, n\u00e3o \u00e9 o imposto do cheque)\" \/>\n<meta property=\"og:description\" content=\"Um pouco dessa tal CPFM, a Contribui\u00e7\u00e3o Provis\u00f3ria sobre Movimenta\u00e7\u00e3o Financeira, vulgo, imposto do cheque, tanto veiculada na m\u00eddia escrita.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/um-pouco-sobre-cpmf-nao-nao-e-o-imposto-do-cheque\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:author\" content=\"http:\/\/www.facebook.com\/aluisioalneto\" \/>\n<meta property=\"article:published_time\" content=\"2015-09-19T00:19:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-07-22T21:16:07+00:00\" \/>\n<meta name=\"author\" content=\"Aluisio Neto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Aluisio Neto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"15 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/um-pouco-sobre-cpmf-nao-nao-e-o-imposto-do-cheque\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/um-pouco-sobre-cpmf-nao-nao-e-o-imposto-do-cheque\/\"},\"author\":{\"name\":\"Aluisio Neto\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/ffa88acf2785fd114e519e068a27ca9e\"},\"headline\":\"Um pouco sobre CPMF (n\u00e3o, n\u00e3o \u00e9 o imposto do cheque)\",\"datePublished\":\"2015-09-19T00:19:52+00:00\",\"dateModified\":\"2016-07-22T21:16:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/um-pouco-sobre-cpmf-nao-nao-e-o-imposto-do-cheque\/\"},\"wordCount\":3111,\"commentCount\":9,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"keywords\":[\"CPMF\"],\"articleSection\":[\"Concursos P\u00fablicos\",\"Policial (Agente, Escriv\u00e3o e Investigador)\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/um-pouco-sobre-cpmf-nao-nao-e-o-imposto-do-cheque\/#respond\"]}],\"copyrightYear\":\"2015\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/um-pouco-sobre-cpmf-nao-nao-e-o-imposto-do-cheque\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/um-pouco-sobre-cpmf-nao-nao-e-o-imposto-do-cheque\/\",\"name\":\"Um pouco sobre CPMF (n\u00e3o, n\u00e3o \u00e9 o imposto do cheque)\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"datePublished\":\"2015-09-19T00:19:52+00:00\",\"dateModified\":\"2016-07-22T21:16:07+00:00\",\"description\":\"Um pouco dessa tal CPFM, a Contribui\u00e7\u00e3o Provis\u00f3ria sobre Movimenta\u00e7\u00e3o Financeira, vulgo, imposto do cheque, tanto veiculada na m\u00eddia escrita.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/um-pouco-sobre-cpmf-nao-nao-e-o-imposto-do-cheque\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/um-pouco-sobre-cpmf-nao-nao-e-o-imposto-do-cheque\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/um-pouco-sobre-cpmf-nao-nao-e-o-imposto-do-cheque\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Um pouco sobre CPMF (n\u00e3o, n\u00e3o \u00e9 o imposto do cheque)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/ffa88acf2785fd114e519e068a27ca9e\",\"name\":\"Aluisio Neto\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/5e333cb4a6d2e4dee8f33229d897634efd36084098a6da40059f6aa20b1c6dc2?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5e333cb4a6d2e4dee8f33229d897634efd36084098a6da40059f6aa20b1c6dc2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5e333cb4a6d2e4dee8f33229d897634efd36084098a6da40059f6aa20b1c6dc2?s=96&d=mm&r=g\",\"caption\":\"Aluisio Neto\"},\"sameAs\":[\"http:\/\/www.facebook.com\/aluisioalneto\"],\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/aluisionetoestrategiaconcursos-com-br\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Um pouco sobre CPMF (n\u00e3o, n\u00e3o \u00e9 o imposto do cheque)","description":"Um pouco dessa tal CPFM, a Contribui\u00e7\u00e3o Provis\u00f3ria sobre Movimenta\u00e7\u00e3o Financeira, vulgo, imposto do cheque, tanto veiculada na m\u00eddia escrita.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/um-pouco-sobre-cpmf-nao-nao-e-o-imposto-do-cheque\/","og_locale":"pt_BR","og_type":"article","og_title":"Um pouco sobre CPMF (n\u00e3o, n\u00e3o \u00e9 o imposto do cheque)","og_description":"Um pouco dessa tal CPFM, a Contribui\u00e7\u00e3o Provis\u00f3ria sobre Movimenta\u00e7\u00e3o Financeira, vulgo, imposto do cheque, tanto veiculada na m\u00eddia escrita.","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/um-pouco-sobre-cpmf-nao-nao-e-o-imposto-do-cheque\/","og_site_name":"Estrat\u00e9gia Concursos","article_author":"http:\/\/www.facebook.com\/aluisioalneto","article_published_time":"2015-09-19T00:19:52+00:00","article_modified_time":"2016-07-22T21:16:07+00:00","author":"Aluisio Neto","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Aluisio Neto","Est. tempo de leitura":"15 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/um-pouco-sobre-cpmf-nao-nao-e-o-imposto-do-cheque\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/um-pouco-sobre-cpmf-nao-nao-e-o-imposto-do-cheque\/"},"author":{"name":"Aluisio Neto","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/ffa88acf2785fd114e519e068a27ca9e"},"headline":"Um pouco sobre CPMF (n\u00e3o, n\u00e3o \u00e9 o imposto do cheque)","datePublished":"2015-09-19T00:19:52+00:00","dateModified":"2016-07-22T21:16:07+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/um-pouco-sobre-cpmf-nao-nao-e-o-imposto-do-cheque\/"},"wordCount":3111,"commentCount":9,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"keywords":["CPMF"],"articleSection":["Concursos P\u00fablicos","Policial (Agente, Escriv\u00e3o e Investigador)"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/um-pouco-sobre-cpmf-nao-nao-e-o-imposto-do-cheque\/#respond"]}],"copyrightYear":"2015","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/um-pouco-sobre-cpmf-nao-nao-e-o-imposto-do-cheque\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/um-pouco-sobre-cpmf-nao-nao-e-o-imposto-do-cheque\/","name":"Um pouco sobre CPMF (n\u00e3o, n\u00e3o \u00e9 o imposto do cheque)","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"datePublished":"2015-09-19T00:19:52+00:00","dateModified":"2016-07-22T21:16:07+00:00","description":"Um pouco dessa tal CPFM, a Contribui\u00e7\u00e3o Provis\u00f3ria sobre Movimenta\u00e7\u00e3o Financeira, vulgo, imposto do cheque, tanto veiculada na m\u00eddia escrita.","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/um-pouco-sobre-cpmf-nao-nao-e-o-imposto-do-cheque\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/um-pouco-sobre-cpmf-nao-nao-e-o-imposto-do-cheque\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/um-pouco-sobre-cpmf-nao-nao-e-o-imposto-do-cheque\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Um pouco sobre CPMF (n\u00e3o, n\u00e3o \u00e9 o imposto do cheque)"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/ffa88acf2785fd114e519e068a27ca9e","name":"Aluisio Neto","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/5e333cb4a6d2e4dee8f33229d897634efd36084098a6da40059f6aa20b1c6dc2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5e333cb4a6d2e4dee8f33229d897634efd36084098a6da40059f6aa20b1c6dc2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5e333cb4a6d2e4dee8f33229d897634efd36084098a6da40059f6aa20b1c6dc2?s=96&d=mm&r=g","caption":"Aluisio Neto"},"sameAs":["http:\/\/www.facebook.com\/aluisioalneto"],"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/aluisionetoestrategiaconcursos-com-br\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/27248","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=27248"}],"version-history":[{"count":2,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/27248\/revisions"}],"predecessor-version":[{"id":27355,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/27248\/revisions\/27355"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=27248"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=27248"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=27248"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=27248"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}