{"id":25165,"date":"2015-08-03T11:31:23","date_gmt":"2015-08-03T14:31:23","guid":{"rendered":"http:\/\/www.estrategiaconcursos.com.br\/blog\/?p=25165"},"modified":"2015-08-03T17:59:00","modified_gmt":"2015-08-03T20:59:00","slug":"divulgados-provas-e-gabaritos-preliminares-do-concurso-petrobras-para-o-cargo-de-advogado-saiba-mais","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/divulgados-provas-e-gabaritos-preliminares-do-concurso-petrobras-para-o-cargo-de-advogado-saiba-mais\/","title":{"rendered":"Divulgados provas e gabaritos preliminares do concurso Petrobras para o cargo de Advogado. Confira!"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><a href=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2014\/06\/petrobras.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-16384 size-medium\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2014\/06\/petrobras-300x63.jpg\" alt=\"concurso petrobras\" width=\"300\" height=\"63\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2014\/06\/petrobras.jpg 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2014\/06\/petrobras.jpg 1024w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2014\/06\/petrobras.jpg 500w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Foram divulgados nesta segunda-feira, 03, as provas e os gabaritos preliminares do\u00a0concurso Petrobras para o cargo de Advogado.\u00a0O candidato poder\u00e1 apresentar recursos quanto aos conte\u00fados das quest\u00f5es objetivas e\/ou aos gabaritos divulgados, desde que devidamente fundamentados e encaminhados nos dias 03 e 04 de agosto, pelo site da organizadora, a Funda\u00e7\u00e3o <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"http:\/\/www.cesgranrio.org.br\/concursos\/evento.aspx?id=petrobras0115\">Cesgranrio<\/a><\/span>.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Confira as provas e os gabaritos preliminares em:<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"http:\/\/www.cesgranrio.org.br\/concursos\/evento.aspx?id=petrobras0115\">http:\/\/www.cesgranrio.org.br\/concursos\/evento.aspx?id=petrobras0115<\/a><\/span><\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"color: #000000;\">Concurso\u00a0Petrobras para o cargo de Advogado<\/span><\/strong><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">O\u00a0concurso Petrobras para o cargo de Advogado oferece\u00a0158 vagas \u2013 sendo\u00a013 vagas imediatas e 145 para forma\u00e7\u00e3o de cadastro de reserva.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Os candidatos devem ter n\u00edvel superior em direito reconhecido pelo Minist\u00e9rio da Educa\u00e7\u00e3o, secretarias ou conselhos estaduais de educa\u00e7\u00e3o e registro definitivo na Ordem dos Advogados do Brasil (OAB).\u00a0As vagas s\u00e3o para os polos de Bras\u00edlia, estado do Amazonas, Rio de Janeiro e Salvador.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Entre as atividades dos advogados na Petrobras est\u00e3o acompanhar, participar e elaborar documentos e pe\u00e7as processuais jur\u00eddicas, fazer estudos especializados sobre temas e problemas jur\u00eddicos necess\u00e1rios \u00e0 defesa dos interesses da Petrobras, segundo a legisla\u00e7\u00e3o e a norma vigentes.Os advogados tamb\u00e9m representam a Petrobras diante de autoridades administrativas e o Poder Judici\u00e1rio, em quest\u00f5es jur\u00eddicas, nas causas que lhe s\u00e3o atribu\u00eddas.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">O concurso Petrobras\u00a0ter\u00e1 validade de 6 meses e poder\u00e1 ser prorrogado, uma vez, por igual per\u00edodo.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>Os professores do Estrat\u00e9gia Concursos comentar\u00e3o, em seus artigos, sobre possibilidades de recurso. Acompanhe em:<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"http:\/\/www.estrategiaconcursos.com.br\/blog\/\">http:\/\/www.estrategiaconcursos.com.br\/blog\/<\/a><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Assessoria de Comunica\u00e7\u00e3o<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">comunicacao@estrategiaconcursos.com.br<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Foram divulgados nesta segunda-feira, 03, as provas e os gabaritos preliminares do\u00a0concurso Petrobras para o cargo de Advogado.\u00a0O candidato poder\u00e1 apresentar recursos quanto aos conte\u00fados das quest\u00f5es objetivas e\/ou aos gabaritos divulgados, desde que devidamente fundamentados e encaminhados nos dias 03 e 04 de agosto, pelo site da organizadora, a Funda\u00e7\u00e3o Cesgranrio. Confira as provas [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"news","footnotes":""},"categories":[],"tags":[762,697,712],"tax_estado":[],"class_list":["post-25165","post","type-post","status-publish","format-standard","hentry","tag-advogado-da-petrobras","tag-gabaritos","tag-provas"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Divulgados provas e gabaritos preliminares do concurso Petrobras para o cargo de Advogado. Confira!<\/title>\n<meta name=\"description\" content=\"Foram divulgados nesta segunda-feira, 03, as provas e os gabaritos preliminares do concurso Petrobras para o cargo de Advogado.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/divulgados-provas-e-gabaritos-preliminares-do-concurso-petrobras-para-o-cargo-de-advogado-saiba-mais\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Divulgados provas e gabaritos preliminares do concurso Petrobras para o cargo de Advogado. Confira!\" \/>\n<meta property=\"og:description\" content=\"Foram divulgados nesta segunda-feira, 03, as provas e os gabaritos preliminares do concurso Petrobras para o cargo de Advogado.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/divulgados-provas-e-gabaritos-preliminares-do-concurso-petrobras-para-o-cargo-de-advogado-saiba-mais\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/EstrategiaConcursos\" \/>\n<meta property=\"article:published_time\" content=\"2015-08-03T14:31:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-08-03T20:59:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2014\/06\/petrobras-300x63.jpg\" \/>\n<meta name=\"author\" content=\"Coordena\u00e7\u00e3o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Coordena\u00e7\u00e3o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/divulgados-provas-e-gabaritos-preliminares-do-concurso-petrobras-para-o-cargo-de-advogado-saiba-mais\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/divulgados-provas-e-gabaritos-preliminares-do-concurso-petrobras-para-o-cargo-de-advogado-saiba-mais\/\"},\"author\":{\"name\":\"Coordena\u00e7\u00e3o\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/b4a388c97673c5f483d72185668afa1f\"},\"headline\":\"Divulgados provas e gabaritos preliminares do concurso Petrobras para o cargo de Advogado. Confira!\",\"datePublished\":\"2015-08-03T14:31:23+00:00\",\"dateModified\":\"2015-08-03T20:59:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/divulgados-provas-e-gabaritos-preliminares-do-concurso-petrobras-para-o-cargo-de-advogado-saiba-mais\/\"},\"wordCount\":287,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/divulgados-provas-e-gabaritos-preliminares-do-concurso-petrobras-para-o-cargo-de-advogado-saiba-mais\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2014\/06\/petrobras-300x63.jpg\",\"keywords\":[\"Advogado da Petrobras\",\"Gabaritos\",\"Provas\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/divulgados-provas-e-gabaritos-preliminares-do-concurso-petrobras-para-o-cargo-de-advogado-saiba-mais\/#respond\"]}],\"copyrightYear\":\"2015\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/divulgados-provas-e-gabaritos-preliminares-do-concurso-petrobras-para-o-cargo-de-advogado-saiba-mais\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/divulgados-provas-e-gabaritos-preliminares-do-concurso-petrobras-para-o-cargo-de-advogado-saiba-mais\/\",\"name\":\"Divulgados provas e gabaritos preliminares do concurso Petrobras para o cargo de Advogado. Confira!\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/divulgados-provas-e-gabaritos-preliminares-do-concurso-petrobras-para-o-cargo-de-advogado-saiba-mais\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/divulgados-provas-e-gabaritos-preliminares-do-concurso-petrobras-para-o-cargo-de-advogado-saiba-mais\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2014\/06\/petrobras-300x63.jpg\",\"datePublished\":\"2015-08-03T14:31:23+00:00\",\"dateModified\":\"2015-08-03T20:59:00+00:00\",\"description\":\"Foram divulgados nesta segunda-feira, 03, as provas e os gabaritos preliminares do concurso Petrobras para o cargo de Advogado.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/divulgados-provas-e-gabaritos-preliminares-do-concurso-petrobras-para-o-cargo-de-advogado-saiba-mais\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/divulgados-provas-e-gabaritos-preliminares-do-concurso-petrobras-para-o-cargo-de-advogado-saiba-mais\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/divulgados-provas-e-gabaritos-preliminares-do-concurso-petrobras-para-o-cargo-de-advogado-saiba-mais\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2014\/06\/petrobras-300x63.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2014\/06\/petrobras-300x63.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/divulgados-provas-e-gabaritos-preliminares-do-concurso-petrobras-para-o-cargo-de-advogado-saiba-mais\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Divulgados provas e gabaritos preliminares do concurso Petrobras para o cargo de Advogado. Confira!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/b4a388c97673c5f483d72185668afa1f\",\"name\":\"Coordena\u00e7\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g\",\"caption\":\"Coordena\u00e7\u00e3o\"},\"sameAs\":[\"https:\/\/www.facebook.com\/EstrategiaConcursos\",\"https:\/\/x.com\/EstratConcursos\"],\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/estrategia2013\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Divulgados provas e gabaritos preliminares do concurso Petrobras para o cargo de Advogado. Confira!","description":"Foram divulgados nesta segunda-feira, 03, as provas e os gabaritos preliminares do concurso Petrobras para o cargo de Advogado.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/divulgados-provas-e-gabaritos-preliminares-do-concurso-petrobras-para-o-cargo-de-advogado-saiba-mais\/","og_locale":"pt_BR","og_type":"article","og_title":"Divulgados provas e gabaritos preliminares do concurso Petrobras para o cargo de Advogado. Confira!","og_description":"Foram divulgados nesta segunda-feira, 03, as provas e os gabaritos preliminares do concurso Petrobras para o cargo de Advogado.","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/divulgados-provas-e-gabaritos-preliminares-do-concurso-petrobras-para-o-cargo-de-advogado-saiba-mais\/","og_site_name":"Estrat\u00e9gia Concursos","article_author":"https:\/\/www.facebook.com\/EstrategiaConcursos","article_published_time":"2015-08-03T14:31:23+00:00","article_modified_time":"2015-08-03T20:59:00+00:00","og_image":[{"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2014\/06\/petrobras-300x63.jpg","type":"","width":"","height":""}],"author":"Coordena\u00e7\u00e3o","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Coordena\u00e7\u00e3o","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/divulgados-provas-e-gabaritos-preliminares-do-concurso-petrobras-para-o-cargo-de-advogado-saiba-mais\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/divulgados-provas-e-gabaritos-preliminares-do-concurso-petrobras-para-o-cargo-de-advogado-saiba-mais\/"},"author":{"name":"Coordena\u00e7\u00e3o","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/b4a388c97673c5f483d72185668afa1f"},"headline":"Divulgados provas e gabaritos preliminares do concurso Petrobras para o cargo de Advogado. Confira!","datePublished":"2015-08-03T14:31:23+00:00","dateModified":"2015-08-03T20:59:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/divulgados-provas-e-gabaritos-preliminares-do-concurso-petrobras-para-o-cargo-de-advogado-saiba-mais\/"},"wordCount":287,"commentCount":1,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/divulgados-provas-e-gabaritos-preliminares-do-concurso-petrobras-para-o-cargo-de-advogado-saiba-mais\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2014\/06\/petrobras-300x63.jpg","keywords":["Advogado da Petrobras","Gabaritos","Provas"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/divulgados-provas-e-gabaritos-preliminares-do-concurso-petrobras-para-o-cargo-de-advogado-saiba-mais\/#respond"]}],"copyrightYear":"2015","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/divulgados-provas-e-gabaritos-preliminares-do-concurso-petrobras-para-o-cargo-de-advogado-saiba-mais\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/divulgados-provas-e-gabaritos-preliminares-do-concurso-petrobras-para-o-cargo-de-advogado-saiba-mais\/","name":"Divulgados provas e gabaritos preliminares do concurso Petrobras para o cargo de Advogado. Confira!","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/divulgados-provas-e-gabaritos-preliminares-do-concurso-petrobras-para-o-cargo-de-advogado-saiba-mais\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/divulgados-provas-e-gabaritos-preliminares-do-concurso-petrobras-para-o-cargo-de-advogado-saiba-mais\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2014\/06\/petrobras-300x63.jpg","datePublished":"2015-08-03T14:31:23+00:00","dateModified":"2015-08-03T20:59:00+00:00","description":"Foram divulgados nesta segunda-feira, 03, as provas e os gabaritos preliminares do concurso Petrobras para o cargo de Advogado.","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/divulgados-provas-e-gabaritos-preliminares-do-concurso-petrobras-para-o-cargo-de-advogado-saiba-mais\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/divulgados-provas-e-gabaritos-preliminares-do-concurso-petrobras-para-o-cargo-de-advogado-saiba-mais\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/divulgados-provas-e-gabaritos-preliminares-do-concurso-petrobras-para-o-cargo-de-advogado-saiba-mais\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2014\/06\/petrobras-300x63.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2014\/06\/petrobras-300x63.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/divulgados-provas-e-gabaritos-preliminares-do-concurso-petrobras-para-o-cargo-de-advogado-saiba-mais\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Divulgados provas e gabaritos preliminares do concurso Petrobras para o cargo de Advogado. Confira!"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/b4a388c97673c5f483d72185668afa1f","name":"Coordena\u00e7\u00e3o","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g","caption":"Coordena\u00e7\u00e3o"},"sameAs":["https:\/\/www.facebook.com\/EstrategiaConcursos","https:\/\/x.com\/EstratConcursos"],"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/estrategia2013\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/25165","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=25165"}],"version-history":[{"count":2,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/25165\/revisions"}],"predecessor-version":[{"id":25167,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/25165\/revisions\/25167"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=25165"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=25165"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=25165"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=25165"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}