{"id":21877,"date":"2015-03-10T14:51:32","date_gmt":"2015-03-10T17:51:32","guid":{"rendered":"http:\/\/www.estrategiaconcursos.com.br\/blog\/?p=21877"},"modified":"2017-09-20T13:54:23","modified_gmt":"2017-09-20T16:54:23","slug":"provas-de-ingles-tce-sp-2015-vunesp","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/provas-de-ingles-tce-sp-2015-vunesp\/","title":{"rendered":"Provas de Ingl\u00eas do TCE-SP &#8211; 2015 &#8211; VUNESP"},"content":{"rendered":"<p>Hi class,<\/p>\n<p style=\"text-align: justify;\">Analisei as provas de Ingl\u00eas do <a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tce-sp\/\">TCE-SP<\/a> aplicada pela VUNESP, foram dois textos ambos da \u00e1rea de TI, e n\u00e3o tenho d\u00favida de que quem fez o curso comigo e estudou o material com carinho se saiu muito bem, pois vimos muitos textos de TI no nosso curso. Ca\u00edram quest\u00f5es de conectivos (como eu havia avisado) dentre eles o conectivo <em>although<\/em> que vimos v\u00e1rias vezes durante o curso e ele caiu tamb\u00e9m na prova da Cesgranrio que analisei hoje de manh\u00e3. As outras quest\u00f5es foram de interpreta\u00e7\u00e3o e foram tranquilas na minha opini\u00e3o. As quest\u00f5es foram muito bem elaboradas, n\u00e3o deixando margem para nenhum recurso. Para quem segue estudando, no momento temos cursos de L\u00edngua Inglesa aqui no Estrat\u00e9gia das bancas ESAF, CESPE, CESGRANRIO e FCC, al\u00e9m do curso regular de Ingl\u00eas que \u00e9 um mix de quest\u00f5es de v\u00e1rias bancas.<\/p>\n<p>&nbsp;<\/p>\n<p>Seguem abaixo os coment\u00e1rios de v\u00e1rias quest\u00f5es de interpreta\u00e7\u00e3o e gram\u00e1tica.<\/p>\n<p>&nbsp;<\/p>\n<p>(TCE-SP-VUNESP-2015)<\/p>\n<ol start=\"9\">\n<li>E-mail spoofing is frequently used by = O e-mail spoofing \u00e9 frequentemente usado por<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p>(A) illegal jurisdictions. = jurisdi\u00e7\u00f5es legais<\/p>\n<p>(B) legitimate sources. = fontes leg\u00edtimas<\/p>\n<p>(C) the actual mail server. = o pr\u00f3prio servidor de correio<\/p>\n<p>(D) spam senders.= remetentes de spam<\/p>\n<p>(E) distributors from your contact list = os distribuidores da sua lista de contatos<\/p>\n<p>&nbsp;<\/p>\n<p>Distributors of spam often use spoofing in an attempt to get recipients to open, and possibly even respond to, their solicitations.<\/p>\n<p>&nbsp;<\/p>\n<p>Os distribuidores de spams utilizam frequentemente spoofing em uma tentativa de obter os destinat\u00e1rios a abrir, e possivelmente at\u00e9 responder suas solicita\u00e7\u00f5es spoofing.<\/p>\n<p>&nbsp;<\/p>\n<p>e-mail spoofing : Envio de e-mail o qual o remetente e outras partes do cabe\u00e7alho s\u00e3o alteradas com o intuito de fazer parecer que tenha originado de uma fonte diferente; pode ser um tipo de fraude na internet;<\/p>\n<p>&nbsp;<\/p>\n<p>Spam = e-mail publicidade n\u00e3o socilitada e que incomoda, e-mails de fontes fraudulentas;<\/p>\n<p>&nbsp;<\/p>\n<p>O trecho do texto e as defini\u00e7\u00f5es acima deixam bem claro que o e-mail spoofing \u00e9 geralmente usado pelos remetentes de spam.<\/p>\n<p>&nbsp;<\/p>\n<p>GABARITO: D<\/p>\n<p>&nbsp;<\/p>\n<ol start=\"10\">\n<li style=\"text-align: justify;\">According to the text, in order to avoid spoofing, one should = De acordo com o texto, a fim de evitar o spoofing, deve-se<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p>(A) discontinue the SMTP as the main mail protocol. = descontinuar o SMTP como sendo o principal protocol de email<\/p>\n<p>(B) be careful to include a security level with the mail server. = (B) ser cuidadoso em incluir um n\u00edvel de seguran\u00e7a com o servidor de email.<\/p>\n<p>(C) exclude all suspect senders from your contact list. = excluir todos os remetentes suspeitos da sua lista de contato<\/p>\n<p>(D) withdraw sensitive data from mails. = retirar as informa\u00e7\u00f5es delicadas dos e-mails.<\/p>\n<p>(E) check the authenticity of self-sending mails = checar a autencidade de auto-envio de e-mails.<\/p>\n<p>&nbsp;<\/p>\n<p>Although an SMTP service extension (specified in IETF RFC 2554) allows an SMTP client to negotiate a security level with a mail server, this precaution is not often taken.<\/p>\n<p>Apesar de uma extens\u00e3o de servi\u00e7o SMTP (especificado no IETF RFC 2554) permitir que um cliente SMTP negocie um n\u00edvel de seguran\u00e7a com um servidor de e-mail , essa precau\u00e7\u00e3o n\u00e3o \u00e9 tomada com frequ\u00eancia.<\/p>\n<p>&nbsp;<\/p>\n<p>O texto diz que existe a possibilidade de se ter um n\u00edvel de seguran\u00e7a junto ao servidor de e-mail. Este servi\u00e7o ajuda a evitar o spoofing. Portanto, o usu\u00e1rio deve ter o cuidado de utilizar essa precau\u00e7\u00e3o.<\/p>\n<p>&nbsp;<\/p>\n<p>GABARITO: B<\/p>\n<p>&nbsp;<\/p>\n<ol start=\"11\">\n<li>In the last sentence of the second paragraph \u2013 Thus, someone could send spoofed e-mail that appears to be from you with a message that you didn\u2019t write. \u2013 The word Thus introduces a\u00a0 = Na \u00faltima frase do segundo par\u00e1grafo- Assim,algu\u00e9m poderia enviar um falso e-mail que parece que voc\u00ea \u00e9 o remetente com uma mensagem que voc\u00ea n\u00e3o escreveu. -A palavra Thus introduz um<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<ul>\n<li>a) result = resultado<\/li>\n<li>b) comparison = compara\u00e7\u00e3o<\/li>\n<li>c) contrast = contraste<\/li>\n<li>d) purpose = prop\u00f3sito<\/li>\n<li>e) exception = exce\u00e7\u00e3o<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Thus = assim, desse modo, dessa maneira = Therefore = portanto, logo, por esse motivo = Hence = por isso<\/p>\n<p>&nbsp;<\/p>\n<p>Na aula 05 na p\u00e1gina 31 do curso de Ingl\u00eas para o TCE-SP, eu chamei a aten\u00e7\u00e3o do aluno com uma observa\u00e7\u00e3o destacada dizendo:<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #333333;\"><strong>\u201cExiste a possibilidade de cair uma quest\u00e3o de conectivos\u201d<\/strong><\/span><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>Abaixo do aviso eu coloquei um quadro com <strong>75<\/strong> conectivos, suas tradu\u00e7\u00f5es e alguns de seus sin\u00f4nimos. Estou certa de que quem fez o curso comigo e estou atenciosamente, lembrou-se. Um dos conectivos era justamente o <strong>Thus<\/strong> e seus sin\u00f4nimos como est\u00e3o acima. Ele n\u00e3o perguntou diretamente o significado, mas sim o que o conectivo introduz. Ora, sabendo o significado do conectivo em Portugu\u00eas, fica f\u00e1cil de saber para que ele \u00e9 usado. Os conectivos que expressam resultado s\u00e3o os mesmos de consequ\u00eancia. \u00c9 s\u00f3 substituir na frase:<\/p>\n<p>&nbsp;<\/p>\n<p>Thus (As a result), someone could send spoofed e-mail.<\/p>\n<p>Assim, (Como resultado \/ consequentemente) algu\u00e9m poderia enviar falso e-mail.<\/p>\n<p>&nbsp;<\/p>\n<p>Todo o segundo par\u00e1grafo explica sobre o que \u00e9 o spoofing, como evit\u00e1-lo, etc. A \u00faltima frase diz qual o resultado, ou seja, o que acontece quando se usa o spoofing. Esse resultado foi introduzido pelo adv\u00e9rbio Thus, que fez a conex\u00e3o dele com o contexto anterior.<\/p>\n<p>&nbsp;<\/p>\n<p>GABARITO: A<\/p>\n<p>&nbsp;<\/p>\n<p>A quest\u00e3o abaixo \u00e9 do texto \u201cTo troubleshoot hardware problems\u201d para o cargo de Auxiliar da Fiscaliza\u00e7\u00e3o Financeira II. Nessa prova tamb\u00e9m caiu uma quest\u00e3o de conectivos.<\/p>\n<p>&nbsp;<\/p>\n<ol start=\"12\">\n<li>In the excerpt of item 7 of the text \u2013 While failed hardware can be frustrating, your documents, pictures, and email should be safe \u2013 the word \u201cwhile\u201d can be correctly replaced by<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<ol start=\"12\">\n<li>No trecho do item 7 do texto \u2013 Embora uma falha no hardware possa ser frustrante, seus documentos, fotos, e e-mail deveriam est\u00e1 seguros &#8211; a palavra &#8220;while&#8221; pode ser substitu\u00edda corretamente por<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<ul>\n<li>a) although = embora, apesar de<\/li>\n<li>b) when = quando<\/li>\n<li>c) whenever = a qualquer hora<\/li>\n<li>d) during = durante<\/li>\n<li>e) along = adiante, junto a<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Novamente, uma quest\u00e3o de conectivos, como eu havia previsto na aula. De todos os conectivos acima vimos no quadro o although, while, when e whenever. Os outros creio que vimos durante o curso pois est\u00e3o sempre presente em textos.<\/p>\n<p>&nbsp;<\/p>\n<p>No quadro estava bem detalhado, assim:<\/p>\n<p>&nbsp;<\/p>\n<p>While = enquanto, embora (although)<\/p>\n<p>&nbsp;<\/p>\n<p>Although = embora, apesar de<\/p>\n<p>&nbsp;<\/p>\n<p>As vezes o while significa \u201cenquanto\u201d quando expressa tempo. No contexto da quest\u00e3o ele significa \u201cembora\u201d e \u00e9 sin\u00f4nimo do although como coloquei l\u00e1 no quadro de resumo na aula 05.<\/p>\n<p>&nbsp;<\/p>\n<p>GABARITO: A<\/p>\n<p>&nbsp;<\/p>\n<p>Abra\u00e7os e bons estudos,<\/p>\n<p>&nbsp;<\/p>\n<p>Profa Ena Smith<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.estrategiaconcursos.com.br\/cursosPorConcurso\/tce-sp-tribunal-de-contas-do-estado-de-sao-paulo\/\">Cursos Online para TCE-SP<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hi class, Analisei as provas de Ingl\u00eas do TCE-SP aplicada pela VUNESP, foram dois textos ambos da \u00e1rea de TI, e n\u00e3o tenho d\u00favida de que quem fez o curso comigo e estudou o material com carinho se saiu muito bem, pois vimos muitos textos de TI no nosso curso. Ca\u00edram quest\u00f5es de conectivos (como [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[],"tags":[511,539],"tax_estado":[],"class_list":["post-21877","post","type-post","status-publish","format-standard","hentry","tag-ingles","tag-tce-sp"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Provas de Ingl\u00eas do TCE-SP - 2015 - VUNESP<\/title>\n<meta name=\"description\" content=\"Prova Comentada TCE-SP 2015 - Quest\u00f5es de Ingl\u00eas para Auxiliar de Administra\u00e7\u00e3o Financeira do Tribunal de Contas de S\u00e3o Paulo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/provas-de-ingles-tce-sp-2015-vunesp\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Provas de Ingl\u00eas do TCE-SP - 2015 - VUNESP\" \/>\n<meta property=\"og:description\" content=\"Prova Comentada TCE-SP 2015 - Quest\u00f5es de Ingl\u00eas para Auxiliar de Administra\u00e7\u00e3o Financeira do Tribunal de Contas de S\u00e3o Paulo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/provas-de-ingles-tce-sp-2015-vunesp\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2015-03-10T17:51:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-09-20T16:54:23+00:00\" \/>\n<meta name=\"author\" content=\"Ena Smith\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ena Smith\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/provas-de-ingles-tce-sp-2015-vunesp\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/provas-de-ingles-tce-sp-2015-vunesp\/\"},\"author\":{\"name\":\"Ena Smith\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/afd1d3e6a3f8ae00c7422d7d00a4f1f3\"},\"headline\":\"Provas de Ingl\u00eas do TCE-SP &#8211; 2015 &#8211; VUNESP\",\"datePublished\":\"2015-03-10T17:51:32+00:00\",\"dateModified\":\"2017-09-20T16:54:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/provas-de-ingles-tce-sp-2015-vunesp\/\"},\"wordCount\":1139,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"keywords\":[\"Ingl\u00eas\",\"TCE-SP\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/provas-de-ingles-tce-sp-2015-vunesp\/#respond\"]}],\"copyrightYear\":\"2015\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/provas-de-ingles-tce-sp-2015-vunesp\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/provas-de-ingles-tce-sp-2015-vunesp\/\",\"name\":\"Provas de Ingl\u00eas do TCE-SP - 2015 - VUNESP\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"datePublished\":\"2015-03-10T17:51:32+00:00\",\"dateModified\":\"2017-09-20T16:54:23+00:00\",\"description\":\"Prova Comentada TCE-SP 2015 - Quest\u00f5es de Ingl\u00eas para Auxiliar de Administra\u00e7\u00e3o Financeira do Tribunal de Contas de S\u00e3o Paulo.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/provas-de-ingles-tce-sp-2015-vunesp\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/provas-de-ingles-tce-sp-2015-vunesp\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/provas-de-ingles-tce-sp-2015-vunesp\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Provas de Ingl\u00eas do TCE-SP &#8211; 2015 &#8211; VUNESP\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/afd1d3e6a3f8ae00c7422d7d00a4f1f3\",\"name\":\"Ena Smith\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/e8f1dd180dc6dd7006b6b8a67f86386e1239e7c04795ef2c09d6e22b489cca34?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e8f1dd180dc6dd7006b6b8a67f86386e1239e7c04795ef2c09d6e22b489cca34?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e8f1dd180dc6dd7006b6b8a67f86386e1239e7c04795ef2c09d6e22b489cca34?s=96&d=mm&r=g\",\"caption\":\"Ena Smith\"},\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/enaglauciaestrategiaconcursos-com-br\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Provas de Ingl\u00eas do TCE-SP - 2015 - VUNESP","description":"Prova Comentada TCE-SP 2015 - Quest\u00f5es de Ingl\u00eas para Auxiliar de Administra\u00e7\u00e3o Financeira do Tribunal de Contas de S\u00e3o Paulo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/provas-de-ingles-tce-sp-2015-vunesp\/","og_locale":"pt_BR","og_type":"article","og_title":"Provas de Ingl\u00eas do TCE-SP - 2015 - VUNESP","og_description":"Prova Comentada TCE-SP 2015 - Quest\u00f5es de Ingl\u00eas para Auxiliar de Administra\u00e7\u00e3o Financeira do Tribunal de Contas de S\u00e3o Paulo.","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/provas-de-ingles-tce-sp-2015-vunesp\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2015-03-10T17:51:32+00:00","article_modified_time":"2017-09-20T16:54:23+00:00","author":"Ena Smith","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Ena Smith","Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/provas-de-ingles-tce-sp-2015-vunesp\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/provas-de-ingles-tce-sp-2015-vunesp\/"},"author":{"name":"Ena Smith","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/afd1d3e6a3f8ae00c7422d7d00a4f1f3"},"headline":"Provas de Ingl\u00eas do TCE-SP &#8211; 2015 &#8211; VUNESP","datePublished":"2015-03-10T17:51:32+00:00","dateModified":"2017-09-20T16:54:23+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/provas-de-ingles-tce-sp-2015-vunesp\/"},"wordCount":1139,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"keywords":["Ingl\u00eas","TCE-SP"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/provas-de-ingles-tce-sp-2015-vunesp\/#respond"]}],"copyrightYear":"2015","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/provas-de-ingles-tce-sp-2015-vunesp\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/provas-de-ingles-tce-sp-2015-vunesp\/","name":"Provas de Ingl\u00eas do TCE-SP - 2015 - VUNESP","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"datePublished":"2015-03-10T17:51:32+00:00","dateModified":"2017-09-20T16:54:23+00:00","description":"Prova Comentada TCE-SP 2015 - Quest\u00f5es de Ingl\u00eas para Auxiliar de Administra\u00e7\u00e3o Financeira do Tribunal de Contas de S\u00e3o Paulo.","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/provas-de-ingles-tce-sp-2015-vunesp\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/provas-de-ingles-tce-sp-2015-vunesp\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/provas-de-ingles-tce-sp-2015-vunesp\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Provas de Ingl\u00eas do TCE-SP &#8211; 2015 &#8211; VUNESP"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/afd1d3e6a3f8ae00c7422d7d00a4f1f3","name":"Ena Smith","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/e8f1dd180dc6dd7006b6b8a67f86386e1239e7c04795ef2c09d6e22b489cca34?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e8f1dd180dc6dd7006b6b8a67f86386e1239e7c04795ef2c09d6e22b489cca34?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e8f1dd180dc6dd7006b6b8a67f86386e1239e7c04795ef2c09d6e22b489cca34?s=96&d=mm&r=g","caption":"Ena Smith"},"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/enaglauciaestrategiaconcursos-com-br\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/21877","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=21877"}],"version-history":[{"count":2,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/21877\/revisions"}],"predecessor-version":[{"id":89526,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/21877\/revisions\/89526"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=21877"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=21877"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=21877"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=21877"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}