{"id":1785088,"date":"2026-09-01T14:11:00","date_gmt":"2026-09-01T17:11:00","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=1785088"},"modified":"2026-08-04T21:09:25","modified_gmt":"2026-08-05T00:09:25","slug":"julgamento-pat-sefaz-df","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/julgamento-pat-sefaz-df\/","title":{"rendered":"Julgamento do PAT para SEFAZ\/DF"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Opa, segue no ritmo!! O objetivo deste artigo do Estrat\u00e9gia Concursos \u00e9 trazer um tema bastante importante para a prova de Auditor Fiscal do Distrito Federal: <strong>julgamento do PAT para SEFAZ\/DF<\/strong> de acordo com a legisla\u00e7\u00e3o nacional e local.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"901\" height=\"472\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2026\/07\/29145910\/image-135.png\" alt=\"Julgamento do PAT para SEFAZ\/DF\" class=\"wp-image-1785089\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2026\/07\/29145910\/image-135.png 901w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2026\/07\/29145910\/image-135-300x157.png 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2026\/07\/29145910\/image-135-768x402.png 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2026\/07\/29145910\/image-135-150x79.png 150w\" sizes=\"auto, (max-width: 901px) 100vw, 901px\" \/><figcaption class=\"wp-element-caption\">Julgamento do PAT para SEFAZ\/DF<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Com garra e dedica\u00e7\u00e3o, iremos tratar dos seguintes t\u00f3picos:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Estudar disposi\u00e7\u00f5es normativas sobre julgamento do PAT para SEFAZ\/DF;\u00a0<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Comentar observa\u00e7\u00f5es relevantes sobre o tema;\u00a0<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Conhecer trechos da legisla\u00e7\u00e3o que podem cair na prova;\u00a0<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Concluir com considera\u00e7\u00f5es finais.\u00a0<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Isto posto, tendo como refer\u00eancia a <a href=\"https:\/\/www.legisweb.com.br\/legislacao\/?id=125663\" target=\"_blank\" rel=\"noreferrer noopener\">Lei n\u00ba 4.567\/2011<\/a>, norma distrital que trata do PAT, vamos agora estudar um pouco mais sobre julgamento do PAT para SEFAZ\/DF.\u00a0<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"113\" class=\"wp-image-1624852\" style=\"width: 150px;\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/08\/17000015\/atencao_03.jpg\" alt=\"aten\u00e7\u00e3o\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/08\/17000015\/atencao_03.jpg 568w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/08\/17000015\/atencao_03-300x226.jpg 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/08\/17000015\/atencao_03-150x113.jpg 150w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/p>\n\n\n\n<h2 id=\"h-julgamento-do-pat-para-sefaz-df-nbsp\" class=\"wp-block-heading\"><strong>Julgamento do PAT para SEFAZ\/DF<\/strong>&nbsp;<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Nas situa\u00e7\u00f5es em que um<strong> sujeito passivo <\/strong>discordar de uma cobran\u00e7a tribut\u00e1ria que ele recebeu do Estado, pode esse contribuinte ingressar com um PAT para discutir aquela taxa\u00e7\u00e3o.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O PAT nada mais \u00e9 que um<mark style=\"background-color:rgba(0, 0, 0, 0);color:#7bdcb5\" class=\"has-inline-color\"> <strong>Processo Administrativo Tribut\u00e1rio,<\/strong> <\/mark>meio formal pelo qual o sujeito passivo pode se posicionar contra a cobran\u00e7a recebida, apresentando suas alega\u00e7\u00f5es e defendendo os seus argumentos e provas.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se de um lado est\u00e1 o sujeito passivo, do outro est\u00e1 a <strong>administra\u00e7\u00e3o p\u00fablica<\/strong>, que tamb\u00e9m ter\u00e1 seus momentos de se posicionar no decorrer do processo, visando a manuten\u00e7\u00e3o daquela cobran\u00e7a tribut\u00e1ria, e evidentemente os seus interesses.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">H\u00e1 <strong>prazos<\/strong> a serem cumpridos pelas partes no curso do PAT, os quais devem ser respeitados para que as provas entregues sejam analisadas por aqueles que far\u00e3o a avalia\u00e7\u00e3o e o julgamento do caso.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por falar em<strong> julgamento,<\/strong> cada ente federativo possui prerrogativa de definir a composi\u00e7\u00e3o dos \u00f3rg\u00e3os que s\u00e3o respons\u00e1veis por julgar as quest\u00f5es relacionadas a discuss\u00f5es dentro do PAT, mas \u00e9 importante que exista alguma imparcialidade nesses julgadores, tendo em vista que a <strong>justi\u00e7a fiscal<\/strong> deve prevalecer no final das contas.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Assim, o julgamento do PAT para SEFAZ\/DF ocorre em fases, em<strong> inst\u00e2ncias<\/strong>, que s\u00f3 v\u00e3o progredindo quando uma inst\u00e2ncia anterior \u00e9 esgotada, ou seja, quando ocorre o julgamento nela e, devido a um recurso de algumas das partes, o processo n\u00e3o se encerra e segue para a inst\u00e2ncia seguinte fazer o seu pr\u00f3prio julgamento.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Chegando \u00e0 <mark style=\"background-color:rgba(0, 0, 0, 0);color:#8ed1fc\" class=\"has-inline-color\"><strong>\u00faltima inst\u00e2ncia administrativa<\/strong>,<\/mark> \u00e0 inst\u00e2ncia superior, temos o encerramento do PAT no \u00e2mbito administrativo, onde ser\u00e1 deferida uma decis\u00e3o final, que dever\u00e1 ser observada pelas partes. Na verdade, se alguma das partes se sentir prejudicada por essa decis\u00e3o, ainda poder\u00e1 ingressar no \u00e2mbito judicial para tratar do mesmo caso, buscando levar mais adiante a discuss\u00e3o.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><mark style=\"background-color:#abb8c3\" class=\"has-inline-color\">Essa possibilidade de entrar com <strong>a\u00e7\u00e3o judicial <\/strong>para tratar de tema j\u00e1 discutido na esfera administrativa \u00e9 vi\u00e1vel devido \u00e0<strong> unicidade de jurisdi\u00e7\u00e3o<\/strong> que existe no Brasil, que basicamente estabelece que apenas um Poder det\u00e9m prerrogativa de dar a palavra final em definitivo em lit\u00edgios, sendo esse Poder exatamente o Judici\u00e1rio.\u00a0<\/mark><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nessa linha, \u00e9 por isso que dizemos que a decis\u00e3o final em um PAT \u00e9 definitiva <strong>apenas no \u00e2mbito administrativo,<\/strong> enquanto a decis\u00e3o final do Judici\u00e1rio tem o cond\u00e3o de decidir definitivamente em julgado. Se liga nisso!&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sendo assim, vamos ent\u00e3o acompanhar o que de mais relevante consta na lei 4567\/2011 sobre julgamento do PAT para SEFAZ\/DF:\u00a0<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"105\" class=\"wp-image-1542466\" style=\"width: 150px;\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/03\/09200407\/tome-nota-5.png\" alt=\"Aten\u00e7\u00e3o\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/03\/09200407\/tome-nota-5.png 258w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/03\/09200407\/tome-nota-5-150x105.png 150w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><mark style=\"background-color:#abb8c3\" class=\"has-inline-color\">Art. 43. O julgamento administrativo do processo sujeito \u00e0 <strong>jurisdi\u00e7\u00e3o contenciosa compete:<\/strong>\u00a0<\/mark><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">I &#8211; em<strong> primeira inst\u00e2ncia<\/strong>, ao Subsecret\u00e1rio da Receita;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">II &#8211; em <strong>segunda inst\u00e2ncia<\/strong>, ao TARF.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a7 1\u00ba A compet\u00eancia prevista no inciso I do caput <strong>poder\u00e1 <\/strong>ser delegada.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a7 2\u00ba A autoridade julgadora <strong>formular\u00e1<\/strong> o julgamento do processo plenamente vinculado \u00e0 legisla\u00e7\u00e3o tribut\u00e1ria,<strong> <\/strong>restringindo-se \u00e0 mat\u00e9ria impugnada.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a7 3\u00ba A compet\u00eancia fixada neste artigo<strong> exclui:<\/strong>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">I &#8211; a aprecia\u00e7\u00e3o <strong>quanto \u00e0 constitucionalidade;<\/strong>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">II &#8211; a aprecia\u00e7\u00e3o de <strong>conflito entre lei tribut\u00e1ria distrital e lei de outra natureza;<\/strong>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">III &#8211; a aplica\u00e7\u00e3o da <strong>equidade.<\/strong>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por fim, para fecharmos nosso texto sobre julgamento do PAT para SEFAZ\/DF, saiba ainda que ser\u00e1 proferido, nos termos do regulamento,<strong> <mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-accent-2-color\">ju\u00edzo de admissibilidade da impugna\u00e7\u00e3o<\/mark><\/strong> contra o lan\u00e7amento, o qual compreender\u00e1 a verifica\u00e7\u00e3o dos requisitos constantes da lei que acabamos de estudar. E, al\u00e9m disso, ser\u00e1 reaberto prazo para apresenta\u00e7\u00e3o de impugna\u00e7\u00e3o contra o lan\u00e7amento se, em raz\u00e3o do ju\u00edzo de admissibilidade, <strong>houver agravamento da exig\u00eancia.<\/strong>\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Passamos, portanto, por uma no\u00e7\u00e3o geral em rela\u00e7\u00e3o a julgamento do PAT para SEFAZ\/DF, assunto essencial para o concurso de auditor fiscal deste Estado.&nbsp;<\/p>\n\n\n\n<h2 id=\"h-consideracoes-finais-nbsp\" class=\"wp-block-heading\"><strong>Considera\u00e7\u00f5es Finais<\/strong>&nbsp;<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Chegamos ao final do nosso breve artigo sobre julgamento do PAT para SEFAZ\/DF, e esperamos que seja muito \u00fatil para a sua prepara\u00e7\u00e3o e aprova\u00e7\u00e3o.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Passar em concurso \u00e9 uma grande oportunidade para ingressar no servi\u00e7o p\u00fablico, ocupando um cargo de destaque e com remunera\u00e7\u00f5es acima da m\u00e9dia nacional, sem falar de diversos outros pontos positivos! O caminho \u00e9 \u00e1rduo, mas vale a pena o esfor\u00e7o para alcan\u00e7ar essa conquista! Por isso, siga firme com os estudos e conte conosco em sua jornada! Vamos em frente!!&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Lembre-se que \u00e9 essencial a <\/em><a href=\"https:\/\/www.estrategiaconcursos.com.br\/\" target=\"_blank\" rel=\"noreferrer noopener\"><em>leitura dos PDF\u2019s e a revis\u00e3o frequente dos conte\u00fados, para que assim os seus estudos fiquem cada vez mais avan\u00e7ados.<\/em><\/a><em>&nbsp;<\/em>&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Um grande abra\u00e7o e at\u00e9 mais!&nbsp;<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><strong>Quer saber quais ser\u00e3o os pr\u00f3ximos concursos?<\/strong>&nbsp;<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><strong>Confira nossos artigos!<\/strong>&nbsp;<\/p>\n\n\n\n<p class=\"has-text-align-center has-luminous-vivid-amber-background-color has-background wp-block-paragraph\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos abertos<\/a>&nbsp;<\/p>\n\n\n\n<p class=\"has-text-align-center has-luminous-vivid-amber-background-color has-background wp-block-paragraph\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2026\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos 2026<\/a>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Opa, segue no ritmo!! O objetivo deste artigo do Estrat\u00e9gia Concursos \u00e9 trazer um tema bastante importante para a prova de Auditor Fiscal do Distrito Federal: julgamento do PAT para SEFAZ\/DF de acordo com a legisla\u00e7\u00e3o nacional e local.&nbsp; Com garra e dedica\u00e7\u00e3o, iremos tratar dos seguintes t\u00f3picos:&nbsp; Isto posto, tendo como refer\u00eancia a Lei [&hellip;]<\/p>\n","protected":false},"author":2887,"featured_media":1785089,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"post_tipo":"article","footnotes":""},"categories":[1,1983],"tags":[],"tax_estado":[219963,219970],"class_list":["post-1785088","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cursos-e-concursos","category-fiscal-estadual","tax_estado-concursos-federais","tax_estado-df"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.1 (Yoast SEO v28.1) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Julgamento do PAT para SEFAZ\/DF<\/title>\n<meta name=\"description\" content=\"O material traz um tema bastante importante para a prova de Auditor Fiscal do Distrito Federal: julgamento do PAT para SEFAZ\/DF.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/julgamento-pat-sefaz-df\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Julgamento do PAT para SEFAZ\/DF\" \/>\n<meta property=\"og:description\" content=\"O material traz um tema bastante importante para a prova de Auditor Fiscal do Distrito Federal: julgamento do PAT para SEFAZ\/DF.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/julgamento-pat-sefaz-df\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2026-09-01T17:11:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2026\/07\/29145910\/image-135.png\" \/>\n\t<meta property=\"og:image:width\" content=\"901\" \/>\n\t<meta property=\"og:image:height\" content=\"472\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"F\u00e1bio Prado dos Santos Santana\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"F\u00e1bio Prado dos Santos Santana\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/julgamento-pat-sefaz-df\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/julgamento-pat-sefaz-df\\\/\"},\"author\":{\"name\":\"F\u00e1bio Prado dos Santos Santana\",\"@id\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/#\\\/schema\\\/person\\\/b1af3515254fed0a6861d754def3f005\"},\"headline\":\"Julgamento do PAT para SEFAZ\\\/DF\",\"datePublished\":\"2026-09-01T17:11:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/julgamento-pat-sefaz-df\\\/\"},\"wordCount\":948,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/julgamento-pat-sefaz-df\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2026\\\/07\\\/29145910\\\/image-135.png\",\"articleSection\":[\"Concursos P\u00fablicos\",\"Fiscal - Estadual (ICMS)\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/julgamento-pat-sefaz-df\\\/#respond\"]}],\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/julgamento-pat-sefaz-df\\\/\",\"url\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/julgamento-pat-sefaz-df\\\/\",\"name\":\"Julgamento do PAT para SEFAZ\\\/DF\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/julgamento-pat-sefaz-df\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/julgamento-pat-sefaz-df\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2026\\\/07\\\/29145910\\\/image-135.png\",\"datePublished\":\"2026-09-01T17:11:00+00:00\",\"description\":\"O material traz um tema bastante importante para a prova de Auditor Fiscal do Distrito Federal: julgamento do PAT para SEFAZ\\\/DF.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/julgamento-pat-sefaz-df\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/julgamento-pat-sefaz-df\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/julgamento-pat-sefaz-df\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2026\\\/07\\\/29145910\\\/image-135.png\",\"contentUrl\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2026\\\/07\\\/29145910\\\/image-135.png\",\"width\":901,\"height\":472,\"caption\":\"Julgamento do PAT para SEFAZ\\\/DF\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/julgamento-pat-sefaz-df\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Julgamento do PAT para SEFAZ\\\/DF\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/#website\",\"url\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2025\\\/06\\\/03203428\\\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2025\\\/06\\\/03203428\\\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/#\\\/schema\\\/person\\\/b1af3515254fed0a6861d754def3f005\",\"name\":\"F\u00e1bio Prado dos Santos Santana\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0e3399436850f804c1d7731313952ccf303887c14b1711595235048e3ec0299b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0e3399436850f804c1d7731313952ccf303887c14b1711595235048e3ec0299b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0e3399436850f804c1d7731313952ccf303887c14b1711595235048e3ec0299b?s=96&d=mm&r=g\",\"caption\":\"F\u00e1bio Prado dos Santos Santana\"},\"description\":\"Principais Aprova\u00e7\u00f5es em Concursos: Auditor Fiscal Tribut\u00e1rio Municipal - ISS S\u00e3o Paulo (2024); Auditor Fiscal - Receita Federal do Brasil (2023); Professor Efetivo - Universidade Federal de Sergipe (2014).\",\"url\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/author\\\/fabioprado-ufsgmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Julgamento do PAT para SEFAZ\/DF","description":"O material traz um tema bastante importante para a prova de Auditor Fiscal do Distrito Federal: julgamento do PAT para SEFAZ\/DF.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/julgamento-pat-sefaz-df\/","og_locale":"pt_BR","og_type":"article","og_title":"Julgamento do PAT para SEFAZ\/DF","og_description":"O material traz um tema bastante importante para a prova de Auditor Fiscal do Distrito Federal: julgamento do PAT para SEFAZ\/DF.","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/julgamento-pat-sefaz-df\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2026-09-01T17:11:00+00:00","og_image":[{"width":901,"height":472,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2026\/07\/29145910\/image-135.png","type":"image\/png"}],"author":"F\u00e1bio Prado dos Santos Santana","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"F\u00e1bio Prado dos Santos Santana","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/julgamento-pat-sefaz-df\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/julgamento-pat-sefaz-df\/"},"author":{"name":"F\u00e1bio Prado dos Santos Santana","@id":"https:\/\/blog-estrategia.mystagingwebsite.com\/#\/schema\/person\/b1af3515254fed0a6861d754def3f005"},"headline":"Julgamento do PAT para SEFAZ\/DF","datePublished":"2026-09-01T17:11:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/julgamento-pat-sefaz-df\/"},"wordCount":948,"commentCount":0,"publisher":{"@id":"https:\/\/blog-estrategia.mystagingwebsite.com\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/julgamento-pat-sefaz-df\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2026\/07\/29145910\/image-135.png","articleSection":["Concursos P\u00fablicos","Fiscal - Estadual (ICMS)"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/julgamento-pat-sefaz-df\/#respond"]}],"copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/julgamento-pat-sefaz-df\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/julgamento-pat-sefaz-df\/","name":"Julgamento do PAT para SEFAZ\/DF","isPartOf":{"@id":"https:\/\/blog-estrategia.mystagingwebsite.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/julgamento-pat-sefaz-df\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/julgamento-pat-sefaz-df\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2026\/07\/29145910\/image-135.png","datePublished":"2026-09-01T17:11:00+00:00","description":"O material traz um tema bastante importante para a prova de Auditor Fiscal do Distrito Federal: julgamento do PAT para SEFAZ\/DF.","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/julgamento-pat-sefaz-df\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/julgamento-pat-sefaz-df\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/julgamento-pat-sefaz-df\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2026\/07\/29145910\/image-135.png","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2026\/07\/29145910\/image-135.png","width":901,"height":472,"caption":"Julgamento do PAT para SEFAZ\/DF"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/julgamento-pat-sefaz-df\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/blog-estrategia.mystagingwebsite.com\/"},{"@type":"ListItem","position":2,"name":"Julgamento do PAT para SEFAZ\/DF"}]},{"@type":"WebSite","@id":"https:\/\/blog-estrategia.mystagingwebsite.com\/#website","url":"https:\/\/blog-estrategia.mystagingwebsite.com\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/blog-estrategia.mystagingwebsite.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog-estrategia.mystagingwebsite.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/blog-estrategia.mystagingwebsite.com\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/blog-estrategia.mystagingwebsite.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/blog-estrategia.mystagingwebsite.com\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/blog-estrategia.mystagingwebsite.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/blog-estrategia.mystagingwebsite.com\/#\/schema\/person\/b1af3515254fed0a6861d754def3f005","name":"F\u00e1bio Prado dos Santos Santana","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/0e3399436850f804c1d7731313952ccf303887c14b1711595235048e3ec0299b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0e3399436850f804c1d7731313952ccf303887c14b1711595235048e3ec0299b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0e3399436850f804c1d7731313952ccf303887c14b1711595235048e3ec0299b?s=96&d=mm&r=g","caption":"F\u00e1bio Prado dos Santos Santana"},"description":"Principais Aprova\u00e7\u00f5es em Concursos: Auditor Fiscal Tribut\u00e1rio Municipal - ISS S\u00e3o Paulo (2024); Auditor Fiscal - Receita Federal do Brasil (2023); Professor Efetivo - Universidade Federal de Sergipe (2014).","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/fabioprado-ufsgmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1785088","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/2887"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1785088"}],"version-history":[{"count":1,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1785088\/revisions"}],"predecessor-version":[{"id":1785090,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1785088\/revisions\/1785090"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/1785089"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1785088"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1785088"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1785088"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1785088"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}