{"id":176419,"date":"2019-04-04T08:04:23","date_gmt":"2019-04-04T11:04:23","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=176419"},"modified":"2019-04-06T04:42:27","modified_gmt":"2019-04-06T07:42:27","slug":"passos-de-gigante-76","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/passos-de-gigante-76\/","title":{"rendered":"PASSOS DE GIGANTE 76\/365"},"content":{"rendered":"\n<p>Fala \u00c1guia! Bom dia das Gal\u00e1xias! Faltam 6 dias para o DIA MAIS INCR\u00cdVEL no fant\u00e1stico mundo de @lacerdaf3 ! Quando me perguntam porque eu enfio F-3 em tudo o que eu fa\u00e7o, sabe o que eu respondo?<\/p>\n\n\n\n<p>\u00c9 TREINAMENTO DI\u00c1RIO! Imagine-se TODOS os dias em contato com algo que vai te levar para o pr\u00f3ximo n\u00edvel? Imaginou? <\/p>\n\n\n\n<p>Assim \u00e9 minha vida&#8230; meu e-mail, por exemplo, \u00e9 algumacoisaf3@yahoo.com.br. \u00c9 o F-3 mais uma vez presente: F\u00c9 + FOCO + FOR\u00c7A! Injetando esses tr\u00eas ingredientes em qualquer coisa, n\u00e3o tem como dar errado&#8230; Se dependesse s\u00f3 de mim (ainda bem que n\u00e3o depende, kkkkk), as crian\u00e7as iria se chamar Fulano F-3 e Beltrano F-3&#8230; <\/p>\n\n\n\n<p>O SUCESSO \u00c9 QUEST\u00c3O DE TEMPO para quem estuda com consist\u00eancia e f\u00e9. J\u00e1 te falei sobre esse lance de tempo ontem nos <a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/passos-de-gigante-75-365\/\">Passos de Gigante 75<\/a>. E j\u00e1 que tocamos no assunto Sucesso&#8230; BORA BORA DECOLAAAAAAARGH!<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/04\/04072621\/sucesso.jpg\" alt=\"\" class=\"wp-image-176421\" width=\"317\" height=\"211\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/04\/04072621\/sucesso.jpg 960w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/04\/04072621\/sucesso.jpg 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/04\/04072621\/sucesso.jpg 768w\" sizes=\"auto, (max-width: 317px) 100vw, 317px\" \/><figcaption>Muito mais gostoso quando estamos JUNTOS! <\/figcaption><\/figure><\/div>\n\n\n\n<p>&#8220;Qual \u00e9 o segredo do sucesso? Frequentemente sugerimos que \u00e9 a genialidade. <strong>Por\u00e9m, acredito que a verdadeira genialidade \u00e9 a capacidade de concentrar nossos recursos mais poderosos simplesmente nos colocando num estado de certeza absoluta. <\/strong><\/p>\n\n\n\n<p>A carreira do bilion\u00e1rio Bill Gates come\u00e7ou quando ainda estava na faculdade, em Harvard, e prometeu entregar um software que ainda n\u00e3o tinha desenvolvido para um computador que ele nunca vira! Devido \u00e0 sua certeza (<strong>que era completamente infundada<\/strong>), Bill Gates p\u00f4de juntar todos os recursos de que precisava para coprojetar o software e come\u00e7ar a construir sua fortuna. (grifo nosso)<\/p>\n\n\n\n<p>Certamente temos mais chance de obter sucesso em qualquer \u00e1rea se n\u00e3o apenas nos comprometermos com o resultado, mas estivermos absolutamente certos de que podemos consegui-lo. <em>Com que frequ\u00eancia voc\u00ea experimenta essa emo\u00e7\u00e3o fortalecedora?&#8221;<\/em>(ROBBINS, Anthony, pag. 91. Passos de Gigante: Pequenas mudan\u00e7as que fazem grande diferen\u00e7a. 2\u00aa ed. Rio de Janeiro: Viva Livros, 2016)<\/p>\n\n\n\n<p>Estado de certeza absoluta? Fala mais sobre isso, Rapha. <\/p>\n\n\n\n<p>Vou exemplificar com mais um trechinho da minha hist\u00f3ria. <\/p>\n\n\n\n<p>Final de 1998, eu tinha acabado de sair do Curso Impacto, na Tijuca, Rio de Janeiro. Era o melhor na \u00e9poca e um dos que mais aprovava para IME\/ITA. O curso foi 100% patrocinado pela minha av\u00f3, pois meus pais n\u00e3o tinham grana para pagar aquela fortuna. S\u00f3 tem um detalhe&#8230; No final do ano, o meu saldo era:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>REPROVADO NA ESCOLA NAVAL EM PORTUGU\u00caS<\/li><li>REPROVADO NA AFA EM PORTUGU\u00caS<\/li><li>REPROVADO NO ITA EM PORTUGU\u00caS<\/li><li>REPROVADO NO IME (nem lembro mais em quais disciplinas) <\/li><\/ul>\n\n\n\n<p>Como \u00e9 que voc\u00ea com esse &#8220;lindo curr\u00edculo&#8221; de reprova\u00e7\u00f5es obteria uma bolsa de 100% em outro cursinho? \u00c9 isso mesmo, 100%! Ou voc\u00eas acreditam que minha av\u00f3 GENERAL, linha dura, iria pagar outro curso para mim? Era APENAS UMA CHANCE! Esse senso de urg\u00eancia despertou em mim a necessidade de um milagre. Eu precisava estudar de gra\u00e7a e num local absurdamente bom.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/04\/04073133\/f%C3%A9.jpg\" alt=\"\" class=\"wp-image-176422\" width=\"327\" height=\"184\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/04\/04073133\/f%C3%A9.jpg 678w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/04\/04073133\/f%C3%A9.jpg 300w\" sizes=\"auto, (max-width: 327px) 100vw, 327px\" \/><figcaption>Fale, Sinta, Acredite!<\/figcaption><\/figure><\/div>\n\n\n\n<p>Todos os dias eu declarava:<\/p>\n\n\n\n<p>&#8220;EU VOU ESTUDAR COM BOLSA DE 100%!&#8221;<\/p>\n\n\n\n<p>&#8220;EU VOU CONSEGUIR!&#8221; &#8220;EU SEREI APROVADO!&#8221; &#8220;EU SOU INTELIGENTE&#8221;<\/p>\n\n\n\n<p>Fui de cursinho em cursinho contando minha hist\u00f3ria (EPCAR) e os meus resultados em F\u00edsica, Ingl\u00eas e Matem\u00e1tica (eu praticamente gabaritava essas disciplinas nos concursos militares)&#8230; Cada N\u00c3O recebido s\u00f3 aumentava a CERTEZA ABSOLUTA de que o pr\u00f3ximo iria dizer sim. <\/p>\n\n\n\n<p>H\u00e1 rumores de que houve um problema administrativo\/financeiro no Impacto em 1998. Ent\u00e3o, em 1999, um grupo de professores do Impacto decidiu criar seu pr\u00f3prio curso, algo totalmente novo&#8230; do zero&#8230; sem tradi\u00e7\u00e3o e sem aprova\u00e7\u00e3o alguma no curr\u00edculo.<\/p>\n\n\n\n<p>MEDO? AHAHAHAHAHHAHahahahahahahahahahahahahahaha&#8230;<\/p>\n\n\n\n<p>EU RIO NA CARA DO PERIGO, lembra? N\u00e3o sei se vai continuar assim quando as crian\u00e7as nascerem e eu vou buscar manter, por mais desafiador que seja.  :) <\/p>\n\n\n\n<p>Eu conhecia todos os professores, por que eu teria medo?<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/04\/04074139\/LINCOLN-E-DENISE.jpg\" alt=\"\" class=\"wp-image-176424\" width=\"338\" height=\"254\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/04\/04074139\/LINCOLN-E-DENISE.jpg 2048w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/04\/04074139\/LINCOLN-E-DENISE.jpg 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/04\/04074139\/LINCOLN-E-DENISE.jpg 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/04\/04074139\/LINCOLN-E-DENISE.jpg 1024w\" sizes=\"auto, (max-width: 338px) 100vw, 338px\" \/><figcaption>Lincoln Abrantes e Denise Modernel, amo voc\u00eas! Gratid\u00e3o ETERNA! :)<\/figcaption><\/figure><\/div>\n\n\n\n<p>\u00c9&#8230; foi l\u00e1 no Curso Planck Einstein (salvo melhor ju\u00edzo, n\u00e3o existe mais) que eu obtive a famigerada bolsa integral. Eu tive apoio da professora Denise Modernel e, talvez, tenha tido influ\u00eancia tamb\u00e9m de um bruxo f\u00edsico GIGANTE Lincoln Abrantes (Matem\u00e1tica\/F\u00edsica)&#8230;<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Lincoln foi s\u00f3 mestre do bruxo Dumbledore da saga Harry Potter (kkkkk) meu melhor professor de f\u00edsica e de matem\u00e1tica at\u00e9 hoje.<\/p>\n\n\n\n<p>A bolsa de estudos aqui na Terra foi dada por eles, mas uma coisa \u00e9 100% certa&#8230; pelo menos para mim&#8230; a M\u00c3O DE GIGANTE DELE estava l\u00e1 novamente para me aben\u00e7oar. (\u00c9 claro que eu estou falando de DEUS). <\/p>\n\n\n\n<p>Em 1998 eu havia prestado concurso para oficial INFANTARIA, pois n\u00e3o havia op\u00e7\u00e3o para aviador. Eu j\u00e1 havia desistido do meu sonho de ser piloto de ca\u00e7a, maaaaaaaaaaaaaaaaaaaaaaaaas &#8230; ah essa vida&#8230; essa vida&#8230; essa vida&#8230;. SAIU O EDITAL PARA OFICIAL AVIADOR! 10 VAGAS para todo Brasil, em 1999. <\/p>\n\n\n\n<p>Algu\u00e9m aqui acha que eu pensei duas vezes antes de decidir pela avia\u00e7\u00e3o? <\/p>\n\n\n\n<p>Se eu me lembro bem&#8230; n\u00e3o sei&#8230; acredito que eram 30 vagas para Infantaria, 60 para Intend\u00eancia e 10 para Avia\u00e7\u00e3o.<\/p>\n\n\n\n<p>Eu, naquele ano, j\u00e1 pertencia ao clube do bolinha (turma especial), pois arrebentava nos simulados, sempre sonhando com a primeira coloca\u00e7\u00e3o. Consegui duas ou tr\u00eas vezes em 1999. Foi incr\u00edvel! :) <\/p>\n\n\n\n<p>Quando me perguntavam para qual cargo eu iria prestar o concurso, sem hesitar eu respondia AVIA\u00c7\u00c3O! SEREI AVIADOR! J\u00e1 me vejo pilotando!<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/04\/04075013\/d%C3%BAvidas.png\" alt=\"\" class=\"wp-image-176427\" width=\"307\" height=\"138\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/04\/04075013\/d%C3%BAvidas.png 500w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/04\/04075013\/d%C3%BAvidas.png 300w\" sizes=\"auto, (max-width: 307px) 100vw, 307px\" \/><figcaption>Enquanto alguns plantavam d\u00favidas, eu plantava\/planto\/plantarei CERTEZAS. <\/figcaption><\/figure><\/div>\n\n\n\n<p>Algumas respostas recebidas:<\/p>\n\n\n\n<p>&#8220;Lacerda, s\u00e3o apenas 10 vagas!&#8221;<\/p>\n\n\n\n<p>&#8220;Voc\u00ea \u00e9 louco? S\u00e3o apenas 10 vagas&#8230; voc\u00ea teria o triplo de chances como infante e ainda muito mais como intendente, tem certeza?&#8221;<\/p>\n\n\n\n<p>Eles plantavam a d\u00favida e eu martelava a certeza absoluta dizendo:<\/p>\n\n\n\n<p>&#8220;Olha&#8230;. sinceramente&#8230; eu s\u00f3 tenho uma coisa a dizer&#8230; n\u00e3o s\u00e3o 10 vagas, s\u00e3o 9&#8230; apenas 9, pois UMA DELAS COM CERTEZA ABSOLUTA \u00c9 MINHA!&#8221;<\/p>\n\n\n\n<p>Para alguns eu poderia parecer um babaca, para outros, um arrogante, e para os meus amigos um cara legal, pois todos l\u00e1 no cursinho sabiam que eu sentava com aqueles que me procuravam para tirar d\u00favidas de matem\u00e1tica, f\u00edsica e ingl\u00eas (nos intervalos).<\/p>\n\n\n\n<p>Sempre me mostrei dispon\u00edvel para ajudar os outros. CRESCER E CONTRIBUIR instalado em mim desde novo&#8230; Olha eu aqui outra vez escrevendo os Passos de Gigante para voc\u00eas! <\/p>\n\n\n\n<p><strong>RESULTADO FINAL:  TERCEIRO COLOCADO NA AFA &#8211; PILOTO MILITAR<\/strong><\/p>\n\n\n\n<p>Ainda obtive a aprova\u00e7\u00e3o na ESCOLA NAVAL, 47\u00ba de 60 vagas. Acabei n\u00e3o fazendo algumas etapas do IME e nem do ITA, pois eu n\u00e3o queria SER engenheiro&#8230; meu sonho era ser piloto e n\u00e3o era de qualquer avi\u00e3o, tinha que ser de ca\u00e7a! <\/p>\n\n\n\n<p>Imagine um CHIP, de cora\u00e7\u00e3o, imagina mesmo. Agora, feche os olhos e imagine mais forte ainda. <\/p>\n\n\n\n<p>Como \u00e9 esse chip? O que voc\u00ea v\u00ea? Ele \u00e9 grande? pequeno? <\/p>\n\n\n\n<p>Qual a cor dele? Tem algo escrito nele? Se sim, o que \u00e9? <\/p>\n\n\n\n<p>Como s\u00e3o as letras? Em que cor est\u00e1 escrito?<\/p>\n\n\n\n<p>Ele est\u00e1 quente? Est\u00e1 frio?<\/p>\n\n\n\n<p>Deixe essa imagem o mais viva poss\u00edvel dentro da sua mente. <\/p>\n\n\n\n<p>Pronto&#8230; Fez isso&#8230; leu tudo o que escrevi acima?<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/04\/04075419\/CHIP-C%C3%89REBRO.jpg\" alt=\"\" class=\"wp-image-176428\" width=\"413\" height=\"232\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/04\/04075419\/CHIP-C%C3%89REBRO.jpg 1200w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/04\/04075419\/CHIP-C%C3%89REBRO.jpg 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/04\/04075419\/CHIP-C%C3%89REBRO.jpg 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/04\/04075419\/CHIP-C%C3%89REBRO.jpg 1024w\" sizes=\"auto, (max-width: 413px) 100vw, 413px\" \/><figcaption>CHIP da CERTEZA ABSOLUTA instalado com sucesso! :)<\/figcaption><\/figure><\/div>\n\n\n\n<p>Agora, sem ler, fa\u00e7a mentalmente e INSTALE O CHIP DA CERTEZA ABSOLUTA DA SUA APROVA\u00c7\u00c3O NO CONCURSO DOS SEUS SONHOS! <\/p>\n\n\n\n<p>Imagine de verdade voc\u00ea sendo aprovado e fortale\u00e7a essa cren\u00e7a dentro de voc\u00ea! Instalar esse chip pode parecer estranho no in\u00edcio, algu\u00e9m lembra de como foi dolorido para o Neo do filme Matrix? <\/p>\n\n\n\n<p>Depois que ele, Neo, viu os resultados, ele queria mais&#8230; cada vez mais!<\/p>\n\n\n\n<p>Sabe o que isso significa? Que a sua aprova\u00e7\u00e3o \u00e9 s\u00f3 um pedacinho do que pode ser transformado na sua vida!<\/p>\n\n\n\n<p>Eu estou aqui para te entregar muito mais do que sua aprova\u00e7\u00e3o, estamos falando de ter uma vida extraordin\u00e1ria! E a\u00ea, estamos JUNTOS? <\/p>\n\n\n\n<p>Quando voc\u00ea ir\u00e1 instalar esse chip da certeza absoluta? Responde para mim l\u00e1 nos coment\u00e1rios e Bora Boraaaaaaaaaaaaaaaaaaaaaaaaaaa! :) <\/p>\n\n\n\n<p>A partir daqui, eu deixo o segundo exerc\u00edcio de hoje. 04 DE ABRIL, CAP\u00cdTULO 4. <\/p>\n\n\n\n<p>Se voc\u00ea j\u00e1 fez, ok&#8230; se n\u00e3o sabe do que estou falando, leia as orienta\u00e7\u00f5es contidas nos <a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/passos-de-gigante-72-365\/\">Passos de Gigante 72.<\/a><\/p>\n\n\n\n<p>PROV\u00c9RBIOS &#8211; CAP\u00cdTULO 4 (Escrito por Salom\u00e3o, o homem mais s\u00e1bio do Universo)<\/p>\n\n\n\n<p>&#8220;Ou\u00e7am, meus filhos, a instru\u00e7\u00e3o de um pai; <strong>estejam atentos<\/strong>, e obter\u00e3o <strong>discernimento<\/strong>.<br \/>O ensino que lhes ofere\u00e7o \u00e9 bom; por isso n\u00e3o abandonem a minha instru\u00e7\u00e3o.<br \/>Quando eu era menino, ainda pequeno, em companhia de meu pai, um filho muito especial para minha m\u00e3e,<br \/>ele me ensinava e me dizia: &#8220;<strong>Apegue-se \u00e0s minhas palavras de todo o cora\u00e7\u00e3o;<\/strong> obede\u00e7a aos meus mandamentos, e voc\u00ea ter\u00e1 vida.<br \/><strong>Procure obter sabedoria e entendimento;<\/strong> n\u00e3o se esque\u00e7a das minhas palavras nem delas se afaste.<br \/>N\u00e3o abandone a sabedoria, e ela o proteger\u00e1; ame-a, e ela cuidar\u00e1 de voc\u00ea.<br \/><strong>O conselho da sabedoria \u00e9: procure obter sabedoria; use tudo que voc\u00ea possui para adquirir entendimento.<\/strong><br \/>Dedique alta estima \u00e0 sabedoria, e ela o exaltar\u00e1; abrace-a, e ela o honrar\u00e1.<br \/>Ela por\u00e1 um belo diadema sobre a sua cabe\u00e7a e lhe dar\u00e1 de presente uma coroa de esplendor&#8221;.<br \/>Ou\u00e7a, meu filho, e aceite o que digo, e voc\u00ea ter\u00e1 vida longa.<br \/>Eu o conduzi pelo caminho da sabedoria e o encaminhei por veredas retas.<br \/>Assim, quando voc\u00ea por elas seguir, <strong>n\u00e3o encontrar\u00e1 obst\u00e1culos;<\/strong> quando correr, <strong>n\u00e3o trope\u00e7ar\u00e1.<\/strong><br \/><strong>Apegue-se \u00e0 instru\u00e7\u00e3o,<\/strong> n\u00e3o a abandone; guarde-a bem, pois <strong>dela depende a sua vida.<\/strong><br \/>N\u00e3o siga pela vereda dos \u00edmpios nem ande no caminho dos maus.<br \/>Evite-o, n\u00e3o passe por ele; afaste-se e n\u00e3o se detenha.<br \/>Pois eles n\u00e3o conseguem dormir enquanto n\u00e3o fazem o mal; perdem o sono se n\u00e3o causarem a ru\u00edna de algu\u00e9m.<br \/>Pois eles se alimentam de maldade, e se embriagam de viol\u00eancia.<br \/>A vereda do justo \u00e9 como a luz da alvorada, que brilha cada vez mais at\u00e9 \u00e0 plena claridade do dia.<br \/>Mas o caminho dos \u00edmpios \u00e9 como densas trevas; nem sequer sabem em que trope\u00e7am.<br \/>Meu filho, escute o que lhe digo; <strong>preste aten\u00e7\u00e3o \u00e0s minhas palavras.<\/strong><br \/>Nunca as perca de vista; <strong>guarde-as no fundo do cora\u00e7\u00e3o,<\/strong><br \/>pois s\u00e3o vida para quem as encontra e sa\u00fade para todo o seu ser.<br \/>Acima de tudo, <strong>guarde o seu cora\u00e7\u00e3o, <\/strong>pois dele depende toda a sua vida.<br \/><strong>Afaste da sua boca as palavras perversas; <\/strong>fique longe dos seus l\u00e1bios a maldade.<br \/><strong>Olhe sempre para a frente, <\/strong>mantenha o olhar fixo no que est\u00e1 adiante de voc\u00ea.<br \/>Veja bem por onde anda, e os seus passos ser\u00e3o seguros.<br \/>N\u00e3o se desvie nem para a direita nem para a esquerda; afaste os seus p\u00e9s da maldade. (grifo nosso)<\/p>\n\n\n\n<p><a href=\"https:\/\/www.bibliaonline.com.br\/nvi\/pv\/4\/1-27+\">Prov\u00e9rbios 4:1-27<\/a><\/p>\n\n\n\n<p><strong>A\u00c7\u00c3O \u00c1GUIA!<\/strong> Lute! D\u00ea o seu melhor! O l\u00e1pis e o papel est\u00e3o contigo neste momento PRESENTE para voc\u00ea crescer e contribuir. O nosso Brasil precisa de voc\u00ea, de mim, de N\u00d3S! <\/p>\n\n\n\n<p>Fez isso? Parab\u00e9ns&#8230; estamos juntos na jornada rumo \u00e0 realiza\u00e7\u00e3o dos seus sonhos.  Abra\u00e7o de Giganteeeeeeeeeeeeeeeeeeeeeeeeee&#8230;!  <\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/01\/29045050\/OBRIGADO-DEUS.jpg\" alt=\"\" class=\"wp-image-162761\" width=\"336\" height=\"252\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/01\/29045050\/OBRIGADO-DEUS.jpg 960w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/01\/29045050\/OBRIGADO-DEUS.jpg 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/01\/29045050\/OBRIGADO-DEUS.jpg 768w\" sizes=\"auto, (max-width: 336px) 100vw, 336px\" \/><figcaption><a href=\"https:\/\/www.youtube.com\/channel\/UC_FRN4LBmIIhQBmUB8rlf8Q?view_as=subscriber\">GRATID\u00c3O ETERNA<\/a><\/figcaption><\/figure><\/div>\n\n\n\n<p><strong><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/como-me-tornei-afre-rj-auditor-fiscal-da-receita-estadual-do-rio-de-janeiro\/\">QUER&nbsp;CONHECER&nbsp;MINHA&nbsp;HIST\u00d3RIA?&nbsp;CLICA&nbsp;AQUI&nbsp;:)<\/a><\/strong><\/p>\n\n\n\n<p><strong><a href=\"https:\/\/www.youtube.com\/watch?v=Hx5oAsJmq4Q&amp;t=4s\">N\u00c3O&nbsp;GOSTA&nbsp;DE&nbsp;ESTUDAR&nbsp;E&nbsp;QUER&nbsp;SER&nbsp;ALGU\u00c9M&nbsp;NA&nbsp;VIDA?&nbsp;CLICA&nbsp;AQUI&nbsp;:)<\/a>\ufeff<\/strong><\/p>\n\n\n\n<p><strong>QUER VOAR RUMO AOS SEUS SONHOS, ENT\u00c3O SIGA MEU CONTE\u00daDO NAS REDES SOCIAIS EM\u2026&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Youtube:<\/strong>&nbsp;<a href=\"https:\/\/www.youtube.com\/channel\/UC_FRN4LBmIIhQBmUB8rlf8Q?view_as=subscriber\">RAPHAEL LACERDA &#8211; EDUCA\u00c7\u00c3O TOP<\/a><\/p>\n\n\n\n<p><strong>Facebook:<\/strong>&nbsp;<a href=\"https:\/\/www.facebook.com\/lacerdaf3\">LACERDAF3<\/a><\/p>\n\n\n\n<p><strong>Instagram:<\/strong>&nbsp;<a href=\"https:\/\/www.instagram.com\/lacerdaf3\/\">LACERDAF3<\/a><\/p>\n\n\n\n<p><strong>Twitter:<\/strong> <a href=\"https:\/\/twitter.com\/Lacerda300\">@Lacerda300<\/a><\/p>\n\n\n\n<p>Uma quinta-feira extraordin\u00e1ria! Fa\u00e7a os exerc\u00edcios propostos! S\u00f3 assim os resultados aparecer\u00e3o! :)  Que seus sonhos se tornem realidade&#8230; acreditem&#8230; \u00e9 poss\u00edvel&#8230; Aos astros e al\u00e9m!<\/p>\n\n\n\n<p>Raphael Lacerda &#8211; <a href=\"https:\/\/www.febracis.com.br\/\">Master Coach FEBRACIS (Federa\u00e7\u00e3o Brasileira de Coaching Integral Sist\u00eamico)<\/a> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fala \u00c1guia! Bom dia das Gal\u00e1xias! Faltam 6 dias para o DIA MAIS INCR\u00cdVEL no fant\u00e1stico mundo de @lacerdaf3 ! Quando me perguntam porque eu enfio F-3 em tudo o que eu fa\u00e7o, sabe o que eu respondo? \u00c9 TREINAMENTO DI\u00c1RIO! Imagine-se TODOS os dias em contato com algo que vai te levar para o [&hellip;]<\/p>\n","protected":false},"author":399,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1],"tags":[],"tax_estado":[],"class_list":["post-176419","post","type-post","status-publish","format-standard","hentry","category-cursos-e-concursos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>PASSOS DE GIGANTE 76\/365<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/passos-de-gigante-76\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PASSOS DE GIGANTE 76\/365\" \/>\n<meta property=\"og:description\" content=\"Fala \u00c1guia! Bom dia das Gal\u00e1xias! Faltam 6 dias para o DIA MAIS INCR\u00cdVEL no fant\u00e1stico mundo de @lacerdaf3 ! Quando me perguntam porque eu enfio F-3 em tudo o que eu fa\u00e7o, sabe o que eu respondo? \u00c9 TREINAMENTO DI\u00c1RIO! Imagine-se TODOS os dias em contato com algo que vai te levar para o [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/passos-de-gigante-76\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/lacerdaf3\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-04T11:04:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-04-06T07:42:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2019\/04\/sucesso.jpg\" \/>\n<meta name=\"author\" content=\"Raphael Lacerda (Coach BALBOA)\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@lacerda300\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Raphael Lacerda (Coach BALBOA)\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/passos-de-gigante-76\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/passos-de-gigante-76\/\"},\"author\":{\"name\":\"Raphael Lacerda (Coach BALBOA)\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/a969a78ade2f998675f42e056104a459\"},\"headline\":\"PASSOS DE GIGANTE 76\/365\",\"datePublished\":\"2019-04-04T11:04:23+00:00\",\"dateModified\":\"2019-04-06T07:42:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/passos-de-gigante-76\/\"},\"wordCount\":1991,\"commentCount\":4,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/passos-de-gigante-76\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2019\/04\/sucesso.jpg\",\"articleSection\":[\"Concursos P\u00fablicos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/passos-de-gigante-76\/#respond\"]}],\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/passos-de-gigante-76\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/passos-de-gigante-76\/\",\"name\":\"PASSOS DE GIGANTE 76\/365\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/passos-de-gigante-76\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/passos-de-gigante-76\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2019\/04\/sucesso.jpg\",\"datePublished\":\"2019-04-04T11:04:23+00:00\",\"dateModified\":\"2019-04-06T07:42:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/passos-de-gigante-76\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/passos-de-gigante-76\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/passos-de-gigante-76\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/04\/04072621\/sucesso.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/04\/04072621\/sucesso.jpg\",\"width\":960,\"height\":640},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/passos-de-gigante-76\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PASSOS DE GIGANTE 76\/365\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/a969a78ade2f998675f42e056104a459\",\"name\":\"Raphael Lacerda (Coach BALBOA)\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/ab5abefb897db03505e2ae6873cf14f2d801607a160754a767c3b17c8629a41d?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ab5abefb897db03505e2ae6873cf14f2d801607a160754a767c3b17c8629a41d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ab5abefb897db03505e2ae6873cf14f2d801607a160754a767c3b17c8629a41d?s=96&d=mm&r=g\",\"caption\":\"Raphael Lacerda (Coach BALBOA)\"},\"sameAs\":[\"http:\/\/www.educacaotop.com.br\",\"https:\/\/www.facebook.com\/lacerdaf3\",\"https:\/\/x.com\/lacerda300\"],\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/raphaelbalboaestrategiaconcursos-com-br\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"PASSOS DE GIGANTE 76\/365","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/passos-de-gigante-76\/","og_locale":"pt_BR","og_type":"article","og_title":"PASSOS DE GIGANTE 76\/365","og_description":"Fala \u00c1guia! Bom dia das Gal\u00e1xias! Faltam 6 dias para o DIA MAIS INCR\u00cdVEL no fant\u00e1stico mundo de @lacerdaf3 ! Quando me perguntam porque eu enfio F-3 em tudo o que eu fa\u00e7o, sabe o que eu respondo? \u00c9 TREINAMENTO DI\u00c1RIO! Imagine-se TODOS os dias em contato com algo que vai te levar para o [&hellip;]","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/passos-de-gigante-76\/","og_site_name":"Estrat\u00e9gia Concursos","article_author":"https:\/\/www.facebook.com\/lacerdaf3","article_published_time":"2019-04-04T11:04:23+00:00","article_modified_time":"2019-04-06T07:42:27+00:00","og_image":[{"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2019\/04\/sucesso.jpg","type":"","width":"","height":""}],"author":"Raphael Lacerda (Coach BALBOA)","twitter_card":"summary_large_image","twitter_creator":"@lacerda300","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Raphael Lacerda (Coach BALBOA)","Est. tempo de leitura":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/passos-de-gigante-76\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/passos-de-gigante-76\/"},"author":{"name":"Raphael Lacerda (Coach BALBOA)","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/a969a78ade2f998675f42e056104a459"},"headline":"PASSOS DE GIGANTE 76\/365","datePublished":"2019-04-04T11:04:23+00:00","dateModified":"2019-04-06T07:42:27+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/passos-de-gigante-76\/"},"wordCount":1991,"commentCount":4,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/passos-de-gigante-76\/#primaryimage"},"thumbnailUrl":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2019\/04\/sucesso.jpg","articleSection":["Concursos P\u00fablicos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/passos-de-gigante-76\/#respond"]}],"copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/passos-de-gigante-76\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/passos-de-gigante-76\/","name":"PASSOS DE GIGANTE 76\/365","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/passos-de-gigante-76\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/passos-de-gigante-76\/#primaryimage"},"thumbnailUrl":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2019\/04\/sucesso.jpg","datePublished":"2019-04-04T11:04:23+00:00","dateModified":"2019-04-06T07:42:27+00:00","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/passos-de-gigante-76\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/passos-de-gigante-76\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/passos-de-gigante-76\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/04\/04072621\/sucesso.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/04\/04072621\/sucesso.jpg","width":960,"height":640},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/passos-de-gigante-76\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"PASSOS DE GIGANTE 76\/365"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/a969a78ade2f998675f42e056104a459","name":"Raphael Lacerda (Coach BALBOA)","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/ab5abefb897db03505e2ae6873cf14f2d801607a160754a767c3b17c8629a41d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ab5abefb897db03505e2ae6873cf14f2d801607a160754a767c3b17c8629a41d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ab5abefb897db03505e2ae6873cf14f2d801607a160754a767c3b17c8629a41d?s=96&d=mm&r=g","caption":"Raphael Lacerda (Coach BALBOA)"},"sameAs":["http:\/\/www.educacaotop.com.br","https:\/\/www.facebook.com\/lacerdaf3","https:\/\/x.com\/lacerda300"],"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/raphaelbalboaestrategiaconcursos-com-br\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/176419","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/399"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=176419"}],"version-history":[{"count":10,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/176419\/revisions"}],"predecessor-version":[{"id":177074,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/176419\/revisions\/177074"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=176419"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=176419"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=176419"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=176419"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}