{"id":1742943,"date":"2026-03-29T19:23:00","date_gmt":"2026-03-29T22:23:00","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=1742943"},"modified":"2026-03-30T08:05:33","modified_gmt":"2026-03-30T11:05:33","slug":"gabarito-extraoficial-sefa-pa-fiscal-conhecimentos-especificos","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-sefa-pa-fiscal-conhecimentos-especificos\/","title":{"rendered":"Gabarito Extraoficial Sefa PA Fiscal: conhecimentos espec\u00edficos"},"content":{"rendered":"\n<p style=\"font-size:clamp(15.747px, 0.984rem + ((1vw - 3.2px) * 0.809), 24px);\"><em><strong>Confira neste artigo a corre\u00e7\u00e3o ao vivo e o gabarito extraoficial da prova de conhecimentos espec\u00edficos do concurso SEFA PA para Fiscal de Receitas!<\/strong><\/em><\/p>\n\n\n\n<p>Acontece neste domingo (29) a segunda etapa de <strong>provas do concurso da <a href=\"https:\/\/www.estrategiaconcursos.com.br\/cursosPorConcurso\/secretaria-da-fazendo-do-para-sefaz-pa\/\" target=\"_blank\" rel=\"noreferrer noopener\">Secretaria da Fazenda do Estado do Par\u00e1<\/a> (SEFA PA) para Fiscal de Receitas. <\/strong><\/p>\n\n\n\n<p>Nesta segunda data, ser\u00e1 aplicada a prova de Conhecimentos Espec\u00edficos do certame. A organiza\u00e7\u00e3o \u00e9 da empresa Fadesp.<\/p>\n\n\n\n<p>Dito isso, vale lembrar que o nosso time de especialistas estar\u00e1 ao seu lado durante essa etapa t\u00e3o importante, realizando a corre\u00e7\u00e3o <strong>AO VIVO!<\/strong><\/p>\n\n\n\n<p>A ideia \u00e9 que aqueles que participaram das provas possam conferir, de forma antecipada, seu desempenho por meio do Gabarito Extraoficial do <strong>concurso Sefa PA &#8211;<\/strong> <strong>Fiscal de Receitas<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-gabarito-extraoficial-sefa-pa-fiscal-conhecimentos-especificos\">Gabarito Extraoficial Sefa PA &#8211; Fiscal: conhecimentos espec\u00edficos<\/h2>\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"lyte-wrapper\" style=\"width:853px;max-width:100%;margin:5px;\"><div class=\"lyMe\" id=\"WYL_E_37LwOGkH4\"><div id=\"lyte_E_37LwOGkH4\" data-src=\"\/\/i.ytimg.com\/vi\/E_37LwOGkH4\/hqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\"><\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/E_37LwOGkH4\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/E_37LwOGkH4\/0.jpg\" alt=\"YouTube video thumbnail\" width=\"853\" height=\"460\" \/><br \/>Assista a este v\u00eddeo no YouTube<\/a><\/noscript><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:853px;margin:5px;\"><\/div><figcaption><\/figcaption><\/figure>\n\n\n<p>Abaixo, voc\u00ea confere os gabaritos das quest\u00f5es corrigidas pelos nossos professores. <strong>Aten\u00e7\u00e3o:<\/strong> a prova corrigida \u00e9 a vers\u00e3o <strong>TIPO 1<\/strong>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading has-text-align-center has-vivid-cyan-blue-color has-text-color has-link-color wp-elements-80bfd3e61cd133c97706dccda3c826a2\" id=\"h-d6-direito-tributario\"><strong>D6 &#8211; DIREITO TRIBUT\u00c1RIO<\/strong><\/h3>\n\n\n\n<p><strong>Quest\u00e3o 1:<\/strong> O princ\u00edpio da anterioridade tribut\u00e1ria, geral e nonagesimal,<br \/><strong>Resposta:<\/strong> (A) se aplica \u00e0s hip\u00f3teses de redu\u00e7\u00e3o ou de supress\u00e3o de benef\u00edcios&#8230;<\/p>\n\n\n\n<p><strong>Quest\u00e3o 2:<\/strong> Sobre responsabilidade tribut\u00e1ria do credor fiduci\u00e1rio na execu\u00e7\u00e3o fiscal, o STJ&#8230;<br \/><strong>Resposta:<\/strong> (D) o credor fiduci\u00e1rio, antes da consolida\u00e7\u00e3o da propriedade&#8230;<\/p>\n\n\n\n<p><strong>Quest\u00e3o 3:<\/strong> Acerca do Sistema Tribut\u00e1rio Nacional, a Constitui\u00e7\u00e3o Federal de 1988 disp\u00f5e o seguinte:<br \/><strong>Resposta:<\/strong> (C) sem preju\u00edzo de outras garantias asseguradas ao contribuinte&#8230;<\/p>\n\n\n\n<p><strong>Quest\u00e3o 4:<\/strong> Sobre o imposto de compet\u00eancia compartilhada entre Estados, Distrito Federal&#8230;<br \/><strong>Resposta:<\/strong> (A) o imposto sobre bens e servi\u00e7os de compet\u00eancia compartilhada&#8230;<\/p>\n\n\n\n<p><strong>Quest\u00e3o 5:<\/strong> Considere as seguintes afirmativas:<br \/><strong>Resposta:<\/strong> (E) I, II e III<\/p>\n\n\n\n<p><strong>Quest\u00e3o 6:<\/strong> A Lei 214\/2025 disp\u00f5e que o Imposto sobre Bens e Servi\u00e7os (IBS)&#8230;<br \/><strong>Resposta:<\/strong> (E) incidem sobre a transmiss\u00e3o, pelo contribuinte&#8230;<\/p>\n\n\n\n<p><strong>Quest\u00e3o 7:<\/strong> Acerca das normas gerais do Imposto sobre Bens e Servi\u00e7os (IBS) e da Contribui\u00e7\u00e3o Social&#8230;<br \/><strong>Resposta:<\/strong> *(B) se considera ocorrido o fato gerador do IBS e da CBS&#8230;<\/p>\n\n\n\n<p><strong>Quest\u00e3o 8:<\/strong> Sobre os Regimes Espec\u00edficos do IBS e da CBS, \u00e9 correto afirmar o seguinte:<br \/><strong>Resposta:<\/strong> (A) o IBS e a CBS incidir\u00e3o uma \u00fanica vez sobre as opera\u00e7\u00f5es&#8230;<\/p>\n\n\n\n<p><strong>Quest\u00e3o 9:<\/strong> A transi\u00e7\u00e3o para o IBS (Imposto sobre Bens e Servi\u00e7os) e e CBS&#8230;<br \/><strong>Resposta:<\/strong> (C) em rela\u00e7\u00e3o aos fatos geradores ocorridos de 1\u00ba de janeiro a 31 de dezembro de 2026&#8230;<\/p>\n\n\n\n<p><strong>Quest\u00e3o 10:<\/strong> A avalia\u00e7\u00e3o quinquenal do Imposto sobre Bens e Servi\u00e7os (IBS) \u00e9 um mecanismo&#8230;<br \/><strong>Resposta:<\/strong> (E) caso a soma das al\u00edquotas de refer\u00eancia estimadas de que trata&#8230;<\/p>\n\n\n\n<p><strong>Quest\u00e3o 11:<\/strong> Diante das disposi\u00e7\u00f5es legais do C\u00f3digo Tribut\u00e1rio Nacional, considere as seguintes afirmativas<br \/><strong>Resposta:<\/strong> (B) I e II, apenas<\/p>\n\n\n\n<p><strong>Quest\u00e3o 12:<\/strong> Acerca da disciplina jur\u00eddica do Imposto Estadual sobre a Propriedade de Ve\u00edculos Automotores&#8230;<br \/><strong>Resposta:<\/strong> (E) II, apenas.<\/p>\n\n\n\n<p><strong>Quest\u00e3o 13:<\/strong> A rela\u00e7\u00e3o entre o Fisco e o Contribuinte sofreu altera\u00e7\u00f5es com a Lei Complementar&#8230;<br \/><strong>Resposta:<\/strong> (B) II, apenas.<\/p>\n\n\n\n<p><strong>Quest\u00e3o 14:<\/strong> Sobre os ditames previstos na Lei Complementar n\u00ba 214\/2025 sobre&#8230;<br \/><strong>Resposta:<\/strong> (A) observada a disciplina estabelecida na legisla\u00e7\u00e3o aduaneira&#8230;<\/p>\n\n\n\n<p><strong>Quest\u00e3o 15:<\/strong> Sobre a harmoniza\u00e7\u00e3o do IBS e da CBS \u00e9 correto afirmar o seguinte<br \/><strong>Resposta:<\/strong> (D) o F\u00f3rum de Harmoniza\u00e7\u00e3o Jur\u00eddica das Procuradorias&#8230;<\/p>\n\n\n\n<p><strong>Quest\u00e3o 16:<\/strong> Sobre o Imposto Sobre Bens e Servi\u00e7os \u00e9 correto afirmar o seguinte&#8230;<br \/><strong>Resposta:<\/strong> (C) ser\u00e1 cobrado pelo somat\u00f3rio das al\u00edquotas do Estado&#8230;<\/p>\n\n\n\n<p><strong>Quest\u00e3o 17:<\/strong> Sobre a disciplina jur\u00eddica do Comit\u00ea Gestor \u00e9 correto afirmar o seguinte:<br \/><strong>Resposta:<\/strong> (A) na forma de lei complementar, o controle externo do Comit\u00ea&#8230;<\/p>\n\n\n\n<p><strong>Quest\u00e3o 18:<\/strong> Considerando as disposi\u00e7\u00f5es legais da Lei Complementar n\u00ba 214\/2025, \u00e9 correto afirmar o seguinte:<br \/><strong>Resposta:<\/strong> (E) Ato Conjunto do Minist\u00e9rio da Fazenda e do Comit\u00ea Gestor&#8230;<\/p>\n\n\n\n<p><strong>Quest\u00e3o 19:<\/strong> Sobre reparti\u00e7\u00e3o de receitas tribut\u00e1rias, \u00e9 correto afirmar que<br \/><strong>Resposta:<\/strong> (C) a Uni\u00e3o, os Estados, o Distrito Federal e&#8230;<\/p>\n\n\n\n<p><strong>Quest\u00e3o 20:<\/strong> O Estado do Par\u00e1 destaca-se pela expressiva disponibilidade de bens naturais&#8230;<br \/><strong>Resposta:<\/strong> (D) n\u00e3o incidir\u00e1 ICMS sobre opera\u00e7\u00f5es que destine&#8230;<\/p>\n\n\n\n<p><strong>Quest\u00e3o 21:<\/strong> Sobre a disciplina jur\u00eddica dos impostos no Sistema Tribut\u00e1rio Nacional considere&#8230;<br \/><strong>Resposta:<\/strong> (E) I, Il e III, apenas.<\/p>\n\n\n\n<p><strong>Quest\u00e3o 22:<\/strong> Considerando as disposi\u00e7\u00f5es legais sobre responsabilidade solid\u00e1ria, responsabilidade&#8230;<br \/><strong>Resposta:<\/strong> (A) nos casos de impossibilidade de exig\u00eancia do cumprimento&#8230;<\/p>\n\n\n\n<p><strong>Quest\u00e3o 23:<\/strong> Considere a seguinte situa\u00e7\u00e3o hipot\u00e9tica:<br \/><strong>Resposta:<\/strong> (C) os tributos incidentes at\u00e9 a data da aliena\u00e7\u00e3o&#8230;<\/p>\n\n\n\n<p><strong>Quest\u00e3o 24:<\/strong> obre a disciplina jur\u00eddica das taxas no Sistema Tribut\u00e1rio Nacional, \u00e9 correto afirmar que<br \/><strong>Resposta:<\/strong> *(C) as taxas municipais de fiscaliza\u00e7\u00e3o e funcionamento<\/p>\n\n\n\n<p><strong>Quest\u00e3o 25:<\/strong> Lei estadual instituiu taxa de utiliza\u00e7\u00e3o de servi\u00e7os p\u00fablicos de preven\u00e7\u00e3o e combate&#8230;<br \/><strong>Resposta:<\/strong> (E) constitucional pela cobran\u00e7a de taxas pela utiliza\u00e7\u00e3o&#8230;<\/p>\n\n\n\n<p><strong>Quest\u00e3o 26:<\/strong> A entidade religiosa Tr\u00eas Cora\u00e7\u00f5es \u00e9 propriet\u00e1ria de um im\u00f3vel&#8230;<br \/><strong>Resposta:<\/strong> (A) a imunidade tribut\u00e1ria para templos de qualquer culto&#8230;<\/p>\n\n\n\n<p><strong>Quest\u00e3o 27:<\/strong> Na realiza\u00e7\u00e3o da atividade fiscalizat\u00f3ria tribut\u00e1ria, um contribuinte foi notificado&#8230;<br \/><strong>Resposta:<\/strong> (A) I, apenas.<\/p>\n\n\n\n<p><strong>Quest\u00e3o 28:<\/strong> Sobre o Simples Nacional e a Lei Complementar n\u00ba 123\/06, avalie as afirmativas abaixo:<br \/><strong>Resposta:<\/strong> (B) I e III, apenas.<\/p>\n\n\n\n<p><strong>Quest\u00e3o 29:<\/strong> Sobre a Lei Complementar n\u00ba 214\/2025, \u00e9 correto afirmar o seguinte:<br \/><strong>Resposta:<\/strong> (C) ficam reduzidas em 60% (sessenta por cento) as al\u00edquotas do IBS e da CBS&#8230;<\/p>\n\n\n\n<p><strong>Quest\u00e3o 30:<\/strong> De acordo com a Lei Complementar n\u00ba 214\/2025, \u00e9\/s\u00e3o opera\u00e7\u00e3o\/opera\u00e7\u00f5es&#8230;<br \/><strong>Resposta:<\/strong> (A) servi\u00e7os prestados por Institui\u00e7\u00e3o Cient\u00edfica, Tecnol\u00f3gica e de Inova\u00e7\u00e3o (ICT)&#8230;<\/p>\n\n\n\n<h3 class=\"wp-block-heading has-text-align-center has-vivid-cyan-blue-color has-text-color has-link-color wp-elements-7fbd4222cc5eac7dbbd9f4b3f4c43108\" id=\"h-d7-legislacao-tributaria-do-estado-do-para\"><strong>D7 &#8211; LEGISLA\u00c7\u00c3O TRIBUT\u00c1RIA DO ESTADO DO PAR\u00c1<\/strong><\/h3>\n\n\n\n<p><strong>Quest\u00e3o 31:<\/strong> Sobre os benef\u00edcios fiscais concedidos nos termos da Lei Complementar Federal n\u00ba 24\/1975&#8230;<br \/><strong>Resposta:<\/strong> (E) a concess\u00e3o de benef\u00edcios depender\u00e1 sempre de decis\u00e3o un\u00e2nime&#8230;<\/p>\n\n\n\n<p><strong>Quest\u00e3o 32:<\/strong> Quanto ao ordenamento jur\u00eddico relacionado \u00e0 concess\u00e3o de incentivos fiscais&#8230;<br \/><strong>Resposta:<\/strong> (B) \u00e9 poss\u00edvel que isen\u00e7\u00f5es, mesmo aquelas criadas sem autoriza\u00e7\u00e3o do CONFAZ&#8230;<\/p>\n\n\n\n<p><strong>Quest\u00e3o 33:<\/strong> A respeito da compet\u00eancia tribut\u00e1ria do ICMS (Imposto Sobre Opera\u00e7\u00f5es Relativas \u00e0&#8230;<br \/><strong>Resposta:<\/strong> (A) ressalvadas as exce\u00e7\u00f5es expressas na lista anexa \u00e0 Lei Complementar Federal n\u00ba 116\/2003&#8230;<\/p>\n\n\n\n<p><strong>Quest\u00e3o 34:<\/strong> Observado o C\u00f3digo de direitos, garantias e obriga\u00e7\u00f5es do Contribuinte do Estado do Par\u00e1&#8230;<br \/><strong>Resposta:<\/strong> (D) \u00e9 permitido \u00e0 fiscaliza\u00e7\u00e3o, na hip\u00f3tese de recusa da exibi\u00e7\u00e3o de livros&#8230;<\/p>\n\n\n\n<p><strong>Quest\u00e3o 35:<\/strong> Considere as seguintes afirmativas:<br \/><strong>Resposta:<\/strong> (A) I e II, apenas.<\/p>\n\n\n\n<p><strong>Quest\u00e3o 36:<\/strong> Observada a disciplina do ICMS \u2013 Imposto Sobre Opera\u00e7\u00f5es Relativas \u00e0 Circula\u00e7\u00e3o&#8230;<br \/><strong>Resposta:<\/strong> (B) o imposto incide sobre a entrada, no territ\u00f3rio do Estado destinat\u00e1rio&#8230;<\/p>\n\n\n\n<p><strong>Quest\u00e3o 37:<\/strong> Sobre o ICMS &#8211; Imposto Sobre Opera\u00e7\u00f5es Relativas \u00e0 Circula\u00e7\u00e3o de Mercadorias&#8230;<br \/><strong>Resposta:<\/strong> (A) a inobserv\u00e2ncia dos comandos da Lei Complementar n\u00ba 24\/1975&#8230;<\/p>\n\n\n\n<p><strong>Quest\u00e3o 38:<\/strong> O art. 20 da Lei Complementar Federal n\u00ba 87\/1996 assegura aos contribuintes do ICMS&#8230;<br \/><strong>Resposta:<\/strong> (D) ao final do quadrag\u00e9simo oitavo m\u00eas contado da data da entrada&#8230;<\/p>\n\n\n\n<p><strong>Quest\u00e3o 39:<\/strong> O art. 20 da Lei Complementar Federal n\u00ba 87\/1996 assegura aos contribuintes do ICMS&#8230;<br \/><strong>Resposta:<\/strong> (C) somente dar\u00e3o direito de cr\u00e9dito as mercadorias destinadas ao&#8230;<\/p>\n\n\n\n<p><strong>Quest\u00e3o 40:<\/strong> Os saldos credores acumulados do ICMS (Imposto Sobre Opera\u00e7\u00f5es Relativa&#8230;<br \/><strong>Resposta:<\/strong> (E) poder\u00e3o ser transferidos, nas condi\u00e7\u00f5es definida&#8230;<\/p>\n\n\n\n<p><strong>Quest\u00e3o 41:<\/strong> Observada a disciplina do ICMS \u2013 Imposto Sobre Opera\u00e7\u00f5es Relativas \u00e0 Circula\u00e7\u00e3o&#8230;<br \/><strong>Resposta:<\/strong> (C) quando a isen\u00e7\u00e3o do imposto depender de condi\u00e7\u00e3o a&#8230;<\/p>\n\n\n\n<p><strong>Quest\u00e3o 42:<\/strong> Observada a disciplina do ICMS &#8211; Imposto Sobre Opera\u00e7\u00f5es Relativas&#8230;<br \/><strong>Resposta:<\/strong> (A) o montante do pr\u00f3prio imposto integra a base de c\u00e1lculo&#8230;<\/p>\n\n\n\n<p><strong>Quest\u00e3o 43:<\/strong> Sobre a figura do sujeito passivo da obriga\u00e7\u00e3o tribut\u00e1ria do ICMS&#8230;<br \/><strong>Resposta:<\/strong> (B) \u00e9 tamb\u00e9m contribuinte a pessoa f\u00edsica<br \/>ou jur\u00eddica que&#8230;<\/p>\n\n\n\n<p><strong>Quest\u00e3o 44:<\/strong> Sobre o Processo Administrativo Tribut\u00e1rio, consoante Lei Estadual&#8230;<br \/><strong>Resposta:<\/strong> (D) a impugna\u00e7\u00e3o ser\u00e1 indeferida quando o sujeito passivo<\/p>\n\n\n\n<p><strong>Quest\u00e3o 45:<\/strong> O Tribunal Administrativo de Recursos Fazend\u00e1rios \u2013 TARF &#8211; tem seu&#8230;<br \/><strong>Resposta:<\/strong> (D) compete, embora n\u00e3o exclusivamente, a qualquer integrante<\/p>\n\n\n\n<p><strong>Quest\u00e3o 46: <\/strong>Conforme Regulamento do ICMS \u2013 Imposto Sobre Opera\u00e7\u00f5es Relativas&#8230;<br \/><strong>Resposta:<\/strong> (E) a sa\u00edda interna e interestadual de bem desincorporado&#8230;<\/p>\n\n\n\n<p><strong>Quest\u00e3o 47:<\/strong> O RICMS, aprovado pelo Decreto n.\u00b0 4.676\/01&#8230;<br \/><strong>Resposta:<\/strong> (C) os conv\u00eanios de natureza autorizativa&#8230;<\/p>\n\n\n\n<p><strong>Quest\u00e3o 48:<\/strong> Sobre o recolhimento do ICMS, consoante disposto no RICMS&#8230;<br \/><strong>Resposta:<\/strong> (C) no caso de mercadorias sujeitas ao regime de antecipa\u00e7\u00e3o do ICMS&#8230;<\/p>\n\n\n\n<p><strong>Quest\u00e3o 49:<\/strong> Considere as seguintes afirmativas:<br \/><strong>Resposta:<\/strong> (D) I e III, apenas.<\/p>\n\n\n\n<p><strong>Quest\u00e3o 50:<\/strong> Observado o RICMS\/PA, aprovado pelo Decreto n.\u00b0 4.676\/01, considere as seguintes afirmativas:<br \/><strong>Resposta:<\/strong> (C) III e IV, apenas.<\/p>\n\n\n\n<p><strong>Quest\u00e3o 51:<\/strong> A respeito do Imposto sobre a Propriedade de Ve\u00edculos Automotores&#8230;<br \/><strong>Resposta:<\/strong> (B) em se tratando de ve\u00edculo de propriedade de empresa&#8230;<\/p>\n\n\n\n<p><strong>Quest\u00e3o 52:<\/strong> Sobre o Imposto sobre a Transmiss\u00e3o Causa Mortis e Doa\u00e7\u00e3o \u2013 ITCMD&#8230;<br \/><strong>Resposta:<\/strong> (A) \u00e9 isenta de ITCMD a aquisi\u00e7\u00e3o, por transmiss\u00e3o &#8220;Causa Mortis&#8221;, de im\u00f3vel&#8230;<\/p>\n\n\n\n<p><strong>Quest\u00e3o 53:<\/strong> Observando a Taxa de Controle, Acompanhamento e Fiscaliza\u00e7\u00e3o das&#8230;<br \/><strong>Resposta:<\/strong> (E) tanto na TFRM quanto na TFRH, a Autoridade lan\u00e7adora&#8230;<\/p>\n\n\n\n<p><strong>Quest\u00e3o 54:<\/strong> O RICMS, aprovado pelo Decreto n.\u00b0 4.676\/01, coloca que&#8230;<br \/><strong>Resposta:<\/strong> (B) respondem pela infra\u00e7\u00e3o, conjunta ou isoladamente&#8230;<\/p>\n\n\n\n<p><strong>Quest\u00e3o 55:<\/strong> Considerando as normas do RICMS\/PA, aprovado pelo Decreto n.\u00ba 4.676\/01&#8230;<br \/><strong>Resposta:<\/strong> (C) I e IV, apenas.<\/p>\n\n\n\n<h3 class=\"wp-block-heading has-text-align-center has-vivid-cyan-blue-color has-text-color has-link-color wp-elements-2a190e858684f7268ea900e2bf3fb7c3\" id=\"h-d8-contabilidade-geral\"><strong>D8 &#8211; CONTABILIDADE GERAL<\/strong><\/h3>\n\n\n\n<p><strong>Quest\u00e3o 56:<\/strong> A comercial Tucunar\u00e9 na Brasa Ltda, no primeiro trimestre de 2025&#8230;<br \/><strong>Resposta:<\/strong> (B) R$ 114.200,00.<\/p>\n\n\n\n<p><strong>Quest\u00e3o 57:<\/strong> A escola de samba Acad\u00eamicos do Gr\u00e3o-Par\u00e1, entidade&#8230;<br \/><strong>Resposta:<\/strong> *(E) R$ 7.500,00 positivo e R$ 14.000,00 positivo.<\/p>\n\n\n\n<p><strong>Quest\u00e3o 58:<\/strong> No segundo semestre de 2025, a escola de samba Acad\u00eamicos do Tacac\u00e1&#8230;<br \/><strong>Resposta:<\/strong> (A) o reconhecimento de despesas incorridas, ainda que n\u00e3o pagas&#8230;<\/p>\n\n\n\n<p><strong>Quest\u00e3o 59:<\/strong> A Cia Castanhal S\/A, ao elaborar suas demonstra\u00e7\u00f5es cont\u00e1beis&#8230;<br \/><strong>Resposta:<\/strong> (B) a an\u00e1lise da opera\u00e7\u00e3o deve priorizar a ess\u00eancia econ\u00f4mica do contrato&#8230;<\/p>\n\n\n\n<p><strong>Quest\u00e3o 60:<\/strong> Ao analisar a contabilidade da Cia Parauapebas S\/A, surgiram d\u00favidas&#8230;<br \/><strong>Resposta:<\/strong> (E) permutativo, modificativo aumentativo e modificativo diminutivo.<\/p>\n\n\n\n<p><strong>Quest\u00e3o 61:<\/strong> A empresa Peixe Boi Ltda, do setor de tecnologia, incorreu&#8230;<br \/><strong>Resposta:<\/strong> (A) os gastos do primeiro exerc\u00edcio devem ser reconhecidos&#8230;<\/p>\n\n\n\n<p><strong>Quest\u00e3o 62:<\/strong> A Cia Moju S.A elaborou suas demonstra\u00e7\u00f5es cont\u00e1beis em 31\/12\/2025&#8230;<br \/><strong>Resposta:<\/strong> (D) I, III e IV, apenas.<\/p>\n\n\n\n<p><strong>Quest\u00e3o 63:<\/strong> A contadora Sra. Maria Paraense, com registro ativo do Conselho&#8230;<br \/><strong>Resposta:<\/strong> (E) I, II, IIl e IV<\/p>\n\n\n\n<p><strong>Quest\u00e3o 64:<\/strong> Em 31\/12\/2025, \u043e \u0441ontador da Comercial Portel Ltda, com o objetivo&#8230;<br \/><strong>Resposta:<\/strong> (C) o patrim\u00f4nio l\u00edquido resultou em R$ 520.000,00.<\/p>\n\n\n\n<p><strong>Quest\u00e3o 65:<\/strong> A Cia Tail\u00e2ndia S.A, sociedade an\u00f4nima de capital aberto&#8230;<br \/><strong>Resposta:<\/strong> (B) o valor adicionado gerado pela entidade corresponde a R$ 580.000,00&#8230;<\/p>\n\n\n\n<p><strong>Quest\u00e3o 66:<\/strong> A empresa Altamira S.A possui participa\u00e7\u00e3o societ\u00e1ria na empresa&#8230;<br \/><strong>Resposta:<\/strong> (D) I, III e IV, apenas.<\/p>\n\n\n\n<p><strong>Quest\u00e3o 67:<\/strong> A companhia Grupo Oriximin\u00e1 S.A controla integralmente a empresa&#8230;<br \/><strong>Resposta:<\/strong> (E) as demonstra\u00e7\u00f5es consolidadas do Grupo Oriximin\u00e1 S.A devem&#8230;<\/p>\n\n\n\n<p><strong>Quest\u00e3o 68:<\/strong> A Cia Medicil\u00e2ndia S.A det\u00e9m participa\u00e7\u00e3o societ\u00e1ria na Cia Uruar\u00e1&#8230;<br \/><strong>Resposta:<\/strong> (A) a Cia Medicil\u00e2ndia S.A deve reclassificar, para a demonstra\u00e7\u00e3o do resultado&#8230;<\/p>\n\n\n\n<p><strong>Quest\u00e3o 69:<\/strong> Visando a ampliar sua capacidade de estocagem de pescados para atender&#8230;<br \/><strong>Resposta:<\/strong> (C) os ativos, passivos, receitas e despesas das controladas&#8230;<\/p>\n\n\n\n<p><strong>Quest\u00e3o 70:<\/strong> A empresa comercial Paragominas Ltda apresenta as seguintes opera\u00e7\u00f5es&#8230;<br \/><strong>Resposta:<\/strong> (A) R$ 22.500,00 e R$ 28.500,00.<\/p>\n\n\n\n<p><strong>Quest\u00e3o 71:<\/strong> A Comercial Santar\u00e9m Ltda, sociedade empres\u00e1ria que trabalha&#8230;<br \/><strong>Resposta:<\/strong> (D) R$ 100.000,00.<\/p>\n\n\n\n<p><strong>Quest\u00e3o 72:<\/strong> Considerando-se as informa\u00e7\u00f5es constantes na quest\u00e3o anterior&#8230;<br \/><strong>Resposta:<\/strong> (E) R$ 120.000,00.<\/p>\n\n\n\n<p><strong>Quest\u00e3o 73:<\/strong> A Cia Nova Ipixuna S.A contratou um contador para organizar suas opera\u00e7\u00f5es&#8230;<br \/><strong>Resposta:<\/strong> (A) R$ 176.400,00.<\/p>\n\n\n\n<p><strong>Quest\u00e3o 74:<\/strong> O Sistema P\u00fablico de Escritura\u00e7\u00e3o Digital (SPED) e seus respectivos projetos&#8230;<br \/><strong>Resposta:<\/strong> (E) 1, II, III e IV.<\/p>\n\n\n\n<p><strong>Quest\u00e3o 75:<\/strong> A empresa Xinguara Ltda e a empresa Reden\u00e7\u00e3o S\/S Ltda&#8230;<br \/><strong>Resposta:<\/strong> (C) II e III, apenas.<\/p>\n\n\n\n<h3 class=\"wp-block-heading has-text-align-center has-vivid-cyan-blue-color has-text-color has-link-color wp-elements-77c5a8513934f9d9525b8254d0b6ac75\" id=\"h-d9-direito-constitucional\"><strong>D9 &#8211; DIREITO CONSTITUCIONAL<\/strong><\/h3>\n\n\n\n<p><strong>Quest\u00e3o 76:<\/strong> Sobre o estado de calamidade p\u00fablica de \u00e2mbito nacional, institu\u00eddo&#8230;<br \/><strong>Resposta:<\/strong> (C) a compet\u00eancia para sua institui\u00e7\u00e3o \u00e9 do Congresso Nacional&#8230;<\/p>\n\n\n\n<p><strong>Quest\u00e3o 77:<\/strong> Sobre a acumula\u00e7\u00e3o remunerada de cargos p\u00fablicos, \u00e9 correto afirmar que<br \/><strong>Resposta:<\/strong> (E) h\u00e1 possibilidade de acumula\u00e7\u00e3o de dois cargos&#8230;<\/p>\n\n\n\n<p><strong>Quest\u00e3o 78:<\/strong> Sobre o sistema tribut\u00e1rio nacional, \u00e9 correto afirmar que&#8230;<br \/><strong>Resposta:<\/strong> (D) a Emenda Constitucional n\u00ba 132, de 20 de dezembro&#8230;<\/p>\n\n\n\n<p><strong>Quest\u00e3o 79:<\/strong> Sobre nacionalidade, \u00e9 correto afirmar que s\u00e3o brasileiros natos<br \/><strong>Resposta:<\/strong> (A) os nascidos no estrangeiro de pai brasileiro, desde&#8230;<\/p>\n\n\n\n<p><strong>Quest\u00e3o 80:<\/strong> Sobre o <em>habeas corpus<\/em>, \u00e9 correto afirmar que a compet\u00eancia de julgamento \u00e9 do<br \/><strong>Resposta:<\/strong> (B) Supremo Tribunal Federal para julgar recurso ordin\u00e1rio de <em>habeas corpus<\/em>&#8230;<\/p>\n\n\n\n<p><strong>Quest\u00e3o 81:<\/strong> Sobre o mandado de seguran\u00e7a, \u00e9 correto afirmar que<br \/><strong>Resposta:<\/strong> (E) a defesa de direitos individuais homog\u00eaneos&#8230;<\/p>\n\n\n\n<p><strong>Quest\u00e3o 82:<\/strong> Sobre direitos pol\u00edticos, \u00e9 correto afirmar que<br \/><strong>Resposta:<\/strong> (A) aqueles que tiveram seus direitos pol\u00edticos suspensos&#8230;<\/p>\n\n\n\n<p><strong>Quest\u00e3o 83:<\/strong> Sobre as compet\u00eancias constitucionais da Uni\u00e3o, dos Estados, do Distrito Federal&#8230;<br \/><strong>Resposta:<\/strong> (B) or\u00e7amento compete concorrentemente \u00e0 Uni\u00e3o&#8230;<\/p>\n\n\n\n<p><strong>Quest\u00e3o 84:<\/strong> Sobre a interven\u00e7\u00e3o nos Estados e Munic\u00edpios, \u00e9 correto afirmar que&#8230;<br \/><strong>Resposta:<\/strong> (D) deixar de entregar aos Munic\u00edpios receitas tribut\u00e1rias&#8230;<\/p>\n\n\n\n<p><strong>Quest\u00e3o 85:<\/strong> Sobre direitos e deveres individuais e coletivos, \u00e9 correto afirmar que<br \/><strong>Resposta:<\/strong> (B) \u00e9 inviol\u00e1vel o sigilo das comunica\u00e7\u00f5es telef\u00f4nicas&#8230;<\/p>\n\n\n\n<p><strong>Quest\u00e3o 86:<\/strong> Sobre o processo legislativo, \u00e9 correto afirmar que<br \/><strong>Resposta:<\/strong> (C) as emendas \u00e0 Constitui\u00e7\u00e3o n\u00e3o est\u00e3o&#8230;<\/p>\n\n\n\n<p><strong>Quest\u00e3o 87:<\/strong> Sobre organiza\u00e7\u00e3o pol\u00edtico-administrativa, \u00e9 correto afirmar que<br \/><strong>Resposta:<\/strong> (B) o n\u00famero de Deputados \u00e0 Assembleia Legislativa&#8230;<\/p>\n\n\n\n<p><strong>Quest\u00e3o 88:<\/strong> Sobre a administra\u00e7\u00e3o p\u00fablica, \u00e9 correto afirmar que<br \/><strong>Resposta:<\/strong> (C) a veda\u00e7\u00e3o de percep\u00e7\u00e3o simult\u00e2nea de proventos de aposentadoria&#8230;<\/p>\n\n\n\n<p><strong>Quest\u00e3o 89:<\/strong> Sobre defesa do estado e das institui\u00e7\u00f5es democr\u00e1ticas, \u00e9 correto afirmar que<br \/><strong>Resposta:<\/strong> (E) na vig\u00eancia de estado de defesa ou de estado de s\u00edtio, n\u00e3o se pode emendar a Constitui\u00e7\u00e3o.<\/p>\n\n\n\n<p><strong>Quest\u00e3o 90:<\/strong> Sobre princ\u00edpios gerais da atividade econ\u00f4mica e financeira, \u00e9 correto afirmar que<br \/><strong>Resposta:<\/strong> (D) a Constitui\u00e7\u00e3o da Rep\u00fablica Federativa do&#8230;<\/p>\n\n\n\n<h3 class=\"wp-block-heading has-text-align-center has-vivid-cyan-blue-color has-text-color has-link-color wp-elements-e3989c285e8fba4562b813c7db7a678d\" id=\"h-10-economia-regional\"><strong>10 &#8211; ECONOMIA REGIONAL<\/strong><\/h3>\n\n\n\n<p><strong>Quest\u00e3o 91:<\/strong> Considere as seguintes afirmativas sobre os indicadores sociais de sa\u00fade no Estado do Par\u00e1<br \/><strong>Resposta:<\/strong> (A) I, apenas.<\/p>\n\n\n\n<p><strong>Quest\u00e3o 92:<\/strong> Considere as seguintes afirmativas sobre os indicadores sociais de educa\u00e7\u00e3o no Estado do Par\u00e1<br \/><strong>Resposta:<\/strong> (B) I e III, apenas<\/p>\n\n\n\n<p><strong>Quest\u00e3o 93:<\/strong> Considere as seguintes afirmativas sobre o mercado de trabalho paraense<br \/><strong>Resposta:<\/strong> (E) II e III, \u0430\u0440enas.<\/p>\n\n\n\n<p><strong>Quest\u00e3o 94:<\/strong> Considere as seguintes afirmativas sobre a balan\u00e7a comercial paraense:<br \/><strong>Resposta:<\/strong> (A) I, apenas.<\/p>\n\n\n\n<p><strong>Quest\u00e3o 95:<\/strong> Sobre os indicadores sociais do Estado do Par\u00e1, \u00e9 correto afirmar que, entre<br \/><strong>Resposta:<\/strong> (E) 2013 e 2023, o acesso \u00e0 internet nos domic\u00edlios cresceu&#8230;<\/p>\n\n\n\n<p><strong>Quest\u00e3o 96:<\/strong> Considere as seguintes afirmativas sobre os indicadores ambientais paraenses:<br \/><strong>Resposta:<\/strong> *recurso*<\/p>\n\n\n\n<p><strong>Quest\u00e3o 97:<\/strong> Considere as seguintes afirmativas sobre o mercado de trabalho paraense:<br \/><strong>Resposta:<\/strong> (C) III, apenas.<\/p>\n\n\n\n<p><strong>Quest\u00e3o 98:<\/strong> Sobre os setores florestal e de silvicultura paraenses, \u00e9 correto afirmar que:<br \/><strong>Resposta:<\/strong> (C) considerando os dados da silvicultura paraense&#8230;<\/p>\n\n\n\n<p><strong>Quest\u00e3o 99:<\/strong> Sobre a infraestrutura de transportes no Estado do Par\u00e1, \u00e9 correto afirmar que<br \/><strong>Resposta:<\/strong> (B) em 2010, o n\u00famero de ve\u00edculos n\u00e3o licenciados (373 mil)&#8230;<\/p>\n\n\n\n<p><strong>Quest\u00e3o 100:<\/strong> Considere as seguintes afirmativas sobre as contas regionais do Estado do Par\u00e1:<br \/><strong>Resposta:<\/strong> (D) II e III, apenas<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-dots\"\/>\n\n\n\n<p class=\"has-text-align-center\"><em>Para ficar por dentro de todas as informa\u00e7\u00f5es sobre o concurso SEFA PA 2026, al\u00e9m do gabaritos extraoficial da prova de conhecimentos espec\u00edficos, n\u00e3o deixe de conferir nosso artigo completo sobre a sele\u00e7\u00e3o:<\/em><\/p>\n\n\n\n<p class=\"has-text-align-center has-background\" style=\"background-color:#e6ecf1\"><strong><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-sefa-pa\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concurso Sefa PA<\/a><\/strong><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"has-text-align-center has-x-large-font-size\" id=\"cursos-assinatura\"><strong><em>Cursos para o concurso Sefa<\/em> <em>PA<\/em>:<\/strong><\/p>\n\n\n\n<div id=\"boxes\" class=\"container\">\n<div class=\"row\">\n<div class=\"col-sm\">\n<div id=\"box-assinatura\" class=\"banner-sefaz-ec\">\n<h3 class=\"titulo-assinatura\">Curso Concurso Sefa PA<\/h3>\n<p class=\"subtitulo-assinatura\">Prepare-se com o Estrat\u00e9gia! \u270d<\/p>\n<div class=\"box-botao\"><a class=\"btn-assinatura\" role=\"button\" href=\"https:\/\/www.estrategiaconcursos.com.br\/cursosPorConcurso\/secretaria-da-fazendo-do-para-sefaz-pa\/\" target=\"_blank\" rel=\"noopener noreferrer\">VER CURSOS<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"container\" id=\"boxes\">\n  <div class=\"row\">\n\n    <div class=\"col-sm\">\n      <div class=\"estrategia\" id=\"box-assinatura\">\n        <h3 class=\"titulo-assinatura\">Assinatura Concursos<\/h3>\n        <p class=\"subtitulo-assinatura\">Assinatura de 1 ano ou 2 anos<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/assinaturas\/\" role=\"button\" rel=\"noopener noreferrer\">ASSINE AGORA<\/a>\n        <\/div>\n      <\/div><\/div><\/div><\/div>\n\n\n\n<p class=\"has-text-align-center has-x-large-font-size\" id=\"quer-saber-tudo-sobre-concursos-previstos-confira-nossos-artigos\"><strong>Quer saber tudo sobre concursos previstos? Confira nossos artigos!<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos Abertos<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-fiscais\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos Fiscais<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2026\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos 2026<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Confira neste artigo a corre\u00e7\u00e3o ao vivo e o gabarito extraoficial da prova de conhecimentos espec\u00edficos do concurso SEFA PA para Fiscal de Receitas! Acontece neste domingo (29) a segunda etapa de provas do concurso da Secretaria da Fazenda do Estado do Par\u00e1 (SEFA PA) para Fiscal de Receitas. Nesta segunda data, ser\u00e1 aplicada a [&hellip;]<\/p>\n","protected":false},"author":659,"featured_media":1742944,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"news","footnotes":""},"categories":[1983,220219],"tags":[],"tax_estado":[219977],"class_list":["post-1742943","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fiscal-estadual","category-noticias","tax_estado-pa"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Gabarito Extraoficial Sefa PA Fiscal: conhecimentos espec\u00edficos<\/title>\n<meta name=\"description\" content=\"Confira o Gabarito Extraoficial Sefa PA Fiscal de Receitas para verificar seu desempenho na prova de conhecimentos espec\u00edficos. Ao vivo!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-sefa-pa-fiscal-conhecimentos-especificos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gabarito Extraoficial Sefa PA Fiscal: conhecimentos espec\u00edficos\" \/>\n<meta property=\"og:description\" content=\"Confira o Gabarito Extraoficial Sefa PA Fiscal de Receitas para verificar seu desempenho na prova de conhecimentos espec\u00edficos. Ao vivo!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-sefa-pa-fiscal-conhecimentos-especificos\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-29T22:23:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-30T11:05:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2026\/03\/25115339\/gabarito-extraoficial-sefa-pa-auditor-conhecimentos-especificos.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Camila Leite\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Camila Leite\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"13 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-sefa-pa-fiscal-conhecimentos-especificos\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-sefa-pa-fiscal-conhecimentos-especificos\/\"},\"author\":{\"name\":\"Camila Leite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/84ecdc6eb58d3cf1689bf76c5cd8fb38\"},\"headline\":\"Gabarito Extraoficial Sefa PA Fiscal: conhecimentos espec\u00edficos\",\"datePublished\":\"2026-03-29T22:23:00+00:00\",\"dateModified\":\"2026-03-30T11:05:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-sefa-pa-fiscal-conhecimentos-especificos\/\"},\"wordCount\":2628,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-sefa-pa-fiscal-conhecimentos-especificos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2026\/03\/25115339\/gabarito-extraoficial-sefa-pa-auditor-conhecimentos-especificos.jpg\",\"articleSection\":[\"Fiscal - Estadual (ICMS)\",\"\u00daltimas not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-sefa-pa-fiscal-conhecimentos-especificos\/#respond\"]}],\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-sefa-pa-fiscal-conhecimentos-especificos\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-sefa-pa-fiscal-conhecimentos-especificos\/\",\"name\":\"Gabarito Extraoficial Sefa PA Fiscal: conhecimentos espec\u00edficos\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-sefa-pa-fiscal-conhecimentos-especificos\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-sefa-pa-fiscal-conhecimentos-especificos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2026\/03\/25115339\/gabarito-extraoficial-sefa-pa-auditor-conhecimentos-especificos.jpg\",\"datePublished\":\"2026-03-29T22:23:00+00:00\",\"dateModified\":\"2026-03-30T11:05:33+00:00\",\"description\":\"Confira o Gabarito Extraoficial Sefa PA Fiscal de Receitas para verificar seu desempenho na prova de conhecimentos espec\u00edficos. Ao vivo!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-sefa-pa-fiscal-conhecimentos-especificos\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-sefa-pa-fiscal-conhecimentos-especificos\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-sefa-pa-fiscal-conhecimentos-especificos\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2026\/03\/25115339\/gabarito-extraoficial-sefa-pa-auditor-conhecimentos-especificos.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2026\/03\/25115339\/gabarito-extraoficial-sefa-pa-auditor-conhecimentos-especificos.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-sefa-pa-fiscal-conhecimentos-especificos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gabarito Extraoficial Sefa PA Fiscal: conhecimentos espec\u00edficos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/84ecdc6eb58d3cf1689bf76c5cd8fb38\",\"name\":\"Camila Leite\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/f2f8faef639c8a2bfb7fb909912a56917f4c3a0aed064500168e2fb8ea55cf61?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f2f8faef639c8a2bfb7fb909912a56917f4c3a0aed064500168e2fb8ea55cf61?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f2f8faef639c8a2bfb7fb909912a56917f4c3a0aed064500168e2fb8ea55cf61?s=96&d=mm&r=g\",\"caption\":\"Camila Leite\"},\"description\":\"Formada em Design Gr\u00e1fico e em Propaganda e Marketing pela UNIP, integra a equipe de jornalismo do Estrat\u00e9gia Concursos desde 2018. Ao longo dos anos, construiu uma s\u00f3lida experi\u00eancia na produ\u00e7\u00e3o de conte\u00fado informativo e relevante para concurseiros. Desde 2020, atua na cobertura das \u00e1reas Fiscal \u2014 com \u00eanfase nas Secretarias de Fazenda (Sefaz) das regi\u00f5es Sul e Sudeste \u2014, al\u00e9m da cobertura de concursos federais, como CNU, Petrobras, CGU, Receita Federal, ag\u00eancias reguladoras (Anvisa, ANAC, entre outras) e INSS. Mant\u00e9m contato direto com os principais \u00f3rg\u00e3os p\u00fablicos, acompanhando editais, atualiza\u00e7\u00f5es e movimenta\u00e7\u00f5es importantes para os candidatos.\",\"sameAs\":[\"https:\/\/www.linkedin.com\/in\/camila-pinheiro-leite-9ba135b6\/\"],\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/camila-leiteestrategiaconcursos-com-br\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Gabarito Extraoficial Sefa PA Fiscal: conhecimentos espec\u00edficos","description":"Confira o Gabarito Extraoficial Sefa PA Fiscal de Receitas para verificar seu desempenho na prova de conhecimentos espec\u00edficos. Ao vivo!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-sefa-pa-fiscal-conhecimentos-especificos\/","og_locale":"pt_BR","og_type":"article","og_title":"Gabarito Extraoficial Sefa PA Fiscal: conhecimentos espec\u00edficos","og_description":"Confira o Gabarito Extraoficial Sefa PA Fiscal de Receitas para verificar seu desempenho na prova de conhecimentos espec\u00edficos. Ao vivo!","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-sefa-pa-fiscal-conhecimentos-especificos\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2026-03-29T22:23:00+00:00","article_modified_time":"2026-03-30T11:05:33+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2026\/03\/25115339\/gabarito-extraoficial-sefa-pa-auditor-conhecimentos-especificos.jpg","type":"image\/jpeg"}],"author":"Camila Leite","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Camila Leite","Est. tempo de leitura":"13 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-sefa-pa-fiscal-conhecimentos-especificos\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-sefa-pa-fiscal-conhecimentos-especificos\/"},"author":{"name":"Camila Leite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/84ecdc6eb58d3cf1689bf76c5cd8fb38"},"headline":"Gabarito Extraoficial Sefa PA Fiscal: conhecimentos espec\u00edficos","datePublished":"2026-03-29T22:23:00+00:00","dateModified":"2026-03-30T11:05:33+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-sefa-pa-fiscal-conhecimentos-especificos\/"},"wordCount":2628,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-sefa-pa-fiscal-conhecimentos-especificos\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2026\/03\/25115339\/gabarito-extraoficial-sefa-pa-auditor-conhecimentos-especificos.jpg","articleSection":["Fiscal - Estadual (ICMS)","\u00daltimas not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-sefa-pa-fiscal-conhecimentos-especificos\/#respond"]}],"copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-sefa-pa-fiscal-conhecimentos-especificos\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-sefa-pa-fiscal-conhecimentos-especificos\/","name":"Gabarito Extraoficial Sefa PA Fiscal: conhecimentos espec\u00edficos","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-sefa-pa-fiscal-conhecimentos-especificos\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-sefa-pa-fiscal-conhecimentos-especificos\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2026\/03\/25115339\/gabarito-extraoficial-sefa-pa-auditor-conhecimentos-especificos.jpg","datePublished":"2026-03-29T22:23:00+00:00","dateModified":"2026-03-30T11:05:33+00:00","description":"Confira o Gabarito Extraoficial Sefa PA Fiscal de Receitas para verificar seu desempenho na prova de conhecimentos espec\u00edficos. Ao vivo!","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-sefa-pa-fiscal-conhecimentos-especificos\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-sefa-pa-fiscal-conhecimentos-especificos\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-sefa-pa-fiscal-conhecimentos-especificos\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2026\/03\/25115339\/gabarito-extraoficial-sefa-pa-auditor-conhecimentos-especificos.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2026\/03\/25115339\/gabarito-extraoficial-sefa-pa-auditor-conhecimentos-especificos.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-sefa-pa-fiscal-conhecimentos-especificos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Gabarito Extraoficial Sefa PA Fiscal: conhecimentos espec\u00edficos"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/84ecdc6eb58d3cf1689bf76c5cd8fb38","name":"Camila Leite","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/f2f8faef639c8a2bfb7fb909912a56917f4c3a0aed064500168e2fb8ea55cf61?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f2f8faef639c8a2bfb7fb909912a56917f4c3a0aed064500168e2fb8ea55cf61?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f2f8faef639c8a2bfb7fb909912a56917f4c3a0aed064500168e2fb8ea55cf61?s=96&d=mm&r=g","caption":"Camila Leite"},"description":"Formada em Design Gr\u00e1fico e em Propaganda e Marketing pela UNIP, integra a equipe de jornalismo do Estrat\u00e9gia Concursos desde 2018. Ao longo dos anos, construiu uma s\u00f3lida experi\u00eancia na produ\u00e7\u00e3o de conte\u00fado informativo e relevante para concurseiros. Desde 2020, atua na cobertura das \u00e1reas Fiscal \u2014 com \u00eanfase nas Secretarias de Fazenda (Sefaz) das regi\u00f5es Sul e Sudeste \u2014, al\u00e9m da cobertura de concursos federais, como CNU, Petrobras, CGU, Receita Federal, ag\u00eancias reguladoras (Anvisa, ANAC, entre outras) e INSS. Mant\u00e9m contato direto com os principais \u00f3rg\u00e3os p\u00fablicos, acompanhando editais, atualiza\u00e7\u00f5es e movimenta\u00e7\u00f5es importantes para os candidatos.","sameAs":["https:\/\/www.linkedin.com\/in\/camila-pinheiro-leite-9ba135b6\/"],"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/camila-leiteestrategiaconcursos-com-br\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1742943","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/659"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1742943"}],"version-history":[{"count":14,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1742943\/revisions"}],"predecessor-version":[{"id":1745127,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1742943\/revisions\/1745127"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/1742944"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1742943"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1742943"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1742943"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1742943"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}