{"id":1741277,"date":"2026-03-23T21:22:34","date_gmt":"2026-03-24T00:22:34","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=1741277"},"modified":"2026-03-23T21:22:37","modified_gmt":"2026-03-24T00:22:37","slug":"o-homem-que-humilhou-a-cebraspe","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/o-homem-que-humilhou-a-cebraspe\/","title":{"rendered":"O homem que humilhou a CEBRASPE"},"content":{"rendered":"\n<p>Nesse artigo iremos contar um pouco da hist\u00f3ria sobre o homem que humilhou a CEBRASPE. Mas, quem \u00e9 esse homem? Qual a diferen\u00e7a isso pode fazer na sua vida? Bom, se voc\u00ea conseguir fazer ao menos algo pr\u00f3ximo do que ele fez, possivelmente voc\u00ea j\u00e1 sai na frente de muitos concorrentes. Desse modo, aprenda estrat\u00e9gias para ir bem na prova e tente fazer algo <strong>que at\u00e9 ent\u00e3o era imposs\u00edvel para muita gente!<\/strong><\/p>\n\n\n\n<p>Assim, confie em mim e venha comigo nesse artigo que foi feito com dicas e hist\u00f3rias!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-quem-e-esse-homem\">Quem \u00e9 esse homem?<\/h2>\n\n\n\n<p>Bom, logo de cara vou matar a curiosidade de voc\u00eas. <strong>Esse homem \u00e9 Lucas Marques Vilela, 1\u00ba colocado no concurso do TCU <\/strong>(T\u00e9cnico Federal de Controle Externo), tendo realizado a fa\u00e7anha de pontuar 118 pontos de um total de 120. Em outras palavras, ele errou apenas uma quest\u00e3o. J\u00e1 imaginaram o que \u00e9 isso?<br \/><br \/>A an\u00e1lise da trajet\u00f3ria de candidatos aprovados em posi\u00e7\u00f5es de destaque \u2014 como o caso de <strong>Lucas Marques Vilela, 1\u00ba lugar no TCU<\/strong> \u2014 fornece evid\u00eancias emp\u00edricas valiosas que, quando combinadas com a literatura cient\u00edfica sobre aprendizagem, permitem compreender os fatores determinantes do alto desempenho.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-a-especificidade-do-modelo-cebraspe-exigencia-cognitiva-superior\">A especificidade do modelo CEBRASPE: exig\u00eancia cognitiva superior<\/h2>\n\n\n\n<p id=\"h-a-especificidade-do-modelo-cebraspe-exigencia-cognitiva-superior\"><strong>As estrat\u00e9gias para ir bem na prova da CEBRASPE<\/strong> s\u00e3o diversas, mas Lucas foi al\u00e9m, muito al\u00e9m! <\/p>\n\n\n\n<p id=\"h-a-especificidade-do-modelo-cebraspe-exigencia-cognitiva-superior\">As provas do CEBRASPE apresentam uma caracter\u00edstica singular: o modelo de julgamento <strong>\u201ccerto ou errado\u201d<\/strong>, com penaliza\u00e7\u00e3o por erro. <\/p>\n\n\n\n<p id=\"h-a-especificidade-do-modelo-cebraspe-exigencia-cognitiva-superior\">Sob a \u00f3tica da <strong>teoria da carga cognitiva (Sweller, 1988)<\/strong>, esse tipo de prova imp\u00f5e maior demanda \u00e0 mem\u00f3ria de trabalho, uma vez que o candidato precisa avaliar n\u00e3o apenas se conhece o conte\u00fado, mas se a assertiva est\u00e1 <strong>integralmente correta<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-pratica-deliberada-e-resolucao-massiva-de-questoes\">Pr\u00e1tica deliberada e resolu\u00e7\u00e3o massiva de quest\u00f5es<\/h2>\n\n\n\n<p>Um dos pontos centrais da prepara\u00e7\u00e3o de candidatos de alto desempenho <strong>\u00e9 a resolu\u00e7\u00e3o intensiva de quest\u00f5es e simulados<\/strong>. O pr\u00f3prio Lucas Marques, o homem que humilhou a CEBRASPE, destaca:<br \/><br \/><em>\u201cFiz os simulados semanais [\u2026] e muitos temas de discursiva.\u201d<\/em><br \/><br \/>Essa pr\u00e1tica encontra respaldo direto no conceito de <strong>pr\u00e1tica deliberada<\/strong> (Ericsson, 2006), que define o desenvolvimento de expertise como resultado de treino estruturado, com feedback cont\u00ednuo e foco em melhoria de desempenho.<\/p>\n\n\n\n<p>Al\u00e9m disso, estudos sobre <strong>retrieval practice<\/strong> demonstram que testar-se constantemente melhora significativamente a reten\u00e7\u00e3o de longo prazo (Roediger &amp; Karpicke, 2006).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-estruturacao-do-estudo-o-papel-do-planejamento-guiado\">Estrutura\u00e7\u00e3o do estudo: o papel do planejamento guiado<\/h2>\n\n\n\n<p><strong>Aprenda estrat\u00e9gias para ir bem na prova<\/strong>. O Lucas aprendeu, colocou em pr\u00e1tica e deu uma verdadeira aula. Olha essa passagem da entrevista dele aqui no Estrat\u00e9gia:<br \/><br \/><em>\u201cTive dificuldade em planejar [\u2026] a Trilha me ajudou bastante.\u201d<\/em><br \/><br \/>A Trilha a que ele se refere, \u00e9 a Trilha Estrat\u00e9gica, voc\u00ea j\u00e1 conhece? <strong>\u00c9 uma esp\u00e9cie de &#8220;Waze dos Concursos&#8221;<\/strong>, uma ferramenta que te d\u00e1 um caminho, diz o que voc\u00ea precisa fazer naquele dia de estudos. Muitos alunos usam e amam. <strong>Ajuda demais, de verdade. <\/strong><\/p>\n\n\n\n<p>Ent\u00e3o imagine ir al\u00e9m disso <strong>e ter um Coach s\u00f3 para voc\u00ea,<\/strong> dizendo exatamente o que voc\u00ea precisa fazer naquele dia de estudos, de modo personalizado. Imaginou? <strong>Pois essa cena que voc\u00ea pensou existe e se chama <a href=\"https:\/\/www.estrategiaconcursos.com.br\/assinaturas-platinum\">Platinum<\/a>, a assinatura mais completa aqui do Estrat\u00e9gia<\/strong>. Se voc\u00ea ainda n\u00e3o conhece, vale a pena conhecer o trabalho dos nossos Coachs que<strong> j\u00e1 conduziram muita gente at\u00e9 \u00e0 aprova\u00e7\u00e3o. <\/strong><\/p>\n\n\n\n<p>Saber como estudar faz toda a diferen\u00e7a: <strong>fazer isso de modo orientado, faz mais diferen\u00e7a ainda! <\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-consistencia-e-volume-de-estudo-ao-longo-do-tempo\">Consist\u00eancia e volume de estudo ao longo do tempo<\/h2>\n\n\n\n<p>O Lucas conta que outro ponto central da prepara\u00e7\u00e3o foi a manuten\u00e7\u00e3o de uma rotina consistente:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>meta de aproximadamente <strong>40 horas semanais l\u00edquidas<\/strong>;<\/li>\n\n\n\n<li>progress\u00e3o <strong>cont\u00ednua <\/strong>na trilha de estudos;<\/li>\n\n\n\n<li><strong>repeti\u00e7\u00e3o <\/strong>de atividades ao longo do tempo.<\/li>\n<\/ul>\n\n\n\n<p>Esse comportamento est\u00e1 alinhado ao conceito de <strong>aprendizagem cumulativa<\/strong>, no qual o conhecimento \u00e9 constru\u00eddo progressivamente por meio de exposi\u00e7\u00e3o repetida e pr\u00e1tica cont\u00ednua.<\/p>\n\n\n\n<p>Em provas de alto n\u00edvel, <strong>vence quem sustenta o processo por mais tempo.<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-treinamento-especifico-para-discursivas\">Treinamento espec\u00edfico para discursivas<\/h2>\n\n\n\n<p id=\"h-treinamento-especifico-para-discursivas\">Dentre as estrat\u00e9gias para ir bem na prova, Lucas ainda destacou ainda que um diferencial relevante na prepara\u00e7\u00e3o <strong>foi o treino sistem\u00e1tico para a prova discursiva:<\/strong><\/p>\n\n\n\n<p id=\"h-treinamento-especifico-para-discursivas\"><em>\u201cNo \u00faltimo m\u00eas, fiz um tema por dia [\u2026] e refazia ap\u00f3s corre\u00e7\u00e3o.\u201d<\/em><\/p>\n\n\n\n<p>Essa abordagem est\u00e1 alinhada \u00e0 pr\u00e1tica de <strong>feedback corretivo<\/strong>, considerada essencial para o desenvolvimento de habilidades complexas (Hattie &amp; Timperley, 2007).<\/p>\n\n\n\n<p id=\"h-treinamento-especifico-para-discursivas\">Al\u00e9m disso, o treino antecipado no in\u00edcio do dia demonstra uma estrat\u00e9gia eficiente de aloca\u00e7\u00e3o de energia cognitiva, <strong>priorizando tarefas de maior complexidade<\/strong> nos momentos de maior desempenho mental.<\/p>\n\n\n\n<p id=\"h-treinamento-especifico-para-discursivas\">Ah, e caso voc\u00ea n\u00e3o saiba, <strong>na assinatura Platinum a corre\u00e7\u00e3o de discursivas \u00e9 ILIMITADA! <\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-saude-mental-e-fisica-como-fator-de-desempenho\">Sa\u00fade mental e f\u00edsica como fator de desempenho<\/h2>\n\n\n\n<p id=\"h-saude-mental-e-fisica-como-fator-de-desempenho\">Por fim, mas n\u00e3o menos importante, o nosso homem que humilhou a CEBRASPE ainda contou que:<\/p>\n\n\n\n<p id=\"h-saude-mental-e-fisica-como-fator-de-desempenho\"><em>\u201cN\u00e3o parei de cuidar da sa\u00fade f\u00edsica e mental.\u201d<\/em><\/p>\n\n\n\n<p id=\"h-saude-mental-e-fisica-como-fator-de-desempenho\"><strong>A literatura em neuroci\u00eancia<\/strong> demonstra que fatores como sono, atividade f\u00edsica e equil\u00edbrio emocional impactam diretamente fun\u00e7\u00f5es cognitivas como mem\u00f3ria, aten\u00e7\u00e3o e tomada de decis\u00e3o (Walker, 2017).<\/p>\n\n\n\n<p id=\"h-saude-mental-e-fisica-como-fator-de-desempenho\">Assim, desempenho em provas n\u00e3o \u00e9 apenas resultado de estudo, mas tamb\u00e9m de <strong>condi\u00e7\u00f5es fisiol\u00f3gicas adequadas<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-conclusao\">Conclus\u00e3o<\/h2>\n\n\n\n<p id=\"h-conclusao\"><strong>O desempenho de alto n\u00edvel em concursos p\u00fablicos, <\/strong>especialmente em provas do CEBRASPE, pode ser compreendido <strong>como resultado da intera\u00e7\u00e3o entre:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>pr\u00e1tica deliberada e resolu\u00e7\u00e3o intensiva de quest\u00f5es;<\/li>\n\n\n\n<li>estrutura organizacional eficiente do estudo;<\/li>\n\n\n\n<li>consist\u00eancia ao longo do tempo;<\/li>\n\n\n\n<li>treino espec\u00edfico para provas discursivas;<\/li>\n\n\n\n<li>capacidade de adapta\u00e7\u00e3o e metacogni\u00e7\u00e3o;<\/li>\n\n\n\n<li>manuten\u00e7\u00e3o da sa\u00fade f\u00edsica e mental.<\/li>\n<\/ul>\n\n\n\n<p id=\"h-conclusao\">A an\u00e1lise da trajet\u00f3ria de candidatos aprovados em posi\u00e7\u00f5es de destaque confirma o que a literatura cient\u00edfica j\u00e1 indica: a aprova\u00e7\u00e3o n\u00e3o \u00e9 resultado de talento isolado, mas de <strong>processos estruturados, repetidos e ajustados ao longo do tempo<\/strong>.<\/p>\n\n\n\n<p id=\"h-conclusao\">E caso voc\u00ea ainda <strong>n\u00e3o tenha lido a entrevista completa do Lucas, leia clicando <a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/aprovado-em-1-lugar-no-concurso-tcu-lucas-vilela\/\">aqui<\/a>!<\/strong><\/p>\n\n\n\n<p id=\"h-conclusao\">Refer\u00eancias<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Anderson, L. W., &amp; Krathwohl, D. (2001). <em>A taxonomy for learning, teaching and assessing<\/em>.<\/li>\n\n\n\n<li>Bransford, J., Brown, A., &amp; Cocking, R. (2000). <em>How people learn<\/em>.<\/li>\n\n\n\n<li>Ericsson, K. A. (2006). <em>The Cambridge handbook of expertise and expert performance<\/em>.<\/li>\n\n\n\n<li>Hattie, J., &amp; Timperley, H. (2007). <em>The power of feedback<\/em>.<\/li>\n\n\n\n<li>Roediger, H. L., &amp; Karpicke, J. D. (2006). <em>Test-enhanced learning<\/em>.<\/li>\n\n\n\n<li>Sweller, J. (1988). <em>Cognitive load theory<\/em>.<\/li>\n\n\n\n<li>Walker, M. (2017). <em>Why We Sleep<\/em>.<\/li>\n\n\n\n<li>Zimmerman, B. (2002). <em>Becoming a self-regulated learner<\/em>.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Aprenda com a experi\u00eancia do Lucas Marques Vilela, o homem que humilhou a CEBRASPE<\/p>\n","protected":false},"author":3118,"featured_media":1741305,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[220215,1,2017,222278,220737,214710],"tags":[834,40,861,48,49593],"tax_estado":[],"class_list":["post-1741277","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agencia-reguladora","category-cursos-e-concursos","category-concursos-legislativos","category-prefeituras","category-tribunais-tribunais","category-tribunais-de-contas","tag-coaching","tag-concurso","tag-dicas-de-estudo","tag-edital","tag-tcu-2"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>O homem que humilhou a CEBRASPE<\/title>\n<meta name=\"description\" content=\"J\u00e1 conhece a hist\u00f3ria e as estrat\u00e9gias do homem que humilhou a CEBRASPE? Ent\u00e3o conhe\u00e7a e evolua nos seus estudos sabendo o que ele fez!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/o-homem-que-humilhou-a-cebraspe\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"O homem que humilhou a CEBRASPE\" \/>\n<meta property=\"og:description\" content=\"J\u00e1 conhece a hist\u00f3ria e as estrat\u00e9gias do homem que humilhou a CEBRASPE? Ent\u00e3o conhe\u00e7a e evolua nos seus estudos sabendo o que ele fez!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/o-homem-que-humilhou-a-cebraspe\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-24T00:22:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-24T00:22:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2026\/03\/22165042\/o-homem-que-humilhou-a-cebraspe-1024x683.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Leonardo Jos\u00e9 da Concei\u00e7\u00e3o Carvalho\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Leonardo Jos\u00e9 da Concei\u00e7\u00e3o Carvalho\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/o-homem-que-humilhou-a-cebraspe\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/o-homem-que-humilhou-a-cebraspe\/\"},\"author\":{\"name\":\"Leonardo Jos\u00e9 da Concei\u00e7\u00e3o Carvalho\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/e66e87f74921078a4611c3efec4fd69d\"},\"headline\":\"O homem que humilhou a CEBRASPE\",\"datePublished\":\"2026-03-24T00:22:34+00:00\",\"dateModified\":\"2026-03-24T00:22:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/o-homem-que-humilhou-a-cebraspe\/\"},\"wordCount\":1089,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/o-homem-que-humilhou-a-cebraspe\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2026\/03\/22165042\/o-homem-que-humilhou-a-cebraspe.png\",\"keywords\":[\"coaching\",\"Concurso\",\"dicas de estudo\",\"edital\",\"TCU\"],\"articleSection\":[\"Ag\u00eancia Reguladora\",\"Concursos P\u00fablicos\",\"Legislativo\",\"Prefeituras\",\"Tribunais\",\"Tribunais de Contas (TCU, TCE, TCM)\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/o-homem-que-humilhou-a-cebraspe\/#respond\"]}],\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/o-homem-que-humilhou-a-cebraspe\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/o-homem-que-humilhou-a-cebraspe\/\",\"name\":\"O homem que humilhou a CEBRASPE\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/o-homem-que-humilhou-a-cebraspe\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/o-homem-que-humilhou-a-cebraspe\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2026\/03\/22165042\/o-homem-que-humilhou-a-cebraspe.png\",\"datePublished\":\"2026-03-24T00:22:34+00:00\",\"dateModified\":\"2026-03-24T00:22:37+00:00\",\"description\":\"J\u00e1 conhece a hist\u00f3ria e as estrat\u00e9gias do homem que humilhou a CEBRASPE? Ent\u00e3o conhe\u00e7a e evolua nos seus estudos sabendo o que ele fez!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/o-homem-que-humilhou-a-cebraspe\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/o-homem-que-humilhou-a-cebraspe\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/o-homem-que-humilhou-a-cebraspe\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2026\/03\/22165042\/o-homem-que-humilhou-a-cebraspe.png\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2026\/03\/22165042\/o-homem-que-humilhou-a-cebraspe.png\",\"width\":1536,\"height\":1024,\"caption\":\"Conhe\u00e7a a hist\u00f3ria e o m\u00e9todo do homem que humilhou a CEBRASPE\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/o-homem-que-humilhou-a-cebraspe\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"O homem que humilhou a CEBRASPE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/e66e87f74921078a4611c3efec4fd69d\",\"name\":\"Leonardo Jos\u00e9 da Concei\u00e7\u00e3o Carvalho\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/ec4f9dbbbc75310de50ddc2c9ca3983fe09bf50a4ea8a90619d7db37960bfef3?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ec4f9dbbbc75310de50ddc2c9ca3983fe09bf50a4ea8a90619d7db37960bfef3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ec4f9dbbbc75310de50ddc2c9ca3983fe09bf50a4ea8a90619d7db37960bfef3?s=96&d=mm&r=g\",\"caption\":\"Leonardo Jos\u00e9 da Concei\u00e7\u00e3o Carvalho\"},\"description\":\"Jornalista de forma\u00e7\u00e3o e servidor p\u00fablico federal desde 2010. Colecionei diversas APROVA\u00c7\u00d4ES ao longo desses anos: - Auditor Fiscal do Trabalho (2025), onde atualmente trabalho - Oficial de Intelig\u00eancia da ABIN (2019-2025), onde vivi experi\u00eancias \u00fanicas - T\u00e9cnico Judici\u00e1rio do STM (2013-2018), onde aprendi muito sobre a \u00e1rea meio - Agente Administrativo da AGU (2010-2013), onde comecei minha jornada federal\",\"sameAs\":[\"https:\/\/www.instagram.com\/auditorrasta\/\"],\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/leonardojosecarvalhogmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"O homem que humilhou a CEBRASPE","description":"J\u00e1 conhece a hist\u00f3ria e as estrat\u00e9gias do homem que humilhou a CEBRASPE? Ent\u00e3o conhe\u00e7a e evolua nos seus estudos sabendo o que ele fez!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/o-homem-que-humilhou-a-cebraspe\/","og_locale":"pt_BR","og_type":"article","og_title":"O homem que humilhou a CEBRASPE","og_description":"J\u00e1 conhece a hist\u00f3ria e as estrat\u00e9gias do homem que humilhou a CEBRASPE? Ent\u00e3o conhe\u00e7a e evolua nos seus estudos sabendo o que ele fez!","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/o-homem-que-humilhou-a-cebraspe\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2026-03-24T00:22:34+00:00","article_modified_time":"2026-03-24T00:22:37+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2026\/03\/22165042\/o-homem-que-humilhou-a-cebraspe-1024x683.png","type":"image\/png"}],"author":"Leonardo Jos\u00e9 da Concei\u00e7\u00e3o Carvalho","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Leonardo Jos\u00e9 da Concei\u00e7\u00e3o Carvalho","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/o-homem-que-humilhou-a-cebraspe\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/o-homem-que-humilhou-a-cebraspe\/"},"author":{"name":"Leonardo Jos\u00e9 da Concei\u00e7\u00e3o Carvalho","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/e66e87f74921078a4611c3efec4fd69d"},"headline":"O homem que humilhou a CEBRASPE","datePublished":"2026-03-24T00:22:34+00:00","dateModified":"2026-03-24T00:22:37+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/o-homem-que-humilhou-a-cebraspe\/"},"wordCount":1089,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/o-homem-que-humilhou-a-cebraspe\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2026\/03\/22165042\/o-homem-que-humilhou-a-cebraspe.png","keywords":["coaching","Concurso","dicas de estudo","edital","TCU"],"articleSection":["Ag\u00eancia Reguladora","Concursos P\u00fablicos","Legislativo","Prefeituras","Tribunais","Tribunais de Contas (TCU, TCE, TCM)"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/o-homem-que-humilhou-a-cebraspe\/#respond"]}],"copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/o-homem-que-humilhou-a-cebraspe\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/o-homem-que-humilhou-a-cebraspe\/","name":"O homem que humilhou a CEBRASPE","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/o-homem-que-humilhou-a-cebraspe\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/o-homem-que-humilhou-a-cebraspe\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2026\/03\/22165042\/o-homem-que-humilhou-a-cebraspe.png","datePublished":"2026-03-24T00:22:34+00:00","dateModified":"2026-03-24T00:22:37+00:00","description":"J\u00e1 conhece a hist\u00f3ria e as estrat\u00e9gias do homem que humilhou a CEBRASPE? Ent\u00e3o conhe\u00e7a e evolua nos seus estudos sabendo o que ele fez!","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/o-homem-que-humilhou-a-cebraspe\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/o-homem-que-humilhou-a-cebraspe\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/o-homem-que-humilhou-a-cebraspe\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2026\/03\/22165042\/o-homem-que-humilhou-a-cebraspe.png","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2026\/03\/22165042\/o-homem-que-humilhou-a-cebraspe.png","width":1536,"height":1024,"caption":"Conhe\u00e7a a hist\u00f3ria e o m\u00e9todo do homem que humilhou a CEBRASPE"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/o-homem-que-humilhou-a-cebraspe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"O homem que humilhou a CEBRASPE"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/e66e87f74921078a4611c3efec4fd69d","name":"Leonardo Jos\u00e9 da Concei\u00e7\u00e3o Carvalho","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/ec4f9dbbbc75310de50ddc2c9ca3983fe09bf50a4ea8a90619d7db37960bfef3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ec4f9dbbbc75310de50ddc2c9ca3983fe09bf50a4ea8a90619d7db37960bfef3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ec4f9dbbbc75310de50ddc2c9ca3983fe09bf50a4ea8a90619d7db37960bfef3?s=96&d=mm&r=g","caption":"Leonardo Jos\u00e9 da Concei\u00e7\u00e3o Carvalho"},"description":"Jornalista de forma\u00e7\u00e3o e servidor p\u00fablico federal desde 2010. Colecionei diversas APROVA\u00c7\u00d4ES ao longo desses anos: - Auditor Fiscal do Trabalho (2025), onde atualmente trabalho - Oficial de Intelig\u00eancia da ABIN (2019-2025), onde vivi experi\u00eancias \u00fanicas - T\u00e9cnico Judici\u00e1rio do STM (2013-2018), onde aprendi muito sobre a \u00e1rea meio - Agente Administrativo da AGU (2010-2013), onde comecei minha jornada federal","sameAs":["https:\/\/www.instagram.com\/auditorrasta\/"],"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/leonardojosecarvalhogmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1741277","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/3118"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1741277"}],"version-history":[{"count":4,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1741277\/revisions"}],"predecessor-version":[{"id":1741308,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1741277\/revisions\/1741308"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/1741305"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1741277"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1741277"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1741277"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1741277"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}