{"id":1729827,"date":"2026-03-24T11:09:00","date_gmt":"2026-03-24T14:09:00","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=1729827"},"modified":"2026-03-11T19:53:37","modified_gmt":"2026-03-11T22:53:37","slug":"inteligencia-emocional-concursos","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/inteligencia-emocional-concursos\/","title":{"rendered":"Intelig\u00eancia emocional para concursos"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"538\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/10\/13223745\/o-que-e-inteligencia-emocional-1-1024x538.png\" alt=\"Intelig\u00eancia emocional para concursos\" class=\"wp-image-1109916\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/10\/13223745\/o-que-e-inteligencia-emocional-1-1024x538.png 1024w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/10\/13223745\/o-que-e-inteligencia-emocional-1-300x158.png 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/10\/13223745\/o-que-e-inteligencia-emocional-1-768x403.png 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/10\/13223745\/o-que-e-inteligencia-emocional-1-610x320.png 610w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/10\/13223745\/o-que-e-inteligencia-emocional-1-150x79.png 150w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/10\/13223745\/o-que-e-inteligencia-emocional-1.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>O presente artigo visa abordar alguns importantes aspectos da intelig\u00eancia emocional para concursos. Apesar da vastid\u00e3o de conte\u00fados de estudo necess\u00e1rios, para enfrentar provas de bancas como a <a href=\"https:\/\/www.cebraspe.org.br\/concursos\/\">CEBRASPE<\/a>, a intelig\u00eancia emocional \u00e9 muito importante para a condu\u00e7\u00e3o dos estudos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-busca-do-autoconhecimento\">Busca do Autoconhecimento<\/h2>\n\n\n\n<p>Iniciando o tema intelig\u00eancia emocional para concursos, aborda-se o <mark style=\"background-color:#abb8c3\" class=\"has-inline-color\"><strong>autoconhecimento<\/strong><\/mark>, que pode ajudar muito o concurseiro.<\/p>\n\n\n\n<p>O <strong>autoconhecimento <\/strong>\u00e9 essencial para a an\u00e1lise do n\u00edvel de conhecimento que o estudante tem nas disciplinas em si. Ele vai medir qual disciplina precisa de mais estudos, e qual disciplina precisa de menos estudos. Vai ajudar a determinar em qual disciplina usar mais PDF, em qual usar v\u00eddeo, e em qual utilizar mais resolu\u00e7\u00e3o de exerc\u00edcios.<\/p>\n\n\n\n<p>Ainda, vai ajudar a <strong>identificar <\/strong>o tempo que cada concurseiro leva em cada tipo de estudo, e qual o melhor m\u00e9todo e local, e necessidades que cada um tem.<\/p>\n\n\n\n<p>Al\u00e9m disso, envolve <strong>controlar emo\u00e7\u00f5es<\/strong>, incentivando as positivas, e trabalhando nas negativas. Identificando press\u00f5es e gatilhos de ansiedade, para saber como melhor lidar com isso. Sabendo quando \u00e9 necess\u00e1rio o descanso e lidar com o limite do tempo.<\/p>\n\n\n\n<p>Por\u00e9m, o conceito \u00e9 profundo, e envolve tamb\u00e9m <strong>autocr\u00edtica<\/strong>. O que n\u00e3o significa ter uma vis\u00e3o negativa ou pessimista, mas sim trabalhar para com que os pontos negativos virem degraus de uma escada rumo \u00e0 aprova\u00e7\u00e3o.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-inteligencia-emocional-para-concursos-nbsp-ansiedade\">Intelig\u00eancia emocional para concursos&nbsp; &#8211; Ansiedade<\/h2>\n\n\n\n<p>Prosseguindo com an\u00e1lise sobre intelig\u00eancia emocional para concursos, o tema \u00e9 a <mark style=\"background-color:#7bdcb5\" class=\"has-inline-color\"><strong>ansiedade<\/strong><\/mark>.<\/p>\n\n\n\n<p><strong>Ansiedade <\/strong>ocorre quando existe uma situa\u00e7\u00e3o com algum tipo de incerteza ou risco. Quem sofre com a ansiedade espera muito pelo resultado de tal situa\u00e7\u00e3o, e fica criando cen\u00e1rios de antecipa\u00e7\u00e3o do futuro em pensamentos.<\/p>\n\n\n\n<p>Em um n\u00edvel normal e natural, a ansiedade \u00e9 positiva, podendo gerar boas resolu\u00e7\u00f5es e at\u00e9 aumentar o foco e concentra\u00e7\u00e3o em estudos e provas.<\/p>\n\n\n\n<p>Por\u00e9m, em <strong>excesso<\/strong>, ela causa&nbsp; estado nervoso, ins\u00f4nia, preocupa\u00e7\u00e3o excessiva e at\u00e9 mal estar f\u00edsico, como o aceleramento dos batimentos card\u00edacos.<\/p>\n\n\n\n<p>No cen\u00e1rio dos <strong>concursos p\u00fablicos<\/strong>, a ansiedade negativa \u00e9 comum. O ambiente dos concursos \u00e9 bastante competitivo. O fato de estudar por muitas horas causa a ansiedade pela prova em si, o que pode ser prejudicial ao concurseiro.<\/p>\n\n\n\n<p>Na hora de esperar o resultado, cria-se muita especula\u00e7\u00e3o sobre a incerteza da aprova\u00e7\u00e3o ou a real posi\u00e7\u00e3o no resultado da prova, outro grande fator de ansiedade.<\/p>\n\n\n\n<p>A <strong>dica <\/strong>aqui \u00e9 pensar o seguinte: o que gera a ansiedade n\u00e3o se pode antecipar. \u00e0s vezes, o tempo perdido com tudo isso, al\u00e9m de insalubre, poderia ser gasto com outras coisas, como aprimoramento dos estudos de maneira saud\u00e1vel.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-lidando-com-pressoes\">Lidando com press\u00f5es<\/h2>\n\n\n\n<p>Continuando com a disserta\u00e7\u00e3o sobre intelig\u00eancia emocional para concursos, aborda-se a necessidade de lidar com <mark style=\"background-color:#cf2e2e\" class=\"has-inline-color\"><strong>press\u00f5es<\/strong><\/mark>.<\/p>\n\n\n\n<p>Na vida do estudante de concurso p\u00fablico, as <strong>press\u00f5es <\/strong>s\u00e3o comuns.<\/p>\n\n\n\n<p>Na fam\u00edlia, esposas, maridos e filhos precisam da devida aten\u00e7\u00e3o. Amigos e familiares marcam jantares e churrascos, e fazem sempre o convite ao estudante. Al\u00e9m disso, existe a press\u00e3o de quem trabalha e estuda, e encara uma jornada dupla, al\u00e9m da press\u00e3o no trabalho.<\/p>\n\n\n\n<p>Existe tamb\u00e9m o <strong>calend\u00e1rio de provas<\/strong>, e o desafio de fechar os editais. A press\u00e3o de escolher qual prova prestar. E, em alguns casos, as viagens de concursos. E tamb\u00e9m, financeiramente, o dinheiro investido nas provas e no material de estudos.<\/p>\n\n\n\n<p>Aprender a dizer \u201cn\u00e3o\u201d quando necess\u00e1rio e negociar com a fam\u00edlia e amigos pode ajudar muito a lidar com press\u00f5es. Encarar as coisas de forma realista, estabelecer e respeitar prioridades e limites ajuda a lidar com a sobrecarga emocional das press\u00f5es.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-estresse-e-descanso\">Estresse e descanso<\/h2>\n\n\n\n<p>Dando continuidade ao tema intelig\u00eancia emocional para concursos, aborda-se o <mark style=\"background-color:#0693e3\" class=\"has-inline-color\"><strong>estresse e o descanso<\/strong><\/mark> necess\u00e1rio.<\/p>\n\n\n\n<p>As horas de estudo costumam ser muitas, para a prepara\u00e7\u00e3o para as provas de concurso. E muitas pessoas ainda trabalham ou realizam outro tipo de atividade. Trabalho, fam\u00edlia, faculdade, por exemplo.<\/p>\n\n\n\n<p>Com isso, o n\u00edvel de <strong>estresse <\/strong>de um concurseiro costuma ser alto. E o descanso acaba sendo essencial, um verdadeiro combust\u00edvel, para a manuten\u00e7\u00e3o da energia necess\u00e1ria para a continuidade dos estudos, e das demais atividades.<\/p>\n\n\n\n<p>O <strong>sono <\/strong>\u00e9 muito importante para o descanso necess\u00e1rio. Cada um tem uma quantidade de horas de sono ideal. E essa \u00e9 a quantidade m\u00ednima que deve ser dormida por dia. Em dias de muito cansa\u00e7o, e quando poss\u00edvel, \u00e9 bom repor o sono dormindo um pouco mais.<\/p>\n\n\n\n<p>Al\u00e9m do sono, existem outras formas de descanso. Praticar atividade f\u00edsica, caminhar em parques ou praias, assistir a um filme, sair algumas vezes, pode ajudar a dar uma descansada na mente, e continuar melhor a rotina de estudos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-inteligencia-emocional-para-concursos-nbsp-resiliencia\">Intelig\u00eancia emocional para concursos&nbsp; &#8211; Resili\u00eancia<\/h2>\n\n\n\n<p>Finalizando o artigo \u201cIntelig\u00eancia emocional para concursos\u201d, aborda-se a <mark style=\"background-color:#9b51e0\" class=\"has-inline-color\"><strong>resili\u00eancia <\/strong><\/mark>necess\u00e1ria na jornada para a aprova\u00e7\u00e3o em concursos.<\/p>\n\n\n\n<p>A aprova\u00e7\u00e3o em concurso \u00e9 uma jornada de longas horas de estudo, e de provas dif\u00edceis. Existem <strong>reprova\u00e7\u00f5es, decep\u00e7\u00f5es e tentativas<\/strong>. Faz parte da caminhada, que muitas vezes \u00e9 longa.<\/p>\n\n\n\n<p>Por\u00e9m, cada etapa dif\u00edcil nunca deve ser encarada como um fracasso. Cada passo na estrada da aprova\u00e7\u00e3o \u00e9 uma <strong>oportunidade de aprimoramento<\/strong>, e um <strong>avan\u00e7o <\/strong>em dire\u00e7\u00e3o ao cumprimento do objetivo.<\/p>\n\n\n\n<p>Assim, a <strong>resili\u00eancia <\/strong>\u00e9 necess\u00e1ria na intelig\u00eancia emocional do concurseiro.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"cursos-assinatura\">Cursos e Assinaturas<\/h2>\n\n\n\n<p>Prepare-se com o melhor material e com quem mais aprova em Concursos P\u00fablicos em todo o pa\u00eds!<\/p>\n\n\n\n<p class=\"has-text-align-center has-vivid-cyan-blue-color has-text-color has-background\" style=\"background-color:#0078bd\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-white-color\">Concursos Abertos<\/mark><\/strong><\/a><\/p>\n\n\n\n<p class=\"has-text-align-center has-vivid-cyan-blue-color has-text-color has-background\" style=\"background-color:#0078bd\"><strong><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2026\/\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-white-color\">Concursos 2026<\/mark><\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O presente artigo visa abordar alguns importantes aspectos da intelig\u00eancia emocional para concursos. Apesar da vastid\u00e3o de conte\u00fados de estudo necess\u00e1rios, para enfrentar provas de bancas como a CEBRASPE, a intelig\u00eancia emocional \u00e9 muito importante para a condu\u00e7\u00e3o dos estudos. Busca do Autoconhecimento Iniciando o tema intelig\u00eancia emocional para concursos, aborda-se o autoconhecimento, que pode [&hellip;]<\/p>\n","protected":false},"author":2978,"featured_media":1109916,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1],"tags":[],"tax_estado":[],"class_list":["post-1729827","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cursos-e-concursos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Intelig\u00eancia emocional para concursos<\/title>\n<meta name=\"description\" content=\"Intelig\u00eancia emocional para concursos ansiedade descanso estresse resili\u00eancia estrat\u00e9gia press\u00e3o autoconhecimento\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/inteligencia-emocional-concursos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Intelig\u00eancia emocional para concursos\" \/>\n<meta property=\"og:description\" content=\"Intelig\u00eancia emocional para concursos ansiedade descanso estresse resili\u00eancia estrat\u00e9gia press\u00e3o autoconhecimento\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/inteligencia-emocional-concursos\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-24T14:09:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/10\/13223745\/o-que-e-inteligencia-emocional-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Carlos Augusto Canada Silva\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Carlos Augusto Canada Silva\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/inteligencia-emocional-concursos\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/inteligencia-emocional-concursos\/\"},\"author\":{\"name\":\"Carlos Augusto Canada Silva\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/ba5353c5ae7c03146aa160997380a321\"},\"headline\":\"Intelig\u00eancia emocional para concursos\",\"datePublished\":\"2026-03-24T14:09:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/inteligencia-emocional-concursos\/\"},\"wordCount\":962,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/inteligencia-emocional-concursos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/10\/13223745\/o-que-e-inteligencia-emocional-1.png\",\"articleSection\":[\"Concursos P\u00fablicos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/inteligencia-emocional-concursos\/#respond\"]}],\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/inteligencia-emocional-concursos\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/inteligencia-emocional-concursos\/\",\"name\":\"Intelig\u00eancia emocional para concursos\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/inteligencia-emocional-concursos\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/inteligencia-emocional-concursos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/10\/13223745\/o-que-e-inteligencia-emocional-1.png\",\"datePublished\":\"2026-03-24T14:09:00+00:00\",\"description\":\"Intelig\u00eancia emocional para concursos ansiedade descanso estresse resili\u00eancia estrat\u00e9gia press\u00e3o autoconhecimento\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/inteligencia-emocional-concursos\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/inteligencia-emocional-concursos\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/inteligencia-emocional-concursos\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/10\/13223745\/o-que-e-inteligencia-emocional-1.png\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/10\/13223745\/o-que-e-inteligencia-emocional-1.png\",\"width\":1200,\"height\":630,\"caption\":\"Intelig\u00eancia emocional para concursos\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/inteligencia-emocional-concursos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Intelig\u00eancia emocional para concursos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/ba5353c5ae7c03146aa160997380a321\",\"name\":\"Carlos Augusto Canada Silva\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/a3678a0de9b78f31cae66e58ba52f2e5ba85775337ae7925bf91eb689694b7e7?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a3678a0de9b78f31cae66e58ba52f2e5ba85775337ae7925bf91eb689694b7e7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a3678a0de9b78f31cae66e58ba52f2e5ba85775337ae7925bf91eb689694b7e7?s=96&d=mm&r=g\",\"caption\":\"Carlos Augusto Canada Silva\"},\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/carlosaugusto-c-silvagmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Intelig\u00eancia emocional para concursos","description":"Intelig\u00eancia emocional para concursos ansiedade descanso estresse resili\u00eancia estrat\u00e9gia press\u00e3o autoconhecimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/inteligencia-emocional-concursos\/","og_locale":"pt_BR","og_type":"article","og_title":"Intelig\u00eancia emocional para concursos","og_description":"Intelig\u00eancia emocional para concursos ansiedade descanso estresse resili\u00eancia estrat\u00e9gia press\u00e3o autoconhecimento","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/inteligencia-emocional-concursos\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2026-03-24T14:09:00+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/10\/13223745\/o-que-e-inteligencia-emocional-1.png","type":"image\/png"}],"author":"Carlos Augusto Canada Silva","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Carlos Augusto Canada Silva","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/inteligencia-emocional-concursos\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/inteligencia-emocional-concursos\/"},"author":{"name":"Carlos Augusto Canada Silva","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/ba5353c5ae7c03146aa160997380a321"},"headline":"Intelig\u00eancia emocional para concursos","datePublished":"2026-03-24T14:09:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/inteligencia-emocional-concursos\/"},"wordCount":962,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/inteligencia-emocional-concursos\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/10\/13223745\/o-que-e-inteligencia-emocional-1.png","articleSection":["Concursos P\u00fablicos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/inteligencia-emocional-concursos\/#respond"]}],"copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/inteligencia-emocional-concursos\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/inteligencia-emocional-concursos\/","name":"Intelig\u00eancia emocional para concursos","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/inteligencia-emocional-concursos\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/inteligencia-emocional-concursos\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/10\/13223745\/o-que-e-inteligencia-emocional-1.png","datePublished":"2026-03-24T14:09:00+00:00","description":"Intelig\u00eancia emocional para concursos ansiedade descanso estresse resili\u00eancia estrat\u00e9gia press\u00e3o autoconhecimento","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/inteligencia-emocional-concursos\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/inteligencia-emocional-concursos\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/inteligencia-emocional-concursos\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/10\/13223745\/o-que-e-inteligencia-emocional-1.png","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/10\/13223745\/o-que-e-inteligencia-emocional-1.png","width":1200,"height":630,"caption":"Intelig\u00eancia emocional para concursos"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/inteligencia-emocional-concursos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Intelig\u00eancia emocional para concursos"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/ba5353c5ae7c03146aa160997380a321","name":"Carlos Augusto Canada Silva","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/a3678a0de9b78f31cae66e58ba52f2e5ba85775337ae7925bf91eb689694b7e7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a3678a0de9b78f31cae66e58ba52f2e5ba85775337ae7925bf91eb689694b7e7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a3678a0de9b78f31cae66e58ba52f2e5ba85775337ae7925bf91eb689694b7e7?s=96&d=mm&r=g","caption":"Carlos Augusto Canada Silva"},"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/carlosaugusto-c-silvagmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1729827","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/2978"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1729827"}],"version-history":[{"count":2,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1729827\/revisions"}],"predecessor-version":[{"id":1729940,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1729827\/revisions\/1729940"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/1109916"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1729827"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1729827"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1729827"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1729827"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}