{"id":1721617,"date":"2026-03-27T08:20:00","date_gmt":"2026-03-27T11:20:00","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=1721617"},"modified":"2026-03-27T08:30:39","modified_gmt":"2026-03-27T11:30:39","slug":"concurso-mogi-mirim-educacao","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-mogi-mirim-educacao\/","title":{"rendered":"Concurso Mogi Mirim (SP) Educa\u00e7\u00e3o: provas em abril"},"content":{"rendered":"\n<p>A\u00a0<strong><a href=\"https:\/\/www.estrategiaconcursos.com.br\/cursosPorConcurso\" target=\"_blank\" rel=\"noreferrer noopener\">Prefeitura de Mogi Mirim<\/a><\/strong>, em S\u00e3o Paulo, oferece oportunidades de n\u00edvel superior de escolaridade para diversas especialidades na carreira de professor.<\/p>\n\n\n\n<p>O certame est\u00e1 sob a responsabilidade da banca IBAM e destina-se ao preenchimento de <strong>16 vagas, al\u00e9m de cadastro de reserva<\/strong>, com sal\u00e1rios que chegam a <strong>R$ 4.992,96<\/strong>.<\/p>\n\n\n\n<p>As&nbsp;<strong>provas objetivas<\/strong>&nbsp;ser\u00e3o realizadas na data de&nbsp;<strong>26 de abril<\/strong> para todos os cargos.<\/p>\n\n\n\n<ul class=\"wp-block-list has-very-light-gray-to-cyan-bluish-gray-gradient-background has-background\">\n<li><strong>Concurso Mogi Mirim &#8211; Educa\u00e7\u00e3o<\/strong><\/li>\n\n\n\n<li><strong>Status:<\/strong>\u00a0inscri\u00e7\u00f5es encerradas<\/li>\n\n\n\n<li><strong>Banca:<\/strong>&nbsp;<a href=\"https:\/\/www.ibamsp-concursos.org.br\/informacoes\/121\/\">IBAM<\/a> <\/li>\n\n\n\n<li><strong>Vagas:<\/strong>&nbsp;16 + CR<\/li>\n\n\n\n<li><strong>Sal\u00e1rio inicial:<\/strong>&nbsp;at\u00e9 R$ 4.992,96<\/li>\n\n\n\n<li><strong>Edital<\/strong>:&nbsp;<a href=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2026\/02\/26112104\/e9bdfbc7-5bdb-40e3-b683-462fd58f486f.pdf\">Mogi Mirim Educa\u00e7\u00e3o 2026<\/a><\/li>\n<\/ul>\n\n\n\n<div class=\"container\" id=\"boxes\">\n  <div class=\"row\">\n\n    <div class=\"col-sm\">\n      <div class=\"banner-estrategia\" id=\"box-assinatura\">\n        <h3 class=\"titulo-assinatura\">Cursos para concursos<\/h3>\n        <p class=\"subtitulo-assinatura\">Conhe\u00e7a os cursos<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/cursosPorConcurso\" role=\"button\" rel=\"noopener noreferrer\">Saiba mais<\/a>\n        <\/div>\n      <\/div>\n     \n    <\/div>\n\n  <\/div>\n<\/div>\n\n\n\n<p>A fim de te deixar sempre bem informado, elaboramos este artigo com as principais informa\u00e7\u00f5es e novidades sobre o concurso. Acompanhe os t\u00f3picos abaixo e n\u00e3o perca nenhum detalhe:<\/p>\n\n\n\n<ul id=\"indice\" class=\"wp-block-list\">\n<li><strong><a href=\"#datas\">Principais datas<\/a><\/strong><\/li>\n\n\n\n<li><strong><a href=\"#cargo\">Cargos, vagas e sal\u00e1rios<\/a><\/strong>\n<ul class=\"wp-block-list\">\n<li><a href=\"#med\">N\u00edvel m\u00e9dio\/t\u00e9cnico<\/a><\/li>\n\n\n\n<li><a href=\"#sup\">N\u00edvel superior<\/a><\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><a href=\"#etapas\"><strong>Etapas de prova<\/strong><\/a><\/li>\n\n\n\n<li><a href=\"#cursos\"><strong>Assinatura e cursos<\/strong><\/a><\/li>\n\n\n\n<li><a href=\"#ficha\"><strong>Ficha t\u00e9cnica<\/strong><\/a><\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"datas\">Concurso Mogi Mirim Educa\u00e7\u00e3o: principais datas<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><s><strong>Inscri\u00e7\u00f5es:<\/strong> 26 de fevereiro a 25 de mar\u00e7o<\/s><\/li>\n\n\n\n<li><s><strong>Pedido de isen\u00e7\u00e3o:<\/strong> 26 e 27 de fevereiro<\/s><\/li>\n\n\n\n<li><s><strong>Isen\u00e7\u00e3o da taxa<\/strong>: 27 de mar\u00e7o<\/s><\/li>\n\n\n\n<li><strong>Provas:<\/strong> 26 de abril de 2026<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"cargo\">Concurso Mogi Mirim Educa\u00e7\u00e3o: cargos, vagas e sal\u00e1rios<\/h2>\n\n\n\n<figure class=\"wp-block-table is-style-stripes\"><table class=\"has-fixed-layout\"><tbody><tr><th>Cargo<\/th><th class=\"has-text-align-center\" data-align=\"center\">Vagas<\/th><th>Sal\u00e1rio (R$)<\/th><\/tr><tr><td>Coordenador Pedag\u00f3gico<\/td><td class=\"has-text-align-center\" data-align=\"center\">CR<\/td><td>R$ 4.992,96<\/td><\/tr><tr><td>Prof. de Educa\u00e7\u00e3o F\u00edsica &#8211; Esporte<\/td><td class=\"has-text-align-center\" data-align=\"center\">1<\/td><td>R$ 2.199,34<\/td><\/tr><tr><td>Professor de Educa\u00e7\u00e3o B\u00e1sica<\/td><td class=\"has-text-align-center\" data-align=\"center\">1<\/td><td>R$ 2.685,70<\/td><\/tr><tr><td>Professor de Primeira Inf\u00e2ncia<\/td><td class=\"has-text-align-center\" data-align=\"center\">1<\/td><td>R$ 4.101,65<\/td><\/tr><tr><td>Professor Educa\u00e7\u00e3o (B\u00e1sica &#8211; Apoio)*<\/td><td class=\"has-text-align-center\" data-align=\"center\">1<\/td><td>R$ 2.141,01<\/td><\/tr><tr><td>Professor Educa\u00e7\u00e3o B\u00e1sica &#8211; Artes Pl\u00e1sticas<\/td><td class=\"has-text-align-center\" data-align=\"center\">1<\/td><td>R$ 2.141,01<\/td><\/tr><tr><td>Professor Educa\u00e7\u00e3o B\u00e1sica &#8211; Ci\u00eancias<\/td><td class=\"has-text-align-center\" data-align=\"center\">1<\/td><td>R$ 2.141,01<\/td><\/tr><tr><td>Professor Educa\u00e7\u00e3o B\u00e1sica &#8211; DA<\/td><td class=\"has-text-align-center\" data-align=\"center\">1<\/td><td>R$ 2.685,70<\/td><\/tr><tr><td>Professor Educa\u00e7\u00e3o B\u00e1sica &#8211; DM<\/td><td class=\"has-text-align-center\" data-align=\"center\">1<\/td><td>R$ 2.685,70<\/td><\/tr><tr><td>Professor Educa\u00e7\u00e3o B\u00e1sica &#8211; DV<\/td><td class=\"has-text-align-center\" data-align=\"center\">1<\/td><td>R$ 2.685,70<\/td><\/tr><tr><td>Professor Educa\u00e7\u00e3o B\u00e1sica &#8211; Educa\u00e7\u00e3o F\u00edsica<\/td><td class=\"has-text-align-center\" data-align=\"center\">1<\/td><td>R$ 2.141,01<\/td><\/tr><tr><td>Professor Educa\u00e7\u00e3o B\u00e1sica &#8211; Geografia<\/td><td class=\"has-text-align-center\" data-align=\"center\">1<\/td><td>R$ 2.141,01<\/td><\/tr><tr><td>Professor Educa\u00e7\u00e3o B\u00e1sica &#8211; Hist\u00f3ria<\/td><td class=\"has-text-align-center\" data-align=\"center\">1<\/td><td>R$ 2.141,01<\/td><\/tr><tr><td>Professor Educa\u00e7\u00e3o B\u00e1sica &#8211; Inform\u00e1tica<\/td><td class=\"has-text-align-center\" data-align=\"center\">1<\/td><td>R$ 2.141,01<\/td><\/tr><tr><td>Professor Educa\u00e7\u00e3o B\u00e1sica &#8211; Ingl\u00eas<\/td><td class=\"has-text-align-center\" data-align=\"center\">1<\/td><td>R$ 2.141,01<\/td><\/tr><tr><td>Professor Educa\u00e7\u00e3o B\u00e1sica &#8211; L\u00edngua Portuguesa<\/td><td class=\"has-text-align-center\" data-align=\"center\">1<\/td><td>R$ 2.141,01<\/td><\/tr><tr><td>Professor Educa\u00e7\u00e3o B\u00e1sica &#8211; Matem\u00e1tica<\/td><td class=\"has-text-align-center\" data-align=\"center\">1<\/td><td>R$ 2.141,01<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p><strong>Benef\u00edcios Adicionais:<\/strong> Al\u00e9m do sal\u00e1rio base informado na tabela, o edital prev\u00ea o pagamento de um <strong>Cart\u00e3o Aux\u00edlio Alimenta\u00e7\u00e3o no valor de R$ 500,00<\/strong> e uma <strong>Cesta B\u00e1sica (optativa)<\/strong>. <\/p>\n\n\n\n<p>Os vencimentos tamb\u00e9m poder\u00e3o ser reajustados de acordo com os percentuais aplicados pela Prefeitura de Mogi Mirim aos sal\u00e1rios dos servidores da mesma categoria.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-requisitos-por-cargo\"><strong>Requisitos por cargo<\/strong><\/h2>\n\n\n\n<p><strong>Coordenador Pedag\u00f3gico:<\/strong><\/p>\n\n\n\n<p>\u2022 Licenciatura plena em Pedagogia com habilita\u00e7\u00e3o ou p\u00f3s-gradua\u00e7\u00e3o em orienta\u00e7\u00e3o escolar, <strong>OU<\/strong> licenciatura plena em Pedagogia (nos moldes da Resolu\u00e7\u00e3o CNE n\u00b0 1, de 15\/5\/2006).<\/p>\n\n\n\n<p>\u2022 No m\u00ednimo, 5 (cinco) anos de experi\u00eancia docente adquirida em qualquer n\u00edvel de ensino (Infantil, Fundamental e M\u00e9dio) em sistema p\u00fablico ou privado.<\/p>\n\n\n\n<p><strong>Professor de Educa\u00e7\u00e3o F\u00edsica &#8211; Esporte<\/strong>:<\/p>\n\n\n\n<p>\u2022 Curso Superior com licenciatura plena e habilita\u00e7\u00e3o nas \u00e1reas espec\u00edficas.<\/p>\n\n\n\n<p>\u2022 Diploma devidamente registrado no Minist\u00e9rio da Educa\u00e7\u00e3o e Cultura (MEC) ou \u00f3rg\u00e3o por ele delegado.<\/p>\n\n\n\n<p>\u2022 Registro no CREF.<\/p>\n\n\n\n<p><strong>Professor de Educa\u00e7\u00e3o B\u00e1sica<\/strong>:<\/p>\n\n\n\n<p>\u2022 Magist\u00e9rio (n\u00edvel m\u00e9dio) e\/ou Normal Superior, <strong>OU<\/strong> Curso Superior de Pedagogia com licenciatura plena.<\/p>\n\n\n\n<p>\u2022 Diploma devidamente registrado no Minist\u00e9rio da Educa\u00e7\u00e3o e Cultura (MEC) ou \u00d3rg\u00e3o por ele delegado.<\/p>\n\n\n\n<p><strong>Professor de Primeira Inf\u00e2ncia<\/strong>:<\/p>\n\n\n\n<p>\u2022 Licenciatura plena em Pedagogia e\/ou normal superior.<\/p>\n\n\n\n<p><strong>Professor Educa\u00e7\u00e3o (B\u00e1sica &#8211; Apoio)<\/strong>:<\/p>\n\n\n\n<p>\u2022 Magist\u00e9rio (n\u00edvel m\u00e9dio) e\/ou normal superior; <strong>OU<\/strong> curso superior registrado no Minist\u00e9rio da Educa\u00e7\u00e3o e Cultura (MEC) ou \u00f3rg\u00e3o por ele delegado.<\/p>\n\n\n\n<p><strong>Professores de Educa\u00e7\u00e3o B\u00e1sica &#8211; Especialidades (Artes Pl\u00e1sticas, Ci\u00eancias, Educa\u00e7\u00e3o F\u00edsica, Geografia, Hist\u00f3ria, Inform\u00e1tica, Ingl\u00eas, L\u00edngua Portuguesa e Matem\u00e1tica)<\/strong>:<\/p>\n\n\n\n<p>\u2022 Curso Superior com licenciatura plena e habilita\u00e7\u00e3o nas \u00e1reas espec\u00edficas.<\/p>\n\n\n\n<p>\u2022 Diploma devidamente registrado no Minist\u00e9rio da Educa\u00e7\u00e3o e Cultura (MEC) ou \u00f3rg\u00e3o por ele delegado.<\/p>\n\n\n\n<p><strong>Professores de Educa\u00e7\u00e3o B\u00e1sica &#8211; Educa\u00e7\u00e3o Especial (DA, DM e DV)<\/strong>:<\/p>\n\n\n\n<p>\u2022 Curso Superior de Pedagogia e licenciatura plena com habilita\u00e7\u00e3o espec\u00edfica em Educa\u00e7\u00e3o Especial <strong>OU<\/strong> especializa\u00e7\u00e3o em Educa\u00e7\u00e3o Inclusiva.<\/p>\n\n\n\n<p>\u2022 Diploma devidamente registrado no Minist\u00e9rio da Educa\u00e7\u00e3o e Cultura (MEC) ou \u00f3rg\u00e3o por ele delegado.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"etapas\">Concurso Concurso Mogi Mirim Educa\u00e7\u00e3o: etapas de avalia\u00e7\u00f5es<\/h2>\n\n\n\n<p>O concurso p\u00fablico ser\u00e1 realizado em duas etapas principais: <strong>Provas Objetivas<\/strong> e <strong>Provas de T\u00edtulos<\/strong>, sendo:<\/p>\n\n\n\n<p><strong>Provas Objetivas (car\u00e1ter classificat\u00f3rio e eliminat\u00f3rio)<\/strong><\/p>\n\n\n\n<p>Esta etapa \u00e9 obrigat\u00f3ria para todos os candidatos. As provas ter\u00e3o a dura\u00e7\u00e3o de 3 horas e meia e ser\u00e3o compostas por quest\u00f5es de m\u00faltipla escolha, contendo 4 op\u00e7\u00f5es de resposta para cada quest\u00e3o.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;\u25e6 <strong>Educador Social:<\/strong> L\u00edngua Portuguesa (10 quest\u00f5es), Matem\u00e1tica (5), Inform\u00e1tica (5), Conhecimentos Gerais (5) e Conhecimentos Espec\u00edficos (15).<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;\u25e6 <strong>Demais cargos:<\/strong> L\u00edngua Portuguesa (6 quest\u00f5es), Matem\u00e1tica (3), Inform\u00e1tica (3), Conhecimentos Gerais (2), Legisla\u00e7\u00e3o Educacional (6), Conhecimentos Pedag\u00f3gicos (14) e Conhecimentos Espec\u00edficos (6).<\/p>\n\n\n\n<p>Para ser considerado habilitado, o candidato deve obter, no m\u00ednimo, <strong>50% do total de pontos<\/strong> da prova. <\/p>\n\n\n\n<p>Al\u00e9m disso, deve estar entre os 07 candidatos com a melhor nota na lista geral (mais os empatados na \u00faltima nota). Para as vagas de cotas, o candidato deve ser o 1\u00ba colocado (ou at\u00e9 o 2\u00ba para a lista de pessoas pretas e pardas), tamb\u00e9m considerando os empatados na \u00faltima posi\u00e7\u00e3o de corte.<\/p>\n\n\n\n<p><strong>Provas de T\u00edtulos (car\u00e1ter apenas classificat\u00f3rio)<\/strong><\/p>\n\n\n\n<p>Somente para os candidatos que forem habilitados nas provas objetivas.<\/p>\n\n\n\n<p>Os pontos dos t\u00edtulos ser\u00e3o somados ao total de pontos obtidos na prova objetiva, e n\u00e3o haver\u00e1 desclassifica\u00e7\u00e3o caso o candidato n\u00e3o possua t\u00edtulos para apresentar.<\/p>\n\n\n\n<p>Os documentos comprobat\u00f3rios dever\u00e3o ser enviados de forma digital (upload) no site do IBAM, em dias a serem definidos por um edital de convoca\u00e7\u00e3o espec\u00edfico.<\/p>\n\n\n\n<p>\u2022 <strong>T\u00edtulos aceitos e pontua\u00e7\u00f5es:<\/strong><\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;\u25e6 <strong>Doutorado<\/strong> na \u00e1rea em que concorre: 2,5 pontos (valor m\u00e1ximo: 2,5).<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;\u25e6 <strong>Mestrado<\/strong> na \u00e1rea em que concorre: 1,5 ponto (valor m\u00e1ximo: 1,5).<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;\u25e6 <strong>P\u00f3s-Gradua\u00e7\u00e3o Lato-Sensu (Especializa\u00e7\u00e3o)<\/strong> na \u00e1rea em que concorre, com dura\u00e7\u00e3o m\u00ednima de 360 horas: 1,0 ponto (valor m\u00e1ximo: 1,0).<\/p>\n\n\n\n<p>Cursos de gradua\u00e7\u00e3o, forma\u00e7\u00e3o em servi\u00e7o ou t\u00edtulos que j\u00e1 sejam exig\u00eancia m\u00ednima para assumir o emprego n\u00e3o ser\u00e3o contabilizados.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"cursos\"><em>Quer estudar para o concurso?<\/em><\/h2>\n\n\n\n<div class=\"container\" id=\"boxes\">\n  <div class=\"row\">\n\n    <div class=\"col-sm\">\n      <div class=\"banner-prefeituras-ec\" id=\"box-assinatura\">\n        <h2 class=\"titulo-assinatura\" style=\"text-align: left;\">Concursos Prefeituras<\/h2>\n        <p class=\"subtitulo-assinatura\" style=\"text-align: left;\">Prepara\u00e7\u00e3o completa para a carreira!<\/p>\n        <div class=\"box-botao\" style=\"text-align: left;\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/pesquisa\/?q=p%C3%A3o+de+a%C3%A7%C3%BAcar\" role=\"button\" rel=\"noopener noreferrer\">EXPLORAR CURSOS<\/a>\n        <\/div>\n      <\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"container\" id=\"boxes\">\n  <div class=\"row\">\n\n    <div class=\"col-sm\">\n      <div class=\"estrategia\" id=\"box-assinatura\">\n        <h3 class=\"titulo-assinatura\">Assinatura Concursos<\/h3>\n        <p class=\"subtitulo-assinatura\">Assinatura de 1 ano ou 2 anos<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/assinaturas\/\" role=\"button\" rel=\"noopener noreferrer\">ASSINE AGORA<\/a>\n        <\/div>\n      <\/div><\/div><\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"h-quer-saber-tudo-sobre-concursos-previstos-confira-os-nossos-artigos\">Quer saber tudo sobre concursos previstos?<br \/>Confira os nossos artigos!<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos Abertos<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-educacao\/\">Concursos Educa\u00e7\u00e3o<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2026\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos 2026<\/a><\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"632\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/04\/01161145\/ficha-tecnica-5-1024x632.png\" alt=\"Informa\u00e7\u00f5es do concurso Prefeitura de P\u00e3o de A\u00e7\u00facar - AL\" class=\"wp-image-706736\" style=\"width:236px;height:145px\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/04\/01161145\/ficha-tecnica-5-1024x632.png 1024w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/04\/01161145\/ficha-tecnica-5-300x185.png 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/04\/01161145\/ficha-tecnica-5-768x474.png 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/04\/01161145\/ficha-tecnica-5-1536x948.png 1536w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/04\/01161145\/ficha-tecnica-5-610x377.png 610w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/04\/01161145\/ficha-tecnica-5.png 1571w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"ficha-tecnica\">Informa\u00e7\u00f5es do Concurso Mogi Mirim (SP)<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Data da prova<\/strong>: 26\/04\/2026<\/li>\n\n\n\n<li><strong>Banca<\/strong>: IBAM<\/li>\n\n\n\n<li><strong>Escolaridade<\/strong>: superior<\/li>\n\n\n\n<li><strong>Vagas:<\/strong> 16 + CR<\/li>\n\n\n\n<li><strong>Cargo<\/strong>: PROFESSOR<\/li>\n\n\n\n<li><strong>Edital<\/strong>:&nbsp;<a href=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2026\/01\/26132342\/37b46b12-bb0e-4353-af2b-b1dcee869419.pdf\" target=\"_blank\" rel=\"noreferrer noopener nofollow\"><\/a><a href=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2026\/02\/26112104\/e9bdfbc7-5bdb-40e3-b683-462fd58f486f.pdf\">Mogi Mirim Educa\u00e7\u00e3o 2026<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>A\u00a0Prefeitura de Mogi Mirim, em S\u00e3o Paulo, oferece oportunidades de n\u00edvel superior de escolaridade para diversas especialidades na carreira de professor. O certame est\u00e1 sob a responsabilidade da banca IBAM e destina-se ao preenchimento de 16 vagas, al\u00e9m de cadastro de reserva, com sal\u00e1rios que chegam a R$ 4.992,96. As&nbsp;provas objetivas&nbsp;ser\u00e3o realizadas na data de&nbsp;26 [&hellip;]<\/p>\n","protected":false},"author":2319,"featured_media":1090639,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"news_page","footnotes":""},"categories":[3766,220219],"tags":[],"tax_estado":[219989],"class_list":["post-1721617","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacional","category-noticias","tax_estado-sp"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Concurso Mogi Mirim (SP) Educa\u00e7\u00e3o: provas em abril<\/title>\n<meta name=\"description\" content=\"A\u00a0Prefeitura de Mogi Mirim, em S\u00e3o Paulo, publicou seu novo concurso, com oportunidades de n\u00edvel superior de escolaridade para diversas especialidades na carreira de professor.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-mogi-mirim-educacao\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Concurso Mogi Mirim (SP) Educa\u00e7\u00e3o: provas em abril\" \/>\n<meta property=\"og:description\" content=\"A\u00a0Prefeitura de Mogi Mirim, em S\u00e3o Paulo, publicou seu novo concurso, com oportunidades de n\u00edvel superior de escolaridade para diversas especialidades na carreira de professor.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-mogi-mirim-educacao\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-27T11:20:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-27T11:30:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/09\/06185737\/concursos_educacao.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"432\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Let\u00edcia Teixeira\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Let\u00edcia Teixeira\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-mogi-mirim-educacao\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-mogi-mirim-educacao\/\"},\"author\":{\"name\":\"Let\u00edcia Teixeira\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/9b94727dcf4410f4a7931c83966c843b\"},\"headline\":\"Concurso Mogi Mirim (SP) Educa\u00e7\u00e3o: provas em abril\",\"datePublished\":\"2026-03-27T11:20:00+00:00\",\"dateModified\":\"2026-03-27T11:30:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-mogi-mirim-educacao\/\"},\"wordCount\":1161,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-mogi-mirim-educacao\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/09\/06185737\/concursos_educacao.jpg\",\"articleSection\":[\"Educa\u00e7\u00e3o\",\"\u00daltimas not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-mogi-mirim-educacao\/#respond\"]}],\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-mogi-mirim-educacao\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-mogi-mirim-educacao\/\",\"name\":\"Concurso Mogi Mirim (SP) Educa\u00e7\u00e3o: provas em abril\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-mogi-mirim-educacao\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-mogi-mirim-educacao\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/09\/06185737\/concursos_educacao.jpg\",\"datePublished\":\"2026-03-27T11:20:00+00:00\",\"dateModified\":\"2026-03-27T11:30:39+00:00\",\"description\":\"A\u00a0Prefeitura de Mogi Mirim, em S\u00e3o Paulo, publicou seu novo concurso, com oportunidades de n\u00edvel superior de escolaridade para diversas especialidades na carreira de professor.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-mogi-mirim-educacao\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-mogi-mirim-educacao\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-mogi-mirim-educacao\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/09\/06185737\/concursos_educacao.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/09\/06185737\/concursos_educacao.jpg\",\"width\":768,\"height\":432,\"caption\":\"Concurso SME Indaial SP\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-mogi-mirim-educacao\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Concurso Mogi Mirim (SP) Educa\u00e7\u00e3o: provas em abril\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/9b94727dcf4410f4a7931c83966c843b\",\"name\":\"Let\u00edcia Teixeira\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/fb589b06b881e20b676d08f9d03226d1e3291ba2f90e751ddc9ccb21abf0244d?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/fb589b06b881e20b676d08f9d03226d1e3291ba2f90e751ddc9ccb21abf0244d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/fb589b06b881e20b676d08f9d03226d1e3291ba2f90e751ddc9ccb21abf0244d?s=96&d=mm&r=g\",\"caption\":\"Let\u00edcia Teixeira\"},\"description\":\"Jornalista com experi\u00eancia de mais de quatro anos no segmento de concursos p\u00fablicos. Especializada em Narrativa Transm\u00eddia e Storytelling pela Universidade Cat\u00f3lica de Bras\u00edlia, com atua\u00e7\u00e3o nas \u00e1reas de SEO, conte\u00fado, Webwriting e Copywriting.\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/leticia-teixeiraestrategia-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Concurso Mogi Mirim (SP) Educa\u00e7\u00e3o: provas em abril","description":"A\u00a0Prefeitura de Mogi Mirim, em S\u00e3o Paulo, publicou seu novo concurso, com oportunidades de n\u00edvel superior de escolaridade para diversas especialidades na carreira de professor.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-mogi-mirim-educacao\/","og_locale":"pt_BR","og_type":"article","og_title":"Concurso Mogi Mirim (SP) Educa\u00e7\u00e3o: provas em abril","og_description":"A\u00a0Prefeitura de Mogi Mirim, em S\u00e3o Paulo, publicou seu novo concurso, com oportunidades de n\u00edvel superior de escolaridade para diversas especialidades na carreira de professor.","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-mogi-mirim-educacao\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2026-03-27T11:20:00+00:00","article_modified_time":"2026-03-27T11:30:39+00:00","og_image":[{"width":768,"height":432,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/09\/06185737\/concursos_educacao.jpg","type":"image\/jpeg"}],"author":"Let\u00edcia Teixeira","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Let\u00edcia Teixeira","Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-mogi-mirim-educacao\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-mogi-mirim-educacao\/"},"author":{"name":"Let\u00edcia Teixeira","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/9b94727dcf4410f4a7931c83966c843b"},"headline":"Concurso Mogi Mirim (SP) Educa\u00e7\u00e3o: provas em abril","datePublished":"2026-03-27T11:20:00+00:00","dateModified":"2026-03-27T11:30:39+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-mogi-mirim-educacao\/"},"wordCount":1161,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-mogi-mirim-educacao\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/09\/06185737\/concursos_educacao.jpg","articleSection":["Educa\u00e7\u00e3o","\u00daltimas not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-mogi-mirim-educacao\/#respond"]}],"copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-mogi-mirim-educacao\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-mogi-mirim-educacao\/","name":"Concurso Mogi Mirim (SP) Educa\u00e7\u00e3o: provas em abril","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-mogi-mirim-educacao\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-mogi-mirim-educacao\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/09\/06185737\/concursos_educacao.jpg","datePublished":"2026-03-27T11:20:00+00:00","dateModified":"2026-03-27T11:30:39+00:00","description":"A\u00a0Prefeitura de Mogi Mirim, em S\u00e3o Paulo, publicou seu novo concurso, com oportunidades de n\u00edvel superior de escolaridade para diversas especialidades na carreira de professor.","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-mogi-mirim-educacao\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-mogi-mirim-educacao\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-mogi-mirim-educacao\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/09\/06185737\/concursos_educacao.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/09\/06185737\/concursos_educacao.jpg","width":768,"height":432,"caption":"Concurso SME Indaial SP"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-mogi-mirim-educacao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Concurso Mogi Mirim (SP) Educa\u00e7\u00e3o: provas em abril"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/9b94727dcf4410f4a7931c83966c843b","name":"Let\u00edcia Teixeira","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/fb589b06b881e20b676d08f9d03226d1e3291ba2f90e751ddc9ccb21abf0244d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fb589b06b881e20b676d08f9d03226d1e3291ba2f90e751ddc9ccb21abf0244d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fb589b06b881e20b676d08f9d03226d1e3291ba2f90e751ddc9ccb21abf0244d?s=96&d=mm&r=g","caption":"Let\u00edcia Teixeira"},"description":"Jornalista com experi\u00eancia de mais de quatro anos no segmento de concursos p\u00fablicos. Especializada em Narrativa Transm\u00eddia e Storytelling pela Universidade Cat\u00f3lica de Bras\u00edlia, com atua\u00e7\u00e3o nas \u00e1reas de SEO, conte\u00fado, Webwriting e Copywriting.","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/leticia-teixeiraestrategia-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1721617","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/2319"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1721617"}],"version-history":[{"count":6,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1721617\/revisions"}],"predecessor-version":[{"id":1744330,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1721617\/revisions\/1744330"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/1090639"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1721617"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1721617"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1721617"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1721617"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}