{"id":1688234,"date":"2025-12-18T18:40:00","date_gmt":"2025-12-18T21:40:00","guid":{"rendered":"https:\/\/blog-estrategia.mystagingwebsite.com\/blog\/?p=1688234"},"modified":"2025-12-18T19:16:43","modified_gmt":"2025-12-18T22:16:43","slug":"alepe-aprova-licenca-compensatoria-e-escalas","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/alepe-aprova-licenca-compensatoria-e-escalas\/","title":{"rendered":"ALEPE aprova licen\u00e7a compensat\u00f3ria e altera escalas! Veja!"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong><em>Confira neste artigo os detalhes do projeto aprovado que altera a licen\u00e7a compensat\u00f3ria e novas escalas de fun\u00e7\u00f5es estrat\u00e9gicas da ALEPE!<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A Assembleia Legislativa de Pernambuco (Alepe) aprovou, em plen\u00e1rio, uma norma interna que altera a organiza\u00e7\u00e3o das escalas de trabalho de parte do seu quadro funcional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m disso, a medida autoriza a concess\u00e3o de compensa\u00e7\u00f5es financeiras quando os per\u00edodos de descanso n\u00e3o forem usufru\u00eddos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O texto foi aprovado na ter\u00e7a-feira (16) por meio de <strong>projeto de resolu\u00e7\u00e3o<\/strong>, o que dispensa san\u00e7\u00e3o do Poder Executivo estadual e permite sua vig\u00eancia imediata, conforme regras da Casa.<\/p>\n\n\n\n<div class=\"container\" id=\"boxes\">\n  <div class=\"row\">\n\n    <div class=\"col-sm\">\n      <div class=\"banner-ale\" id=\"box-assinatura\">\n        <h2 class=\"titulo-assinatura\">Curso Concurso ALEPE<\/h2>\n        <p class=\"subtitulo-assinatura\">Explore os cursos preparat\u00f3rios completos! \u2728<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/cursosPorConcurso\/assembleia-legislativa-de-pernambuco-alepe-240\/\" role=\"button\" rel=\"noopener noreferrer\">VER CURSOS<\/a>\n        <\/div>\n      <\/div>\n     \n\n  <\/div>\n<\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-o-que-preve-a-nova-norma-aprovada-pela-alepe\">O que prev\u00ea a nova norma aprovada pela ALEPE?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">A emenda cria a chamada <strong>licen\u00e7a compensat\u00f3ria<\/strong>, na propor\u00e7\u00e3o de <strong>tr\u00eas dias \u00fateis de trabalho para um dia de licen\u00e7a<\/strong>, condicionada ao interesse do servi\u00e7o. De acordo com o texto aprovado:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>a licen\u00e7a ser\u00e1 adquirida em dias, sem possibilidade de fracionamento;<\/li>\n\n\n\n<li>o limite m\u00e1ximo ser\u00e1 de <strong>at\u00e9 10 dias de licen\u00e7a por m\u00eas<\/strong>;<\/li>\n\n\n\n<li>o benef\u00edcio poder\u00e1 ser convertido em indeniza\u00e7\u00e3o caso n\u00e3o seja usufru\u00eddo.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Na pr\u00e1tica, o sistema permite uma escala em que o servidor pode trabalhar quatro dias consecutivos e folgar tr\u00eas (4&#215;3), desde que atendidas as necessidades da administra\u00e7\u00e3o.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-e-quem-tera-direito-a-licenca-compensatoria-da-alepe\">E quem ter\u00e1 direito \u00e0 licen\u00e7a compensat\u00f3ria da ALEPE?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">O benef\u00edcio ser\u00e1 restrito a servidores que exercem fun\u00e7\u00f5es consideradas estrat\u00e9gicas na Alepe, especificamente para Consultores Legislativos e Procuradores Legislativos:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m disso, a norma autoriza a concess\u00e3o da licen\u00e7a a <strong>at\u00e9 dez servidores vinculados \u00e0 Mesa Diretora<\/strong>, sendo 5 indicados pela Presid\u00eancia e o restante pela Primeira-Secretaria.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ademais, as indica\u00e7\u00f5es caber\u00e3o aos deputados \u00c1lvaro Porto (PSDB), presidente da Alepe, e Francismar Pontes (PSB), primeiro-secret\u00e1rio da Casa.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-conversao-em-indenizacao-e-limitacoes-da-norma-da-alepe\">Convers\u00e3o em indeniza\u00e7\u00e3o e limita\u00e7\u00f5es da norma da ALEPE<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Caso a licen\u00e7a n\u00e3o seja usufru\u00edda, os dias poder\u00e3o ser convertidos em indeniza\u00e7\u00e3o, respeitado o limite mensal estabelecido. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No entanto, a pr\u00f3pria Alepe esclareceu que a <strong>efetiva implanta\u00e7\u00e3o do benef\u00edcio depende de disponibilidade or\u00e7ament\u00e1ria<\/strong>, do efetivo exerc\u00edcio do servidor e tamb\u00e9m de requerimento formal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Em nota oficial, a Assembleia informou que n\u00e3o h\u00e1 previs\u00e3o or\u00e7ament\u00e1ria para o pagamento da licen\u00e7a compensat\u00f3ria no exerc\u00edcio de 2026, o que inviabiliza sua implementa\u00e7\u00e3o para o pr\u00f3ximo ano. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A Casa tamb\u00e9m ressaltou que n\u00e3o h\u00e1 previs\u00e3o legal para convers\u00e3o retroativa do benef\u00edcio quando ele vier a ser implementado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por fim, \u00e9 importante destacar que o projeto gerou cr\u00edticas por parte de entidades sindicais e foi amplamente debatido pelos parlamentares ap\u00f3s a vota\u00e7\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para saber mais informa\u00e7\u00f5es sobre a nova escala das fun\u00e7\u00f5es estrat\u00e9gias da ALEPE, bem como de todos os detalhes sobre o projeto aprovado, acesse o linka abaixo:<\/p>\n\n\n\n<p class=\"has-text-align-center has-very-light-gray-to-cyan-bluish-gray-gradient-background has-background has-medium-font-size wp-block-paragraph\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-alepe\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Saiba tudo sobre o concurso ALEPE<\/strong><\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"cursos\">Quer saber tudo sobre concursos previstos?<br \/>Confira nossos artigos!<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2026\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos 2026<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos abertos<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-area-legislativa\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos legislativos<\/a><\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"curso\">Quer estudar para o concurso ALEPE?<\/h2>\n\n\n\n<div class=\"container\" id=\"boxes\">\n  <div class=\"row\">\n\n    <div class=\"col-sm\">\n      <div class=\"estrategia\" id=\"box-assinatura\">\n        <h3 class=\"titulo-assinatura\">Assinatura Concursos<\/h3>\n        <p class=\"subtitulo-assinatura\">Assinatura de 1 ano ou 2 anos<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/assinaturas\/\" role=\"button\" rel=\"noopener noreferrer\">ASSINE AGORA<\/a>\n        <\/div>\n      <\/div>\n     \n    <\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Confira neste artigo os detalhes do projeto aprovado que altera a licen\u00e7a compensat\u00f3ria e novas escalas de fun\u00e7\u00f5es estrat\u00e9gicas da ALEPE! A Assembleia Legislativa de Pernambuco (Alepe) aprovou, em plen\u00e1rio, uma norma interna que altera a organiza\u00e7\u00e3o das escalas de trabalho de parte do seu quadro funcional. Al\u00e9m disso, a medida autoriza a concess\u00e3o de [&hellip;]<\/p>\n","protected":false},"author":2134,"featured_media":921738,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"news","footnotes":""},"categories":[2017,220219],"tags":[],"tax_estado":[219979],"class_list":["post-1688234","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-concursos-legislativos","category-noticias","tax_estado-pe"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>ALEPE aprova licen\u00e7a compensat\u00f3ria e altera escalas! Veja!<\/title>\n<meta name=\"description\" content=\"Edital do Concurso ALEPE est\u00e1 previsto no Planejamento Estrat\u00e9gico; veja neste artigo os detalhes da licen\u00e7a compensat\u00f3ria e novas escalas!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/alepe-aprova-licenca-compensatoria-e-escalas\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ALEPE aprova licen\u00e7a compensat\u00f3ria e altera escalas! Veja!\" \/>\n<meta property=\"og:description\" content=\"Edital do Concurso ALEPE est\u00e1 previsto no Planejamento Estrat\u00e9gico; veja neste artigo os detalhes da licen\u00e7a compensat\u00f3ria e novas escalas!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/alepe-aprova-licenca-compensatoria-e-escalas\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-18T21:40:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-18T22:16:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/03140706\/alepe-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"432\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Rafaela Teixeira\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rafaela Teixeira\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/alepe-aprova-licenca-compensatoria-e-escalas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/alepe-aprova-licenca-compensatoria-e-escalas\\\/\"},\"author\":{\"name\":\"Rafaela Teixeira\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/e75352021ea7f60781c599934f916eb1\"},\"headline\":\"ALEPE aprova licen\u00e7a compensat\u00f3ria e altera escalas! Veja!\",\"datePublished\":\"2025-12-18T21:40:00+00:00\",\"dateModified\":\"2025-12-18T22:16:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/alepe-aprova-licenca-compensatoria-e-escalas\\\/\"},\"wordCount\":553,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/alepe-aprova-licenca-compensatoria-e-escalas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2020\\\/06\\\/03140706\\\/alepe-1.jpg\",\"articleSection\":[\"Legislativo\",\"\u00daltimas not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/alepe-aprova-licenca-compensatoria-e-escalas\\\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/alepe-aprova-licenca-compensatoria-e-escalas\\\/\",\"url\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/alepe-aprova-licenca-compensatoria-e-escalas\\\/\",\"name\":\"ALEPE aprova licen\u00e7a compensat\u00f3ria e altera escalas! Veja!\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/alepe-aprova-licenca-compensatoria-e-escalas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/alepe-aprova-licenca-compensatoria-e-escalas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2020\\\/06\\\/03140706\\\/alepe-1.jpg\",\"datePublished\":\"2025-12-18T21:40:00+00:00\",\"dateModified\":\"2025-12-18T22:16:43+00:00\",\"description\":\"Edital do Concurso ALEPE est\u00e1 previsto no Planejamento Estrat\u00e9gico; veja neste artigo os detalhes da licen\u00e7a compensat\u00f3ria e novas escalas!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/alepe-aprova-licenca-compensatoria-e-escalas\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/alepe-aprova-licenca-compensatoria-e-escalas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/alepe-aprova-licenca-compensatoria-e-escalas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2020\\\/06\\\/03140706\\\/alepe-1.jpg\",\"contentUrl\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2020\\\/06\\\/03140706\\\/alepe-1.jpg\",\"width\":768,\"height\":432},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/alepe-aprova-licenca-compensatoria-e-escalas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ALEPE aprova licen\u00e7a compensat\u00f3ria e altera escalas! Veja!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2025\\\/06\\\/03203428\\\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2025\\\/06\\\/03203428\\\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/e75352021ea7f60781c599934f916eb1\",\"name\":\"Rafaela Teixeira\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a349a2b22039b1ee88fc06461487c950fd6aa411ea8af8633314b43334ae793?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a349a2b22039b1ee88fc06461487c950fd6aa411ea8af8633314b43334ae793?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a349a2b22039b1ee88fc06461487c950fd6aa411ea8af8633314b43334ae793?s=96&d=mm&r=g\",\"caption\":\"Rafaela Teixeira\"},\"description\":\"Rafaela Teixeira \u00e9 advogada conveniada \u00e0 Defensoria P\u00fablica de S\u00e3o Paulo pela OAB, com experi\u00eancia em reda\u00e7\u00e3o jur\u00eddica e atua\u00e7\u00e3o em institui\u00e7\u00f5es p\u00fablicas, incluindo est\u00e1gio no TRE-SP. Possui mais de 7 anos de experi\u00eancia na produ\u00e7\u00e3o de conte\u00fados voltados ao nicho de concursos p\u00fablicos, com foco em apura\u00e7\u00e3o jornal\u00edstica cont\u00ednua, an\u00e1lise de editais e obten\u00e7\u00e3o de informa\u00e7\u00f5es diretamente junto a \u00f3rg\u00e3os e fontes oficiais. No Blog do Estrat\u00e9gia Concursos, atua como Analista de Conte\u00fado S\u00eanior, respons\u00e1vel pelo jornalismo do per\u00edodo noturno e da madrugada, com atua\u00e7\u00e3o transversal na cobertura de concursos p\u00fablicos, garantindo a continuidade, fluidez e confiabilidade das publica\u00e7\u00f5es e dos bastidores dos certames.\",\"url\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/author\\\/rafaela-teixeira\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"ALEPE aprova licen\u00e7a compensat\u00f3ria e altera escalas! Veja!","description":"Edital do Concurso ALEPE est\u00e1 previsto no Planejamento Estrat\u00e9gico; veja neste artigo os detalhes da licen\u00e7a compensat\u00f3ria e novas escalas!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/alepe-aprova-licenca-compensatoria-e-escalas\/","og_locale":"pt_BR","og_type":"article","og_title":"ALEPE aprova licen\u00e7a compensat\u00f3ria e altera escalas! Veja!","og_description":"Edital do Concurso ALEPE est\u00e1 previsto no Planejamento Estrat\u00e9gico; veja neste artigo os detalhes da licen\u00e7a compensat\u00f3ria e novas escalas!","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/alepe-aprova-licenca-compensatoria-e-escalas\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2025-12-18T21:40:00+00:00","article_modified_time":"2025-12-18T22:16:43+00:00","og_image":[{"width":768,"height":432,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/03140706\/alepe-1.jpg","type":"image\/jpeg"}],"author":"Rafaela Teixeira","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Rafaela Teixeira","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/alepe-aprova-licenca-compensatoria-e-escalas\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/alepe-aprova-licenca-compensatoria-e-escalas\/"},"author":{"name":"Rafaela Teixeira","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/e75352021ea7f60781c599934f916eb1"},"headline":"ALEPE aprova licen\u00e7a compensat\u00f3ria e altera escalas! Veja!","datePublished":"2025-12-18T21:40:00+00:00","dateModified":"2025-12-18T22:16:43+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/alepe-aprova-licenca-compensatoria-e-escalas\/"},"wordCount":553,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/alepe-aprova-licenca-compensatoria-e-escalas\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/03140706\/alepe-1.jpg","articleSection":["Legislativo","\u00daltimas not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/alepe-aprova-licenca-compensatoria-e-escalas\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/alepe-aprova-licenca-compensatoria-e-escalas\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/alepe-aprova-licenca-compensatoria-e-escalas\/","name":"ALEPE aprova licen\u00e7a compensat\u00f3ria e altera escalas! Veja!","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/alepe-aprova-licenca-compensatoria-e-escalas\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/alepe-aprova-licenca-compensatoria-e-escalas\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/03140706\/alepe-1.jpg","datePublished":"2025-12-18T21:40:00+00:00","dateModified":"2025-12-18T22:16:43+00:00","description":"Edital do Concurso ALEPE est\u00e1 previsto no Planejamento Estrat\u00e9gico; veja neste artigo os detalhes da licen\u00e7a compensat\u00f3ria e novas escalas!","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/alepe-aprova-licenca-compensatoria-e-escalas\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/alepe-aprova-licenca-compensatoria-e-escalas\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/alepe-aprova-licenca-compensatoria-e-escalas\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/03140706\/alepe-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/03140706\/alepe-1.jpg","width":768,"height":432},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/alepe-aprova-licenca-compensatoria-e-escalas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"ALEPE aprova licen\u00e7a compensat\u00f3ria e altera escalas! Veja!"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/e75352021ea7f60781c599934f916eb1","name":"Rafaela Teixeira","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/8a349a2b22039b1ee88fc06461487c950fd6aa411ea8af8633314b43334ae793?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8a349a2b22039b1ee88fc06461487c950fd6aa411ea8af8633314b43334ae793?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8a349a2b22039b1ee88fc06461487c950fd6aa411ea8af8633314b43334ae793?s=96&d=mm&r=g","caption":"Rafaela Teixeira"},"description":"Rafaela Teixeira \u00e9 advogada conveniada \u00e0 Defensoria P\u00fablica de S\u00e3o Paulo pela OAB, com experi\u00eancia em reda\u00e7\u00e3o jur\u00eddica e atua\u00e7\u00e3o em institui\u00e7\u00f5es p\u00fablicas, incluindo est\u00e1gio no TRE-SP. Possui mais de 7 anos de experi\u00eancia na produ\u00e7\u00e3o de conte\u00fados voltados ao nicho de concursos p\u00fablicos, com foco em apura\u00e7\u00e3o jornal\u00edstica cont\u00ednua, an\u00e1lise de editais e obten\u00e7\u00e3o de informa\u00e7\u00f5es diretamente junto a \u00f3rg\u00e3os e fontes oficiais. No Blog do Estrat\u00e9gia Concursos, atua como Analista de Conte\u00fado S\u00eanior, respons\u00e1vel pelo jornalismo do per\u00edodo noturno e da madrugada, com atua\u00e7\u00e3o transversal na cobertura de concursos p\u00fablicos, garantindo a continuidade, fluidez e confiabilidade das publica\u00e7\u00f5es e dos bastidores dos certames.","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/rafaela-teixeira\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1688234","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/2134"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1688234"}],"version-history":[{"count":0,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1688234\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/921738"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1688234"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1688234"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1688234"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1688234"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}