{"id":1671988,"date":"2025-11-18T09:28:54","date_gmt":"2025-11-18T12:28:54","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=1671988"},"modified":"2025-11-18T09:28:56","modified_gmt":"2025-11-18T12:28:56","slug":"informativo-stj-867-comentado","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-867-comentado\/","title":{"rendered":"Informativo STJ 867 Comentado"},"content":{"rendered":"\n<p><\/p><p class=\"has-text-align-center\"><a href=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/11\/18092830\/stj-info-867.pdf\" rel=\"sponsored nofollow\">DOWNLOAD do PDF AQUI!<\/a><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"lyte-wrapper\" style=\"width:853px;max-width:100%;margin:5px;\"><div class=\"lyMe\" id=\"WYL_yqErRcI6cMA\"><div id=\"lyte_yqErRcI6cMA\" data-src=\"\/\/i.ytimg.com\/vi\/yqErRcI6cMA\/hqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\"><\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/yqErRcI6cMA\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/yqErRcI6cMA\/0.jpg\" alt=\"YouTube video thumbnail\" width=\"853\" height=\"460\" \/><br \/>Assista a este v\u00eddeo no YouTube<\/a><\/noscript><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:853px;margin:5px;\"><\/div>\n<\/div><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-1-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-taxa-de-juros-moratorios-nas-dividas-civis-aplicacao-da-selic\">1.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Taxa de juros morat\u00f3rios nas d\u00edvidas civis: aplica\u00e7\u00e3o da SELIC<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-destaque\">Destaque<\/h3>\n\n\n\n<p>O art. 406 do C\u00f3digo Civil de 2002, antes da entrada em vigor da Lei 14.905\/2024, deve ser interpretado no sentido de que a taxa SELIC \u00e9 a taxa de juros de mora aplic\u00e1vel \u00e0s d\u00edvidas de natureza civil, por ser a mesma taxa em vigor para a atualiza\u00e7\u00e3o monet\u00e1ria e a mora no pagamento de tributos devidos \u00e0 Fazenda Nacional.<\/p>\n\n\n\n<p>REsp 2.199.164-PR e REsp 2.070.882-RS (Tema 1368\/STJ), Rel. Min. Ricardo Villas B\u00f4as Cueva, Corte Especial, por unanimidade, julgados em 15\/10\/2025.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-conteudo-base\">Conte\u00fado-Base<\/h3>\n\n\n\n<p>???? CC, arts. 404 e 406; CTN, art. 161 \u00a71\u00ba; Leis 8.981\/1995, 9.065\/1995, 9.250\/1995, 9.393\/1996, 10.522\/2002; EC 113\/2021.<\/p>\n\n\n\n<p>???? O art. 406 do CC vincula os juros civis \u00e0 taxa aplic\u00e1vel aos tributos federais, ou seja, \u00e0 SELIC.<\/p>\n\n\n\n<p>???? A taxa SELIC incorpora juros morat\u00f3rios e corre\u00e7\u00e3o monet\u00e1ria, evitando cumula\u00e7\u00e3o de \u00edndices.<\/p>\n\n\n\n<p>???? A uniformiza\u00e7\u00e3o visa garantir previsibilidade e estabilidade macroecon\u00f4mica.<\/p>\n\n\n\n<p>???? A fun\u00e7\u00e3o dos juros civis \u00e9 compensat\u00f3ria, n\u00e3o punitiva.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-discussao-e-tese\">Discuss\u00e3o e Tese<\/h3>\n\n\n\n<p>???? A Corte Especial consolidou a jurisprud\u00eancia das Se\u00e7\u00f5es de Direito P\u00fablico e Privado sobre o alcance do art. 406 do C\u00f3digo Civil.<\/p>\n\n\n\n<p>\u2696\ufe0f Tese do Tema 1368\/STJ: \u201cAntes da entrada em vigor da Lei 14.905\/2024, o art. 406 do C\u00f3digo Civil deve ser interpretado no sentido de que a taxa de juros de mora aplic\u00e1vel \u00e0s d\u00edvidas civis \u00e9 a SELIC, por ser a taxa vigente para atualiza\u00e7\u00e3o monet\u00e1ria e mora de tributos federais.\u201d<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-como-sera-cobrado-em-prova\">Como ser\u00e1 Cobrado em Prova<\/h3>\n\n\n\n<p>???? A taxa de juros civis de mora, antes da Lei 14.905\/2024, \u00e9 de 1% ao m\u00eas, nos termos do art. 161 \u00a71\u00ba do CTN.<\/p>\n\n\n\n<p>\u274c Errado. A Corte Especial fixou a SELIC como taxa aplic\u00e1vel.<\/p>\n\n\n\n<p>???? A SELIC \u00e9 a taxa legal de juros morat\u00f3rios nas d\u00edvidas civis, conforme interpreta\u00e7\u00e3o do art. 406 do CC.<\/p>\n\n\n\n<p>\u2705 Correto. Essa foi a tese fixada no Tema 1368\/STJ.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-versao-esquematizada\">Vers\u00e3o Esquematizada<\/h3>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td>???? Juros morat\u00f3rios civis \u2013 SELIC<\/td><\/tr><tr><td>???? CC, art. 406 ???? CTN, art. 161 \u00a71\u00ba ???? SELIC = juros + corre\u00e7\u00e3o monet\u00e1ria ???? Tema 1368\/STJ<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-inteiro-teor\">Inteiro Teor<\/h3>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; A quest\u00e3o em discuss\u00e3o consiste em saber se a taxa referencial do Sistema Especial de Liquida\u00e7\u00e3o e Cust\u00f3dia (SELIC) deve ser considerada para a fixa\u00e7\u00e3o dos juros morat\u00f3rios a que se referia o art. 406 do C\u00f3digo Civil antes da entrada em vigor da Lei n. 14.905\/2024.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; De in\u00edcio, ressalta-se que<em> a taxa SELIC \u00e9 a \u00fanica taxa atualmente em vigor para a mora no pagamento de impostos federais<\/em>, conforme previsto em diversas legisla\u00e7\u00f5es tribut\u00e1rias (Leis n. 8.981\/1995, 9.065\/1995, 9.250\/9195, 9.393\/1996, 10.522\/2002, Decreto 7.212\/2010, entre outras), possuindo tamb\u00e9m status constitucional a partir da Emenda Constitucional n. 113.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Ainda destaca-se que o art. 161, \u00a7 1\u00ba, do CTN prev\u00ea a taxa de 1% ao m\u00eas apenas de forma subsidi\u00e1ria, ou seja, quando n\u00e3o houver disposi\u00e7\u00e3o legal diversa. E como h\u00e1 leis espec\u00edficas que determinam a aplica\u00e7\u00e3o da SELIC para os impostos federais, o dispositivo do CTN n\u00e3o se aplica ao caso.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Dessa forma, n\u00e3o h\u00e1 falar em fun\u00e7\u00e3o punitiva dos juros morat\u00f3rios, eis que para isso existem as previs\u00f5es contratuais de multa morat\u00f3ria, sendo a sua fun\u00e7\u00e3o apenas a de compensar o des\u00e1gio do credor. Segundo o art. 404 do C\u00f3digo Civil, se os juros n\u00e3o cobrem o preju\u00edzo, o juiz pode inclusive conceder indeniza\u00e7\u00e3o suplementar.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Nesse sentido, fixar juros civis de mora diferentes do par\u00e2metro nacional viola o art. 406 do CC e causa impacto macroecon\u00f4mico. A lei prev\u00ea que os juros morat\u00f3rios civis sigam a mesma taxa aplicada \u00e0 mora de impostos federais, garantindo harmonia entre obriga\u00e7\u00f5es p\u00fablicas e privadas. Como esses \u00edndices oficiais s\u00e3o ajustados conforme a macroeconomia, o valor aplicado nas rela\u00e7\u00f5es privadas n\u00e3o deve superar o n\u00edvel b\u00e1sico definido para toda a economia.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Consigna-se, ademais, que nos Temas 99, 112 e 113 fixados em recursos especiais repetitivos, a Primeira Se\u00e7\u00e3o desta Corte definiu as teses no sentido de ser <strong>a SELIC a taxa legal referenciada na reda\u00e7\u00e3o original do art. 406 do C\u00f3digo Civil<\/strong>. A jurisprud\u00eancia consolidada do Superior Tribunal de Justi\u00e7a e do Supremo Tribunal Federal reconhece a validade da SELIC como \u00edndice de corre\u00e7\u00e3o monet\u00e1ria e juros morat\u00f3rios, aplic\u00e1vel \u00e0s condena\u00e7\u00f5es c\u00edveis em geral.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Ressalta-se, por fim, que, a SELIC, por englobar juros de mora e corre\u00e7\u00e3o monet\u00e1ria, evita a cumula\u00e7\u00e3o de \u00edndices distintos, garantindo maior previsibilidade e alinhamento com o sistema econ\u00f4mico nacional.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-2-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-irpf-e-pagamento-de-multa-de-colaboracao-premiada-por-terceiro\">2.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; IRPF e pagamento de multa de colabora\u00e7\u00e3o premiada por terceiro<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-destaque-0\">Destaque<\/h3>\n\n\n\n<p>A quita\u00e7\u00e3o, por terceiro, de multa assumida por pessoa f\u00edsica em acordo de colabora\u00e7\u00e3o premiada configura acr\u00e9scimo patrimonial indireto, caracterizando fato gerador do Imposto sobre a Renda das Pessoas F\u00edsicas (IRPF).<\/p>\n\n\n\n<p>Processo em segredo de justi\u00e7a, Rel. Min. Regina Helena Costa, Primeira Turma, por unanimidade, julgado em 7\/10\/2025.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-conteudo-base-0\">Conte\u00fado-Base<\/h3>\n\n\n\n<p>???? CTN, art. 43; Lei 9.430\/1996, art. 70.<\/p>\n\n\n\n<p>???? A libera\u00e7\u00e3o de obriga\u00e7\u00e3o pessoal por terceiro representa disponibilidade de renda.<\/p>\n\n\n\n<p>???? A multa de colabora\u00e7\u00e3o premiada tem natureza personal\u00edssima.<\/p>\n\n\n\n<p>???? A quita\u00e7\u00e3o volunt\u00e1ria por ex-empregadora constitui liberalidade sujeita \u00e0 tributa\u00e7\u00e3o.<\/p>\n\n\n\n<p>???? O fato gerador do IRPF ocorre com o acr\u00e9scimo patrimonial, ainda que indireto.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-discussao-e-tese-0\">Discuss\u00e3o e Tese<\/h3>\n\n\n\n<p>???? O STJ confirmou que a assun\u00e7\u00e3o volunt\u00e1ria de d\u00edvida pessoal por terceiro gera acr\u00e9scimo patrimonial tribut\u00e1vel.<\/p>\n\n\n\n<p>\u2696\ufe0f A Primeira Turma entendeu que, por n\u00e3o haver obriga\u00e7\u00e3o legal da empresa, o pagamento configurou benef\u00edcio econ\u00f4mico ao colaborador, incidindo IRPF.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-como-sera-cobrado-em-prova-0\">Como ser\u00e1 Cobrado em Prova<\/h3>\n\n\n\n<p>???? O pagamento de multa de colabora\u00e7\u00e3o premiada por terceiro n\u00e3o configura fato gerador do IRPF, por n\u00e3o haver transfer\u00eancia direta de renda.<\/p>\n\n\n\n<p>\u274c Errado. A libera\u00e7\u00e3o de despesa pessoal \u00e9 acr\u00e9scimo patrimonial indireto.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-versao-esquematizada-0\">Vers\u00e3o Esquematizada<\/h3>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td>???? IRPF \u2013 colabora\u00e7\u00e3o premiada<\/td><\/tr><tr><td>???? CTN, art. 43 ???? Lei 9.430\/1996, art. 70 ???? Acr\u00e9scimo patrimonial indireto ???? Incid\u00eancia do imposto reconhecida<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-inteiro-teor-0\">Inteiro Teor<\/h3>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; A controv\u00e9rsia tem origem em Mandado de Seguran\u00e7a impetrado buscando-se afastar a incid\u00eancia do Imposto sobre a Renda das Pessoas F\u00edsicas (IRPF), relativamente a acr\u00e9scimo patrimonial experimentado diante da quita\u00e7\u00e3o, por sua ex-empregadora, empresa construtora, de multa assumida pelo impetrante em acordo de colabora\u00e7\u00e3o premiada.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Em primeira inst\u00e2ncia, a seguran\u00e7a foi denegada, decis\u00e3o mantida pelo Tribunal Regional Federal da 2\u00aa Regi\u00e3o, sob o fundamento de que o pagamento de obriga\u00e7\u00e3o pecuni\u00e1ria firmada em acordo de colabora\u00e7\u00e3o premiada \u00e9 dever exclusivo do colaborador, raz\u00e3o pela qual eventual assun\u00e7\u00e3o de \u00f4nus financeiro por terceiro, sobretudo a ex-empregadora, encerra mera liberalidade em decorr\u00eancia de rescis\u00e3o de contrato de trabalho, configurando, assim, acr\u00e9scimo patrimonial sujeito ao Imposto sobre a Renda das Pessoas F\u00edsicas.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Com efeito, como consignado pelo tribunal de origem, a ex-empregadora disponibilizou o montante para pagamento da multa, tendo o dep\u00f3sito em conta judicial sido efetuado em seu pr\u00f3prio nome.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Ainda que a construtora tenha quitado diretamente o valor da penalidade assumida pelo recorrente em acordo de colabora\u00e7\u00e3o premiada e sem tr\u00e2nsito de valores nas contas da pessoa f\u00edsica, tal circunst\u00e2ncia n\u00e3o \u00e9 apta, por si s\u00f3, a afastar a perfectibiliza\u00e7\u00e3o do aspecto material da hip\u00f3tese de incid\u00eancia do imposto em tela, porquanto a libera\u00e7\u00e3o de obriga\u00e7\u00e3o passiva do contribuinte por terceiros denota disponibilidade de renda mediante acr\u00e9scimo patrimonial indireto, configurando, assim, o fato gerador descrito no art. 43 do C\u00f3digo Tribut\u00e1rio Nacional.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; No caso, <em>a multa possui natureza jur\u00eddica de san\u00e7\u00e3o, assumida pela parte em seu pr\u00f3prio nome, em car\u00e1ter personal\u00edssimo, a qual deve ser suportada pelo seu pr\u00f3prio patrim\u00f4nio<\/em>.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Assim, ausente dever legal ou decorrente de neg\u00f3cio jur\u00eddico de natureza p\u00fablica impondo \u00e0 empresa o \u00f4nus financeiro de adimplir com a san\u00e7\u00e3o assumida pelo impetrante no acordo de colabora\u00e7\u00e3o premiada &#8211; o qual, reitere-se, det\u00e9m natureza personal\u00edssima -, impende reconhecer-se ter sido o valor espontaneamente creditado.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Dessa maneira, tendo o tribunal a quo firmado a premissa f\u00e1tica de que a companhia &#8220;[&#8230;] conferiu ao seu ex-empregado\/impetrante verba por mera liberalidade, em decorr\u00eancia da rescis\u00e3o do contrato de trabalho&#8221;, de rigor a aplica\u00e7\u00e3o do art. 70 da Lei n. 9.430\/1996, segundo o qual &#8220;[&#8230;] a multa ou qualquer outra vantagem paga ou creditada por pessoa jur\u00eddica, ainda que a t\u00edtulo de indeniza\u00e7\u00e3o, a benefici\u00e1ria pessoa f\u00edsica ou jur\u00eddica, inclusive isenta, em virtude de rescis\u00e3o de contrato, sujeitam-se \u00e0 incid\u00eancia do imposto de renda&#8221;.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-3-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-execucao-fiscal-e-legitimidade-passiva-do-consorcio-de-empresas\">3.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Execu\u00e7\u00e3o fiscal e legitimidade passiva do cons\u00f3rcio de empresas<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-destaque-1\">Destaque<\/h3>\n\n\n\n<p>O cons\u00f3rcio de empresas, embora desprovido de personalidade jur\u00eddica, possui personalidade judici\u00e1ria e pode figurar no polo passivo de execu\u00e7\u00e3o fiscal, desde que tenha realizado o fato gerador da obriga\u00e7\u00e3o tribut\u00e1ria.<\/p>\n\n\n\n<p>REsp 1.647.368-PE, Rel. Min. Marco Aur\u00e9lio Bellizze, Segunda Turma, por unanimidade, julgado em 7\/10\/2025.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-conteudo-base-1\">Conte\u00fado-Base<\/h3>\n\n\n\n<p>???? CTN, art. 126 III; CC, arts. 45 e 985; CPC, art. 75 IX; Lei 6.404\/1976, art. 278; Lei 12.402\/2011, art. 1\u00ba \u00a71\u00ba.<\/p>\n\n\n\n<p>???? O cons\u00f3rcio \u00e9 unidade econ\u00f4mica com capacidade tribut\u00e1ria passiva.<\/p>\n\n\n\n<p>???? A aus\u00eancia de personalidade jur\u00eddica n\u00e3o afasta sua legitimidade processual.<\/p>\n\n\n\n<p>???? A responsabilidade das consorciadas \u00e9 solid\u00e1ria apenas nas condi\u00e7\u00f5es contratuais.<\/p>\n\n\n\n<p>???? O cons\u00f3rcio pode ser demandado por tributos devidos em seu nome.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-discussao-e-tese-1\">Discuss\u00e3o e Tese<\/h3>\n\n\n\n<p>???? O STJ reconheceu que o cons\u00f3rcio, ainda que sem personalidade jur\u00eddica, possui legitimidade para responder em execu\u00e7\u00e3o fiscal.<\/p>\n\n\n\n<p>\u2696\ufe0f A Segunda Turma reafirmou que basta a configura\u00e7\u00e3o de unidade econ\u00f4mica para legitimar a cobran\u00e7a, conforme o art. 126 III do CTN.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-como-sera-cobrado-em-prova-1\">Como ser\u00e1 Cobrado em Prova<\/h3>\n\n\n\n<p>???? O cons\u00f3rcio pode figurar no polo passivo da execu\u00e7\u00e3o fiscal, desde que tenha praticado o fato gerador tribut\u00e1rio.<\/p>\n\n\n\n<p>\u2705 Correto. O STJ reconheceu a personalidade judici\u00e1ria do cons\u00f3rcio e capacidade tribut\u00e1ria passiva.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-versao-esquematizada-1\">Vers\u00e3o Esquematizada<\/h3>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td>???? Execu\u00e7\u00e3o fiscal \u2013 cons\u00f3rcio de empresas<\/td><\/tr><tr><td>???? CTN, art. 126 III ???? Lei 6.404\/1976, art. 278 ???? Personalidade judici\u00e1ria reconhecida ???? Responsabilidade conforme contrato<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-inteiro-teor-1\">Inteiro Teor<\/h3>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; A quest\u00e3o em discuss\u00e3o consiste em saber se <em>o cons\u00f3rcio de empresas, constitu\u00eddo<\/em> nos termos da Lei n. 6.404\/1976, possui legitimidade para integrar o polo passivo da execu\u00e7\u00e3o fiscal, mesmo sem personalidade jur\u00eddica.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Assenta o art. 278, caput, da Lei n. 6.404\/1976 que &#8220;as companhias e quaisquer outras sociedades, sob o mesmo controle ou n\u00e3o, podem constituir cons\u00f3rcio para executar determinado empreendimento, observado o disposto neste Cap\u00edtulo&#8221;. No respectivo \u00a7 1\u00ba, especifica-se que &#8220;o cons\u00f3rcio n\u00e3o tem personalidade jur\u00eddica e as consorciadas somente se obrigam nas condi\u00e7\u00f5es previstas no respectivo contrato, respondendo cada uma por suas obriga\u00e7\u00f5es, sem presun\u00e7\u00e3o de solidariedade&#8221;.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; A despeito da aus\u00eancia de personalidade jur\u00eddica do cons\u00f3rcio de empresas, tal circunst\u00e2ncia n\u00e3o o impede que figure como sujeito passivo da obriga\u00e7\u00e3o tribut\u00e1ria, visto que, nos termos do art. 126, III, do C\u00f3digo Tribut\u00e1rio Nacional &#8211; CTN, &#8220;<em>a capacidade tribut\u00e1ria passiva independe [&#8230;] de estar a pessoa jur\u00eddica regularmente constitu\u00edda, bastando que configure uma unidade econ\u00f4mica ou profissional<\/em>&#8220;.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Em rela\u00e7\u00e3o a esse dispositivo legal, conv\u00e9m destacar que a regular constitui\u00e7\u00e3o da pessoa jur\u00eddica d\u00e1-se, segundo a intelig\u00eancia dos arts. 45 e 985 do C\u00f3digo Civil, a partir do registro do seu ato constitutivo (contrato social ou estatuto social) no registro competente (registro p\u00fablico de empresas mercantis &#8211; juntas comerciais &#8211; ou registro civil de pessoas jur\u00eddicas), o que marca o in\u00edcio da exist\u00eancia legal da pessoa jur\u00eddica de direito privado.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Atrav\u00e9s de uma leitura mais detida do art. 126 do CTN, infere-se, conforme entendimento doutrin\u00e1rio, que quem realiza o fato gerador est\u00e1 obrigado ao pagamento do tributo, ainda que n\u00e3o tenha ou n\u00e3o esteja no gozo de capacidade civil plena ou que esteja atuando mediante sociedade irregular ou de fato.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Logo, sendo o fato gerador praticado pelo cons\u00f3rcio de empresas, da\u00ed exsurge a sua responsabilidade pelo adimplemento da obriga\u00e7\u00e3o tribut\u00e1ria, sendo irrelevante, para esse fim, a exist\u00eancia ou n\u00e3o de personalidade jur\u00eddica. Afinal, o cons\u00f3rcio consubstancia inequ\u00edvoca unidade econ\u00f4mica, ensejadora da capacidade tribut\u00e1ria passiva, como preceitua o inciso III do art. 126 do CTN.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Essa acep\u00e7\u00e3o de direito material converge com o tratamento jur\u00eddico dado pela norma adjetiva. O C\u00f3digo de Processo Civil de 2015 preconiza, em seu art. 75, IX, que ser\u00e3o representados em ju\u00edzo, ativa e passivamente, a sociedade e a associa\u00e7\u00e3o irregulares e outros entes organizados sem personalidade jur\u00eddica, pela pessoa a quem couber a administra\u00e7\u00e3o de seus bens.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Al\u00e9m disso, a Lei n. 6.830\/1980 &#8211; que regulamenta e execu\u00e7\u00e3o fiscal de cr\u00e9dito tribut\u00e1rio e n\u00e3o tribut\u00e1rio &#8211; estabelece em seu art. 4\u00ba, III e IV, que a execu\u00e7\u00e3o fiscal poder\u00e1 ser promovida contra o esp\u00f3lio e a massa, que s\u00e3o esp\u00e9cies de entes despersonalizados, tal como o referido cons\u00f3rcio.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Por conseguinte, em interpreta\u00e7\u00e3o sistem\u00e1tica do ordenamento jur\u00eddico p\u00e1trio, depreende-se que cons\u00f3rcio de empresas institu\u00eddo com amparo na Lei n. 6.404\/1976, <strong>embora n\u00e3o detenha personalidade jur\u00eddica, possui personalidade judici\u00e1ria, podendo ser demandado &#8211; notadamente em execu\u00e7\u00e3o fiscal &#8211; pelas obriga\u00e7\u00f5es tribut\u00e1rias a que deu causa<\/strong>.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Tal acep\u00e7\u00e3o \u00e9 corroborada pelo art. 1\u00ba, \u00a7 1\u00ba, da Lei n. 12.402\/2011, segundo o qual &#8220;o cons\u00f3rcio que realizar a contrata\u00e7\u00e3o, em nome pr\u00f3prio, de pessoas jur\u00eddicas e f\u00edsicas, com ou sem v\u00ednculo empregat\u00edcio, poder\u00e1 efetuar a reten\u00e7\u00e3o de tributos e o cumprimento das respectivas obriga\u00e7\u00f5es acess\u00f3rias, ficando as empresas consorciadas solidariamente respons\u00e1veis&#8221;.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-4-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-penhora-de-bem-indivisivel-e-direito-de-preferencia-do-coproprietario-nao-executado\">4.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Penhora de bem indivis\u00edvel e direito de prefer\u00eancia do copropriet\u00e1rio n\u00e3o executado<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-destaque-2\">Destaque<\/h3>\n\n\n\n<p>Na penhora de bem indivis\u00edvel, a quota-parte do copropriet\u00e1rio alheio \u00e0 execu\u00e7\u00e3o, que exerce o direito de prefer\u00eancia na arremata\u00e7\u00e3o, deve ser calculada com base no valor de avalia\u00e7\u00e3o do bem, e n\u00e3o sobre o valor de arremate.<\/p>\n\n\n\n<p>REsp 2.180.611-DF, Rel. Min. Nancy Andrighi, Terceira Turma, por unanimidade, julgado em 16\/9\/2025, DJEN 19\/9\/2025.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-conteudo-base-2\">Conte\u00fado-Base<\/h3>\n\n\n\n<p>???? CPC, art. 843 \u00a7\u00a71\u00ba e 2\u00ba.<\/p>\n\n\n\n<p>???? O exerc\u00edcio do direito de prefer\u00eancia visa a assegurar igualdade entre o copropriet\u00e1rio e terceiros interessados.<\/p>\n\n\n\n<p>???? O c\u00e1lculo sobre o valor de avalia\u00e7\u00e3o preserva o patrim\u00f4nio do copropriet\u00e1rio alheio \u00e0 execu\u00e7\u00e3o.<\/p>\n\n\n\n<p>???? A base de c\u00e1lculo sobre o valor de arremate reduziria indevidamente o valor de sua quota-parte.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-discussao-e-tese-2\">Discuss\u00e3o e Tese<\/h3>\n\n\n\n<p>???? O STJ analisou a extens\u00e3o do direito de prefer\u00eancia e da prote\u00e7\u00e3o ao copropriet\u00e1rio n\u00e3o executado.<\/p>\n\n\n\n<p>\u2696\ufe0f O Tribunal concluiu que o art. 843 do CPC garante o direito de prefer\u00eancia com base no valor de avalia\u00e7\u00e3o, para impedir perda patrimonial indevida.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-como-sera-cobrado-em-prova-2\">Como ser\u00e1 Cobrado em Prova<\/h3>\n\n\n\n<p>???? A quota-parte do copropriet\u00e1rio alheio \u00e0 execu\u00e7\u00e3o deve ser calculada sobre o valor de arremate.<\/p>\n\n\n\n<p>\u274c Errado. O valor de avalia\u00e7\u00e3o do bem \u00e9 a base para o c\u00e1lculo da quota-parte do copropriet\u00e1rio que exerce a prefer\u00eancia.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-versao-esquematizada-2\">Vers\u00e3o Esquematizada<\/h3>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td>???? Penhora \u2013 bem indivis\u00edvel<\/td><\/tr><tr><td>???? CPC, art. 843 \u00a7\u00a71\u00ba-2\u00ba ???? Direito de prefer\u00eancia ???? Base de c\u00e1lculo: valor de avalia\u00e7\u00e3o<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-inteiro-teor-2\">Inteiro Teor<\/h3>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Segundo o art. 843, caput e \u00a7 2\u00ba, do CPC, em se tratando de penhora de bem indivis\u00edvel, a quota-parte do copropriet\u00e1rio ou do c\u00f4njuge alheio \u00e0 execu\u00e7\u00e3o recair\u00e1 sobre o valor de avalia\u00e7\u00e3o do bem, como forma de preservar seu patrim\u00f4nio.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; O exerc\u00edcio do direito de prefer\u00eancia, conferido pelo \u00a7 1\u00ba do art. 843, visa a garantir ao copropriet\u00e1rio a possibilidade de aquisi\u00e7\u00e3o integral do bem, em igualdade de condi\u00e7\u00f5es com terceiros, sem preju\u00edzo de assegurar-lhe o recebimento de sua quota-parte na integralidade, <strong>calculada sobre o valor de avalia\u00e7\u00e3o<\/strong>.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; A prote\u00e7\u00e3o legal ao copropriet\u00e1rio n\u00e3o executado impede que sua quota-parte seja apurada sobre valor inferior ao da avalia\u00e7\u00e3o, mesmo no exerc\u00edcio de seu direito de prefer\u00eancia.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Com isso, o direito assegurado ao copropriet\u00e1rio n\u00e3o executado de receber sua quota-parte pelo valor de avalia\u00e7\u00e3o, subsiste ao exerc\u00edcio do direito de prefer\u00eancia da arremata\u00e7\u00e3o do bem leiloado. Pois do contr\u00e1rio, n\u00e3o estaria sendo garantida a igualdade de condi\u00e7\u00f5es do copropriet\u00e1rio alheio \u00e0 execu\u00e7\u00e3o, uma vez que, <em>ao recalcular sua quota-parte em rela\u00e7\u00e3o ao valor de arremate, delapidaria seu patrim\u00f4nio<\/em>, o qual em nada \u00e9 respons\u00e1vel pela d\u00edvida do copropriet\u00e1rio executado. Ensejando em preju\u00edzo ao copropriet\u00e1rio alheio \u00e0 execu\u00e7\u00e3o quando este optasse pela prefer\u00eancia na arremata\u00e7\u00e3o.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Assim, em caso de arremata\u00e7\u00e3o inferior ao valor da avalia\u00e7\u00e3o, e preferindo o copropriet\u00e1rio alheio \u00e0 execu\u00e7\u00e3o pela prefer\u00eancia na arremata\u00e7\u00e3o, a igualdade de condi\u00e7\u00f5es ser\u00e1 efetivada ao complementar a diferen\u00e7a entre a sua quota-parte avaliada e o valor da arremata\u00e7\u00e3o.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-5-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-leilao-extrajudicial-e-nulidade-por-descricao-desatualizada-do-imovel\">5.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Leil\u00e3o extrajudicial e nulidade por descri\u00e7\u00e3o desatualizada do im\u00f3vel<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-destaque-3\">Destaque<\/h3>\n\n\n\n<p>O edital de leil\u00e3o extrajudicial deve conter a descri\u00e7\u00e3o atualizada do im\u00f3vel, sob pena de nulidade da arremata\u00e7\u00e3o, especialmente quando o bem tiver sofrido valoriza\u00e7\u00e3o relevante decorrente de obras ou benfeitorias.<\/p>\n\n\n\n<p>REsp 2.167.979-PB, Rel. Min. Nancy Andrighi, Terceira Turma, por unanimidade, julgado em 9\/9\/2025, DJEN 17\/9\/2025.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-conteudo-base-3\">Conte\u00fado-Base<\/h3>\n\n\n\n<p>???? CPC, art. 886 I; Lei 9.514\/1997.<\/p>\n\n\n\n<p>???? A descri\u00e7\u00e3o do bem deve refletir a situa\u00e7\u00e3o f\u00e1tica e registral atual.<\/p>\n\n\n\n<p>???? A falta de atualiza\u00e7\u00e3o pode causar pre\u00e7o vil e enriquecimento sem causa do arrematante.<\/p>\n\n\n\n<p>???? A nulidade protege o devedor e garante a efetividade da execu\u00e7\u00e3o.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-discussao-e-tese-3\">Discuss\u00e3o e Tese<\/h3>\n\n\n\n<p>???? O STJ definiu que o edital de leil\u00e3o deve conter a descri\u00e7\u00e3o atualizada do bem, considerando as modifica\u00e7\u00f5es ocorridas desde a constitui\u00e7\u00e3o da garantia fiduci\u00e1ria.<\/p>\n\n\n\n<p>\u2696\ufe0f O Tribunal concluiu que a omiss\u00e3o viola o princ\u00edpio da menor onerosidade ao devedor e acarreta nulidade da arremata\u00e7\u00e3o.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-como-sera-cobrado-em-prova-3\">Como ser\u00e1 Cobrado em Prova<\/h3>\n\n\n\n<p>???? A aus\u00eancia de descri\u00e7\u00e3o atualizada do im\u00f3vel no edital enseja nulidade da arremata\u00e7\u00e3o.<\/p>\n\n\n\n<p>\u2705 Correto. Esse foi o entendimento aplicado.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-versao-esquematizada-3\">Vers\u00e3o Esquematizada<\/h3>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td>???? Leil\u00e3o extrajudicial \u2013 descri\u00e7\u00e3o do im\u00f3vel<\/td><\/tr><tr><td>???? CPC, art. 886 I ???? Atualiza\u00e7\u00e3o obrigat\u00f3ria ???? Pre\u00e7o vil \u2192 nulidade da arremata\u00e7\u00e3o<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-inteiro-teor-3\">Inteiro Teor<\/h3>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; A controv\u00e9rsia consiste em decidir se a descri\u00e7\u00e3o do im\u00f3vel constante no edital de leil\u00e3o extrajudicial \u00e9 independente da descri\u00e7\u00e3o no contrato que constituiu a propriedade fiduci\u00e1ria e qual a consequ\u00eancia jur\u00eddica da mudan\u00e7a de descri\u00e7\u00e3o do im\u00f3vel.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Nos termos do art. 886, I do C\u00f3digo de Processo Civil, &#8220;o leil\u00e3o ser\u00e1 precedido de publica\u00e7\u00e3o de edital, que conter\u00e1: [&#8230;] a descri\u00e7\u00e3o do bem penhorado, com suas caracter\u00edsticas, e, tratando-se de im\u00f3vel, sua situa\u00e7\u00e3o e suas divisas, com remiss\u00e3o \u00e0 matr\u00edcula e aos registros&#8221;.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Diante disso, a descri\u00e7\u00e3o do inciso I do art. 886 ocorrer\u00e1 no edital de leil\u00e3o extrajudicial em conformidade com a avalia\u00e7\u00e3o atualizada do bem. Isso deve acontecer em raz\u00e3o de o artigo determinar a descri\u00e7\u00e3o do im\u00f3vel para que se possa alcan\u00e7ar a finalidade do leil\u00e3o, qual seja, atribuir liquidez ao bem dado em garantia e assim satisfazer a d\u00edvida.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Portanto, o contrato de m\u00fatuo, o registro do contrato para constitui\u00e7\u00e3o da propriedade fiduci\u00e1ria, o registro da penhora e o edital de leil\u00e3o s\u00e3o atos independentes realizados em suas pr\u00f3prias circunst\u00e2ncias, e cada um dever\u00e1 conter a descri\u00e7\u00e3o atualizada do im\u00f3vel, conforme a realidade \u00e0 \u00e9poca de sua formaliza\u00e7\u00e3o, devendo-se, a cada ato registral, proceder \u00e0 atualiza\u00e7\u00e3o do livro de registros com a atual descri\u00e7\u00e3o do im\u00f3vel.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Na hip\u00f3tese em tela \u00e9 percept\u00edvel o preju\u00edzo, na medida em que o im\u00f3vel do devedor foi arrematado na import\u00e2ncia de 23% do valor avaliado, em fun\u00e7\u00e3o do erro na descri\u00e7\u00e3o do im\u00f3vel no edital, o qual n\u00e3o apresentava a completa dimens\u00e3o do im\u00f3vel, tendo em vista que estava sendo descrito apenas como um terreno.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Nesse sentido, o erro na descri\u00e7\u00e3o do im\u00f3vel faz com que ele seja vendido por pre\u00e7o vil, considerando a dimens\u00e3o real, sendo, portanto, inv\u00e1lida a aliena\u00e7\u00e3o judicial.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Com efeito, caso ocorra uma valoriza\u00e7\u00e3o expressiva do im\u00f3vel em fun\u00e7\u00e3o de uma obra ou benfeitoria significativa, \u00e9 necess\u00e1rio que a descri\u00e7\u00e3o do bem no edital acompanhe a situa\u00e7\u00e3o f\u00e1tica atual, em prol da efetividade da execu\u00e7\u00e3o e da menor onerosidade ao devedor. Pois, de outro modo, proceder com leil\u00e3o constando uma descri\u00e7\u00e3o incorreta do bem ou uma avalia\u00e7\u00e3o desatualizada, poder\u00e1 implicar no desinteresse dos poss\u00edveis arrematantes ou no enriquecimento sem causa do arrematante e em excessiva onerosidade para o devedor.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Destarte, <strong>o edital do leil\u00e3o deve conter avalia\u00e7\u00e3o adequada e descri\u00e7\u00e3o atualizada do im\u00f3vel, para assim auferir o maior valor poss\u00edvel no leil\u00e3o<\/strong> e, dessa forma, satisfazer o cr\u00e9dito, bem como proteger o patrim\u00f4nio do executado, de modo que este n\u00e3o seja onerado excessivamente. Portanto, na hip\u00f3tese de ser arrematado o im\u00f3vel a pre\u00e7o vil, deve ser declarada a nulidade da arremata\u00e7\u00e3o nas execu\u00e7\u00f5es extrajudiciais de im\u00f3veis alienados fiduciariamente.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-6-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-impugnacao-ao-valor-da-causa-em-contrarrazoes-a-apelacao\">6.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Impugna\u00e7\u00e3o ao valor da causa em contrarraz\u00f5es \u00e0 apela\u00e7\u00e3o<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-destaque-4\">Destaque<\/h3>\n\n\n\n<p>A impugna\u00e7\u00e3o ao valor da causa pode ser apresentada em contrarraz\u00f5es \u00e0 apela\u00e7\u00e3o quando a parte n\u00e3o teve oportunidade de faz\u00ea-lo em primeira inst\u00e2ncia, n\u00e3o havendo preclus\u00e3o.<\/p>\n\n\n\n<p>REsp 2.113.605-CE, Rel. Min. Moura Ribeiro, Terceira Turma, por unanimidade, julgado em 16\/9\/2025, DJEN 22\/9\/2025<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-conteudo-base-4\">Conte\u00fado-Base<\/h3>\n\n\n\n<p>???? CPC, arts. 292 \u00a73\u00ba e 293.<\/p>\n\n\n\n<p>???? O valor da causa \u00e9 mat\u00e9ria de ordem p\u00fablica e pode ser revisto de of\u00edcio.<\/p>\n\n\n\n<p>???? A aus\u00eancia de oportunidade anterior impede a preclus\u00e3o.<\/p>\n\n\n\n<p>???? A impugna\u00e7\u00e3o pode ocorrer em contrarraz\u00f5es, dispensando recurso adesivo.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-discussao-e-tese-4\">Discuss\u00e3o e Tese<\/h3>\n\n\n\n<p>???? O STJ reafirmou que a parte s\u00f3 est\u00e1 sujeita \u00e0 preclus\u00e3o se tiver tido oportunidade anterior de impugnar o valor da causa.<\/p>\n\n\n\n<p>\u2696\ufe0f O Tribunal reconheceu a possibilidade de impugna\u00e7\u00e3o em sede recursal, quando o r\u00e9u foi chamado ao processo apenas ap\u00f3s senten\u00e7a.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-como-sera-cobrado-em-prova-4\">Como ser\u00e1 Cobrado em Prova<\/h3>\n\n\n\n<p>???? A impugna\u00e7\u00e3o ao valor da causa deve ser feita em contesta\u00e7\u00e3o, sob pena de preclus\u00e3o.<\/p>\n\n\n\n<p>\u274c Errado. \u00c9 poss\u00edvel a impugna\u00e7\u00e3o posteriormente, inclusive em contrarraz\u00f5es, quando n\u00e3o houve oportunidade anterior.<\/p>\n\n\n\n<p>???? O valor da causa pode ser questionado em qualquer grau de jurisdi\u00e7\u00e3o se a parte n\u00e3o teve chance de faz\u00ea-lo antes.<\/p>\n\n\n\n<p>\u2705 Correto. Esse foi o entendimento aplicado no REsp 2.113.605-CE.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-versao-esquematizada-4\">Vers\u00e3o Esquematizada<\/h3>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td>???? Impugna\u00e7\u00e3o ao valor da causa<\/td><\/tr><tr><td>???? CPC, arts. 292 \u00a73\u00ba e 293 ???? Valor da causa \u2192 mat\u00e9ria de ordem p\u00fablica ???? Impugna\u00e7\u00e3o poss\u00edvel em contrarraz\u00f5es<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-inteiro-teor-4\">Inteiro Teor<\/h3>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; A controv\u00e9rsia reside em saber se houve a preclus\u00e3o ao direito de impugnar o valor atribu\u00eddo \u00e0 causa, na situa\u00e7\u00e3o em que a pretens\u00e3o autoral de declara\u00e7\u00e3o de nulidade de testamento p\u00fablico foi extinta, com resolu\u00e7\u00e3o do m\u00e9rito, em virtude de decad\u00eancia e a parte contr\u00e1ria somente foi intimada para figurar no feito em grau recursal (contrarraz\u00f5es da apela\u00e7\u00e3o), ocasi\u00e3o em que se insurgiu contra o valor da causa e se a parte demandada estaria obrigada a interpor recurso de apela\u00e7\u00e3o adesivo para tal mister.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Pela leitura do art. 292, \u00a7 3\u00ba c\/c o art. 293 do CPC, ocorre a preclus\u00e3o quando juiz, embora possa alterar ou corrigir de of\u00edcio do valor da causa, n\u00e3o o faz durante o curso do processo, e o r\u00e9u n\u00e3o impugna tal quest\u00e3o em preliminar de contesta\u00e7\u00e3o, o que n\u00e3o \u00e9 a hip\u00f3tese.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Ora, se nos termos da jurisprud\u00eancia, se mostra preclusa a discuss\u00e3o sobre tema que n\u00e3o foi impugnado no primeiro momento em que a parte podia sobre ele falar nos autos e configura-se a preclus\u00e3o quando a parte n\u00e3o providencia aquilo que lhe \u00e9 devido na primeira oportunidade de manifesta\u00e7\u00e3o nos autos, o inverso tamb\u00e9m \u00e9 verdadeiro.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; No mais, na linha da jurisprud\u00eancia do STJ, o valor da causa \u00e9 mat\u00e9ria de ordem p\u00fablica, sendo poss\u00edvel seu exame at\u00e9 de of\u00edcio, n\u00e3o podendo ser reconhecida a preclus\u00e3o quando a parte n\u00e3o teve a oportunidade de impugn\u00e1-la em primeiro grau de jurisdi\u00e7\u00e3o. Assim, \u00e9 vi\u00e1vel que o incidente seja manejado em contrarraz\u00f5es a apela\u00e7\u00e3o.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Diante desse contexto, em que chamada aos autos somente por ocasi\u00e3o da interposi\u00e7\u00e3o de recurso de apela\u00e7\u00e3o, nenhuma outra forma de impugna\u00e7\u00e3o ao valor da causa seria poss\u00edvel, sen\u00e3o por meio das contrarraz\u00f5es ao recurso de apela\u00e7\u00e3o, tal como realizado. Poiso recurso adesivo previsto no art. 997 e par\u00e1grafos do CPC pressup\u00f5e, al\u00e9m da exist\u00eancia de sucumb\u00eancia rec\u00edproca, uma conforma\u00e7\u00e3o inicial da parte, no caso, a recorrente, com a senten\u00e7a, ainda que t\u00e1cita, circunst\u00e2ncias que n\u00e3o se mostraram presentes na hip\u00f3tese.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-7-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-operacao-barter-e-exclusao-do-credito-da-recuperacao-judicial\">7.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Opera\u00e7\u00e3o Barter e exclus\u00e3o do cr\u00e9dito da recupera\u00e7\u00e3o judicial<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-destaque-5\">Destaque<\/h3>\n\n\n\n<p>O cr\u00e9dito decorrente de c\u00e9dula de produto rural representativa de opera\u00e7\u00e3o Barter n\u00e3o se submete aos efeitos da recupera\u00e7\u00e3o judicial, mesmo quando convertida a execu\u00e7\u00e3o para entrega de coisa em execu\u00e7\u00e3o por quantia certa.<\/p>\n\n\n\n<p>REsp 2.178.558-MT, Rel. Min. Ricardo Villas B\u00f4as Cueva, Terceira Turma, por unanimidade, julgado em 9\/9\/2025, DJEN 15\/9\/2025.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-conteudo-base-5\">Conte\u00fado-Base<\/h3>\n\n\n\n<p>???? Lei 8.929\/1995; Lei 14.112\/2020.<\/p>\n\n\n\n<p>???? A CPR de liquida\u00e7\u00e3o f\u00edsica representativa de opera\u00e7\u00e3o Barter \u00e9 cr\u00e9dito extraconcursal.<\/p>\n\n\n\n<p>???? A convers\u00e3o da execu\u00e7\u00e3o em quantia certa n\u00e3o altera a natureza da obriga\u00e7\u00e3o.<\/p>\n\n\n\n<p>???? A exclus\u00e3o visa preservar o equil\u00edbrio contratual e a seguran\u00e7a jur\u00eddica do agroneg\u00f3cio.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-discussao-e-tese-5\">Discuss\u00e3o e Tese<\/h3>\n\n\n\n<p>???? O STJ analisou a natureza dos cr\u00e9ditos de CPR f\u00edsica no contexto da recupera\u00e7\u00e3o judicial do produtor rural.<\/p>\n\n\n\n<p>\u2696\ufe0f O Tribunal entendeu que o cr\u00e9dito extraconcursal permanece exclu\u00eddo, mesmo ap\u00f3s convers\u00e3o da obriga\u00e7\u00e3o em dinheiro.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-como-sera-cobrado-em-prova-5\">Como ser\u00e1 Cobrado em Prova<\/h3>\n\n\n\n<p>???? A convers\u00e3o da execu\u00e7\u00e3o de CPR f\u00edsica em execu\u00e7\u00e3o por quantia certa sujeita o cr\u00e9dito \u00e0 recupera\u00e7\u00e3o judicial.<\/p>\n\n\n\n<p>\u274c Errado. O cr\u00e9dito de opera\u00e7\u00e3o Barter \u00e9 exclu\u00eddo da recupera\u00e7\u00e3o judicial, ainda que convertido em dinheiro.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-versao-esquematizada-5\">Vers\u00e3o Esquematizada<\/h3>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td>???? Recupera\u00e7\u00e3o judicial \u2013 opera\u00e7\u00e3o Barter<\/td><\/tr><tr><td>???? Lei 14.112\/2020 ???? CPR f\u00edsica = cr\u00e9dito extraconcursal ???? Convers\u00e3o \u2192 n\u00e3o altera natureza<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-inteiro-teor-5\">Inteiro Teor<\/h3>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; A controv\u00e9rsia cinge-se em definir se o pedido de convers\u00e3o da execu\u00e7\u00e3o aparelhada com c\u00e9dula de cr\u00e9dito rural para execu\u00e7\u00e3o por quantia certa implica a ren\u00fancia da garantia (penhor agr\u00edcola), acarretando a submiss\u00e3o do cr\u00e9dito aos efeitos da recupera\u00e7\u00e3o judicial.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; <em>A opera\u00e7\u00e3o Barter \u00e9 o neg\u00f3cio jur\u00eddico em que o credor fornece insumos para viabilizar a atividade agr\u00edcola e recebe como pagamento o produto agr\u00edcola<\/em>. A c\u00e9dula de produto rural (CPR) \u00e9 o instrumento representativo desse neg\u00f3cio. Trata-se de um t\u00edtulo de cr\u00e9dito \u00e0 ordem, l\u00edquido e certo, representativo de promessa de entrega futura de produtos rurais institu\u00edda pela Lei n. 8.929\/1965, cuja emiss\u00e3o \u00e9 exclusiva dos produtores rurais, suas associa\u00e7\u00f5es e cooperativas. Assim, tanto nas CPRs de liquida\u00e7\u00e3o f\u00edsica como nas representativas de opera\u00e7\u00e3o Barter o pagamento \u00e9 feito com produtos agr\u00edcolas.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Por seu turno, a Lei n. 14.112\/2020 buscou regulamentar a recupera\u00e7\u00e3o judicial do produtor rural. Nesse contexto, o legislador expressamente excluiu o cr\u00e9dito representado na C\u00e9dula de Produto Rural F\u00edsica e as garantias a ela vinculadas, com antecipa\u00e7\u00e3o total ou parcial do pre\u00e7o, assim como as que resultem de permuta (opera\u00e7\u00e3o Barter) dos efeitos da recupera\u00e7\u00e3o judicial do produtor rural. Nessas hip\u00f3teses, requerida a recupera\u00e7\u00e3o judicial pelo devedor, o credor estar\u00e1 exclu\u00eddo da recupera\u00e7\u00e3o judicial, salvo se o cumprimento do contrato estiver obstado por motivo de caso fortuito ou for\u00e7a maior.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; No caso das CPRs representativas de permuta (Barter), o que se verifica \u00e9 que o <em>inadimplemento significa no mais das vezes a n\u00e3o exist\u00eancia do produto que deveria ser entregue ao credor<\/em>. Trata-se do perecimento n\u00e3o somente da garantia (no caso de penhor dos gr\u00e3os), como tamb\u00e9m do pr\u00f3prio objeto do contrato. Em outras palavras, <em>a obriga\u00e7\u00e3o de entrega dos gr\u00e3os da safra contratada n\u00e3o tem mais como ser cumprida<\/em>, n\u00e3o tendo o credor outra op\u00e7\u00e3o sen\u00e3o o recebimento do valor em dinheiro.<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td>&nbsp;&nbsp;&nbsp;&nbsp; Nessa circunst\u00e2ncia, a alega\u00e7\u00e3o no sentido de que o pedido de convers\u00e3o da execu\u00e7\u00e3o implicaria a ren\u00fancia \u00e0 garantia e, em raz\u00e3o disso, a submiss\u00e3o do cr\u00e9dito aos efeitos da recupera\u00e7\u00e3o judicial, seria deixar ao alvedrio exclusivo do devedor a submiss\u00e3o ou n\u00e3o do cr\u00e9dito aos efeitos da recupera\u00e7\u00e3o judicial, bastando, para tanto, dar outra destina\u00e7\u00e3o aos gr\u00e3os, impossibilitando o adimplemento.<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Assim, o pedido de convers\u00e3o da a\u00e7\u00e3o executiva em execu\u00e7\u00e3o por quantia certa em raz\u00e3o de o devedor n\u00e3o ter entregue os gr\u00e3os n\u00e3o parece ser suficiente para transmudar a natureza do cr\u00e9dito, tratado pelo legislador como extraconcursal.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Nesse sentido, <strong>o cr\u00e9dito decorrente de CPR representativa de opera\u00e7\u00e3o Barter n\u00e3o se submete aos efeitos da recupera\u00e7\u00e3o judicial mesmo quando h\u00e1 convers\u00e3o da execu\u00e7\u00e3o para entrega de coisa incerta em execu\u00e7\u00e3o por quantia certa<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-8-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-principio-da-saisine-e-supressio-nas-relacoes-de-administracao-de-imoveis\">8.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Princ\u00edpio da saisine e supressio nas rela\u00e7\u00f5es de administra\u00e7\u00e3o de im\u00f3veis<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-destaque-6\">Destaque<\/h3>\n\n\n\n<p>Os herdeiros n\u00e3o podem exigir a restitui\u00e7\u00e3o retroativa dos frutos obtidos pelo ascendente que exerceu, por longo per\u00edodo e com aquiesc\u00eancia dos propriet\u00e1rios, a administra\u00e7\u00e3o dos im\u00f3veis, pois a situa\u00e7\u00e3o consolidada \u00e9 transmitida integralmente pela sucess\u00e3o, em observ\u00e2ncia ao princ\u00edpio da saisine e \u00e0 boa-f\u00e9 objetiva.<\/p>\n\n\n\n<p>REsp 2.214.957-PR, Rel. Min. Antonio Carlos Ferreira, Quarta Turma, por unanimidade, julgado em 7\/10\/2025, DJEN 15\/10\/2025<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-conteudo-base-6\">Conte\u00fado-Base<\/h3>\n\n\n\n<p>???? CC, arts. 1.784, 421, 422 e 884.<\/p>\n\n\n\n<p>???? O princ\u00edpio da saisine assegura a imediata transmiss\u00e3o do patrim\u00f4nio e da situa\u00e7\u00e3o jur\u00eddica do falecido aos herdeiros.<\/p>\n\n\n\n<p>???? A supressio impede o exerc\u00edcio tardio de direito que, pela in\u00e9rcia qualificada do titular, gerou expectativa leg\u00edtima em terceiros.<\/p>\n\n\n\n<p>???? A surrectio protege o surgimento dessa expectativa leg\u00edtima e refor\u00e7a a estabilidade das rela\u00e7\u00f5es jur\u00eddicas.<\/p>\n\n\n\n<p>???? As limita\u00e7\u00f5es jur\u00eddicas criadas pela conduta do de cujus integram o patrim\u00f4nio transmitido.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-discussao-e-tese-6\">Discuss\u00e3o e Tese<\/h3>\n\n\n\n<p>???? O STJ decidiu que, se o ascendente administrava im\u00f3veis e percebia frutos com a anu\u00eancia dos copropriet\u00e1rios por longo tempo, a boa-f\u00e9 consolidada se transmite aos herdeiros.<\/p>\n\n\n\n<p>\u2696\ufe0f O Tribunal considerou que a situa\u00e7\u00e3o f\u00e1tica consolidada pelo comportamento do falecido integra o acervo sucess\u00f3rio, impedindo a pretens\u00e3o retroativa de restitui\u00e7\u00e3o de alugu\u00e9is.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-como-sera-cobrado-em-prova-6\">Como ser\u00e1 Cobrado em Prova<\/h3>\n\n\n\n<p>???? A administra\u00e7\u00e3o de im\u00f3veis com aquiesc\u00eancia dos propriet\u00e1rios e por longo per\u00edodo gera situa\u00e7\u00e3o jur\u00eddica protegida pela boa-f\u00e9 objetiva.<\/p>\n\n\n\n<p>\u2705 Correto. Os herdeiros n\u00e3o podem exigir retroativamente os frutos percebidos pelo ascendente que administrava im\u00f3veis com anu\u00eancia dos copropriet\u00e1rios por longo tempo, aplicando-se os princ\u00edpios da supressio e surrectio + saisine.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-versao-esquematizada-6\">Vers\u00e3o Esquematizada<\/h3>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td>???? Saisine \u2013 supressio e surrectio<\/td><\/tr><tr><td>???? CC, arts. 1.784 e 422 ???? Boa-f\u00e9 objetiva e estabilidade jur\u00eddica ???? Situa\u00e7\u00e3o consolidada \u2192 transmite-se aos herdeiros<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-inteiro-teor-6\">Inteiro Teor<\/h3>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; A controv\u00e9rsia consiste em definir se os herdeiros podem exigir a restitui\u00e7\u00e3o retroativa dos frutos percebidos pelo ascendente que exerceu ininterruptamente, por longo per\u00edodo, a administra\u00e7\u00e3o dos im\u00f3veis com pleno conhecimento e aquiesc\u00eancia dos propriet\u00e1rios.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Pelo princ\u00edpio da saisine, os herdeiros sucedem o de cujus na exata situa\u00e7\u00e3o jur\u00eddica em que este se encontrava no momento da abertura da sucess\u00e3o, incluindo as rela\u00e7\u00f5es f\u00e1ticas consolidadas, as expectativas leg\u00edtimas criadas por seu comportamento e, sobretudo, as limita\u00e7\u00f5es ao exerc\u00edcio de direitos decorrentes de sua pr\u00f3pria conduta.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Essa perspectiva ampliada do princ\u00edpio da saisine revela que a transmiss\u00e3o heredit\u00e1ria n\u00e3o se opera em abstrato, mas considera a realidade concreta das rela\u00e7\u00f5es estabelecidas pelo de cujus. Quando algu\u00e9m, por sua conduta reiterada e duradoura, cria limita\u00e7\u00f5es ao exerc\u00edcio pleno de seus direitos &#8211; seja pela aquiesc\u00eancia prolongada, pela cria\u00e7\u00e3o de expectativas leg\u00edtimas em terceiros, ou mesmo pela pr\u00f3pria in\u00e9rcia qualificada -, essas limita\u00e7\u00f5es integram o patrim\u00f4nio jur\u00eddico transmiss\u00edvel, vinculando os sucessores.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; J\u00e1 a supressio opera quando o titular de um direito, por sua in\u00e9rcia prolongada e qualificada, cria na contraparte leg\u00edtima expectativa de que tal direito n\u00e3o ser\u00e1 exercido, tornando inadmiss\u00edvel seu exerc\u00edcio posterior.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Paralelamente \u00e0 supress\u00e3o do direito, opera-se o instituto da surrectio, que representa o aspecto positivo do fen\u00f4meno: enquanto a supressio elimina a possibilidade de exerc\u00edcio de direito pela in\u00e9rcia de seu titular, a surrectio representa o nascimento de uma expectativa leg\u00edtima protegida juridicamente, criada n\u00e3o por ato volitivo expresso, mas pela converg\u00eancia entre a conduta reiterada de quem exerce determinada situa\u00e7\u00e3o jur\u00eddica e a aquiesc\u00eancia duradoura daqueles que poderiam opor-se a tal exerc\u00edcio.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; A conjuga\u00e7\u00e3o desses institutos com o princ\u00edpio da saisine oferece solu\u00e7\u00e3o jur\u00eddica adequada: quando o de cujus, por sua conduta omissiva prolongada, opera a supress\u00e3o de determinado direito e, paralelamente, consolida expectativa leg\u00edtima em favor de terceiro, essa situa\u00e7\u00e3o jur\u00eddica complexa transmite-se integralmente aos herdeiros. N\u00e3o podem estes invocar direitos que o pr\u00f3prio antecessor, por sua conduta reiterada, havia tornado juridicamente inadmiss\u00edvel exercer.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; No caso, a administra\u00e7\u00e3o dos im\u00f3veis, exercida de forma transparente e ininterrupta por mais de 20 anos, com percep\u00e7\u00e3o integral dos alugu\u00e9is, sob pleno conhecimento e aquiesc\u00eancia dos propriet\u00e1rios, consolida situa\u00e7\u00e3o jur\u00eddica protegida pela boa-f\u00e9 objetiva e pela veda\u00e7\u00e3o ao comportamento contradit\u00f3rio.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Apenas com a notifica\u00e7\u00e3o extrajudicial \u00e9 que se comprovou o t\u00e9rmino da situa\u00e7\u00e3o jur\u00eddica consolidada, momento em que findou a expectativa de direito gerada pela situa\u00e7\u00e3o f\u00e1tica duradoura e tornou-se poss\u00edvel aos herdeiros exercerem plenamente a administra\u00e7\u00e3o dos im\u00f3veis e receberem os alugu\u00e9is deles provenientes.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; At\u00e9 esse marco temporal, a situa\u00e7\u00e3o permaneceu legitimamente consolidada, n\u00e3o sendo devida restitui\u00e7\u00e3o alguma pelos frutos obtidos durante o per\u00edodo de aquiesc\u00eancia.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-9-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-contrato-de-promessa-de-compra-e-venda-e-taxa-de-fruicao-em-lote-nao-edificado\">9.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Contrato de promessa de compra e venda e taxa de frui\u00e7\u00e3o em lote n\u00e3o edificado<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-destaque-7\">Destaque<\/h3>\n\n\n\n<p>Ap\u00f3s a entrada em vigor da Lei 13.786\/2018, \u00e9 leg\u00edtima a cobran\u00e7a da taxa de frui\u00e7\u00e3o prevista contratualmente, mesmo em contratos de compra e venda de lote n\u00e3o edificado, desde que respeitados os limites legais e havendo pr\u00e9via informa\u00e7\u00e3o ao consumidor.<\/p>\n\n\n\n<p>REsp 2.104.086-SP, Rel. Min. Maria Isabel Gallotti, Quarta Turma, por maioria, julgado em 7\/10\/2025, DJEN 15\/10\/2025.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-conteudo-base-7\">Conte\u00fado-Base<\/h3>\n\n\n\n<p>???? Lei 13.786\/2018; Lei 6.766\/1979, arts. 26-A e 32-A; S\u00famula 543\/STJ.<\/p>\n\n\n\n<p>???? O distrato permite reten\u00e7\u00e3o de valores e cobran\u00e7a de taxa de frui\u00e7\u00e3o quando prevista e limitada a 0,75% do valor do contrato.<\/p>\n\n\n\n<p>???? A lei aplica-se a contratos posteriores \u00e0 sua vig\u00eancia.<\/p>\n\n\n\n<p>???? A taxa de frui\u00e7\u00e3o incide da posse do im\u00f3vel at\u00e9 sua restitui\u00e7\u00e3o ao loteador.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-discussao-e-tese-7\">Discuss\u00e3o e Tese<\/h3>\n\n\n\n<p>???? O STJ reafirmou a possibilidade de dedu\u00e7\u00e3o da taxa de frui\u00e7\u00e3o em contratos firmados ap\u00f3s a Lei 13.786\/2018.<\/p>\n\n\n\n<p>\u2696\ufe0f A Turma entendeu que o tipo de lote (edificado ou n\u00e3o) n\u00e3o altera a incid\u00eancia da taxa, desde que observados os limites legais e a informa\u00e7\u00e3o pr\u00e9via.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-como-sera-cobrado-em-prova-7\">Como ser\u00e1 Cobrado em Prova<\/h3>\n\n\n\n<p>???? \u00c9 leg\u00edtima a dedu\u00e7\u00e3o da taxa de frui\u00e7\u00e3o nos distratos firmados ap\u00f3s a Lei 13.786\/2018, desde que respeitados os limites legais e contratualmente previstos.<\/p>\n\n\n\n<p>\u2705 Correto. Esse foi o entendimento aplicado no REsp 2.104.086-SP.<\/p>\n\n\n\n<p>???? A taxa de frui\u00e7\u00e3o s\u00f3 \u00e9 cab\u00edvel em contratos de im\u00f3veis edificados.<\/p>\n\n\n\n<p>\u274c Errado. A Lei 13.786\/2018 autoriza sua cobran\u00e7a tamb\u00e9m em lotes n\u00e3o edificados.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-versao-esquematizada-7\">Vers\u00e3o Esquematizada<\/h3>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td>???? Taxa de frui\u00e7\u00e3o \u2013 lote n\u00e3o edificado<\/td><\/tr><tr><td>???? Lei 13.786\/2018; Lei 6.766\/1979 ???? Limite: 0,75% do valor do contrato ???? Contratos posteriores \u00e0 lei \u2192 cobran\u00e7a v\u00e1lida<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-inteiro-teor-7\">Inteiro Teor<\/h3>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Cinge-se a controv\u00e9rsia a saber se, em se tratando de rescis\u00e3o de contrato de compra e venda de lote n\u00e3o edificado, celebrado ap\u00f3s a entrada em vigor da Lei n. 13.786, de 27 de dezembro de 2018, por iniciativa do adquirente, seria poss\u00edvel ao promitente vendedor, devido ao distrato, reter valores pagos pelo promiss\u00e1rio comprador, a saber o percentual de 10% (dez por cento) sobre o valor do contrato, e a denominada taxa de ocupa\u00e7\u00e3o ou frui\u00e7\u00e3o.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Quanto \u00e0 quest\u00e3o relativa \u00e0 reten\u00e7\u00e3o de valores pagos pelo adquirente do im\u00f3vel que desistiu do neg\u00f3cio, registre-se que, antes mesmo do advento da Lei n. 13.786\/2018, a jurisprud\u00eancia do Superior Tribunal de Justi\u00e7a j\u00e1 se orientava no sentido de que, nesses casos, o promitente vendedor poderia reter percentual de valores por ele pagos, conforme estabelecido na S\u00famula 543 do STJ.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Ademais, estabeleceu-se, no \u00e2mbito da Segunda Se\u00e7\u00e3o do STJ, que, em caso de resolu\u00e7\u00e3o por culpa exclusiva do consumidor, se n\u00e3o houvesse nenhuma previs\u00e3o contratual em sentido diverso ou circunst\u00e2ncia excepcional, o percentual de 25% dos valores pagos seria valor suficiente para compensar os preju\u00edzos do incorporador.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Com a edi\u00e7\u00e3o da Lei n. 13.786\/2018, passou a ser previsto expressamente o direito de distrato, por meio da inclus\u00e3o, na Lei n. 6.766\/1979, do art. 26-A, dispondo que os contratos de compra e venda, cess\u00e3o ou promessa de cess\u00e3o de loteamento devem ser iniciados por quadro-resumo, que dever\u00e1 conter, entre outros requisitos, &#8220;as consequ\u00eancias do desfazimento do contrato, seja mediante distrato, seja por meio de resolu\u00e7\u00e3o contratual motivada por inadimplemento de obriga\u00e7\u00e3o do adquirente ou do loteador, com destaque negritado para as penalidades aplic\u00e1veis e para os prazos para devolu\u00e7\u00e3o dos valores ao adquirente&#8221; (inciso V). Essas consequ\u00eancias s\u00e3o delimitadas no art. 32-A tamb\u00e9m inserido na referida lei.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; No caso, tendo o Tribunal de origem esclarecido que (i) a reten\u00e7\u00e3o de valores foi feita pela incorporadora dentro dos par\u00e2metros previstos pela Lei n. 13.786\/2018 e (ii) que houve informa\u00e7\u00e3o pr\u00e9via ao comprador a respeito das consequ\u00eancias da desist\u00eancia do neg\u00f3cio, n\u00e3o h\u00e1 como afastar suas disposi\u00e7\u00f5es, especialmente quando n\u00e3o constatada inconstitucionalidade na lei, nem viola\u00e7\u00e3o ao C\u00f3digo de Defesa do Consumidor.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Dessa forma, tendo sido a cl\u00e1usula penal estabelecida em 10% do valor atualizado do contrato, dentro dos limites estabelecidos no art. 32-A da Lei n. 6.766\/1979, correto o entendimento pela legalidade da respectiva reten\u00e7\u00e3o.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Quanto \u00e0 taxa de frui\u00e7\u00e3o, em se tratando de rescis\u00e3o de contrato de compra e venda de lote n\u00e3o edificado, at\u00e9 28\/12\/2018, quando entrou em vigor a Lei n. 13.786\/2018, em regra n\u00e3o era devida a devolu\u00e7\u00e3o, pelo promiss\u00e1rio comprador ao promitente vendedor, da denominada taxa de ocupa\u00e7\u00e3o ou frui\u00e7\u00e3o, haja vista que a jurisprud\u00eancia do Superior Tribunal de Justi\u00e7a consolidou-se no sentido de afastar a sua exig\u00eancia presumida e n\u00e3o havia nenhuma lei regulando a quest\u00e3o.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Contudo, a partir da Lei n. 13.786\/2018 pode haver a dedu\u00e7\u00e3o da taxa de frui\u00e7\u00e3o dos valores a serem restitu\u00eddos ao comprador, em caso de rescis\u00e3o de promessa de compra e venda de lote n\u00e3o edificado, desde que respeitados todos os termos da legisla\u00e7\u00e3o e se houver expressa disposi\u00e7\u00e3o contratual nesse sentido.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Assim, havendo, atualmente, expressa previs\u00e3o legal, o adquirente que desiste da compra e venda de lote ap\u00f3s ser-lhe transmitida a posse, estando apto a dele usufruir, inclusive para constru\u00e7\u00e3o, n\u00e3o mais pode se escusar do pagamento da taxa de frui\u00e7\u00e3o, ao argumento de que n\u00e3o houve ocupa\u00e7\u00e3o efetiva do bem.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Como a lei n\u00e3o tem palavras in\u00fateis, a fixa\u00e7\u00e3o dos termos inicial e final para a incid\u00eancia da taxa de frui\u00e7\u00e3o (a partir da data da transmiss\u00e3o da posse do im\u00f3vel ao adquirente at\u00e9 sua restitui\u00e7\u00e3o ao loteador) tem a consequ\u00eancia l\u00f3gica de definir que a referida taxa n\u00e3o est\u00e1 mais condicionada \u00e0 exist\u00eancia de lote edificado ou n\u00e3o edificado, mas exclusivamente \u00e0 disponibilidade do lote para o comprador.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Com a disponibiliza\u00e7\u00e3o do lote, no momento da transmiss\u00e3o da posse, cumpre o loteador a sua obriga\u00e7\u00e3o, passando o promitente comprador a ter a disponibilidade plena do im\u00f3vel para o uso que melhor lhe aprouver, inclusive decidir se e quando ir\u00e1 constru\u00ed-lo, dar outro tipo de uso ao lote, como lazer, ou revend\u00ea-lo. O uso &#8211; ou n\u00e3o uso do im\u00f3vel &#8211; n\u00e3o deve afetar a esfera jur\u00eddica do loteador, que cumpriu sua obriga\u00e7\u00e3o e perdeu a disponibilidade sobre o bem.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Nesse contexto, o tipo de empreendimento (lote n\u00e3o edificado, lote edificado ou com destina\u00e7\u00e3o econ\u00f4mica espec\u00edfica) dever\u00e1 ser sopesado apenas na fixa\u00e7\u00e3o do valor da taxa de frui\u00e7\u00e3o, &#8220;at\u00e9 o equivalente a 0,75% (setenta e cinco cent\u00e9simos por cento sobre o valor atualizado do contrato)&#8221;, mas n\u00e3o afasta a possibilidade de sua reten\u00e7\u00e3o, dos valores a serem restitu\u00eddos ao comprador desistente, nos termos da lei.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-10-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-seguro-de-vida-em-grupo-e-interesse-de-agir\">10.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Seguro de vida em grupo e interesse de agir<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-destaque-8\">Destaque<\/h3>\n\n\n\n<p>O requerimento administrativo pr\u00e9vio \u00e9 requisito necess\u00e1rio para o reconhecimento do interesse de agir na a\u00e7\u00e3o de cobran\u00e7a de indeniza\u00e7\u00e3o securit\u00e1ria, salvo quando a seguradora j\u00e1 tiver manifestado resist\u00eancia inequ\u00edvoca ao pedido.<\/p>\n\n\n\n<p>AgInt no REsp 2.091.602-MS, Rel. Min. Antonio Carlos Ferreira, Quarta Turma, por unanimidade, julgado em 15\/9\/2025, DJEN 19\/9\/2025.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-conteudo-base-8\">Conte\u00fado-Base<\/h3>\n\n\n\n<p>???? CC, art. 771; CPC, art. 17.<\/p>\n\n\n\n<p>???? O aviso de sinistro equivale ao requerimento administrativo para pagamento da indeniza\u00e7\u00e3o.<\/p>\n\n\n\n<p>???? Sem comunica\u00e7\u00e3o formal, n\u00e3o h\u00e1 resist\u00eancia da seguradora nem les\u00e3o a direito.<\/p>\n\n\n\n<p>???? Excepcionalmente, o interesse de agir subsiste se a seguradora contesta o pedido judicial sem alegar aus\u00eancia de requerimento.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-discussao-e-tese-8\">Discuss\u00e3o e Tese<\/h3>\n\n\n\n<p>???? O STJ reafirmou que a aus\u00eancia de requerimento administrativo pr\u00e9vio impede o reconhecimento do interesse de agir na a\u00e7\u00e3o de cobran\u00e7a de seguro.<\/p>\n\n\n\n<p>\u2696\ufe0f Contudo, a exig\u00eancia pode ser mitigada quando houver resist\u00eancia expressa da seguradora ao pagamento.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-como-sera-cobrado-em-prova-8\">Como ser\u00e1 Cobrado em Prova<\/h3>\n\n\n\n<p>???? O ajuizamento de a\u00e7\u00e3o de cobran\u00e7a de seguro prescinde de pr\u00e9vio requerimento administrativo.<\/p>\n\n\n\n<p>\u274c Errado. O requerimento \u00e9 condi\u00e7\u00e3o para o interesse de agir.<\/p>\n\n\n\n<p>???? A falta de requerimento administrativo n\u00e3o impede a a\u00e7\u00e3o quando a seguradora manifesta resist\u00eancia expressa ao pagamento.<\/p>\n\n\n\n<p>\u2705 Correto. Esse foi o entendimento aplicado.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-versao-esquematizada-8\">Vers\u00e3o Esquematizada<\/h3>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td>???? Seguro de vida \u2013 interesse de agir<\/td><\/tr><tr><td>???? CC, art. 771 ???? CPC, art. 17 ???? Aviso de sinistro = requerimento ???? Resist\u00eancia inequ\u00edvoca \u2192 dispensa<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-inteiro-teor-8\">Inteiro Teor<\/h3>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; A controv\u00e9rsia consiste em analisar se o requerimento administrativo pr\u00e9vio constitui requisito para a exist\u00eancia de interesse de agir na a\u00e7\u00e3o de cobran\u00e7a de indeniza\u00e7\u00e3o securit\u00e1ria.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Quanto ao assunto, o entendimento do Superior Tribunal de Justi\u00e7a \u00e9 no sentido de que &#8220;[&#8230;] o art. 771 do CC\/2002 exige que o segurado comunique o sinistro \u00e0 seguradora, logo que o saiba, sob pena de perder o direito \u00e0 indeniza\u00e7\u00e3o. Embora a finalidade prec\u00edpua dessa norma seja evitar o agravamento das consequ\u00eancias geradas pelo sinistro, o aviso de sinistro representa a formaliza\u00e7\u00e3o do pedido de pagamento da indeniza\u00e7\u00e3o securit\u00e1ria. Antes disso, a seguradora n\u00e3o est\u00e1 obrigada a pagar, simplesmente porque n\u00e3o tem ci\u00eancia do evento. Portanto, n\u00e3o realizada a comunica\u00e7\u00e3o acerca do sinistro, n\u00e3o h\u00e1 les\u00e3o a direito ou interesse do segurado&#8221;. (REsp 2.050.513\/MT, Rel. Ministra Nancy Andrighi, Terceira Turma, julgado em 25\/4\/2023, DJe de 27\/4\/2023).<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Todavia, deve ser consignado que esta Corte de Justi\u00e7a tamb\u00e9m entende que, excepcionalmente, a depender do caso, a aus\u00eancia de requerimento administrativo pr\u00e9vio n\u00e3o impedir\u00e1 o prosseguimento do processo.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Assim, &#8220;se j\u00e1 tiver se operado a cita\u00e7\u00e3o da seguradora, eventual oposi\u00e7\u00e3o desta ao pedido de indeniza\u00e7\u00e3o deixa clara a sua resist\u00eancia frente \u00e0 pretens\u00e3o do segurado, evidenciando a presen\u00e7a do interesse de agir. Por\u00e9m, nem sempre a resposta da seguradora implicar\u00e1 impugna\u00e7\u00e3o ao pedido de pagamento. \u00c9 poss\u00edvel por exemplo, que ela invoque a aus\u00eancia de pr\u00e9via solicita\u00e7\u00e3o administrativa, hip\u00f3tese em que caber\u00e1 a extin\u00e7\u00e3o do processo sem resolu\u00e7\u00e3o do m\u00e9rito, por aus\u00eancia de interesse processual&#8221;. (REsp 2.050.513\/MT, Rel. Ministra Nancy Andrighi, Terceira Turma, julgado em 25\/4\/2023, DJe de 27\/4\/2023).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-11-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-parcelamento-de-taxas-e-custas-judiciais\">11.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Parcelamento de taxas e custas judiciais<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-destaque-9\">Destaque<\/h3>\n\n\n\n<p>\u00c9 poss\u00edvel o parcelamento das taxas e custas judiciais, pois elas se enquadram no conceito de despesas processuais abrangido pelo art. 98 \u00a76\u00ba do CPC, instrumento que concretiza o direito fundamental de acesso \u00e0 Justi\u00e7a.<\/p>\n\n\n\n<p>REsp 2.208.615-SP, Rel. Min. Antonio Carlos Ferreira, Quarta Turma, por unanimidade, julgado em 7\/10\/2025, DJEN 15\/10\/2025.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-conteudo-base-9\">Conte\u00fado-Base<\/h3>\n\n\n\n<p>???? CPC, art. 98 \u00a7\u00a71\u00ba e 6\u00ba; ADI 1378\/ES; REsp 1.893.966\/SP.<\/p>\n\n\n\n<p>???? As taxas e custas judiciais s\u00e3o esp\u00e9cies de despesas processuais.<\/p>\n\n\n\n<p>???? O parcelamento n\u00e3o implica ren\u00fancia ou redu\u00e7\u00e3o, mas mera dila\u00e7\u00e3o do pagamento.<\/p>\n\n\n\n<p>???? O juiz pode conceder o parcelamento como medida intermedi\u00e1ria entre o indeferimento da gratuidade e a isen\u00e7\u00e3o total.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-discussao-e-tese-9\">Discuss\u00e3o e Tese<\/h3>\n\n\n\n<p>???? CPC, art. 98 \u00a7\u00a71\u00ba e 6\u00ba; ADI 1378\/ES; REsp 1.893.966\/SP.<\/p>\n\n\n\n<p>???? As taxas e custas judiciais s\u00e3o esp\u00e9cies de despesas processuais.<\/p>\n\n\n\n<p>???? O parcelamento n\u00e3o implica ren\u00fancia ou redu\u00e7\u00e3o, mas mera dila\u00e7\u00e3o do pagamento.<\/p>\n\n\n\n<p>???? O juiz pode conceder o parcelamento como medida intermedi\u00e1ria entre o indeferimento da gratuidade e a isen\u00e7\u00e3o total.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-como-sera-cobrado-em-prova-9\">Como ser\u00e1 Cobrado em Prova<\/h3>\n\n\n\n<p>???? O art. 98 \u00a76\u00ba do CPC n\u00e3o se aplica \u00e0s taxas judiciais em raz\u00e3o de sua natureza tribut\u00e1ria.<\/p>\n\n\n\n<p>\u274c Errado. O STJ reconheceu que o parcelamento \u00e9 aplic\u00e1vel.<\/p>\n\n\n\n<p>???? O juiz pode autorizar o parcelamento das taxas e custas judiciais quando comprovada dificuldade financeira da parte.<\/p>\n\n\n\n<p>\u2705 Correto. Trata-se de medida intermedi\u00e1ria entre o indeferimento da gratuidade e a isen\u00e7\u00e3o total.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-versao-esquematizada-9\">Vers\u00e3o Esquematizada<\/h3>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td>???? Custas e taxas \u2013 parcelamento<\/td><\/tr><tr><td>???? CPC, art. 98 \u00a76\u00ba ???? Acesso \u00e0 Justi\u00e7a e proporcionalidade ???? Parcelamento autorizado pelo juiz<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-inteiro-teor-9\">Inteiro Teor<\/h3>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Cinge-se a controv\u00e9rsia a definir se o disposto no art. 98, \u00a7 6\u00ba, do C\u00f3digo de Processo Civil, que prev\u00ea expressamente a possibilidade de parcelamento de &#8220;despesas processuais&#8221;, abrange o parcelamento das custas judiciais e das taxas judici\u00e1rias iniciais.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; A quest\u00e3o inicial a ser dirimida, portanto, \u00e9 se a express\u00e3o &#8220;despesas processuais&#8221; empregada pelo legislador abrange tamb\u00e9m as custas judiciais e as taxas judici\u00e1rias, ou se estas, por sua natureza tribut\u00e1ria, estariam exclu\u00eddas do alcance da norma federal.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Uma interpreta\u00e7\u00e3o sistem\u00e1tica e teleol\u00f3gica do C\u00f3digo de Processo Civil conduz \u00e0 conclus\u00e3o inequ\u00edvoca de que as custas judiciais e as taxas judici\u00e1rias integram o g\u00eanero despesas processuais, para fins de aplica\u00e7\u00e3o do art. 98, \u00a7 6\u00ba.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; No entendimento consolidado da doutrina processualista, as despesas processuais abrangem a totalidade dos desembolsos necess\u00e1rios \u00e0 instaura\u00e7\u00e3o, desenvolvimento e conclus\u00e3o da rela\u00e7\u00e3o processual. Essa conceitua\u00e7\u00e3o abrangente encontra respaldo na jurisprud\u00eancia do Superior Tribunal de Justi\u00e7a, que sistematicamente reconhece as despesas processuais como categoria ampla (g\u00eanero), da qual derivam, como esp\u00e9cies, as custas judiciais, a taxa judici\u00e1ria e os emolumentos.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Cabe observar que o pr\u00f3prio CPC, ao disciplinar os benef\u00edcios da gratuidade da justi\u00e7a em seu art. 98, \u00a7 1\u00ba, incluiu expressamente &#8220;as taxas ou as custas judiciais&#8221; (inciso I) entre os itens abrangidos pelo conceito mais amplo de despesas processuais. O legislador adotou t\u00e9cnica redacional que estabelece clara sistem\u00e1tica jur\u00eddica, posicionando as custas e taxas judici\u00e1rias como esp\u00e9cie das despesas processuais.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Ademais, o parcelamento das custas judiciais e das taxas judici\u00e1rias previsto no art. 98, \u00a7 6\u00ba, do CPC representa n\u00edtida aplica\u00e7\u00e3o do princ\u00edpio da proporcionalidade na concretiza\u00e7\u00e3o do direito fundamental de acesso \u00e0 Justi\u00e7a. Trata-se de medida que se situa entre dois extremos: de um lado, a imposi\u00e7\u00e3o do pagamento integral das taxas de uma s\u00f3 vez, potencialmente impeditiva do acesso ao Judici\u00e1rio; de outro, a concess\u00e3o da gratuidade total, que dispensa o pagamento de qualquer valor.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; <em>A pr\u00f3pria ratio legis do parcelamento fundamenta-se no princ\u00edpio de que quem pode o mais pode o menos<\/em> &#8211; sendo il\u00f3gico conferir ao magistrado o poder de conceder gratuidade total (isen\u00e7\u00e3o do tributo), dispensando integralmente o recolhimento das taxas, mas negar-lhe a prerrogativa de autorizar simples parcelamento, provid\u00eancia manifestamente menos onerosa aos cofres p\u00fablicos. Tal mecanismo n\u00e3o representa nenhuma dispensa ou redu\u00e7\u00e3o do valor devido, constituindo mera dila\u00e7\u00e3o do prazo para adimplemento, com integral preserva\u00e7\u00e3o do montante e garantia de sua efetiva arrecada\u00e7\u00e3o.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Cumpre ressaltar ainda que a natureza tribut\u00e1ria das custas judiciais e das taxas judici\u00e1rias, reconhecida pelo STF no julgamento da ADI n. 1378\/ES e pelo STJ no REsp n. 1.893.966\/SP, n\u00e3o constitui \u00f3bice \u00e0 aplica\u00e7\u00e3o do art. 98, \u00a7 6\u00ba, do CPC\/2015.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; As custas judiciais e as taxas judici\u00e1rias constituem tributo diretamente vinculado \u00e0 efetiva\u00e7\u00e3o da garantia constitucional de acesso ao Judici\u00e1rio. Em virtude de sua relev\u00e2ncia para o exerc\u00edcio da cidadania, o pr\u00f3prio C\u00f3digo de Processo Civil estabeleceu mecanismos de flexibiliza\u00e7\u00e3o de seu pagamento, conferindo ao magistrado a prerrogativa de, mediante an\u00e1lise criteriosa do caso concreto, conceder isen\u00e7\u00e3o aos comprovadamente hipossuficientes ou autorizar o parcelamento dos valores devidos.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Nesse contexto, \u00e9 necess\u00e1rio reconhecer que as normas processuais que disciplinam o acesso \u00e0 Justi\u00e7a possuem aplicabilidade imediata em todo o territ\u00f3rio nacional, n\u00e3o podendo ser afastadas sob o argumento de aus\u00eancia de previs\u00e3o espec\u00edfica em legisla\u00e7\u00e3o estadual.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Desse modo, <strong>n\u00e3o sendo caso de concess\u00e3o do benef\u00edcio integral da justi\u00e7a gratuita, ao magistrado \u00e9 conferido o poder discricion\u00e1rio de determinar o fracionamento do pagamento das taxas e custas judiciais<\/strong>, estabelecendo suas condi\u00e7\u00f5es e forma de adimplemento quando comprovada a dificuldade financeira da parte requerente para a quita\u00e7\u00e3o integral e imediata dos valores devidos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-12-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-acordo-de-nao-persecucao-penal-anpp-e-continuidade-delitiva\">12.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Acordo de n\u00e3o persecu\u00e7\u00e3o penal (ANPP) e continuidade delitiva<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-destaque-10\">Destaque<\/h3>\n\n\n\n<p>A continuidade delitiva n\u00e3o impede a celebra\u00e7\u00e3o do Acordo de N\u00e3o Persecu\u00e7\u00e3o Penal (ANPP), desde que a pena m\u00ednima resultante, calculada com as fra\u00e7\u00f5es m\u00ednimas das majorantes e m\u00e1ximas das atenuantes, n\u00e3o ultrapasse quatro anos. \u00c9 vedado o uso de \u201cpena hipot\u00e9tica\u201d para afastar o exame de admissibilidade do ANPP.<\/p>\n\n\n\n<p>Processo em segredo de justi\u00e7a, Rel. Min. Joel Ilan Paciornik, Rel. p\/ ac\u00f3rd\u00e3o Min. Ribeiro Dantas, Quinta Turma, por empate, julgado em 7\/10\/2025, DJEN 17\/10\/2025.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-conteudo-base-10\">Conte\u00fado-Base<\/h3>\n\n\n\n<p>???? CPP, art. 28-A \u00a71\u00ba; Lei 13.964\/2019; Lei 9.099\/1995, art. 89; S\u00famulas 243 e 438\/STJ, 723\/STF.<\/p>\n\n\n\n<p>???? O requisito objetivo do ANPP \u00e9 aferido pela pena m\u00ednima em abstrato.<\/p>\n\n\n\n<p>???? Deve-se adotar a fra\u00e7\u00e3o m\u00ednima das majorantes e a m\u00e1xima das atenuantes.<\/p>\n\n\n\n<p>???? \u00c9 vedada a proje\u00e7\u00e3o de \u201cpena hipot\u00e9tica\u201d em perspectiva.<\/p>\n\n\n\n<p>???? A continuidade delitiva n\u00e3o obsta o ANPP se a pena m\u00ednima final n\u00e3o exceder quatro anos.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-discussao-e-tese-10\">Discuss\u00e3o e Tese<\/h3>\n\n\n\n<p>???? O STJ harmonizou o art. 28-A do CPP com a jurisprud\u00eancia dos Juizados Especiais (Lei 9.099\/1995), aplicando analogia in bonam partem ao ANPP.<\/p>\n\n\n\n<p>\u2696\ufe0f O Tribunal afastou a tese de que a continuidade delitiva excluiria automaticamente a negocia\u00e7\u00e3o, refor\u00e7ando que o c\u00e1lculo deve considerar as fra\u00e7\u00f5es m\u00ednimas e n\u00e3o proje\u00e7\u00f5es hipot\u00e9ticas de pena, em coer\u00eancia com a S\u00famula 438\/STJ (veda\u00e7\u00e3o \u00e0 prescri\u00e7\u00e3o em perspectiva).<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-como-sera-cobrado-em-prova-10\">Como ser\u00e1 Cobrado em Prova<\/h3>\n\n\n\n<p>???? A continuidade delitiva impede o ANPP por elevar a pena m\u00ednima al\u00e9m de quatro anos.<\/p>\n\n\n\n<p>\u274c Errado. O STJ entendeu que \u00e9 poss\u00edvel o acordo se a pena m\u00ednima com fra\u00e7\u00f5es m\u00ednimas n\u00e3o exceder quatro anos.<\/p>\n\n\n\n<p>???? O exame de admissibilidade do ANPP deve considerar a pena m\u00ednima em abstrato, com incid\u00eancia das majorantes na fra\u00e7\u00e3o m\u00ednima e das atenuantes na fra\u00e7\u00e3o m\u00e1xima.<\/p>\n\n\n\n<p>\u2705 Correto. Esse \u00e9 o entendimento do STJ.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-versao-esquematizada-10\">Vers\u00e3o Esquematizada<\/h3>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td>???? ANPP \u2013 continuidade delitiva<\/td><\/tr><tr><td>???? CPP, art. 28-A \u00a71\u00ba ???? Pena m\u00ednima em abstrato ???? Veda\u00e7\u00e3o \u00e0 \u201cpena hipot\u00e9tica\u201d (S\u00famula 438\/STJ) ???? Analogias: sursis processual e Tema 723\/STF<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-inteiro-teor-10\">Inteiro Teor<\/h3>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; A controv\u00e9rsia consiste em definir se, em crimes em continuidade delitiva, a aferi\u00e7\u00e3o do requisito objetivo previsto no art. 28-A do CPP para o ANPP deve se pautar pela pena m\u00ednima em abstrato &#8211; com incid\u00eancia das causas de aumento na fra\u00e7\u00e3o m\u00ednima -, permitindo, assim, a an\u00e1lise ministerial do acordo de n\u00e3o persecu\u00e7\u00e3o penal.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; O acordo de n\u00e3o persecu\u00e7\u00e3o penal, introduzido pela Lei n. 13.964\/2019, exige, entre outros requisitos, que o crime seja sem viol\u00eancia ou grave amea\u00e7a e que a pena m\u00ednima em abstrato seja inferior a 4 anos, cabendo ao Minist\u00e9rio P\u00fablico avaliar motivadamente o cabimento, sem que haja direito subjetivo do investigado ao acordo.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Dada a fun\u00e7\u00e3o despenalizadora que lhe \u00e9 atribu\u00edda pela Lei n. 13.964\/2019, o ANPP exige interpreta\u00e7\u00e3o teleol\u00f3gica e sist\u00e9mica, em conson\u00e2ncia com institutos cong\u00eaneres que partilham o mesmo horizonte normativo e valorativo, entre os quais se inclui a suspens\u00e3o condicional do processo, nos termos do art. 89 da Lei n. 9.099\/1995. Ambos os mecanismos orientam-se pela reduzida interven\u00e7\u00e3o estatal e pela busca de solu\u00e7\u00f5es que privilegiem a consensualidade e a efetividade da tutela penal m\u00ednima, exigindo, por isso, leitura harmonizadora que preserve a coes\u00e3o do ordenamento e a finalidade despenalizadora do legislador.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; No plano interpretativo, a exig\u00eancia do art. 28-A, caput, do CPP quanto \u00e0 &#8220;pena m\u00ednima inferior a 4 (quatro) anos&#8221; reclama entendimento t\u00e9cnico: a express\u00e3o deve ser aferida no plano abstrato da tipicidade sancionat\u00f3ria, isto \u00e9, tomando-se por par\u00e2metro a pena m\u00ednima legalmente cominada ao tipo, e n\u00e3o proje\u00e7\u00f5es hipot\u00e9ticas resultantes da dosimetria concreta ou de c\u00e1lculos prospectivos sobre as consequ\u00eancias da continuidade delitiva. Assim compreendida, a previs\u00e3o legal assegura previsibilidade e delimita\u00e7\u00e3o normativa ao crit\u00e9rio de elegibilidade para o instituto, afastando avalia\u00e7\u00f5es que se confundam com o ju\u00edzo de dosagem sancionat\u00f3ria pr\u00f3prio da fase de culpabilidade e pena.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Admitir o c\u00e1lculo &#8220;em perspectiva&#8221;, como pretende o Minist\u00e9rio P\u00fablico, importaria em introduzir no exame de admissibilidade do ANPP racioc\u00ednios an\u00e1logos \u00e0 extinta figura da chamada prescri\u00e7\u00e3o em perspectiva, cuja instrumentaliza\u00e7\u00e3o pelo int\u00e9rprete fora severamente <em>recha\u00e7ada pela jurisprud\u00eancia<\/em> que culminou na consolida\u00e7\u00e3o da S\u00famula n. 438\/STJ.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Em subst\u00e2ncia, referido racioc\u00ednio permitiria valora\u00e7\u00e3o de penas hipot\u00e9ticas como par\u00e2metro decis\u00f3rio, pr\u00e1tica que fragiliza a seguran\u00e7a jur\u00eddica e enseja discricionariedades indefinidas. Em suma, a interpreta\u00e7\u00e3o coerente com o texto legal e com o sistema recomenda que a aferi\u00e7\u00e3o da aptid\u00e3o ao acordo se fa\u00e7a \u00e0 luz da pena m\u00ednima em abstrato, preservando-se, na fase pr\u00f3pria, a liberdade do magistrado para a dosimetria concreta e para a valora\u00e7\u00e3o dos elementos f\u00e1ticos.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; \u00c9 certo que o art. 28-A, \u00a7 1\u00ba, do CPP disp\u00f5e que, &#8220;para aferi\u00e7\u00e3o da pena m\u00ednima cominada ao delito a que se refere o caput deste artigo, ser\u00e3o consideradas as causas de aumento e de diminui\u00e7\u00e3o aplic\u00e1veis ao caso concreto.&#8221; Tal enunciado demanda, por\u00e9m, interpreta\u00e7\u00e3o em chave sistem\u00e1tica e final\u00edstica. Tratando-se de requisito objetivo de elegibilidade, a norma n\u00e3o autoriza que o exame preliminar se converta em ensaio prospectivo de dosimetria; imp\u00f5e-se, ao rev\u00e9s, que se adote como par\u00e2metro inicial a pena m\u00ednima em abstrato, valorizando-se, na aplica\u00e7\u00e3o das majorantes, a fra\u00e7\u00e3o m\u00ednima legal pertinente, porquanto essa solu\u00e7\u00e3o resguarda a delimita\u00e7\u00e3o normativa do crit\u00e9rio de admissibilidade e preserva a separa\u00e7\u00e3o de fun\u00e7\u00f5es entre a fase de sele\u00e7\u00e3o do instrumento despenalizador e a fase sentencial de individualiza\u00e7\u00e3o da pena.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; A jurisprud\u00eancia que trata do sursis processual consagrou racioc\u00ednio an\u00e1logo. N\u00e3o obstante a omiss\u00e3o da Lei n. 9.099\/1995 quanto \u00e0 continuidade delitiva, sedimentou-se entendimento segundo o qual, para aferi\u00e7\u00e3o da elegibilidade ao benef\u00edcio, procede-se \u00e0 soma da pena m\u00ednima da infra\u00e7\u00e3o mais grave com o acr\u00e9scimo de 1\/6, conforme sedimentado na S\u00famula n. 243\/STJ e S\u00famula n. 723\/STF. A analogia in bonam partem imp\u00f5e a transposi\u00e7\u00e3o desse racioc\u00ednio ao ANPP, em raz\u00e3o da proximidade da causa final\u00edstica entre os institutos.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Desse modo, \u00e0 luz do texto e da finalidade do art. 28-A, \u00a7 1\u00ba, do CPP, o qual determina considerar causas de aumento e diminui\u00e7\u00e3o para aferi\u00e7\u00e3o da pena m\u00ednima, a interpreta\u00e7\u00e3o normativa correta \u00e9 a que, nas vari\u00e1veis, toma a fra\u00e7\u00e3o m\u00ednima das majorantes e a fra\u00e7\u00e3o m\u00e1xima das atenuantes, na medida em que o crit\u00e9rio legal visa precisamente \u00e0 aferi\u00e7\u00e3o da pena m\u00ednima em abstrato, e n\u00e3o a sua proje\u00e7\u00e3o na dimens\u00e3o m\u00e1xima; em suma, procura-se a menor pena poss\u00edvel em abstrato, n\u00e3o a pena em sua extens\u00e3o m\u00e1xima.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-13-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-tribunal-do-juri-e-nulidade-por-prova-exclusivamente-extrajudicial\">13.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Tribunal do J\u00fari e nulidade por prova exclusivamente extrajudicial<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-destaque-11\">Destaque<\/h3>\n\n\n\n<p>A pron\u00fancia e a condena\u00e7\u00e3o n\u00e3o podem ser fundamentadas exclusivamente em elementos colhidos na fase extrajudicial; \u00e9 imprescind\u00edvel a produ\u00e7\u00e3o de provas em contradit\u00f3rio judicial.<\/p>\n\n\n\n<p>REsp 2.232.036-DF, Rel. Min. Sebasti\u00e3o Reis J\u00fanior, Sexta Turma, por unanimidade, julgado em 14\/10\/2025.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-conteudo-base-11\">Conte\u00fado-Base<\/h3>\n\n\n\n<p>???? CPP, arts. 155 e 197; CF, art. 5\u00ba LIV e LVII.<\/p>\n\n\n\n<p>???? \u00c9 vedado ao juiz utilizar elementos inquisitoriais como prova exclusiva de pron\u00fancia ou condena\u00e7\u00e3o.<\/p>\n\n\n\n<p>???? A confiss\u00e3o extrajudicial isolada n\u00e3o sustenta den\u00fancia, pron\u00fancia ou condena\u00e7\u00e3o.<\/p>\n\n\n\n<p>???? A decis\u00e3o deve respeitar a presun\u00e7\u00e3o de inoc\u00eancia e o devido processo legal.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-discussao-e-tese-11\">Discuss\u00e3o e Tese<\/h3>\n\n\n\n<p>???? O STJ analisou caso em que o r\u00e9u foi pronunciado e condenado com base apenas em confiss\u00f5es e depoimentos prestados na fase inquisitorial.<\/p>\n\n\n\n<p>\u2696\ufe0f A Sexta Turma reconheceu a nulidade do processo, por viola\u00e7\u00e3o ao contradit\u00f3rio e \u00e0 ampla defesa, determinando o trancamento da a\u00e7\u00e3o penal, com possibilidade de nova den\u00fancia se houver elementos v\u00e1lidos.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-como-sera-cobrado-em-prova-11\">Como ser\u00e1 Cobrado em Prova<\/h3>\n\n\n\n<p>???? \u00c9 v\u00e1lida a condena\u00e7\u00e3o baseada exclusivamente em provas colhidas na fase extrajudicial.<\/p>\n\n\n\n<p>\u274c Errado. O STJ declarou a nulidade por ofensa ao contradit\u00f3rio e \u00e0 presun\u00e7\u00e3o de inoc\u00eancia.<\/p>\n\n\n\n<p>???? A pron\u00fancia e a condena\u00e7\u00e3o exigem provas colhidas em ju\u00edzo sob o crivo do contradit\u00f3rio.<\/p>\n\n\n\n<p>\u2705 Correto. Esse foi o entendimento aplicado.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-versao-esquematizada-11\">Vers\u00e3o Esquematizada<\/h3>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td>???? Tribunal do J\u00fari \u2013 provas extrajudiciais<\/td><\/tr><tr><td>???? CPP, arts. 155 e 197 ???? CF, art. 5\u00ba LIV e LVII ???? Confiss\u00e3o isolada \u2192 insuficiente ???? Nulidade da pron\u00fancia e da condena\u00e7\u00e3o<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-nbsp\">&nbsp;<\/h3>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-inteiro-teor-11\">Inteiro Teor<\/h3>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;A controv\u00e9rsia consiste em definir se a pron\u00fancia e a condena\u00e7\u00e3o podem ser fundamentadas exclusivamente em elementos colhidos na fase extrajudicial, sem confirma\u00e7\u00e3o em ju\u00edzo; e se o entendimento jurisprudencial mais ben\u00e9fico ao recorrente pode ser aplicado ap\u00f3s o tr\u00e2nsito em julgado da condena\u00e7\u00e3o.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; De inicio, registre-se que, nos autos da revis\u00e3o criminal, \u00e9 fato incontroverso que o acusado foi submetido a julgamento pelo Tribunal do J\u00fari mediante elementos de informa\u00e7\u00e3o coletados apenas na fase extrajudicial, quais sejam, sua confiss\u00e3o e o relato dos corr\u00e9us, exclusivamente, sem que o Ju\u00edzo tenha aliado esses elementos a qualquer outro decorrente da larga investiga\u00e7\u00e3o instaurada para apurar a pr\u00e1tica dos crimes.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Ademais, no caso, salta aos olhos que existiu s\u00e9ria contradi\u00e7\u00e3o entre os depoimentos dos corr\u00e9us prestados em fase inquisitorial, em que imputam a autoria ao recorrente, e as considera\u00e7\u00f5es apresentadas em ju\u00edzo, ocasi\u00e3o na qual o consideraram inocente.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Caberia ao magistrado singular, a fim de afastar o depoimento judicial que inocenta o recorrente, minimamente, corroborar o depoimento extrajudicial que o incrimina com outros elementos de convic\u00e7\u00e3o, mas isso n\u00e3o consta da decis\u00e3o de pron\u00fancia, que apenas opta pelo depoimento extrajudicial incriminador para submeter o acusado a julgamento pelo Conselho de ju\u00edzes leigos, sem sequer mencionar a exist\u00eancia dos depoimentos judiciais exculpantes.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; O mais grave no caso em quest\u00e3o \u00e9 que existe prova judicial que aponta para a inoc\u00eancia do sentenciado, mas esta foi totalmente desconsiderada e ignorada pelo Magistrado singular.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Da\u00ed por diante, a pergunta que se deve fazer \u00e9 a seguinte: poderia um acusado ser submetido a julgamento por um Tribunal de Ju\u00edzes leigos, mediante a sobreposi\u00e7\u00e3o de um depoimento extrajudicial, que nem sequer menciona a forma de execu\u00e7\u00e3o dos crimes imputados, ao depoimento prestado em ju\u00edzo, pelos mesmos corr\u00e9us que o apontaram como executor, de que ele seria inocente?<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Ainda no campo dos questionamentos, indago: o brocardo in dubio pro societate, considerado na ocasi\u00e3o da decis\u00e3o de pron\u00fancia, que nem sequer faz parte da categoria dos princ\u00edpios processuais penais, poderia justificar o julgamento de um acusado por ju\u00edzes leigos apenas com base em depoimentos de corr\u00e9us, sem qualquer elemento dos autos que confirmassem a veracidade dessas acusa\u00e7\u00f5es? N\u00e3o estaria o magistrado dando a esses depoimentos um valor maior do que eles de fato ostentem?<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; E o que dizer da pr\u00f3pria confiss\u00e3o do acusado, que vacilou em diversas ocasi\u00f5es em que indagado pela autoridade policial? Poderia sua confiss\u00e3o ser considerada para submiss\u00e3o a um julgamento pelo J\u00fari, sem que tal elemento de convic\u00e7\u00e3o tenha sido confrontado com as demais provas dos autos, em total afronta ao art. 197 do C\u00f3digo de Processo Penal?<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Para todos esses questionamentos, a resposta se baseia no fato de que, ainda que em algum momento a jurisprud\u00eancia tenha admitido a submiss\u00e3o do acusado a julgamento pelo Tribunal do J\u00fari, mediante elementos produzidos exclusivamente na fase investigat\u00f3ria, considerada \u00e0 base constitucional do Estado Democr\u00e1tico de Direito garantido pela Constitui\u00e7\u00e3o Federal de1988, mesmo que o C\u00f3digo de Processo Penal no qual nos baseamos seja de 1941 e ostente alguns resqu\u00edcios inquisitoriais, nenhum dispositivo legal dali constante pode se sobrepor \u00e0s garantias constitucionais, dentre elas a presun\u00e7\u00e3o de inoc\u00eancia e o devido processo legal (art. 5\u00ba, LVII e LIV, da CF\/1988).<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Ainda que se sustente a respeito da instru\u00e7\u00e3o em plen\u00e1rio, da an\u00e1lise da ata de julgamento do Tribunal do J\u00fari, observa-se que a tese defensiva \u00e9 de negativa de autoria, ou seja, contr\u00e1ria \u00e0 confiss\u00e3o extrajudicial do recorrente e dos corr\u00e9us que o incriminaram somente naquela ocasi\u00e3o.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Ademais, \u00e9 importante reconhecer e consignar que este Superior Tribunal, em rela\u00e7\u00e3o \u00e0 impossibilidade de submeter o acusado a julgamento pelo Tribunal do J\u00fari com base apenas em elementos de convic\u00e7\u00e3o da fase extrajudicial, firmado a partir de meados de 2022, mas n\u00e3o em precedente qualificado, n\u00e3o estabeleceu balizas para sua aplica\u00e7\u00e3o retroativa.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Da\u00ed porque a an\u00e1lise tem sido feita de acordo com o caso concreto, a depender do quanto a nulidade \u00e9 manifesta, a t\u00edtulo de cogni\u00e7\u00e3o, inerente a recurso ou habeas corpus, da destreza do advogado em demonstrar a viola\u00e7\u00e3o do dispositivo legal e do preju\u00edzo causado ao acusado, podendo o v\u00edcio ser reconhecido at\u00e9 mesmo ap\u00f3s a senten\u00e7a condenat\u00f3ria.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Nesse contexto, n\u00e3o existe outra provid\u00eancia a n\u00e3o ser o trancamento da a\u00e7\u00e3o penal, uma vez que a mera confiss\u00e3o desvinculada de outros elementos de informa\u00e7\u00e3o n\u00e3o \u00e9 capaz de sustentar sequer a den\u00fancia, raz\u00e3o pela qual o recorrente dever\u00e1 ser colocado imediatamente em liberdade, sem preju\u00edzo de que outra den\u00fancia seja formulada pelo \u00f3rg\u00e3o da acusa\u00e7\u00e3o, desde que mediante suficientes elementos de informa\u00e7\u00e3o que denotem a exist\u00eancia de ind\u00edcios de autoria em rela\u00e7\u00e3o ao acusado.<\/p>\n\n\n\n<p>***<\/p>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object aria-label=\"Incorporar PDF\" data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden><\/object><a id=\"wp-block-file--media-dcea47b6-b366-41d5-8594-24a116212a5e\" href=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/11\/18092830\/stj-info-867.pdf\">STJ &#8211; Info 867<\/a><a href=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/11\/18092830\/stj-info-867.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-dcea47b6-b366-41d5-8594-24a116212a5e\">Baixar<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>DOWNLOAD do PDF AQUI! 1.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Taxa de juros morat\u00f3rios nas d\u00edvidas civis: aplica\u00e7\u00e3o da SELIC Destaque O art. 406 do C\u00f3digo Civil de 2002, antes da entrada em vigor da Lei 14.905\/2024, deve ser interpretado no sentido de que a taxa SELIC \u00e9 a taxa de juros de mora aplic\u00e1vel \u00e0s d\u00edvidas de natureza civil, [&hellip;]<\/p>\n","protected":false},"author":833,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1],"tags":[],"tax_estado":[],"class_list":["post-1671988","post","type-post","status-publish","format-standard","hentry","category-cursos-e-concursos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Informativo STJ 867 Comentado<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-867-comentado\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Informativo STJ 867 Comentado\" \/>\n<meta property=\"og:description\" content=\"DOWNLOAD do PDF AQUI! 1.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Taxa de juros morat\u00f3rios nas d\u00edvidas civis: aplica\u00e7\u00e3o da SELIC Destaque O art. 406 do C\u00f3digo Civil de 2002, antes da entrada em vigor da Lei 14.905\/2024, deve ser interpretado no sentido de que a taxa SELIC \u00e9 a taxa de juros de mora aplic\u00e1vel \u00e0s d\u00edvidas de natureza civil, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-867-comentado\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-18T12:28:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-18T12:28:56+00:00\" \/>\n<meta name=\"author\" content=\"Jean Vilbert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jean Vilbert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"56 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-867-comentado\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-867-comentado\/\"},\"author\":{\"name\":\"Jean Vilbert\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/475a0922f10cff0d1bc8bfecde05f999\"},\"headline\":\"Informativo STJ 867 Comentado\",\"datePublished\":\"2025-11-18T12:28:54+00:00\",\"dateModified\":\"2025-11-18T12:28:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-867-comentado\/\"},\"wordCount\":11276,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"articleSection\":[\"Concursos P\u00fablicos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-867-comentado\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-867-comentado\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-867-comentado\/\",\"name\":\"Informativo STJ 867 Comentado\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"datePublished\":\"2025-11-18T12:28:54+00:00\",\"dateModified\":\"2025-11-18T12:28:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-867-comentado\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-867-comentado\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-867-comentado\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Informativo STJ 867 Comentado\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/475a0922f10cff0d1bc8bfecde05f999\",\"name\":\"Jean Vilbert\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/1667694e4ebdd32feeac9ea2794de3f0470b5c55c6198181ab0b0c333b121921?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1667694e4ebdd32feeac9ea2794de3f0470b5c55c6198181ab0b0c333b121921?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1667694e4ebdd32feeac9ea2794de3f0470b5c55c6198181ab0b0c333b121921?s=96&d=mm&r=g\",\"caption\":\"Jean Vilbert\"},\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/jeanvilbertgmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Informativo STJ 867 Comentado","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-867-comentado\/","og_locale":"pt_BR","og_type":"article","og_title":"Informativo STJ 867 Comentado","og_description":"DOWNLOAD do PDF AQUI! 1.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Taxa de juros morat\u00f3rios nas d\u00edvidas civis: aplica\u00e7\u00e3o da SELIC Destaque O art. 406 do C\u00f3digo Civil de 2002, antes da entrada em vigor da Lei 14.905\/2024, deve ser interpretado no sentido de que a taxa SELIC \u00e9 a taxa de juros de mora aplic\u00e1vel \u00e0s d\u00edvidas de natureza civil, [&hellip;]","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-867-comentado\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2025-11-18T12:28:54+00:00","article_modified_time":"2025-11-18T12:28:56+00:00","author":"Jean Vilbert","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Jean Vilbert","Est. tempo de leitura":"56 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-867-comentado\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-867-comentado\/"},"author":{"name":"Jean Vilbert","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/475a0922f10cff0d1bc8bfecde05f999"},"headline":"Informativo STJ 867 Comentado","datePublished":"2025-11-18T12:28:54+00:00","dateModified":"2025-11-18T12:28:56+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-867-comentado\/"},"wordCount":11276,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"articleSection":["Concursos P\u00fablicos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-867-comentado\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-867-comentado\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-867-comentado\/","name":"Informativo STJ 867 Comentado","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"datePublished":"2025-11-18T12:28:54+00:00","dateModified":"2025-11-18T12:28:56+00:00","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-867-comentado\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-867-comentado\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-867-comentado\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Informativo STJ 867 Comentado"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/475a0922f10cff0d1bc8bfecde05f999","name":"Jean Vilbert","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/1667694e4ebdd32feeac9ea2794de3f0470b5c55c6198181ab0b0c333b121921?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1667694e4ebdd32feeac9ea2794de3f0470b5c55c6198181ab0b0c333b121921?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1667694e4ebdd32feeac9ea2794de3f0470b5c55c6198181ab0b0c333b121921?s=96&d=mm&r=g","caption":"Jean Vilbert"},"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/jeanvilbertgmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1671988","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/833"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1671988"}],"version-history":[{"count":2,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1671988\/revisions"}],"predecessor-version":[{"id":1674818,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1671988\/revisions\/1674818"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1671988"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1671988"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1671988"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1671988"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}