{"id":1659200,"date":"2025-10-22T15:58:49","date_gmt":"2025-10-22T18:58:49","guid":{"rendered":"https:\/\/blog-estrategia.mystagingwebsite.com\/blog\/?p=1659200"},"modified":"2025-10-22T18:03:56","modified_gmt":"2025-10-22T21:03:56","slug":"concurso-iases-2025-prova-de-redacao","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-iases-2025-prova-de-redacao\/","title":{"rendered":"Concurso IASES 2025: como ser\u00e1 a prova de reda\u00e7\u00e3o?"},"content":{"rendered":"\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong><em>Edital do concurso IASES tem iniciais de at\u00e9 R$ 7,5 mil!<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Voc\u00ea que vai participar do novo <a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-iases-edital-publicado-2025\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>concurso IASES<\/strong><\/a> (<a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/cursosPorConcurso\/instituto-de-atendimento-socioeducativo-do-espirito-santo-iases\/\" target=\"_blank\" rel=\"noreferrer noopener\">Instituto de Atendimento Socioeducativo do Esp\u00edrito Santo<\/a>), com <strong>1.008 vagas imediatas<\/strong> e em cadastro de reserva, j\u00e1 descobriu como ser\u00e1 r<strong>ealizada a prova de reda\u00e7\u00e3o<\/strong>?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O edital tem oportunidades para os cargos de <strong>Agente Socioeducativo e T\u00e9cnico Superior Socioeducativo<\/strong>, de n\u00edveis m\u00e9dio e superior. Os sal\u00e1rios iniciais variam de <strong>R$ 5.597,64 a R$ 7.547,78<\/strong>, al\u00e9m do aux\u00edlio-alimenta\u00e7\u00e3o de R$ 800,00.<\/p>\n\n\n\n<div class=\"container\" id=\"boxes\">\n  <div class=\"row\">\n\n    <div class=\"col-sm\">\n      <div class=\"banner-estrat-corj\" id=\"box-assinatura\">\n        <h3 class=\"titulo-assinatura\">Concurso IASES ES<\/h3>\n        <p class=\"subtitulo-assinatura\">Prepara\u00e7\u00e3o completa para o concurso!\u270d<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/cursosPorConcurso\/instituto-de-atendimento-socioeducativo-do-espirito-santo-iases\/\" role=\"button\" rel=\"noopener noreferrer\">VER CURSOS<\/a>\n        <\/div>\n      <\/div>\n      <p class=\"texto-auxiliar\"><\/p><\/div>\n\n  <\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-como-sera-a-prova-de-redacao-do-concurso-iases-2025\">Como ser\u00e1 a prova de reda\u00e7\u00e3o do concurso IASES 2025?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Para <strong>Agente Socioeducativo<\/strong> a etapa do concurso IASES consistir\u00e1 na <strong>elabora\u00e7\u00e3o de um texto dissertativo<\/strong>, aplicada simultaneamente \u00e0 prova objetiva.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">J\u00e1 para <strong>T\u00e9cnico Superior<\/strong>, a prova de reda\u00e7\u00e3o consistir\u00e1 na<strong> elabora\u00e7\u00e3o de um texto dissertativo<\/strong>, com base em tema relacionado a disciplina de conhecimentos espec\u00edficos referente \u00e0 pol\u00edtica socioeducativa indicados no conte\u00fado program\u00e1tico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A reda\u00e7\u00e3o dever\u00e1 conter<strong> no m\u00ednimo 20 e no m\u00e1ximo 30 linhas<\/strong>. Ser\u00e3o considerados classificados os candidatos que obtiverem, no m\u00ednimo, 50% da pontua\u00e7\u00e3o total da prova. Veja os crit\u00e9rios de corre\u00e7\u00e3o para a etapa!<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"670\" height=\"506\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/10\/22155712\/image-239.png\" alt=\"Crit\u00e9rios de avalia\u00e7\u00e3o da prova de reda\u00e7\u00e3o\" class=\"wp-image-1659203\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/10\/22155712\/image-239.png 670w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/10\/22155712\/image-239-300x227.png 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/10\/22155712\/image-239-150x113.png 150w\" sizes=\"auto, (max-width: 670px) 100vw, 670px\" \/><figcaption class=\"wp-element-caption\">Crit\u00e9rios de avalia\u00e7\u00e3o da prova de reda\u00e7\u00e3o<\/figcaption><\/figure>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><em>Para mais informa\u00e7\u00f5es do concurso IASES 2025, acesse o link abaixo. Preparamos um artigo completo e exclusivo para voc\u00ea!<\/em><\/p>\n\n\n\n<p class=\"has-text-align-center has-cyan-bluish-gray-background-color has-background has-medium-font-size wp-block-paragraph\"><strong>Saiba mais: <a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-iases-es\/\" target=\"_blank\" rel=\"noreferrer noopener\">concurso IASES<\/a><\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"h-quer-saber-tudo-sobre-concursos-previstos-confira-nossos-artigos\">Quer saber tudo sobre concursos previstos?<br \/>Confira nossos artigos!<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos abertos<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2025\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos 2025<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2026\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos 2026<\/a><\/li>\n<\/ul>\n\n\n\n<div class=\"container\" id=\"boxes\">\n  <div class=\"row\">\n\n    <div class=\"col-sm\">\n      <div class=\"estrategia\" id=\"box-assinatura\">\n        <h3 class=\"titulo-assinatura\">Assinatura de Concursos<\/h3>\n        <p class=\"subtitulo-assinatura\">Assinatura de 1 ano ou 2 anos<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/assinaturas\/\" role=\"button\" rel=\"noopener noreferrer\">ASSINE AGORA<\/a>\n        <\/div>\n      <\/div><\/div><\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Edital do concurso IASES tem iniciais de at\u00e9 R$ 7,5 mil! Voc\u00ea que vai participar do novo concurso IASES (Instituto de Atendimento Socioeducativo do Esp\u00edrito Santo), com 1.008 vagas imediatas e em cadastro de reserva, j\u00e1 descobriu como ser\u00e1 realizada a prova de reda\u00e7\u00e3o? O edital tem oportunidades para os cargos de Agente Socioeducativo e [&hellip;]<\/p>\n","protected":false},"author":1483,"featured_media":838305,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"post_tipo":"news","footnotes":""},"categories":[220188,220219],"tags":[],"tax_estado":[219971],"class_list":["post-1659200","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policial-agente-penitenciario","category-noticias","tax_estado-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Concurso IASES 2025: como ser\u00e1 a prova de reda\u00e7\u00e3o?<\/title>\n<meta name=\"description\" content=\"Como ser\u00e1 realizada a prova de reda\u00e7\u00e3o do concurso IASES 2025? Acesse o site do Estrat\u00e9gia e confira os detalhes!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-iases-2025-prova-de-redacao\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Concurso IASES 2025: como ser\u00e1 a prova de reda\u00e7\u00e3o?\" \/>\n<meta property=\"og:description\" content=\"Como ser\u00e1 realizada a prova de reda\u00e7\u00e3o do concurso IASES 2025? Acesse o site do Estrat\u00e9gia e confira os detalhes!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-iases-2025-prova-de-redacao\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-22T18:58:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-22T21:03:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/07\/17110913\/iases-es.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"432\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Diogo Mendes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Diogo Mendes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/concurso-iases-2025-prova-de-redacao\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/concurso-iases-2025-prova-de-redacao\\\/\"},\"author\":{\"name\":\"Diogo Mendes\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/cc9e76173880338ce9f656c88664a1f6\"},\"headline\":\"Concurso IASES 2025: como ser\u00e1 a prova de reda\u00e7\u00e3o?\",\"datePublished\":\"2025-10-22T18:58:49+00:00\",\"dateModified\":\"2025-10-22T21:03:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/concurso-iases-2025-prova-de-redacao\\\/\"},\"wordCount\":268,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/concurso-iases-2025-prova-de-redacao\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2021\\\/07\\\/17110913\\\/iases-es.jpeg\",\"articleSection\":[\"Policial (Agente Penitenci\u00e1rio)\",\"\u00daltimas not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/concurso-iases-2025-prova-de-redacao\\\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/concurso-iases-2025-prova-de-redacao\\\/\",\"url\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/concurso-iases-2025-prova-de-redacao\\\/\",\"name\":\"Concurso IASES 2025: como ser\u00e1 a prova de reda\u00e7\u00e3o?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/concurso-iases-2025-prova-de-redacao\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/concurso-iases-2025-prova-de-redacao\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2021\\\/07\\\/17110913\\\/iases-es.jpeg\",\"datePublished\":\"2025-10-22T18:58:49+00:00\",\"dateModified\":\"2025-10-22T21:03:56+00:00\",\"description\":\"Como ser\u00e1 realizada a prova de reda\u00e7\u00e3o do concurso IASES 2025? Acesse o site do Estrat\u00e9gia e confira os detalhes!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/concurso-iases-2025-prova-de-redacao\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/concurso-iases-2025-prova-de-redacao\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/concurso-iases-2025-prova-de-redacao\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2021\\\/07\\\/17110913\\\/iases-es.jpeg\",\"contentUrl\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2021\\\/07\\\/17110913\\\/iases-es.jpeg\",\"width\":768,\"height\":432,\"caption\":\"iases\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/concurso-iases-2025-prova-de-redacao\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Concurso IASES 2025: como ser\u00e1 a prova de reda\u00e7\u00e3o?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2025\\\/06\\\/03203428\\\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2025\\\/06\\\/03203428\\\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/cc9e76173880338ce9f656c88664a1f6\",\"name\":\"Diogo Mendes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9754d6777d460a45ef4067b586b94c32005cc2345a0404b8d96adc620cf63806?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9754d6777d460a45ef4067b586b94c32005cc2345a0404b8d96adc620cf63806?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9754d6777d460a45ef4067b586b94c32005cc2345a0404b8d96adc620cf63806?s=96&d=mm&r=g\",\"caption\":\"Diogo Mendes\"},\"description\":\"Diogo Mendes \u00e9 jornalista formado pela Universidade Paulista, com experi\u00eancia em reda\u00e7\u00f5es de diversos ve\u00edculos e na produ\u00e7\u00e3o de conte\u00fados especializados em concursos p\u00fablicos. Desde 2019, atua no Estrat\u00e9gia Concursos como Jornalista e Analista de Conte\u00fado, com foco na apura\u00e7\u00e3o de informa\u00e7\u00f5es junto a \u00f3rg\u00e3os e fontes oficiais. Dedica-se especialmente \u00e0 produ\u00e7\u00e3o de not\u00edcias e reportagens sobre Concursos Legislativos, al\u00e9m de acompanhar diariamente os concursos policiais, banc\u00e1rios e da \u00e1rea da sa\u00fade.\",\"url\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/author\\\/diogo-mendesestrategiaconcursos-com-br\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Concurso IASES 2025: como ser\u00e1 a prova de reda\u00e7\u00e3o?","description":"Como ser\u00e1 realizada a prova de reda\u00e7\u00e3o do concurso IASES 2025? Acesse o site do Estrat\u00e9gia e confira os detalhes!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-iases-2025-prova-de-redacao\/","og_locale":"pt_BR","og_type":"article","og_title":"Concurso IASES 2025: como ser\u00e1 a prova de reda\u00e7\u00e3o?","og_description":"Como ser\u00e1 realizada a prova de reda\u00e7\u00e3o do concurso IASES 2025? Acesse o site do Estrat\u00e9gia e confira os detalhes!","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-iases-2025-prova-de-redacao\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2025-10-22T18:58:49+00:00","article_modified_time":"2025-10-22T21:03:56+00:00","og_image":[{"width":768,"height":432,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/07\/17110913\/iases-es.jpeg","type":"image\/jpeg"}],"author":"Diogo Mendes","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Diogo Mendes","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-iases-2025-prova-de-redacao\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-iases-2025-prova-de-redacao\/"},"author":{"name":"Diogo Mendes","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/cc9e76173880338ce9f656c88664a1f6"},"headline":"Concurso IASES 2025: como ser\u00e1 a prova de reda\u00e7\u00e3o?","datePublished":"2025-10-22T18:58:49+00:00","dateModified":"2025-10-22T21:03:56+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-iases-2025-prova-de-redacao\/"},"wordCount":268,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-iases-2025-prova-de-redacao\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/07\/17110913\/iases-es.jpeg","articleSection":["Policial (Agente Penitenci\u00e1rio)","\u00daltimas not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-iases-2025-prova-de-redacao\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-iases-2025-prova-de-redacao\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-iases-2025-prova-de-redacao\/","name":"Concurso IASES 2025: como ser\u00e1 a prova de reda\u00e7\u00e3o?","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-iases-2025-prova-de-redacao\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-iases-2025-prova-de-redacao\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/07\/17110913\/iases-es.jpeg","datePublished":"2025-10-22T18:58:49+00:00","dateModified":"2025-10-22T21:03:56+00:00","description":"Como ser\u00e1 realizada a prova de reda\u00e7\u00e3o do concurso IASES 2025? Acesse o site do Estrat\u00e9gia e confira os detalhes!","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-iases-2025-prova-de-redacao\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-iases-2025-prova-de-redacao\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-iases-2025-prova-de-redacao\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/07\/17110913\/iases-es.jpeg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/07\/17110913\/iases-es.jpeg","width":768,"height":432,"caption":"iases"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-iases-2025-prova-de-redacao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Concurso IASES 2025: como ser\u00e1 a prova de reda\u00e7\u00e3o?"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/cc9e76173880338ce9f656c88664a1f6","name":"Diogo Mendes","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/9754d6777d460a45ef4067b586b94c32005cc2345a0404b8d96adc620cf63806?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9754d6777d460a45ef4067b586b94c32005cc2345a0404b8d96adc620cf63806?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9754d6777d460a45ef4067b586b94c32005cc2345a0404b8d96adc620cf63806?s=96&d=mm&r=g","caption":"Diogo Mendes"},"description":"Diogo Mendes \u00e9 jornalista formado pela Universidade Paulista, com experi\u00eancia em reda\u00e7\u00f5es de diversos ve\u00edculos e na produ\u00e7\u00e3o de conte\u00fados especializados em concursos p\u00fablicos. Desde 2019, atua no Estrat\u00e9gia Concursos como Jornalista e Analista de Conte\u00fado, com foco na apura\u00e7\u00e3o de informa\u00e7\u00f5es junto a \u00f3rg\u00e3os e fontes oficiais. Dedica-se especialmente \u00e0 produ\u00e7\u00e3o de not\u00edcias e reportagens sobre Concursos Legislativos, al\u00e9m de acompanhar diariamente os concursos policiais, banc\u00e1rios e da \u00e1rea da sa\u00fade.","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/diogo-mendesestrategiaconcursos-com-br\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1659200","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/1483"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1659200"}],"version-history":[{"count":0,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1659200\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/838305"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1659200"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1659200"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1659200"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1659200"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}