{"id":1644901,"date":"2025-10-29T08:01:00","date_gmt":"2025-10-29T11:01:00","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=1644901"},"modified":"2025-10-21T16:00:14","modified_gmt":"2025-10-21T19:00:14","slug":"soldado-1a-2a-classe","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/soldado-1a-2a-classe\/","title":{"rendered":"Qual \u00e9 a diferen\u00e7a entre Soldado de 1\u00aa e de 2\u00aa Classe?"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\" id=\"h-confira-neste-artigo-a-diferenca-entre-soldado-de-1\u00aa-e-de-2\u00aa-classe-entenda-o-que-isso-significa-dentro-dos-quadros-das-policias-militares\"><strong><em>Confira neste artigo a diferen\u00e7a entre Soldado de 1\u00aa e de 2\u00aa classe. Entenda o que isso significa dentro dos quadros das pol\u00edcias militares<\/em><\/strong><\/h2>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"543\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/09\/04223403\/1000064129-1024x543.jpg\" alt=\"Qual \u00e9 a diferen\u00e7a entre Soldado de 1\u00aa e de 2\u00aa Classe?\" class=\"wp-image-1649994\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/09\/04223403\/1000064129-1024x543.jpg 1024w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/09\/04223403\/1000064129-300x159.jpg 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/09\/04223403\/1000064129-768x407.jpg 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/09\/04223403\/1000064129-1536x814.jpg 1536w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/09\/04223403\/1000064129-150x79.jpg 150w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/09\/04223403\/1000064129.jpg 2038w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Qual a diferen\u00e7a entre Soldado de 1\u00aa e de 2\u00aa classe?<\/figcaption><\/figure>\n\n\n\n<p>Ol\u00e1, pessoal! Tudo bem? Hoje analisaremos a <strong>diferen\u00e7a entre Soldado de 1\u00aa e de 2\u00aa classe.<\/strong><\/p>\n\n\n\n<p>\u200bCertamente o sonho de vestir a farda e servir \u00e0 sociedade \u00e9 o que move milhares de pessoas a se prepararem para <strong>concursos p\u00fablicos da \u00e1rea policial.\u00a0<\/strong><\/p>\n\n\n\n<p>Entretanto, ao ler o edital, n\u00e3o raro voc\u00ea se depara com uma distin\u00e7\u00e3o que parece simples, mas que \u00e9 crucial para entender a sua futura carreira: a diferen\u00e7a entre <strong>Soldado de 1\u00aa e de 2\u00aa Classe.<\/strong><\/p>\n\n\n\n<p>Nesse artigo, \u200bvamos analisar essa <strong>diferen\u00e7a<\/strong> e te mostrar o que isso significa dentro dos quadros das pol\u00edcias militares. Acompanhe!<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-vivid-cyan-blue-color has-very-light-gray-to-cyan-bluish-gray-gradient-background has-text-color has-background has-link-color wp-elements-c58264ac53aff78535a22e0cfa1a67f9\" id=\"h-soldado-de-2\u00aa-classe-formacao\">\u200bSoldado de 2\u00aa classe: forma\u00e7\u00e3o<\/h2>\n\n\n\n<p>\u200bPrimeiramente, pense no <strong>Soldado de 2\u00aa classe<\/strong> como a primeira etapa oficial na Pol\u00edcia Militar. Nesse sentido, \u00e9 como se a etapa fosse uma esp\u00e9cie de porta de entrada para quem foi aprovado em todas as fases do concurso p\u00fablico (provas, testes f\u00edsicos, psicol\u00f3gico, etc.).&nbsp;<\/p>\n\n\n\n<p>No entanto, ser aprovado no concurso \u00e9 apenas o in\u00edcio da jornada. Ou seja, <strong>o candidato aprovado ainda n\u00e3o \u00e9 um Policial Militar de fato, mas sim um aluno-soldado.<\/strong> Vejamos as <strong>principais caracter\u00edsticas de um Soldado de 2\u00aa classe:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u200b<strong>Status e fun\u00e7\u00e3o:<\/strong> o Soldado de 2\u00aa classe \u00e9 o rec\u00e9m-ingresso na corpora\u00e7\u00e3o. Desse modo, seu principal e \u00fanico objetivo \u00e9 o treinamento. Ap\u00f3s a matr\u00edcula no Curso de Forma\u00e7\u00e3o de Soldados (CFS), uma etapa obrigat\u00f3ria e eliminat\u00f3ria, sua rotina se resume a aulas te\u00f3ricas e pr\u00e1ticas, desde legisla\u00e7\u00e3o penal e militar at\u00e9 aulas de tiro, defesa pessoal e o manual de procedimentos operacionais.<\/li>\n\n\n\n<li>\u200b<strong>Atribui\u00e7\u00f5es:<\/strong> o Soldado de 2\u00aa classe n\u00e3o possui autoridade legal para atuar como policial de forma aut\u00f4noma. Assim sendo, n\u00e3o anda armado, n\u00e3o realiza policiamento ostensivo e n\u00e3o pode prender ningu\u00e9m. Todas as suas atividades est\u00e3o limitadas ao ambiente da academia, sob a estrita orienta\u00e7\u00e3o dos instrutores.<\/li>\n\n\n\n<li>\u200b<strong>Remunera\u00e7\u00e3o:<\/strong> durante o per\u00edodo de forma\u00e7\u00e3o, o Soldado de 2\u00aa classe recebe um sal\u00e1rio-aluno ou bolsa-aux\u00edlio. Esse valor \u00e9, geralmente, menor do que o sal\u00e1rio de um policial em exerc\u00edcio, pois reflete o fato de que o militar est\u00e1 em fase de treinamento e ainda n\u00e3o pode ser empregado na atividade-fim da corpora\u00e7\u00e3o.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading has-vivid-cyan-blue-color has-very-light-gray-to-cyan-bluish-gray-gradient-background has-text-color has-background has-link-color wp-elements-e04870561d7006860f89d9f2d6445af3\" id=\"h-soldado-de-1\u00aa-classe-profissional-na-ativa\">\u200bSoldado de 1\u00aa classe: profissional na ativa<\/h2>\n\n\n\n<p>Em suma, a <strong>promo\u00e7\u00e3o a Soldado de 1\u00aa classe<\/strong> \u00e9 o grande marco na carreira de um Policial Militar rec\u00e9m chegado. Ou seja, trata-se do fim do per\u00edodo de treinamento e da entrada oficial na corpora\u00e7\u00e3o. Vejamos as <strong>principais caracter\u00edsticas de um Soldado de 1\u00aa classe:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u200b<strong>Status e fun\u00e7\u00e3o:<\/strong> ap\u00f3s concluir o Curso de Forma\u00e7\u00e3o de Soldados, o Soldado de 2\u00aa classe \u00e9 promovido ao posto de Soldado de 1\u00aa Classe, tornando-se um Policial Militar plenamente apto e legalmente habilitado ao exerc\u00edcio de todas as fun\u00e7\u00f5es do cargo.<\/li>\n\n\n\n<li>\u200b<strong>Atribui\u00e7\u00f5es:<\/strong> o Soldado de 1\u00aa classe j\u00e1 pode, e deve, atuar de forma aut\u00f4noma. O agente far\u00e1 o policiamento ostensivo, que \u00e9 a atividade mais vis\u00edvel da Pol\u00edcia Militar, e estar\u00e1 nas ruas, em viaturas ou a p\u00e9, atuando para prevenir crimes, prender infratores e garantir a seguran\u00e7a da popula\u00e7\u00e3o.<\/li>\n\n\n\n<li>\u200b<strong>Remunera\u00e7\u00e3o:<\/strong> a partir da promo\u00e7\u00e3o, o Soldado de 1\u00aa classe passa a receber o sal\u00e1rio integral previsto para o cargo, com todos os benef\u00edcios e adicionais.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading has-vivid-cyan-blue-color has-very-light-gray-to-cyan-bluish-gray-gradient-background has-text-color has-background has-link-color wp-elements-7ea015aec460cc76ec577eafdfdb4f1b\" id=\"h-quadro-comparativo\">\u200bQuadro comparativo<\/h2>\n\n\n\n<p>Como vimos, \u200ba <strong>diferen\u00e7a entre Soldado de 1\u00aa e de 2\u00aa classe<\/strong> \u00e9 a distin\u00e7\u00e3o entre o aluno e o profissional em exerc\u00edcio. Em outras palavras, \u00e9 a passagem da fase de forma\u00e7\u00e3o para a atua\u00e7\u00e3o real, um rito que transforma um civil em um Policial Militar.<\/p>\n\n\n\n<p>Dessa maneira, para sedimentar de vez o conhecimento, elaboramos um quadro comparativo que mostra a diferen\u00e7a entre Soldado de 1\u00aa e de 2\u00aa classe. Vejamos:<\/p>\n\n\n\n<figure class=\"wp-block-table is-style-stripes\"><table class=\"has-fixed-layout\"><thead><tr><th class=\"has-text-align-center\" data-align=\"center\">Caracter\u00edstica<\/th><th class=\"has-text-align-center\" data-align=\"center\">2\u00aa classe<\/th><th class=\"has-text-align-center\" data-align=\"center\">1\u00aa classe<\/th><\/tr><\/thead><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Fase da carreira<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">Forma\u00e7\u00e3o<\/td><td class=\"has-text-align-center\" data-align=\"center\">Exerc\u00edcio<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Status<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">Aluno-Soldado<\/td><td class=\"has-text-align-center\" data-align=\"center\">Policial Militar<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Atribui\u00e7\u00f5es<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">Aprendizado e treino<\/td><td class=\"has-text-align-center\" data-align=\"center\">Atuar na fun\u00e7\u00e3o<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Armamento<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">N\u00e3o autorizado<\/td><td class=\"has-text-align-center\" data-align=\"center\">Autorizado<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Remunera\u00e7\u00e3o<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">Bolsa-aux\u00edlio<\/td><td class=\"has-text-align-center\" data-align=\"center\">Sal\u00e1rio integral<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p>Assim, evidencia-se que a <strong>jornada para se tornar um Policial Militar<\/strong> come\u00e7a com a aprova\u00e7\u00e3o em um concurso p\u00fablico. Contudo, para que o candidato entre em exerc\u00edcio, \u00e9 necess\u00e1ria a aprova\u00e7\u00e3o no Curso de Forma\u00e7\u00e3o.<\/p>\n\n\n\n<p>\u200bEntender essa diferen\u00e7a \u00e9 fundamental para que voc\u00ea saiba o que esperar ap\u00f3s ver o seu nome na lista de aprovados do concurso.&nbsp;<\/p>\n\n\n\n<p>Nesse sentido, o <strong>posto de Soldado de 2\u00aa classe \u00e9 a porta de entrada <\/strong>para a carreira na Pol\u00edcia Militar. Ou seja, somente ap\u00f3s o per\u00edodo de forma\u00e7\u00e3o \u00e9 que voc\u00ea vai adquirir todas as habilidades necess\u00e1rias para proteger e servir.\u00a0<\/p>\n\n\n\n<p>Por outro lado, a <strong>promo\u00e7\u00e3o a Soldado de 1\u00aa classe<\/strong> \u00e9 a recompensa por todo o esfor\u00e7o que \u00e9 despendido nesta \u00e1rdua trajet\u00f3ria de prepara\u00e7\u00e3o.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-vivid-cyan-blue-color has-text-color has-link-color wp-elements-68a1d16e75a8f2ca7474c8c856b331d5\" id=\"h-consideracoes-finais\"><strong>Considera\u00e7\u00f5es finais<\/strong><\/h2>\n\n\n\n<p>Ent\u00e3o, \u00e9 isso, pessoal! Chegamos ao fim da nossa an\u00e1lise sobre <strong>a diferen\u00e7a entre Soldado de 1\u00aa e de 2\u00aa classe.<\/strong> Esperamos que tenham gostado.<\/p>\n\n\n\n<p>Confira tamb\u00e9m:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-policia-legislativa-alego\/\"><strong>Concurso da Pol\u00edcia Legislativa da ALEGO: como se preparar no pr\u00e9-edital?<\/strong><\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-policial-camara-deputados\/\"><strong>Concurso Policial da C\u00e2mara dos Deputados: saiba como foi o \u00faltimo certame para o cargo de Agente de Pol\u00edcia Legislativa<\/strong><\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/agente-policia-legislativa-ales\/\"><strong>Concurso Policial: Agente de Pol\u00edcia Legislativa da ALES<\/strong><\/a><\/li>\n<\/ul>\n\n\n\n<p>Se voc\u00ea quer se preparar para chegar <strong>competitivo <\/strong>em qualquer prova da \u00e1rea, invista nos cursos da <a href=\"https:\/\/www.estrategiaconcursos.com.br\/pesquisa\/?q=policial\"><strong>\u00e1rea Policial<\/strong><\/a> do <a href=\"https:\/\/www.estrategiaconcursos.com.br\/\"><strong>Estrat\u00e9gia Concursos<\/strong><\/a>. L\u00e1 voc\u00ea encontrar\u00e1 <strong>aulas completas e detalhadas, com os melhores professores do mercado<\/strong>.<\/p>\n\n\n\n<p>Conhe\u00e7a tamb\u00e9m o <a href=\"https:\/\/concursos.estrategia.com\/\"><strong>Sistema de Quest\u00f5es do Estrat\u00e9gia<\/strong><\/a>. Afinal, a \u00fanica forma de <strong>consolidar o conte\u00fado <\/strong>de maneira satisfat\u00f3ria \u00e9 atrav\u00e9s da <strong>resolu\u00e7\u00e3o de quest\u00f5es.<\/strong><\/p>\n\n\n\n<p>Bons estudos a todos e at\u00e9 a pr\u00f3xima!<\/p>\n\n\n\n<p class=\"has-text-align-center\"><strong>Cursos e Assinaturas<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center\"><strong>Quer saber quais ser\u00e3o os pr\u00f3ximos concursos?<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center\"><strong>Confira nossos artigos!<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center has-white-color has-vivid-cyan-blue-background-color has-text-color has-background has-link-color wp-elements-4ee3858d78f8e73e6a059835bfd98e6f\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\"><strong>Concursos Abertos<\/strong><\/a><\/p>\n\n\n\n<p class=\"has-text-align-center has-white-color has-vivid-cyan-blue-background-color has-text-color has-background has-link-color wp-elements-1aca1c51fe870dad71059b988ff0425d\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2025\/\"><strong>Concursos 2025<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Confira neste artigo a diferen\u00e7a entre Soldado de 1\u00aa e de 2\u00aa classe. Entenda o que isso significa dentro dos quadros das pol\u00edcias militares Ol\u00e1, pessoal! Tudo bem? Hoje analisaremos a diferen\u00e7a entre Soldado de 1\u00aa e de 2\u00aa classe. \u200bCertamente o sonho de vestir a farda e servir \u00e0 sociedade \u00e9 o que move [&hellip;]<\/p>\n","protected":false},"author":2974,"featured_media":1649994,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[220188,220189,220186,220187],"tags":[],"tax_estado":[],"class_list":["post-1644901","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policial-agente-penitenciario","category-policial-guarda-civis","category-policial-oficial","category-policial-pracas"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Soldado de 1\u00aa e de 2\u00aa classe<\/title>\n<meta name=\"description\" content=\"Confira neste artigo a diferen\u00e7a entre Soldado de 1\u00aa e de 2\u00aa classe. Entenda o que isso significa dentro dos quadros das pol\u00edcias militares.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/soldado-1a-2a-classe\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Qual \u00e9 a diferen\u00e7a entre Soldado de 1\u00aa e de 2\u00aa Classe?\" \/>\n<meta property=\"og:description\" content=\"Confira neste artigo a diferen\u00e7a entre Soldado de 1\u00aa e de 2\u00aa classe. Entenda o que isso significa dentro dos quadros das pol\u00edcias militares.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/soldado-1a-2a-classe\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-29T11:01:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/09\/04223403\/1000064129.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2038\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edmar Bezerra Araujo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edmar Bezerra Araujo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/soldado-1a-2a-classe\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/soldado-1a-2a-classe\/\"},\"author\":{\"name\":\"Edmar Bezerra Araujo\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/5516090bbe46c1c8aab9a7c5bf8595da\"},\"headline\":\"Qual \u00e9 a diferen\u00e7a entre Soldado de 1\u00aa e de 2\u00aa Classe?\",\"datePublished\":\"2025-10-29T11:01:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/soldado-1a-2a-classe\/\"},\"wordCount\":1020,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/soldado-1a-2a-classe\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/09\/04223403\/1000064129.jpg\",\"articleSection\":[\"Policial (Agente Penitenci\u00e1rio)\",\"Policial (Guardas Civis)\",\"Policial (PM\/BM - Oficial)\",\"Policial (PM\/BM - Pra\u00e7as)\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/soldado-1a-2a-classe\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/soldado-1a-2a-classe\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/soldado-1a-2a-classe\/\",\"name\":\"Soldado de 1\u00aa e de 2\u00aa classe\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/soldado-1a-2a-classe\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/soldado-1a-2a-classe\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/09\/04223403\/1000064129.jpg\",\"datePublished\":\"2025-10-29T11:01:00+00:00\",\"description\":\"Confira neste artigo a diferen\u00e7a entre Soldado de 1\u00aa e de 2\u00aa classe. Entenda o que isso significa dentro dos quadros das pol\u00edcias militares.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/soldado-1a-2a-classe\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/soldado-1a-2a-classe\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/soldado-1a-2a-classe\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/09\/04223403\/1000064129.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/09\/04223403\/1000064129.jpg\",\"width\":2038,\"height\":1080,\"caption\":\"Qual \u00e9 a diferen\u00e7a entre Soldado de 1\u00aa e de 2\u00aa Classe?\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/soldado-1a-2a-classe\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Qual \u00e9 a diferen\u00e7a entre Soldado de 1\u00aa e de 2\u00aa Classe?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/5516090bbe46c1c8aab9a7c5bf8595da\",\"name\":\"Edmar Bezerra Araujo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/3ec0a15819de7eef1b7fcba85aadb329188a10da1e37eb279bb6e0f264e6b9c7?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/3ec0a15819de7eef1b7fcba85aadb329188a10da1e37eb279bb6e0f264e6b9c7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/3ec0a15819de7eef1b7fcba85aadb329188a10da1e37eb279bb6e0f264e6b9c7?s=96&d=mm&r=g\",\"caption\":\"Edmar Bezerra Araujo\"},\"sameAs\":[\"https:\/\/www.instagram.com\/edmarbezerraaraujo\/\"],\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/edmarbezerraaraujogmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Soldado de 1\u00aa e de 2\u00aa classe","description":"Confira neste artigo a diferen\u00e7a entre Soldado de 1\u00aa e de 2\u00aa classe. Entenda o que isso significa dentro dos quadros das pol\u00edcias militares.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/soldado-1a-2a-classe\/","og_locale":"pt_BR","og_type":"article","og_title":"Qual \u00e9 a diferen\u00e7a entre Soldado de 1\u00aa e de 2\u00aa Classe?","og_description":"Confira neste artigo a diferen\u00e7a entre Soldado de 1\u00aa e de 2\u00aa classe. Entenda o que isso significa dentro dos quadros das pol\u00edcias militares.","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/soldado-1a-2a-classe\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2025-10-29T11:01:00+00:00","og_image":[{"width":2038,"height":1080,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/09\/04223403\/1000064129.jpg","type":"image\/jpeg"}],"author":"Edmar Bezerra Araujo","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Edmar Bezerra Araujo","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/soldado-1a-2a-classe\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/soldado-1a-2a-classe\/"},"author":{"name":"Edmar Bezerra Araujo","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/5516090bbe46c1c8aab9a7c5bf8595da"},"headline":"Qual \u00e9 a diferen\u00e7a entre Soldado de 1\u00aa e de 2\u00aa Classe?","datePublished":"2025-10-29T11:01:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/soldado-1a-2a-classe\/"},"wordCount":1020,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/soldado-1a-2a-classe\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/09\/04223403\/1000064129.jpg","articleSection":["Policial (Agente Penitenci\u00e1rio)","Policial (Guardas Civis)","Policial (PM\/BM - Oficial)","Policial (PM\/BM - Pra\u00e7as)"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/soldado-1a-2a-classe\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/soldado-1a-2a-classe\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/soldado-1a-2a-classe\/","name":"Soldado de 1\u00aa e de 2\u00aa classe","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/soldado-1a-2a-classe\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/soldado-1a-2a-classe\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/09\/04223403\/1000064129.jpg","datePublished":"2025-10-29T11:01:00+00:00","description":"Confira neste artigo a diferen\u00e7a entre Soldado de 1\u00aa e de 2\u00aa classe. Entenda o que isso significa dentro dos quadros das pol\u00edcias militares.","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/soldado-1a-2a-classe\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/soldado-1a-2a-classe\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/soldado-1a-2a-classe\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/09\/04223403\/1000064129.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/09\/04223403\/1000064129.jpg","width":2038,"height":1080,"caption":"Qual \u00e9 a diferen\u00e7a entre Soldado de 1\u00aa e de 2\u00aa Classe?"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/soldado-1a-2a-classe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Qual \u00e9 a diferen\u00e7a entre Soldado de 1\u00aa e de 2\u00aa Classe?"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/5516090bbe46c1c8aab9a7c5bf8595da","name":"Edmar Bezerra Araujo","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/3ec0a15819de7eef1b7fcba85aadb329188a10da1e37eb279bb6e0f264e6b9c7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3ec0a15819de7eef1b7fcba85aadb329188a10da1e37eb279bb6e0f264e6b9c7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3ec0a15819de7eef1b7fcba85aadb329188a10da1e37eb279bb6e0f264e6b9c7?s=96&d=mm&r=g","caption":"Edmar Bezerra Araujo"},"sameAs":["https:\/\/www.instagram.com\/edmarbezerraaraujo\/"],"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/edmarbezerraaraujogmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1644901","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/2974"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1644901"}],"version-history":[{"count":6,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1644901\/revisions"}],"predecessor-version":[{"id":1649996,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1644901\/revisions\/1649996"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/1649994"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1644901"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1644901"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1644901"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1644901"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}