{"id":1639760,"date":"2026-05-04T18:24:29","date_gmt":"2026-05-04T21:24:29","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=1639760"},"modified":"2026-05-04T18:24:31","modified_gmt":"2026-05-04T21:24:31","slug":"concurso-pf-ultimas-noticias","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-pf-ultimas-noticias\/","title":{"rendered":"Concurso PF 2026: \u00faltimas not\u00edcias e situa\u00e7\u00e3o hoje\u00a0"},"content":{"rendered":"\n<p><strong><em>Veja a situa\u00e7\u00e3o atual do Concurso PF e PF Administrativo e fique por dentro das \u00faltimas informa\u00e7\u00f5es sobre um dos certames mais desejados dos \u00faltimos anos<\/em><\/strong><\/p>\n\n\n\n<p>Com as \u00faltimas edi\u00e7\u00f5es realizadas em 2025, a PF e a PF Administrativo ainda seguem sendo os concursos mais desejados por aqueles que pretendem ingressar na \u00e1rea de seguran\u00e7a p\u00fablica. Afinal, a Pol\u00edcia Federal e a Pol\u00edcia Federal Administrativa oferecem sal\u00e1rios atrativos e progress\u00e3o de carreira.<\/p>\n\n\n\n<p>Atualmente, o <strong>concurso da PF est\u00e1 em andamento, j\u00e1 da PF Administrativo foi homologado e est\u00e1 v\u00e1lido at\u00e9 2027<\/strong>.<\/p>\n\n\n\n<p>Para te ajudar a ficar por dentro das informa\u00e7\u00f5es mais importantes, o <strong>blog Estrat\u00e9gia Concursos<\/strong> listou as <strong>\u00faltimas not\u00edcias do Concurso PF e PF Administrativo<\/strong>, al\u00e9m de verificar qual \u00e9 a situa\u00e7\u00e3o do novo certame hoje:&nbsp;<\/p>\n\n\n\n<div class=\"container\" id=\"boxes\">\r\n  <div class=\"row\">\r\n\r\n    <div class=\"col-sm\">\r\n      <div class=\"banner-policia-federal\" id=\"box-assinatura\">\r\n        <h2 class=\"titulo-assinatura\">Concurso Pol\u00edcia Federal<\/h2>\r\n        <p class=\"subtitulo-assinatura\">Trilhe o caminho rumo \u00e0 aprova\u00e7\u00e3o na PF!<\/p>\r\n        <div class=\"box-botao\">\r\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/cursosPorConcurso\/cursos-para-policia-federal\/\" role=\"button\" rel=\"noopener noreferrer\">VER CURSOS<\/a>\r\n        <\/div>\r\n      <\/div>\r\n     \r\n    <\/div>\r\n\r\n  <\/div>\r\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-ultimas-noticias-sobre-o-concurso-pf-2026\">\u00daltimas not\u00edcias sobre o Concurso PF 2026<\/h2>\n\n\n\n<p>Confira abaixo as informa\u00e7\u00f5es mais recentes sobre o certame da PF e PF Administrativo:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-ministra-confirma-convocacao-de-1-5-mil-excedentes-da-pf\">Ministra confirma convoca\u00e7\u00e3o de 1,5 mil excedentes da PF!<\/h3>\n\n\n\n<p><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/diogo-mendesestrategiaconcursos-com-br\/\"><\/a>A ministra Esther Dweck confirmou nesta quinta-feira (2) a <a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-pf-ministra-excedentes\/\" target=\"_blank\" rel=\"noreferrer noopener\">convoca\u00e7\u00e3o de\u00a0<strong>1,5 mil excedentes\u00a0<\/strong>no\u00a0<strong>concurso PF<\/strong><\/a>. A chamada de mil aprovados deve ocorrer de forma imediata e mais 500 ao longo do ano!<\/p>\n\n\n\n<p>A declara\u00e7\u00e3o foi feita durante entrevista ao programa&nbsp;<em>\u201cBom Dia, Ministra\u201d<\/em>, e refor\u00e7a o movimento do governo federal para recompor o efetivo da corpora\u00e7\u00e3o.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-cargos-do-concurso-pf-serao-preenchidos\">Cargos do Concurso PF ser\u00e3o preenchidos!<\/h3>\n\n\n\n<p>A Pol\u00edcia Federal anunciou a inten\u00e7\u00e3o de avan\u00e7ar para o <a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-pf-mgi-nega-pedidos-excedentes\/\" target=\"_blank\" rel=\"noreferrer noopener\">preenchimento integral dos cargos vagos<\/a>, com a meta de recompor todo o efetivo das carreiras da institui\u00e7\u00e3o.<\/p>\n\n\n\n<p>O an\u00fancio foi feito pelo diretor-geral da corpora\u00e7\u00e3o, Andrei Augusto Passos Rodrigues, durante a cerim\u00f4nia de comemora\u00e7\u00e3o dos 82 anos da Pol\u00edcia Federal.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-mgi-nega-pedidos-de-excedentes-da-pf\">MGI nega pedidos de excedentes da PF<\/h3>\n\n\n\n<p>O<a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-pf-mgi-nega-pedidos-excedentes\/\" target=\"_blank\" rel=\"noreferrer noopener\"> governo federal negou os pedidos de autoriza\u00e7\u00e3o para convoca\u00e7\u00e3o<\/a> de&nbsp;<strong>1.456 excedentes no concurso da Pol\u00edcia Federal.<\/strong><\/p>\n\n\n\n<p>As solicita\u00e7\u00f5es foram formalizadas pelo Minist\u00e9rio da Justi\u00e7a e Seguran\u00e7a P\u00fablica em 20 de mar\u00e7o, por meio de dois of\u00edcios encaminhados ao Minist\u00e9rio da Gest\u00e3o e da Inova\u00e7\u00e3o em Servi\u00e7os P\u00fablicos (MGI).<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-novas-convocacoes-e-resultados-do-concurso-pf\">Novas convoca\u00e7\u00f5es e resultados do Concurso PF<\/h3>\n\n\n\n<p>Nesta segunda-feira (2), foram divulgados <a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-pf-novos-resultados-convocacoes-2026\/\" type=\"link\" id=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-pf-novos-resultados-convocacoes-2026\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>novos resultados e convoca\u00e7\u00f5es referentes ao certame<\/strong><\/a>, trazendo atualiza\u00e7\u00f5es importantes para quem segue na disputa por uma das vagas na PF. <\/p>\n\n\n\n<p> O documento, publicado no DOU, contempla a rela\u00e7\u00e3o definitiva da Avalia\u00e7\u00e3o Psicol\u00f3gica para os cargos de <strong>Delegado<\/strong>, <strong>Escriv\u00e3o<\/strong>, <strong>Perito<\/strong> e <strong>Papiloscopista<\/strong>, al\u00e9m do resultado final do procedimento de heteroidentifica\u00e7\u00e3o para esses mesmos cargos. Tamb\u00e9m foi divulgado o resultado final da primeira etapa para<strong> Escriv\u00e3o<\/strong> e <strong>Papiloscopista<\/strong>, bem como a convoca\u00e7\u00e3o para a Avalia\u00e7\u00e3o de T\u00edtulos destinada aos candidatos aos cargos de Delegado e Perito, fase essencial para a classifica\u00e7\u00e3o final desses concorrentes.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-diretor-reforca-pedido-para-convocar-excedentes-do-concurso-pf\">Diretor refor\u00e7a pedido para convocar excedentes do Concurso PF<\/h3>\n\n\n\n<p>A Pol\u00edcia Federal refor\u00e7ou, junto ao Minist\u00e9rio da Justi\u00e7a e Seguran\u00e7a P\u00fablica, o pedido para&nbsp;<strong><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-pf-diretor-reforca-pedido-excedentes\/\" target=\"_blank\" rel=\"noreferrer noopener\">autoriza\u00e7\u00e3o de aproveitamento de at\u00e9 1.456 candidatos aprovados<\/a><\/strong>&nbsp;no concurso p\u00fablico PF.<\/p>\n\n\n\n<p>A solicita\u00e7\u00e3o consta no&nbsp;<strong>Of\u00edcio n\u00ba 123\/2026\/SEAPRO\/GAB\/PF<\/strong>, assinado pelo Diretor-Geral da PF, Andrei Augusto Passos Rodrigues, tratando da edi\u00e7\u00e3o de decreto que permita a nomea\u00e7\u00e3o dos aprovados dentro do limite de vagas.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-concurso-pf-administrativo-e-homologado\">Concurso PF Administrativo \u00e9 homologado<\/h3>\n\n\n\n<p>Com seu resultado devidamente homologado, a&nbsp;<strong>sele\u00e7\u00e3o seguir\u00e1 v\u00e1lida at\u00e9 outubro de 2027<\/strong>, podendo o prazo ser prorrogado uma \u00fanica vez, por igual per\u00edodo.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Concurso PF divulga novos resultados e convoca\u00e7\u00f5es<\/h3>\n\n\n\n<p>Foi divulgado no dia 1\u00ba de dezembro <a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-pf-novos-resultados-convocacoes\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>novos resultados e convoca\u00e7\u00f5es do<\/strong>&nbsp;<strong>concurso PF 2025<\/strong><\/a>.<\/p>\n\n\n\n<p>De acordo com o documento publicado, s\u00e3o divulgados os&nbsp;<strong>resultados finais de avalia\u00e7\u00e3o m\u00e9dica e avalia\u00e7\u00e3o biopsicossocial<\/strong>, bem como as convoca\u00e7\u00f5es para Convoca\u00e7\u00e3o: avalia\u00e7\u00e3o psicol\u00f3gica, procedimento de heteroidentifica\u00e7\u00e3o e desempate de notas na primeira etapa (somente para Agente).<a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/diogo-mendesestrategiaconcursos-com-br\/\"><\/a><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-pf-tem-mais-de-2-mil-cargos-vagos\">PF tem mais de 2 mil cargos vagos<\/h3>\n\n\n\n<p>Dados recentes, obtidos pelo jornalismo do Estrat\u00e9gia Concursos, apontam que a&nbsp;<strong><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-pf-2025-2-mil-cargos-vagos\/\" target=\"_blank\" rel=\"noreferrer noopener\">Pol\u00edcia Federal&nbsp;conta com&nbsp;2.230 cargos vagos<\/a>.<\/strong><\/p>\n\n\n\n<p>O cargo com mais d\u00e9ficit \u00e9 o de Agente de Pol\u00edcia Federal, com 1.421 fun\u00e7\u00f5es vagas, seguido por Escriv\u00e3o e Delegado, sendo 444 e 337 vac\u00e2ncias, respectivamente.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-diretor-geral-fala-em-dobrar-o-efetivo-da-pf\">Diretor-geral fala em dobrar o efetivo da PF<\/h3>\n\n\n\n<p>Em depoimento \u00e0 CPI do Crime Organizado, o diretor-geral da Pol\u00edcia Federal, Andrei Rodrigues, afirmou que o&nbsp;<strong><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-pf-diretor-geral-dobrar-efetivo\/\" target=\"_blank\" rel=\"noreferrer noopener\">efetivo da PF precisa dobrar<\/a> para garantir um atendimento mais eficaz \u00e0 popula\u00e7\u00e3o<\/strong>.<\/p>\n\n\n\n<p>Rodrigues ressaltou que, embora a PF disponha de cerca de 13 mil policiais e outros 2 mil servidores administrativos, o contingente ainda n\u00e3o acompanha o aumento das demandas na \u00e1rea de seguran\u00e7a p\u00fablica.<\/p>\n\n\n\n<p>\u201c<em>Nosso efetivo \u00e9 diminuto, somos menos de 13 mil policiais. Temos cerca de 2 mil servidores administrativos. Estamos fazendo isso que se chama estudo de dimensionamento de trabalho, um estudo t\u00e9cnico, para chegarmos a um n\u00famero ideal. Hoje, eu estimo que precisar\u00edamos ter o dobro do efetivo para atender com ainda mais efici\u00eancia tudo aquilo o que a gente faz<\/em>\u201c, disse Andrei.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-ministro-quer-novas-gratificacoes-para-pf\">Ministro quer novas gratifica\u00e7\u00f5es para PF<\/h3>\n\n\n\n<p>O ministro da Justi\u00e7a e Seguran\u00e7a P\u00fablica, Ricardo Lewandowski, apresentou um <strong>projeto de lei<\/strong> que visa instituir o Fundo Nacional de Combate ao Crime Organizado, que prev\u00ea, entre outras medidas, a concess\u00e3o de <a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/ministro-gratificacoes-policiais-federais\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>gratifica\u00e7\u00f5es para policiai<\/strong><\/a><strong><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/ministro-gratificacoes-policiais-federais\/\" target=\"_blank\" rel=\"noreferrer noopener\">s da Pol\u00edcia Federal (PF), Pol\u00edcia Rodovi\u00e1ria Federal (PRF) e Pol\u00edcia Penal Federal (PPF)<\/a>.<\/strong><\/p>\n\n\n\n<p>De acordo com a proposta, os policiais dessas corpora\u00e7\u00f5es, inclusive os aposentados, <strong>poder\u00e3o receber b\u00f4nus por efici\u00eancia e m\u00e9rito<\/strong>, como forma de reconhecer suas atua\u00e7\u00f5es em opera\u00e7\u00f5es de alto risco e para aumentar a motiva\u00e7\u00e3o funcional.<\/p>\n\n\n\n<p>O novo fundo tamb\u00e9m dever\u00e1 financiar iniciativas de enfrentamento ao crime organizado, direcionando recursos para opera\u00e7\u00f5es conjuntas e estrat\u00e9gias integradas entre as for\u00e7as de seguran\u00e7a.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-diretores-sinalizam-novos-editais-da-prf-e-pf\">Diretores sinalizam novos editais da PRF e PF<\/h3>\n\n\n\n<p>Novos concursos da PF e PRF em vista? Segundo os diretores-gerais Ant\u00f4nio Oliveira e Andrei Rodrigues, detalhes in\u00e9ditos podem surgir!<\/p>\n\n\n\n<p>Ambos estiveram na audi\u00eancia p\u00fablica \u201cIntegra\u00e7\u00e3o interag\u00eancias no sistema nacional de seguran\u00e7a p\u00fablica\u201d, realizada na C\u00e2mara dos Deputados no dia 03 de novembro.<\/p>\n\n\n\n<p>No encontro, o diretor da PRF, Ant\u00f4nio Oliveira, disse que, em caso de aprova\u00e7\u00e3o da PEC que cria o sistema \u00fanico de Seguran\u00e7a P\u00fablica no Brasil, o ministro da Justi\u00e7a Ricardo Lewandovski sinalizou que um&nbsp;<strong><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-prf-pf-novos-editais\/\" target=\"_blank\" rel=\"noreferrer noopener\">novo concurso seria realizado para a amplia\u00e7\u00e3o do efetivo<\/a><\/strong>.<\/p>\n\n\n\n<p>J\u00e1 o diretor da PF, Andrei Rodrigues, voltou a mencionar a<strong>&nbsp;convoca\u00e7\u00e3o de 2 mil aprovados&nbsp;<\/strong>do \u00faltimo concurso p\u00fablico, com resultados j\u00e1 divulgados.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-concurso-pf-administrativo-e-homologado-0\">Concurso PF Administrativo \u00e9 homologado<\/h3>\n\n\n\n<p>&nbsp;Os resultados definitivos da avalia\u00e7\u00e3o biopsicossocial, do procedimento de heteroidentifica\u00e7\u00e3o e a&nbsp;<strong>classifica\u00e7\u00e3o final<\/strong>&nbsp;<strong>do concurso p\u00fablico PF Administrativo<\/strong><\/p>\n\n\n\n<p>Com isso, o&nbsp;<strong><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-pf-administrativo-homologado\/\" target=\"_blank\" rel=\"noreferrer noopener\">concurso PF Administrativo fica devidamente homologado<\/a><\/strong>. A validade ser\u00e1 de dois anos, at\u00e9 outubro de 2027, podendo o prazo ser prorrogado, uma \u00fanica vez, por igual per\u00edodo.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-pf-pode-ter-concurso-recorrente\">PF pode ter concurso recorrente<a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/diogo-mendesestrategiaconcursos-com-br\/\"><\/a><\/h3>\n\n\n\n<p>A C\u00e2mara dos Deputados dever\u00e1 pautar em breve o&nbsp;<strong><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-pf-recorrente-vacancia-5\/\" target=\"_blank\" rel=\"noreferrer noopener\">projeto de lei que prev\u00ea a realiza\u00e7\u00e3o autom\u00e1tica do concurso PF<\/a> <\/strong>sempre que&nbsp;<strong>mais de 5% dos cargos estiverem vagos<\/strong>.<\/p>\n\n\n\n<p>A proposta tem o objetivo de garantir a&nbsp;<strong>reposi\u00e7\u00e3o constante de servidores<\/strong>&nbsp;na institui\u00e7\u00e3o e j\u00e1 passou pelo&nbsp;<strong>Senado Federal<\/strong>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-resultado-definitivo-do-taf-da-pf-2025-e-publicado\">Resultado definitivo do TAF da PF 2025 \u00e9 publicado<\/h3>\n\n\n\n<p>Foi divulgado no dia 3 de outubro<strong>&nbsp;o <\/strong><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-pf-2025-resultado-definitivo-taf\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>resultado definitivo da prova de aptid\u00e3o f\u00edsica<\/strong>&nbsp;do&nbsp;<strong>concurso p\u00fablico da Pol\u00edcia Federal<\/strong><\/a>.<\/p>\n\n\n\n<p>Al\u00e9m disso, est\u00e3o dispon\u00edveis o resultado final no preenchimento da FIC, a convoca\u00e7\u00e3o para a avalia\u00e7\u00e3o m\u00e9dica e a convoca\u00e7\u00e3o para a avalia\u00e7\u00e3o biopsicossocial dos candidatos que solicitaram concorrer \u00e0s vagas reservadas \u00e0s pessoas com defici\u00eancia.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong><a href=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/10\/03154812\/taf-definitivo-resultado-pf-2025.pdf\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Veja aqui o resultado definitivo do TAF do Concurso PF 2025<\/a><\/strong><\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-resultados-provisorios-do-concurso-pf-administrativo-divulgados\">Resultados provis\u00f3rios do Concurso PF Administrativo divulgados<\/h3>\n\n\n\n<p>Foram divulgados no dia 29 de setembro os resultados provis\u00f3rios das etapas de avalia\u00e7\u00e3o biopsicossocial e heteroidentifica\u00e7\u00e3o do&nbsp;<strong>Concurso PF Administrativo<\/strong>.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Resultados provis\u00f3rios<\/strong>:&nbsp;<a href=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/09\/29111910\/edital-no-8-pf-administrativo-de-25-de-setembro-de-2025-edital-no-8-pf-administrativo-de-25-de-setembro-de-2025-dou-imprensa-nacional-1.pdf\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">avalia\u00e7\u00e3o biopsicossocial \/ heteroidentifica\u00e7\u00e3o<\/a><\/li>\n<\/ul>\n\n\n\n<p>Os interessados poder\u00e3o ingressar com recursos contra os resultados at\u00e9 \u00e0s&nbsp;<strong>18h do dia 30 de setembro<\/strong>, no site da banca organizadora, Cebraspe.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-veja-resultado-do-taf-do-concurso-pf-2025\">Veja resultado do TAF do Concurso PF 2025<\/h3>\n\n\n\n<p>Foi divulgado no dia 23 de setembro <strong>o resultado preliminar da prova de aptid\u00e3o f\u00edsica<\/strong>&nbsp;do&nbsp;<strong>concurso p\u00fablico da Pol\u00edcia Federal<\/strong>.<\/p>\n\n\n\n<p>Aqueles que n\u00e3o concordarem com as informa\u00e7\u00f5es podem solicitar a&nbsp;<strong>interposi\u00e7\u00e3o de recursos<\/strong>&nbsp;contra os resultados e ter acesso ao espelho de avalia\u00e7\u00e3o&nbsp;<strong>nos dias 24 e 25 de setembro<\/strong>, pelo&nbsp;<a href=\"https:\/\/www.cebraspe.org.br\/concursos\/pf_25\" target=\"_blank\" rel=\"noreferrer noopener\">site do Cebraspe<\/a>.<\/p>\n\n\n\n<p>No mesmo per\u00edodo, estar\u00e1 dispon\u00edvel a grava\u00e7\u00e3o em v\u00eddeo dos testes aos candidatos inaptos e desistentes. J\u00e1 as candidatas gestantes devem encaminhar um novo laudo m\u00e9dico, com a data do parto ou do fim do per\u00edodo gestacional (no caso de aborto).<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-nova-retificacao-do-concurso-pf-2025-e-publicada\">Nova retifica\u00e7\u00e3o do Concurso PF 2025 \u00e9 publicada<\/h3>\n\n\n\n<p>A Pol\u00edcia Federal fez uma <a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-pf-2025-nova-retificacao-avaliacao-medica\/\" target=\"_blank\" rel=\"noreferrer noopener\">nova retifica\u00e7\u00e3o referente ao <strong>Concurso PF 2025<\/strong> para os cargos de&nbsp;Delegado<strong>,&nbsp;<\/strong>Perito Criminal, Escriv\u00e3o, Agente e Papiloscopista<\/a>. As mudan\u00e7as constam em publica\u00e7\u00e3o no Di\u00e1rio Oficial da Uni\u00e3o desta quarta-feira, 17 de setembro.<\/p>\n\n\n\n<p>O documento altera diversos pontos do Anexo IV do <strong>edital PF 2025<\/strong>, especialmente relacionados \u00e0 avalia\u00e7\u00e3o m\u00e9dica dos candidatos.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-saiu-a-convocacao-do-taf-do-concurso-pf-2025\">Saiu a convoca\u00e7\u00e3o do TAF do Concurso PF 2025<\/h3>\n\n\n\n<p>Foi divulgada no dia 5 de setembro<strong>&nbsp;a <\/strong><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-pf-2025-convocacao-taf-orientacoes\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>convoca\u00e7\u00e3o da prova de aptid\u00e3o f\u00edsica<\/strong>&nbsp;do&nbsp;<strong>concurso p\u00fablico da Pol\u00edcia Federal<\/strong><\/a> 2025.<\/p>\n\n\n\n<p>Segundo o documento, a&nbsp;<strong>etapa \u00e9 prevista nos dias 13 e 14 de setembro<\/strong>&nbsp;e o candidato convocado poder\u00e1 consultar o hor\u00e1rio e local de realiza\u00e7\u00e3o da etapa a partir de 8 de setembro, pelo&nbsp;site do Cebraspe.<\/p>\n\n\n\n<p>O atestado m\u00e9dico dever\u00e1 ser apresentado com data de emiss\u00e3o a partir do dia 29 de agosto (para os convocados em 13 de setembro) e a partir do dia 30 de agosto (para os convocados em 14 de setembro). Vale ressaltar que o atestado m\u00e9dico n\u00e3o ser\u00e1 devolvido.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-novos-resultados-do-concurso-pf-administrativo-2025-sao-divulgados\">Novos resultados do Concurso PF Administrativo 2025 s\u00e3o divulgados<\/h3>\n\n\n\n<p>Foram divulgados no dia 02 de setembro os<strong>&nbsp;resultados finais da prova discursiva<\/strong>, al\u00e9m da <a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-pf-administrativo-novos-resultados-convocacoes\/\" target=\"_blank\" rel=\"noreferrer noopener\">convoca\u00e7\u00e3o para a avalia\u00e7\u00e3o biopsicossocial e para procedimento de heteroidentifica\u00e7\u00e3o do&nbsp;<strong>concurso Pol\u00edcia Federal Administrativo<\/strong><\/a>.<\/p>\n\n\n\n<p>O&nbsp;edital&nbsp;de resultados provis\u00f3rios na avalia\u00e7\u00e3o biopsicossocial e do procedimento de heteroidentifica\u00e7\u00e3o ser\u00e1 publicado na data prov\u00e1vel de&nbsp;<strong>26 de setembro de&nbsp;2025<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-qual-e-a-situacao-do-concurso-pf-hoje\">Qual \u00e9 a situa\u00e7\u00e3o do Concurso PF hoje?<\/h2>\n\n\n\n<p><em>Atualiza\u00e7\u00e3o em 06\/04\/2026:<\/em> <strong>os editais dos Concurso PF e PF Administrativo seguem em andamento e n\u00e3o h\u00e1 previs\u00e3o novos certames<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-quando-foi-o-ultimo-edital-da-pf\">Quando foi o \u00faltimo edital da PF?<\/h2>\n\n\n\n<p>Publicado no ano de 2025, o <a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-pf-edital-publicado-2025\/\" target=\"_blank\" rel=\"noreferrer noopener\">\u00faltimo edital da PF<\/a> ofertou 1.000 mil vagas para os cargos de Agente, Escriv\u00e3o, Perito, Delegado e Papiloscopistas, sal\u00e1rios iniciais que variam de&nbsp;<strong>R$ 14.164,81 a R$ 26.800,00<\/strong>. Era esperado um novo edital para 2026, por\u00e9m a <a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-pf-2026-previsao-edital-e-excedentes\/\" target=\"_blank\" rel=\"noreferrer noopener\">Pol\u00edcia Federal voltou atr\u00e1s e chamar\u00e1 mais 1.000 candidatos excedentes<\/a>.<\/p>\n\n\n\n<p>J\u00e1 o <a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-pf-administrativo-2025-edital-publicado\/\" target=\"_blank\" rel=\"noreferrer noopener\">\u00faltimo Concurso PF Administrativo<\/a> ocorreu tamb\u00e9m em 2025, com 192 vagas imediatas de n\u00edvel m\u00e9dio e superior, sendo o sal\u00e1rio inicial entre R$ 7.605,31 a R$ 11.070,93.<\/p>\n\n\n\n<p class=\"has-text-align-center\"><em>Para mais informa\u00e7\u00f5es do concurso Pol\u00edcia Federal, acesse o link abaixo!<\/em><\/p>\n\n\n\n<p class=\"has-text-align-center has-cyan-bluish-gray-background-color has-background has-medium-font-size\"><strong>Saiba mais: <a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-policia-federal\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concurso PF<\/a><\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"h-quer-saber-tudo-sobre-concursos-da-pf-confira-nossos-artigos\">Quer saber tudo sobre concursos da PF?<br \/>Confira nossos artigos!<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-pf-administrativo\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concurso PF Administrativo<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2026\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos 2026<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos abertos<\/a><\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"h-quer-estudar-para-o-concurso-pf\">Quer estudar para o concurso PF?<\/h2>\n\n\n\n<div class=\"container\" id=\"boxes\">\r\n  <div class=\"row\">\r\n\r\n    <div class=\"col-sm\">\r\n      <div class=\"estrategia\" id=\"box-assinatura\">\r\n        <h3 class=\"titulo-assinatura\">Assinatura Concursos<\/h3>\r\n        <p class=\"subtitulo-assinatura\">Assinatura de 1 ano ou 2 anos<\/p>\r\n        <div class=\"box-botao\">\r\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/assinaturas\/\" role=\"button\" rel=\"noopener noreferrer\">ASSINE AGORA<\/a>\r\n        <\/div>\r\n      <\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Veja a situa\u00e7\u00e3o atual do Concurso PF e PF Administrativo e fique por dentro das \u00faltimas informa\u00e7\u00f5es sobre um dos certames mais desejados dos \u00faltimos anos Com as \u00faltimas edi\u00e7\u00f5es realizadas em 2025, a PF e a PF Administrativo ainda seguem sendo os concursos mais desejados por aqueles que pretendem ingressar na \u00e1rea de seguran\u00e7a [&hellip;]<\/p>\n","protected":false},"author":2283,"featured_media":1418953,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1988,220219],"tags":[],"tax_estado":[],"class_list":["post-1639760","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policia","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Concurso PF 2026: \u00faltimas not\u00edcias e situa\u00e7\u00e3o hoje\u00a0<\/title>\n<meta name=\"description\" content=\"Veja a situa\u00e7\u00e3o atual do Concurso PF e PF Administrativo e fique por dentro das \u00faltimas not\u00edcias sobre um dos certames mais concorridos\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-pf-ultimas-noticias\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Concurso PF 2026: \u00faltimas not\u00edcias e situa\u00e7\u00e3o hoje\u00a0\" \/>\n<meta property=\"og:description\" content=\"Veja a situa\u00e7\u00e3o atual do Concurso PF e PF Administrativo e fique por dentro das \u00faltimas not\u00edcias sobre um dos certames mais concorridos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-pf-ultimas-noticias\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-04T21:24:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-04T21:24:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/06\/21170337\/policia-federal-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"432\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Isabela Giordan\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Isabela Giordan\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-pf-ultimas-noticias\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-pf-ultimas-noticias\/\"},\"author\":{\"name\":\"Isabela Giordan\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/730be6d1244f83410618206c68a00721\"},\"headline\":\"Concurso PF 2026: \u00faltimas not\u00edcias e situa\u00e7\u00e3o hoje\u00a0\",\"datePublished\":\"2026-05-04T21:24:29+00:00\",\"dateModified\":\"2026-05-04T21:24:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-pf-ultimas-noticias\/\"},\"wordCount\":2000,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-pf-ultimas-noticias\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/06\/21170337\/policia-federal-1.png\",\"articleSection\":[\"Policial (Agente, Escriv\u00e3o e Investigador)\",\"\u00daltimas not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-pf-ultimas-noticias\/#respond\"]}],\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-pf-ultimas-noticias\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-pf-ultimas-noticias\/\",\"name\":\"Concurso PF 2026: \u00faltimas not\u00edcias e situa\u00e7\u00e3o hoje\u00a0\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-pf-ultimas-noticias\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-pf-ultimas-noticias\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/06\/21170337\/policia-federal-1.png\",\"datePublished\":\"2026-05-04T21:24:29+00:00\",\"dateModified\":\"2026-05-04T21:24:31+00:00\",\"description\":\"Veja a situa\u00e7\u00e3o atual do Concurso PF e PF Administrativo e fique por dentro das \u00faltimas not\u00edcias sobre um dos certames mais concorridos\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-pf-ultimas-noticias\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-pf-ultimas-noticias\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-pf-ultimas-noticias\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/06\/21170337\/policia-federal-1.png\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/06\/21170337\/policia-federal-1.png\",\"width\":768,\"height\":432,\"caption\":\"Concurso PF\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-pf-ultimas-noticias\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Concurso PF 2026: \u00faltimas not\u00edcias e situa\u00e7\u00e3o hoje\u00a0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/730be6d1244f83410618206c68a00721\",\"name\":\"Isabela Giordan\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/3e4342ae22c6e323159ff8e4c177ec0c1cb62151515f0824588c29ac78df73ec?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/3e4342ae22c6e323159ff8e4c177ec0c1cb62151515f0824588c29ac78df73ec?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/3e4342ae22c6e323159ff8e4c177ec0c1cb62151515f0824588c29ac78df73ec?s=96&d=mm&r=g\",\"caption\":\"Isabela Giordan\"},\"description\":\"Jornalista formada pela Universidade Estadual J\u00falio de Mesquita Filho (Unesp) e com atua\u00e7\u00e3o exclusiva na \u00e1rea da educa\u00e7\u00e3o e de concursos p\u00fablicos h\u00e1 quase 10 anos. Atua como Especialista de SEO e Jornalista no Estrat\u00e9gia Concursos.\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/isabela-giordanestrategiavestibulares-com-br\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Concurso PF 2026: \u00faltimas not\u00edcias e situa\u00e7\u00e3o hoje\u00a0","description":"Veja a situa\u00e7\u00e3o atual do Concurso PF e PF Administrativo e fique por dentro das \u00faltimas not\u00edcias sobre um dos certames mais concorridos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-pf-ultimas-noticias\/","og_locale":"pt_BR","og_type":"article","og_title":"Concurso PF 2026: \u00faltimas not\u00edcias e situa\u00e7\u00e3o hoje\u00a0","og_description":"Veja a situa\u00e7\u00e3o atual do Concurso PF e PF Administrativo e fique por dentro das \u00faltimas not\u00edcias sobre um dos certames mais concorridos","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-pf-ultimas-noticias\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2026-05-04T21:24:29+00:00","article_modified_time":"2026-05-04T21:24:31+00:00","og_image":[{"width":768,"height":432,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/06\/21170337\/policia-federal-1.png","type":"image\/png"}],"author":"Isabela Giordan","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Isabela Giordan","Est. tempo de leitura":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-pf-ultimas-noticias\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-pf-ultimas-noticias\/"},"author":{"name":"Isabela Giordan","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/730be6d1244f83410618206c68a00721"},"headline":"Concurso PF 2026: \u00faltimas not\u00edcias e situa\u00e7\u00e3o hoje\u00a0","datePublished":"2026-05-04T21:24:29+00:00","dateModified":"2026-05-04T21:24:31+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-pf-ultimas-noticias\/"},"wordCount":2000,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-pf-ultimas-noticias\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/06\/21170337\/policia-federal-1.png","articleSection":["Policial (Agente, Escriv\u00e3o e Investigador)","\u00daltimas not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-pf-ultimas-noticias\/#respond"]}],"copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-pf-ultimas-noticias\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-pf-ultimas-noticias\/","name":"Concurso PF 2026: \u00faltimas not\u00edcias e situa\u00e7\u00e3o hoje\u00a0","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-pf-ultimas-noticias\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-pf-ultimas-noticias\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/06\/21170337\/policia-federal-1.png","datePublished":"2026-05-04T21:24:29+00:00","dateModified":"2026-05-04T21:24:31+00:00","description":"Veja a situa\u00e7\u00e3o atual do Concurso PF e PF Administrativo e fique por dentro das \u00faltimas not\u00edcias sobre um dos certames mais concorridos","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-pf-ultimas-noticias\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-pf-ultimas-noticias\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-pf-ultimas-noticias\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/06\/21170337\/policia-federal-1.png","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/06\/21170337\/policia-federal-1.png","width":768,"height":432,"caption":"Concurso PF"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-pf-ultimas-noticias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Concurso PF 2026: \u00faltimas not\u00edcias e situa\u00e7\u00e3o hoje\u00a0"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/730be6d1244f83410618206c68a00721","name":"Isabela Giordan","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/3e4342ae22c6e323159ff8e4c177ec0c1cb62151515f0824588c29ac78df73ec?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3e4342ae22c6e323159ff8e4c177ec0c1cb62151515f0824588c29ac78df73ec?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3e4342ae22c6e323159ff8e4c177ec0c1cb62151515f0824588c29ac78df73ec?s=96&d=mm&r=g","caption":"Isabela Giordan"},"description":"Jornalista formada pela Universidade Estadual J\u00falio de Mesquita Filho (Unesp) e com atua\u00e7\u00e3o exclusiva na \u00e1rea da educa\u00e7\u00e3o e de concursos p\u00fablicos h\u00e1 quase 10 anos. Atua como Especialista de SEO e Jornalista no Estrat\u00e9gia Concursos.","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/isabela-giordanestrategiavestibulares-com-br\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1639760","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/2283"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1639760"}],"version-history":[{"count":19,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1639760\/revisions"}],"predecessor-version":[{"id":1759807,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1639760\/revisions\/1759807"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/1418953"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1639760"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1639760"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1639760"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1639760"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}