{"id":1630659,"date":"2025-09-20T08:06:00","date_gmt":"2025-09-20T11:06:00","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=1630659"},"modified":"2025-09-24T19:32:51","modified_gmt":"2025-09-24T22:32:51","slug":"estatuto-dos-funcionarios-publicos-tjsp","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/estatuto-dos-funcionarios-publicos-tjsp\/","title":{"rendered":"Estatuto dos Funcion\u00e1rios P\u00fablicos do Estado de S\u00e3o Paulo para o TJSP\u00a0"},"content":{"rendered":"\n<p>Neste artigo voc\u00ea encontrar\u00e1 um resumo de pontos importantes da Lei n\u00ba 10.261\/68, que institui o Estatuto dos Funcion\u00e1rios P\u00fablicos do Estado de S\u00e3o Paulo.\u00a0<\/p>\n\n\n\n<p>Ol\u00e1, concurseiro, tudo bem com voc\u00ea? Estudando muito para o concurso do <a href=\"https:\/\/www.tjsp.jus.br\/\" target=\"_blank\" rel=\"noreferrer noopener\">Tribunal de Justi\u00e7a de S\u00e3o Paulo<\/a>? Certamente sim! Afinal, essa \u00e9 uma grande oportunidade de ser tornar servidor em um dos \u00f3rg\u00e3os mais cobi\u00e7ados do Judici\u00e1rio.\u00a0<\/p>\n\n\n\n<p>Para auxiliar voc\u00ea nessa miss\u00e3o, elaboramos um resumo de pontos importantes da <strong>Lei n\u00ba 10.261\/68<\/strong>, o <strong>Estatuto dos Funcion\u00e1rios P\u00fablicos do Estado de S\u00e3o Paulo<\/strong>.\u00a0<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-consideracoes-iniciais\">Considera\u00e7\u00f5es Iniciais\u00a0<\/h2>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"268\" height=\"183\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/08\/06114703\/se-liga.png\" alt=\"aten\u00e7\u00e3o\" class=\"wp-image-1619053\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/08\/06114703\/se-liga.png 268w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/08\/06114703\/se-liga-150x102.png 150w\" sizes=\"auto, (max-width: 268px) 100vw, 268px\" \/><\/figure>\n\n\n\n<p>Primeiramente, vale ressaltar que a <strong>Lei n\u00ba 10.261\/68 <\/strong>que institui o\u00a0<strong>Estatuto dos Funcion\u00e1rios P\u00fablicos do Estado de S\u00e3o Paulo<\/strong>\u00a0\u00e9 uma lei bastante antiga, do ano de 1968 e que, por conta disso, nela encontramos termos em desuso no contexto atual, mas que, por vezes, traremos aqui por se tratar da literalidade do dispositivo legal.\u00a0<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-o-regime-estatutario\">O regime estatut\u00e1rio\u00a0<\/h3>\n\n\n\n<p>Conforme a Lei n\u00ba 10.261\/68, <strong>funcion\u00e1rio p\u00fablico \u00e9 a pessoa legalmente investida em cargo p\u00fablico. <\/strong>Desse modo, \u00e9 importante frisar que as disposi\u00e7\u00f5es contidas no estatuto em an\u00e1lise s\u00e3o dirigidas aos <strong>funcion\u00e1rios p\u00fablicos estatut\u00e1rios, <\/strong>sejam eles efetivos ou comissionados.\u00a0<\/p>\n\n\n\n<p>O artigo 2\u00ba do dispositivo legal em an\u00e1lise afirma que as disposi\u00e7\u00f5es da lei <strong>n\u00e3o <\/strong>se aplicam aos <strong>empregados <\/strong>das autarquias, entidades paraestatais e servi\u00e7os p\u00fablicos de natureza industrial, ressalvada a situa\u00e7\u00e3o daqueles que, por lei anterior, j\u00e1 tenham a qualidade de <strong>funcion\u00e1rio p\u00fablico<\/strong>.\u00a0<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-cargo-publico\">Cargo P\u00fablico\u00a0<\/h3>\n\n\n\n<p>Outro conceito de extrema import\u00e2ncia trazido pela lei \u00e9 o de <strong>cargo p\u00fablico<\/strong>, que, de acordo com o dispositivo legal, <strong>trata-se do conjunto de atribui\u00e7\u00f5es e responsabilidades cometidas a um funcion\u00e1rio<\/strong>.\u00a0<\/p>\n\n\n\n<p>Os cargos p\u00fablicos, conforme preceitua a lei, podem ser isolados ou de carreira.&nbsp;<\/p>\n\n\n\n<p>Mais uma vez, vale refor\u00e7ar que as disposi\u00e7\u00f5es estabelecidas na lei <strong>n\u00e3o <\/strong>se aplicam aos empregados p\u00fablicos, cuja rela\u00e7\u00e3o jur\u00eddica se submete \u00e0 CLT (Consolida\u00e7\u00e3o das Leis do Trabalho).&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-requisitos-para-a-investidura-no-cargo-publico\">Requisitos para a investidura no cargo p\u00fablico\u00a0<\/h2>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"596\" height=\"180\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/08\/04210617\/esclarecendo-2.png\" alt=\"aten\u00e7\u00e3o\" class=\"wp-image-1618058\" style=\"width:470px;height:auto\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/08\/04210617\/esclarecendo-2.png 596w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/08\/04210617\/esclarecendo-2-300x91.png 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/08\/04210617\/esclarecendo-2-150x45.png 150w\" sizes=\"auto, (max-width: 596px) 100vw, 596px\" \/><\/figure>\n\n\n\n<p>A lei traz alguns <strong>requisitos b\u00e1sicos para a posse em cargo p\u00fablico<\/strong>. Vale lembrara que a posse \u00e9 o ato que investe o cidad\u00e3o em cargo p\u00fablico. Desse modo, <strong>s\u00e3o requisitos para a posse em cargo p\u00fablico<\/strong>:\u00a0<\/p>\n\n\n\n<p>I &#8211; ser <strong>brasileiro<\/strong>;\u00a0<br \/>II &#8211; ter completado <strong>18 (dezoito) anos<\/strong> de idade;\u00a0<br \/>III &#8211; estar em dia com as <strong>obriga\u00e7\u00f5es militares<\/strong>;\u00a0<br \/>IV &#8211; estar no <strong>gozo dos direitos pol\u00edticos<\/strong>;\u00a0<br \/>V &#8211; ter <strong>boa conduta<\/strong>;\u00a0<\/p>\n\n\n\n<p>VI &#8211; <strong>gozar de boa sa\u00fade<\/strong>, comprovada em <strong>inspe\u00e7\u00e3o realizada por \u00f3rg\u00e3o m\u00e9dico oficial do Estado<\/strong>, para provimento de cargo efetivo, ou mediante apresenta\u00e7\u00e3o de Atestado de Sa\u00fade Ocupacional, expedido por m\u00e9dico registrado no Conselho Regional correspondente, para provimento de cargo em comiss\u00e3o;\u00a0<\/p>\n\n\n\n<p>VII &#8211; possuir <strong>aptid\u00e3o para o exerc\u00edcio do cargo<\/strong>; e\u00a0<br \/>VIII &#8211; ter atendido \u00e0s <strong>condi\u00e7\u00f5es especiais prescritas para o cargo<\/strong>.\u00a0<\/p>\n\n\n\n<p>O par\u00e1grafo \u00fanico do artigo 47 afirma que a <strong>defici\u00eancia da capacidade f\u00edsica<\/strong>, comprovadamente estacion\u00e1ria, <strong>n\u00e3o ser\u00e1 considerada impedimento<\/strong> para a caracteriza\u00e7\u00e3o da capacidade ps\u00edquica e som\u00e1tica, desde que tal defici\u00eancia n\u00e3o impe\u00e7a o desempenho normal das fun\u00e7\u00f5es inerentes ao cargo de cujo provimento se trata.\u00a0<\/p>\n\n\n\n<p>Outrossim, vale enfatizar ainda que a posse <strong>verificar-se-\u00e1 mediante a assinatura de termo <\/strong>em que o funcion\u00e1rio prometa cumprir fielmente os deveres do cargo.\u00a0<\/p>\n\n\n\n<p>A lei afirma tamb\u00e9m que,<strong>\u00a0<\/strong>se a posse n\u00e3o se der dentro do prazo, que \u00e9 de <strong>30 dias<\/strong> (contados da publica\u00e7\u00e3o do ato de provimento), ser\u00e1 tornado sem efeito o ato de provimento.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-competencia-para-dar-posse\">Compet\u00eancia para dar posse<\/h3>\n\n\n\n<p>A lei tamb\u00e9m destaca, em seu artigo 48, quem \u00e9 competente para dar posse, vejamos:\u00a0<\/p>\n\n\n\n<p><strong>I &#8211;<\/strong> Os <strong>Secret\u00e1rios de Estado<\/strong>, aos diretores gerais, aos diretores ou chefes das reparti\u00e7\u00f5es e aos funcion\u00e1rios que lhes s\u00e3o diretamente subordinados; e\u00a0<\/p>\n\n\n\n<p><strong>II &#8211;<\/strong> Os <strong>diretores gerais e os diretores ou chefes de reparti\u00e7\u00e3o ou servi\u00e7o<\/strong>, nos demais casos, de acordo com o que dispuser o regulamento.\u00a0<\/p>\n\n\n\n<p>Destaque-se ainda que, conforme a lei, o termo ser\u00e1 lavrado em livro pr\u00f3prio e assinado pela autoridade que der posse.<\/p>\n\n\n\n<p>Al\u00e9m disso, a autoridade que der posse dever\u00e1 verificar, sob pena de responsabilidade, se foram satisfeitas as condi\u00e7\u00f5es estabelecidas, em lei ou regulamento, para a investidura no cargo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-para-finalizar\">Para finalizar<\/h2>\n\n\n\n<p>Por fim, lembre-se de que o Concurso Tribunal de Justi\u00e7a do Estado de S\u00e3o Paulo \u00e9 uma excelente oportunidade para que voc\u00ea consiga ingressar na esfera do Poder Judici\u00e1rio. Outrossim, os concursos no \u00e2mbito da Justi\u00e7a oferecem excelentes remunera\u00e7\u00f5es. Portanto se esforce e se debruce nos estudos para alcan\u00e7ar o t\u00e3o sonhado cargo p\u00fablico.&nbsp;&nbsp;<\/p>\n\n\n\n<p>Enquanto isso, n\u00f3s do <a href=\"https:\/\/www.estrategiaconcursos.com.br\/\" target=\"_blank\" rel=\"noreferrer noopener\">Estrat\u00e9gia Concursos<\/a> buscaremos facilitar a sua caminhada rumo a esse objetivo. Se voc\u00ea ainda n\u00e3o conhece os nossos cursos, entre no nosso site e encontre o curso que atender\u00e1 \u00e0s suas necessidades.\u00a0\u00a0<\/p>\n\n\n\n<p>Finalmente, n\u00e3o deixe de acompanhar e ficar por dentro do que acontece no mundo dos concursos.&nbsp;&nbsp;<\/p>\n\n\n\n<p>Bons estudos e at\u00e9 mais!&nbsp;<\/p>\n\n\n\n<p class=\"has-text-align-center has-pale-cyan-blue-background-color has-background\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos abertos<\/a>&nbsp;<\/p>\n\n\n\n<p class=\"has-text-align-center has-pale-cyan-blue-background-color has-background\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2025\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos 2025<\/a>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Neste artigo voc\u00ea encontrar\u00e1 um resumo de pontos importantes da Lei n\u00ba 10.261\/68, que institui o Estatuto dos Funcion\u00e1rios P\u00fablicos do Estado de S\u00e3o Paulo.\u00a0 Ol\u00e1, concurseiro, tudo bem com voc\u00ea? Estudando muito para o concurso do Tribunal de Justi\u00e7a de S\u00e3o Paulo? Certamente sim! Afinal, essa \u00e9 uma grande oportunidade de ser tornar servidor [&hellip;]<\/p>\n","protected":false},"author":2982,"featured_media":1193825,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1],"tags":[],"tax_estado":[219989],"class_list":["post-1630659","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cursos-e-concursos","tax_estado-sp"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Estatuto dos Funcion\u00e1rios P\u00fablicos para o TJSP<\/title>\n<meta name=\"description\" content=\"Neste artigo voc\u00ea encontrar\u00e1 um resumo de pontos importantes da Lei n\u00ba 10.261\/68, o Estatuto dos Funcion\u00e1rios P\u00fablicos de S\u00e3o Paulo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/estatuto-dos-funcionarios-publicos-tjsp\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Estatuto dos Funcion\u00e1rios P\u00fablicos do Estado de S\u00e3o Paulo para o TJSP\u00a0\" \/>\n<meta property=\"og:description\" content=\"Neste artigo voc\u00ea encontrar\u00e1 um resumo de pontos importantes da Lei n\u00ba 10.261\/68, o Estatuto dos Funcion\u00e1rios P\u00fablicos de S\u00e3o Paulo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/estatuto-dos-funcionarios-publicos-tjsp\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-20T11:06:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-24T22:32:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/03\/29143423\/logo-tjsp-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"342\" \/>\n\t<meta property=\"og:image:height\" content=\"172\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Caroline Martins da Costa Leite\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Caroline Martins da Costa Leite\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/estatuto-dos-funcionarios-publicos-tjsp\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/estatuto-dos-funcionarios-publicos-tjsp\/\"},\"author\":{\"name\":\"Caroline Martins da Costa Leite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/1c7ac186f04b04e87eeba66c2467cf6a\"},\"headline\":\"Estatuto dos Funcion\u00e1rios P\u00fablicos do Estado de S\u00e3o Paulo para o TJSP\u00a0\",\"datePublished\":\"2025-09-20T11:06:00+00:00\",\"dateModified\":\"2025-09-24T22:32:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/estatuto-dos-funcionarios-publicos-tjsp\/\"},\"wordCount\":896,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/estatuto-dos-funcionarios-publicos-tjsp\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/03\/29143423\/logo-tjsp-1.png\",\"articleSection\":[\"Concursos P\u00fablicos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/estatuto-dos-funcionarios-publicos-tjsp\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/estatuto-dos-funcionarios-publicos-tjsp\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/estatuto-dos-funcionarios-publicos-tjsp\/\",\"name\":\"Estatuto dos Funcion\u00e1rios P\u00fablicos para o TJSP\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/estatuto-dos-funcionarios-publicos-tjsp\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/estatuto-dos-funcionarios-publicos-tjsp\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/03\/29143423\/logo-tjsp-1.png\",\"datePublished\":\"2025-09-20T11:06:00+00:00\",\"dateModified\":\"2025-09-24T22:32:51+00:00\",\"description\":\"Neste artigo voc\u00ea encontrar\u00e1 um resumo de pontos importantes da Lei n\u00ba 10.261\/68, o Estatuto dos Funcion\u00e1rios P\u00fablicos de S\u00e3o Paulo.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/estatuto-dos-funcionarios-publicos-tjsp\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/estatuto-dos-funcionarios-publicos-tjsp\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/estatuto-dos-funcionarios-publicos-tjsp\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/03\/29143423\/logo-tjsp-1.png\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/03\/29143423\/logo-tjsp-1.png\",\"width\":342,\"height\":172,\"caption\":\"aten\u00e7\u00e3o\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/estatuto-dos-funcionarios-publicos-tjsp\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Estatuto dos Funcion\u00e1rios P\u00fablicos do Estado de S\u00e3o Paulo para o TJSP\u00a0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/1c7ac186f04b04e87eeba66c2467cf6a\",\"name\":\"Caroline Martins da Costa Leite\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/061997e69e4fd91b5e3d45dff736c5f05b3c02a4283b46708faf52b75701224e?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/061997e69e4fd91b5e3d45dff736c5f05b3c02a4283b46708faf52b75701224e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/061997e69e4fd91b5e3d45dff736c5f05b3c02a4283b46708faf52b75701224e?s=96&d=mm&r=g\",\"caption\":\"Caroline Martins da Costa Leite\"},\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/carol_leite1706hotmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Estatuto dos Funcion\u00e1rios P\u00fablicos para o TJSP","description":"Neste artigo voc\u00ea encontrar\u00e1 um resumo de pontos importantes da Lei n\u00ba 10.261\/68, o Estatuto dos Funcion\u00e1rios P\u00fablicos de S\u00e3o Paulo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/estatuto-dos-funcionarios-publicos-tjsp\/","og_locale":"pt_BR","og_type":"article","og_title":"Estatuto dos Funcion\u00e1rios P\u00fablicos do Estado de S\u00e3o Paulo para o TJSP\u00a0","og_description":"Neste artigo voc\u00ea encontrar\u00e1 um resumo de pontos importantes da Lei n\u00ba 10.261\/68, o Estatuto dos Funcion\u00e1rios P\u00fablicos de S\u00e3o Paulo.","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/estatuto-dos-funcionarios-publicos-tjsp\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2025-09-20T11:06:00+00:00","article_modified_time":"2025-09-24T22:32:51+00:00","og_image":[{"width":342,"height":172,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/03\/29143423\/logo-tjsp-1.png","type":"image\/png"}],"author":"Caroline Martins da Costa Leite","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Caroline Martins da Costa Leite","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/estatuto-dos-funcionarios-publicos-tjsp\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/estatuto-dos-funcionarios-publicos-tjsp\/"},"author":{"name":"Caroline Martins da Costa Leite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/1c7ac186f04b04e87eeba66c2467cf6a"},"headline":"Estatuto dos Funcion\u00e1rios P\u00fablicos do Estado de S\u00e3o Paulo para o TJSP\u00a0","datePublished":"2025-09-20T11:06:00+00:00","dateModified":"2025-09-24T22:32:51+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/estatuto-dos-funcionarios-publicos-tjsp\/"},"wordCount":896,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/estatuto-dos-funcionarios-publicos-tjsp\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/03\/29143423\/logo-tjsp-1.png","articleSection":["Concursos P\u00fablicos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/estatuto-dos-funcionarios-publicos-tjsp\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/estatuto-dos-funcionarios-publicos-tjsp\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/estatuto-dos-funcionarios-publicos-tjsp\/","name":"Estatuto dos Funcion\u00e1rios P\u00fablicos para o TJSP","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/estatuto-dos-funcionarios-publicos-tjsp\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/estatuto-dos-funcionarios-publicos-tjsp\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/03\/29143423\/logo-tjsp-1.png","datePublished":"2025-09-20T11:06:00+00:00","dateModified":"2025-09-24T22:32:51+00:00","description":"Neste artigo voc\u00ea encontrar\u00e1 um resumo de pontos importantes da Lei n\u00ba 10.261\/68, o Estatuto dos Funcion\u00e1rios P\u00fablicos de S\u00e3o Paulo.","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/estatuto-dos-funcionarios-publicos-tjsp\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/estatuto-dos-funcionarios-publicos-tjsp\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/estatuto-dos-funcionarios-publicos-tjsp\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/03\/29143423\/logo-tjsp-1.png","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/03\/29143423\/logo-tjsp-1.png","width":342,"height":172,"caption":"aten\u00e7\u00e3o"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/estatuto-dos-funcionarios-publicos-tjsp\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Estatuto dos Funcion\u00e1rios P\u00fablicos do Estado de S\u00e3o Paulo para o TJSP\u00a0"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/1c7ac186f04b04e87eeba66c2467cf6a","name":"Caroline Martins da Costa Leite","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/061997e69e4fd91b5e3d45dff736c5f05b3c02a4283b46708faf52b75701224e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/061997e69e4fd91b5e3d45dff736c5f05b3c02a4283b46708faf52b75701224e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/061997e69e4fd91b5e3d45dff736c5f05b3c02a4283b46708faf52b75701224e?s=96&d=mm&r=g","caption":"Caroline Martins da Costa Leite"},"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/carol_leite1706hotmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1630659","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/2982"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1630659"}],"version-history":[{"count":6,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1630659\/revisions"}],"predecessor-version":[{"id":1630678,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1630659\/revisions\/1630678"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/1193825"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1630659"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1630659"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1630659"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1630659"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}