{"id":1624798,"date":"2025-09-19T11:28:00","date_gmt":"2025-09-19T14:28:00","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=1624798"},"modified":"2025-08-25T12:14:34","modified_gmt":"2025-08-25T15:14:34","slug":"competencia-absoluta-competencia-relativa","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/competencia-absoluta-competencia-relativa\/","title":{"rendered":"Compet\u00eancia absoluta e compet\u00eancia relativa"},"content":{"rendered":"\n<p>Ol\u00e1, estudantes do Direito! Preparados para mais uma sess\u00e3o de aprendizado? Neste artigo estudaremos quest\u00f5es atinentes \u00e0 compet\u00eancia absoluta e \u00e0 compet\u00eancia relativa.<\/p>\n\n\n\n<p>Para melhor compreens\u00e3o, o assunto foi dividido nos seguintes t\u00f3picos:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Introdu\u00e7\u00e3o<\/strong><\/li>\n\n\n\n<li><strong>Crit\u00e9rios determinativos da compet\u00eancia<\/strong><\/li>\n\n\n\n<li><strong>Compet\u00eancia absoluta em raz\u00e3o da mat\u00e9ria<\/strong><\/li>\n\n\n\n<li><strong>Compet\u00eancia absoluta em raz\u00e3o da pessoa<\/strong><\/li>\n\n\n\n<li><strong>Compet\u00eancia absoluta em raz\u00e3o da fun\u00e7\u00e3o<\/strong><\/li>\n\n\n\n<li><strong>Compet\u00eancia relativa em raz\u00e3o do valor da causa<\/strong>\n<ul class=\"wp-block-list\">\n<li><strong>Compet\u00eancia absoluta em raz\u00e3o do valor da causa<\/strong><\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>Compet\u00eancia relativa em raz\u00e3o do territ\u00f3rio<\/strong>\n<ul class=\"wp-block-list\">\n<li><strong>Compet\u00eancia absoluta em raz\u00e3o do territ\u00f3rio<\/strong><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<p>Vamos l\u00e1!<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1536\" height=\"1024\" src=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2025\/08\/chatgpt-image-aug-16-2025-05_10_28-pm-2.png\" alt=\"compet\u00eancia absoluta\" class=\"wp-image-1624808\" srcset=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2025\/08\/chatgpt-image-aug-16-2025-05_10_28-pm-2.png 1536w, https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2025\/08\/chatgpt-image-aug-16-2025-05_10_28-pm-2-300x200.png 300w\" sizes=\"auto, (max-width: 1536px) 100vw, 1536px\" \/><\/figure>\n\n\n\n<h1 class=\"wp-block-heading\" id=\"h-introducao\">Introdu\u00e7\u00e3o<\/h1>\n\n\n\n<p>A jurisdi\u00e7\u00e3o \u00e9 uma fun\u00e7\u00e3o una e indivis\u00edvel do Estado que consiste em dizer o direito. Por meio da jurisdi\u00e7\u00e3o os julgadores aplicam o direito nos casos que s\u00e3o levados \u00e0 tutela jurisdicional.<\/p>\n\n\n\n<p>Essa fun\u00e7\u00e3o \u00e9 tida como um poder-dever do Estado. \u00c9 um poder, pois permite que o Estado resolva as situa\u00e7\u00f5es levadas a seu conhecimento por meio da imposi\u00e7\u00e3o de sua decis\u00e3o, independentemente do consentimento dos afetados. Por outro lado, \u00e9 um dever, pois veda que o Estado deixe de decidir sobre os casos que sejam levados \u00e0 tutela jurisdicional:<\/p>\n\n\n\n<p><em>art. 5\u00ba, XXXV, da CF de 88 &#8211; a lei n\u00e3o excluir\u00e1 da aprecia\u00e7\u00e3o do Poder Judici\u00e1rio les\u00e3o ou amea\u00e7a a direito<\/em><\/p>\n\n\n\n<p>Contudo, mesmo os \u00f3rg\u00e3os do judici\u00e1rio dotados de jurisdi\u00e7\u00e3o n\u00e3o podem analisar todo e qualquer caso que seja levado a seu conhecimento. Visando \u00e0 melhor organiza\u00e7\u00e3o, \u00e0 impessoalidade, \u00e0 efici\u00eancia e outros aspectos que tendam a melhor a presta\u00e7\u00e3o jurisdicional, foram feitas diversas divis\u00f5es com o intuito de atribuir a \u00f3rg\u00e3os espec\u00edficos a tarefa de julgar determinados casos.<\/p>\n\n\n\n<p>Essas divis\u00f5es correspondem \u00e0 fixa\u00e7\u00e3o de compet\u00eancias. A delimita\u00e7\u00e3o de compet\u00eancias, al\u00e9m de corroborar para o que foi dito no par\u00e1grafo anterior, tamb\u00e9m assegura o princ\u00edpio do juiz natural e princ\u00edpio da veda\u00e7\u00e3o a tribunais de exce\u00e7\u00e3o. Essa pr\u00e1tica reduz a possibilidade de cometimento de abusos e, consequentemente, aumenta a probabilidade de serem proferidas decis\u00f5es justas.<\/p>\n\n\n\n<p>Para delimita\u00e7\u00e3o da compet\u00eancia dos \u00f3rg\u00e3o julgadores s\u00e3o levadas em considera\u00e7\u00f5es algumas quest\u00f5es atinentes \u00e0 causa. Algumas delas acarretam a fixa\u00e7\u00e3o da compet\u00eancia de um \u00fanico \u00f3rg\u00e3o (compet\u00eancia absoluta), enquanto outras possibilitam o julgamento por mais de um \u00f3rg\u00e3o (compet\u00eancia relativa), existindo, neste caso, a possibilidade das partes influenciarem na sua fixa\u00e7\u00e3o.<\/p>\n\n\n\n<p>Nos t\u00f3picos a seguir, estudaremos como diferentes quest\u00f5es podem estar relacionadas \u00e0 compet\u00eancia absoluta e a compet\u00eancia relativa.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-large-font-size\" id=\"h-criterios-determinativos-da-competencia\">Crit\u00e9rios determinativos da compet\u00eancia<\/h2>\n\n\n\n<p>A doutrina classifica os crit\u00e9rios determinativos da compet\u00eancia de tr\u00eas maneiras: crit\u00e9rio objetivo; crit\u00e9rio funcional; e crit\u00e9rio territorial.<\/p>\n\n\n\n<p>Os crit\u00e9rios objetivos s\u00e3o o valor da causa (compet\u00eancia relativa), a mat\u00e9ria (compet\u00eancia absoluta) e a pessoa (compet\u00eancia absoluta). O crit\u00e9rio funcional leva em considera\u00e7\u00e3o a fun\u00e7\u00e3o exercida pela pessoa (compet\u00eancia absoluta). J\u00e1 o crit\u00e9rio territorial leva em considera\u00e7\u00e3o o local do fato, a\u00e7\u00e3o ou omiss\u00e3o (compet\u00eancia relativa).<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-large-font-size\" id=\"h-competencia-absoluta-em-razao-da-materia\">Compet\u00eancia absoluta em raz\u00e3o da mat\u00e9ria<\/h2>\n\n\n\n<p>Entende-se como mat\u00e9ria a <strong>natureza da rela\u00e7\u00e3o jur\u00eddica a ser tratada no processo<\/strong>. O crit\u00e9rio da mat\u00e9ria enseja a fixa\u00e7\u00e3o da c<strong>ompet\u00eancia absoluta<\/strong> para processamento e julgamento da causa. S\u00e3o exemplos de determina\u00e7\u00e3o da compet\u00eancia em raz\u00e3o da mat\u00e9ria a cria\u00e7\u00e3o de varas de fam\u00edlia, de fal\u00eancia ou de julgamento de crimes praticados por organiza\u00e7\u00f5es criminosas (quanto a estas \u00faltimas, ler este artigo sobre <a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/varas-criminais-colegiadas-juizes-anonimos\/\">varas criminais colegiadas e ju\u00edzes an\u00f4nimos<\/a>).<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-large-font-size\" id=\"h-competencia-absoluta-em-razao-da-pessoa\">Compet\u00eancia absoluta em raz\u00e3o da pessoa<\/h2>\n\n\n\n<p>O crit\u00e9rio da pessoa leva em considera\u00e7\u00e3o a <strong>qualidade dos sujeitos envolvidos no processo<\/strong>. A <strong>compet\u00eancia fixada com base nesse crit\u00e9rio \u00e9 absoluta <\/strong>(n\u00e3o permite altera\u00e7\u00e3o conforme vontade das partes). Tem-se como exemplo de compet\u00eancia determinada em raz\u00e3o da pessoa as varas de fazenda p\u00fablica, nas quais tramitam processos em que a fazenda p\u00fablica seja parte.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-large-font-size\" id=\"h-competencia-absoluta-em-razao-da-funcao\">Compet\u00eancia absoluta em raz\u00e3o da fun\u00e7\u00e3o<\/h2>\n\n\n\n<p>O crit\u00e9rio de fun\u00e7\u00e3o relaciona-se \u00e0 <strong>fun\u00e7\u00e3o desempenhada pelo \u00f3rg\u00e3o jurisdicional<\/strong>. A compet\u00eancia nesse caso \u00e9 absoluta.<\/p>\n\n\n\n<p>Segundo Jaylton Lopes Jr. (Manual de Processo Civil, 2023), a compet\u00eancia funcional pode ser sistematizada por:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>grau de jurisdi\u00e7\u00e3o (compet\u00eancia origin\u00e1ria e recursal de \u00f3rg\u00e3os jurisdicionais);<\/li>\n\n\n\n<li>fase do processo (execu\u00e7\u00e3o c\u00edvel de repara\u00e7\u00e3o de danos fixada por ju\u00edzo criminal);<\/li>\n\n\n\n<li>objeto do ju\u00edzo (incidentes processuais que demandem decis\u00e3o de \u00f3rg\u00e3o espec\u00edficos).<\/li>\n<\/ul>\n\n\n\n<p>Por se tratar de compet\u00eancia absoluta, somente os \u00f3rg\u00e3os designados para o tratamento dos processos podem atuar nesses casos. Trata-se de restri\u00e7\u00e3o da atividade jurisdicional, que <strong>n\u00e3o se confunde com o exerc\u00edcio da atividade administrativa<\/strong> (fun\u00e7\u00e3o at\u00edpica do judici\u00e1rio). Atividades de natureza administrativa podem ser atribu\u00eddas a outros \u00f3rg\u00e3os, desde que cumpridas as exig\u00eancias legais e respeitadas as veda\u00e7\u00f5es aplic\u00e1veis a cada caso.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-large-font-size\" id=\"h-competencia-relativa-em-razao-do-valor-da-causa\">Compet\u00eancia relativa em raz\u00e3o do valor da causa<\/h2>\n\n\n\n<p>O crit\u00e9rio do valor da causa \u00e9 f\u00e1cil compreens\u00e3o. A depender do valor da causa, o ju\u00edzo competente para processamento e julgamento da demanda pode ser alterado. Como regra, esse tipo de compet\u00eancia \u00e9 relativa, pois caso o valor da causa fosse diverso, outro ju\u00edzo poderia ser competente para tratamento da causa. \u00c9 o caso dos processos c\u00edveis estaduais em que o valor da causa seja inferior a 40 sal\u00e1rios m\u00ednimos. O interessado pode escolher se deseja ingressar com a a\u00e7\u00e3o no juizado especial ou no ju\u00edzo comum.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-competencia-absoluta-em-razao-do-valor-da-causa\">Compet\u00eancia absoluta em raz\u00e3o do valor da causa<\/h3>\n\n\n\n<p>Apesar de a grande maioria dos materiais de estudo apontarem o valor da causa como crit\u00e9rio de fixa\u00e7\u00e3o de compet\u00eancia relativa, Jaylton Lopes faz algumas ressalvas:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Quando o valor da causa ultrapassar o teto dos juizados, a incompet\u00eancia ser\u00e1 absoluta do ju\u00edzo comum, exceto nas hip\u00f3teses de ren\u00fancia expressa do valor que ultrapassar esse limite.<\/li>\n\n\n\n<li>Quando o valor da causa for igual ou inferior ao teto estipulado para os juizados da fazenda p\u00fablica, a compet\u00eancia do juizado da fazenda ser\u00e1 absoluta.<\/li>\n<\/ul>\n\n\n\n<p>Quanto aos juizados estaduais, federais e da fazenda, existem requisitos e diferen\u00e7as procedimentais que merecem ser estudados de maneira espec\u00edfica, conforme a necessidade de cada aluno.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-large-font-size\" id=\"h-competencia-relativa-em-razao-do-territorio\">Compet\u00eancia relativa em raz\u00e3o do territ\u00f3rio<\/h2>\n\n\n\n<p>O crit\u00e9rio territorial leva em considera\u00e7\u00e3o caracter\u00edsticas geogr\u00e1ficas para fixa\u00e7\u00e3o de compet\u00eancia. Como regra, esse tipo de compet\u00eancia \u00e9 relativa.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-competencia-absoluta-em-razao-do-territorio\">Compet\u00eancia absoluta em raz\u00e3o do territ\u00f3rio<\/h3>\n\n\n\n<p><strong>Existem algumas situa\u00e7\u00f5es em que a compet\u00eancia territorial \u00e9 absoluta<\/strong>. Isso decorre de imposi\u00e7\u00f5es legais, como \u00e9 o caso das a\u00e7\u00f5es civis p\u00fablicas, que devem ser propostas nos locais em que ocorrer o dano ou no foro da capital dos estados afetados, quando o dano for regional. Todavia, mesmo nas situa\u00e7\u00f5es em que a pr\u00f3pria lei prev\u00ea regra de compet\u00eancia territorial, pode haver <strong>diverg\u00eancia doutrin\u00e1ria e jurisprudencial<\/strong> sobre seu reconhecimento como absoluta.<\/p>\n\n\n\n<p>A norma do art. 101, I, do CDC, representa essa controv\u00e9rsia: alguns tribunais entendem ser o caso de compet\u00eancia absoluta (entendimento majorit\u00e1rio), o que enseja a possibilidade de reconhecimento de of\u00edcio, enquanto outros entendem tratar de compet\u00eancia relativa, que impede sua pron\u00fancia de of\u00edcio.<\/p>\n\n\n\n<p>Gostou do texto? Deixe um coment\u00e1rio abaixo.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.instagram.com\/gabrielssantos96\">https:\/\/www.instagram.com\/gabrielssantos96<\/a><\/p>\n\n\n\n<p class=\"has-text-align-center has-white-color has-vivid-cyan-blue-background-color has-text-color has-background has-link-color wp-elements-934bee992b67b6144e8b666952a903fb\"><strong><a href=\"https:\/\/www.youtube.com\/@EstrategiaConcursosBrasil\">Canal do Estrat\u00e9gia Concursos no Youtube<\/a><\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center has-white-color has-vivid-cyan-blue-background-color has-text-color has-background has-link-color wp-elements-4ee3858d78f8e73e6a059835bfd98e6f\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\"><strong>Concursos Abertos<\/strong><\/a><\/p>\n\n\n\n<p class=\"has-text-align-center has-white-color has-vivid-cyan-blue-background-color has-text-color has-background has-link-color wp-elements-1aca1c51fe870dad71059b988ff0425d\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2025\/\"><strong>Concursos 2025<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ol\u00e1, estudantes do Direito! Preparados para mais uma sess\u00e3o de aprendizado? Neste artigo estudaremos quest\u00f5es atinentes \u00e0 compet\u00eancia absoluta e \u00e0 compet\u00eancia relativa. Para melhor compreens\u00e3o, o assunto foi dividido nos seguintes t\u00f3picos: Vamos l\u00e1! Introdu\u00e7\u00e3o A jurisdi\u00e7\u00e3o \u00e9 uma fun\u00e7\u00e3o una e indivis\u00edvel do Estado que consiste em dizer o direito. Por meio da [&hellip;]<\/p>\n","protected":false},"author":3013,"featured_media":1624808,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1],"tags":[],"tax_estado":[219963],"class_list":["post-1624798","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cursos-e-concursos","tax_estado-concursos-federais"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Compet\u00eancia absoluta e compet\u00eancia relativa<\/title>\n<meta name=\"description\" content=\"Aprenda as regras de compet\u00eancia absoluta e compet\u00eancia relativa e veja como funcionam os respectivos crit\u00e9rios determinativos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/competencia-absoluta-competencia-relativa\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Compet\u00eancia absoluta e compet\u00eancia relativa\" \/>\n<meta property=\"og:description\" content=\"Aprenda as regras de compet\u00eancia absoluta e compet\u00eancia relativa e veja como funcionam os respectivos crit\u00e9rios determinativos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/competencia-absoluta-competencia-relativa\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-19T14:28:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2025\/08\/chatgpt-image-aug-16-2025-05_10_28-pm-2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1536\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Gabriel Souza Santos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gabriel Souza Santos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/competencia-absoluta-competencia-relativa\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/competencia-absoluta-competencia-relativa\/\"},\"author\":{\"name\":\"Gabriel Souza Santos\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/d948c69f6dd3bbd74ea6c9f7451a93c6\"},\"headline\":\"Compet\u00eancia absoluta e compet\u00eancia relativa\",\"datePublished\":\"2025-09-19T14:28:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/competencia-absoluta-competencia-relativa\/\"},\"wordCount\":1319,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/competencia-absoluta-competencia-relativa\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2025\/08\/chatgpt-image-aug-16-2025-05_10_28-pm-2.png\",\"articleSection\":[\"Concursos P\u00fablicos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/competencia-absoluta-competencia-relativa\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/competencia-absoluta-competencia-relativa\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/competencia-absoluta-competencia-relativa\/\",\"name\":\"Compet\u00eancia absoluta e compet\u00eancia relativa\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/competencia-absoluta-competencia-relativa\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/competencia-absoluta-competencia-relativa\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2025\/08\/chatgpt-image-aug-16-2025-05_10_28-pm-2.png\",\"datePublished\":\"2025-09-19T14:28:00+00:00\",\"description\":\"Aprenda as regras de compet\u00eancia absoluta e compet\u00eancia relativa e veja como funcionam os respectivos crit\u00e9rios determinativos.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/competencia-absoluta-competencia-relativa\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/competencia-absoluta-competencia-relativa\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/competencia-absoluta-competencia-relativa\/#primaryimage\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2025\/08\/chatgpt-image-aug-16-2025-05_10_28-pm-2.png\",\"contentUrl\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2025\/08\/chatgpt-image-aug-16-2025-05_10_28-pm-2.png\",\"width\":1536,\"height\":1024,\"caption\":\"compet\u00eancia absoluta\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/competencia-absoluta-competencia-relativa\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Compet\u00eancia absoluta e compet\u00eancia relativa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/d948c69f6dd3bbd74ea6c9f7451a93c6\",\"name\":\"Gabriel Souza Santos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/fd1003725e80f9cbb3f5083f64f112beb33dbd3bcbc7d34e628143a7cdd6cb8a?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/fd1003725e80f9cbb3f5083f64f112beb33dbd3bcbc7d34e628143a7cdd6cb8a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/fd1003725e80f9cbb3f5083f64f112beb33dbd3bcbc7d34e628143a7cdd6cb8a?s=96&d=mm&r=g\",\"caption\":\"Gabriel Souza Santos\"},\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/gabriel-s-96hotmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Compet\u00eancia absoluta e compet\u00eancia relativa","description":"Aprenda as regras de compet\u00eancia absoluta e compet\u00eancia relativa e veja como funcionam os respectivos crit\u00e9rios determinativos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/competencia-absoluta-competencia-relativa\/","og_locale":"pt_BR","og_type":"article","og_title":"Compet\u00eancia absoluta e compet\u00eancia relativa","og_description":"Aprenda as regras de compet\u00eancia absoluta e compet\u00eancia relativa e veja como funcionam os respectivos crit\u00e9rios determinativos.","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/competencia-absoluta-competencia-relativa\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2025-09-19T14:28:00+00:00","og_image":[{"width":1536,"height":1024,"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2025\/08\/chatgpt-image-aug-16-2025-05_10_28-pm-2.png","type":"image\/png"}],"author":"Gabriel Souza Santos","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Gabriel Souza Santos","Est. tempo de leitura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/competencia-absoluta-competencia-relativa\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/competencia-absoluta-competencia-relativa\/"},"author":{"name":"Gabriel Souza Santos","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/d948c69f6dd3bbd74ea6c9f7451a93c6"},"headline":"Compet\u00eancia absoluta e compet\u00eancia relativa","datePublished":"2025-09-19T14:28:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/competencia-absoluta-competencia-relativa\/"},"wordCount":1319,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/competencia-absoluta-competencia-relativa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2025\/08\/chatgpt-image-aug-16-2025-05_10_28-pm-2.png","articleSection":["Concursos P\u00fablicos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/competencia-absoluta-competencia-relativa\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/competencia-absoluta-competencia-relativa\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/competencia-absoluta-competencia-relativa\/","name":"Compet\u00eancia absoluta e compet\u00eancia relativa","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/competencia-absoluta-competencia-relativa\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/competencia-absoluta-competencia-relativa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2025\/08\/chatgpt-image-aug-16-2025-05_10_28-pm-2.png","datePublished":"2025-09-19T14:28:00+00:00","description":"Aprenda as regras de compet\u00eancia absoluta e compet\u00eancia relativa e veja como funcionam os respectivos crit\u00e9rios determinativos.","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/competencia-absoluta-competencia-relativa\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/competencia-absoluta-competencia-relativa\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/competencia-absoluta-competencia-relativa\/#primaryimage","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2025\/08\/chatgpt-image-aug-16-2025-05_10_28-pm-2.png","contentUrl":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2025\/08\/chatgpt-image-aug-16-2025-05_10_28-pm-2.png","width":1536,"height":1024,"caption":"compet\u00eancia absoluta"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/competencia-absoluta-competencia-relativa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Compet\u00eancia absoluta e compet\u00eancia relativa"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/d948c69f6dd3bbd74ea6c9f7451a93c6","name":"Gabriel Souza Santos","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/fd1003725e80f9cbb3f5083f64f112beb33dbd3bcbc7d34e628143a7cdd6cb8a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fd1003725e80f9cbb3f5083f64f112beb33dbd3bcbc7d34e628143a7cdd6cb8a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fd1003725e80f9cbb3f5083f64f112beb33dbd3bcbc7d34e628143a7cdd6cb8a?s=96&d=mm&r=g","caption":"Gabriel Souza Santos"},"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/gabriel-s-96hotmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1624798","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/3013"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1624798"}],"version-history":[{"count":5,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1624798\/revisions"}],"predecessor-version":[{"id":1624817,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1624798\/revisions\/1624817"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/1624808"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1624798"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1624798"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1624798"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1624798"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}