{"id":1622401,"date":"2025-08-12T17:21:16","date_gmt":"2025-08-12T20:21:16","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=1622401"},"modified":"2025-08-12T17:58:39","modified_gmt":"2025-08-12T20:58:39","slug":"concurso-aft-excedentes","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-aft-excedentes\/","title":{"rendered":"Concurso AFT: MTE pede maior or\u00e7amento para excedentes"},"content":{"rendered":"\n<p style=\"font-size:clamp(16.293px, 1.018rem + ((1vw - 3.2px) * 0.854), 25px);\"><strong><em>Excedentes do concurso AFT poderiam ser convocados com cria\u00e7\u00e3o de 2 mil cargos e expans\u00e3o or\u00e7ament\u00e1ria<\/em><\/strong><\/p>\n\n\n\n<p>No dia 8 de agosto, \u00faltima sexta-feira, o Minist\u00e9rio do Trabalho e Emprego (MTE) solicitou \u00e0 pasta de Planejamento e Or\u00e7amento uma amplia\u00e7\u00e3o or\u00e7ament\u00e1ria para 2026.<\/p>\n\n\n\n<p>A medida est\u00e1 alinhada \u00e0 necessidade de novos auditores fiscais do trabalho que, mesmo com os 900 aprovados na 1\u00ba edi\u00e7\u00e3o do <strong>CNU<\/strong>, representam 25% do total da carreira, com 3.644 cargos, conforme dados divulgados pela entidade sindical SINAIT.<\/p>\n\n\n\n<p>No of\u00edcio, foram solicitados cerca de <strong>R$ 30,5 milh\u00f5es<\/strong> a mais para a cria\u00e7\u00e3o de <strong>2.000 cargos<\/strong> de <strong>Auditor Fiscal do Trabalho (AFT),<\/strong> de modo a refor\u00e7ar os n\u00fameros do quadro profissional.<\/p>\n\n\n\n<p>A cria\u00e7\u00e3o possibilitaria o chamamento de <strong>excedentes do concurso AFT<\/strong>, realizado atrav\u00e9s do CNU, a\u00e7\u00e3o defendida pelo SINAIT. A entidade argumenta que a falta de auditores tem prejudicado a execu\u00e7\u00e3o das tarefas do minist\u00e9rio.<\/p>\n\n\n\n<p>J\u00e1 o MTE disse, no documento, que<em> &#8220;h\u00e1 necessidade de expans\u00e3o dos valores inicialmente propostos pelo referencial monet\u00e1rio, com o intuito de possibilitar a entrega de servi\u00e7os \u00e0 sociedade, bem como honrar os pagamentos das repactua\u00e7\u00f5es dos contratos continuados de 2026.&#8221;<\/em><\/p>\n\n\n\n<p>A pasta do Trabalho tamb\u00e9m relata que, se a expans\u00e3o or\u00e7ament\u00e1ria &#8211; que tamb\u00e9m inclui amplia\u00e7\u00f5es para outras medidas &#8211; n\u00e3o for acatada, pode alcan\u00e7ar um impacto significativo nas a\u00e7\u00f5es governamentais.<\/p>\n\n\n\n<p>A cria\u00e7\u00e3o de <strong>2 mil cargos<\/strong> de AFT foi uma das <a href=\"https:\/\/www.sinait.org.br\/noticia\/22710\/ministro-do-trabalho-atende-ao-pedido-do-sinait-para-criacao-de-2-mil-cargos-de-auditores-fiscais-do-trabalho\" target=\"_blank\" rel=\"noreferrer noopener\">solicita\u00e7\u00f5es<\/a> apresentadas pelo SINAIT em julho (23). Na \u00e9poca, o presidente do sindicato, Bob Machado, e a diretora Rosa Jorge se reuniram com o ministro Luiz Marinho.<\/p>\n\n\n\n<p>No encontro, o ministro disse que atender\u00e1 o pedido da entidade, o que foi realizado atrav\u00e9s do of\u00edcio enviado na \u00faltima sexta-feira, (8).<\/p>\n\n\n\n<p>&gt;&gt;&gt; <a href=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/08\/12171515\/sei_mte-6297126-oficio.pdf\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Confira o documento na \u00edntegra<\/a><\/p>\n\n\n\n<div class=\"container\" id=\"boxes\">\r\n  <div class=\"row\">\r\n\r\n    <div class=\"col-sm\">\r\n      <div class=\"banner-fiscal-01\" id=\"box-assinatura\">\r\n        <h3 class=\"titulo-assinatura\">Concurso AFT<\/h3>\r\n        <p class=\"subtitulo-assinatura\">Conhe\u00e7a os cursos<\/p>\r\n        <div class=\"box-botao\">\r\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/cursosPorConcurso\/aft-auditor-fiscal-do-trabalho-11\/\" role=\"button\" rel=\"noopener noreferrer\">Conhe\u00e7a mais<\/a>\r\n        <\/div>\r\n      <\/div>\r\n      \r\n    <\/div>\r\n\r\n  <\/div>\r\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-nomeacoes-do-cnu-para-o-concurso-aft-ainda-nao-foram-anunciadas\">Nomea\u00e7\u00f5es do CNU para o concurso AFT ainda n\u00e3o foram anunciadas<\/h2>\n\n\n\n<p>Apesar da divulga\u00e7\u00e3o do resultado final do Curso de Forma\u00e7\u00e3o dos aprovados no concurso AFT, ainda n\u00e3o houve partida do governo para a nomea\u00e7\u00e3o dos novos servidores.<\/p>\n\n\n\n<p>Mesmo sem previs\u00e3o de chamamento, o MTE enviou outro of\u00edcio\u00a0<a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/aft-criacao-de-cargos\/\" target=\"_blank\" rel=\"noreferrer noopener\">solicitando que os aprovados no cadastro reserva<\/a>\u00a0tamb\u00e9m sejam chamados.<\/p>\n\n\n\n<p>A ideia \u00e9 zerar o quantitativo e permitir a quantidade necess\u00e1ria de auditores para a execu\u00e7\u00e3o das tarefas e atribui\u00e7\u00f5es do minist\u00e9rio.<\/p>\n\n\n\n<p>Ademais, o concurso AFT ofertou <strong>900 vagas imediatas<\/strong> para o cargo de auditor, respons\u00e1vel por sal\u00e1rios iniciais de <strong>R$ 22,9 mil<\/strong>.<\/p>\n\n\n\n<p class=\"has-text-align-center\"><em>Ficou interessado nas informa\u00e7\u00f5es dispon\u00edveis at\u00e9 aqui? Quer saber mais acerca da cria\u00e7\u00e3o de cargos na carreira de AFT, al\u00e9m de poss\u00edveis excedentes do concurso? Ent\u00e3o, acesse agora mesmo o artigo abaixo:<\/em><\/p>\n\n\n\n<p class=\"has-text-align-center has-background\" style=\"background-color:#f4f4f4;font-size:clamp(14.642px, 0.915rem + ((1vw - 3.2px) * 0.721), 22px);\"><strong>Saiba mais: <a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-aft\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concurso AFT<\/a> <\/strong><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"cursos-assinatura\"><em>Quer estudar para o concurso AFT?<\/em><\/h2>\n\n\n\n<div class=\"container\" id=\"boxes\">\r\n  <div class=\"row\">\r\n\r\n    <div class=\"col-sm\">\r\n      <div class=\"estrategia\" id=\"box-assinatura\">\r\n        <h3 class=\"titulo-assinatura\">Assinatura Concursos<\/h3>\r\n        <p class=\"subtitulo-assinatura\">Assinatura de 1 ano ou 2 anos<\/p>\r\n        <div class=\"box-botao\">\r\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/assinaturas\/\" role=\"button\" rel=\"noopener noreferrer\">ASSINE AGORA<\/a>\r\n        <\/div>\r\n      <\/div><\/div><\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"h-quer-saber-tudo-sobre-concursos-previstos-confira-nossos-artigos\">Quer saber tudo sobre concursos previstos?<br \/>Confira nossos artigos!<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos Abertos<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-fiscais\/\">Concursos Fiscais<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2025\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos 2025<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2026\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos 2026<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Excedentes do concurso AFT poderiam ser convocados com cria\u00e7\u00e3o de 2 mil cargos e expans\u00e3o or\u00e7ament\u00e1ria No dia 8 de agosto, \u00faltima sexta-feira, o Minist\u00e9rio do Trabalho e Emprego (MTE) solicitou \u00e0 pasta de Planejamento e Or\u00e7amento uma amplia\u00e7\u00e3o or\u00e7ament\u00e1ria para 2026. A medida est\u00e1 alinhada \u00e0 necessidade de novos auditores fiscais do trabalho que, [&hellip;]<\/p>\n","protected":false},"author":2692,"featured_media":783067,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"news","footnotes":""},"categories":[220182,220219],"tags":[],"tax_estado":[219963],"class_list":["post-1622401","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fiscal-federal","category-noticias","tax_estado-concursos-federais"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Concurso AFT: MTE pede maior or\u00e7amento para excedentes<\/title>\n<meta name=\"description\" content=\"Minist\u00e9rio do Trabalho e Emprego (MTE) solicitou amplia\u00e7\u00e3o do or\u00e7amento para cria\u00e7\u00e3o de novos cargos e chamamento de excedentes do concurso.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-aft-excedentes\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Concurso AFT: MTE pede maior or\u00e7amento para excedentes\" \/>\n<meta property=\"og:description\" content=\"Minist\u00e9rio do Trabalho e Emprego (MTE) solicitou amplia\u00e7\u00e3o do or\u00e7amento para cria\u00e7\u00e3o de novos cargos e chamamento de excedentes do concurso.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-aft-excedentes\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-12T20:21:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-12T20:58:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/06\/01174123\/aft.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"432\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ronaldo Scanavini Neto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ronaldo Scanavini Neto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-aft-excedentes\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-aft-excedentes\/\"},\"author\":{\"name\":\"Ronaldo Scanavini Neto\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/70c2ad4297aa24ff8815b08215b23a76\"},\"headline\":\"Concurso AFT: MTE pede maior or\u00e7amento para excedentes\",\"datePublished\":\"2025-08-12T20:21:16+00:00\",\"dateModified\":\"2025-08-12T20:58:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-aft-excedentes\/\"},\"wordCount\":512,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-aft-excedentes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/06\/01174123\/aft.jpg\",\"articleSection\":[\"Fiscal - Federal (RFB e AFT)\",\"\u00daltimas not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-aft-excedentes\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-aft-excedentes\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-aft-excedentes\/\",\"name\":\"Concurso AFT: MTE pede maior or\u00e7amento para excedentes\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-aft-excedentes\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-aft-excedentes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/06\/01174123\/aft.jpg\",\"datePublished\":\"2025-08-12T20:21:16+00:00\",\"dateModified\":\"2025-08-12T20:58:39+00:00\",\"description\":\"Minist\u00e9rio do Trabalho e Emprego (MTE) solicitou amplia\u00e7\u00e3o do or\u00e7amento para cria\u00e7\u00e3o de novos cargos e chamamento de excedentes do concurso.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-aft-excedentes\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-aft-excedentes\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-aft-excedentes\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/06\/01174123\/aft.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/06\/01174123\/aft.jpg\",\"width\":768,\"height\":432,\"caption\":\"Concurso AFT: Cesgranrio confirma convoca\u00e7\u00e3o de aprovados!\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-aft-excedentes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Concurso AFT: MTE pede maior or\u00e7amento para excedentes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/70c2ad4297aa24ff8815b08215b23a76\",\"name\":\"Ronaldo Scanavini Neto\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/f93d8e56fe264596e94aee6b3feb737d98ad0fc5bac7eb0a245f04723c5c8f21?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f93d8e56fe264596e94aee6b3feb737d98ad0fc5bac7eb0a245f04723c5c8f21?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f93d8e56fe264596e94aee6b3feb737d98ad0fc5bac7eb0a245f04723c5c8f21?s=96&d=mm&r=g\",\"caption\":\"Ronaldo Scanavini Neto\"},\"description\":\"Graduando em Comunica\u00e7\u00e3o Social \u2013 Jornalismo pela Universidade Federal de Vi\u00e7osa (UFV). Integra a equipe de jornalismo do Estrat\u00e9gia Concursos desde 2023, atuando com \u00eanfase na cobertura da \u00e1rea fiscal. Tamb\u00e9m realiza a apura\u00e7\u00e3o e produ\u00e7\u00e3o de not\u00edcias sobre concursos federais, \u00f3rg\u00e3os participantes do CNU e das \u00e1reas de controle, gest\u00e3o, engenharia, Exame CFC, comunica\u00e7\u00e3o social TI e \u00e1rea de concursos administrativos.\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/ronaldo-netoestrategia-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Concurso AFT: MTE pede maior or\u00e7amento para excedentes","description":"Minist\u00e9rio do Trabalho e Emprego (MTE) solicitou amplia\u00e7\u00e3o do or\u00e7amento para cria\u00e7\u00e3o de novos cargos e chamamento de excedentes do concurso.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-aft-excedentes\/","og_locale":"pt_BR","og_type":"article","og_title":"Concurso AFT: MTE pede maior or\u00e7amento para excedentes","og_description":"Minist\u00e9rio do Trabalho e Emprego (MTE) solicitou amplia\u00e7\u00e3o do or\u00e7amento para cria\u00e7\u00e3o de novos cargos e chamamento de excedentes do concurso.","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-aft-excedentes\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2025-08-12T20:21:16+00:00","article_modified_time":"2025-08-12T20:58:39+00:00","og_image":[{"width":768,"height":432,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/06\/01174123\/aft.jpg","type":"image\/jpeg"}],"author":"Ronaldo Scanavini Neto","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Ronaldo Scanavini Neto","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-aft-excedentes\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-aft-excedentes\/"},"author":{"name":"Ronaldo Scanavini Neto","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/70c2ad4297aa24ff8815b08215b23a76"},"headline":"Concurso AFT: MTE pede maior or\u00e7amento para excedentes","datePublished":"2025-08-12T20:21:16+00:00","dateModified":"2025-08-12T20:58:39+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-aft-excedentes\/"},"wordCount":512,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-aft-excedentes\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/06\/01174123\/aft.jpg","articleSection":["Fiscal - Federal (RFB e AFT)","\u00daltimas not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-aft-excedentes\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-aft-excedentes\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-aft-excedentes\/","name":"Concurso AFT: MTE pede maior or\u00e7amento para excedentes","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-aft-excedentes\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-aft-excedentes\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/06\/01174123\/aft.jpg","datePublished":"2025-08-12T20:21:16+00:00","dateModified":"2025-08-12T20:58:39+00:00","description":"Minist\u00e9rio do Trabalho e Emprego (MTE) solicitou amplia\u00e7\u00e3o do or\u00e7amento para cria\u00e7\u00e3o de novos cargos e chamamento de excedentes do concurso.","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-aft-excedentes\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-aft-excedentes\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-aft-excedentes\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/06\/01174123\/aft.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/06\/01174123\/aft.jpg","width":768,"height":432,"caption":"Concurso AFT: Cesgranrio confirma convoca\u00e7\u00e3o de aprovados!"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-aft-excedentes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Concurso AFT: MTE pede maior or\u00e7amento para excedentes"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/70c2ad4297aa24ff8815b08215b23a76","name":"Ronaldo Scanavini Neto","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/f93d8e56fe264596e94aee6b3feb737d98ad0fc5bac7eb0a245f04723c5c8f21?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f93d8e56fe264596e94aee6b3feb737d98ad0fc5bac7eb0a245f04723c5c8f21?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f93d8e56fe264596e94aee6b3feb737d98ad0fc5bac7eb0a245f04723c5c8f21?s=96&d=mm&r=g","caption":"Ronaldo Scanavini Neto"},"description":"Graduando em Comunica\u00e7\u00e3o Social \u2013 Jornalismo pela Universidade Federal de Vi\u00e7osa (UFV). Integra a equipe de jornalismo do Estrat\u00e9gia Concursos desde 2023, atuando com \u00eanfase na cobertura da \u00e1rea fiscal. Tamb\u00e9m realiza a apura\u00e7\u00e3o e produ\u00e7\u00e3o de not\u00edcias sobre concursos federais, \u00f3rg\u00e3os participantes do CNU e das \u00e1reas de controle, gest\u00e3o, engenharia, Exame CFC, comunica\u00e7\u00e3o social TI e \u00e1rea de concursos administrativos.","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/ronaldo-netoestrategia-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1622401","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/2692"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1622401"}],"version-history":[{"count":3,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1622401\/revisions"}],"predecessor-version":[{"id":1622477,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1622401\/revisions\/1622477"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/783067"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1622401"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1622401"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1622401"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1622401"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}