{"id":1622264,"date":"2025-08-12T15:36:32","date_gmt":"2025-08-12T18:36:32","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=1622264"},"modified":"2025-08-12T17:49:52","modified_gmt":"2025-08-12T20:49:52","slug":"edital-do-concurso-goinfra","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-do-concurso-goinfra\/","title":{"rendered":"Edital do concurso Goinfra passa por adequa\u00e7\u00f5es \u00e0 lei de cotas"},"content":{"rendered":"\n<p>O aguardado edital do concurso da <strong>Ag\u00eancia Goiana de Infraestrutura e Transportes (Goinfra)<\/strong> s\u00f3 n\u00e3o foi publicado ainda porque est\u00e1 passando <strong>por adequa\u00e7\u00f5es referentes \u00e0 Lei de Cotas<\/strong>.<\/p>\n\n\n\n<p>Esses s\u00e3o os \u00faltimos ajustes antes da publica\u00e7\u00e3o do edital, que n\u00e3o deve passar do m\u00eas de outubro. As informa\u00e7\u00f5es <strong>exclusivas<\/strong> foram confirmadas por meio de uma fonte interna da Ag\u00eancia.<\/p>\n\n\n\n<p>O edital j\u00e1 estava basicamente pronto, mas, com a san\u00e7\u00e3o da Lei n\u00ba 23.389, passa a ser obrigat\u00f3ria a reserva de <strong>20% das vagas para cotas <\/strong>em concursos no estado de Goi\u00e1s.<\/p>\n\n\n\n<p>Vale lembrar que a banca organizadora j\u00e1 est\u00e1 devidamente contratada, sendo o Instituto Avalia a empresa escolhida para aplicar as etapas de provas, que tamb\u00e9m j\u00e1 est\u00e3o pr\u00e9-estipuladas.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"526\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/08\/12152446\/image-150-1024x526.png\" alt=\"Edital do concurso Goinfra em breve! | Imagem da pr\u00f3pria Ag\u00eancia Goiana de Infraestrutura e Transportes \" class=\"wp-image-1622289\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/08\/12152446\/image-150-1024x526.png 1024w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/08\/12152446\/image-150-300x154.png 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/08\/12152446\/image-150-768x395.png 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/08\/12152446\/image-150-1536x789.png 1536w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/08\/12152446\/image-150-2048x1052.png 2048w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/08\/12152446\/image-150-150x77.png 150w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Edital do concurso Goinfra em breve! | Imagem da pr\u00f3pria <a href=\"https:\/\/www.goinfra.go.gov.br\/\" target=\"_blank\" rel=\"noreferrer noopener\">Ag\u00eancia Goiana de Infraestrutura e Transportes<\/a> <\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-edital-do-concurso-goinfra-quais-serao-as-etapas-de-provas\">Edital do concurso Goinfra: quais ser\u00e3o as etapas de provas?<\/h3>\n\n\n\n<p>O Termo de Refer\u00eancia do concurso Goinfra foi disponibilizado pela Secretaria de Administra\u00e7\u00e3o, \u00f3rg\u00e3o respons\u00e1vel pela organiza\u00e7\u00e3o de todas as atividades do certame. <\/p>\n\n\n\n<p>No documento \u00e9 poss\u00edvel observar as etapas de avalia\u00e7\u00f5es, que ser\u00e3o constitu\u00eddas de provas objetivas e discursivas, ambas de car\u00e1ter classificat\u00f3rio e eliminat\u00f3rio, al\u00e9m de uma avalia\u00e7\u00e3o de t\u00edtulos, apenas classificat\u00f3rio.<\/p>\n\n\n\n<p>A prova objetiva do edital Goinfra ser\u00e1 aplicada no per\u00edodo matutino e ter\u00e1 cerca de 3 a 4 horas. J\u00e1 a prova discursiva ser\u00e1 no per\u00edodo vespertino, com 2 a 3 horas de dura\u00e7\u00e3o.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-prepare-se-para-o-edital-do-concurso-goinfra-estude-com-quem-mais-aprova-no-mercado\">Prepare-se para o edital do concurso Goinfra: estude com quem mais aprova no mercado!<\/h2>\n\n\n\n<div class=\"container\" id=\"boxes\">\n  <div class=\"row\">\n\n    <div class=\"col-sm\">\n      <div class=\"banner-estrat-corj\" id=\"box-assinatura\">\n        <h2 class=\"titulo-assinatura\" style=\"text-align: left;\">Cursos para Concurso Goinfra<\/h2>\n        <p class=\"subtitulo-assinatura\" style=\"text-align: left;\">Prepare-se com quem mais aprova!<\/p>\n        <div class=\"box-botao\" style=\"text-align: left;\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/cursosPorConcurso\/agencia-goiania-de-infraestrutura-e-transportes-goinfra\/\" role=\"button\" rel=\"noopener noreferrer\">CLIQUE AQUI<\/a>\n        <\/div>\n      <\/div><\/div><\/div><\/div>\n\n\n\n<p>Se voc\u00ea est\u00e1 se perguntando se vale a pena estudar para o concurso Goinfra, a resposta \u00e9 sim! Isso porque, o edital promete oferecer 63 vagas para o cargo de <strong>Gestor de Infraestrutura<\/strong>.<\/p>\n\n\n\n<p>O cargo permite a participa\u00e7\u00e3o de candidatos formados em Engenharia Civil, El\u00e9trica, Florestal, Agronomia, Mec\u00e2nica, Arquitetura ou \u00e1reas equivalentes.<\/p>\n\n\n\n<p>E o melhor: o <strong>sal\u00e1rio inicial do cargo \u00e9 de R$ 14.973,70<\/strong>, podendo chegar a <strong>mais de R$ 36 mil<\/strong> no final da carreira. Al\u00e9m disso, os futuros aprovados ter\u00e3o direito a diversos benef\u00edcios e vantagens que s\u00f3 a carreira p\u00fablica oferece!<\/p>\n\n\n\n<p class=\"has-text-align-center\"><em>Ficou interessado nas informa\u00e7\u00f5es dispon\u00edveis at\u00e9 aqui? Quer saber mais acerca do edital do concurso Goinfra? Ent\u00e3o acesse agora mesmo o artigo completo que preparamos para voc\u00ea:<\/em><\/p>\n\n\n\n<p class=\"has-text-align-center has-background\" style=\"background-color:#f3f3f3;font-size:clamp(14.642px, 0.915rem + ((1vw - 3.2px) * 0.721), 22px);\"><strong>Saiba mais: <a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-goinfra\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concurso Goinfra<\/a><\/strong><\/p>\n\n\n\n<div class=\"container\" id=\"boxes\">\n  <div class=\"row\">\n\n    <div class=\"col-sm\">\n      <div class=\"estrategia\" id=\"box-assinatura\">\n        <h3 class=\"titulo-assinatura\">Assinatura Concursos<\/h3>\n        <p class=\"subtitulo-assinatura\">Assinatura de 1 ano ou 2 anos<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/assinaturas\/\" role=\"button\" rel=\"noopener noreferrer\">ASSINE AGORA<\/a>\n        <\/div>\n      <\/div><\/div><\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"h-quer-saber-tudo-sobre-concursos-previstos-confira-nossos-artigos\">Quer saber tudo sobre concursos previstos?<br \/>Confira nossos artigos!<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-administrativos\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos Administrativos<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos Abertos<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2025\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos 2025<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2026\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos 2026<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>O aguardado edital do concurso da Ag\u00eancia Goiana de Infraestrutura e Transportes (Goinfra) s\u00f3 n\u00e3o foi publicado ainda porque est\u00e1 passando por adequa\u00e7\u00f5es referentes \u00e0 Lei de Cotas. Esses s\u00e3o os \u00faltimos ajustes antes da publica\u00e7\u00e3o do edital, que n\u00e3o deve passar do m\u00eas de outubro. As informa\u00e7\u00f5es exclusivas foram confirmadas por meio de uma [&hellip;]<\/p>\n","protected":false},"author":656,"featured_media":889334,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"news","footnotes":""},"categories":[214992,220219],"tags":[],"tax_estado":[219972],"class_list":["post-1622264","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-concursos-administrativos","category-noticias","tax_estado-go"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Edital do concurso Goinfra passa por adequa\u00e7\u00f5es \u00e0 lei de cotas<\/title>\n<meta name=\"description\" content=\"Edital do concurso Goinfra passa por adequa\u00e7\u00f5es \u00e0 lei de cotas. Publica\u00e7\u00e3o pode ocorrer at\u00e9 outubro. Cargo com sal\u00e1rio de R$ 14,9 mil!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-do-concurso-goinfra\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Edital do concurso Goinfra passa por adequa\u00e7\u00f5es \u00e0 lei de cotas\" \/>\n<meta property=\"og:description\" content=\"Edital do concurso Goinfra passa por adequa\u00e7\u00f5es \u00e0 lei de cotas. Publica\u00e7\u00e3o pode ocorrer at\u00e9 outubro. Cargo com sal\u00e1rio de R$ 14,9 mil!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-do-concurso-goinfra\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-12T18:36:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-12T20:49:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/10\/20144059\/goinfra.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"432\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"F\u00e1bio Scaldelai\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"F\u00e1bio Scaldelai\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-do-concurso-goinfra\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-do-concurso-goinfra\/\"},\"author\":{\"name\":\"F\u00e1bio Scaldelai\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/e3b6b7ce0192dd4ad270655969d61750\"},\"headline\":\"Edital do concurso Goinfra passa por adequa\u00e7\u00f5es \u00e0 lei de cotas\",\"datePublished\":\"2025-08-12T18:36:32+00:00\",\"dateModified\":\"2025-08-12T20:49:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-do-concurso-goinfra\/\"},\"wordCount\":452,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-do-concurso-goinfra\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/10\/20144059\/goinfra.jpg\",\"articleSection\":[\"Executivo (Administrativa)\",\"\u00daltimas not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-do-concurso-goinfra\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-do-concurso-goinfra\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-do-concurso-goinfra\/\",\"name\":\"Edital do concurso Goinfra passa por adequa\u00e7\u00f5es \u00e0 lei de cotas\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-do-concurso-goinfra\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-do-concurso-goinfra\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/10\/20144059\/goinfra.jpg\",\"datePublished\":\"2025-08-12T18:36:32+00:00\",\"dateModified\":\"2025-08-12T20:49:52+00:00\",\"description\":\"Edital do concurso Goinfra passa por adequa\u00e7\u00f5es \u00e0 lei de cotas. Publica\u00e7\u00e3o pode ocorrer at\u00e9 outubro. Cargo com sal\u00e1rio de R$ 14,9 mil!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-do-concurso-goinfra\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-do-concurso-goinfra\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-do-concurso-goinfra\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/10\/20144059\/goinfra.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/10\/20144059\/goinfra.jpg\",\"width\":768,\"height\":432,\"caption\":\"Edital do concurso Goinfra\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-do-concurso-goinfra\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Edital do concurso Goinfra passa por adequa\u00e7\u00f5es \u00e0 lei de cotas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/e3b6b7ce0192dd4ad270655969d61750\",\"name\":\"F\u00e1bio Scaldelai\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/8ed7492c4d88d8495bc0cb24cda6847b8ae23eec459a919e08e77d0ca0fd79ec?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8ed7492c4d88d8495bc0cb24cda6847b8ae23eec459a919e08e77d0ca0fd79ec?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8ed7492c4d88d8495bc0cb24cda6847b8ae23eec459a919e08e77d0ca0fd79ec?s=96&d=mm&r=g\",\"caption\":\"F\u00e1bio Scaldelai\"},\"description\":\"Jornalista no Estrat\u00e9gia Concursos e Produtor de Televis\u00e3o, formado em Jornalismo, R\u00e1dio e TV pela Faculdade Integrada Rio Branco, com especializa\u00e7\u00f5es em Gest\u00e3o Empresarial e Marketing pelo M\u00f3dulo. Atuou como produtor no SBT, TV Bandeirantes e R\u00e1dio Band FM, al\u00e9m de acumular tr\u00eas anos de experi\u00eancia no setor de concursos p\u00fablicos pela LFG (Luiz Fl\u00e1vio Gomes). No Estrat\u00e9gia Concursos, atua na apura\u00e7\u00e3o de not\u00edcias da \u00e1rea fiscal, al\u00e9m de coberturas sobre concursos das \u00e1reas de controle (TCU, TCE, etc), concurso AFT, \u00e1rea de gest\u00e3o e administrativa, bem como dos \u00f3rg\u00e3os participantes do CNU. Tamb\u00e9m possui experi\u00eancia em link building e an\u00e1lise de m\u00eddia, adquirida durante sua atua\u00e7\u00e3o na ag\u00eancia SEO Marketing.\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/fabio-scaldelaiestrategiaconcursos-com-br\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Edital do concurso Goinfra passa por adequa\u00e7\u00f5es \u00e0 lei de cotas","description":"Edital do concurso Goinfra passa por adequa\u00e7\u00f5es \u00e0 lei de cotas. Publica\u00e7\u00e3o pode ocorrer at\u00e9 outubro. Cargo com sal\u00e1rio de R$ 14,9 mil!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-do-concurso-goinfra\/","og_locale":"pt_BR","og_type":"article","og_title":"Edital do concurso Goinfra passa por adequa\u00e7\u00f5es \u00e0 lei de cotas","og_description":"Edital do concurso Goinfra passa por adequa\u00e7\u00f5es \u00e0 lei de cotas. Publica\u00e7\u00e3o pode ocorrer at\u00e9 outubro. Cargo com sal\u00e1rio de R$ 14,9 mil!","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-do-concurso-goinfra\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2025-08-12T18:36:32+00:00","article_modified_time":"2025-08-12T20:49:52+00:00","og_image":[{"width":768,"height":432,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/10\/20144059\/goinfra.jpg","type":"image\/jpeg"}],"author":"F\u00e1bio Scaldelai","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"F\u00e1bio Scaldelai","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-do-concurso-goinfra\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-do-concurso-goinfra\/"},"author":{"name":"F\u00e1bio Scaldelai","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/e3b6b7ce0192dd4ad270655969d61750"},"headline":"Edital do concurso Goinfra passa por adequa\u00e7\u00f5es \u00e0 lei de cotas","datePublished":"2025-08-12T18:36:32+00:00","dateModified":"2025-08-12T20:49:52+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-do-concurso-goinfra\/"},"wordCount":452,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-do-concurso-goinfra\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/10\/20144059\/goinfra.jpg","articleSection":["Executivo (Administrativa)","\u00daltimas not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-do-concurso-goinfra\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-do-concurso-goinfra\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-do-concurso-goinfra\/","name":"Edital do concurso Goinfra passa por adequa\u00e7\u00f5es \u00e0 lei de cotas","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-do-concurso-goinfra\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-do-concurso-goinfra\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/10\/20144059\/goinfra.jpg","datePublished":"2025-08-12T18:36:32+00:00","dateModified":"2025-08-12T20:49:52+00:00","description":"Edital do concurso Goinfra passa por adequa\u00e7\u00f5es \u00e0 lei de cotas. Publica\u00e7\u00e3o pode ocorrer at\u00e9 outubro. Cargo com sal\u00e1rio de R$ 14,9 mil!","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-do-concurso-goinfra\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-do-concurso-goinfra\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-do-concurso-goinfra\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/10\/20144059\/goinfra.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/10\/20144059\/goinfra.jpg","width":768,"height":432,"caption":"Edital do concurso Goinfra"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-do-concurso-goinfra\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Edital do concurso Goinfra passa por adequa\u00e7\u00f5es \u00e0 lei de cotas"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/e3b6b7ce0192dd4ad270655969d61750","name":"F\u00e1bio Scaldelai","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/8ed7492c4d88d8495bc0cb24cda6847b8ae23eec459a919e08e77d0ca0fd79ec?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8ed7492c4d88d8495bc0cb24cda6847b8ae23eec459a919e08e77d0ca0fd79ec?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8ed7492c4d88d8495bc0cb24cda6847b8ae23eec459a919e08e77d0ca0fd79ec?s=96&d=mm&r=g","caption":"F\u00e1bio Scaldelai"},"description":"Jornalista no Estrat\u00e9gia Concursos e Produtor de Televis\u00e3o, formado em Jornalismo, R\u00e1dio e TV pela Faculdade Integrada Rio Branco, com especializa\u00e7\u00f5es em Gest\u00e3o Empresarial e Marketing pelo M\u00f3dulo. Atuou como produtor no SBT, TV Bandeirantes e R\u00e1dio Band FM, al\u00e9m de acumular tr\u00eas anos de experi\u00eancia no setor de concursos p\u00fablicos pela LFG (Luiz Fl\u00e1vio Gomes). No Estrat\u00e9gia Concursos, atua na apura\u00e7\u00e3o de not\u00edcias da \u00e1rea fiscal, al\u00e9m de coberturas sobre concursos das \u00e1reas de controle (TCU, TCE, etc), concurso AFT, \u00e1rea de gest\u00e3o e administrativa, bem como dos \u00f3rg\u00e3os participantes do CNU. Tamb\u00e9m possui experi\u00eancia em link building e an\u00e1lise de m\u00eddia, adquirida durante sua atua\u00e7\u00e3o na ag\u00eancia SEO Marketing.","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/fabio-scaldelaiestrategiaconcursos-com-br\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1622264","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/656"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1622264"}],"version-history":[{"count":9,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1622264\/revisions"}],"predecessor-version":[{"id":1622467,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1622264\/revisions\/1622467"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/889334"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1622264"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1622264"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1622264"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1622264"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}