{"id":1621157,"date":"2025-08-31T11:45:00","date_gmt":"2025-08-31T14:45:00","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=1621157"},"modified":"2025-08-25T11:23:51","modified_gmt":"2025-08-25T14:23:51","slug":"crime-atentado-soberania-cnu","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/crime-atentado-soberania-cnu\/","title":{"rendered":"Crime de Atentado \u00e0 Soberania para o CNU"},"content":{"rendered":"\n<p>Ol\u00e1, tudo bem? Hoje faremos um resumo sobre o <strong>crime de atentado \u00e0 soberania (art. 359-I do C\u00f3digo Penal)<\/strong>, visando ao CNU (Concurso Nacional Unificado).<\/p>\n\n\n\n<p>O<a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-nacional-unificado\/\" target=\"_blank\" rel=\"noreferrer noopener\"> edital do CNU<\/a> (o \u201cENEM dos concursos\u201d) foi lan\u00e7ado e destrinchado em<a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-blocos-tematicos\/\" target=\"_blank\" rel=\"noreferrer noopener\"> 09 blocos tem\u00e1ticos do CNU<\/a> 2025, conforme as suas respectivas \u201c\u00e1reas de conhecimento\u201d.<\/p>\n\n\n\n<p>Foram disponibilizadas <strong>3.652 vagas<\/strong> para este pr\u00f3ximo certame, sendo 2.480 imediatas e 1.172 para forma\u00e7\u00e3o de cadastro reserva, com sal\u00e1rios variando de R$4.804,89 a R$16.413,35.<\/p>\n\n\n\n<p>Portanto, vamos ao que interessa!<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/08\/11071131\/crime-de-atentado-a-soberania-para-o-cnu-1024x1024.png\" alt=\"Crime de Atentado \u00e0 Soberania para o CNU\" class=\"wp-image-1621162\" style=\"width:704px;height:auto\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/08\/11071131\/crime-de-atentado-a-soberania-para-o-cnu-1024x1024.png 1024w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/08\/11071131\/crime-de-atentado-a-soberania-para-o-cnu-300x300.png 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/08\/11071131\/crime-de-atentado-a-soberania-para-o-cnu-150x150.png 150w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/08\/11071131\/crime-de-atentado-a-soberania-para-o-cnu-768x768.png 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/08\/11071131\/crime-de-atentado-a-soberania-para-o-cnu-96x96.png 96w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/08\/11071131\/crime-de-atentado-a-soberania-para-o-cnu.png 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Crime de Atentado \u00e0 Soberania para o CNU<\/figcaption><\/figure>\n\n\n\n<div class=\"wp-block-yoast-seo-table-of-contents yoast-table-of-contents\"><h2><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">Tabela de conte\u00fados<\/mark><\/h2><ul><li><a href=\"#h-crime-de-atentado-a-soberania-para-o-cnu\" data-level=\"2\">Crime de Atentado \u00e0 Soberania para o CNU<\/a><ul><li><a href=\"#h-previsao-legal-nbsp\" data-level=\"3\">Previs\u00e3o legal\u00a0<\/a><\/li><li><a href=\"#h-sujeitos-ativo-e-passivo-objeto-juridico-tutelado-do-crime-de-atentado-a-soberania\" data-level=\"3\">Sujeitos ativo e passivo + Objeto jur\u00eddico tutelado do crime de atentado \u00e0 soberania<\/a><\/li><li><a href=\"#h-causa-de-aumento-de-pena-nbsp\" data-level=\"3\">Causa de aumento de pena\u00a0<\/a><\/li><li><a href=\"#h-figura-qualificada-do-crime-de-atentado-a-soberania\" data-level=\"3\">Figura qualificada do crime de atentado \u00e0 soberania<\/a><\/li><li><a href=\"#h-penas-cominadas-ao-crime-de-atentado-a-soberania\" data-level=\"3\">Penas cominadas ao crime de atentado \u00e0 soberania<\/a><ul><li><a href=\"#h-pena-do-caput\" data-level=\"4\">Pena do caput<\/a><\/li><\/ul><\/li><\/ul><\/li><li><a href=\"#h-consideracoes-finais\" data-level=\"2\">Considera\u00e7\u00f5es finais<\/a><\/li><li><a href=\"#h-quer-saber-tudo-sobre-concursos-previstos-confira-nossos-artigos\" data-level=\"2\">Quer saber tudo sobre concursos previstos? Confira nossos artigos!<\/a><\/li><\/ul><\/div>\n\n\n\n<h2 class=\"wp-block-heading has-vivid-cyan-blue-color has-text-color has-link-color wp-elements-fa7da96c30bf8df35322bd144ae0ebea\" id=\"h-crime-de-atentado-a-soberania-para-o-cnu\">Crime de Atentado \u00e0 Soberania para o CNU<\/h2>\n\n\n\n<h3 class=\"wp-block-heading has-vivid-cyan-blue-color has-text-color has-link-color wp-elements-e9b96cebda061df3a020d2d518353576\" id=\"h-previsao-legal-nbsp\">Previs\u00e3o legal&nbsp;<\/h3>\n\n\n\n<p>De in\u00edcio, aponta-se que o crime de atentado \u00e0 soberania est\u00e1 previsto no artigo 359-I do C\u00f3digo Penal (CP), o qual foi inserido pela Lei 14.197\/2021:<\/p>\n\n\n\n<div class=\"wp-block-group has-background has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\" style=\"background-color:#8dd2fc38\">\n<p><strong>Atentado \u00e0 soberania&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/strong><\/p>\n\n\n\n<p>Art. 359-I. Negociar com governo ou grupo estrangeiro, ou seus agentes, com o fim de provocar atos t\u00edpicos de guerra contra o Pa\u00eds ou invadi-lo:&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p>Pena &#8211; reclus\u00e3o, de 3 (tr\u00eas) a 8 (oito) anos.&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n<\/div>\n\n\n\n<p>A conduta pun\u00edvel, portanto, \u00e9 a de <strong>negociar<\/strong>, que pode significar a barganha, o com\u00e9rcio, a transa\u00e7\u00e3o <strong>com governo ou grupo estrangeiro, ou com seus agentes<\/strong>.<\/p>\n\n\n\n<p>Essa negocia\u00e7\u00e3o deve ser realizada com a <strong>finalidade espec\u00edfica de provocar atos t\u00edpicos de guerra contra o Pa\u00eds ou de invadi-lo.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter\"><img decoding=\"async\" src=\"https:\/\/lh7-rt.googleusercontent.com\/docsz\/AD_4nXcAJ3H2szf1be3_OpshkDpN6V6EDTzJt2Xpa2rRYLC72SQaobqgCWs_29ABkRciYpPEEr1Jums6X8EBHFzBo5R7fX9x59n3D2e2RMMbQqauJbD6bYqCH93azBriJVZaPA_o4pPLqw?key=EdvpFtOQ0cqT4A35RU1Eaw\" alt=\"\"\/><\/figure>\n\n\n\n<p>Imagine que Jo\u00e3o e Maria tenham morado por alguns anos em um pa\u00eds estrangeiro e retornado para o Brasil. Alguns anos depois, agentes daquele governo estrangeiro, visando roubar recursos naturais do Brasil, entraram em contato com eles e lhes ofereceram certa quantia em dinheiro para que esses praticassem atos que permitissem a invas\u00e3o do territ\u00f3rio nacional. Nesse caso, estaremos diante do tipo penal do art. 359-I.&nbsp;<\/p>\n\n\n\n<p>Neste momento, \u00e9 importante destacarmos as li\u00e7\u00f5es de Cezar Roberto Bitencourt, que chama aten\u00e7\u00e3o para o fato de que tais condutas de gravidade nunca antes vistas na legisla\u00e7\u00e3o brasileira tenham sido apenas de forma t\u00e3o branda:<\/p>\n\n\n\n<div class=\"wp-block-group has-background has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\" style=\"background-color:#9b51e024\">\n<p>\u201c(&#8230;) Deixa-nos perplexos s\u00f3 de imaginar uma hipot\u00e9tica situa\u00e7\u00e3o dessas, nosso Pa\u00eds sendo invadido pela trai\u00e7\u00e3o de um ou alguns brasileiros! No entanto, as penas cominadas n\u00e3o s\u00e3o condizentes com essa gravidade, sendo, ali\u00e1s, inferiores \u00e0s penas cominadas para um crime de roubo simples que \u00e9 dez anos de reclus\u00e3o (&#8230;)\u201d.<\/p>\n<\/div>\n\n\n\n<h3 class=\"wp-block-heading has-vivid-cyan-blue-color has-text-color has-link-color wp-elements-a6be29e96d87d650a7567d2ff0266735\" id=\"h-sujeitos-ativo-e-passivo-objeto-juridico-tutelado-do-crime-de-atentado-a-soberania\">Sujeitos ativo e passivo + Objeto jur\u00eddico tutelado do crime de atentado \u00e0 soberania<\/h3>\n\n\n\n<p>O <strong>sujeito ativo<\/strong> pode ser qualquer pessoa, raz\u00e3o pela qual classificamos esse crime como \u201ccomum\u201d. O <strong>sujeito passivo<\/strong> \u00e9 a pr\u00f3pria Rep\u00fablica Federativa do Brasil, o Estado Democr\u00e1tico de Direito, conforme leciona Bitencourt.&nbsp;<\/p>\n\n\n\n<p>Por sua vez, o <strong>objeto jur\u00eddico tutelado<\/strong> \u00e9 a <strong>soberania nacional<\/strong>, a qual, inclusive, \u00e9 erigida pela Constitui\u00e7\u00e3o Federal de 1988 como <strong>um dos fundamentos da Rep\u00fablica<\/strong> Federativa do Brasil (art. 1\u00ba, inciso I, da CF\/88).<\/p>\n\n\n\n<p>O Supremo Tribunal Federal entende a soberania como \u201co poder pol\u00edtico supremo dentro do territ\u00f3rio\u201d. J\u00e1 no plano internacional, o STF entende que a soberania funda-se no princ\u00edpio da independ\u00eancia nacional (art. 4\u00ba, inciso I, da CF), efetivada pelo presidente da Rep\u00fablica, consoante suas atribui\u00e7\u00f5es previstas no art. 84, VII e VIII, da Lei Maior [<a href=\"https:\/\/redir.stf.jus.br\/paginadorpub\/paginador.jsp?docTP=TP&amp;docID=1495257\" target=\"_blank\" rel=\"noreferrer noopener\"><em>Rcl 11.243<\/em><\/a><em>, rel. min. Gilmar Mendes, red. do ac. min. Luiz Fux, j. 8-6-2011, P, DJE de 5-10-2011.<\/em>].<\/p>\n\n\n\n<h3 class=\"wp-block-heading has-vivid-cyan-blue-color has-text-color has-link-color wp-elements-118050034cd9399790ac2c1cd9d5b727\" id=\"h-causa-de-aumento-de-pena-nbsp\">Causa de aumento de pena&nbsp;<\/h3>\n\n\n\n<p>O C\u00f3digo Penal ainda prev\u00ea causa de aumento de pena (majorante) para os casos em que as condutas praticadas <strong>acarretam a declara\u00e7\u00e3o de guerra<\/strong>:<\/p>\n\n\n\n<div class=\"wp-block-group has-background has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\" style=\"background-color:#8dd2fc38\">\n<p>\u00a7 1\u00ba Aumenta-se a pena de metade at\u00e9 o dobro, se declarada guerra em decorr\u00eancia das condutas previstas no caput deste artigo.<\/p>\n<\/div>\n\n\n\n<p>Nesse caso, as penas podem ser aumentadas <strong>da metade<\/strong> <strong>at\u00e9 o dobro<\/strong> quando da terceira fase da dosimetria da pena (art. 68 do CP).<\/p>\n\n\n\n<p>Ent\u00e3o, por exemplo, se o indiv\u00edduo tem, nas primeira e segunda fase da dosimetria, pena fixada no m\u00ednimo legal de 03 (tr\u00eas) anos, a pena poderia aumentar de 4 anos e 6 meses at\u00e9 06 anos, caso aplicada essa causa de aumento de pena.<\/p>\n\n\n\n<p>Cezar Roberto Bitencourt ainda comenta que a presente causa de aumento de pena, embora possa chegar a duplicar a pena do <em>caput<\/em>, ainda assim n\u00e3o \u00e9 suficiente para penalizar conduta de tamanha gravidade.<\/p>\n\n\n\n<h3 class=\"wp-block-heading has-vivid-cyan-blue-color has-text-color has-link-color wp-elements-d3adabfea238b55f9aa51d496576466a\" id=\"h-figura-qualificada-do-crime-de-atentado-a-soberania\">Figura qualificada do crime de atentado \u00e0 soberania<\/h3>\n\n\n\n<p>O C\u00f3digo Penal ainda prev\u00ea uma figura qualificada (qualificadora) para o caso de o agente participar de opera\u00e7\u00e3o b\u00e9lica com a finalidade de submeter o territ\u00f3rio nacional, ou parte dele, ao dom\u00ednio ou \u00e0 soberania de outro pa\u00eds:&nbsp;&nbsp;<\/p>\n\n\n\n<div class=\"wp-block-group has-background has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\" style=\"background-color:#8dd2fc38\">\n<p>\u00a7 2\u00ba Se o agente participa de opera\u00e7\u00e3o b\u00e9lica com o fim de submeter o territ\u00f3rio nacional, ou parte dele, ao dom\u00ednio ou \u00e0 soberania de outro pa\u00eds:&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p>Pena &#8211; reclus\u00e3o, de 4 (quatro) a 12 (doze) anos.<\/p>\n<\/div>\n\n\n\n<p>Nesse caso tamb\u00e9m estamos de conduta grav\u00edssima em que a inten\u00e7\u00e3o do agente \u00e9 submeter todo o territ\u00f3rio nacional e, assim, milh\u00f5es de brasileiros, ao dom\u00ednio ou \u00e0 soberania de outro pa\u00eds.&nbsp;<\/p>\n\n\n\n<p>A qualificadora tamb\u00e9m se configura caso a inten\u00e7\u00e3o seja submeter apenas parte do territ\u00f3rio. Como n\u00e3o houve especifica\u00e7\u00e3o do legislador sobre o \u201ctamanho\u201d dessa express\u00e3o \u201cparte dele\u201d, entendemos que qualquer fra\u00e7\u00e3o do territ\u00f3rio nacional servir\u00e1 como elementar dessa qualificadora.<\/p>\n\n\n\n<h3 class=\"wp-block-heading has-vivid-cyan-blue-color has-text-color has-link-color wp-elements-2537937143ac01f85c9b7e9c78a22076\" id=\"h-penas-cominadas-ao-crime-de-atentado-a-soberania\">Penas cominadas ao crime de atentado \u00e0 soberania<\/h3>\n\n\n\n<h4 class=\"wp-block-heading has-vivid-cyan-blue-color has-text-color has-link-color wp-elements-5a50ce8f7d609ce962dd4119710c4397\" id=\"h-pena-do-caput\">Pena do <em>caput<\/em><\/h4>\n\n\n\n<p>A pena do <em>caput<\/em> de <strong>reclus\u00e3o, de 3 (tr\u00eas) a 8 (oito) anos<\/strong>.<\/p>\n\n\n\n<p>Diante da pena de <strong>reclus\u00e3o<\/strong>, temos que o legislador permite o in\u00edcio do cumprimento de pena em qualquer <strong>regime, inclusive o fechado<\/strong>, vide art. 33 do C\u00f3digo Penal.&nbsp;<\/p>\n\n\n\n<p>Como a pena m\u00e1xima cominada \u00e9 superior a 02 anos, <strong>n\u00e3o \u00e9 poss\u00edvel<\/strong> a utiliza\u00e7\u00e3o do benef\u00edcio da <strong>transa\u00e7\u00e3o penal<\/strong>, prevista no artigo 76 da Lei 9.099\/1995 (Lei dos Juizados Especiais).&nbsp;<\/p>\n\n\n\n<p>Al\u00e9m disso, n\u00e3o sendo a pena m\u00ednima superior a 01 ano, <strong>n\u00e3o \u00e9 cab\u00edvel a suspens\u00e3o condicional do processo <\/strong>(\u201c<em>sursis<\/em> processual\u201d &#8211; artigo 89 da Lei 9.099\/1995).&nbsp;<\/p>\n\n\n\n<p>Por outro lado, tratando-se de pena m\u00ednima inferior a 04 anos, <strong>\u00e9 cab\u00edvel<\/strong> em tese o <strong>acordo de n\u00e3o persecu\u00e7\u00e3o penal <\/strong>(ANPP &#8211; artigo 28-A do C\u00f3digo de Processo Penal), desde que n\u00e3o incida a majorante do \u00a7 1\u00ba ou a qualificadora do \u00a7 2\u00ba. No entanto, diante da gravidade da conduta, pode ser que o Minist\u00e9rio P\u00fablico deixe de oferecer tal acordo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-vivid-cyan-blue-color has-text-color has-link-color wp-elements-2bedaf953dddcc5060475c06777272ac\" id=\"h-consideracoes-finais\">Considera\u00e7\u00f5es finais<\/h2>\n\n\n\n<p>Portanto, pessoal, esse foi nosso breve resumo sobre o crime de atentado \u00e0 soberania visando ao CNU (Concurso Nacional Unificado), conforme art. 359-I do C\u00f3digo Penal.<\/p>\n\n\n\n<p>Nosso tempo aqui \u00e9 breve e n\u00e3o conseguimos, claro, esgotar o assunto. Portanto, n\u00e3o deixe de revisar o tema em seu material de estudo e praticar com diversas quest\u00f5es.<\/p>\n\n\n\n<p>At\u00e9 a pr\u00f3xima!<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img decoding=\"async\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/09\/18141901\/Coruja_Concursos%404x-506x1024.png\" alt=\"Concursos 2024 Estrat\u00e9gia Concursos\" class=\"wp-image-574355\" style=\"aspect-ratio:0.5;width:30px;height:auto\"\/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"h-quer-saber-tudo-sobre-concursos-previstos-confira-nossos-artigos\">Quer saber tudo sobre concursos previstos?<br \/>Confira nossos artigos!<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos Abertos<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2025\/\">Concursos 2025<\/a><\/li>\n<\/ul>\n\n\n\n<div class=\"container\" id=\"boxes\">\n  <div class=\"row\">\n\n    <div class=\"col-sm\">\n      <div class=\"banner-estrat-corj\" id=\"box-assinatura\">\n        <h3 class=\"titulo-assinatura\" style=\"text-align: left;\">Concursos 2025<\/h3>\n        <p class=\"subtitulo-assinatura\" style=\"text-align: left;\">Explore os cursos preparat\u00f3rios completos! \u2728<\/p>\n        <div class=\"box-botao\" style=\"text-align: left;\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/cursos\/concurso\/\" role=\"button\" rel=\"noopener noreferrer\">CLIQUE AQUI<\/a>\n        <\/div>\n      <\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"container\" id=\"boxes\">\n  <div class=\"row\">\n\n    <div class=\"col-sm\">\n      <div class=\"estrategia\" id=\"box-assinatura\">\n        <h3 class=\"titulo-assinatura\">Assinatura Concursos<\/h3>\n        <p class=\"subtitulo-assinatura\">Assinatura de 1 ano ou 2 anos<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/assinaturas\/\" role=\"button\" rel=\"noopener noreferrer\">ASSINE AGORA<\/a>\n        <\/div>\n      <\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Ol\u00e1, tudo bem? Hoje faremos um resumo sobre o crime de atentado \u00e0 soberania (art. 359-I do C\u00f3digo Penal), visando ao CNU (Concurso Nacional Unificado). O edital do CNU (o \u201cENEM dos concursos\u201d) foi lan\u00e7ado e destrinchado em 09 blocos tem\u00e1ticos do CNU 2025, conforme as suas respectivas \u201c\u00e1reas de conhecimento\u201d. Foram disponibilizadas 3.652 vagas [&hellip;]<\/p>\n","protected":false},"author":2567,"featured_media":1621162,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[220215,220216,1,3766,214992,220191,1981],"tags":[],"tax_estado":[219964,219965,219966,219967,219968,219969,219963,219970,219971,219972,219973,219974,219975,219976,219977,219978,219979,219980,219981,219982,219983,219984,219985,219986,219987,219988,219989,219990],"class_list":["post-1621157","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agencia-reguladora","category-agencia-reguladora-agencia-reguladora","category-cursos-e-concursos","category-educacional","category-concursos-administrativos","category-previdenciaria","category-saude","tax_estado-ac","tax_estado-al","tax_estado-am","tax_estado-ap","tax_estado-ba","tax_estado-ce","tax_estado-concursos-federais","tax_estado-df","tax_estado-es","tax_estado-go","tax_estado-ma","tax_estado-mg","tax_estado-ms","tax_estado-mt","tax_estado-pa","tax_estado-pb","tax_estado-pe","tax_estado-pi","tax_estado-pr","tax_estado-rj","tax_estado-rn","tax_estado-ro","tax_estado-rr","tax_estado-rs","tax_estado-sc","tax_estado-se","tax_estado-sp","tax_estado-to"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Crime de Atentado \u00e0 Soberania para o CNU<\/title>\n<meta name=\"description\" content=\"Resumo sobre o crime de atentado \u00e0 soberania (art. 359-I do C\u00f3digo Penal), visando ao CNU (Concurso Nacional Unificado).\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/crime-atentado-soberania-cnu\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Crime de Atentado \u00e0 Soberania para o CNU\" \/>\n<meta property=\"og:description\" content=\"Resumo sobre o crime de atentado \u00e0 soberania (art. 359-I do C\u00f3digo Penal), visando ao CNU (Concurso Nacional Unificado).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/crime-atentado-soberania-cnu\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-31T14:45:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/08\/11071131\/crime-de-atentado-a-soberania-para-o-cnu.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Frederico Tadeu Borlot Peixoto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Frederico Tadeu Borlot Peixoto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/crime-atentado-soberania-cnu\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/crime-atentado-soberania-cnu\/\"},\"author\":{\"name\":\"Frederico Tadeu Borlot Peixoto\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/48a7e085e45aee7c3d4596399af50ebb\"},\"headline\":\"Crime de Atentado \u00e0 Soberania para o CNU\",\"datePublished\":\"2025-08-31T14:45:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/crime-atentado-soberania-cnu\/\"},\"wordCount\":1241,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/crime-atentado-soberania-cnu\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/08\/11071131\/crime-de-atentado-a-soberania-para-o-cnu.png\",\"articleSection\":[\"Ag\u00eancia Reguladora\",\"Ag\u00eancia Reguladora\",\"Concursos P\u00fablicos\",\"Educa\u00e7\u00e3o\",\"Executivo (Administrativa)\",\"Previdenci\u00e1ria (INSS, PREVIC)\",\"Sa\u00fade\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/crime-atentado-soberania-cnu\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"accessibilityFeature\":[\"tableOfContents\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/crime-atentado-soberania-cnu\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/crime-atentado-soberania-cnu\/\",\"name\":\"Crime de Atentado \u00e0 Soberania para o CNU\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/crime-atentado-soberania-cnu\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/crime-atentado-soberania-cnu\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/08\/11071131\/crime-de-atentado-a-soberania-para-o-cnu.png\",\"datePublished\":\"2025-08-31T14:45:00+00:00\",\"description\":\"Resumo sobre o crime de atentado \u00e0 soberania (art. 359-I do C\u00f3digo Penal), visando ao CNU (Concurso Nacional Unificado).\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/crime-atentado-soberania-cnu\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/crime-atentado-soberania-cnu\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/crime-atentado-soberania-cnu\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/08\/11071131\/crime-de-atentado-a-soberania-para-o-cnu.png\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/08\/11071131\/crime-de-atentado-a-soberania-para-o-cnu.png\",\"width\":1080,\"height\":1080,\"caption\":\"Crime de Atentado \u00e0 Soberania para o CNU\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/crime-atentado-soberania-cnu\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Crime de Atentado \u00e0 Soberania para o CNU\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/48a7e085e45aee7c3d4596399af50ebb\",\"name\":\"Frederico Tadeu Borlot Peixoto\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/df8a49e2321c1e32f85e9e7c2a9c92c688f1f53a947220f40017ff5858b09fdb?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/df8a49e2321c1e32f85e9e7c2a9c92c688f1f53a947220f40017ff5858b09fdb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/df8a49e2321c1e32f85e9e7c2a9c92c688f1f53a947220f40017ff5858b09fdb?s=96&d=mm&r=g\",\"caption\":\"Frederico Tadeu Borlot Peixoto\"},\"description\":\"Analista Judici\u00e1rio - \u00c1rea Judici\u00e1ria do TRF da 4\u00aa regi\u00e3o. Bacharel em Direito. P\u00f3s-graduado em Direito Administrativo, Legisla\u00e7\u00e3o Penal Especial, Direito Penal e Direito Processual Penal. Tamb\u00e9m nomeado no TRF da 3\u00aa regi\u00e3o (8\u00ba lugar); SPPREV (3\u00ba lugar); IFES (2\u00ba lugar); e PMES. https:\/\/www.instagram.com\/proffrederico\/\",\"sameAs\":[\"https:\/\/www.instagram.com\/proffrederico\/\"],\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/xfredericohotmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Crime de Atentado \u00e0 Soberania para o CNU","description":"Resumo sobre o crime de atentado \u00e0 soberania (art. 359-I do C\u00f3digo Penal), visando ao CNU (Concurso Nacional Unificado).","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/crime-atentado-soberania-cnu\/","og_locale":"pt_BR","og_type":"article","og_title":"Crime de Atentado \u00e0 Soberania para o CNU","og_description":"Resumo sobre o crime de atentado \u00e0 soberania (art. 359-I do C\u00f3digo Penal), visando ao CNU (Concurso Nacional Unificado).","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/crime-atentado-soberania-cnu\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2025-08-31T14:45:00+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/08\/11071131\/crime-de-atentado-a-soberania-para-o-cnu.png","type":"image\/png"}],"author":"Frederico Tadeu Borlot Peixoto","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Frederico Tadeu Borlot Peixoto","Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/crime-atentado-soberania-cnu\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/crime-atentado-soberania-cnu\/"},"author":{"name":"Frederico Tadeu Borlot Peixoto","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/48a7e085e45aee7c3d4596399af50ebb"},"headline":"Crime de Atentado \u00e0 Soberania para o CNU","datePublished":"2025-08-31T14:45:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/crime-atentado-soberania-cnu\/"},"wordCount":1241,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/crime-atentado-soberania-cnu\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/08\/11071131\/crime-de-atentado-a-soberania-para-o-cnu.png","articleSection":["Ag\u00eancia Reguladora","Ag\u00eancia Reguladora","Concursos P\u00fablicos","Educa\u00e7\u00e3o","Executivo (Administrativa)","Previdenci\u00e1ria (INSS, PREVIC)","Sa\u00fade"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/crime-atentado-soberania-cnu\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"accessibilityFeature":["tableOfContents"]},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/crime-atentado-soberania-cnu\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/crime-atentado-soberania-cnu\/","name":"Crime de Atentado \u00e0 Soberania para o CNU","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/crime-atentado-soberania-cnu\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/crime-atentado-soberania-cnu\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/08\/11071131\/crime-de-atentado-a-soberania-para-o-cnu.png","datePublished":"2025-08-31T14:45:00+00:00","description":"Resumo sobre o crime de atentado \u00e0 soberania (art. 359-I do C\u00f3digo Penal), visando ao CNU (Concurso Nacional Unificado).","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/crime-atentado-soberania-cnu\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/crime-atentado-soberania-cnu\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/crime-atentado-soberania-cnu\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/08\/11071131\/crime-de-atentado-a-soberania-para-o-cnu.png","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/08\/11071131\/crime-de-atentado-a-soberania-para-o-cnu.png","width":1080,"height":1080,"caption":"Crime de Atentado \u00e0 Soberania para o CNU"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/crime-atentado-soberania-cnu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Crime de Atentado \u00e0 Soberania para o CNU"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/48a7e085e45aee7c3d4596399af50ebb","name":"Frederico Tadeu Borlot Peixoto","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/df8a49e2321c1e32f85e9e7c2a9c92c688f1f53a947220f40017ff5858b09fdb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/df8a49e2321c1e32f85e9e7c2a9c92c688f1f53a947220f40017ff5858b09fdb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/df8a49e2321c1e32f85e9e7c2a9c92c688f1f53a947220f40017ff5858b09fdb?s=96&d=mm&r=g","caption":"Frederico Tadeu Borlot Peixoto"},"description":"Analista Judici\u00e1rio - \u00c1rea Judici\u00e1ria do TRF da 4\u00aa regi\u00e3o. Bacharel em Direito. P\u00f3s-graduado em Direito Administrativo, Legisla\u00e7\u00e3o Penal Especial, Direito Penal e Direito Processual Penal. Tamb\u00e9m nomeado no TRF da 3\u00aa regi\u00e3o (8\u00ba lugar); SPPREV (3\u00ba lugar); IFES (2\u00ba lugar); e PMES. https:\/\/www.instagram.com\/proffrederico\/","sameAs":["https:\/\/www.instagram.com\/proffrederico\/"],"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/xfredericohotmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1621157","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/2567"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1621157"}],"version-history":[{"count":2,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1621157\/revisions"}],"predecessor-version":[{"id":1621164,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1621157\/revisions\/1621164"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/1621162"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1621157"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1621157"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1621157"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1621157"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}