{"id":1620996,"date":"2025-08-21T13:47:31","date_gmt":"2025-08-21T16:47:31","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=1620996"},"modified":"2025-08-21T13:47:33","modified_gmt":"2025-08-21T16:47:33","slug":"motim-e-revolta-entenda-as-suas-nuances","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/motim-e-revolta-entenda-as-suas-nuances\/","title":{"rendered":"Motim e revolta: entenda as suas nuances"},"content":{"rendered":"\n<p>Ol\u00e1, pessoal, tudo bem? Falaremos hoje sobre os <strong>crimes militares<\/strong> de motim e revolta.<\/p>\n\n\n\n<p>O <strong>motim e a revolta <\/strong>s\u00e3o crimes militares praticados contra a autoridade ou disciplina militar.&nbsp;<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p style=\"font-size:clamp(16.293px, 1.018rem + ((1vw - 3.2px) * 0.854), 25px);\"><strong>Motim<\/strong><\/p>\n\n\n\n<p>O motim \u00e9 um<strong> <\/strong>crime militar que ocorre quando <strong>dois ou mais<\/strong> militares se re\u00fanem para agir contra uma autoridade ou ordem militar.<\/p>\n\n\n\n<p>Assim, podemos concluir que o motim \u00e9 um <strong>crime militar de concurso necess\u00e1rio de pessoas<\/strong>, tendo em vista que a pr\u00e1tica delituosa n\u00e3o pode ser cometida por apenas uma pessoa.<\/p>\n\n\n\n<p>De acordo com o <a href=\"https:\/\/www.planalto.gov.br\/ccivil_03\/decreto-lei\/Del1001Compilado.htm\" target=\"_blank\" rel=\"noreferrer noopener\">C\u00f3digo Penal Militar (CPM)<\/a>, a pr\u00e1tica de motim compreende as seguintes condutas dos agentes reunidos:<\/p>\n\n\n\n<p style=\"font-size:0px\"><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>agir <strong>contra a ordem<\/strong> recebida de superior, ou negar-se a cumpri-la;<\/li>\n\n\n\n<li><strong>recusar obedi\u00eancia<\/strong> a superior, quando estejam agindo sem ordem ou praticando viol\u00eancia;<\/li>\n\n\n\n<li><strong>assentir em recusa conjunta de obedi\u00eancia, ou em resist\u00eancia ou viol\u00eancia<\/strong>, em comum, contra superior; e<\/li>\n\n\n\n<li><strong>utilizar-se de local ou meio de transporte militar <\/strong>para a\u00e7\u00e3o ou pr\u00e1tica de viol\u00eancia, em desobedi\u00eancia a ordem superior ou em detrimento da ordem ou da disciplina militar.<\/li>\n<\/ul>\n\n\n\n<p style=\"font-size:0px\"><\/p>\n\n\n\n<p>Anote-se ainda que a figura de superior hier\u00e1rquico compreende tamb\u00e9m a de um <strong>militar do mesmo posto ou gradua\u00e7\u00e3o <\/strong>dos amotinados, quando no exerc\u00edcio de uma fun\u00e7\u00e3o de comando.<\/p>\n\n\n\n<p>A pena prevista para os agentes que cometem motim \u00e9 de <strong>reclus\u00e3o<\/strong>, de <strong>quatro a oito anos<\/strong>, com aumento de <strong>um ter\u00e7o<\/strong> (\u2153) para os cabe\u00e7as.<\/p>\n\n\n\n<p>Lembre-se de que os cabe\u00e7as s\u00e3o aqueles que <strong>dirigem,<\/strong> <strong>provocam, instigam ou excitam a a\u00e7\u00e3o<\/strong>, nos termos do art. 53, \u00a7 4\u00ba&nbsp; do CPM.<\/p>\n\n\n\n<p>Al\u00e9m disso, o motim <strong>somente pode ser praticado por militares da ativa<\/strong>, n\u00e3o podendo ser cometido por civis ou militares da reserva ou reformados.&nbsp;<\/p>\n\n\n\n<p>No entanto, parte da doutrina admite a participa\u00e7\u00e3o do civil e do militar inativo quando atuarem como coautores ou part\u00edcipes e&nbsp; <strong>houver pelo menos dois militares da ativa <\/strong>envolvidos.&nbsp;<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p style=\"font-size:clamp(16.293px, 1.018rem + ((1vw - 3.2px) * 0.854), 25px);\"><strong>Revolta<\/strong><\/p>\n\n\n\n<p>O crime de revolta \u00e9 uma esp\u00e9cie de <strong>motim qualificado<\/strong>, haja vista se configurar pelo simples fato de os agentes em motim estarem armados.<\/p>\n\n\n\n<p>Em outras palavras, a mera <strong>presen\u00e7a de arma <\/strong>entre os agentes amotinados j\u00e1 <strong>caracteriza <\/strong>o crime de revolta.<\/p>\n\n\n\n<p>A pena prevista para o crime de revolta \u00e9 de <strong>reclus\u00e3o <\/strong>de <strong>oito a vinte<\/strong> anos. Assim, como ocorre no motim, a pena \u00e9 aumentada de \u2153 (um ter\u00e7o) para os cabe\u00e7as.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p style=\"font-size:clamp(16.293px, 1.018rem + ((1vw - 3.2px) * 0.854), 25px);\"><strong>Organiza\u00e7\u00e3o de grupo para a pr\u00e1tica de viol\u00eancia<\/strong><\/p>\n\n\n\n<p>Configura crime de organiza\u00e7\u00e3o de grupo para a pr\u00e1tica de viol\u00eancia quando <strong>dois ou mais<\/strong> militares se re\u00fanem, com <strong>armamento ou material b\u00e9lico<\/strong> de propriedade militar, <strong>para praticar viol\u00eancia<\/strong> \u00e0 pessoa ou \u00e0 coisa p\u00fablica ou particular em lugar sujeito ou n\u00e3o \u00e0 administra\u00e7\u00e3o militar.<\/p>\n\n\n\n<p>Repare que a presen\u00e7a de <strong>armamento ou material b\u00e9lico<\/strong> constitui uma elementar do tipo penal.<\/p>\n\n\n\n<p>A pena aplic\u00e1vel ao crime \u00e9 a de<strong> reclus\u00e3o de quatro a oito anos<\/strong>.<\/p>\n\n\n\n<p>N\u00e3o \u00e9 demais lembrar que o crime \u00e9 de<strong> concurso necess\u00e1rio de agentes,<\/strong> sendo necess\u00e1rio<strong> haver a pr\u00e1tica de viol\u00eancia<\/strong> para a sua consuma\u00e7\u00e3o.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p style=\"font-size:clamp(16.293px, 1.018rem + ((1vw - 3.2px) * 0.854), 25px);\"><strong>Omiss\u00e3o de lealdade militar<\/strong><\/p>\n\n\n\n<p>O crime de omiss\u00e3o de lealdade militar se configura quando h\u00e1 <strong>omiss\u00e3o<\/strong> do agente ao tomar conhecimento da a\u00e7\u00e3o planejada para a pr\u00e1tica de<strong> motim ou revolta<\/strong>.<\/p>\n\n\n\n<p>Nos termos do art. 151 do CPM, comete omiss\u00e3o de lealdade militar o agente que:<\/p>\n\n\n\n<p class=\"has-pale-cyan-blue-background-color has-background\"><em>\u201cDeixar [&#8230;] de levar ao conhecimento do superior o motim ou a revolta de cuja prepara\u00e7\u00e3o teve not\u00edcia ou, se presenciar o ato criminoso, n\u00e3o usar de todos os meios ao seu alcance para impedi-lo.\u201d<\/em><\/p>\n\n\n\n<p>Assim, verifica-se que a omiss\u00e3o de lealdade militar \u00e9 um <strong>crime propriamente militar<\/strong>, j\u00e1 que s\u00f3 pode ser praticado por militares.<\/p>\n\n\n\n<p>Por outro lado, ao contr\u00e1rio dos demais crimes estudados, a omiss\u00e3o de lealdade militar <strong>pode ser cometida por apenas uma pessoa<\/strong>.<\/p>\n\n\n\n<p>Repare que esse crime comporta uma a\u00e7\u00e3o omissiva e outra comissiva.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Omissiva<\/strong>: Deixar de levar ao conhecimento do superior os atos preparat\u00f3rios do motim e da revolta de que teve conhecimento;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Comissiva<\/strong>: Deixar de empregar todos os meios ao seu alcance para impedir a pr\u00e1tica do motim e da revolta.<\/li>\n<\/ul>\n\n\n\n<p><\/p>\n\n\n\n<p style=\"font-size:clamp(16.293px, 1.018rem + ((1vw - 3.2px) * 0.854), 25px);\"><strong>Conspira\u00e7\u00e3o<\/strong><\/p>\n\n\n\n<p>O crime de conspira\u00e7\u00e3o consiste na<strong> a\u00e7\u00e3o combinada entre os agentes<\/strong> para a pr\u00e1tica do crime de motim.<\/p>\n\n\n\n<p>Repare que a conspira\u00e7\u00e3o est\u00e1 presente nos <strong>atos preparat\u00f3rios <\/strong>do motim.&nbsp;<\/p>\n\n\n\n<p>O seu <strong>elemento objetivo<\/strong> (concertar, combinar, pactuar etc.) traz a ideia de que os agentes devem <strong>reunir-se para planejar<\/strong> a a\u00e7\u00e3o delituosa.<\/p>\n\n\n\n<p>Previsto no art. 152 do CPM, o crime de conspira\u00e7\u00e3o sujeita os envolvidos \u00e0 pena de<strong> reclus\u00e3o de tr\u00eas a cinco anos<\/strong>.<\/p>\n\n\n\n<p>Ser\u00e1 <strong>isento de pena<\/strong> o agente que denunciar<strong> o ajuste<\/strong> de que participou antes da execu\u00e7\u00e3o do crime e enquanto ainda for poss\u00edvel evitar as suas consequ\u00eancias.<\/p>\n\n\n\n<p>A exemplo do motim e da revolta, a conspira\u00e7\u00e3o tamb\u00e9m \u00e9 um <strong>crime de concurso necess\u00e1rio de agentes<\/strong>, tendo em vista que a sua ocorr\u00eancia depende do envolvimento de <strong>pelo menos duas <\/strong>pessoas.<\/p>\n\n\n\n<p>Al\u00e9m disso, a conspira\u00e7\u00e3o \u00e9 tamb\u00e9m um<strong> crime propriamente militar<\/strong>, pois ele \u00e9 praticado apenas por militares, n\u00e3o cabendo a participa\u00e7\u00e3o de civis.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Ficamos por aqui\u2026<\/p>\n\n\n\n<p>Para se aprofundar sobre o motim e a revolta, estude com nossos <strong><a href=\"https:\/\/www.estrategiaconcursos.com.br\/cursos\/concurso\/\" target=\"_blank\" rel=\"noreferrer noopener\">materiais em pdf e em v\u00eddeo aulas<\/a><\/strong>, e aumente as suas chances de aprova\u00e7\u00e3o.<\/p>\n\n\n\n<p>Bons estudos e at\u00e9 a pr\u00f3xima!<\/p>\n\n\n\n<p>Nilson Assis<\/p>\n\n\n\n<p>Analista Legislativo do Senado Federal<\/p>\n\n\n\n<p>@nsassis.concursos<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2025\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos 2025<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-federais-2023\/\">Concursos federais<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/cj.estrategia.com\/portal\/concursos-abertos-carreiras-juridicas\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos abertos Carreiras Jur\u00eddicas<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\">Concursos abertos<\/a><\/li>\n<\/ul>\n\n\n\n<p><\/p>\n\n\n\n<p style=\"font-size:clamp(16.293px, 1.018rem + ((1vw - 3.2px) * 0.854), 25px);\"><strong>Refer\u00eancias Bibliogr\u00e1ficas<\/strong><\/p>\n\n\n\n<p>BRASIL. Decreto-Lei n\u00ba 1.001 de 21 de outubro de 1969,\u00a0<strong>institui o C\u00f3digo Penal Militar<\/strong>. Bras\u00edlia, DF: Di\u00e1rio Oficial da Uni\u00e3o de 21.10.1969.<\/p>\n\n\n\n<p>NEVES, C\u00edcero Robson Coimbra; STREIFINGER, Marcello.\u00a0<strong>Manual de Direito Penal Militar<\/strong>. 7. ed. S\u00e3o Paulo: Editora JusPodivm.<\/p>\n\n\n\n<p>PEQUENO, Ant\u00f4nio. <strong>STM (Analista Judici\u00e1rio &#8211; \u00c1rea Judici\u00e1ria) Direito Penal Militar &#8211; 2025 (P\u00f3s-Edital)<\/strong>. Estrat\u00e9gia Concursos, Aula 08.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ol\u00e1, pessoal, tudo bem? Falaremos hoje sobre os crimes militares de motim e revolta. O motim e a revolta s\u00e3o crimes militares praticados contra a autoridade ou disciplina militar.&nbsp; Motim O motim \u00e9 um crime militar que ocorre quando dois ou mais militares se re\u00fanem para agir contra uma autoridade ou ordem militar. Assim, podemos [&hellip;]<\/p>\n","protected":false},"author":2894,"featured_media":1478428,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1],"tags":[],"tax_estado":[],"class_list":["post-1620996","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cursos-e-concursos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Motim e revolta: entenda as suas nuances<\/title>\n<meta name=\"description\" content=\"Ol\u00e1, pessoal, tudo bem? O motim e a revolta s\u00e3o crimes militares praticados contra a autoridade ou disciplina militar.\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/motim-e-revolta-entenda-as-suas-nuances\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Motim e revolta: entenda as suas nuances\" \/>\n<meta property=\"og:description\" content=\"Ol\u00e1, pessoal, tudo bem? O motim e a revolta s\u00e3o crimes militares praticados contra a autoridade ou disciplina militar.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/motim-e-revolta-entenda-as-suas-nuances\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-21T16:47:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-21T16:47:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/10\/18134623\/policia-militar-do-tocantins-pm-to.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1190\" \/>\n\t<meta property=\"og:image:height\" content=\"578\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nilson Silva de Assis\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nilson Silva de Assis\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/motim-e-revolta-entenda-as-suas-nuances\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/motim-e-revolta-entenda-as-suas-nuances\/\"},\"author\":{\"name\":\"Nilson Silva de Assis\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/2602628e49ec93d5f782b149f91603ab\"},\"headline\":\"Motim e revolta: entenda as suas nuances\",\"datePublished\":\"2025-08-21T16:47:31+00:00\",\"dateModified\":\"2025-08-21T16:47:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/motim-e-revolta-entenda-as-suas-nuances\/\"},\"wordCount\":1018,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/motim-e-revolta-entenda-as-suas-nuances\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/10\/18134623\/policia-militar-do-tocantins-pm-to.png\",\"articleSection\":[\"Concursos P\u00fablicos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/motim-e-revolta-entenda-as-suas-nuances\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/motim-e-revolta-entenda-as-suas-nuances\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/motim-e-revolta-entenda-as-suas-nuances\/\",\"name\":\"Motim e revolta: entenda as suas nuances\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/motim-e-revolta-entenda-as-suas-nuances\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/motim-e-revolta-entenda-as-suas-nuances\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/10\/18134623\/policia-militar-do-tocantins-pm-to.png\",\"datePublished\":\"2025-08-21T16:47:31+00:00\",\"dateModified\":\"2025-08-21T16:47:33+00:00\",\"description\":\"Ol\u00e1, pessoal, tudo bem? O motim e a revolta s\u00e3o crimes militares praticados contra a autoridade ou disciplina militar.\u00a0\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/motim-e-revolta-entenda-as-suas-nuances\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/motim-e-revolta-entenda-as-suas-nuances\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/motim-e-revolta-entenda-as-suas-nuances\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/10\/18134623\/policia-militar-do-tocantins-pm-to.png\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/10\/18134623\/policia-militar-do-tocantins-pm-to.png\",\"width\":1190,\"height\":578,\"caption\":\"motim e revolta\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/motim-e-revolta-entenda-as-suas-nuances\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Motim e revolta: entenda as suas nuances\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/2602628e49ec93d5f782b149f91603ab\",\"name\":\"Nilson Silva de Assis\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/cdec26ae7042f64d4ddcb70bcf78a4fcbc02661bfa30a7ce3d8bf515b625a75a?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cdec26ae7042f64d4ddcb70bcf78a4fcbc02661bfa30a7ce3d8bf515b625a75a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cdec26ae7042f64d4ddcb70bcf78a4fcbc02661bfa30a7ce3d8bf515b625a75a?s=96&d=mm&r=g\",\"caption\":\"Nilson Silva de Assis\"},\"description\":\"Atualmente \u00e9 Analista Legislativo do Senado Federal e Professor do Estrat\u00e9gia Concursos. Suas principais aprova\u00e7\u00f5es: Analista Legislativo do Senado Federal; Auditor Federal de Finan\u00e7as e Controle da CGU; Auditor-Fiscal da Receita Estadual da SEFAZ ES; T\u00e9cnico Fazend\u00e1rio do ISS Manaus; Assistente Executivo em Metrologia e Qualidade do Inmetro; Agente Fazend\u00e1rio do ISS Niter\u00f3i\/RJ; Assistente Administrativo da Prefeitura do Rio (RioSa\u00fade); Assistente Administrativo da Secretaria de Administra\u00e7\u00e3o do Munic\u00edpio do RJ.\",\"sameAs\":[\"https:\/\/www.instagram.com\/nilsonassis.concursos\/\",\"kedin.com\/in\/nilson-assis-954132295\/\"],\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/nilson-sdeassisgmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Motim e revolta: entenda as suas nuances","description":"Ol\u00e1, pessoal, tudo bem? O motim e a revolta s\u00e3o crimes militares praticados contra a autoridade ou disciplina militar.\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/motim-e-revolta-entenda-as-suas-nuances\/","og_locale":"pt_BR","og_type":"article","og_title":"Motim e revolta: entenda as suas nuances","og_description":"Ol\u00e1, pessoal, tudo bem? O motim e a revolta s\u00e3o crimes militares praticados contra a autoridade ou disciplina militar.\u00a0","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/motim-e-revolta-entenda-as-suas-nuances\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2025-08-21T16:47:31+00:00","article_modified_time":"2025-08-21T16:47:33+00:00","og_image":[{"width":1190,"height":578,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/10\/18134623\/policia-militar-do-tocantins-pm-to.png","type":"image\/png"}],"author":"Nilson Silva de Assis","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Nilson Silva de Assis","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/motim-e-revolta-entenda-as-suas-nuances\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/motim-e-revolta-entenda-as-suas-nuances\/"},"author":{"name":"Nilson Silva de Assis","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/2602628e49ec93d5f782b149f91603ab"},"headline":"Motim e revolta: entenda as suas nuances","datePublished":"2025-08-21T16:47:31+00:00","dateModified":"2025-08-21T16:47:33+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/motim-e-revolta-entenda-as-suas-nuances\/"},"wordCount":1018,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/motim-e-revolta-entenda-as-suas-nuances\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/10\/18134623\/policia-militar-do-tocantins-pm-to.png","articleSection":["Concursos P\u00fablicos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/motim-e-revolta-entenda-as-suas-nuances\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/motim-e-revolta-entenda-as-suas-nuances\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/motim-e-revolta-entenda-as-suas-nuances\/","name":"Motim e revolta: entenda as suas nuances","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/motim-e-revolta-entenda-as-suas-nuances\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/motim-e-revolta-entenda-as-suas-nuances\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/10\/18134623\/policia-militar-do-tocantins-pm-to.png","datePublished":"2025-08-21T16:47:31+00:00","dateModified":"2025-08-21T16:47:33+00:00","description":"Ol\u00e1, pessoal, tudo bem? O motim e a revolta s\u00e3o crimes militares praticados contra a autoridade ou disciplina militar.\u00a0","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/motim-e-revolta-entenda-as-suas-nuances\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/motim-e-revolta-entenda-as-suas-nuances\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/motim-e-revolta-entenda-as-suas-nuances\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/10\/18134623\/policia-militar-do-tocantins-pm-to.png","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/10\/18134623\/policia-militar-do-tocantins-pm-to.png","width":1190,"height":578,"caption":"motim e revolta"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/motim-e-revolta-entenda-as-suas-nuances\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Motim e revolta: entenda as suas nuances"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/2602628e49ec93d5f782b149f91603ab","name":"Nilson Silva de Assis","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/cdec26ae7042f64d4ddcb70bcf78a4fcbc02661bfa30a7ce3d8bf515b625a75a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cdec26ae7042f64d4ddcb70bcf78a4fcbc02661bfa30a7ce3d8bf515b625a75a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cdec26ae7042f64d4ddcb70bcf78a4fcbc02661bfa30a7ce3d8bf515b625a75a?s=96&d=mm&r=g","caption":"Nilson Silva de Assis"},"description":"Atualmente \u00e9 Analista Legislativo do Senado Federal e Professor do Estrat\u00e9gia Concursos. Suas principais aprova\u00e7\u00f5es: Analista Legislativo do Senado Federal; Auditor Federal de Finan\u00e7as e Controle da CGU; Auditor-Fiscal da Receita Estadual da SEFAZ ES; T\u00e9cnico Fazend\u00e1rio do ISS Manaus; Assistente Executivo em Metrologia e Qualidade do Inmetro; Agente Fazend\u00e1rio do ISS Niter\u00f3i\/RJ; Assistente Administrativo da Prefeitura do Rio (RioSa\u00fade); Assistente Administrativo da Secretaria de Administra\u00e7\u00e3o do Munic\u00edpio do RJ.","sameAs":["https:\/\/www.instagram.com\/nilsonassis.concursos\/","kedin.com\/in\/nilson-assis-954132295\/"],"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/nilson-sdeassisgmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1620996","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/2894"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1620996"}],"version-history":[{"count":2,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1620996\/revisions"}],"predecessor-version":[{"id":1621007,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1620996\/revisions\/1621007"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/1478428"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1620996"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1620996"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1620996"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1620996"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}