{"id":1619579,"date":"2025-08-11T09:00:00","date_gmt":"2025-08-11T12:00:00","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=1619579"},"modified":"2025-08-19T07:59:36","modified_gmt":"2025-08-19T10:59:36","slug":"carta-aos-assinantes-250","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/carta-aos-assinantes-250\/","title":{"rendered":"Carta aos Assinantes do Estrat\u00e9gia Concursos &#8211; 250"},"content":{"rendered":"\n<p class=\"has-text-align-right has-luminous-vivid-amber-background-color has-background\"><em>Confira, em nossa <strong>ducent\u00e9sima quinquag\u00e9sima <\/strong>carta aos assinantes, a nossa programa\u00e7\u00e3o semanal, as novidades do nosso Sistema de Quest\u00f5es e as principais movimenta\u00e7\u00f5es de concursos.<\/em><\/p>\n\n\n\n<p>Ol\u00e1, pessoal. Tudo bem?<\/p>\n\n\n\n<p>Aqui \u00e9 o<strong>&nbsp;Prof. Diego Cerqueira&nbsp;<\/strong>em nossa <strong>ducent\u00e9sima quinquag\u00e9sima <\/strong>carta aos Assinantes do Estrat\u00e9gia Concursos.<\/p>\n\n\n\n<p>A Controladoria-Geral do Estado de S\u00e3o Paulo deve publicar seu novo edital de concurso p\u00fablico ainda em agosto. Sob organiza\u00e7\u00e3o da FGV, ser\u00e3o ofertadas 200 vagas para o cargo de&nbsp;<strong>Auditor Estadual de Controle I<\/strong>, em diferentes \u00e1reas.<\/p>\n\n\n\n<p>Por isso, preparamos a <strong>Contagem Regressiva CGE SP<\/strong>: domine a estrat\u00e9gia de 85% aprovados antes que seja tarde demais para conquistar at\u00e9 <strong>R$&nbsp;20 mil<\/strong>! <a href=\"https:\/\/mkt.estrategia.com\/concursos\/contagem-regressiva-cge-sp\/?utm_source=banner&amp;utm_medium=banner&amp;utm_campaign=ec-ctrgta-ld-banner-contagemcgesp-semesp-110825+\" target=\"_blank\" rel=\"noreferrer noopener\">Inscreva-se aqui e participe<\/a>!<\/p>\n\n\n\n<p>E para quem almeja ingressar na \u00e1rea policial, teremos a <strong>Tropa de Elite PRF<\/strong>! Comece na frente com o m\u00e9todo que j\u00e1&nbsp;aprovou 952 candidatos&nbsp;e conquiste um sal\u00e1rio de&nbsp;R$ 12 mil por m\u00eas.<\/p>\n\n\n\n<p>Ser\u00e3o tr\u00eas noites de imers\u00e3o estrat\u00e9gica! Saiba tudo sobre o pr\u00f3ximo concurso da&nbsp;<strong>Pol\u00edcia Rodovi\u00e1ria Federal<\/strong>, descubra os detalhes da carreira, monte seu plano de estudos e participe de um aul\u00e3o sobre o&nbsp;C\u00f3digo de Tr\u00e2nsito Brasileiro (CTB). <a href=\"https:\/\/mkt.estrategia.com\/concursos\/tropa-de-elite-prf\/?utm_source=banner&amp;utm_medium=banner&amp;utm_campaign=+ec-pol-ld-banner-tropaprf-semesp-110825+\" target=\"_blank\" rel=\"noreferrer noopener\">N\u00e3o fique de fora e inscreva-se<\/a>!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-sistema-de-questoes-do-estrategia\">Sistema de Quest\u00f5es do Estrat\u00e9gia<\/h2>\n\n\n\n<p>Na \u00faltima semana, a nossa equipe do Sistema de Quest\u00f5es&nbsp;<strong>criou&nbsp;<\/strong>os seguintes&nbsp;<strong>Cadernos de Quest\u00f5es<\/strong>:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Reta Final ISS Mag\u00e9 RJ (<a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/cadernos-de-reta-final-iss-mage\/\" target=\"_blank\" rel=\"noreferrer noopener\">clique aqui<\/a>)<\/li>\n\n\n\n<li>Reta Final ISS Castelo ES (<a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/cadernos-de-reta-final-iss-castelo\/\" target=\"_blank\" rel=\"noreferrer noopener\">clique aqui<\/a>)<\/li>\n\n\n\n<li>Reta Final ISS Varginha MG (<a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/cadernos-de-reta-final-iss-varginha\/\" target=\"_blank\" rel=\"noreferrer noopener\">clique aqui<\/a>)<\/li>\n<\/ul>\n\n\n\n<p>Al\u00e9m disso, tamb\u00e9m foram <strong>atualizados&nbsp;<\/strong>os seguintes&nbsp;<strong>Cadernos de Quest\u00f5es<\/strong>:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Reta Final TCE MS (<a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=1606463\" target=\"_blank\" rel=\"noreferrer noopener\">clique aqui<\/a>)<\/li>\n\n\n\n<li>Quest\u00f5es In\u00e9ditas Sefaz SE (<a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/questoes-ineditas-sefaz-se\/\" target=\"_blank\" rel=\"noreferrer noopener\">clique aqui<\/a>)<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-agora-vamos-ver-as-principais-movimentacoes-de-concursos-da-ultima-semana\">Agora, vamos ver as principais movimenta\u00e7\u00f5es de concursos da \u00faltima semana?<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-unificado-pe\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concurso Unificado PE<\/a>:<\/strong> O governo do estado anunciou nesta quarta-feira (6) a cria\u00e7\u00e3o do Concurso P\u00fablico Unificado de Pernambuco (CPU-PE), uma vers\u00e3o estadual do Concurso P\u00fablico Nacional Unificado (CNU), do governo federal. Os candidatos poder\u00e3o concorrer a tr\u00eas cargos do edital. Ser\u00e3o 455 vagas, com provas sendo aplicadas em dez cidades do estado. As oportunidades contemplam 40 cargos ou especialidades, e os aprovados v\u00e3o trabalhar em ag\u00eancias, funda\u00e7\u00f5es e secretarias do estado, al\u00e9m do Instituto de Pesos e Medidas. De acordo com a secret\u00e1ria estadual de Administra\u00e7\u00e3o, Ana Mara\u00edza, a iniciativa visa ampliar o acesso ao servi\u00e7o p\u00fablico e tornar mais transparente e eficiente os processos seletivos de Pernambuco.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-sefaz-sp\/\" target=\"_blank\" rel=\"noreferrer noopener\">Sefaz SP<\/a><\/strong>: O governador de S\u00e3o Paulo, Tarc\u00edsio de Freitas, autorizou oficialmente a realiza\u00e7\u00e3o de um novo concurso da Sefaz SP, especificamente para o cargo de Auditor Fiscal da Receita Estadual. A informa\u00e7\u00e3o foi publicada no Di\u00e1rio Oficial do Estado. A autoriza\u00e7\u00e3o permite \u00e0 Secretaria da Fazenda e Planejamento (Sefaz SP) iniciar as provid\u00eancias necess\u00e1rias para a abertura do certame, que ofertar\u00e1 200 vagas para o cargo, com jornada de 40 horas semanais. O decreto foi emitido ap\u00f3s manifesta\u00e7\u00f5es t\u00e9cnicas da pr\u00f3pria secretaria, da Subsecretaria de Or\u00e7amento e da Diretoria de Remunera\u00e7\u00e3o e Benef\u00edcios da Secretaria de Gest\u00e3o e Governo Digital (SGGD), que refor\u00e7aram a viabilidade or\u00e7ament\u00e1ria e a necessidade de reposi\u00e7\u00e3o de servidores. Dessa forma, espera-se que o pr\u00f3ximo passo seja a forma\u00e7\u00e3o da comiss\u00e3o organizadora e, na sequ\u00eancia, a defini\u00e7\u00e3o da banca respons\u00e1vel pela execu\u00e7\u00e3o do concurso.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-mp-ap\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>MP AP<\/strong><\/a>: O concurso para servidores do Minist\u00e9rio P\u00fablico do Estado do Amap\u00e1 (MP AP) ser\u00e1 organizado pela Funda\u00e7\u00e3o Carlos Chagas (FCC) e teve contrato assinado. Est\u00e3o previstas 17 vagas imediatas, al\u00e9m de cadastro de reserva, para os cargos de t\u00e9cnico e analista ministerial. A publica\u00e7\u00e3o do edital deve ocorrer ainda em 2025, com aplica\u00e7\u00e3o das provas em 2026.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ufg\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>UFG<\/strong><\/a>: O novo concurso UFG (Universidade Federal de Goi\u00e1s) para T\u00e9cnico Administrativo em Educa\u00e7\u00e3o oferta 33 vagas. As oportunidades s\u00e3o de n\u00edveis m\u00e9dio\/t\u00e9cnico e superior. As remunera\u00e7\u00f5es s\u00e3o de at\u00e9 R$ 4.967,04, al\u00e9m de benef\u00edcios! A inscri\u00e7\u00e3o ser\u00e1 realizada entre os dias 18 de agosto e 04 de setembro, exclusivamente no endere\u00e7o eletr\u00f4nico da banca, o Instituto Verbena, ao custo de R$ 130,00 a R$ 150,00.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ufla\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>UFLA<\/strong><\/a>: O edital do concurso da Universidade Federal de Lavras (UFLA) oferta 34 vagas para diferentes cargos de n\u00edveis m\u00e9dio, t\u00e9cnico e superior para t\u00e9cnico administrativo. A remunera\u00e7\u00e3o varia entre R$ 3.029,90 e R$ 4.967,04, al\u00e9m de benef\u00edcios. As inscri\u00e7\u00f5es ser\u00e3o feitas de 11 de agosto a 12 de setembro, ao custo de R$ 120,00 a R$ 200,00. A prova objetiva ser\u00e1 realizada em 30 de novembro, no munic\u00edpio de Lavras\/MG.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-sesapi\/\" target=\"_blank\" rel=\"noreferrer noopener\">SESAPI<\/a><\/strong>: Est\u00e1 oficialmente autorizada a realiza\u00e7\u00e3o do pr\u00f3ximo concurso SESAPI (Secretaria de Estado de Sa\u00fade do Piau\u00ed). Al\u00e9m disso, a comiss\u00e3o tamb\u00e9m foi institu\u00edda. Ser\u00e3o ofertadas 500 vagas imediatas e 500 em cadastro de reserva em diferentes \u00e1reas, sendo: Enfermagem, Psicologia, Farm\u00e1cia, Biomedicina, Nutri\u00e7\u00e3o, Fisioterapia, Fonoaudiologia e Medicina.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-pc-sc\/\" target=\"_blank\" rel=\"noreferrer noopener\">PC SC<\/a><\/strong>: A realiza\u00e7\u00e3o do novo concurso PC SC (Pol\u00edcia Civil de Santa Catarina) est\u00e1 autorizada! A expectativa \u00e9 de que o edital seja publicado ainda em 2025. A informa\u00e7\u00e3o foi confirmada pelo governador Jorginho Mello durante a formatura de novos psic\u00f3logos e policiais civis. Na ocasi\u00e3o, o chefe do Executivo manifestou o desejo de formar um cadastro de reserva com 200 vagas para 2026. Ser\u00e3o ofertadas 300 vagas para o cargo de Oficial Investigador de Pol\u00edcia (atual nomenclatura de Agente e Escriv\u00e3o). O sal\u00e1rio inicial \u00e9 de R$ 6.000,00.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-policia-civil-pi\/\" target=\"_blank\" rel=\"noreferrer noopener\">PC PI<\/a><\/strong>: Foi divulgado o termo de refer\u00eancia do novo concurso PC PI (Pol\u00edcia Civil do Estado do Piau\u00ed). O documento confirma a distribui\u00e7\u00e3o das vagas e demais detalhes do edital. Sob organiza\u00e7\u00e3o da FGV, ser\u00e3o ofertadas 200 vagas imediatas e 200 em cadastro de reserva para os cargos de Oficial Investigador de Pol\u00edcia, Perito (diversas \u00e1reas) e Delegado. Os sal\u00e1rios variam de R$ 7.210,48 a R$ 20.601,38.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ses-sc\/\" target=\"_blank\" rel=\"noreferrer noopener\">SES SC<\/a><\/strong>: A realiza\u00e7\u00e3o do novo concurso SES SC (Secretaria de Estado da Sa\u00fade de Santa Catarina) contar\u00e1 com organiza\u00e7\u00e3o do Instituto AOCP. Ser\u00e3o ofertadas 511 vagas, sendo 268 destinadas a candidatos com forma\u00e7\u00e3o de n\u00edvel m\u00e9dio e 243 para quem possui ensino superior. Al\u00e9m disso, a publica\u00e7\u00e3o do edital est\u00e1 prevista para agosto, com aplica\u00e7\u00e3o de provas em novembro.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-policia-civil-rs\/\" target=\"_blank\" rel=\"noreferrer noopener\">PC RS<\/a><\/strong>: A publica\u00e7\u00e3o do edital do pr\u00f3ximo concurso PC RS (Pol\u00edcia Civil do Rio Grande do Sul) \u00e9 prevista para o m\u00eas de setembro. A informa\u00e7\u00e3o foi revelada no \u2018Jornal Hoje\u2019, da Rede Globo. Ser\u00e3o ofertadas 720 vagas imediatas, sendo 360 para Escriv\u00e3o e outras 360 para Inspetor, com sal\u00e1rio inicial de R$ 6.748,84. A organiza\u00e7\u00e3o \u00e9 da Fundatec.<\/li>\n<\/ul>\n\n\n\n<p>Espero que tenham gostado da Carta aos Assinantes. Desejo a todos uma excelente semana de estudos!<\/p>\n\n\n\n<p>Abra\u00e7os,<\/p>\n\n\n\n<p><strong>Prof. Diego Cerqueira<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Confira, em nossa ducent\u00e9sima quinquag\u00e9sima carta aos assinantes, a nossa programa\u00e7\u00e3o semanal, as novidades do nosso Sistema de Quest\u00f5es e as principais movimenta\u00e7\u00f5es de concursos. Ol\u00e1, pessoal. Tudo bem? Aqui \u00e9 o&nbsp;Prof. Diego Cerqueira&nbsp;em nossa ducent\u00e9sima quinquag\u00e9sima carta aos Assinantes do Estrat\u00e9gia Concursos. A Controladoria-Geral do Estado de S\u00e3o Paulo deve publicar seu novo edital [&hellip;]<\/p>\n","protected":false},"author":1789,"featured_media":1058143,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1,220219],"tags":[],"tax_estado":[219963],"class_list":["post-1619579","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cursos-e-concursos","category-noticias","tax_estado-concursos-federais"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Carta aos Assinantes do Estrat\u00e9gia Concursos - 250<\/title>\n<meta name=\"description\" content=\"Confira em nossa 250\u00aa carta aos assinantes as novidades do nosso SQ e principais movimenta\u00e7\u00f5es de concursos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/carta-aos-assinantes-250\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Carta aos Assinantes do Estrat\u00e9gia Concursos - 250\" \/>\n<meta property=\"og:description\" content=\"Confira em nossa 250\u00aa carta aos assinantes as novidades do nosso SQ e principais movimenta\u00e7\u00f5es de concursos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/carta-aos-assinantes-250\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-11T12:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-19T10:59:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/07\/08165823\/imagem-carta-aos-assinantes-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Coordena\u00e7\u00e3o Estrat\u00e9gia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Coordena\u00e7\u00e3o Estrat\u00e9gia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/carta-aos-assinantes-250\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/carta-aos-assinantes-250\/\"},\"author\":{\"name\":\"Coordena\u00e7\u00e3o Estrat\u00e9gia\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/ba5fab3b1fa4a358429e37bc50f74021\"},\"headline\":\"Carta aos Assinantes do Estrat\u00e9gia Concursos &#8211; 250\",\"datePublished\":\"2025-08-11T12:00:00+00:00\",\"dateModified\":\"2025-08-19T10:59:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/carta-aos-assinantes-250\/\"},\"wordCount\":1187,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/carta-aos-assinantes-250\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/07\/08165823\/imagem-carta-aos-assinantes-1.png\",\"articleSection\":[\"Concursos P\u00fablicos\",\"\u00daltimas not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/carta-aos-assinantes-250\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/carta-aos-assinantes-250\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/carta-aos-assinantes-250\/\",\"name\":\"Carta aos Assinantes do Estrat\u00e9gia Concursos - 250\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/carta-aos-assinantes-250\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/carta-aos-assinantes-250\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/07\/08165823\/imagem-carta-aos-assinantes-1.png\",\"datePublished\":\"2025-08-11T12:00:00+00:00\",\"dateModified\":\"2025-08-19T10:59:36+00:00\",\"description\":\"Confira em nossa 250\u00aa carta aos assinantes as novidades do nosso SQ e principais movimenta\u00e7\u00f5es de concursos.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/carta-aos-assinantes-250\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/carta-aos-assinantes-250\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/carta-aos-assinantes-250\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/07\/08165823\/imagem-carta-aos-assinantes-1.png\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/07\/08165823\/imagem-carta-aos-assinantes-1.png\",\"width\":800,\"height\":450,\"caption\":\"Carta aos Assinantes\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/carta-aos-assinantes-250\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Carta aos Assinantes do Estrat\u00e9gia Concursos &#8211; 250\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/ba5fab3b1fa4a358429e37bc50f74021\",\"name\":\"Coordena\u00e7\u00e3o Estrat\u00e9gia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/adff33ff18541ba37c900dd2b1e82dbfb0fe33d873b92636b4827a8da462feb3?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/adff33ff18541ba37c900dd2b1e82dbfb0fe33d873b92636b4827a8da462feb3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/adff33ff18541ba37c900dd2b1e82dbfb0fe33d873b92636b4827a8da462feb3?s=96&d=mm&r=g\",\"caption\":\"Coordena\u00e7\u00e3o Estrat\u00e9gia\"},\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/victor-tanakaaestrategiaconcursos-com-br\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Carta aos Assinantes do Estrat\u00e9gia Concursos - 250","description":"Confira em nossa 250\u00aa carta aos assinantes as novidades do nosso SQ e principais movimenta\u00e7\u00f5es de concursos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/carta-aos-assinantes-250\/","og_locale":"pt_BR","og_type":"article","og_title":"Carta aos Assinantes do Estrat\u00e9gia Concursos - 250","og_description":"Confira em nossa 250\u00aa carta aos assinantes as novidades do nosso SQ e principais movimenta\u00e7\u00f5es de concursos.","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/carta-aos-assinantes-250\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2025-08-11T12:00:00+00:00","article_modified_time":"2025-08-19T10:59:36+00:00","og_image":[{"width":800,"height":450,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/07\/08165823\/imagem-carta-aos-assinantes-1.png","type":"image\/png"}],"author":"Coordena\u00e7\u00e3o Estrat\u00e9gia","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Coordena\u00e7\u00e3o Estrat\u00e9gia","Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/carta-aos-assinantes-250\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/carta-aos-assinantes-250\/"},"author":{"name":"Coordena\u00e7\u00e3o Estrat\u00e9gia","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/ba5fab3b1fa4a358429e37bc50f74021"},"headline":"Carta aos Assinantes do Estrat\u00e9gia Concursos &#8211; 250","datePublished":"2025-08-11T12:00:00+00:00","dateModified":"2025-08-19T10:59:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/carta-aos-assinantes-250\/"},"wordCount":1187,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/carta-aos-assinantes-250\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/07\/08165823\/imagem-carta-aos-assinantes-1.png","articleSection":["Concursos P\u00fablicos","\u00daltimas not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/carta-aos-assinantes-250\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/carta-aos-assinantes-250\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/carta-aos-assinantes-250\/","name":"Carta aos Assinantes do Estrat\u00e9gia Concursos - 250","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/carta-aos-assinantes-250\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/carta-aos-assinantes-250\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/07\/08165823\/imagem-carta-aos-assinantes-1.png","datePublished":"2025-08-11T12:00:00+00:00","dateModified":"2025-08-19T10:59:36+00:00","description":"Confira em nossa 250\u00aa carta aos assinantes as novidades do nosso SQ e principais movimenta\u00e7\u00f5es de concursos.","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/carta-aos-assinantes-250\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/carta-aos-assinantes-250\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/carta-aos-assinantes-250\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/07\/08165823\/imagem-carta-aos-assinantes-1.png","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/07\/08165823\/imagem-carta-aos-assinantes-1.png","width":800,"height":450,"caption":"Carta aos Assinantes"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/carta-aos-assinantes-250\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Carta aos Assinantes do Estrat\u00e9gia Concursos &#8211; 250"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/ba5fab3b1fa4a358429e37bc50f74021","name":"Coordena\u00e7\u00e3o Estrat\u00e9gia","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/adff33ff18541ba37c900dd2b1e82dbfb0fe33d873b92636b4827a8da462feb3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/adff33ff18541ba37c900dd2b1e82dbfb0fe33d873b92636b4827a8da462feb3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/adff33ff18541ba37c900dd2b1e82dbfb0fe33d873b92636b4827a8da462feb3?s=96&d=mm&r=g","caption":"Coordena\u00e7\u00e3o Estrat\u00e9gia"},"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/victor-tanakaaestrategiaconcursos-com-br\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1619579","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/1789"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1619579"}],"version-history":[{"count":4,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1619579\/revisions"}],"predecessor-version":[{"id":1620506,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1619579\/revisions\/1620506"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/1058143"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1619579"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1619579"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1619579"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1619579"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}