{"id":1619364,"date":"2025-08-06T16:53:36","date_gmt":"2025-08-06T19:53:36","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=1619364"},"modified":"2025-08-06T16:53:38","modified_gmt":"2025-08-06T19:53:38","slug":"concurso-camara-de-manaus-atividades-suspensas","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-camara-de-manaus-atividades-suspensas\/","title":{"rendered":"Concurso C\u00e2mara de Manaus: comiss\u00e3o e atividades suspensas"},"content":{"rendered":"\n<p style=\"font-size:clamp(14.642px, 0.915rem + ((1vw - 3.2px) * 0.721), 22px);\"><em><strong>Concurso C\u00e2mara de Manaus tem atividades suspensas pelo TJ AM!<\/strong><\/em><\/p>\n\n\n\n<p>O Tribunal de Justi\u00e7a do Amazonas (TJAM) <strong>suspendeu a cria\u00e7\u00e3o da comiss\u00e3o e demais avan\u00e7os do concurso p\u00fablico da C\u00e2mara Municipal de Manaus<\/strong>.<\/p>\n\n\n\n<p>Segundo decis\u00e3o publicada na \u00faltima ter\u00e7a-feira, 5 de agosto, a medida \u00e9 provis\u00f3ria e <strong>pro\u00edbe qualquer movimenta\u00e7\u00e3o <\/strong>no novo certame at\u00e9 que a Justi\u00e7a <strong>avalie a legalidade do edital anterior<\/strong>, anulado por decis\u00e3o da presid\u00eancia da Casa.<\/p>\n\n\n\n<p>A a\u00e7\u00e3o foi movida por candidatos aprovados no concurso cancelado, que alegam que a anula\u00e7\u00e3o ocorreu sem uma justificativa jur\u00eddica consistente, baseada unicamente em uma recomenda\u00e7\u00e3o do Minist\u00e9rio P\u00fablico.<\/p>\n\n\n\n<p>Vale ressaltar que o pedido de suspens\u00e3o foi negado em primeira inst\u00e2ncia, mas os autores recorreram ao TJAM dentro do prazo legal e conseguiram reverter a decis\u00e3o, obtendo um parecer favor\u00e1vel.<\/p>\n\n\n\n<div class=\"container\" id=\"boxes\">\n  <div class=\"row\">\n\n    <div class=\"col-sm\">\n      <div class=\"banner-camaras\" id=\"box-assinatura\">\n        <h3 class=\"titulo-assinatura\">Cursos C\u00e2mara de Manaus<\/h3>\n        <p class=\"subtitulo-assinatura\">Prepara\u00e7\u00e3o completa para a carreira na C\u00e2mara<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/cursosPorConcurso\/area-legislativa-pacotes-promocionais\/\" role=\"button\" rel=\"noopener noreferrer\">VER CURSOS<\/a>\n        <\/div>\n      <\/div>\n     \n    <\/div>\n\n  <\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-ultimo-edital-da-camara-de-manaus-foi-anulado\">\u00daltimo edital da C\u00e2mara de Manaus foi anulado<\/h2>\n\n\n\n<p>Em mar\u00e7o, a&nbsp;C\u00e2mara Municipal de Manaus <strong>acatou&nbsp;a recomenda\u00e7\u00e3o<\/strong> do Minist\u00e9rio P\u00fablico do Amazonas e optou por&nbsp;<strong>anular os tr\u00eas editais do concurso p\u00fablico<\/strong>, publicados em setembro de 2024.<\/p>\n\n\n\n<p>Com isso, um novo certame entrou no planejamento da Casa, com o prazo m\u00e1ximo para realiza\u00e7\u00e3o de seis meses, conforme as orienta\u00e7\u00f5es do MPAM.<\/p>\n\n\n\n<p class=\"has-text-align-center\"><em>Quer saber mais sobre as atividades suspensas e todos os detalhes do concurso C\u00e2mara de Manaus? Ent\u00e3o, acesse nosso artigo na \u00edntegra:<\/em><\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center has-cyan-bluish-gray-background-color has-background has-medium-font-size\" id=\"h-saiba-mais-concurso-camara-municipal-de-manaus\">Saiba mais: <a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-camara-de-manaus\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concurso C\u00e2mara Municipal de Manaus<\/a><\/h2>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"curso\">Quer saber tudo sobre concursos previstos?<br \/>Confira nossos artigos!<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-camaras-municipais\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos C\u00e2maras<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos abertos<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2025\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos 2025<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2026\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos 2026<\/a><\/li>\n<\/ul>\n\n\n\n<div class=\"container\" id=\"boxes\">\n  <div class=\"row\">\n\n    <div class=\"col-sm\">\n      <div class=\"estrategia\" id=\"box-assinatura\">\n        <h3 class=\"titulo-assinatura\">Assinatura Concursos<\/h3>\n        <p class=\"subtitulo-assinatura\">Assinatura de 1 ano ou 2 anos<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/assinaturas\/\" role=\"button\" rel=\"noopener noreferrer\">ASSINE AGORA<\/a>\n        <\/div>\n      <\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Concurso C\u00e2mara de Manaus tem atividades suspensas pelo TJ AM! O Tribunal de Justi\u00e7a do Amazonas (TJAM) suspendeu a cria\u00e7\u00e3o da comiss\u00e3o e demais avan\u00e7os do concurso p\u00fablico da C\u00e2mara Municipal de Manaus. Segundo decis\u00e3o publicada na \u00faltima ter\u00e7a-feira, 5 de agosto, a medida \u00e9 provis\u00f3ria e pro\u00edbe qualquer movimenta\u00e7\u00e3o no novo certame at\u00e9 que [&hellip;]<\/p>\n","protected":false},"author":1206,"featured_media":1147600,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"news","footnotes":""},"categories":[2017,220219],"tags":[],"tax_estado":[219966],"class_list":["post-1619364","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-concursos-legislativos","category-noticias","tax_estado-am"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Concurso C\u00e2mara de Manaus: comiss\u00e3o e atividades suspensas<\/title>\n<meta name=\"description\" content=\"TJ AM suspende a cria\u00e7\u00e3o da comiss\u00e3o e demais avan\u00e7os do concurso p\u00fablico da C\u00e2mara Municipal de Manaus. Confira os detalhes!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-camara-de-manaus-atividades-suspensas\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Concurso C\u00e2mara de Manaus: comiss\u00e3o e atividades suspensas\" \/>\n<meta property=\"og:description\" content=\"TJ AM suspende a cria\u00e7\u00e3o da comiss\u00e3o e demais avan\u00e7os do concurso p\u00fablico da C\u00e2mara Municipal de Manaus. Confira os detalhes!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-camara-de-manaus-atividades-suspensas\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-06T19:53:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-06T19:53:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/01\/04180934\/768-432-max-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"432\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bruna de Andrade Fran\u00e7a\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bruna de Andrade Fran\u00e7a\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-camara-de-manaus-atividades-suspensas\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-camara-de-manaus-atividades-suspensas\/\"},\"author\":{\"name\":\"Bruna de Andrade Fran\u00e7a\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/6630f91134abc08115cca62ce6372855\"},\"headline\":\"Concurso C\u00e2mara de Manaus: comiss\u00e3o e atividades suspensas\",\"datePublished\":\"2025-08-06T19:53:36+00:00\",\"dateModified\":\"2025-08-06T19:53:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-camara-de-manaus-atividades-suspensas\/\"},\"wordCount\":311,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-camara-de-manaus-atividades-suspensas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/01\/04180934\/768-432-max-1.jpg\",\"articleSection\":[\"Legislativo\",\"\u00daltimas not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-camara-de-manaus-atividades-suspensas\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-camara-de-manaus-atividades-suspensas\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-camara-de-manaus-atividades-suspensas\/\",\"name\":\"Concurso C\u00e2mara de Manaus: comiss\u00e3o e atividades suspensas\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-camara-de-manaus-atividades-suspensas\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-camara-de-manaus-atividades-suspensas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/01\/04180934\/768-432-max-1.jpg\",\"datePublished\":\"2025-08-06T19:53:36+00:00\",\"dateModified\":\"2025-08-06T19:53:38+00:00\",\"description\":\"TJ AM suspende a cria\u00e7\u00e3o da comiss\u00e3o e demais avan\u00e7os do concurso p\u00fablico da C\u00e2mara Municipal de Manaus. Confira os detalhes!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-camara-de-manaus-atividades-suspensas\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-camara-de-manaus-atividades-suspensas\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-camara-de-manaus-atividades-suspensas\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/01\/04180934\/768-432-max-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/01\/04180934\/768-432-max-1.jpg\",\"width\":768,\"height\":432,\"caption\":\"c\u00e2mara de manaus\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-camara-de-manaus-atividades-suspensas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Concurso C\u00e2mara de Manaus: comiss\u00e3o e atividades suspensas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/6630f91134abc08115cca62ce6372855\",\"name\":\"Bruna de Andrade Fran\u00e7a\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/d6316d36d50cea0fadae28ed3015b8870cc90a2d3d8a95c37b44006af36a00e3?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d6316d36d50cea0fadae28ed3015b8870cc90a2d3d8a95c37b44006af36a00e3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d6316d36d50cea0fadae28ed3015b8870cc90a2d3d8a95c37b44006af36a00e3?s=96&d=mm&r=g\",\"caption\":\"Bruna de Andrade Fran\u00e7a\"},\"description\":\"Bruna de Andrade Fran\u00e7a \u00e9 publicit\u00e1ria com p\u00f3s-gradua\u00e7\u00e3o em Marketing &amp; Growth, atuando h\u00e1 mais de 6 anos no universo dos concursos p\u00fablicos. Desde 2021, lidera no Blog do Estrat\u00e9gia Concursos a cobertura editorial especializada em Concursos Policiais (PF, PRF, PM, PC, etc.), al\u00e9m das frentes de concursos banc\u00e1rios, de sa\u00fade e da \u00e1rea legislativa. Especialista em reda\u00e7\u00e3o, com pr\u00e1ticas de SEO e Copywriting, possui tamb\u00e9m atua\u00e7\u00e3o pr\u00e1tica de contato direto com \u00f3rg\u00e3os p\u00fablicos respons\u00e1veis por editais, permitindo acesso antecipado a informa\u00e7\u00f5es, desdobramentos importantes e atualiza\u00e7\u00e3o eficiente dos concursos p\u00fablicos.\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/bruna-andrade\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Concurso C\u00e2mara de Manaus: comiss\u00e3o e atividades suspensas","description":"TJ AM suspende a cria\u00e7\u00e3o da comiss\u00e3o e demais avan\u00e7os do concurso p\u00fablico da C\u00e2mara Municipal de Manaus. Confira os detalhes!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-camara-de-manaus-atividades-suspensas\/","og_locale":"pt_BR","og_type":"article","og_title":"Concurso C\u00e2mara de Manaus: comiss\u00e3o e atividades suspensas","og_description":"TJ AM suspende a cria\u00e7\u00e3o da comiss\u00e3o e demais avan\u00e7os do concurso p\u00fablico da C\u00e2mara Municipal de Manaus. Confira os detalhes!","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-camara-de-manaus-atividades-suspensas\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2025-08-06T19:53:36+00:00","article_modified_time":"2025-08-06T19:53:38+00:00","og_image":[{"width":768,"height":432,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/01\/04180934\/768-432-max-1.jpg","type":"image\/jpeg"}],"author":"Bruna de Andrade Fran\u00e7a","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Bruna de Andrade Fran\u00e7a","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-camara-de-manaus-atividades-suspensas\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-camara-de-manaus-atividades-suspensas\/"},"author":{"name":"Bruna de Andrade Fran\u00e7a","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/6630f91134abc08115cca62ce6372855"},"headline":"Concurso C\u00e2mara de Manaus: comiss\u00e3o e atividades suspensas","datePublished":"2025-08-06T19:53:36+00:00","dateModified":"2025-08-06T19:53:38+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-camara-de-manaus-atividades-suspensas\/"},"wordCount":311,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-camara-de-manaus-atividades-suspensas\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/01\/04180934\/768-432-max-1.jpg","articleSection":["Legislativo","\u00daltimas not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-camara-de-manaus-atividades-suspensas\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-camara-de-manaus-atividades-suspensas\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-camara-de-manaus-atividades-suspensas\/","name":"Concurso C\u00e2mara de Manaus: comiss\u00e3o e atividades suspensas","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-camara-de-manaus-atividades-suspensas\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-camara-de-manaus-atividades-suspensas\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/01\/04180934\/768-432-max-1.jpg","datePublished":"2025-08-06T19:53:36+00:00","dateModified":"2025-08-06T19:53:38+00:00","description":"TJ AM suspende a cria\u00e7\u00e3o da comiss\u00e3o e demais avan\u00e7os do concurso p\u00fablico da C\u00e2mara Municipal de Manaus. Confira os detalhes!","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-camara-de-manaus-atividades-suspensas\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-camara-de-manaus-atividades-suspensas\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-camara-de-manaus-atividades-suspensas\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/01\/04180934\/768-432-max-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/01\/04180934\/768-432-max-1.jpg","width":768,"height":432,"caption":"c\u00e2mara de manaus"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-camara-de-manaus-atividades-suspensas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Concurso C\u00e2mara de Manaus: comiss\u00e3o e atividades suspensas"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/6630f91134abc08115cca62ce6372855","name":"Bruna de Andrade Fran\u00e7a","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/d6316d36d50cea0fadae28ed3015b8870cc90a2d3d8a95c37b44006af36a00e3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d6316d36d50cea0fadae28ed3015b8870cc90a2d3d8a95c37b44006af36a00e3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d6316d36d50cea0fadae28ed3015b8870cc90a2d3d8a95c37b44006af36a00e3?s=96&d=mm&r=g","caption":"Bruna de Andrade Fran\u00e7a"},"description":"Bruna de Andrade Fran\u00e7a \u00e9 publicit\u00e1ria com p\u00f3s-gradua\u00e7\u00e3o em Marketing &amp; Growth, atuando h\u00e1 mais de 6 anos no universo dos concursos p\u00fablicos. Desde 2021, lidera no Blog do Estrat\u00e9gia Concursos a cobertura editorial especializada em Concursos Policiais (PF, PRF, PM, PC, etc.), al\u00e9m das frentes de concursos banc\u00e1rios, de sa\u00fade e da \u00e1rea legislativa. Especialista em reda\u00e7\u00e3o, com pr\u00e1ticas de SEO e Copywriting, possui tamb\u00e9m atua\u00e7\u00e3o pr\u00e1tica de contato direto com \u00f3rg\u00e3os p\u00fablicos respons\u00e1veis por editais, permitindo acesso antecipado a informa\u00e7\u00f5es, desdobramentos importantes e atualiza\u00e7\u00e3o eficiente dos concursos p\u00fablicos.","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/bruna-andrade\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1619364","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/1206"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1619364"}],"version-history":[{"count":3,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1619364\/revisions"}],"predecessor-version":[{"id":1619378,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1619364\/revisions\/1619378"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/1147600"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1619364"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1619364"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1619364"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1619364"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}