{"id":1618401,"date":"2025-08-06T11:37:00","date_gmt":"2025-08-06T14:37:00","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=1618401"},"modified":"2025-08-06T11:38:01","modified_gmt":"2025-08-06T14:38:01","slug":"concurso-tcu-2025-recursos-tecnico","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tcu-2025-recursos-tecnico\/","title":{"rendered":"Concurso TCU 2025: recursos para T\u00e9cnico de Controle"},"content":{"rendered":"\n<p style=\"font-size:clamp(14.642px, 0.915rem + ((1vw - 3.2px) * 0.721), 22px);\"><em><strong>Quer interpor recursos contra os gabaritos preliminares do concurso TCU para o cargo de T\u00e9cnico Federal de Controle Externo? Confira as possibilidades neste artigo!<\/strong><\/em><\/p>\n\n\n\n<p>O <strong>concurso p\u00fablico do Tribunal de Contas da Uni\u00e3o 2025 <\/strong>teve suas provas aplicadas neste \u00faltimo domingo, 3 de agosto. Com isso, os gabaritos preliminares da etapa j\u00e1 foram divulgados.&nbsp;<\/p>\n\n\n\n<p>Se voc\u00ea pretende <strong>interpor recurso contra o gabarito de T\u00e9cnico Federal de Controle Externo do concurso TCU<\/strong>, muita aten\u00e7\u00e3o: todo o processo deve ser realizado <strong>nos dias 6 e 7 de agosto<\/strong>, atrav\u00e9s do&nbsp;<a href=\"https:\/\/www.cebraspe.org.br\/concursos\/tcu_25_tefc\" target=\"_blank\" rel=\"noreferrer noopener\">site do Cebraspe<\/a>.<\/p>\n\n\n\n<p>E para te ajudar, nossos professores analisaram o resultado e identificaram algumas possibilidades de recursos. Confira abaixo!<\/p>\n\n\n\n<ul id=\"indice\" class=\"wp-block-list\">\n<li><a href=\"#execucao-orcamentaria-e-financeira\">Recursos de Execu\u00e7\u00e3o Or\u00e7ament\u00e1ria e Financeira<\/a><\/li>\n\n\n\n<li><a href=\"#lingua-inglesa\">Recursos de L\u00edngua Inglesa<\/a><\/li>\n\n\n\n<li><a href=\"#legislacao-e-controle-externo\">Recursos de Legisla\u00e7\u00e3o e Controle Externo<\/a><\/li>\n\n\n\n<li><a href=\"#ti\">Recursos de Tecnologia da Informa\u00e7\u00e3o<\/a><\/li>\n\n\n\n<li><a href=\"#direito-administrativo-gestao-contratos\">Recursos de Direito Administrativo e Gest\u00e3o de Contratos<\/a><\/li>\n<\/ul>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"lyte-wrapper\" style=\"width:853px;max-width:100%;margin:5px;\"><div class=\"lyMe\" id=\"WYL_pil6CqSk5M0\"><div id=\"lyte_pil6CqSk5M0\" data-src=\"\/\/i.ytimg.com\/vi\/pil6CqSk5M0\/hqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\"><\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/pil6CqSk5M0\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/pil6CqSk5M0\/0.jpg\" alt=\"YouTube video thumbnail\" width=\"853\" height=\"460\" \/><br \/>Assista a este v\u00eddeo no YouTube<\/a><\/noscript><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:853px;margin:5px;\"><\/div>\n<\/div><\/figure>\n\n\n\n<h2 class=\"wp-block-heading has-very-light-gray-to-cyan-bluish-gray-gradient-background has-background\" id=\"execucao-orcamentaria-e-financeira\">Concurso TCU &#8211; T\u00e9cnico de Controle: recursos de Execu\u00e7\u00e3o Or\u00e7ament\u00e1ria e Financeira<\/h2>\n\n\n\n<p><strong>Prof. Gabriela Zavadinack<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"672\" height=\"657\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/08\/05162047\/image-66.png\" alt=\"Recursos de Execu\u00e7\u00e3o Or\u00e7ament\u00e1ria e Financeira do TCU T\u00e9cnico\" class=\"wp-image-1618630\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/08\/05162047\/image-66.png 672w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/08\/05162047\/image-66-300x293.png 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/08\/05162047\/image-66-150x147.png 150w\" sizes=\"auto, (max-width: 672px) 100vw, 672px\" \/><figcaption class=\"wp-element-caption\">Recursos de Execu\u00e7\u00e3o Or\u00e7ament\u00e1ria e Financeira do TCU T\u00e9cnico<\/figcaption><\/figure>\n\n\n\n<p>Recurso para <strong>ANULA\u00c7\u00c3O<\/strong> das quest\u00f5es 91, 93 e 94, por extrapola\u00e7\u00e3o do conte\u00fado program\u00e1tico.<\/p>\n\n\n\n<p>Fundamentos:<\/p>\n\n\n\n<p>O conte\u00fado program\u00e1tico de Execu\u00e7\u00e3o Or\u00e7ament\u00e1ria e Financeira trouxe os seguintes itens: \u201cEXECU\u00c7\u00c3O OR\u00c7AMENT\u00c1RIA E FINANCEIRA: 1 Programa\u00e7\u00e3o, execu\u00e7\u00e3o e controle de recursos or\u00e7ament\u00e1rios e financeiros. 1.1 Empenho, liquida\u00e7\u00e3o e pagamento da despesa. 1.2 Guia de Recolhimento da Uni\u00e3o (GRU). 1.3 Sistemas de informa\u00e7\u00f5es. 1.4 Controle e pagamento de restos a pagar e de despesas de exerc\u00edcios anteriores. 1.5 Suprimento de fundos. 1.6 Conformidade di\u00e1ria e documental. 1.7 Rol de respons\u00e1veis. 2 Reten\u00e7\u00e3o e recolhimento de tributos incidentes sobre bens e servi\u00e7os. 3 No\u00e7\u00f5es de SIAFI e CPR \u2013 contas a pagar e a receber. 4 <strong>MCASP 11\u00aa Edi\u00e7\u00e3o<\/strong>. 5 Lei de Responsabilidade Fiscal (Lei complementar n\u00ba 101\/2000 e suas altera\u00e7\u00f5es)\u201d.<\/p>\n\n\n\n<p>As quest\u00f5es 91, 93 e 94 foram baseadas em Manuais n\u00e3o constantes do conte\u00fado program\u00e1tico, quais sejam: <strong><u>Manual de Demonstrativos Fiscais 14\u00aa edi\u00e7\u00e3o e Manual de Estat\u00edsticas Fiscais do Banco Central do Brasil<\/u><\/strong>.<\/p>\n\n\n\n<p>A estimada Banca previu expressamente apenas o Manual de Contabilidade Aplicada ao Setor P\u00fablico (11\u00aa edi\u00e7\u00e3o) no referido conte\u00fado program\u00e1tico, o que demonstra que, para haver a cobran\u00e7a de assuntos oriundos de Manuais T\u00e9cnicos, \u00e9 obrigat\u00f3ria a previs\u00e3o edital\u00edcia.<\/p>\n\n\n\n<p>Para responder \u00e0s quest\u00f5es 91, 93 e 94, o candidato deveria ter o conhecimento <strong><u>espec\u00edfico<\/u><\/strong> das p\u00e1ginas 264 a 268 do Manual de Demonstrativos Fiscais 14\u00aa Edi\u00e7\u00e3o (<a href=\"https:\/\/sisweb.tesouro.gov.br\/apex\/cosis\/manuais\/mdf\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/sisweb.tesouro.gov.br\/apex\/cosis\/manuais\/mdf<\/a>), bem como da p\u00e1gina 13 do Manual de Estat\u00edsticas Fiscais do Banco Central do Brasil (<a href=\"https:\/\/www.bcb.gov.br\/ftp\/infecon\/estatisticasfiscais.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.bcb.gov.br\/ftp\/infecon\/estatisticasfiscais.pdf<\/a>). <\/p>\n\n\n\n<p>Tal conte\u00fado est\u00e1 atrelado ao estudo de Economia no Setor P\u00fablico e das Finan\u00e7as P\u00fablicas, o que n\u00e3o guarda rela\u00e7\u00e3o com o conte\u00fado program\u00e1tico delimitado na disciplina Execu\u00e7\u00e3o Or\u00e7ament\u00e1ria e Financeira.<\/p>\n\n\n\n<p>Especificamente com rela\u00e7\u00e3o \u00e0 quest\u00e3o 94, deve-se registrar que ela foi constru\u00edda eminentemente com fundamento na p\u00e1gina 13 do Manual de Estat\u00edsticas Fiscais do BACEN: <em>\u201cO crit\u00e9rio \u2018abaixo da linha\u2019 n\u00e3o permite conhecer os fatores que levaram ao resultado. Isso \u00e9 realizado por meio da an\u00e1lise das receitas e despesas do setor p\u00fablico, que permite chegar ao resultado pelo crit\u00e9rio \u2018acima da linha\u2019. <\/em><\/p>\n\n\n\n<p><em><strong>Em princ\u00edpio, os dois crit\u00e9rios s\u00e3o equivalentes, e deveriam chegar aos mesmos n\u00fameros. Entretanto, podem ocorrer discrep\u00e2ncias estat\u00edsticas em decorr\u00eancia de quest\u00f5es espec\u00edficas relacionadas, por exemplo, \u00e0 abrang\u00eancia e\/ou per\u00edodo da compila\u00e7\u00e3o<\/strong>\u201d.<\/em><\/p>\n\n\n\n<p>Destaque-se que nenhum dos itens previstos no conte\u00fado program\u00e1tico de Execu\u00e7\u00e3o Or\u00e7ament\u00e1ria e Financeira possui rela\u00e7\u00e3o com o c\u00e1lculo dos resultados prim\u00e1rio e nominal, acima e abaixo da linha. <\/p>\n\n\n\n<p>N\u00e3o se extrai o referido conte\u00fado da Lei de Responsabilidade Fiscal, da Lei n\u00ba 4.320\/64, do Decreto n\u00ba 93.872\/86, tampouco do MCASP 11\u00aa edi\u00e7\u00e3o, o que demonstra que, de fato, a cobran\u00e7a do assunto extrapola o conte\u00fado program\u00e1tico de Execu\u00e7\u00e3o Or\u00e7ament\u00e1ria e Financeira.<\/p>\n\n\n\n<p>Como exemplo, a estimada Banca, no concurso para o Minist\u00e9rio do Planejamento e Or\u00e7amento &#8211; 2024 (Cargo 1: Analista de Planejamento e Or\u00e7amento \u2013 Especialidade: Geral) trouxe expressamente os itens \u201c9 Resultados Prim\u00e1rio e Nominal. 10 Os crit\u00e9rios acima da linha e abaixo da linha. 11 Necessidades de financiamento do setor p\u00fablico (NFSP)\u201d <strong>dentro da disciplina \u201cFinan\u00e7as P\u00fablicas\u201d, e n\u00e3o da disciplina \u201cPlanejamento e Or\u00e7amento P\u00fablico\u201d<\/strong> (<a href=\"https:\/\/cdn.cebraspe.org.br\/concursos\/mpo_24\/arquivos\/ED_1_MPO_24_ABERTURA.PDF\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/cdn.cebraspe.org.br\/concursos\/mpo_24\/arquivos\/ED_1_MPO_24_ABERTURA.PDF<\/a>).<\/p>\n\n\n\n<p>Al\u00e9m disso, no concurso para a Secretaria de Finan\u00e7as de Fortaleza \u2013 2023 (Cargo 4: Analista Fazend\u00e1rio Municipal \u2013 \u00c1rea Do Conhecimento: Contabilidade), a estimada banca previu expressamente o item \u201c6.2 Resultados nominal, operacional e prim\u00e1rio\u201d <strong>dentro da disciplina \u201cEconomia do Setor P\u00fablico\u201d<\/strong> e os itens \u201c7.5.2 D\u00e9ficit p\u00fablico. 7.5.3 Resultado prim\u00e1rio. 7.5.4 Resultado nominal\u201d <strong>dentro da disciplina \u201cFinan\u00e7as P\u00fablicas\u201d,<\/strong> <strong>e n\u00e3o da disciplina \u201cOr\u00e7amento P\u00fablico\u201d<\/strong> (<a href=\"https:\/\/cdn.cebraspe.org.br\/concursos\/sefin_fortaleza_ce_23\/arquivos\/ED_1_SEFIN_FORTALEZA_ABT.PDF\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/cdn.cebraspe.org.br\/concursos\/sefin_fortaleza_ce_23\/arquivos\/ED_1_SEFIN_FORTALEZA_ABT.PDF<\/a>).<\/p>\n\n\n\n<p>Indubit\u00e1vel que as tr\u00eas quest\u00f5es acerca de resultados fiscais acima e abaixo da linha n\u00e3o constam do conte\u00fado program\u00e1tico da disciplina Execu\u00e7\u00e3o Or\u00e7ament\u00e1ria e Financeira, raz\u00e3o por que devem ser anuladas por extrapola\u00e7\u00e3o do conte\u00fado program\u00e1tico e por afronta ao item 8.1 do edital, segundo o qual \u201c8.1 As provas objetivas, de car\u00e1ter eliminat\u00f3rio e classificat\u00f3rio, valer\u00e3o 120,00 pontos e abranger\u00e3o os objetos de avalia\u00e7\u00e3o constantes do item 18 deste edital\u201d.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-dots\"\/>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"824\" height=\"180\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/08\/05162124\/image-67.png\" alt=\"Recursos de Execu\u00e7\u00e3o Or\u00e7ament\u00e1ria e Financeira do TCU T\u00e9cnico\" class=\"wp-image-1618631\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/08\/05162124\/image-67.png 824w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/08\/05162124\/image-67-300x66.png 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/08\/05162124\/image-67-768x168.png 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/08\/05162124\/image-67-150x33.png 150w\" sizes=\"auto, (max-width: 824px) 100vw, 824px\" \/><figcaption class=\"wp-element-caption\">Recursos de Execu\u00e7\u00e3o Or\u00e7ament\u00e1ria e Financeira do TCU T\u00e9cnico<\/figcaption><\/figure>\n\n\n\n<p><strong>Gabarito preliminar: ERRADO.<\/strong><\/p>\n\n\n\n<p><strong>Gabarito sugerido: ANULA\u00c7\u00c3O<\/strong>.<\/p>\n\n\n\n<p>Fundamentos:<\/p>\n\n\n\n<p>O gabarito preliminar apontado pela estimada Banca para a quest\u00e3o n\u00ba 92 foi Errado.<\/p>\n\n\n\n<p>Ocorre que a reda\u00e7\u00e3o do item prejudicou o seu julgamento objetivo. Isso porque n\u00e3o \u00e9 poss\u00edvel concluir se a frase \u201c<em>podendo ser alterado durante o exerc\u00edcio mediante justificativa t\u00e9cnica e aprova\u00e7\u00e3o do Poder Legislativo\u201d<\/em> diz respeito \u00e0 exist\u00eancia de previs\u00e3o na Lei de Responsabilidade Fiscal (conforme parte inicial da assertiva) ou se \u00e9 apenas a explica\u00e7\u00e3o acerca da meta de resultado prim\u00e1rio, sem necessariamente estar atrelada \u00e0 primeira frase.<\/p>\n\n\n\n<p>Em outras palavras: da leitura do item, o candidato n\u00e3o consegue concluir se a assertiva afirma que a possibilidade de altera\u00e7\u00e3o da meta de resultado prim\u00e1rio consta, ou n\u00e3o, da Lei de Responsabilidade Fiscal, o que, obviamente, prejudica o seu julgamento objetivo e a marca\u00e7\u00e3o do gabarito.<\/p>\n\n\n\n<p>Al\u00e9m disso, n\u00e3o \u00e9 poss\u00edvel concluir se a estimada Banca utilizou o termo \u201cresultado prim\u00e1rio m\u00ednimo\u201d como sin\u00f4nimo de \u201cmeta\u201d (tendo em vista que o art. 4\u00ba, \u00a7 5\u00ba, IV, da LRF prev\u00ea que o Anexo de Metas Fiscais na Uni\u00e3o deve conter \u201cos intervalos de toler\u00e2ncia para verifica\u00e7\u00e3o do cumprimento das metas anuais de resultado prim\u00e1rio, convertido em valores correntes, de menos 0,25 p.p. (vinte e cinco cent\u00e9simos ponto percentual) e de mais 0,25 p.p. (vinte e cinco cent\u00e9simos ponto percentual) do PIB previsto no respectivo projeto de lei de diretrizes or\u00e7ament\u00e1rias\u201d) ou se a Banca entendeu que os termos \u201cresultado prim\u00e1rio m\u00ednimo\u201d e \u201cmeta de resultado prim\u00e1rio\u201d s\u00e3o distintos.<\/p>\n\n\n\n<p>Assim, havendo duas possibilidades de interpreta\u00e7\u00e3o em dois pontos espec\u00edficos da assertiva, tamb\u00e9m h\u00e1 duas possibilidades de resposta, o que afronta as regras previstas no item 8.2 do edital, segundo o qual \u201c8.2 Cada prova objetiva ser\u00e1 constitu\u00edda de itens para julgamento, agrupados por comandos que dever\u00e3o ser respeitados. O julgamento de cada item ser\u00e1 CERTO ou ERRADO, de acordo com o(s) comando(s) a que se refere o item.(&#8230;)\u201d.<\/p>\n\n\n\n<p>Requerer ANULA\u00c7\u00c3O da quest\u00e3o, tendo em vista que a reda\u00e7\u00e3o do item prejudicou o seu julgamento objetivo.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-dots\"\/>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"775\" height=\"170\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/08\/05162237\/image-69.png\" alt=\"Recursos de Execu\u00e7\u00e3o Or\u00e7ament\u00e1ria e Financeira\" class=\"wp-image-1618633\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/08\/05162237\/image-69.png 775w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/08\/05162237\/image-69-300x66.png 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/08\/05162237\/image-69-768x168.png 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/08\/05162237\/image-69-150x33.png 150w\" sizes=\"auto, (max-width: 775px) 100vw, 775px\" \/><figcaption class=\"wp-element-caption\">Recursos de Execu\u00e7\u00e3o Or\u00e7ament\u00e1ria e Financeira do TCU T\u00e9cnico<\/figcaption><\/figure>\n\n\n\n<p><strong>Gabarito preliminar: ERRADO.<\/strong><\/p>\n\n\n\n<p><strong>Gabarito sugerido: ANULA\u00c7\u00c3O<\/strong>.<\/p>\n\n\n\n<p>Fundamentos:<\/p>\n\n\n\n<p>O comando do bloco de quest\u00f5es em que o item 99 est\u00e1 inserido assim determina: \u201cCom base nessa situa\u00e7\u00e3o hipot\u00e9tica e na legisla\u00e7\u00e3o aplic\u00e1vel, julgue os itens a seguir\u201d.<\/p>\n\n\n\n<p>De acordo com o art. 38 da L. 4.320\/64: \u201cArt. 38. Reverte \u00e0 dota\u00e7\u00e3o a import\u00e2ncia de despesa anulada no exerc\u00edcio; <strong><u>quando a anula\u00e7\u00e3o ocorrer ap\u00f3s o encerramento deste considerar-se-\u00e1 receita do ano em que se efetivar<\/u><\/strong>\u201d. Ou seja, de acordo com o art. 38, atualmente vigente e aplic\u00e1vel, o cancelamento de restos a pagar \u00e9 considerado receita do exerc\u00edcio em que se der o cancelamento.<\/p>\n\n\n\n<p>Por sua vez, de acordo com o MCASP 11\u00aa ed. (p. 56), \u201c<strong><u>N\u00e3o devem ser reconhecidos como receita or\u00e7ament\u00e1ria os recursos financeiros oriundos de: (&#8230;) b. Cancelamento de Despesas Inscritas em Restos a Pagar<\/u> <\/strong>\u2013 consiste na baixa da obriga\u00e7\u00e3o constitu\u00edda em exerc\u00edcios anteriores, portanto, trata-se de restabelecimento de saldo de disponibilidade comprometida, origin\u00e1ria de receitas arrecadadas em exerc\u00edcios anteriores e n\u00e3o de uma nova receita a ser registrada. <\/p>\n\n\n\n<p>O cancelamento de restos a pagar n\u00e3o se confunde com o recebimento de recursos provenientes do ressarcimento ou da restitui\u00e7\u00e3o de despesas pagas em exerc\u00edcios anteriores que devem ser reconhecidos como receita or\u00e7ament\u00e1ria do exerc\u00edcio\u201d.<\/p>\n\n\n\n<p>Tendo em vista a exist\u00eancia de dois entendimentos opostos sobre uma mesma situa\u00e7\u00e3o, \u00e9 necess\u00e1rio que haja no comando da quest\u00e3o a especifica\u00e7\u00e3o da norma requerida.<\/p>\n\n\n\n<p>Repise-se que o comando do bloco das quest\u00f5es 98 a 101 preceitua que: \u201cCom base nessa situa\u00e7\u00e3o hipot\u00e9tica e na legisla\u00e7\u00e3o aplic\u00e1vel, julgue os itens a seguir\u201d.<\/p>\n\n\n\n<p>Portanto, da leitura da assertiva, n\u00e3o \u00e9 poss\u00edvel saber se a estimada Banca considerar\u00e1 como correto o texto literal previsto na L. 4.320\/64 (vigente e aplic\u00e1vel) ou no MCASP (Manual T\u00e9cnico que interpreta a legisla\u00e7\u00e3o aplic\u00e1vel), raz\u00e3o por que \u00e9 poss\u00edvel marcar os gabaritos \u201ccerto\u201d e \u201cerrado\u201d.<\/p>\n\n\n\n<p>A reda\u00e7\u00e3o, portanto, prejudicou o julgamento objetivo do item.<\/p>\n\n\n\n<p>Requerer anula\u00e7\u00e3o.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-dots\"\/>\n\n\n\n<h2 class=\"wp-block-heading has-very-light-gray-to-cyan-bluish-gray-gradient-background has-background\" id=\"lingua-inglesa\">Concurso TCU &#8211; T\u00e9cnico de Controle: recursos de L\u00edngua Inglesa<\/h2>\n\n\n\n<p><strong>RECURSO CONTRA O GABARITO DA QUEST\u00c3O 23 DO CONCURSO TCU<\/strong><\/p>\n\n\n\n<p><strong>23 According to the text, one of the anticipated outcomes of the scholarship initiative is helping scholars obtain stable, specialised jobs.<\/strong><\/p>\n\n\n\n<p>Prezada Banca Examinadora,<\/p>\n\n\n\n<p>Venho, por meio deste recurso, expressar meu desacordo com o gabarito oficial divulgado para a quest\u00e3o 23, da prova TCU, cuja frase \u00e9 &#8220;Em busca do destino, a pessoa descobre-se a si mesmo&#8221;.<\/p>\n\n\n\n<p>Ap\u00f3s uma an\u00e1lise minuciosa do texto base na quest\u00e3o 23, apesar do gabarito preliminar apresentar Errado, solicita-se altera\u00e7\u00e3o para: Certo<\/p>\n\n\n\n<p>O item afirma que \u201c<em>one of the anticipated outcomes of the scholarship initiative is helping scholars obtain stable, specialised jobs.<\/em>\u201d<\/p>\n\n\n\n<p>De acordo com o texto-base, o secret\u00e1rio de tecnologia Peter Kyle declarou que acredita que o programa de bolsas ajudar\u00e1 os estudantes a conseguirem \u201c<em>highly skilled jobs<\/em>\u201d (empregos altamente qualificados) e a construir uma \u201c<em>workforce fit for the future.<\/em>\u201d Tais express\u00f5es indicam claramente que um dos objetivos do programa \u00e9 a inser\u00e7\u00e3o dos bolsistas em empregos especializados e alinhados \u00e0s necessidades do mercado futuro, que se conecta \u00e0 ideia de bons empregos, incluindo os est\u00e1veis.<\/p>\n\n\n\n<p>A associa\u00e7\u00e3o entre \u201c<em>highly skilled jobs<\/em>\u201d e empregos est\u00e1veis \u00e9 natural no contexto do texto, que trata de um programa governamental estruturado, com grande investimento, focado no desenvolvimento de talentos para uma \u00e1rea de alta demanda e crescimento.<\/p>\n\n\n\n<p>&nbsp;Ademais, o enunciado do item utiliza a express\u00e3o \u201c<em>one of the anticipated outcomes<\/em>\u201d, ou seja, n\u00e3o exige correspond\u00eancia literal, apenas a coer\u00eancia com os objetivos mencionados no texto.<\/p>\n\n\n\n<p>Portanto, a leitura do item est\u00e1 plenamente de acordo com o conte\u00fado textual, e o gabarito correto \u00e9 Certo.<\/p>\n\n\n\n<p>Solicita-se, assim, a revis\u00e3o do gabarito oficial.<\/p>\n\n\n\n<p>Att, Andrea Belo<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-dots\"\/>\n\n\n\n<h2 class=\"wp-block-heading has-very-light-gray-to-cyan-bluish-gray-gradient-background has-background\" id=\"legislacao-e-controle-externo\">Concurso TCU &#8211; T\u00e9cnico de Controle: recursos de Legisla\u00e7\u00e3o e Controle Externo<\/h2>\n\n\n\n<p>Ol\u00e1, pessoal! Aqui \u00e9 o Prof. Herbert Almeida. Seguem as minhas sugest\u00f5es de recursos para a prova do TCU. N\u00e3o se esque\u00e7a de usar as suas palavras, evitando a mera reprodu\u00e7\u00e3o das propostas a seguir.<\/p>\n\n\n\n<p><strong>Quest\u00e3o: As provas produzidas pelas partes devem ser apresentadas, sempre que poss\u00edvel, de forma documental, inclusive as declara\u00e7\u00f5es pessoais de terceiros.<\/strong><\/p>\n\n\n\n<p><strong><u>Coment\u00e1rio<\/u><\/strong>:<\/p>\n\n\n\n<p>A quest\u00e3o afirma que as partes dever\u00e3o apresentar prova documental \u201csempre que poss\u00edvel\u201d. O Regimento Interno do TCU, por outro lado, disp\u00f5e que:<\/p>\n\n\n\n<p>Art. 162. As provas que a parte quiser produzir perante o Tribunal <strong>devem SEMPRE ser apresentadas de forma documental<\/strong>, mesmo as declara\u00e7\u00f5es pessoais de terceiros.<\/p>\n\n\n\n<p>No Regimento, n\u00e3o existe nenhuma ressalva sobre a apresenta\u00e7\u00e3o de prova documental. Segundo o Regimento, as provas ser\u00e3o SEMPRE apresentadas de forma documental.<\/p>\n\n\n\n<p>Portanto, o trecho \u201csempre que poss\u00edvel\u201d d\u00e1 ideia de exce\u00e7\u00e3o que n\u00e3o existe no Regimento Interno do TCU, tornando a quest\u00e3o incorreta.<\/p>\n\n\n\n<p>Logo, sugere-se a altera\u00e7\u00e3o da quest\u00e3o para ERRADO.<\/p>\n\n\n\n<p>Gabarito preliminar: correto \/ Sugest\u00e3o: errado.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-dots\"\/>\n\n\n\n<p><strong>Quest\u00e3o: No Brasil, o sistema de controle interno de cada Poder da Rep\u00fablica tem como uma de suas atribui\u00e7\u00f5es prec\u00edpuas apoiar o controle externo, fornecendo informa\u00e7\u00f5es e realizando auditorias, mas sem compet\u00eancia para aplicar san\u00e7\u00f5es aos respons\u00e1veis por irregularidades financeiras.<\/strong><\/p>\n\n\n\n<p><strong><u>Coment\u00e1rio<\/u><\/strong>:<\/p>\n\n\n\n<p>Segundo a banca, a quest\u00e3o est\u00e1 incorreta. Contudo, n\u00e3o h\u00e1 erro na quest\u00e3o, sob o prisma constitucional.<\/p>\n\n\n\n<p>Nesse sentido, a CF disp\u00f5e que:<\/p>\n\n\n\n<p>Art. 74. Os Poderes Legislativo, Executivo e Judici\u00e1rio manter\u00e3o, de forma integrada, sistema de controle interno com a finalidade de:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>I &#8211; avaliar o cumprimento das metas previstas no plano plurianual, a execu\u00e7\u00e3o dos programas de governo e dos or\u00e7amentos da Uni\u00e3o;<\/li>\n\n\n\n<li>II &#8211; comprovar a legalidade e avaliar os resultados, quanto \u00e0 efic\u00e1cia e efici\u00eancia, da gest\u00e3o or\u00e7ament\u00e1ria, financeira e patrimonial nos \u00f3rg\u00e3os e entidades da administra\u00e7\u00e3o federal, bem como da aplica\u00e7\u00e3o de recursos p\u00fablicos por entidades de direito privado;<\/li>\n\n\n\n<li>III &#8211; exercer o controle das opera\u00e7\u00f5es de cr\u00e9dito, avais e garantias, bem como dos direitos e haveres da Uni\u00e3o;<\/li>\n\n\n\n<li>IV &#8211; apoiar o controle externo no exerc\u00edcio de sua miss\u00e3o institucional.<\/li>\n<\/ul>\n\n\n\n<p>\u00a7 1\u00ba Os respons\u00e1veis pelo controle interno, ao tomarem conhecimento de qualquer irregularidade ou ilegalidade, dela dar\u00e3o ci\u00eancia ao Tribunal de Contas da Uni\u00e3o, sob pena de responsabilidade solid\u00e1ria.<\/p>\n\n\n\n<p>Dessa forma, \u00e9 verdadeira a parte de que o sistema de controle interno (SCI) dever\u00e1 apoiar o controle externo (art. 74, III). Tamb\u00e9m \u00e9 verdadeira a informa\u00e7\u00e3o de que o SCI dever\u00e1 fornecer informa\u00e7\u00f5es, nos termos do art. 74, \u00a7 1\u00ba. Por fim, o SCI realiza auditorias, em raz\u00e3o da sua compet\u00eancia fiscalizat\u00f3ria constante nos incisos I a III do art. 74.<\/p>\n\n\n\n<p>Talvez a banca tenha considerado o quesito incorreto com base na decis\u00e3o recente do STF, na ADI 5.705\/SC, quando a Corte considerou que \u201c\u00c9 inconstitucional \u2014 por violar o princ\u00edpio da separa\u00e7\u00e3o de Poderes (CF\/1988, art. 2\u00ba) e os sistemas de controle externo e interno (CF\/1988, arts. 70 e 74, IV) \u2014 norma estadual que confere ao Tribunal de Contas local a prerrogativa de determinar a realiza\u00e7\u00e3o de auditorias aos \u00f3rg\u00e3os de controle interno de cada Poder\u201d. <\/p>\n\n\n\n<p>Todavia, o enunciado da quest\u00e3o n\u00e3o prev\u00ea que o TC vai determinar auditoria. Assim, cabe ao controle interno, no seu planejamento pr\u00f3prio, decidir por realizar auditorias. Sendo assim, o item continua correto.<\/p>\n\n\n\n<p>Por fim, nenhum dos dispositivos do art. 74 outorga ao SCI a compet\u00eancia para aplicar san\u00e7\u00f5es no \u00e2mbito do controle financeiro. Este papel, por outro lado, \u00e9 previsto para o sistema de controle externo, nos termos do art. 71, VIII:<\/p>\n\n\n\n<p>Art. 71. O controle externo, a cargo do Congresso Nacional, ser\u00e1 exercido com o aux\u00edlio do Tribunal de Contas da Uni\u00e3o, ao qual compete: [&#8230;] VIII &#8211; aplicar aos respons\u00e1veis, em caso de ilegalidade de despesa ou irregularidade de contas, as san\u00e7\u00f5es previstas em lei, que estabelecer\u00e1, entre outras comina\u00e7\u00f5es, multa proporcional ao dano causado ao er\u00e1rio;<\/p>\n\n\n\n<p>Logo, todas as afirma\u00e7\u00f5es do quesito est\u00e3o corretas.<\/p>\n\n\n\n<p>Caso a banca tenha considerado o termo \u201ccontrole interno\u201d, no sentido de controle interno administrativo, at\u00e9 poder\u00edamos prever a aplica\u00e7\u00e3o de san\u00e7\u00f5es disciplinares. Por exemplo: o chefe de um servidor tem compet\u00eancia para lhe aplicar san\u00e7\u00f5es disciplinares. Contudo, n\u00e3o se trata de \u201cirregularidade financeira\u201d, que \u00e9 tema abordado nos arts. 70 a 75 da CF.<\/p>\n\n\n\n<p>Dessa forma, sugere-se a altera\u00e7\u00e3o do gabarito para CORRETO.<\/p>\n\n\n\n<p>Gabarito preliminar: errado \/ Sugest\u00e3o: correto.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-dots\"\/>\n\n\n\n<p><strong>Quest\u00e3o: A cria\u00e7\u00e3o de um tribunal administrativo com poder de julgamento definitivo, cuja decis\u00e3o impedisse a revis\u00e3o judicial sobre o m\u00e9rito do ato, seria compat\u00edvel com o sistema brasileiro de controle da administra\u00e7\u00e3o p\u00fablica, desde que a Constitui\u00e7\u00e3o Federal fosse alterada para prever expressamente essa compet\u00eancia excepcional.<\/strong><\/p>\n\n\n\n<p><strong><u>Coment\u00e1rio<\/u><\/strong>:<\/p>\n\n\n\n<p>Segundo a banca, o quesito est\u00e1 CORRETO. Entretanto, a afirmativa apresenta algumas contradi\u00e7\u00f5es e erros.<\/p>\n\n\n\n<p>Primeiro, cabe anotar que, no Brasil, o Poder Judici\u00e1rio n\u00e3o analisa m\u00e9rito de ato administrativo. Dessa forma, n\u00e3o haveria necessidade de criar um tribunal administrativo mediante emenda \u00e0 Constitui\u00e7\u00e3o, pois o modelo brasileiro j\u00e1 separa o ju\u00edzo de m\u00e9rito (privativo da autoridade administrativa) do controle jurisdicional (exclusivo do controle de legalidade). <\/p>\n\n\n\n<p>Portanto, repita-se: o modelo nacional j\u00e1 adota esta divis\u00e3o, n\u00e3o havendo necessidade de alterar a Constitui\u00e7\u00e3o para isso. Nesse caso, a compet\u00eancia tamb\u00e9m n\u00e3o seria \u201cexcepcional\u201d, j\u00e1 que o ju\u00edzo de conveni\u00eancia e oportunidade j\u00e1 pertence \u00e0 Administra\u00e7\u00e3o.<\/p>\n\n\n\n<p>Por outro lado, desconsiderando as informa\u00e7\u00f5es acima, o item continuaria incorreto. Caso fosse poss\u00edvel ao Judici\u00e1rio, no ordenamento atual, realizar controle de m\u00e9rito (o que, repita-se, n\u00e3o \u00e9), n\u00e3o seria poss\u00edvel alterar o texto constitucional, sob pena de violar o art. 60, \u00a7 4\u00ba, III, da CF:<\/p>\n\n\n\n<p>Art. 60 [&#8230;] \u00a7 4\u00ba N\u00e3o ser\u00e1 objeto de delibera\u00e7\u00e3o a proposta de emenda tendente a abolir: III &#8211; a separa\u00e7\u00e3o dos Poderes;<\/p>\n\n\n\n<p>Haveria viola\u00e7\u00e3o ao princ\u00edpio da inafastabilidade da tutela de jurisdi\u00e7\u00e3o, previsto no art. 5\u00ba, XXXV, da Constitui\u00e7\u00e3o Federal. No Brasil, somente o Poder Judici\u00e1rio pode tomar decis\u00f5es com for\u00e7a de definitividade, constituindo o sistema da jurisdi\u00e7\u00e3o uma.<\/p>\n\n\n\n<p>Portanto, a quest\u00e3o \u00e9 incorreta, seja por considerar o controle administrativo de m\u00e9rito como algo excepcional, seja por permitir que o sistema da jurisdi\u00e7\u00e3o una fosse extinto do modelo nacional, violando cl\u00e1usula p\u00e9trea da Constitui\u00e7\u00e3o.<\/p>\n\n\n\n<p>Gabarito preliminar: certo \/ Sugest\u00e3o: errado.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-dots\"\/>\n\n\n\n<h2 class=\"wp-block-heading has-very-light-gray-to-cyan-bluish-gray-gradient-background has-background\" id=\"ti\">Concurso TCU &#8211; T\u00e9cnico de Controle: recursos de Tecnologia da Informa\u00e7\u00e3o<\/h2>\n\n\n\n<p>Enunciado:<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"532\" height=\"289\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/08\/06083124\/image-74.png\" alt=\"Recursos de Tecnologia da Informa\u00e7\u00e3o do TCU T\u00e9cnico\" class=\"wp-image-1618824\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/08\/06083124\/image-74.png 532w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/08\/06083124\/image-74-300x163.png 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/08\/06083124\/image-74-150x81.png 150w\" sizes=\"auto, (max-width: 532px) 100vw, 532px\" \/><figcaption class=\"wp-element-caption\">Recursos de Tecnologia da Informa\u00e7\u00e3o do TCU T\u00e9cnico<\/figcaption><\/figure>\n\n\n\n<p>Com base na planilha precedente, elaborada no MS Excel 365, julgue o pr\u00f3ximo item.<\/p>\n\n\n\n<p>A f\u00f3rmula a seguir retorna 185, que corresponde \u00e0 soma de inscritos apenas nos cargos Analista de TI e Suporte T\u00e9cnico.<\/p>\n\n\n\n<p>=SOMAR(FILTRAR(B2:B6;(A2:A6=&#8221;Suporte&nbsp;&nbsp;&nbsp;&nbsp; T\u00e9cnico&#8221;)+(A2:A6=&#8221;Analista&nbsp; de TI&#8221;)))<\/p>\n\n\n\n<p>Gabarito Oficial: C Gabarito Proposto: E Fundamentos:<\/p>\n\n\n\n<p>A fun\u00e7\u00e3o \u201cSomar\u201d, utilizada na assertiva da quest\u00e3o n\u00e3o est\u00e1 documentada no manual da pr\u00f3pria Microsoft e n\u00e3o \u00e9 reconhecida pelas vers\u00f5es do Excel.<\/p>\n\n\n\n<p>Seguem as telas do manual da Microsoft<\/p>\n\n\n\n<p>1- Listagem&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; das&nbsp;&nbsp;&nbsp;&nbsp; fun\u00e7\u00f5es&nbsp;&nbsp;&nbsp;&nbsp; do&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Excel&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; por&nbsp;&nbsp;&nbsp;&nbsp; ordem&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; alfab\u00e9tica (https:\/\/support.microsoft.com\/pt-br\/office\/fun%C3%A7%C3%B5es-do- excel-ordem-alfab%C3%A9tica-b3944572-255d-4efb-bb96- c6d90033e188#bm19)<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"883\" height=\"551\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/08\/06083139\/image-75.png\" alt=\"\" class=\"wp-image-1618825\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/08\/06083139\/image-75.png 883w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/08\/06083139\/image-75-300x187.png 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/08\/06083139\/image-75-768x479.png 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/08\/06083139\/image-75-150x94.png 150w\" sizes=\"auto, (max-width: 883px) 100vw, 883px\" \/><figcaption class=\"wp-element-caption\">Recursos de Tecnologia da Informa\u00e7\u00e3o do TCU T\u00e9cnico<\/figcaption><\/figure>\n\n\n\n<p><strong>Dessa forma, solicita-se a troca de gabarito da quest\u00e3o. Sendo, ent\u00e3o, o gabarito definitivo proposto E.<\/strong><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-dots\"\/>\n\n\n\n<p><strong>Enunciado:<\/strong><\/p>\n\n\n\n<p><strong>No \u00e2mbito da administra\u00e7\u00e3o p\u00fablica, \u00e9 recomend\u00e1vel que o armazenamento de <em>backups <\/em>de dados cr\u00edticos seja realizado preferencialmente em infraestrutura interna \u00e0 organiza\u00e7\u00e3o, de modo a garantir maior controle f\u00edsico e facilitar a recupera\u00e7\u00e3o imediata dos dados em caso de falhas locais.<\/strong><\/p>\n\n\n\n<p>Gabarito Oficial: E<\/p>\n\n\n\n<p>Gabarito Proposto: anula\u00e7\u00e3o da quest\u00e3o Fundamentos:<\/p>\n\n\n\n<p>O Guia de Boas Pr\u00e1ticas do GSI\/PR, o Manual de Continuidade de Neg\u00f3cios da SLTI\/MP e orienta\u00e7\u00f5es da NIST (National Institute of Standards and Technology) defendem o conceito de off-site backups (externos), inclusive com uso de nuvem segura, criptografada e geograficamente redundante, sendo a melhor pr\u00e1tica a combina\u00e7\u00e3o de backup local (r\u00e1pido) + backup externo (seguro)<\/p>\n\n\n\n<p>\u2014 muitas vezes implementado como estrat\u00e9gia 3-2-1: 3 c\u00f3pias dos dados, em 2 tipos de m\u00eddia diferentes, com 1 c\u00f3pia off-site.<\/p>\n\n\n\n<p>Por\u00e9m, a Cartilha de Seguran\u00e7a para Internet \u2013 CERT.br. e o ABNT NBR ISO\/IEC 27002:2022 \u2013 Controles para backup e recupera\u00e7\u00e3o, tamb\u00e9m orientam que em ambientes p\u00fablicos e cr\u00edticos, como na administra\u00e7\u00e3o p\u00fablica, \u00e9 de fato recomend\u00e1vel manter backups locais (on-premises) para: Garantir controle f\u00edsico direto dos dados; permitir recupera\u00e7\u00e3o imediata em casos de falhas l\u00f3gicas ou operacionais; minimizar a depend\u00eancia de links de internet em cen\u00e1rios emergenciais. <\/p>\n\n\n\n<p>O que n\u00e3o exclui o uso de backups em nuvem como parte de uma estrat\u00e9gia de backup h\u00edbrido ou 3-2-1, mas a recomenda\u00e7\u00e3o da assertiva est\u00e1 em conson\u00e2ncia com boas pr\u00e1ticas.<\/p>\n\n\n\n<p>Na assertiva: \u201cNo \u00e2mbito da administra\u00e7\u00e3o p\u00fablica, \u00e9 recomend\u00e1vel que o armazenamento de <em>backups <\/em>de dados cr\u00edticos seja realizado preferencialmente em infraestrutura interna \u00e0 organiza\u00e7\u00e3o, de modo a garantir maior controle f\u00edsico e facilitar a recupera\u00e7\u00e3o imediata dos dados em caso de falhas locais.\u201d<\/p>\n\n\n\n<p>Observe que n\u00e3o \u00e9 dito se essa infraestrutura interna da Organiza\u00e7\u00e3o \u00e9 ou n\u00e3o no mesmo ambiente f\u00edsico, visto que podemos ter o backup feito dentro da infraestrutura da Organiza\u00e7\u00e3o, mas em sedes distintas, por exemplo. E fala apenas dos dados cr\u00edticos, o que n\u00e3o exclui o uso do backup em nuvem ou em outra solu\u00e7\u00e3o.<\/p>\n\n\n\n<p><strong>Dessa forma, solicita-se a anula\u00e7\u00e3o da quest\u00e3o, devido a ambiguidade do texto.<\/strong><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-dots\"\/>\n\n\n\n<h2 class=\"wp-block-heading has-very-light-gray-to-cyan-bluish-gray-gradient-background has-background\" id=\"direito-administrativo-gestao-contratos\">Concurso TCU &#8211; T\u00e9cnico de Controle: recursos de Direito Administrativo e Gest\u00e3o de Contratos<\/h2>\n\n\n\n<p><strong>Quest\u00e3o 69: Ato comissivo ou omissivo de Jo\u00e3o \u00e9 considerado ato administrativo, mesmo que ele n\u00e3o exer\u00e7a cargo p\u00fablico efetivo.<\/strong><\/p>\n\n\n\n<p>Gabarito oficial preliminar: Certo<\/p>\n\n\n\n<p>A despeito de a pr\u00e1tica de atos administrativos, de fato, n\u00e3o depender da exist\u00eancia v\u00ednculo efetivo, n\u00e3o se pode olvidar que a <strong>conduta omissiva do agente p\u00fablico <\/strong>em regra<strong> n\u00e3o caracteriza um ato administrativo<\/strong>. Para a doutrina majorit\u00e1ria, o sil\u00eancio administrativo (a in\u00e9rcia, a omiss\u00e3o) \u00e9 mero fato administrativo, visto n\u00e3o caracterizar efetivamente uma manifesta\u00e7\u00e3o de vontade do poder p\u00fablico.<\/p>\n\n\n\n<p>Portanto, sugere-se recurso para a altera\u00e7\u00e3o de gabarito, dando a afirmativa como ERRADA.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-dots\"\/>\n\n\n\n<p><strong>Quest\u00e3o 85: Para definir a produtividade de refer\u00eancia contratual, deve-se atentar para os fatores que estejam fora do controle do prestador e que possam interferir no atendimento das metas, bem como para o uso de indicadores complexos e sobrepostos.<\/strong><\/p>\n\n\n\n<p>Gabarito oficial preliminar: Errado<\/p>\n\n\n\n<p>A reda\u00e7\u00e3o do item apresenta-se imprecisa, gerando dubiedade na interpreta\u00e7\u00e3o e inseguran\u00e7a no candidato ao examinar a assertiva. <\/p>\n\n\n\n<p>A partir da ado\u00e7\u00e3o do verbo \u201catentar\u201d, seria cab\u00edvel interpretar que os aspectos mencionados na assertiva (indicadores simples\/complexos, sobrepostos\/n\u00e3o sobrepostos e que considerem fatores dentro\/fora do controle do prestador) devem ser <strong>considerados pelo gestor p\u00fablico<\/strong>, seja para evitar tais situa\u00e7\u00f5es, seja para serem buscados.<\/p>\n\n\n\n<p>Portanto, mesmo o candidato ciente das recomenda\u00e7\u00f5es estabelecidas no anexo V da IN 5\/2017 ficaria em d\u00favida sobre a correta interpreta\u00e7\u00e3o do item e, por conseguinte, prejudicando seu julgamento.<\/p>\n\n\n\n<p>Nestes termos, solicita-se sua anula\u00e7\u00e3o, em raz\u00e3o da imprecis\u00e3o do enunciado.<\/p>\n\n\n\n<p><em>IN 5\/2017, anexo V, 2.6. Modelo de gest\u00e3o do contrato e crit\u00e9rios de medi\u00e7\u00e3o e pagamento: (..)<br \/>d.3. identificar os indicadores m\u00ednimos de desempenho para aferi\u00e7\u00e3o da qualidade esperada da presta\u00e7\u00e3o dos servi\u00e7os, com base nas seguintes diretrizes: (..)<\/em><br \/><em>d.3.4. evitar indicadores complexos ou sobrepostos.<br \/>d.4. descrever detalhadamente, de acordo com o previsto na subal\u00ednea \u201cd.3\u201d acima, os indicadores m\u00ednimos de desempenho esperados, em rela\u00e7\u00e3o \u00e0 natureza do servi\u00e7o, com a finalidade de adequar o pagamento \u00e0 conformidade dos servi\u00e7os prestados e dos resultados efetivamente obtidos, devendo conter, dentre outros requisitos:<br \/>d.4.1. indicadores e metas estipulados de forma sistem\u00e1tica, de modo que possam contribuir cumulativamente para o resultado global do servi\u00e7o e n\u00e3o interfiram negativamente uns nos outros;<br \/>d.4.2. indicadores que reflitam fatores que est\u00e3o sob controle do prestador do servi\u00e7o;<\/em><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-dots\"\/>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center has-very-light-gray-to-cyan-bluish-gray-gradient-background has-background has-medium-font-size\" id=\"h-saiba-mais-concurso-tribunal-de-contas-da-uniao\">Saiba mais: <a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tcu\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concurso Tribunal de Contas da Uni\u00e3o<\/a><\/h2>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"h-quer-saber-tudo-sobre-concursos-previstos-confira-nossos-artigos\">Quer saber tudo sobre concursos previstos?<br \/>Confira nossos artigos!<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos Abertos<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-controle\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos Controle<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2025\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos 2025<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2026\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos 2026<\/a><\/li>\n<\/ul>\n\n\n\n<div id=\"boxes\" class=\"container\">\n<div class=\"row\">\n<div class=\"col-sm\">\n<div id=\"box-assinatura\" class=\"banner-tcu-ec\">\n<h2 class=\"titulo-assinatura\">Concurso TCU<\/h2>\n<p class=\"subtitulo-assinatura\">Prepare-se para o Tribunal de Contas da Uni\u00e3o!<\/p>\n<div class=\"box-botao\"><a class=\"btn-assinatura\" role=\"button\" href=\"https:\/\/www.estrategiaconcursos.com.br\/cursosPorConcurso\/tcu-tecnico-federal-de-controle-externo-66\/\" target=\"_blank\" rel=\"noopener noreferrer\">VER CURSOS<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div id=\"boxes\" class=\"container\">\n<div class=\"row\">\n<div class=\"col-sm\">\n<div id=\"box-assinatura\" class=\"estrategia\">\n<h3 class=\"titulo-assinatura\">Assinatura Concursos<\/h3>\n<p class=\"subtitulo-assinatura\">Assinatura de 1 ano ou 2 anos<\/p>\n<div class=\"box-botao\"><a class=\"btn-assinatura\" role=\"button\" href=\"https:\/\/www.estrategiaconcursos.com.br\/assinaturas\/\" target=\"_blank\" rel=\"noopener noreferrer\">ASSINE AGORA<\/a><\/div>\n<\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Quer interpor recursos contra os gabaritos preliminares do concurso TCU para o cargo de T\u00e9cnico Federal de Controle Externo? Confira as possibilidades neste artigo! O concurso p\u00fablico do Tribunal de Contas da Uni\u00e3o 2025 teve suas provas aplicadas neste \u00faltimo domingo, 3 de agosto. Com isso, os gabaritos preliminares da etapa j\u00e1 foram divulgados.&nbsp; Se [&hellip;]<\/p>\n","protected":false},"author":1206,"featured_media":903336,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"news","footnotes":""},"categories":[214710,220219],"tags":[],"tax_estado":[219963],"class_list":["post-1618401","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tribunais-de-contas","category-noticias","tax_estado-concursos-federais"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Concurso TCU 2025: recursos para T\u00e9cnico de Controle<\/title>\n<meta name=\"description\" content=\"Quer interpor recursos contra os gabaritos do concurso TCU para T\u00e9cnico Federal de Controle Externo? Veja as possibilidades!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tcu-2025-recursos-tecnico\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Concurso TCU 2025: recursos para T\u00e9cnico de Controle\" \/>\n<meta property=\"og:description\" content=\"Quer interpor recursos contra os gabaritos do concurso TCU para T\u00e9cnico Federal de Controle Externo? Veja as possibilidades!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tcu-2025-recursos-tecnico\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-06T14:37:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-06T14:38:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/11\/08141609\/tcu.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"536\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bruna de Andrade Fran\u00e7a\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bruna de Andrade Fran\u00e7a\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"21 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tcu-2025-recursos-tecnico\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tcu-2025-recursos-tecnico\/\"},\"author\":{\"name\":\"Bruna de Andrade Fran\u00e7a\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/6630f91134abc08115cca62ce6372855\"},\"headline\":\"Concurso TCU 2025: recursos para T\u00e9cnico de Controle\",\"datePublished\":\"2025-08-06T14:37:00+00:00\",\"dateModified\":\"2025-08-06T14:38:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tcu-2025-recursos-tecnico\/\"},\"wordCount\":4238,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tcu-2025-recursos-tecnico\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/11\/08141609\/tcu.jpg\",\"articleSection\":[\"Tribunais de Contas (TCU, TCE, TCM)\",\"\u00daltimas not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tcu-2025-recursos-tecnico\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tcu-2025-recursos-tecnico\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tcu-2025-recursos-tecnico\/\",\"name\":\"Concurso TCU 2025: recursos para T\u00e9cnico de Controle\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tcu-2025-recursos-tecnico\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tcu-2025-recursos-tecnico\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/11\/08141609\/tcu.jpg\",\"datePublished\":\"2025-08-06T14:37:00+00:00\",\"dateModified\":\"2025-08-06T14:38:01+00:00\",\"description\":\"Quer interpor recursos contra os gabaritos do concurso TCU para T\u00e9cnico Federal de Controle Externo? Veja as possibilidades!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tcu-2025-recursos-tecnico\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tcu-2025-recursos-tecnico\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tcu-2025-recursos-tecnico\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/11\/08141609\/tcu.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/11\/08141609\/tcu.jpg\",\"width\":1024,\"height\":536,\"caption\":\"TCU explica sobre contrata\u00e7\u00e3o de terceirizados\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tcu-2025-recursos-tecnico\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Concurso TCU 2025: recursos para T\u00e9cnico de Controle\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/6630f91134abc08115cca62ce6372855\",\"name\":\"Bruna de Andrade Fran\u00e7a\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/d6316d36d50cea0fadae28ed3015b8870cc90a2d3d8a95c37b44006af36a00e3?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d6316d36d50cea0fadae28ed3015b8870cc90a2d3d8a95c37b44006af36a00e3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d6316d36d50cea0fadae28ed3015b8870cc90a2d3d8a95c37b44006af36a00e3?s=96&d=mm&r=g\",\"caption\":\"Bruna de Andrade Fran\u00e7a\"},\"description\":\"Bruna de Andrade Fran\u00e7a \u00e9 publicit\u00e1ria com p\u00f3s-gradua\u00e7\u00e3o em Marketing &amp; Growth, atuando h\u00e1 mais de 6 anos no universo dos concursos p\u00fablicos. Desde 2021, lidera no Blog do Estrat\u00e9gia Concursos a cobertura editorial especializada em Concursos Policiais (PF, PRF, PM, PC, etc.), al\u00e9m das frentes de concursos banc\u00e1rios, de sa\u00fade e da \u00e1rea legislativa. Especialista em reda\u00e7\u00e3o, com pr\u00e1ticas de SEO e Copywriting, possui tamb\u00e9m atua\u00e7\u00e3o pr\u00e1tica de contato direto com \u00f3rg\u00e3os p\u00fablicos respons\u00e1veis por editais, permitindo acesso antecipado a informa\u00e7\u00f5es, desdobramentos importantes e atualiza\u00e7\u00e3o eficiente dos concursos p\u00fablicos.\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/bruna-andrade\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Concurso TCU 2025: recursos para T\u00e9cnico de Controle","description":"Quer interpor recursos contra os gabaritos do concurso TCU para T\u00e9cnico Federal de Controle Externo? Veja as possibilidades!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tcu-2025-recursos-tecnico\/","og_locale":"pt_BR","og_type":"article","og_title":"Concurso TCU 2025: recursos para T\u00e9cnico de Controle","og_description":"Quer interpor recursos contra os gabaritos do concurso TCU para T\u00e9cnico Federal de Controle Externo? Veja as possibilidades!","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tcu-2025-recursos-tecnico\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2025-08-06T14:37:00+00:00","article_modified_time":"2025-08-06T14:38:01+00:00","og_image":[{"width":1024,"height":536,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/11\/08141609\/tcu.jpg","type":"image\/jpeg"}],"author":"Bruna de Andrade Fran\u00e7a","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Bruna de Andrade Fran\u00e7a","Est. tempo de leitura":"21 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tcu-2025-recursos-tecnico\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tcu-2025-recursos-tecnico\/"},"author":{"name":"Bruna de Andrade Fran\u00e7a","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/6630f91134abc08115cca62ce6372855"},"headline":"Concurso TCU 2025: recursos para T\u00e9cnico de Controle","datePublished":"2025-08-06T14:37:00+00:00","dateModified":"2025-08-06T14:38:01+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tcu-2025-recursos-tecnico\/"},"wordCount":4238,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tcu-2025-recursos-tecnico\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/11\/08141609\/tcu.jpg","articleSection":["Tribunais de Contas (TCU, TCE, TCM)","\u00daltimas not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tcu-2025-recursos-tecnico\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tcu-2025-recursos-tecnico\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tcu-2025-recursos-tecnico\/","name":"Concurso TCU 2025: recursos para T\u00e9cnico de Controle","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tcu-2025-recursos-tecnico\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tcu-2025-recursos-tecnico\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/11\/08141609\/tcu.jpg","datePublished":"2025-08-06T14:37:00+00:00","dateModified":"2025-08-06T14:38:01+00:00","description":"Quer interpor recursos contra os gabaritos do concurso TCU para T\u00e9cnico Federal de Controle Externo? Veja as possibilidades!","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tcu-2025-recursos-tecnico\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tcu-2025-recursos-tecnico\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tcu-2025-recursos-tecnico\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/11\/08141609\/tcu.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/11\/08141609\/tcu.jpg","width":1024,"height":536,"caption":"TCU explica sobre contrata\u00e7\u00e3o de terceirizados"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tcu-2025-recursos-tecnico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Concurso TCU 2025: recursos para T\u00e9cnico de Controle"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/6630f91134abc08115cca62ce6372855","name":"Bruna de Andrade Fran\u00e7a","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/d6316d36d50cea0fadae28ed3015b8870cc90a2d3d8a95c37b44006af36a00e3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d6316d36d50cea0fadae28ed3015b8870cc90a2d3d8a95c37b44006af36a00e3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d6316d36d50cea0fadae28ed3015b8870cc90a2d3d8a95c37b44006af36a00e3?s=96&d=mm&r=g","caption":"Bruna de Andrade Fran\u00e7a"},"description":"Bruna de Andrade Fran\u00e7a \u00e9 publicit\u00e1ria com p\u00f3s-gradua\u00e7\u00e3o em Marketing &amp; Growth, atuando h\u00e1 mais de 6 anos no universo dos concursos p\u00fablicos. Desde 2021, lidera no Blog do Estrat\u00e9gia Concursos a cobertura editorial especializada em Concursos Policiais (PF, PRF, PM, PC, etc.), al\u00e9m das frentes de concursos banc\u00e1rios, de sa\u00fade e da \u00e1rea legislativa. Especialista em reda\u00e7\u00e3o, com pr\u00e1ticas de SEO e Copywriting, possui tamb\u00e9m atua\u00e7\u00e3o pr\u00e1tica de contato direto com \u00f3rg\u00e3os p\u00fablicos respons\u00e1veis por editais, permitindo acesso antecipado a informa\u00e7\u00f5es, desdobramentos importantes e atualiza\u00e7\u00e3o eficiente dos concursos p\u00fablicos.","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/bruna-andrade\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1618401","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/1206"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1618401"}],"version-history":[{"count":6,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1618401\/revisions"}],"predecessor-version":[{"id":1619038,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1618401\/revisions\/1619038"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/903336"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1618401"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1618401"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1618401"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1618401"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}