{"id":1617706,"date":"2025-08-15T11:19:00","date_gmt":"2025-08-15T14:19:00","guid":{"rendered":"https:\/\/blog-estrategia.mystagingwebsite.com\/blog\/?p=1617706"},"modified":"2025-08-15T13:56:03","modified_gmt":"2025-08-15T16:56:03","slug":"ocorrencia-omissao-operacoes-sefaz-se","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/ocorrencia-omissao-operacoes-sefaz-se\/","title":{"rendered":"Ind\u00edcio de ocorr\u00eancia de omiss\u00e3o de opera\u00e7\u00f5es para o concurso SEFAZ SE"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Oi, coruja!! Este&nbsp;artigo do Estrat\u00e9gia Concursos analisa um assunto muito importante para a prova de Auditor Fiscal de Sergipe: <strong>presun\u00e7\u00e3o ou ind\u00edcio de ocorr\u00eancia de omiss\u00e3o de opera\u00e7\u00f5es para SEFAZ\/SE<\/strong> de acordo com a legisla\u00e7\u00e3o nacional e estadual.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"901\" height=\"507\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/08\/04151712\/image-15.png\" alt=\"Presun\u00e7\u00e3o de ocorr\u00eancia de omiss\u00e3o de opera\u00e7\u00f5es para SEFAZ\/SE\" class=\"wp-image-1617708\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/08\/04151712\/image-15.png 901w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/08\/04151712\/image-15-300x169.png 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/08\/04151712\/image-15-768x432.png 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/08\/04151712\/image-15-150x84.png 150w\" sizes=\"auto, (max-width: 901px) 100vw, 901px\" \/><figcaption class=\"wp-element-caption\">Presun\u00e7\u00e3o de ocorr\u00eancia de omiss\u00e3o de opera\u00e7\u00f5es para SEFAZ\/SE<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Com direcionalidade, iremos passar pelos seguintes t\u00f3picos:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Conhecer disposi\u00e7\u00f5es normativas sobre presun\u00e7\u00e3o de ocorr\u00eancia de omiss\u00e3o de opera\u00e7\u00f5es para SEFAZ\/SE;&nbsp;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Entender observa\u00e7\u00f5es relevantes sobre o tema;&nbsp;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Encerrar com considera\u00e7\u00f5es finais.&nbsp;<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Tendo isso em vista, e usando como refer\u00eancia a <a href=\"https:\/\/aleselegis.al.se.leg.br\/Arquivo\/Documents\/legislacao\/html\/l37961996.html\" target=\"_blank\" rel=\"noreferrer noopener\">Lei estadual n\u00ba 3.796\/1996, que trata do ICMS no Estado<\/a>, vamos agora estudar um pouco mais sobre presun\u00e7\u00e3o de ocorr\u00eancia de omiss\u00e3o de opera\u00e7\u00f5es para SEFAZ\/SE.&nbsp;<\/p>\n\n\n\n<div class=\"container\" id=\"boxes\">\n  <div class=\"row\">\n\n    <div class=\"col-sm\">\n      <div class=\"banner-sefaz-ec\" id=\"box-assinatura\">\n        <h2 class=\"titulo-assinatura\">Curso Concurso Sefaz SE<\/h2>\n        <p class=\"subtitulo-assinatura\">Conhe\u00e7a os cursos para Sefaz SE<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/cursosPorConcurso\/secretaria-da-fazenda-de-sergipe-sefaz-se\/\" role=\"button\" rel=\"noopener noreferrer\">VER CURSOS<\/a>\n        <\/div>\n      <\/div>\n     \n    <\/div>\n\n  <\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-presuncao-de-ocorrencia-de-omissao-de-operacoes-para-sefaz-se\">Presun\u00e7\u00e3o de ocorr\u00eancia de omiss\u00e3o de opera\u00e7\u00f5es para SEFAZ SE\u00a0<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">No Estado Democr\u00e1tico de Direito, os tributos possuem papel essencial na manuten\u00e7\u00e3o e equil\u00edbrio da sociedade, tendo, <strong>al\u00e9m da arrecada\u00e7\u00e3o, ainda um car\u00e1ter social.<\/strong>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Isso porque \u00e9 atrav\u00e9s deles que os recursos s\u00e3o inseridos nos cofres p\u00fablicos. Todos n\u00f3s devemos pagar tributos para assim o poder p\u00fablico angariar<strong> recursos suficientes<\/strong> para manter a m\u00e1quina p\u00fablica em pleno funcionamento, pagando sal\u00e1rios de policiais, professores, legisladores, entre outros servidores, investindo em infraestrutura e melhorias dos servi\u00e7os prestados, dando assist\u00eancia a grupos vulner\u00e1veis e hipossuficientes etc.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Assim, de maneira coletiva, ajudamos a suprir as necessidades da sociedade do ponto de vista do financiamento da coisa p\u00fablica. Por isso, \u00e9 essencial conhecermos as nossas <strong>obriga\u00e7\u00f5es tribut\u00e1rias, <\/strong>especialmente quais os fatos que fazem surgir essas eventuais obriga\u00e7\u00f5es.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quando isso ocorre, nos tornamos o que chamamos de sujeito passivo, quer dizer, aquele sujeito que apenas tem a fun\u00e7\u00e3o de realizar o pagamento. Do outro lado est\u00e1 o sujeito ativo, que \u00e9 o Estado, e que tem a prerrogativa de fazer a cobran\u00e7a ativamente daquele valor que tem a receber.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Do ponto de vista de ICMS, temos que cada legisla\u00e7\u00e3o estadual deve conter os fatos geradores deste tributo. Al\u00e9m disso, \u00e9 importante que os <strong>contribuintes <\/strong>desta taxa\u00e7\u00e3o estejam atentos aos prazos e as formas de pagamento, que tamb\u00e9m figuram em norma legal.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por\u00e9m, cabe aos <mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-green-cyan-color\"><strong>Auditores Fiscais<\/strong>, <\/mark>atuar de modo a identificar poss\u00edvel presun\u00e7\u00e3o de ocorr\u00eancia de omiss\u00e3o de opera\u00e7\u00f5es para SEFAZ\/SE e para todos os demais fiscos do pa\u00eds.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para explicar melhor, basicamente, o ICMS incide sobre opera\u00e7\u00f5es que envolva algum ou alguns empreendimentos comerciais. Entretanto, para buscar pagar menos tributos, certas empresas podem agir de maneira indevida, omitindo opera\u00e7\u00f5es, burlando regras financeiras, cont\u00e1beis ou de mercado, criando movimenta\u00e7\u00f5es fict\u00edcias, entra tantas outras possibilidades, muitas vezes bastante criativas, com o objetivo de <strong>omitir <\/strong>valores que seriam taxados pelo ICMS ou por algum outro tributo.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por isso a fun\u00e7\u00e3o de Auditor Fiscal \u00e9 t\u00e3o relevante, pois garante que os maus pagadores, aqueles que prejudicam toda a l\u00f3gica de sustentabilidade tribut\u00e1ria, possam ser fiscalizados e devidamente combatidos.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sendo assim, vamos acompanhar o que imp\u00f5e a lei 3.796\/1996 sobre presun\u00e7\u00e3o de ocorr\u00eancia de omiss\u00e3o de opera\u00e7\u00f5es para SEFAZ\/SE:&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Art. 8\u00ba \u00a7 4\u00ba&nbsp;H\u00e1 a caracteriza\u00e7\u00e3o da presun\u00e7\u00e3o da ocorr\u00eancia de omiss\u00e3o de opera\u00e7\u00f5es para SEFAZ\/SE e de presta\u00e7\u00f5es de servi\u00e7os tribut\u00e1veis, realizadas sem o pagamento do imposto,<strong> <mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-luminous-vivid-amber-color\">ressalvada<\/mark><\/strong> ao contribuinte a prova da improced\u00eancia da presun\u00e7\u00e3o, nas seguintes hip\u00f3teses:&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">I &#8211; exist\u00eancia de <strong>saldo credor de caixa;<\/strong>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">II &#8211; constata\u00e7\u00e3o de suprimentos a caixa <strong>n\u00e3o comprovados;&nbsp;<\/strong>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">III &#8211; manuten\u00e7\u00e3o, <strong>no passivo,<\/strong> de obriga\u00e7\u00f5es j\u00e1 pagas ou inexistentes;&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">IV &#8211; constata\u00e7\u00e3o de <strong>ativos ocultos<\/strong>, nos termos definidos pelo Poder Executivo;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">V&nbsp;&#8211; ocorr\u00eancia de entrada de mercadorias <strong>n\u00e3o contabilizadas e n\u00e3o escrituradas<\/strong> em livros fiscais pr\u00f3prios, na forma da legisla\u00e7\u00e3o pertinente;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">VI &#8211; declara\u00e7\u00e3o de vendas informada pelo contribuinte em valores <strong>inferiores<\/strong> \u00e0s informa\u00e7\u00f5es fornecidas por institui\u00e7\u00f5es financeiras e de pagamento, integrantes ou n\u00e3o do Sistema de Pagamentos Brasileiro &#8211; SPB, relativas \u00e0s transa\u00e7\u00f5es com cart\u00f5es de d\u00e9bito, cr\u00e9dito, de loja (private&nbsp;label) e demais instrumentos de pagamento eletr\u00f4nico;&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">VII &#8211; <strong>falta de escritura\u00e7\u00e3o<\/strong> de pagamentos efetuados;&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">VIII &#8211; exist\u00eancia de valores creditados em conta de dep\u00f3sito ou de investimento mantida junto a institui\u00e7\u00e3o financeira, em rela\u00e7\u00e3o aos quais o titular, regularmente notificado a prestar informa\u00e7\u00f5es, <strong>n\u00e3o comprove,<\/strong> mediante documenta\u00e7\u00e3o id\u00f4nea, a origem dos recursos utilizados nessas opera\u00e7\u00f5es;&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">IX &#8211; os valores vinculados a equipamento de cart\u00e3o de cr\u00e9dito ou d\u00e9bito de <strong>outra<\/strong> pessoa jur\u00eddica ou f\u00edsica.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m disso, continuando nosso estudo sobre presun\u00e7\u00e3o de ocorr\u00eancia de omiss\u00e3o de opera\u00e7\u00f5es para SEFAZ\/SE, saiba ainda que a presun\u00e7\u00e3o de que esse par\u00e1grafo da lei que acabamos de estudar aplica-se, <strong>igualmente<\/strong>, a qualquer situa\u00e7\u00e3o em que a soma das despesas, pagamentos de t\u00edtulos, sal\u00e1rios, retiradas, prolabore, servi\u00e7os de terceiros, aquisi\u00e7\u00e3o de bens em geral e outros gastos do contribuinte seja superior \u00e0 receita do estabelecimento.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">E para terminar, entenda tamb\u00e9m que<mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\"> <strong>em caso de existir diferen\u00e7a<\/strong><\/mark><strong> <\/strong>de base de c\u00e1lculo apurada por meio de levantamento financeiro ou por confronto das informa\u00e7\u00f5es do contribuinte com as prestadas pelas institui\u00e7\u00f5es financeiras e de pagamento, integrantes ou n\u00e3o do Sistema de Pagamentos Brasileiro &#8211; SPB, relativas \u00e0s transa\u00e7\u00f5es com cart\u00f5es de d\u00e9bito, cr\u00e9dito, de loja (private&nbsp;label) e demais instrumentos de pagamento eletr\u00f4nico, <strong>essa diferen\u00e7a \u00e9 considerada decorrente de opera\u00e7\u00e3o ou presta\u00e7\u00e3o tributada,<\/strong> devendo, dessa forma, ser taxada normalmente.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Passamos, portanto, pelo tema presun\u00e7\u00e3o de ocorr\u00eancia de omiss\u00e3o de opera\u00e7\u00f5es para SEFAZ\/SE, assunto fundamental para o concurso de auditor fiscal deste Estado.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-consideracoes-finais\">Considera\u00e7\u00f5es Finais\u00a0<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Chegamos ao final do nosso breve artigo sobre presun\u00e7\u00e3o de ocorr\u00eancia de omiss\u00e3o de opera\u00e7\u00f5es para SEFAZ\/SE, e esperamos que seja muito \u00fatil para a sua prepara\u00e7\u00e3o e aprova\u00e7\u00e3o.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Lembre-se que \u00e9 essencial a <\/em><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\" target=\"_blank\" rel=\"noreferrer noopener\"><em>leitura dos PDF\u2019s e a revis\u00e3o frequente dos conte\u00fados, para que assim os seus estudos fiquem cada vez mais avan\u00e7ados.<\/em><\/a><em>&nbsp;<\/em>&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Um grande abra\u00e7o e at\u00e9 mais!&nbsp;<\/p>\n\n\n\n<p class=\"has-text-align-center has-very-light-gray-to-cyan-bluish-gray-gradient-background has-background has-medium-font-size wp-block-paragraph\"><strong>Saiba mais: <a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-sefaz-se\/\" target=\"_blank\" rel=\"noreferrer noopener\">concurso Sefaz SE<\/a><\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><strong>Quer saber quais ser\u00e3o os pr\u00f3ximos concursos?<\/strong>&nbsp;<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><strong>Confira nossos artigos!<\/strong>&nbsp;<\/p>\n\n\n\n<p class=\"has-text-align-center has-very-light-gray-to-cyan-bluish-gray-gradient-background has-background wp-block-paragraph\"><strong><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos abertos<\/a>\u00a0<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center has-very-light-gray-to-cyan-bluish-gray-gradient-background has-background wp-block-paragraph\"><strong><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2025\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos 2025<\/a>\u00a0<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center has-very-light-gray-to-cyan-bluish-gray-gradient-background has-background wp-block-paragraph\"><strong><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2026\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos 2026<\/a>\u00a0<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"cursos\"><em>Cursos&nbsp;para&nbsp;o&nbsp;concurso SEFAZ SE<\/em><\/h2>\n\n\n\n<div class=\"container\" id=\"boxes\">\n  <div class=\"row\">\n\n    <div class=\"col-sm\">\n      <div class=\"banner-sefaz-ec\" id=\"box-assinatura\">\n        <h3 class=\"titulo-assinatura\">Curso Concurso Sefaz SE<\/h3>\n        <p class=\"subtitulo-assinatura\">Conhe\u00e7a os cursos para Sefaz SE<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/cursosPorConcurso\/secretaria-da-fazenda-de-sergipe-sefaz-se\/\" role=\"button\" rel=\"noopener noreferrer\">INICIAR PREPARA\u00c7\u00c3O<\/a>\n        <\/div>\n      <\/div>\n     \n    <\/div>\n\n  <\/div>\n<\/div>\n\n\n\n<div class=\"container\" id=\"boxes\">\n  <div class=\"row\">\n\n    <div class=\"col-sm\">\n      <div class=\"estrategia\" id=\"box-assinatura\">\n        <h3 class=\"titulo-assinatura\">Assinatura Concursos<\/h3>\n        <p class=\"subtitulo-assinatura\">Assinatura de 1 ano ou 2 anos<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/assinaturas\/\" role=\"button\" rel=\"noopener noreferrer\">ASSINE AGORA<\/a>\n        <\/div>\n      <\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Oi, coruja!! Este&nbsp;artigo do Estrat\u00e9gia Concursos analisa um assunto muito importante para a prova de Auditor Fiscal de Sergipe: presun\u00e7\u00e3o ou ind\u00edcio de ocorr\u00eancia de omiss\u00e3o de opera\u00e7\u00f5es para SEFAZ\/SE de acordo com a legisla\u00e7\u00e3o nacional e estadual.&nbsp; Com direcionalidade, iremos passar pelos seguintes t\u00f3picos:&nbsp; Tendo isso em vista, e usando como refer\u00eancia a Lei [&hellip;]<\/p>\n","protected":false},"author":2887,"featured_media":1617708,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"post_tipo":"article","footnotes":""},"categories":[1,1983],"tags":[],"tax_estado":[219963,219988],"class_list":["post-1617706","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cursos-e-concursos","category-fiscal-estadual","tax_estado-concursos-federais","tax_estado-se"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ind\u00edcio de ocorr\u00eancia de omiss\u00e3o de opera\u00e7\u00f5es para o concurso SEFAZ SE<\/title>\n<meta name=\"description\" content=\"Hoje veremos um tema \u00fatil para a prova de Auditor Fiscal de Sergipe: presun\u00e7\u00e3o ou ind\u00edcio de ocorr\u00eancia de omiss\u00e3o de opera\u00e7\u00f5es para SEFAZ\/SE\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/ocorrencia-omissao-operacoes-sefaz-se\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ind\u00edcio de ocorr\u00eancia de omiss\u00e3o de opera\u00e7\u00f5es para o concurso SEFAZ SE\" \/>\n<meta property=\"og:description\" content=\"Hoje veremos um tema \u00fatil para a prova de Auditor Fiscal de Sergipe: presun\u00e7\u00e3o ou ind\u00edcio de ocorr\u00eancia de omiss\u00e3o de opera\u00e7\u00f5es para SEFAZ\/SE\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/ocorrencia-omissao-operacoes-sefaz-se\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-15T14:19:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-15T16:56:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/08\/04151712\/image-15.png\" \/>\n\t<meta property=\"og:image:width\" content=\"901\" \/>\n\t<meta property=\"og:image:height\" content=\"507\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"F\u00e1bio Prado dos Santos Santana\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"F\u00e1bio Prado dos Santos Santana\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/ocorrencia-omissao-operacoes-sefaz-se\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/ocorrencia-omissao-operacoes-sefaz-se\\\/\"},\"author\":{\"name\":\"F\u00e1bio Prado dos Santos Santana\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/b1af3515254fed0a6861d754def3f005\"},\"headline\":\"Ind\u00edcio de ocorr\u00eancia de omiss\u00e3o de opera\u00e7\u00f5es para o concurso SEFAZ SE\",\"datePublished\":\"2025-08-15T14:19:00+00:00\",\"dateModified\":\"2025-08-15T16:56:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/ocorrencia-omissao-operacoes-sefaz-se\\\/\"},\"wordCount\":1223,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/ocorrencia-omissao-operacoes-sefaz-se\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2025\\\/08\\\/04151712\\\/image-15.png\",\"articleSection\":[\"Concursos P\u00fablicos\",\"Fiscal - Estadual (ICMS)\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/ocorrencia-omissao-operacoes-sefaz-se\\\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/ocorrencia-omissao-operacoes-sefaz-se\\\/\",\"url\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/ocorrencia-omissao-operacoes-sefaz-se\\\/\",\"name\":\"Ind\u00edcio de ocorr\u00eancia de omiss\u00e3o de opera\u00e7\u00f5es para o concurso SEFAZ SE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/ocorrencia-omissao-operacoes-sefaz-se\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/ocorrencia-omissao-operacoes-sefaz-se\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2025\\\/08\\\/04151712\\\/image-15.png\",\"datePublished\":\"2025-08-15T14:19:00+00:00\",\"dateModified\":\"2025-08-15T16:56:03+00:00\",\"description\":\"Hoje veremos um tema \u00fatil para a prova de Auditor Fiscal de Sergipe: presun\u00e7\u00e3o ou ind\u00edcio de ocorr\u00eancia de omiss\u00e3o de opera\u00e7\u00f5es para SEFAZ\\\/SE\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/ocorrencia-omissao-operacoes-sefaz-se\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/ocorrencia-omissao-operacoes-sefaz-se\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/ocorrencia-omissao-operacoes-sefaz-se\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2025\\\/08\\\/04151712\\\/image-15.png\",\"contentUrl\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2025\\\/08\\\/04151712\\\/image-15.png\",\"width\":901,\"height\":507,\"caption\":\"Concurso Sefaz SE taxa de inscri\u00e7\u00e3o\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/ocorrencia-omissao-operacoes-sefaz-se\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ind\u00edcio de ocorr\u00eancia de omiss\u00e3o de opera\u00e7\u00f5es para o concurso SEFAZ SE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2025\\\/06\\\/03203428\\\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2025\\\/06\\\/03203428\\\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/b1af3515254fed0a6861d754def3f005\",\"name\":\"F\u00e1bio Prado dos Santos Santana\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0e3399436850f804c1d7731313952ccf303887c14b1711595235048e3ec0299b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0e3399436850f804c1d7731313952ccf303887c14b1711595235048e3ec0299b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0e3399436850f804c1d7731313952ccf303887c14b1711595235048e3ec0299b?s=96&d=mm&r=g\",\"caption\":\"F\u00e1bio Prado dos Santos Santana\"},\"description\":\"Principais Aprova\u00e7\u00f5es em Concursos: Auditor Fiscal Tribut\u00e1rio Municipal - ISS S\u00e3o Paulo (2024); Auditor Fiscal - Receita Federal do Brasil (2023); Professor Efetivo - Universidade Federal de Sergipe (2014).\",\"url\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/author\\\/fabioprado-ufsgmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ind\u00edcio de ocorr\u00eancia de omiss\u00e3o de opera\u00e7\u00f5es para o concurso SEFAZ SE","description":"Hoje veremos um tema \u00fatil para a prova de Auditor Fiscal de Sergipe: presun\u00e7\u00e3o ou ind\u00edcio de ocorr\u00eancia de omiss\u00e3o de opera\u00e7\u00f5es para SEFAZ\/SE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/ocorrencia-omissao-operacoes-sefaz-se\/","og_locale":"pt_BR","og_type":"article","og_title":"Ind\u00edcio de ocorr\u00eancia de omiss\u00e3o de opera\u00e7\u00f5es para o concurso SEFAZ SE","og_description":"Hoje veremos um tema \u00fatil para a prova de Auditor Fiscal de Sergipe: presun\u00e7\u00e3o ou ind\u00edcio de ocorr\u00eancia de omiss\u00e3o de opera\u00e7\u00f5es para SEFAZ\/SE","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/ocorrencia-omissao-operacoes-sefaz-se\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2025-08-15T14:19:00+00:00","article_modified_time":"2025-08-15T16:56:03+00:00","og_image":[{"width":901,"height":507,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/08\/04151712\/image-15.png","type":"image\/png"}],"author":"F\u00e1bio Prado dos Santos Santana","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"F\u00e1bio Prado dos Santos Santana","Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/ocorrencia-omissao-operacoes-sefaz-se\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/ocorrencia-omissao-operacoes-sefaz-se\/"},"author":{"name":"F\u00e1bio Prado dos Santos Santana","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/b1af3515254fed0a6861d754def3f005"},"headline":"Ind\u00edcio de ocorr\u00eancia de omiss\u00e3o de opera\u00e7\u00f5es para o concurso SEFAZ SE","datePublished":"2025-08-15T14:19:00+00:00","dateModified":"2025-08-15T16:56:03+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/ocorrencia-omissao-operacoes-sefaz-se\/"},"wordCount":1223,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/ocorrencia-omissao-operacoes-sefaz-se\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/08\/04151712\/image-15.png","articleSection":["Concursos P\u00fablicos","Fiscal - Estadual (ICMS)"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/ocorrencia-omissao-operacoes-sefaz-se\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/ocorrencia-omissao-operacoes-sefaz-se\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/ocorrencia-omissao-operacoes-sefaz-se\/","name":"Ind\u00edcio de ocorr\u00eancia de omiss\u00e3o de opera\u00e7\u00f5es para o concurso SEFAZ SE","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/ocorrencia-omissao-operacoes-sefaz-se\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/ocorrencia-omissao-operacoes-sefaz-se\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/08\/04151712\/image-15.png","datePublished":"2025-08-15T14:19:00+00:00","dateModified":"2025-08-15T16:56:03+00:00","description":"Hoje veremos um tema \u00fatil para a prova de Auditor Fiscal de Sergipe: presun\u00e7\u00e3o ou ind\u00edcio de ocorr\u00eancia de omiss\u00e3o de opera\u00e7\u00f5es para SEFAZ\/SE","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/ocorrencia-omissao-operacoes-sefaz-se\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/ocorrencia-omissao-operacoes-sefaz-se\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/ocorrencia-omissao-operacoes-sefaz-se\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/08\/04151712\/image-15.png","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/08\/04151712\/image-15.png","width":901,"height":507,"caption":"Concurso Sefaz SE taxa de inscri\u00e7\u00e3o"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/ocorrencia-omissao-operacoes-sefaz-se\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Ind\u00edcio de ocorr\u00eancia de omiss\u00e3o de opera\u00e7\u00f5es para o concurso SEFAZ SE"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/b1af3515254fed0a6861d754def3f005","name":"F\u00e1bio Prado dos Santos Santana","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/0e3399436850f804c1d7731313952ccf303887c14b1711595235048e3ec0299b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0e3399436850f804c1d7731313952ccf303887c14b1711595235048e3ec0299b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0e3399436850f804c1d7731313952ccf303887c14b1711595235048e3ec0299b?s=96&d=mm&r=g","caption":"F\u00e1bio Prado dos Santos Santana"},"description":"Principais Aprova\u00e7\u00f5es em Concursos: Auditor Fiscal Tribut\u00e1rio Municipal - ISS S\u00e3o Paulo (2024); Auditor Fiscal - Receita Federal do Brasil (2023); Professor Efetivo - Universidade Federal de Sergipe (2014).","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/fabioprado-ufsgmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1617706","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/2887"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1617706"}],"version-history":[{"count":0,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1617706\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/1617708"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1617706"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1617706"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1617706"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1617706"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}