{"id":1611182,"date":"2025-08-11T11:29:00","date_gmt":"2025-08-11T14:29:00","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=1611182"},"modified":"2025-08-12T09:56:01","modified_gmt":"2025-08-12T12:56:01","slug":"artigo-1-lia-cnu","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/artigo-1-lia-cnu\/","title":{"rendered":"Artigo 1\u00ba da LIA para o CNU"},"content":{"rendered":"\n<p>Ol\u00e1, tudo bem? Hoje faremos um resumo sobre o Artigo 1\u00ba da Lei de Improbidade (Lei 8.429\/1992 &#8211; LIA), visando ao CNU (Concurso Nacional Unificado).<\/p>\n\n\n\n<p>O edital do CNU (o \u201cENEM dos concursos\u201d) foi lan\u00e7ado e destrinchado em<a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-blocos-tematicos\/\" target=\"_blank\" rel=\"noreferrer noopener\"> 09 blocos tem\u00e1ticos do CNU<\/a> 2025, conforme as suas respectivas \u201c\u00e1reas de conhecimento\u201d.<\/p>\n\n\n\n<p>Foram disponibilizadas <strong>3.652 vagas<\/strong> para este pr\u00f3ximo certame, sendo 2.480 imediatas e 1.172 para forma\u00e7\u00e3o de cadastro reserva, com sal\u00e1rios variando de R$4.804,89 a R$16.413,35.<\/p>\n\n\n\n<p>Portanto, vamos ao que interessa!<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/07\/22105904\/artigo-1o-da-lei-de-improbidade-para-o-cnu-1024x1024.png\" alt=\"Artigo 1\u00ba da Lei de Improbidade para o CNU\" class=\"wp-image-1611187\" style=\"width:656px;height:auto\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/07\/22105904\/artigo-1o-da-lei-de-improbidade-para-o-cnu-1024x1024.png 1024w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/07\/22105904\/artigo-1o-da-lei-de-improbidade-para-o-cnu-300x300.png 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/07\/22105904\/artigo-1o-da-lei-de-improbidade-para-o-cnu-150x150.png 150w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/07\/22105904\/artigo-1o-da-lei-de-improbidade-para-o-cnu-768x768.png 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/07\/22105904\/artigo-1o-da-lei-de-improbidade-para-o-cnu-96x96.png 96w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/07\/22105904\/artigo-1o-da-lei-de-improbidade-para-o-cnu.png 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Artigo 1\u00ba da LIA para o CNU<\/figcaption><\/figure>\n\n\n\n<div class=\"wp-block-yoast-seo-table-of-contents yoast-table-of-contents\"><ul><li><a href=\"#h-artigo-1\u00ba-da-lia-para-o-cnu\" data-level=\"2\">Artigo 1\u00ba da LIA para o CNU<\/a><ul><li><a href=\"#h-caput-do-art-1\u00ba-da-lia-e-5\u00ba\" data-level=\"3\">Caput do art. 1\u00ba da LIA e \u00a7 5\u00ba<\/a><\/li><li><a href=\"#h-1\u00ba-2\u00ba-e-3\u00ba-do-artigo-1\u00ba-da-lia\" data-level=\"3\">\u00a7\u00a7 1\u00ba, 2\u00ba e 3\u00ba do artigo 1\u00ba da LIA<\/a><\/li><li><a href=\"#h-4\u00ba-do-artigo-1\u00ba-da-lia\" data-level=\"3\">\u00a7 4\u00ba do artigo 1\u00ba da LIA<\/a><\/li><li><a href=\"#h-6\u00ba-e-7\u00ba-do-artigo-1\u00ba-da-lia\" data-level=\"3\">\u00a7\u00a7 6\u00ba e 7\u00ba do artigo 1\u00ba da LIA<\/a><\/li><li><a href=\"#h-8\u00ba-do-artigo-1\u00ba-da-lia\" data-level=\"3\">\u00a7 8\u00ba do artigo 1\u00ba da LIA<\/a><\/li><\/ul><\/li><li><a href=\"#h-consideracoes-finais\" data-level=\"2\">Considera\u00e7\u00f5es finais<\/a><\/li><li><a href=\"#h-quer-saber-tudo-sobre-concursos-previstos-confira-nossos-artigos\" data-level=\"2\">Quer saber tudo sobre concursos previstos? Confira nossos artigos!<\/a><\/li><\/ul><\/div>\n\n\n\n<div class=\"container\" id=\"boxes\">\n  <div class=\"row\">\n\n    <div class=\"col-sm\">\n      <div class=\"banner-federais\" id=\"box-assinatura\">\n        <h2 class=\"titulo-assinatura\" style=\"text-align: left;\">Cursos para o CNU 2025<\/h2>\n        <p class=\"subtitulo-assinatura\" style=\"text-align: left;\">Prepare-se para o &#8220;ENEM dos Concursos&#8221;!<\/p>\n        <div class=\"box-botao\" style=\"text-align: left;\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/cursosPorConcurso\/concurso-nacional-unificado-cnu\/\" role=\"button\" rel=\"noopener noreferrer\">INICIAR PREPARA\u00c7\u00c3O<\/a>\n        <\/div>\n      <\/div><\/div><\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading has-vivid-cyan-blue-color has-text-color has-link-color wp-elements-4735b23609c20a1a838c09e85adcbb6d\" id=\"h-artigo-1\u00ba-da-lia-para-o-cnu\">Artigo 1\u00ba da LIA para o CNU<\/h2>\n\n\n\n<h3 class=\"wp-block-heading has-vivid-cyan-blue-color has-text-color has-link-color wp-elements-dfeeaae511a1a40caec49ecb4930baf2\" id=\"h-caput-do-art-1\u00ba-da-lia-e-5\u00ba\"><em>Caput<\/em> do art. 1\u00ba da LIA e \u00a7 5\u00ba<\/h3>\n\n\n\n<p>O <a href=\"https:\/\/www.planalto.gov.br\/ccivil_03\/constituicao\/constituicaocompilado.htm#:~:text=%C2%A7%204%C2%BA%20%2D%20Os%20atos%20de%20improbidade%20administrativa%20importar%C3%A3o%20a%20suspens%C3%A3o%20dos%20direitos%20pol%C3%ADticos%2C%20a%20perda%20da%20fun%C3%A7%C3%A3o%20p%C3%BAblica%2C%20a%20indisponibilidade%20dos%20bens%20e%20o%20ressarcimento%20ao%20er%C3%A1rio%2C%20na%20forma%20e%20grada%C3%A7%C3%A3o%20previstas%20em%20lei%2C%20sem%20preju%C3%ADzo%20da%20a%C3%A7%C3%A3o%20penal%20cab%C3%ADvel.\" target=\"_blank\" rel=\"noreferrer noopener\">artigo 37, \u00a7 4\u00ba, da Constitui\u00e7\u00e3o Federal (CF)<\/a> disp\u00f5e que os atos de improbidade administrativa importar\u00e3o a suspens\u00e3o dos direitos pol\u00edticos, a perda da fun\u00e7\u00e3o p\u00fablica, a indisponibilidade dos bens e o ressarcimento ao er\u00e1rio, na forma e grada\u00e7\u00e3o previstas em lei, <strong>sem preju\u00edzo da a\u00e7\u00e3o penal cab\u00edvel.<\/strong><\/p>\n\n\n\n<p>A fim de regular esse importante dispositivo constitucional, a Lei 8.429\/92 foi aprovada, tendo passado, recentemente, por significativas mudan\u00e7as a partir da Lei 14.230\/2021.<\/p>\n\n\n\n<p>Atualmente, o <em>caput <\/em>do artigo 1\u00ba da LIA disp\u00f5e que o sistema de responsabiliza\u00e7\u00e3o por atos de improbidade administrativa <strong>tutelar\u00e1 a probidade na organiza\u00e7\u00e3o do Estado e no exerc\u00edcio de suas fun\u00e7\u00f5es<\/strong>, como <strong>forma de assegurar a integridade do patrim\u00f4nio p\u00fablico e social<\/strong>, nos termos desta Lei.<\/p>\n\n\n\n<p>Portanto, podemos afirmar que<strong> esse \u00e9 o objeto jur\u00eddico tutelado <\/strong>pela LIA e que os atos de improbidade, quando praticados, acabam por violar aqueles valores (probidade na organiza\u00e7\u00e3o do Estado <strong>+<\/strong> integridade do patrim\u00f4nio p\u00fablico e social).<\/p>\n\n\n\n<p>Tanto \u00e9 assim que o \u00a7 5\u00ba do art. 1\u00ba da LIA disp\u00f5e que os atos de improbidade <strong>violam a probidade na organiza\u00e7\u00e3o do Estado e no exerc\u00edcio de suas fun\u00e7\u00f5es e a integridade do patrim\u00f4nio p\u00fablico e social <\/strong>dos Poderes Executivo, Legislativo e Judici\u00e1rio, bem como da administra\u00e7\u00e3o direta e indireta, no \u00e2mbito da Uni\u00e3o, dos Estados, dos Munic\u00edpios e do Distrito Federal.&nbsp;<\/p>\n\n\n\n<p>Desse modo, o <strong>sujeito ativo<\/strong> do ato de improbidade \u00e9 aquele que praticar tal conduta contra esses sujeitos passivos acima, bem como contra o objeto jur\u00eddico acima tutelado.<\/p>\n\n\n\n<p>Ainda \u00e9 importante sabermos que <strong>a responsabiliza\u00e7\u00e3o por atos de improbidade possui natureza C\u00cdVEL<\/strong>, de modo que o agente pode ser punido, ainda, nas esferas penal e administrativa.<\/p>\n\n\n\n<h3 class=\"wp-block-heading has-vivid-cyan-blue-color has-text-color has-link-color wp-elements-bf0b8b70ca08c3d31d98f3ed24bfb13d\" id=\"h-1\u00ba-2\u00ba-e-3\u00ba-do-artigo-1\u00ba-da-lia\">\u00a7\u00a7 1\u00ba, 2\u00ba e 3\u00ba do artigo 1\u00ba da LIA<\/h3>\n\n\n\n<p>O \u00a7 1\u00ba do artigo 1\u00ba disp\u00f5e que, ressalvados tipos previstos em leis especiais, s\u00e3o considerados atos de improbidade administrativa as <strong>condutas DOLOSAS<\/strong> tipificadas nos arts. 9\u00ba, 10 e 11 da LIA:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Art. 9\u00ba da LIA: <\/strong>atos de improbidade que importam enriquecimento il\u00edcito;<\/li>\n\n\n\n<li><strong>Art. 10 da LIA: <\/strong>atos de improbidade que causam preju\u00edzo ao Er\u00e1rio;<\/li>\n\n\n\n<li><strong>Art. 11 da LIA: <\/strong>atos de improbidade que atentam contra os princ\u00edpios da Administra\u00e7\u00e3o P\u00fablica.<\/li>\n<\/ul>\n\n\n\n<p>Com a mudan\u00e7a provocada pela Lei 14.230\/2021, <strong>n\u00e3o h\u00e1 mais possibilidade de condutas culposas <\/strong>configurarem ato de improbidade.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter\"><img decoding=\"async\" src=\"https:\/\/lh7-rt.googleusercontent.com\/docsz\/AD_4nXfprMrRvt8h_f_7eZ8Z3X9DCFXKNze1T4tC048aIr5Q0KF_vs0GeDwX54IJ7h_C-IyDGL4gMxF8zfQiOx0M5_wl353hoaqEvzc0zjWIWIsJenmY19-qO_OCydSNThRhdtazTjMGLg?key=1lXFN3LFzfLgxFh2bJi7Cg\" alt=\"\"\/><\/figure>\n\n\n\n<p>Nesse sentido, o Supremo Tribunal Federal (STF) entende que apenas com a comprova\u00e7\u00e3o de responsabilidade subjetiva (presen\u00e7a do elemento subjetivo DOLO) \u00e9 que se pode imputar a algu\u00e9m um ato de improbidade administrativa.<\/p>\n\n\n\n<p>Al\u00e9m disso, o STF prev\u00ea que a norma ben\u00e9fica da Lei 14.230\/2021 retroage para alcan\u00e7ar os atos ocorridos antes de sua entrada em vigor, desde que n\u00e3o se trate de processo com condena\u00e7\u00e3o transitada em julgado (<a href=\"https:\/\/portal.stf.jus.br\/jurisprudenciaRepercussao\/verAndamentoProcesso.asp?incidente=4652910&amp;numeroProcesso=843989&amp;classeProcesso=ARE&amp;numeroTema=1199\" target=\"_blank\" rel=\"noreferrer noopener\">Tema de Repercuss\u00e3o Geral n\u00ba 1.199<\/a>).<\/p>\n\n\n\n<p>Por sua vez, o \u00a7 2\u00ba do art. 1\u00ba da LIA disp\u00f5e que <strong>se considera dolo a vontade livre e consciente de alcan\u00e7ar o resultado il\u00edcito<\/strong> tipificado nos arts. 9\u00ba, 10 e 11 desta Lei, <strong>n\u00e3o bastando a voluntariedade do agente.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter\"><img decoding=\"async\" src=\"https:\/\/lh7-rt.googleusercontent.com\/docsz\/AD_4nXdLUi2yvI4QS1KAl0xX6Zwj0lhhKZ_v6ZXCcshObAqWAYwIE10fMcLAm5i6TmJ2pJ4ItLWTuQkNyDXe61H3Tyb1ifkHQy8nL9Q4FfLW6NUw0N2mjEzpJ2ve68XdQIPvKFothRVh?key=1lXFN3LFzfLgxFh2bJi7Cg\" alt=\"\"\/><\/figure>\n\n\n\n<p>Ou seja, n\u00e3o basta que o agente pratique uma determinada conduta il\u00edcita que, em tese, configure ato de improbidade (<strong><em>exemplo<\/em><\/strong><em>: libera\u00e7\u00e3o de verba p\u00fablica fora das hip\u00f3teses legais<\/em>). \u00c9 necess\u00e1rio que ele tenha a inten\u00e7\u00e3o, isto \u00e9, o dolo espec\u00edfico de fazer isso (<em>sabia que a libera\u00e7\u00e3o da verba era irregular<\/em>).&nbsp;<\/p>\n\n\n\n<p>Veja que a libera\u00e7\u00e3o de verba p\u00fablica \u00e9 um ato volunt\u00e1rio dele (n\u00e3o foi for\u00e7ado a fazer isso). Por\u00e9m, n\u00e3o h\u00e1 inten\u00e7\u00e3o (dolo espec\u00edfico) de liberar a verba sabendo que n\u00e3o o podia fazer.<\/p>\n\n\n\n<p>Na mesma esteira, o \u00a7 3\u00ba do art. 1\u00ba da LIA disp\u00f5e que o mero exerc\u00edcio da fun\u00e7\u00e3o ou desempenho de compet\u00eancias p\u00fablicas,<strong> sem comprova\u00e7\u00e3o de ato doloso com fim il\u00edcito, afasta a responsabilidade<\/strong> por ato de improbidade administrativa.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading has-vivid-cyan-blue-color has-text-color has-link-color wp-elements-911470491c746f542e2df3c705b39802\" id=\"h-4\u00ba-do-artigo-1\u00ba-da-lia\">\u00a7 4\u00ba do artigo 1\u00ba da LIA<\/h3>\n\n\n\n<p>O \u00a7 4\u00ba do artigo 1\u00ba da LIA prev\u00ea que se aplicam ao sistema da improbidade disciplinado nesta Lei os <strong>princ\u00edpios constitucionais do direito administrativo sancionador.<\/strong><\/p>\n\n\n\n<p>Isso significa dizer que dever\u00e3o ser observadas determinadas garantias constitucionais no processo de responsabiliza\u00e7\u00e3o por atos de improbidade, tais como a <strong>ampla defesa, <\/strong>o <strong>contradit\u00f3rio<\/strong>, o <strong>devido processo legal<\/strong>, a <strong>presun\u00e7\u00e3o de inoc\u00eancia<\/strong>, a <strong>intranscend\u00eancia das penas<\/strong>, a <strong>individualiza\u00e7\u00e3o das penas<\/strong>, dentre outros.<\/p>\n\n\n\n<p>Foi isso que possibilitou, por exemplo, que o STF, no julgamento do <a href=\"https:\/\/portal.stf.jus.br\/jurisprudenciaRepercussao\/verAndamentoProcesso.asp?incidente=4652910&amp;numeroProcesso=843989&amp;classeProcesso=ARE&amp;numeroTema=1199\" target=\"_blank\" rel=\"noreferrer noopener\">Tema de Repercuss\u00e3o Geral n\u00ba 1.199<\/a> de que falamos acima, entendesse que as novas disposi\u00e7\u00f5es da LIA trazidas pela Lei 14.230\/2021 tivessem car\u00e1ter retroativo (<em>embora n\u00e3o se possa aplicar de forma autom\u00e1tica o princ\u00edpio da retroatividade da lei penal mais ben\u00e9fica em qualquer caso<\/em>).<\/p>\n\n\n\n<h3 class=\"wp-block-heading has-vivid-cyan-blue-color has-text-color has-link-color wp-elements-0cae816f4e95c7922e8f36643aa12a5b\" id=\"h-6\u00ba-e-7\u00ba-do-artigo-1\u00ba-da-lia\">\u00a7\u00a7 6\u00ba e 7\u00ba do artigo 1\u00ba da LIA<\/h3>\n\n\n\n<p>Como vimos no \u00a7 5\u00ba, t\u00ednhamos a defini\u00e7\u00e3o dos <strong>sujeitos passivos, do objeto jur\u00eddico tutelado<\/strong> pela Lei 8.429\/1992 e, por consequ\u00eancia, dos <strong>sujeitos ativos<\/strong>.<\/p>\n\n\n\n<p>Por sua vez, os <strong>\u00a7\u00a7 6\u00ba e 7\u00ba<\/strong> do art. 1\u00ba da LIA <strong>ampliam os sujeitos ativos do ato de improbidade <\/strong>para assim entender alguns atos praticados contra entidades privadas. Podemos chamar de \u201c<strong>sujeitos ativos por equipara\u00e7\u00e3o\u201d.<\/strong><\/p>\n\n\n\n<p>O \u00a7 6\u00ba disp\u00f5e que se aplica a LIA \u00e0queles que praticaram atos de improbidade <strong>contra o patrim\u00f4nio de entidade privada, desde que esta receba<\/strong> <strong>subven\u00e7\u00e3o, benef\u00edcio ou incentivo, fiscal ou credit\u00edcio, de entes p\u00fablicos ou governamentais<\/strong>, previstos no \u00a7 5\u00ba do artigo 1\u00ba da LIA.<\/p>\n\n\n\n<p>J\u00e1 o \u00a7 7\u00ba preconiza que, independentemente de integrar a administra\u00e7\u00e3o indireta, est\u00e3o sujeitos \u00e0s san\u00e7\u00f5es da LIA os atos de improbidade praticados <strong>contra o patrim\u00f4nio de entidade privada para cuja cria\u00e7\u00e3o ou custeio o er\u00e1rio haja concorrido ou concorra no seu patrim\u00f4nio ou receita atual,<\/strong> limitado o ressarcimento de preju\u00edzos, nesse caso, \u00e0 repercuss\u00e3o do il\u00edcito sobre a contribui\u00e7\u00e3o dos cofres p\u00fablicos.<\/p>\n\n\n\n<h3 class=\"wp-block-heading has-vivid-cyan-blue-color has-text-color has-link-color wp-elements-aa0178aa2ad89dfddb4f2ab0067b0f52\" id=\"h-8\u00ba-do-artigo-1\u00ba-da-lia\">\u00a7 8\u00ba do artigo 1\u00ba da LIA<\/h3>\n\n\n\n<p>Finalizando nosso artigo, o \u00a7 8\u00ba do artigo 1\u00ba da LIA disp\u00f5e que <strong>N\u00c3O <\/strong>configura improbidade a <strong>a\u00e7\u00e3o ou omiss\u00e3o decorrente de diverg\u00eancia interpretativa da lei, baseada em jurisprud\u00eancia, ainda que n\u00e3o pacificada, <\/strong>mesmo que n\u00e3o venha a ser posteriormente prevalecente nas decis\u00f5es dos \u00f3rg\u00e3os de controle ou dos tribunais do Poder Judici\u00e1rio.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter\"><img decoding=\"async\" src=\"https:\/\/lh7-rt.googleusercontent.com\/docsz\/AD_4nXcQUxpZTKgKmL7Hq6uE_QUALYZGAdxic66qaG46ATAJb7H0-jXKKKJ1K1EhayAhPhryT-4pJLCoMdImaGtwf35yoYqdJ_UOldyETSRvFPl7Iiy09KIKmlunJokNGaI3kykKm0LkaA?key=1lXFN3LFzfLgxFh2bJi7Cg\" alt=\"\"\/><\/figure>\n\n\n\n<p>Imagine que um Tribunal de Justi\u00e7a possua um entendimento sobre determinada Lei e a Administra\u00e7\u00e3o P\u00fablica adote seus procedimentos com base naquela interpreta\u00e7\u00e3o.&nbsp;<\/p>\n\n\n\n<p>No entanto, pode ser que esse Tribunal reveja sua compreens\u00e3o sobre aquele assunto e passe, por exemplo, a seguir a jurisprud\u00eancia do STF sobre o tema.<\/p>\n\n\n\n<p>A pergunta que fica \u00e9: o gestor p\u00fablico que adotou o procedimento com base naquela primeira interpreta\u00e7\u00e3o pode ser responsabilizado por ato de improbidade? A resposta que o \u00a7 8\u00ba nos d\u00e1 \u00e9 <strong>N\u00c3O<\/strong>!<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-vivid-cyan-blue-color has-text-color has-link-color wp-elements-2bedaf953dddcc5060475c06777272ac\" id=\"h-consideracoes-finais\">Considera\u00e7\u00f5es finais<\/h2>\n\n\n\n<p>Portanto, pessoal, esse foi nosso breve resumo sobre o Artigo 1\u00ba da LIA (Lei 8.429\/1992), visando ao CNU (Concurso Nacional Unificado).<\/p>\n\n\n\n<p>Nosso tempo aqui \u00e9 breve e n\u00e3o conseguimos, claro, esgotar o assunto. No entanto, aconselhamos a leitura completa do artigo 1\u00ba da Lei 8.429\/1992 (<em>caput <\/em>e seus oito par\u00e1grafos), at\u00e9 mesmo em virtude de uma cobran\u00e7a literal em prova.<\/p>\n\n\n\n<p>Portanto, n\u00e3o deixe de revisar o tema em seu material de estudo e praticar com diversas quest\u00f5es.<\/p>\n\n\n\n<p>At\u00e9 a pr\u00f3xima!<\/p>\n\n\n\n<p class=\"has-text-align-center has-very-light-gray-to-cyan-bluish-gray-gradient-background has-background has-medium-font-size\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-nacional-unificado\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>CNU 2025<\/strong><\/a><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img decoding=\"async\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/09\/18141901\/Coruja_Concursos%404x-506x1024.png\" alt=\"Concursos 2024 Estrat\u00e9gia Concursos\" class=\"wp-image-574355\" style=\"aspect-ratio:0.5;width:30px;height:auto\"\/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"h-quer-saber-tudo-sobre-concursos-previstos-confira-nossos-artigos\">Quer saber tudo sobre concursos previstos?<br \/>Confira nossos artigos!<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos Abertos<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2025\/\">Concursos 2025<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2026\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos 2026<\/a><\/li>\n<\/ul>\n\n\n\n<div class=\"container\" id=\"boxes\">\n  <div class=\"row\">\n\n    <div class=\"col-sm\">\n      <div class=\"banner-estrat-corj\" id=\"box-assinatura\">\n        <h3 class=\"titulo-assinatura\" style=\"text-align: left;\">Concursos 2025<\/h3>\n        <p class=\"subtitulo-assinatura\" style=\"text-align: left;\">Explore os cursos preparat\u00f3rios completos! \u2728<\/p>\n        <div class=\"box-botao\" style=\"text-align: left;\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/cursos\/concurso\/\" role=\"button\" rel=\"noopener noreferrer\">CLIQUE AQUI<\/a>\n        <\/div>\n      <\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"container\" id=\"boxes\">\n  <div class=\"row\">\n\n    <div class=\"col-sm\">\n      <div class=\"estrategia\" id=\"box-assinatura\">\n        <h3 class=\"titulo-assinatura\">Assinatura Concursos<\/h3>\n        <p class=\"subtitulo-assinatura\">Assinatura de 1 ano ou 2 anos<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/assinaturas\/\" role=\"button\" rel=\"noopener noreferrer\">ASSINE AGORA<\/a>\n        <\/div>\n      <\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Ol\u00e1, tudo bem? Hoje faremos um resumo sobre o Artigo 1\u00ba da Lei de Improbidade (Lei 8.429\/1992 &#8211; LIA), visando ao CNU (Concurso Nacional Unificado). O edital do CNU (o \u201cENEM dos concursos\u201d) foi lan\u00e7ado e destrinchado em 09 blocos tem\u00e1ticos do CNU 2025, conforme as suas respectivas \u201c\u00e1reas de conhecimento\u201d. Foram disponibilizadas 3.652 vagas [&hellip;]<\/p>\n","protected":false},"author":2567,"featured_media":1611187,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1,3766,214992,220191,1981],"tags":[],"tax_estado":[219964,219965,219966,219967,219968,219969,219963,219970,219971,219972,219973,219974,219975,219976,219977,219978,219979,219980,219981,219982,219983,219984,219985,219986,219987,219988,219989,219990],"class_list":["post-1611182","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cursos-e-concursos","category-educacional","category-concursos-administrativos","category-previdenciaria","category-saude","tax_estado-ac","tax_estado-al","tax_estado-am","tax_estado-ap","tax_estado-ba","tax_estado-ce","tax_estado-concursos-federais","tax_estado-df","tax_estado-es","tax_estado-go","tax_estado-ma","tax_estado-mg","tax_estado-ms","tax_estado-mt","tax_estado-pa","tax_estado-pb","tax_estado-pe","tax_estado-pi","tax_estado-pr","tax_estado-rj","tax_estado-rn","tax_estado-ro","tax_estado-rr","tax_estado-rs","tax_estado-sc","tax_estado-se","tax_estado-sp","tax_estado-to"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Artigo 1\u00ba da LIA para o CNU<\/title>\n<meta name=\"description\" content=\"Resumo sobre o Artigo 1\u00ba da LIA (Lei 8.429\/1992 - Lei de Improbidade Administrativa), visando ao CNU (Concurso Nacional Unificado).\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/artigo-1-lia-cnu\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Artigo 1\u00ba da LIA para o CNU\" \/>\n<meta property=\"og:description\" content=\"Resumo sobre o Artigo 1\u00ba da LIA (Lei 8.429\/1992 - Lei de Improbidade Administrativa), visando ao CNU (Concurso Nacional Unificado).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/artigo-1-lia-cnu\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-11T14:29:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-12T12:56:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/07\/22105904\/artigo-1o-da-lei-de-improbidade-para-o-cnu.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Frederico Tadeu Borlot Peixoto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Frederico Tadeu Borlot Peixoto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/artigo-1-lia-cnu\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/artigo-1-lia-cnu\/\"},\"author\":{\"name\":\"Frederico Tadeu Borlot Peixoto\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/48a7e085e45aee7c3d4596399af50ebb\"},\"headline\":\"Artigo 1\u00ba da LIA para o CNU\",\"datePublished\":\"2025-08-11T14:29:00+00:00\",\"dateModified\":\"2025-08-12T12:56:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/artigo-1-lia-cnu\/\"},\"wordCount\":1410,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/artigo-1-lia-cnu\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/07\/22105904\/artigo-1o-da-lei-de-improbidade-para-o-cnu.png\",\"articleSection\":[\"Concursos P\u00fablicos\",\"Educa\u00e7\u00e3o\",\"Executivo (Administrativa)\",\"Previdenci\u00e1ria (INSS, PREVIC)\",\"Sa\u00fade\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/artigo-1-lia-cnu\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"accessibilityFeature\":[\"tableOfContents\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/artigo-1-lia-cnu\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/artigo-1-lia-cnu\/\",\"name\":\"Artigo 1\u00ba da LIA para o CNU\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/artigo-1-lia-cnu\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/artigo-1-lia-cnu\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/07\/22105904\/artigo-1o-da-lei-de-improbidade-para-o-cnu.png\",\"datePublished\":\"2025-08-11T14:29:00+00:00\",\"dateModified\":\"2025-08-12T12:56:01+00:00\",\"description\":\"Resumo sobre o Artigo 1\u00ba da LIA (Lei 8.429\/1992 - Lei de Improbidade Administrativa), visando ao CNU (Concurso Nacional Unificado).\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/artigo-1-lia-cnu\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/artigo-1-lia-cnu\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/artigo-1-lia-cnu\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/07\/22105904\/artigo-1o-da-lei-de-improbidade-para-o-cnu.png\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/07\/22105904\/artigo-1o-da-lei-de-improbidade-para-o-cnu.png\",\"width\":1080,\"height\":1080,\"caption\":\"Artigo 1\u00ba da Lei de Improbidade para o CNU\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/artigo-1-lia-cnu\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Artigo 1\u00ba da LIA para o CNU\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/48a7e085e45aee7c3d4596399af50ebb\",\"name\":\"Frederico Tadeu Borlot Peixoto\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/df8a49e2321c1e32f85e9e7c2a9c92c688f1f53a947220f40017ff5858b09fdb?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/df8a49e2321c1e32f85e9e7c2a9c92c688f1f53a947220f40017ff5858b09fdb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/df8a49e2321c1e32f85e9e7c2a9c92c688f1f53a947220f40017ff5858b09fdb?s=96&d=mm&r=g\",\"caption\":\"Frederico Tadeu Borlot Peixoto\"},\"description\":\"Analista Judici\u00e1rio - \u00c1rea Judici\u00e1ria do TRF da 4\u00aa regi\u00e3o. Bacharel em Direito. P\u00f3s-graduado em Direito Administrativo, Legisla\u00e7\u00e3o Penal Especial, Direito Penal e Direito Processual Penal. Tamb\u00e9m nomeado no TRF da 3\u00aa regi\u00e3o (8\u00ba lugar); SPPREV (3\u00ba lugar); IFES (2\u00ba lugar); e PMES. https:\/\/www.instagram.com\/proffrederico\/\",\"sameAs\":[\"https:\/\/www.instagram.com\/proffrederico\/\"],\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/xfredericohotmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Artigo 1\u00ba da LIA para o CNU","description":"Resumo sobre o Artigo 1\u00ba da LIA (Lei 8.429\/1992 - Lei de Improbidade Administrativa), visando ao CNU (Concurso Nacional Unificado).","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/artigo-1-lia-cnu\/","og_locale":"pt_BR","og_type":"article","og_title":"Artigo 1\u00ba da LIA para o CNU","og_description":"Resumo sobre o Artigo 1\u00ba da LIA (Lei 8.429\/1992 - Lei de Improbidade Administrativa), visando ao CNU (Concurso Nacional Unificado).","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/artigo-1-lia-cnu\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2025-08-11T14:29:00+00:00","article_modified_time":"2025-08-12T12:56:01+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/07\/22105904\/artigo-1o-da-lei-de-improbidade-para-o-cnu.png","type":"image\/png"}],"author":"Frederico Tadeu Borlot Peixoto","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Frederico Tadeu Borlot Peixoto","Est. tempo de leitura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/artigo-1-lia-cnu\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/artigo-1-lia-cnu\/"},"author":{"name":"Frederico Tadeu Borlot Peixoto","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/48a7e085e45aee7c3d4596399af50ebb"},"headline":"Artigo 1\u00ba da LIA para o CNU","datePublished":"2025-08-11T14:29:00+00:00","dateModified":"2025-08-12T12:56:01+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/artigo-1-lia-cnu\/"},"wordCount":1410,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/artigo-1-lia-cnu\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/07\/22105904\/artigo-1o-da-lei-de-improbidade-para-o-cnu.png","articleSection":["Concursos P\u00fablicos","Educa\u00e7\u00e3o","Executivo (Administrativa)","Previdenci\u00e1ria (INSS, PREVIC)","Sa\u00fade"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/artigo-1-lia-cnu\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"accessibilityFeature":["tableOfContents"]},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/artigo-1-lia-cnu\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/artigo-1-lia-cnu\/","name":"Artigo 1\u00ba da LIA para o CNU","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/artigo-1-lia-cnu\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/artigo-1-lia-cnu\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/07\/22105904\/artigo-1o-da-lei-de-improbidade-para-o-cnu.png","datePublished":"2025-08-11T14:29:00+00:00","dateModified":"2025-08-12T12:56:01+00:00","description":"Resumo sobre o Artigo 1\u00ba da LIA (Lei 8.429\/1992 - Lei de Improbidade Administrativa), visando ao CNU (Concurso Nacional Unificado).","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/artigo-1-lia-cnu\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/artigo-1-lia-cnu\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/artigo-1-lia-cnu\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/07\/22105904\/artigo-1o-da-lei-de-improbidade-para-o-cnu.png","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/07\/22105904\/artigo-1o-da-lei-de-improbidade-para-o-cnu.png","width":1080,"height":1080,"caption":"Artigo 1\u00ba da Lei de Improbidade para o CNU"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/artigo-1-lia-cnu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Artigo 1\u00ba da LIA para o CNU"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/48a7e085e45aee7c3d4596399af50ebb","name":"Frederico Tadeu Borlot Peixoto","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/df8a49e2321c1e32f85e9e7c2a9c92c688f1f53a947220f40017ff5858b09fdb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/df8a49e2321c1e32f85e9e7c2a9c92c688f1f53a947220f40017ff5858b09fdb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/df8a49e2321c1e32f85e9e7c2a9c92c688f1f53a947220f40017ff5858b09fdb?s=96&d=mm&r=g","caption":"Frederico Tadeu Borlot Peixoto"},"description":"Analista Judici\u00e1rio - \u00c1rea Judici\u00e1ria do TRF da 4\u00aa regi\u00e3o. Bacharel em Direito. P\u00f3s-graduado em Direito Administrativo, Legisla\u00e7\u00e3o Penal Especial, Direito Penal e Direito Processual Penal. Tamb\u00e9m nomeado no TRF da 3\u00aa regi\u00e3o (8\u00ba lugar); SPPREV (3\u00ba lugar); IFES (2\u00ba lugar); e PMES. https:\/\/www.instagram.com\/proffrederico\/","sameAs":["https:\/\/www.instagram.com\/proffrederico\/"],"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/xfredericohotmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1611182","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/2567"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1611182"}],"version-history":[{"count":4,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1611182\/revisions"}],"predecessor-version":[{"id":1622040,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1611182\/revisions\/1622040"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/1611187"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1611182"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1611182"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1611182"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1611182"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}