{"id":1601902,"date":"2025-07-16T14:45:00","date_gmt":"2025-07-16T17:45:00","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=1601902"},"modified":"2025-07-07T15:04:14","modified_gmt":"2025-07-07T18:04:14","slug":"pensao-por-morte-cnu","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/pensao-por-morte-cnu\/","title":{"rendered":"Pens\u00e3o por morte para o CNU"},"content":{"rendered":"\n<p>Ol\u00e1, tudo bem? Hoje faremos um resumo sobre a pens\u00e3o por morte, visando ao CNU (Concurso Nacional Unificado), com base na legisla\u00e7\u00e3o.<\/p>\n\n\n\n<p>O<a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-nacional-unificado\/\" target=\"_blank\" rel=\"noreferrer noopener\"> edital do CNU<\/a> (o \u201cENEM dos concursos\u201d) foi lan\u00e7ado e destrinchado em<a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-blocos-tematicos\/\" target=\"_blank\" rel=\"noreferrer noopener\"> 09 blocos tem\u00e1ticos do CNU<\/a> 2025, conforme as suas respectivas \u201c\u00e1reas de conhecimento\u201d.<\/p>\n\n\n\n<p>Foram disponibilizadas <strong>3.652 vagas<\/strong> para este pr\u00f3ximo certame, sendo 2.480 imediatas e 1.172 para forma\u00e7\u00e3o de cadastro reserva, com sal\u00e1rios variando de R$4.804,89 a R$16.413,35.<\/p>\n\n\n\n<p>Portanto, vamos ao que interessa!<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/07\/04085332\/pensao-por-morte-para-o-cnu-1024x1024.png\" alt=\"Pens\u00e3o por morte para o CNU\" class=\"wp-image-1601914\" style=\"width:534px;height:auto\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/07\/04085332\/pensao-por-morte-para-o-cnu-1024x1024.png 1024w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/07\/04085332\/pensao-por-morte-para-o-cnu-300x300.png 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/07\/04085332\/pensao-por-morte-para-o-cnu-150x150.png 150w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/07\/04085332\/pensao-por-morte-para-o-cnu-768x768.png 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/07\/04085332\/pensao-por-morte-para-o-cnu-96x96.png 96w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/07\/04085332\/pensao-por-morte-para-o-cnu.png 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Pens\u00e3o por morte para o CNU<\/figcaption><\/figure>\n\n\n\n<div class=\"wp-block-yoast-seo-table-of-contents yoast-table-of-contents\"><h2><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">Tabela de conte\u00fados<\/mark><\/h2><ul><li><a href=\"#h-pensao-por-morte-para-o-cnu\" data-level=\"2\">Pens\u00e3o por morte para o CNU<\/a><ul><li><a href=\"#h-consideracoes-iniciais-e-previsao-legal\" data-level=\"3\">Considera\u00e7\u00f5es iniciais e previs\u00e3o legal<\/a><\/li><li><a href=\"#h-o-que-e-a-pensao-por-morte\" data-level=\"3\">O que \u00e9 a pens\u00e3o por morte?<\/a><\/li><li><a href=\"#h-data-de-inicio-do-beneficio-dib-da-pensao-por-morte\" data-level=\"3\">Data de in\u00edcio do benef\u00edcio (DIB) da pens\u00e3o por morte<\/a><\/li><li><a href=\"#h-carencia-e-renda-mensal-inicial-rmi\" data-level=\"3\">Car\u00eancia e Renda Mensal Inicial (RMI)<\/a><\/li><li><a href=\"#h-cessacao-da-pensao-por-morte\" data-level=\"3\">Cessa\u00e7\u00e3o da pens\u00e3o por morte<\/a><\/li><li><a href=\"#h-perda-do-direito-a-pensao\" data-level=\"3\">Perda do direito \u00e0 pens\u00e3o<\/a><ul><li><a href=\"#h-primeiro-caso-de-perda-do-direito-a-pensao\" data-level=\"4\">Primeiro caso de perda do direito \u00e0 pens\u00e3o<\/a><\/li><li><a href=\"#h-segundo-caso-de-perda-do-direito-a-pensao\" data-level=\"4\">Segundo caso de perda do direito \u00e0 pens\u00e3o<\/a><\/li><\/ul><\/li><\/ul><\/li><li><a href=\"#h-consideracoes-finais\" data-level=\"2\">Considera\u00e7\u00f5es finais<\/a><\/li><li><a href=\"#h-quer-saber-tudo-sobre-concursos-previstos-confira-nossos-artigos\" data-level=\"2\">Quer saber tudo sobre concursos previstos? Confira nossos artigos!<\/a><\/li><\/ul><\/div>\n\n\n\n<h2 class=\"wp-block-heading has-vivid-cyan-blue-color has-text-color has-link-color wp-elements-8a82bd45c47c2c85f17852ab3b0f20c9\" id=\"h-pensao-por-morte-para-o-cnu\">Pens\u00e3o por morte para o CNU<\/h2>\n\n\n\n<h3 class=\"wp-block-heading has-vivid-cyan-blue-color has-text-color has-link-color wp-elements-f82c5b903e7a21e8bba3ec731c2ac6ee\" id=\"h-consideracoes-iniciais-e-previsao-legal\">Considera\u00e7\u00f5es iniciais e previs\u00e3o legal<\/h3>\n\n\n\n<p>A Constitui\u00e7\u00e3o Federal prev\u00ea que a Previd\u00eancia Social ser\u00e1 organizada sob a forma do Regime Geral de Previd\u00eancia Social, de car\u00e1ter contributivo e de filia\u00e7\u00e3o obrigat\u00f3ria.<\/p>\n\n\n\n<p>Portanto, todo aquele que \u00e9 filiado e contribui para a Previd\u00eancia Social \u00e9 considerado, via de regra, como segurado.<\/p>\n\n\n\n<p>Al\u00e9m disso, a CF\/88 prev\u00ea que a Previd\u00eancia Social, dentre outros riscos sociais, atender\u00e1 a <strong>pens\u00e3o por morte do segurado, homem ou mulher, ao c\u00f4njuge ou companheiro e dependentes <\/strong>(art. 201, inciso V).<\/p>\n\n\n\n<p>No entanto, a CF n\u00e3o entra em especifica\u00e7\u00f5es &#8211; e nem deveria &#8211; sobre esse benef\u00edcio, cabendo essa tarefa \u00e0 legisla\u00e7\u00e3o ordin\u00e1ria infraconstitucional, principalmente \u00e0 <a href=\"https:\/\/www.planalto.gov.br\/ccivil_03\/leis\/l8213cons.htm\">Lei 8.213\/1991 (Lei de Benef\u00edcios da Previd\u00eancia Social &#8211; LBPS)<\/a>.<\/p>\n\n\n\n<p>Ent\u00e3o, vamos ver no que consiste esse benef\u00edcio da Previd\u00eancia Social.<\/p>\n\n\n\n<h3 class=\"wp-block-heading has-vivid-cyan-blue-color has-text-color has-link-color wp-elements-d70f51229b977230446641128bb4b2c0\" id=\"h-o-que-e-a-pensao-por-morte\">O que \u00e9 a pens\u00e3o por morte?<\/h3>\n\n\n\n<p>Desde o in\u00edcio, devemos ter em mente que a pens\u00e3o por morte \u00e9 um <strong>benef\u00edcio que ser\u00e1 pago aos DEPENDENTES do segurado da Previd\u00eancia Social quando este falecer<\/strong>.<\/p>\n\n\n\n<p>Com isso, j\u00e1 percebemos que <strong>o fato gerador<\/strong> da pens\u00e3o por morte \u00e9 a <strong>morte<\/strong> de quem era segurado da Previd\u00eancia Social, <strong>independentemente se o segurado estivesse em atividade ou aposentado<\/strong>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading has-vivid-cyan-blue-color has-text-color has-link-color wp-elements-27be374adb5a5c8fb4ec4b38285812e7\" id=\"h-data-de-inicio-do-beneficio-dib-da-pensao-por-morte\">Data de in\u00edcio do benef\u00edcio (DIB) da pens\u00e3o por morte<\/h3>\n\n\n\n<p>A DIB da pens\u00e3o por morte pode ter 04 hip\u00f3teses variadas, as quais esquematizamos em uma tabela de simples visualiza\u00e7\u00e3o:&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Pens\u00e3o por morte<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>DIB (Ser\u00e1 paga ao dependente):<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>Hip\u00f3tese<\/strong><\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>1<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">Desde a data do \u00f3bito do segurado<\/td><td class=\"has-text-align-center\" data-align=\"center\">Quando requerida em <strong>at\u00e9 180 dias<\/strong> ap\u00f3s o \u00f3bito &#8211; Para os filhos <strong>menores de 16 anos<\/strong><\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>2<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">Desde a data do \u00f3bito do segurado<\/td><td class=\"has-text-align-center\" data-align=\"center\">Quando requerida em <strong>at\u00e9 90 dias<\/strong> ap\u00f3s o \u00f3bito &#8211; Para os <strong>demais dependentes<\/strong><\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>3<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">A partir do requerimento<\/td><td class=\"has-text-align-center\" data-align=\"center\">Se os segurados n\u00e3o requererem nos prazos acima<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>4<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">A partir da decis\u00e3o judicial<\/td><td class=\"has-text-align-center\" data-align=\"center\">Quando for o caso de \u201cmorte presumida\u201d, vide <a href=\"https:\/\/www.planalto.gov.br\/ccivil_03\/leis\/2002\/l10406compilada.htm#:~:text=Art.%207%20o%20Pode%20ser%20declarada%20a%20morte%20presumida%2C%20sem%20decreta%C3%A7%C3%A3o%20de%20aus%C3%AAncia%3A\" target=\"_blank\" rel=\"noreferrer noopener\">art. 7\u00ba do C\u00f3digo Civil<\/a> e <a href=\"https:\/\/www.planalto.gov.br\/ccivil_03\/leis\/L8213compilado.htm#:~:text=%C2%A0%C2%A0%C2%A0%C2%A0%C2%A0%C2%A0%C2%A0%20Art.%2078.%C2%A0Por%20morte%20presumida%20do%20segurado%2C%20declarada%20pela%20autoridade%20judicial%20competente%2C%20depois%20de%206%20(seis)%20meses%20de%20aus%C3%AAncia%2C%20ser%C3%A1%20concedida%20pens%C3%A3o%20provis%C3%B3ria%2C%20na%20forma%20desta%20Subse%C3%A7%C3%A3o.\" target=\"_blank\" rel=\"noreferrer noopener\">artigo 78 da Lei 8.213\/91<\/a><\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p>Al\u00e9m disso, \u00e9 importante destacar que <strong>a concess\u00e3o<\/strong> da pens\u00e3o por morte <strong>n\u00e3o ser\u00e1 atrasada pela falta de habilita\u00e7\u00e3o de outro poss\u00edvel dependente<\/strong>.<\/p>\n\n\n\n<p>Ou seja, se h\u00e1 mais de um dependente poss\u00edvel daquela classe (vide art. 16 da LBPS), a pens\u00e3o por morte come\u00e7ar\u00e1 a ser paga para quem for se habilitando, n\u00e3o dependendo seu pagamento de que todos se habilitem conjuntamente.<\/p>\n\n\n\n<p>Da mesma forma, qualquer inscri\u00e7\u00e3o ou habilita\u00e7\u00e3o posterior que importe em exclus\u00e3o ou inclus\u00e3o de dependente s\u00f3 produzir\u00e1 efeito a contar da data da inscri\u00e7\u00e3o ou habilita\u00e7\u00e3o. Ex.: quando um dependente de classe superior se habilita, fazendo com que o de classe inferior perca o direito ao benef\u00edcio.<\/p>\n\n\n\n<h3 class=\"wp-block-heading has-vivid-cyan-blue-color has-text-color has-link-color wp-elements-226fcfefb8cfd163dfeb279b0586e7ff\" id=\"h-carencia-e-renda-mensal-inicial-rmi\">Car\u00eancia e Renda Mensal Inicial (RMI)<\/h3>\n\n\n\n<p>De acordo com o artigo 26 da Lei 8.213\/1991, a concess\u00e3o da pens\u00e3o por morte <strong>n\u00e3o depende <\/strong>do cumprimento de qualquer car\u00eancia.&nbsp;<\/p>\n\n\n\n<p>Ou seja, n\u00e3o \u00e9 necess\u00e1rio que o segurado que faleceu tenha contribu\u00eddo por um determinado n\u00famero m\u00ednimo de meses para que seus dependentes pudessem ter direito \u00e0 pens\u00e3o por morte.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter\"><img decoding=\"async\" src=\"https:\/\/lh7-rt.googleusercontent.com\/docsz\/AD_4nXdIQ0b4DaK0X-d783h-8YjIQkoHAITO9DasYx3Y_kCSAxgh0Ipm-T6mj1S_pUpwZuXDz8h_P1p3pU1Ifz2BeLhVr0cP5nXKfwcClwi4_-DKBuV7EG_Vb0zghFtsrTAXWwIerHLaJA?key=mxERiXv7tMquJFoWjqZ-Xg\" alt=\"\"\/><\/figure>\n\n\n\n<p>Ent\u00e3o, por exemplo, se eu come\u00e7o a trabalhar em uma empresa (e, portanto, passo a ser considerado segurado empregado da Previd\u00eancia) e venho a falecer dias depois, meus dependentes ter\u00e3o direito \u00e0 pens\u00e3o por morte da mesma forma que os dependentes de quem trabalha h\u00e1 20 anos naquela empresa.<\/p>\n\n\n\n<p>J\u00e1 no que tange ao valor do benef\u00edcio, temos que a RMI da pens\u00e3o por morte, ser\u00e1 de <strong>100% do valor da aposentadoria que o segurado recebia ou daquela a que teria direito se estivesse aposentado por invalidez<\/strong> na data de seu falecimento.<\/p>\n\n\n\n<p>Havendo mais de um pensionista, o valor da pens\u00e3o por morte ser\u00e1 <strong>rateada entre todos em parte iguais<\/strong>. Al\u00e9m disso, se algum dos dependentes perder posteriormente o direito \u00e0 pens\u00e3o por morte, sua parte <strong>reverter\u00e1 em favor dos demais.<\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading has-vivid-cyan-blue-color has-text-color has-link-color wp-elements-fa6fffef8d876eb733d458fb43f5e115\" id=\"h-cessacao-da-pensao-por-morte\">Cessa\u00e7\u00e3o da pens\u00e3o por morte<\/h3>\n\n\n\n<p>O dependente pensionista ter\u00e1 seu direito \u00e0 pens\u00e3o cessado em diversas hip\u00f3teses:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Quando o <strong>pensionista de qualquer classe<\/strong> falecer;<\/li>\n\n\n\n<li>para o <strong>filho, a pessoa a ele equiparada ou o irm\u00e3o<\/strong>, de ambos os sexos, <strong>ao completar 21 de idade<\/strong>, salvo se for inv\u00e1lido ou tiver defici\u00eancia intelectual ou mental ou defici\u00eancia grave;<\/li>\n\n\n\n<li>para <strong>filho ou irm\u00e3o<\/strong> <strong>inv\u00e1lido<\/strong>, pela <strong>cessa\u00e7\u00e3o da invalidez<\/strong>;<\/li>\n\n\n\n<li>para <strong>filho ou irm\u00e3o que tenha defici\u00eancia<\/strong> intelectual ou mental ou defici\u00eancia grave, <strong>pelo afastamento da defici\u00eancia<\/strong>, nos termos do regulamento;<\/li>\n\n\n\n<li>para <strong>c\u00f4njuge ou companheiro<\/strong>: quando decorrido os prazos previstos no <a href=\"https:\/\/www.planalto.gov.br\/ccivil_03\/leis\/L8213compilado.htm#:~:text=V%20%2D%20para%20c%C3%B4njuge%20ou%20companheiro%3A%C2%A0%C2%A0%C2%A0%C2%A0%C2%A0%C2%A0%C2%A0%C2%A0%C2%A0%C2%A0%20(Inclu%C3%ADdo%20pela%20Lei%20n%C2%BA%2013.135%2C%20de%202015)\" target=\"_blank\" rel=\"noreferrer noopener\">inciso V do \u00a7 2\u00ba do art. 77 da LBPS<\/a> ou, se inv\u00e1lido ou com defici\u00eancia, pela cessa\u00e7\u00e3o da invalidez ou pelo afastamento da defici\u00eancia &#8211; respeitados os prazos m\u00ednimos;<\/li>\n\n\n\n<li>pela <strong>perda do direito<\/strong> \u00e0 pens\u00e3o por morte.<\/li>\n<\/ol>\n\n\n\n<p>Vamos falar mais especificamente sobre essa \u00faltima causa de cess\u00e3o (perda do direito \u00e0 pens\u00e3o).<\/p>\n\n\n\n<h3 class=\"wp-block-heading has-vivid-cyan-blue-color has-text-color has-link-color wp-elements-15ca7265442a2d3cc0838f3435f0c35e\" id=\"h-perda-do-direito-a-pensao\">Perda do direito \u00e0 pens\u00e3o<\/h3>\n\n\n\n<h4 class=\"wp-block-heading has-vivid-cyan-blue-color has-text-color has-link-color wp-elements-f0937628cb72743590607f8f8a1d2dcf\" id=\"h-primeiro-caso-de-perda-do-direito-a-pensao\">Primeiro caso de perda do direito \u00e0 pens\u00e3o<\/h4>\n\n\n\n<p>O \u00a7 1\u00ba do artigo 74 da LBPS disp\u00f5e que perde o direito \u00e0 pens\u00e3o por morte <strong>o condenado criminalmente por senten\u00e7a com tr\u00e2nsito em julgado<\/strong>, como <strong>autor, coautor ou part\u00edcipe de homic\u00eddio doloso, ou de tentativa<\/strong> desse crime, cometido <strong>contra a pessoa do segurado<\/strong>, ressalvados os absolutamente incapazes e os inimput\u00e1veis.<\/p>\n\n\n\n<p>No entanto, o trecho final do faz uma ressalva <strong>(exce\u00e7\u00e3o) em rela\u00e7\u00e3o aos absolutamente incapazes e os inimput\u00e1veis<\/strong>. Ou seja, nesses casos, n\u00e3o haver\u00e1 exclus\u00e3o da condi\u00e7\u00e3o de dependente.&nbsp;<\/p>\n\n\n\n<p>Os <strong>absolutamente incapazes <\/strong>s\u00e3o os menores de 16 (dezesseis) anos, de acordo com o artigo 3\u00ba do C\u00f3digo Civil.<\/p>\n\n\n\n<p>J\u00e1 os <strong>inimput\u00e1veis<\/strong>, de acordo com os artigos 26 a 28 do C\u00f3digo Penal, s\u00e3o:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Os menores de 18 (dezoito) anos;<\/li>\n\n\n\n<li>O agente que, por doen\u00e7a mental ou desenvolvimento mental incompleto ou retardado, era, ao tempo da a\u00e7\u00e3o ou da omiss\u00e3o, <strong>inteiramente incapaz de entender<\/strong> o car\u00e1ter il\u00edcito do fato <strong>ou de determinar-se <\/strong>de acordo com esse entendimento; e\u00a0<\/li>\n\n\n\n<li>O agente que, por embriaguez completa, proveniente de caso fortuito ou for\u00e7a maior, era, ao tempo da a\u00e7\u00e3o ou da omiss\u00e3o, <strong>inteiramente incapaz de entender <\/strong>o car\u00e1ter il\u00edcito do fato <strong>ou de determinar-se<\/strong> de acordo com esse entendimento.<\/li>\n<\/ul>\n\n\n\n<p>Ali\u00e1s, desde que haja <strong>fundados ind\u00edcios de autoria, coautoria ou participa\u00e7\u00e3o, <\/strong>ser\u00e1 poss\u00edvel a <strong>suspens\u00e3o provis\u00f3ria<\/strong> da parte daquele dependente no benef\u00edcio de pens\u00e3o por morte, mediante processo administrativo pr\u00f3prio, respeitados a ampla defesa e o contradit\u00f3rio (primeira parte do \u00a7 7\u00ba do art. 77).<\/p>\n\n\n\n<p>Por outro lado, caso seja posteriormente absolvido esse dependente que teve o benef\u00edcio suspenso provisoriamente, ter\u00e1 direito todas as parcelas corrigidas desde a data da suspens\u00e3o, bem como a reativa\u00e7\u00e3o imediata do benef\u00edcio (segunda parte do \u00a7 7\u00ba do art. 77).<\/p>\n\n\n\n<h4 class=\"wp-block-heading has-vivid-cyan-blue-color has-text-color has-link-color wp-elements-6e96e056ada6ea6a5273d50bfaaaada0\" id=\"h-segundo-caso-de-perda-do-direito-a-pensao\">Segundo caso de perda do direito \u00e0 pens\u00e3o<\/h4>\n\n\n\n<p>Al\u00e9m disso, <strong>tamb\u00e9m perde<\/strong> o direito \u00e0 pens\u00e3o por morte <strong>o c\u00f4njuge, o companheiro ou a companheira<\/strong> se comprovada, a qualquer tempo, <strong>simula\u00e7\u00e3o ou fraude no casamento ou na uni\u00e3o est\u00e1vel, ou a formaliza\u00e7\u00e3o desses com o fim exclusivo de constituir benef\u00edcio previdenci\u00e1rio<\/strong>, apuradas em processo judicial no qual ser\u00e1 assegurado o direito ao contradit\u00f3rio e \u00e0 ampla defesa.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-vivid-cyan-blue-color has-text-color has-link-color wp-elements-2bedaf953dddcc5060475c06777272ac\" id=\"h-consideracoes-finais\">Considera\u00e7\u00f5es finais<\/h2>\n\n\n\n<p>Portanto, pessoal, esse foi nosso breve resumo sobre a pens\u00e3o por morte, visando ao CNU (Concurso Nacional Unificado), com base na legisla\u00e7\u00e3o.<\/p>\n\n\n\n<p>Nosso tempo aqui \u00e9 breve e n\u00e3o conseguimos, claro, esgotar o assunto. Portanto, n\u00e3o deixe de revisar o tema em seu material de estudo e praticar com diversas quest\u00f5es.<\/p>\n\n\n\n<p>At\u00e9 a pr\u00f3xima!<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img decoding=\"async\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/09\/18141901\/Coruja_Concursos%404x-506x1024.png\" alt=\"Concursos 2024 Estrat\u00e9gia Concursos\" class=\"wp-image-574355\" style=\"aspect-ratio:0.5;width:30px;height:auto\"\/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"h-quer-saber-tudo-sobre-concursos-previstos-confira-nossos-artigos\">Quer saber tudo sobre concursos previstos?<br \/>Confira nossos artigos!<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos Abertos<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2025\/\">Concursos 2025<\/a><\/li>\n<\/ul>\n\n\n\n<div class=\"container\" id=\"boxes\">\n  <div class=\"row\">\n\n    <div class=\"col-sm\">\n      <div class=\"banner-estrat-corj\" id=\"box-assinatura\">\n        <h3 class=\"titulo-assinatura\" style=\"text-align: left;\">Concursos 2025<\/h3>\n        <p class=\"subtitulo-assinatura\" style=\"text-align: left;\">Explore os cursos preparat\u00f3rios completos! \u2728<\/p>\n        <div class=\"box-botao\" style=\"text-align: left;\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/cursos\/concurso\/\" role=\"button\" rel=\"noopener noreferrer\">CLIQUE AQUI<\/a>\n        <\/div>\n      <\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"container\" id=\"boxes\">\n  <div class=\"row\">\n\n    <div class=\"col-sm\">\n      <div class=\"estrategia\" id=\"box-assinatura\">\n        <h3 class=\"titulo-assinatura\">Assinatura Concursos<\/h3>\n        <p class=\"subtitulo-assinatura\">Assinatura de 1 ano ou 2 anos<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/assinaturas\/\" role=\"button\" rel=\"noopener noreferrer\">ASSINE AGORA<\/a>\n        <\/div>\n      <\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Ol\u00e1, tudo bem? Hoje faremos um resumo sobre a pens\u00e3o por morte, visando ao CNU (Concurso Nacional Unificado), com base na legisla\u00e7\u00e3o. O edital do CNU (o \u201cENEM dos concursos\u201d) foi lan\u00e7ado e destrinchado em 09 blocos tem\u00e1ticos do CNU 2025, conforme as suas respectivas \u201c\u00e1reas de conhecimento\u201d. Foram disponibilizadas 3.652 vagas para este pr\u00f3ximo [&hellip;]<\/p>\n","protected":false},"author":2567,"featured_media":1601914,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1,3766,214992,220191,1981],"tags":[],"tax_estado":[219964,219965,219966,219967,219968,219969,219963,219970,219971,219972,219973,219974,219975,219976,219977,219978,219979,219980,219981,219982,219983,219984,219985,219986,219987,219988,219989,219990],"class_list":["post-1601902","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cursos-e-concursos","category-educacional","category-concursos-administrativos","category-previdenciaria","category-saude","tax_estado-ac","tax_estado-al","tax_estado-am","tax_estado-ap","tax_estado-ba","tax_estado-ce","tax_estado-concursos-federais","tax_estado-df","tax_estado-es","tax_estado-go","tax_estado-ma","tax_estado-mg","tax_estado-ms","tax_estado-mt","tax_estado-pa","tax_estado-pb","tax_estado-pe","tax_estado-pi","tax_estado-pr","tax_estado-rj","tax_estado-rn","tax_estado-ro","tax_estado-rr","tax_estado-rs","tax_estado-sc","tax_estado-se","tax_estado-sp","tax_estado-to"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Pens\u00e3o por morte para o CNU<\/title>\n<meta name=\"description\" content=\"Resumo sobre o benef\u00edcio da pens\u00e3o por morte, visando ao CNU (Concurso Nacional Unificado), com base na legisla\u00e7\u00e3o.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/pensao-por-morte-cnu\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pens\u00e3o por morte para o CNU\" \/>\n<meta property=\"og:description\" content=\"Resumo sobre o benef\u00edcio da pens\u00e3o por morte, visando ao CNU (Concurso Nacional Unificado), com base na legisla\u00e7\u00e3o.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/pensao-por-morte-cnu\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-16T17:45:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/07\/04085332\/pensao-por-morte-para-o-cnu.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Frederico Tadeu Borlot Peixoto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Frederico Tadeu Borlot Peixoto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/pensao-por-morte-cnu\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/pensao-por-morte-cnu\/\"},\"author\":{\"name\":\"Frederico Tadeu Borlot Peixoto\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/48a7e085e45aee7c3d4596399af50ebb\"},\"headline\":\"Pens\u00e3o por morte para o CNU\",\"datePublished\":\"2025-07-16T17:45:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/pensao-por-morte-cnu\/\"},\"wordCount\":1521,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/pensao-por-morte-cnu\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/07\/04085332\/pensao-por-morte-para-o-cnu.png\",\"articleSection\":[\"Concursos P\u00fablicos\",\"Educa\u00e7\u00e3o\",\"Executivo (Administrativa)\",\"Previdenci\u00e1ria (INSS, PREVIC)\",\"Sa\u00fade\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/pensao-por-morte-cnu\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"accessibilityFeature\":[\"tableOfContents\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/pensao-por-morte-cnu\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/pensao-por-morte-cnu\/\",\"name\":\"Pens\u00e3o por morte para o CNU\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/pensao-por-morte-cnu\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/pensao-por-morte-cnu\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/07\/04085332\/pensao-por-morte-para-o-cnu.png\",\"datePublished\":\"2025-07-16T17:45:00+00:00\",\"description\":\"Resumo sobre o benef\u00edcio da pens\u00e3o por morte, visando ao CNU (Concurso Nacional Unificado), com base na legisla\u00e7\u00e3o.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/pensao-por-morte-cnu\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/pensao-por-morte-cnu\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/pensao-por-morte-cnu\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/07\/04085332\/pensao-por-morte-para-o-cnu.png\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/07\/04085332\/pensao-por-morte-para-o-cnu.png\",\"width\":1080,\"height\":1080,\"caption\":\"Pens\u00e3o por morte para o CNU\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/pensao-por-morte-cnu\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pens\u00e3o por morte para o CNU\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/48a7e085e45aee7c3d4596399af50ebb\",\"name\":\"Frederico Tadeu Borlot Peixoto\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/df8a49e2321c1e32f85e9e7c2a9c92c688f1f53a947220f40017ff5858b09fdb?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/df8a49e2321c1e32f85e9e7c2a9c92c688f1f53a947220f40017ff5858b09fdb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/df8a49e2321c1e32f85e9e7c2a9c92c688f1f53a947220f40017ff5858b09fdb?s=96&d=mm&r=g\",\"caption\":\"Frederico Tadeu Borlot Peixoto\"},\"description\":\"Analista Judici\u00e1rio - \u00c1rea Judici\u00e1ria do TRF da 4\u00aa regi\u00e3o. Bacharel em Direito. P\u00f3s-graduado em Direito Administrativo, Legisla\u00e7\u00e3o Penal Especial, Direito Penal e Direito Processual Penal. Tamb\u00e9m nomeado no TRF da 3\u00aa regi\u00e3o (8\u00ba lugar); SPPREV (3\u00ba lugar); IFES (2\u00ba lugar); e PMES. https:\/\/www.instagram.com\/proffrederico\/\",\"sameAs\":[\"https:\/\/www.instagram.com\/proffrederico\/\"],\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/xfredericohotmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Pens\u00e3o por morte para o CNU","description":"Resumo sobre o benef\u00edcio da pens\u00e3o por morte, visando ao CNU (Concurso Nacional Unificado), com base na legisla\u00e7\u00e3o.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/pensao-por-morte-cnu\/","og_locale":"pt_BR","og_type":"article","og_title":"Pens\u00e3o por morte para o CNU","og_description":"Resumo sobre o benef\u00edcio da pens\u00e3o por morte, visando ao CNU (Concurso Nacional Unificado), com base na legisla\u00e7\u00e3o.","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/pensao-por-morte-cnu\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2025-07-16T17:45:00+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/07\/04085332\/pensao-por-morte-para-o-cnu.png","type":"image\/png"}],"author":"Frederico Tadeu Borlot Peixoto","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Frederico Tadeu Borlot Peixoto","Est. tempo de leitura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/pensao-por-morte-cnu\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/pensao-por-morte-cnu\/"},"author":{"name":"Frederico Tadeu Borlot Peixoto","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/48a7e085e45aee7c3d4596399af50ebb"},"headline":"Pens\u00e3o por morte para o CNU","datePublished":"2025-07-16T17:45:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/pensao-por-morte-cnu\/"},"wordCount":1521,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/pensao-por-morte-cnu\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/07\/04085332\/pensao-por-morte-para-o-cnu.png","articleSection":["Concursos P\u00fablicos","Educa\u00e7\u00e3o","Executivo (Administrativa)","Previdenci\u00e1ria (INSS, PREVIC)","Sa\u00fade"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/pensao-por-morte-cnu\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"accessibilityFeature":["tableOfContents"]},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/pensao-por-morte-cnu\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/pensao-por-morte-cnu\/","name":"Pens\u00e3o por morte para o CNU","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/pensao-por-morte-cnu\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/pensao-por-morte-cnu\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/07\/04085332\/pensao-por-morte-para-o-cnu.png","datePublished":"2025-07-16T17:45:00+00:00","description":"Resumo sobre o benef\u00edcio da pens\u00e3o por morte, visando ao CNU (Concurso Nacional Unificado), com base na legisla\u00e7\u00e3o.","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/pensao-por-morte-cnu\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/pensao-por-morte-cnu\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/pensao-por-morte-cnu\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/07\/04085332\/pensao-por-morte-para-o-cnu.png","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/07\/04085332\/pensao-por-morte-para-o-cnu.png","width":1080,"height":1080,"caption":"Pens\u00e3o por morte para o CNU"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/pensao-por-morte-cnu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Pens\u00e3o por morte para o CNU"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/48a7e085e45aee7c3d4596399af50ebb","name":"Frederico Tadeu Borlot Peixoto","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/df8a49e2321c1e32f85e9e7c2a9c92c688f1f53a947220f40017ff5858b09fdb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/df8a49e2321c1e32f85e9e7c2a9c92c688f1f53a947220f40017ff5858b09fdb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/df8a49e2321c1e32f85e9e7c2a9c92c688f1f53a947220f40017ff5858b09fdb?s=96&d=mm&r=g","caption":"Frederico Tadeu Borlot Peixoto"},"description":"Analista Judici\u00e1rio - \u00c1rea Judici\u00e1ria do TRF da 4\u00aa regi\u00e3o. Bacharel em Direito. P\u00f3s-graduado em Direito Administrativo, Legisla\u00e7\u00e3o Penal Especial, Direito Penal e Direito Processual Penal. Tamb\u00e9m nomeado no TRF da 3\u00aa regi\u00e3o (8\u00ba lugar); SPPREV (3\u00ba lugar); IFES (2\u00ba lugar); e PMES. https:\/\/www.instagram.com\/proffrederico\/","sameAs":["https:\/\/www.instagram.com\/proffrederico\/"],"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/xfredericohotmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1601902","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/2567"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1601902"}],"version-history":[{"count":2,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1601902\/revisions"}],"predecessor-version":[{"id":1601916,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1601902\/revisions\/1601916"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/1601914"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1601902"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1601902"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1601902"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1601902"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}