{"id":1600198,"date":"2025-07-01T22:54:01","date_gmt":"2025-07-02T01:54:01","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=1600198"},"modified":"2025-07-09T18:24:55","modified_gmt":"2025-07-09T21:24:55","slug":"concurso-tce-mg-cotas-trans","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tce-mg-cotas-trans\/","title":{"rendered":"Concurso TCE MG ter\u00e1 cotas para transg\u00eaneros; edital final de julho!"},"content":{"rendered":"\n<p style=\"font-size:clamp(16.293px, 1.018rem + ((1vw - 3.2px) * 0.854), 25px);\"><em><strong>Durante evento da comunidade LGBTQ+, presidente anuncia que novo concurso TCE MG ter\u00e1 cotas para transg\u00eaneros!<\/strong><\/em><\/p>\n\n\n\n<p>O que muitos j\u00e1 sabem \u00e9 que um novo edital de concurso para o <strong>TCE MG (<a href=\"https:\/\/www.estrategiaconcursos.com.br\/cursosPorConcurso\/tce-mg\/\" target=\"_blank\" rel=\"noreferrer noopener\">Tribunal de Contas do Estado de Minas Gerais<\/a>)<\/strong> finalmente vai sair em 2025!<\/p>\n\n\n\n<p>Mais uma novidade quent\u00edssima que acabou de sair, nesta ter\u00e7a-feira (1\u00ba), \u00e9 que o certame do \u00f3rg\u00e3o de controle mineiro ser\u00e1 o primeiro <strong>da hist\u00f3ria<\/strong> <strong>brasileira<\/strong> a ter cotas para transg\u00eaneros.<\/p>\n\n\n\n<p>A informa\u00e7\u00e3o foi confirmada pelo pr\u00f3prio presidente do <strong>TCE MG<\/strong>, Durval \u00c2ngelo, que, na abertura do evento \u201cSemana do Orgulho LGBTQIAPN+: Vozes, Cores e Resist\u00eancia \u2013 A Diversidade que Transforma, promovida pelo TCEMG\u201d, revelou a novidade.<\/p>\n\n\n\n<p><em>\u201cO conselheiro relator, Licurgo Mour\u00e3o, incluiu, no edital do novo concurso do TCEMG, cota para pessoas transg\u00eanero. Vamos votar o edital no Tribunal Pleno do dia 09\/07. Seremos o primeiro Tribunal no Brasil que, no seu concurso p\u00fablico, incluir\u00e1 cotas para pessoas transg\u00eanero\u201d<\/em>, afirmou Durval, destacando a necessidade urgente da busca pela igualdade e oportunidades para todos e todas.<\/p>\n\n\n\n<p>Agora, o tribunal votar\u00e1 acerca da publica\u00e7\u00e3o e dos detalhes do edital de abertura no dia <strong>9 de julho<\/strong>, conforme informa\u00e7\u00f5es exclusivas apuradas pela nossa jornalista Tha\u00eds Mendes.<\/p>\n\n\n\n<p>Lembrando que a abertura do concurso acontecer\u00e1 <strong>at\u00e9 este m\u00eas<\/strong>, isso de acordo com a primeira portaria de defini\u00e7\u00e3o da comiss\u00e3o organizadora. <\/p>\n\n\n\n<p>Ser\u00e3o ofertadas oportunidades imediatas para o cargo de <strong>Auditor de Controle Externo<\/strong>, cujo sal\u00e1rio inicial \u00e9 de <strong>R$ 12 mil<\/strong> mais o <strong>adicional de desempenho<\/strong>.<\/p>\n\n\n\n<p>Outro ponto importante \u00e9 que o Tribunal de Contas estuda a possibilidade de oferecer vagas para<strong> todas as especialidades do cargo<\/strong>. <\/p>\n\n\n\n<p>No entanto, a prioridade ser\u00e1 para a \u00e1rea de<strong> Ci\u00eancias da Computa\u00e7\u00e3o (TI)<\/strong>, por ser a que apresenta maior necessidade de reposi\u00e7\u00e3o de pessoal.<\/p>\n\n\n\n<div class=\"container\" id=\"boxes\">\n  <div class=\"row\">\n\n    <div class=\"col-sm\">\n      <div class=\"banner-sncp\" id=\"box-assinatura\">\n        <p class=\"titulo-assinatura\" style=\"text-align: left;\">\n          <strong>\n            <span style=\"display: block; font-size: 0.95em; line-height: 1.3;\">SEMANA NACIONAL DOS<\/span>\n            <span style=\"display: block; font-size: 0.95em; color: #f5e188; line-height: 1.3;\">CONCURSOS P\u00daBLICOS<\/span>\n          <\/strong>\n        <\/p>\n <p class=\"subtitulo-assinatura\" style=\"text-align: left;\">Estabilidade para a vida toda \u2b50<\/p> \n          <div class=\"box-botao\" style=\"text-align: left;\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/mkt.estrategia.com\/concursos\/semana-nacional-dos-concursos-publicos-2025-publ-frio\/?utm_source=blog&#038;utm_medium=artigo&#038;utm_campaign=sndc-concurso-tce-mg\" role=\"button\" rel=\"noopener noreferrer\">QUERO SER CONCURSADO!<\/a>\n        <\/div>\n      <\/div>\n    <\/div>\n\n  <\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-tce-mg-composicao-dos-salarios-do-novo-concurso\">TCE MG: composi\u00e7\u00e3o dos sal\u00e1rios do novo concurso<\/h2>\n\n\n\n<p>Vale lembrar que a mudan\u00e7a no cargo n\u00e3o afetar\u00e1 os requisitos exigidos, muito menos o sal\u00e1rio inicial que consta em lei. A carreira possui um vencimento inicial de&nbsp;<strong>R$ 12.502,85<\/strong>, mais o&nbsp;<strong>adicional de desempenho<\/strong>.<\/p>\n\n\n\n<p>Al\u00e9m disso, o cargo conta com um total de <strong>4 categorias<\/strong>, com a possibilidade do servidor ser promovido ao longo do tempo, subindo de classe, com aumentos salariais progressivos.<\/p>\n\n\n\n<p>Confira mais detalhes acerca dos sal\u00e1rios do cargo de Auditor do pr\u00f3ximo concurso TCE MG:<\/p>\n\n\n\n<figure class=\"wp-block-table is-style-stripes\"><table><thead><tr><th class=\"has-text-align-center\" data-align=\"center\">CARGO<\/th><th class=\"has-text-align-center\" data-align=\"center\">CATEGORIA<\/th><th class=\"has-text-align-center\" data-align=\"center\">CLASSE<\/th><th class=\"has-text-align-center\" data-align=\"center\">VAGAS<\/th><th class=\"has-text-align-center\" data-align=\"center\">SAL\u00c1RIO<\/th><\/tr><\/thead><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\" rowspan=\"11\">Auditor de Controle Externo<\/td><td class=\"has-text-align-center\" data-align=\"center\" rowspan=\"3\">Terceira<\/td><td class=\"has-text-align-center\" data-align=\"center\">3\u00aa classe<\/td><td class=\"has-text-align-center\" data-align=\"center\">1000<\/td><td class=\"has-text-align-center\" data-align=\"center\">R$ 12.935,41<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">2\u00aa classe<\/td><td class=\"has-text-align-center\" data-align=\"center\">1000<\/td><td class=\"has-text-align-center\" data-align=\"center\">R$ 14.228,95<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">1\u00aa classe<\/td><td class=\"has-text-align-center\" data-align=\"center\">800<\/td><td class=\"has-text-align-center\" data-align=\"center\">R$ 15.522,49<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\" rowspan=\"3\">Segunda<\/td><td class=\"has-text-align-center\" data-align=\"center\">3\u00aa classe<\/td><td class=\"has-text-align-center\" data-align=\"center\">800<\/td><td class=\"has-text-align-center\" data-align=\"center\">R$ 18.109,57<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">2\u00aa classe<\/td><td class=\"has-text-align-center\" data-align=\"center\">600<\/td><td class=\"has-text-align-center\" data-align=\"center\">R$ 19.403,11<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">1\u00aa classe<\/td><td class=\"has-text-align-center\" data-align=\"center\">600<\/td><td class=\"has-text-align-center\" data-align=\"center\">R$ 20.696,65<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\" rowspan=\"3\">Primeira<\/td><td class=\"has-text-align-center\" data-align=\"center\">3\u00aa classe<\/td><td class=\"has-text-align-center\" data-align=\"center\">400<\/td><td class=\"has-text-align-center\" data-align=\"center\">R$ 23.283,73<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">2\u00aa classe<\/td><td class=\"has-text-align-center\" data-align=\"center\">400<\/td><td class=\"has-text-align-center\" data-align=\"center\">R$ 24.577,27<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">1\u00aa classe<\/td><td class=\"has-text-align-center\" data-align=\"center\">300<\/td><td class=\"has-text-align-center\" data-align=\"center\">R$ 25.870,81<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\" rowspan=\"2\">Especial<\/td><td class=\"has-text-align-center\" data-align=\"center\">2\u00aa classe<\/td><td class=\"has-text-align-center\" data-align=\"center\">200<\/td><td class=\"has-text-align-center\" data-align=\"center\">R$ 28.457,90<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">1\u00aa classe<\/td><td class=\"has-text-align-center\" data-align=\"center\">100<\/td><td class=\"has-text-align-center\" data-align=\"center\">R$ 29.751,44<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p class=\"has-text-align-center\"><em>Quer saber mais sobre o cargo e outras disposi\u00e7\u00f5es do concurso <a href=\"https:\/\/www.tce.mg.gov.br\/\" target=\"_blank\" rel=\"noreferrer noopener\">TCE MG<\/a>, al\u00e9m de cotas para transg\u00eaneros? Ent\u00e3o, acesse agora mesmo o nosso artigo completo:<\/em><\/p>\n\n\n\n<p class=\"has-text-align-center has-background has-medium-font-size\" style=\"background-color:#e3f4fe\"><strong>SAIBA TUDO SOBRE O <a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tce-mg\/\" target=\"_blank\" rel=\"noreferrer noopener\">CONCURSO TCE MG<\/a><\/strong><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"cursos-assinatura\">Quer saber tudo sobre concursos previstos?<br \/>Confira nossos artigos!<\/h2>\n\n\n\n<div class=\"container\" id=\"boxes\">\n  <div class=\"row\">\n\n    <div class=\"col-sm\">\n      <div class=\"estrategia\" id=\"box-assinatura\">\n        <h3 class=\"titulo-assinatura\">Assinatura Concursos<\/h3>\n        <p class=\"subtitulo-assinatura\">Assinatura de 1 ano ou 2 anos<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/assinaturas\/\" role=\"button\" rel=\"noopener noreferrer\">ASSINE AGORA<\/a>\n        <\/div>\n      <\/div><\/div><\/div><\/div>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos Abertos<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-controle\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos Controle<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2025\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos 2025<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2026\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos 2026<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Durante evento da comunidade LGBTQ+, presidente anuncia que novo concurso TCE MG ter\u00e1 cotas para transg\u00eaneros! O que muitos j\u00e1 sabem \u00e9 que um novo edital de concurso para o TCE MG (Tribunal de Contas do Estado de Minas Gerais) finalmente vai sair em 2025! Mais uma novidade quent\u00edssima que acabou de sair, nesta ter\u00e7a-feira [&hellip;]<\/p>\n","protected":false},"author":2692,"featured_media":1185014,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"news","footnotes":""},"categories":[214710,220219],"tags":[],"tax_estado":[219974],"class_list":["post-1600198","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tribunais-de-contas","category-noticias","tax_estado-mg"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Concurso TCE MG ter\u00e1 cotas para transg\u00eaneros; edital final de julho!<\/title>\n<meta name=\"description\" content=\"O concurso do Tribunal de Contas do Estado de Minas Gerais (TCE MG) de 2025 ser\u00e1 o primeiro certame no Brasil a ter cotas para transg\u00eaneros!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tce-mg-cotas-trans\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Concurso TCE MG ter\u00e1 cotas para transg\u00eaneros; edital final de julho!\" \/>\n<meta property=\"og:description\" content=\"O concurso do Tribunal de Contas do Estado de Minas Gerais (TCE MG) de 2025 ser\u00e1 o primeiro certame no Brasil a ter cotas para transg\u00eaneros!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tce-mg-cotas-trans\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-02T01:54:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-09T21:24:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/03\/10164823\/tce-mg.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"432\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ronaldo Scanavini Neto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ronaldo Scanavini Neto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tce-mg-cotas-trans\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tce-mg-cotas-trans\/\"},\"author\":{\"name\":\"Ronaldo Scanavini Neto\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/70c2ad4297aa24ff8815b08215b23a76\"},\"headline\":\"Concurso TCE MG ter\u00e1 cotas para transg\u00eaneros; edital final de julho!\",\"datePublished\":\"2025-07-02T01:54:01+00:00\",\"dateModified\":\"2025-07-09T21:24:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tce-mg-cotas-trans\/\"},\"wordCount\":523,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tce-mg-cotas-trans\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/03\/10164823\/tce-mg.jpg\",\"articleSection\":[\"Tribunais de Contas (TCU, TCE, TCM)\",\"\u00daltimas not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tce-mg-cotas-trans\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tce-mg-cotas-trans\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tce-mg-cotas-trans\/\",\"name\":\"Concurso TCE MG ter\u00e1 cotas para transg\u00eaneros; edital final de julho!\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tce-mg-cotas-trans\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tce-mg-cotas-trans\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/03\/10164823\/tce-mg.jpg\",\"datePublished\":\"2025-07-02T01:54:01+00:00\",\"dateModified\":\"2025-07-09T21:24:55+00:00\",\"description\":\"O concurso do Tribunal de Contas do Estado de Minas Gerais (TCE MG) de 2025 ser\u00e1 o primeiro certame no Brasil a ter cotas para transg\u00eaneros!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tce-mg-cotas-trans\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tce-mg-cotas-trans\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tce-mg-cotas-trans\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/03\/10164823\/tce-mg.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/03\/10164823\/tce-mg.jpg\",\"width\":768,\"height\":432,\"caption\":\"Inscri\u00e7\u00f5es ABERTAS para o concurso TCE MG\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tce-mg-cotas-trans\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Concurso TCE MG ter\u00e1 cotas para transg\u00eaneros; edital final de julho!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/70c2ad4297aa24ff8815b08215b23a76\",\"name\":\"Ronaldo Scanavini Neto\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/f93d8e56fe264596e94aee6b3feb737d98ad0fc5bac7eb0a245f04723c5c8f21?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f93d8e56fe264596e94aee6b3feb737d98ad0fc5bac7eb0a245f04723c5c8f21?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f93d8e56fe264596e94aee6b3feb737d98ad0fc5bac7eb0a245f04723c5c8f21?s=96&d=mm&r=g\",\"caption\":\"Ronaldo Scanavini Neto\"},\"description\":\"Graduando em Comunica\u00e7\u00e3o Social \u2013 Jornalismo pela Universidade Federal de Vi\u00e7osa (UFV). Integra a equipe de jornalismo do Estrat\u00e9gia Concursos desde 2023, atuando com \u00eanfase na cobertura da \u00e1rea fiscal. Tamb\u00e9m realiza a apura\u00e7\u00e3o e produ\u00e7\u00e3o de not\u00edcias sobre concursos federais, \u00f3rg\u00e3os participantes do CNU e das \u00e1reas de controle, gest\u00e3o, engenharia, Exame CFC, comunica\u00e7\u00e3o social TI e \u00e1rea de concursos administrativos.\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/ronaldo-netoestrategia-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Concurso TCE MG ter\u00e1 cotas para transg\u00eaneros; edital final de julho!","description":"O concurso do Tribunal de Contas do Estado de Minas Gerais (TCE MG) de 2025 ser\u00e1 o primeiro certame no Brasil a ter cotas para transg\u00eaneros!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tce-mg-cotas-trans\/","og_locale":"pt_BR","og_type":"article","og_title":"Concurso TCE MG ter\u00e1 cotas para transg\u00eaneros; edital final de julho!","og_description":"O concurso do Tribunal de Contas do Estado de Minas Gerais (TCE MG) de 2025 ser\u00e1 o primeiro certame no Brasil a ter cotas para transg\u00eaneros!","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tce-mg-cotas-trans\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2025-07-02T01:54:01+00:00","article_modified_time":"2025-07-09T21:24:55+00:00","og_image":[{"width":768,"height":432,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/03\/10164823\/tce-mg.jpg","type":"image\/jpeg"}],"author":"Ronaldo Scanavini Neto","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Ronaldo Scanavini Neto","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tce-mg-cotas-trans\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tce-mg-cotas-trans\/"},"author":{"name":"Ronaldo Scanavini Neto","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/70c2ad4297aa24ff8815b08215b23a76"},"headline":"Concurso TCE MG ter\u00e1 cotas para transg\u00eaneros; edital final de julho!","datePublished":"2025-07-02T01:54:01+00:00","dateModified":"2025-07-09T21:24:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tce-mg-cotas-trans\/"},"wordCount":523,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tce-mg-cotas-trans\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/03\/10164823\/tce-mg.jpg","articleSection":["Tribunais de Contas (TCU, TCE, TCM)","\u00daltimas not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tce-mg-cotas-trans\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tce-mg-cotas-trans\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tce-mg-cotas-trans\/","name":"Concurso TCE MG ter\u00e1 cotas para transg\u00eaneros; edital final de julho!","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tce-mg-cotas-trans\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tce-mg-cotas-trans\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/03\/10164823\/tce-mg.jpg","datePublished":"2025-07-02T01:54:01+00:00","dateModified":"2025-07-09T21:24:55+00:00","description":"O concurso do Tribunal de Contas do Estado de Minas Gerais (TCE MG) de 2025 ser\u00e1 o primeiro certame no Brasil a ter cotas para transg\u00eaneros!","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tce-mg-cotas-trans\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tce-mg-cotas-trans\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tce-mg-cotas-trans\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/03\/10164823\/tce-mg.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/03\/10164823\/tce-mg.jpg","width":768,"height":432,"caption":"Inscri\u00e7\u00f5es ABERTAS para o concurso TCE MG"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tce-mg-cotas-trans\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Concurso TCE MG ter\u00e1 cotas para transg\u00eaneros; edital final de julho!"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/70c2ad4297aa24ff8815b08215b23a76","name":"Ronaldo Scanavini Neto","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/f93d8e56fe264596e94aee6b3feb737d98ad0fc5bac7eb0a245f04723c5c8f21?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f93d8e56fe264596e94aee6b3feb737d98ad0fc5bac7eb0a245f04723c5c8f21?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f93d8e56fe264596e94aee6b3feb737d98ad0fc5bac7eb0a245f04723c5c8f21?s=96&d=mm&r=g","caption":"Ronaldo Scanavini Neto"},"description":"Graduando em Comunica\u00e7\u00e3o Social \u2013 Jornalismo pela Universidade Federal de Vi\u00e7osa (UFV). Integra a equipe de jornalismo do Estrat\u00e9gia Concursos desde 2023, atuando com \u00eanfase na cobertura da \u00e1rea fiscal. Tamb\u00e9m realiza a apura\u00e7\u00e3o e produ\u00e7\u00e3o de not\u00edcias sobre concursos federais, \u00f3rg\u00e3os participantes do CNU e das \u00e1reas de controle, gest\u00e3o, engenharia, Exame CFC, comunica\u00e7\u00e3o social TI e \u00e1rea de concursos administrativos.","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/ronaldo-netoestrategia-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1600198","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/2692"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1600198"}],"version-history":[{"count":5,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1600198\/revisions"}],"predecessor-version":[{"id":1604749,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1600198\/revisions\/1604749"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/1185014"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1600198"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1600198"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1600198"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1600198"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}