{"id":1600186,"date":"2025-07-01T20:36:20","date_gmt":"2025-07-01T23:36:20","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=1600186"},"modified":"2025-07-02T13:46:55","modified_gmt":"2025-07-02T16:46:55","slug":"concurso-unb-possiveis-recursos-tae","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-unb-possiveis-recursos-tae\/","title":{"rendered":"Concurso UNB: veja os poss\u00edveis recursos para TAE!"},"content":{"rendered":"\n<p>Neste domingo, 29 de junho, foram aplicadas as <strong>provas do concurso UNB (<a href=\"https:\/\/www.estrategiaconcursos.com.br\/cursosPorConcurso\/fundacao-universidade-de-brasilia-unb\/?utm_source=google&amp;utm_medium=cpc&amp;utm_campaign=ec-ge-vd-pmax-assinaturavitalicia-semesp-310325-vitalicia&amp;gad_source=1&amp;gbraid=0AAAAADpTrccqnvQouqsIhT2PMWGUE8rsv&amp;gclid=Cj0KCQjwhr6_BhD4ARIsAH1YdjA_6nFHxVt6nq2z7ITYfCgHMwWC20-AYcp8osOyIgRcHfJCv2NpGk0aApcsEALw_wcB\" target=\"_blank\" rel=\"noreferrer noopener\">Universidade de Bras\u00edlia<\/a>) <\/strong>para o cargo de <strong>T\u00e9cnico em Assuntos Educacionais (TAE)<\/strong>.<\/p>\n\n\n\n<p>Com isso, o prazo para interposi\u00e7\u00e3o de recursos ficar\u00e1 aberto entre os dias 02 e 03 de julho, diretamente na \u00e1rea do candidato no site do Cebraspe.<\/p>\n\n\n\n<p>E para te ajudar, assim como na <a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-unb-correcao-de-tae\/\" target=\"_blank\" rel=\"noreferrer noopener\">corre\u00e7\u00e3o extraoficial<\/a>, nossos professores identificaram algumas possibilidades de recursos para a avalia\u00e7\u00e3o. Veja abaixo:<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-very-light-gray-to-cyan-bluish-gray-gradient-background has-background\" id=\"ingles\">Concurso UNB: recursos de TAE<\/h2>\n\n\n\n<p><strong>QUEST\u00c3O 78<\/strong><\/p>\n\n\n\n<p>A partir dos objetivos desenhados, \u00e9 necess\u00e1rio criar uma ferramenta espec\u00edfica de avalia\u00e7\u00e3o capaz de avaliar dimens\u00f5es do treinamento referentes a custo, qualidade, servi\u00e7o, rapidez e resultados.<\/p>\n\n\n\n<p><strong>Gabarito preliminar: CERTO<\/strong><br \/><strong>Proposta: Anula\u00e7\u00e3o do item<\/strong><\/p>\n\n\n\n<p>Solicito a anula\u00e7\u00e3o da quest\u00e3o 78 por entender que a reda\u00e7\u00e3o da afirmativa compromete o princ\u00edpio da objetividade, ao permitir interpreta\u00e7\u00f5es amb\u00edguas e tecnicamente question\u00e1veis sobre a avalia\u00e7\u00e3o de programas de treinamento e desenvolvimento.<\/p>\n\n\n\n<p>O trecho &#8220;uma ferramenta espec\u00edfica de avalia\u00e7\u00e3o&#8221; pode induzir o candidato a compreender que uma \u00fanica ferramenta deve ser criada para avaliar, simultaneamente, todas as dimens\u00f5es mencionadas (custo, qualidade, servi\u00e7o, rapidez e resultados). Essa leitura literal est\u00e1 em desacordo com a teoria cl\u00e1ssica e a pr\u00e1tica profissional na \u00e1rea de gest\u00e3o de pessoas.<\/p>\n\n\n\n<p>Conforme aponta Idalberto Chiavenato, uma das principais refer\u00eancias bibliogr\u00e1ficas cobradas em provas da \u00e1rea, cada dimens\u00e3o do treinamento deve ser avaliada por meio de crit\u00e9rios pr\u00f3prios e instrumentos distintos, o que torna inadequada a ideia de uma ferramenta \u00fanica para fins t\u00e3o diversos:<\/p>\n\n\n\n<p>\u201cAs principais medidas para avaliar o treinamento s\u00e3o:<\/p>\n\n\n\n<p>\u2022 Custo: qual foi o valor investido no programa de treinamento?; \u2022 Qualidade: como o programa atendeu \u00e0s expectativas?; \u2022 Servi\u00e7o: o programa atendeu \u00e0s necessidades dos participantes?; \u2022 Rapidez: como o programa se ajustou aos novos desafios oferecidos?; e \u2022 Resultados: quais foram os resultados do programa?\u201d (CHIAVENATO, 2014, p. 327)<\/p>\n\n\n\n<p>Al\u00e9m disso, o mesmo autor complementa ao abordar os n\u00edveis de avalia\u00e7\u00e3o segundo o modelo de Kirkpatrick, reafirmando a necessidade de diferentes instrumentos para cada tipo de avalia\u00e7\u00e3o (rea\u00e7\u00e3o, aprendizagem, impacto, resultado e ROI), como entrevistas, observa\u00e7\u00f5es, testes, pesquisas de satisfa\u00e7\u00e3o e indicadores objetivos. Ele afirma:<\/p>\n\n\n\n<p>\u201cA avalia\u00e7\u00e3o do ROI em treinamento requer defini\u00e7\u00e3o pr\u00e9via de indicadores e mensuradores claros e objetivos. Os indicadores citados poder\u00e3o ser \u00fateis para verificar se o treinamento atingiu os objetivos e se valeu a pena.\u201d (CHIAVENATO, 2014, p. 328)<\/p>\n\n\n\n<p>Diante disso, a reda\u00e7\u00e3o do item 78 abre margem a interpreta\u00e7\u00f5es conflitantes, podendo induzir o candidato a erro, caso entenda que o termo \u201cuma ferramenta espec\u00edfica\u201d representa uma abordagem \u00fanica.<\/p>\n\n\n\n<p>Portanto, diante da ambiguidade da reda\u00e7\u00e3o, do poss\u00edvel induzimento ao erro e da contradi\u00e7\u00e3o com a bibliografia cl\u00e1ssica da \u00e1rea, solicito a anula\u00e7\u00e3o do item 78.<\/p>\n\n\n\n<p><strong>Refer\u00eancias<\/strong>:<\/p>\n\n\n\n<p><br \/>CHIAVENATO, Idalberto. <em>Gest\u00e3o de pessoas: o novo papel dos recursos humanos nas organiza\u00e7\u00f5es<\/em>. 4. ed. Rio de Janeiro: Elsevier, 2014. p. 327-328.<\/p>\n\n\n\n<p><strong>QUEST\u00c3O 119<\/strong><\/p>\n\n\n\n<p><strong>Gabarito preliminar:<\/strong> ERRADO<br \/><strong>Recurso: Solicita altera\u00e7\u00e3o para CERTO<\/strong><\/p>\n\n\n\n<p><strong>Justificativa t\u00e9cnica:<\/strong><\/p>\n\n\n\n<p>Solicita-se a altera\u00e7\u00e3o do gabarito da quest\u00e3o 119 para <strong>CERTO<\/strong>, uma vez que a assertiva est\u00e1 <strong>correta conforme a Nota T\u00e9cnica n\u00ba 5\/2023 do INEP<\/strong>, que descreve a <strong>metodologia estat\u00edstica de c\u00e1lculo do \u00cdndice Geral de Cursos (IGC)<\/strong>.<\/p>\n\n\n\n<p>A referida nota esclarece que conforme o enunciado da quest\u00e3o, <strong>ap\u00f3s a aplica\u00e7\u00e3o dos c\u00e1lculos estat\u00edsticos<\/strong> os <strong>cursos de gradua\u00e7\u00e3o e p\u00f3s-gradua\u00e7\u00e3o stricto sensu<\/strong> (mestrado e doutorado) s\u00e3o considerados na avalia\u00e7\u00e3o institucional, e que ambos contribuem para a nota do IGC, posterior a convers\u00e3o, s\u00e3o expressas <strong>em uma escala de 1 a 5<\/strong>.<\/p>\n\n\n\n<p>Conforme trecho da Nota T\u00e9cnica n\u00ba 5\/2023 \u2013 INEP (p. 3):<br \/><em>\u201c<\/em><em>O c\u00e1lculo do IGC, realizado por c\u00f3digo da IES, leva em considera\u00e7\u00e3o as seguintes informa\u00e7\u00f5es:<\/em><\/p>\n\n\n\n<p><strong><em>a)<\/em><\/strong><em> notas cont\u00ednuas de Conceitos Preliminares de Curso referentes aos cursos de gradua\u00e7\u00e3o avaliados no tri\u00eanio 2019-2021-2022, calculadas conforme metodologias apresentadas nas Notas T\u00e9cnicas do Inep n\u00bas 58\/2020\/CGCQES\/DAES, 9\/2022\/CGCQES\/DAES e 4\/2023\/CEI\/CGGI\/DAES, respectivamente, considerando o CPC mais recentemente publicado para cada curso;<\/em><\/p>\n\n\n\n<p><strong><em>b)<\/em><\/strong><em> n\u00famero de matr\u00edculas nos cursos de gradua\u00e7\u00e3o (estudantes cursando ou formandos no ano de refer\u00eancia do CPC), conforme base de dados oficial do Censo da Educa\u00e7\u00e3o Superior, cujos per\u00edodos de informa\u00e7\u00e3o e de confer\u00eancia, ajustes e valida\u00e7\u00e3o dos dados pelas IES foram definidos na Portaria Inep n\u00ba 525, de 29 de novembro de 2022, e na Portaria Inep n\u00ba 538, de 15 de dezembro de 2022;<\/em><\/p>\n\n\n\n<p><strong><em>c)<\/em><\/strong><em> conceitos dos cursos de Mestrado e Doutorado atribu\u00eddos pela Capes na \u00faltima avalia\u00e7\u00e3o divulgada oficialmente, para os programas de p\u00f3s-gradua\u00e7\u00e3o reconhecidos, incluindo a avalia\u00e7\u00e3o dos novos programas recomendados para o ano de refer\u00eancia do IGC, conforme base de dados oficial encaminhada pela Capes ao Inep; e<\/em><\/p>\n\n\n\n<p><strong><em>d)<\/em><\/strong><em> n\u00famero de matr\u00edculas (matriculados e titulados em 2022) nos cursos de Mestrado e Doutorado, conforme base de dados oficial encaminhada pela Capes ao Inep, nos termos previstos na Portaria Capes n\u00ba 50, de 22 de mar\u00e7o de 2023 e na Portaria Capes n\u00ba 312, de 28 de dezembro de 2022, no Manual de Coleta de Dados: conceitos e Orienta\u00e7\u00f5es da Capes.<\/em><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"506\" height=\"207\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/07\/01203510\/image-30.png\" alt=\"\" class=\"wp-image-1600187\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/07\/01203510\/image-30.png 506w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/07\/01203510\/image-30-300x123.png 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/07\/01203510\/image-30-150x61.png 150w\" sizes=\"auto, (max-width: 506px) 100vw, 506px\" \/><\/figure>\n\n\n\n<p>Portanto, no contexto da <strong>avalia\u00e7\u00e3o institucional<\/strong>, \u00e9 correto afirmar que os cursos de gradua\u00e7\u00e3o e p\u00f3s-gradua\u00e7\u00e3o s\u00e3o avaliados <strong>em uma escala de 1 a 5<\/strong>, conforme consta na quest\u00e3o.<\/p>\n\n\n\n<p><strong>Solicita-se, portanto, a altera\u00e7\u00e3o do gabarito preliminar de ERRADO para CERTO.<\/strong><\/p>\n\n\n\n<p><strong>Fonte normativa:<\/strong><\/p>\n\n\n\n<p>INEP \u2013 <strong>Nota T\u00e9cnica n\u00ba 5\/2023 \u2013 CEI\/Cggi\/DAES<\/strong><br \/><em>(Descri\u00e7\u00e3o da metodologia de c\u00e1lculo do IGC). Dispon\u00edvel em: <\/em><a href=\"https:\/\/download.inep.gov.br\/educacao_superior\/enade\/notas_tecnicas\/2023\/nota_tecnica_n_5_2023_cei_cggi_daes_descricao_da_metodologia_de_calculo_do_igc.pdf\"><em>https:\/\/download.inep.gov.br\/educacao_superior\/enade\/notas_tecnicas\/2023\/nota_tecnica_n_5_2023_cei_cggi_daes_descricao_da_metodologia_de_calculo_do_igc.pdf<\/em><\/a><em><\/em><\/p>\n\n\n\n<p><strong>QUEST\u00c3O 107<\/strong><\/p>\n\n\n\n<p><strong>Gabarito extraoficial: Correta<br \/>Gabarito banca: Errada<\/strong><\/p>\n\n\n\n<p>An\u00e1lise: a banca est\u00e1 correta<\/p>\n\n\n\n<p>Justificativa: De acordo com a LDB 9394\/96 o artigo 46, em todos seus par\u00e1grafos, salienta-se a n\u00e3o penalidade do aluno. Por isso, a Portaria 40\/2007 (n\u00b0 40 de 12 de dezembro de 2007) estabelece no artigo 30, par\u00e1grafo s\u00e9timo: \u201c\u00a7 7\u00ba Mantido o entendimento desfavor\u00e1vel pela CES\/CNE, com a homologa\u00e7\u00e3o ministerial, a decis\u00e3o importar\u00e1 indeferimento do pedido de autoriza\u00e7\u00e3o ou reconhecimento e, neste caso, de transfer\u00eancia dos alunos ou deferimento para efeito de expedi\u00e7\u00e3o de diplomas, vedado, em qualquer caso, o ingresso de novos alunos\u201d. Em outras palavras, o aluno dever\u00e1 ser transferido para outra institui\u00e7\u00e3o de ensino.<\/p>\n\n\n\n<p><strong>QUEST\u00c3O 108<\/strong><\/p>\n\n\n\n<p><strong>Gabarito extraoficial: Correta<br \/>Gabarito banca: Errada<\/strong><\/p>\n\n\n\n<p>An\u00e1lise: a banca est\u00e1 correta<\/p>\n\n\n\n<p>Justificativa: De acordo com a LDB 9394\/96 o artigo 9\u00ba, item IX, responsabiliza-se a uni\u00e3o pela autoriza\u00e7\u00e3o dos cursos de gradua\u00e7\u00e3o na educa\u00e7\u00e3o superior. De forma complementar, a Lei n\u00ba 10.870, de 19 de maio de 2004, no seu artigo 1\u00ba, institui o INEP (Instituo Nacional de Estudos e Pesquisas Educacionais) como recebedor de taxas de avalia\u00e7\u00e3o de credenciamento. Por isso, n\u00e3o \u00e9 poss\u00edvel afirmar que h\u00e1 uma autoriza\u00e7\u00e3o pr\u00e9via do MEC (Minist\u00e9rio da Educa\u00e7\u00e3o) para cursos de gradua\u00e7\u00e3o. Portanto, a responsabilidade do credenciamento \u00e9 do INEP, n\u00e3o existindo par\u00e2metro legal de autoriza\u00e7\u00e3o pr\u00e9via do MEC.<\/p>\n\n\n\n<p><strong>QUEST\u00c3O 111<\/strong><\/p>\n\n\n\n<p><strong>Gabarito extraoficial: Correta<br \/>Gabarito banca: Errada<\/strong><\/p>\n\n\n\n<p>An\u00e1lise: recurso para anula\u00e7\u00e3o da quest\u00e3o<\/p>\n\n\n\n<p>A assertiva possui ambiguidade em rela\u00e7\u00e3o aos acontecimentos hist\u00f3ricos e ao pr\u00f3prio conceito sistema de avalia\u00e7\u00e3o da educa\u00e7\u00e3o superior. A banca considera que o Exame Nacional de Cursos (ENC), implementado logo ap\u00f3s a LDB 9394\/96, como um sistema de avalia\u00e7\u00e3o da educa\u00e7\u00e3o superior. H\u00e1 uma confus\u00e3o de conceitos entre o que \u00e9 sistema de avalia\u00e7\u00e3o e o que \u00e9 exame de curso. Sistema de avalia\u00e7\u00e3o \u00e9 todo um conjunto de regras e de monitoramento. Exame \u00e9 uma prova \u00fanica aplicada com a finalidade de extra\u00e7\u00e3o de dados. O Sistema Nacional de Avalia\u00e7\u00e3o da Educa\u00e7\u00e3o Superior (SINAES) somente ocorreu em 2004. &nbsp;H\u00e1 autores que consideram o ENC como o in\u00edcio de um sistema de avalia\u00e7\u00e3o de da educa\u00e7\u00e3o superior, por\u00e9m h\u00e1 outros que validam apenas o SINAES.<\/p>\n\n\n\n<p>A ambiguidade reside em duas interpreta\u00e7\u00f5es poss\u00edveis: 1- considerar o ENC como um sistema de avalia\u00e7\u00e3o propriamente dito. 2- considerar o SINAES como, efetivamente, um sistema de avalia\u00e7\u00e3o da educa\u00e7\u00e3o superior.<\/p>\n\n\n\n<p><strong>QUEST\u00c3O 114<\/strong><\/p>\n\n\n\n<p><strong>Gabarito extraoficial: Errada<br \/>Gabarito banca: Correta<\/strong><\/p>\n\n\n\n<p>An\u00e1lise: recurso para considerar a quest\u00e3o errada<\/p>\n\n\n\n<p>A avalia\u00e7\u00e3o institucional \u00e9 um recurso para monitorar as dificuldades e as facilidades das institui\u00e7\u00f5es educativas. Nesse sentido, n\u00e3o pode ser utilizada para \u201cfomentar pol\u00edticas p\u00fablicas\u201d, uma vez que sua finalidade \u00e9 circunscrita apenas na pr\u00f3pria institui\u00e7\u00e3o de educa\u00e7\u00e3o superior (IES). A avalia\u00e7\u00e3o externa em larga escala seria uma op\u00e7\u00e3o mais adequada para fomentar pol\u00edticas p\u00fablicas.<\/p>\n\n\n\n<p class=\"has-text-align-center has-cyan-bluish-gray-background-color has-background has-medium-font-size\"><strong>Saiba mais: <a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-unb\/\" target=\"_blank\" rel=\"noreferrer noopener\">UNB<\/a><\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"h-quer-saber-tudo-sobre-concursos-previstos-confira-nossos-artigos\">Quer saber tudo sobre concursos previstos?<br \/>Confira  nossos artigos!<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos abertos<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2025\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos 2025<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2026\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos 2026<\/a><\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"h-quer-estudar-para-o-concurso-unb\">Quer estudar para o concurso UNB?<\/h2>\n\n\n\n<div class=\"container\" id=\"boxes\">\n  <div class=\"row\">\n\n    <div class=\"col-sm\">\n      <div class=\"banner-estrategia\" id=\"box-assinatura\">\n        <h3 class=\"titulo-assinatura\">Cursos para concursos<\/h3>\n        <p class=\"subtitulo-assinatura\">Estude conosco<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/cursos\/\" role=\"button\" rel=\"noopener noreferrer\">Conhe\u00e7a os cursos<\/a>\n        <\/div>\n      <\/div>\n     \n    <\/div>\n\n  <\/div>\n<\/div>\n\n\n\n<div class=\"container\" id=\"boxes\">\n  <div class=\"row\">\n\n    <div class=\"col-sm\">\n      <div class=\"estrategia\" id=\"box-assinatura\">\n        <h3 class=\"titulo-assinatura\">Assinatura de Concursos<\/h3>\n        <p class=\"subtitulo-assinatura\">Assinatura de 1 ano ou 2 anos<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/assinaturas\/\" role=\"button\" rel=\"noopener noreferrer\">ASSINE AGORA<\/a>\n        <\/div>\n      <\/div>\n     \n    <\/div><\/div><\/div>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Neste domingo, 29 de junho, foram aplicadas as provas do concurso UNB (Universidade de Bras\u00edlia) para o cargo de T\u00e9cnico em Assuntos Educacionais (TAE). Com isso, o prazo para interposi\u00e7\u00e3o de recursos ficar\u00e1 aberto entre os dias 02 e 03 de julho, diretamente na \u00e1rea do candidato no site do Cebraspe. E para te ajudar, [&hellip;]<\/p>\n","protected":false},"author":2134,"featured_media":1557734,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"news","footnotes":""},"categories":[3766,220219],"tags":[],"tax_estado":[219970],"class_list":["post-1600186","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacional","category-noticias","tax_estado-df"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Concurso UNB: veja os poss\u00edveis recursos para TAE!<\/title>\n<meta name=\"description\" content=\"Confira neste artigo que preparamos quais s\u00e3o as quest\u00f5es pass\u00edveis de recursos das provas do concurso UNB para TAE!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-unb-possiveis-recursos-tae\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Concurso UNB: veja os poss\u00edveis recursos para TAE!\" \/>\n<meta property=\"og:description\" content=\"Confira neste artigo que preparamos quais s\u00e3o as quest\u00f5es pass\u00edveis de recursos das provas do concurso UNB para TAE!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-unb-possiveis-recursos-tae\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-01T23:36:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-02T16:46:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/04\/04090617\/concurso-unb.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"432\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Rafaela Teixeira\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rafaela Teixeira\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-unb-possiveis-recursos-tae\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-unb-possiveis-recursos-tae\/\"},\"author\":{\"name\":\"Rafaela Teixeira\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/e75352021ea7f60781c599934f916eb1\"},\"headline\":\"Concurso UNB: veja os poss\u00edveis recursos para TAE!\",\"datePublished\":\"2025-07-01T23:36:20+00:00\",\"dateModified\":\"2025-07-02T16:46:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-unb-possiveis-recursos-tae\/\"},\"wordCount\":1528,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-unb-possiveis-recursos-tae\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/04\/04090617\/concurso-unb.jpg\",\"articleSection\":[\"Educa\u00e7\u00e3o\",\"\u00daltimas not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-unb-possiveis-recursos-tae\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-unb-possiveis-recursos-tae\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-unb-possiveis-recursos-tae\/\",\"name\":\"Concurso UNB: veja os poss\u00edveis recursos para TAE!\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-unb-possiveis-recursos-tae\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-unb-possiveis-recursos-tae\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/04\/04090617\/concurso-unb.jpg\",\"datePublished\":\"2025-07-01T23:36:20+00:00\",\"dateModified\":\"2025-07-02T16:46:55+00:00\",\"description\":\"Confira neste artigo que preparamos quais s\u00e3o as quest\u00f5es pass\u00edveis de recursos das provas do concurso UNB para TAE!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-unb-possiveis-recursos-tae\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-unb-possiveis-recursos-tae\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-unb-possiveis-recursos-tae\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/04\/04090617\/concurso-unb.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/04\/04090617\/concurso-unb.jpg\",\"width\":768,\"height\":432,\"caption\":\"campis do concurso UNB\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-unb-possiveis-recursos-tae\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Concurso UNB: veja os poss\u00edveis recursos para TAE!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/e75352021ea7f60781c599934f916eb1\",\"name\":\"Rafaela Teixeira\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/8a349a2b22039b1ee88fc06461487c950fd6aa411ea8af8633314b43334ae793?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8a349a2b22039b1ee88fc06461487c950fd6aa411ea8af8633314b43334ae793?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8a349a2b22039b1ee88fc06461487c950fd6aa411ea8af8633314b43334ae793?s=96&d=mm&r=g\",\"caption\":\"Rafaela Teixeira\"},\"description\":\"Rafaela Teixeira \u00e9 advogada conveniada \u00e0 Defensoria P\u00fablica de S\u00e3o Paulo pela OAB, com experi\u00eancia em reda\u00e7\u00e3o jur\u00eddica e atua\u00e7\u00e3o em institui\u00e7\u00f5es p\u00fablicas, incluindo est\u00e1gio no TRE-SP. Possui mais de 7 anos de experi\u00eancia na produ\u00e7\u00e3o de conte\u00fados voltados ao nicho de concursos p\u00fablicos, com foco em apura\u00e7\u00e3o jornal\u00edstica cont\u00ednua, an\u00e1lise de editais e obten\u00e7\u00e3o de informa\u00e7\u00f5es diretamente junto a \u00f3rg\u00e3os e fontes oficiais. No Blog do Estrat\u00e9gia Concursos, atua como Analista de Conte\u00fado S\u00eanior, respons\u00e1vel pelo jornalismo do per\u00edodo noturno e da madrugada, com atua\u00e7\u00e3o transversal na cobertura de concursos p\u00fablicos, garantindo a continuidade, fluidez e confiabilidade das publica\u00e7\u00f5es e dos bastidores dos certames.\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/rafaela-teixeira\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Concurso UNB: veja os poss\u00edveis recursos para TAE!","description":"Confira neste artigo que preparamos quais s\u00e3o as quest\u00f5es pass\u00edveis de recursos das provas do concurso UNB para TAE!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-unb-possiveis-recursos-tae\/","og_locale":"pt_BR","og_type":"article","og_title":"Concurso UNB: veja os poss\u00edveis recursos para TAE!","og_description":"Confira neste artigo que preparamos quais s\u00e3o as quest\u00f5es pass\u00edveis de recursos das provas do concurso UNB para TAE!","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-unb-possiveis-recursos-tae\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2025-07-01T23:36:20+00:00","article_modified_time":"2025-07-02T16:46:55+00:00","og_image":[{"width":768,"height":432,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/04\/04090617\/concurso-unb.jpg","type":"image\/jpeg"}],"author":"Rafaela Teixeira","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Rafaela Teixeira","Est. tempo de leitura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-unb-possiveis-recursos-tae\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-unb-possiveis-recursos-tae\/"},"author":{"name":"Rafaela Teixeira","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/e75352021ea7f60781c599934f916eb1"},"headline":"Concurso UNB: veja os poss\u00edveis recursos para TAE!","datePublished":"2025-07-01T23:36:20+00:00","dateModified":"2025-07-02T16:46:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-unb-possiveis-recursos-tae\/"},"wordCount":1528,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-unb-possiveis-recursos-tae\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/04\/04090617\/concurso-unb.jpg","articleSection":["Educa\u00e7\u00e3o","\u00daltimas not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-unb-possiveis-recursos-tae\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-unb-possiveis-recursos-tae\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-unb-possiveis-recursos-tae\/","name":"Concurso UNB: veja os poss\u00edveis recursos para TAE!","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-unb-possiveis-recursos-tae\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-unb-possiveis-recursos-tae\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/04\/04090617\/concurso-unb.jpg","datePublished":"2025-07-01T23:36:20+00:00","dateModified":"2025-07-02T16:46:55+00:00","description":"Confira neste artigo que preparamos quais s\u00e3o as quest\u00f5es pass\u00edveis de recursos das provas do concurso UNB para TAE!","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-unb-possiveis-recursos-tae\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-unb-possiveis-recursos-tae\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-unb-possiveis-recursos-tae\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/04\/04090617\/concurso-unb.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/04\/04090617\/concurso-unb.jpg","width":768,"height":432,"caption":"campis do concurso UNB"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-unb-possiveis-recursos-tae\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Concurso UNB: veja os poss\u00edveis recursos para TAE!"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/e75352021ea7f60781c599934f916eb1","name":"Rafaela Teixeira","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/8a349a2b22039b1ee88fc06461487c950fd6aa411ea8af8633314b43334ae793?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8a349a2b22039b1ee88fc06461487c950fd6aa411ea8af8633314b43334ae793?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8a349a2b22039b1ee88fc06461487c950fd6aa411ea8af8633314b43334ae793?s=96&d=mm&r=g","caption":"Rafaela Teixeira"},"description":"Rafaela Teixeira \u00e9 advogada conveniada \u00e0 Defensoria P\u00fablica de S\u00e3o Paulo pela OAB, com experi\u00eancia em reda\u00e7\u00e3o jur\u00eddica e atua\u00e7\u00e3o em institui\u00e7\u00f5es p\u00fablicas, incluindo est\u00e1gio no TRE-SP. Possui mais de 7 anos de experi\u00eancia na produ\u00e7\u00e3o de conte\u00fados voltados ao nicho de concursos p\u00fablicos, com foco em apura\u00e7\u00e3o jornal\u00edstica cont\u00ednua, an\u00e1lise de editais e obten\u00e7\u00e3o de informa\u00e7\u00f5es diretamente junto a \u00f3rg\u00e3os e fontes oficiais. No Blog do Estrat\u00e9gia Concursos, atua como Analista de Conte\u00fado S\u00eanior, respons\u00e1vel pelo jornalismo do per\u00edodo noturno e da madrugada, com atua\u00e7\u00e3o transversal na cobertura de concursos p\u00fablicos, garantindo a continuidade, fluidez e confiabilidade das publica\u00e7\u00f5es e dos bastidores dos certames.","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/rafaela-teixeira\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1600186","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/2134"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1600186"}],"version-history":[{"count":4,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1600186\/revisions"}],"predecessor-version":[{"id":1600619,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1600186\/revisions\/1600619"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/1557734"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1600186"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1600186"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1600186"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1600186"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}