{"id":1593598,"date":"2025-06-18T19:17:49","date_gmt":"2025-06-18T22:17:49","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=1593598"},"modified":"2025-06-19T09:53:22","modified_gmt":"2025-06-19T12:53:22","slug":"cnu-2025-orgaos","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-orgaos\/","title":{"rendered":"CNU 2025: quais \u00f3rg\u00e3os tamb\u00e9m estiveram na edi\u00e7\u00e3o anterior?"},"content":{"rendered":"\n<p style=\"font-size:clamp(16.293px, 1.018rem + ((1vw - 3.2px) * 0.854), 25px);\"><strong><em>Saiba quais \u00f3rg\u00e3os do edital de 2025 que tamb\u00e9m fizeram parte do \u00faltimo CNU<\/em><\/strong><\/p>\n\n\n\n<p>O <a href=\"https:\/\/www.estrategiaconcursos.com.br\/cursosPorConcurso\/concurso-nacional-unificado-cnu\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Concurso Nacional Unificado<\/strong><\/a> <strong>(CNU 2025)<\/strong> j\u00e1 tem sua banca definida e chega cada vez mais pr\u00f3ximo de finalmente ser seu novo edital publicado.<\/p>\n\n\n\n<p>Com a chegada iminente do edital, torna-se super relevante decidir qual carreira trilhar para a t\u00e3o sonhada aprova\u00e7\u00e3o.<\/p>\n\n\n\n<p>Uma das op\u00e7\u00f5es \u00e9 <strong>apostar<\/strong> suas fichas em \u00f3rg\u00e3os que j\u00e1 participaram do \u00faltimo <strong>ENEM dos concursos.<\/strong> Afinal, \u00e9 uma base interessante de conte\u00fado que muitos conhecem. <\/p>\n\n\n\n<p>Por isso, saber quais s\u00e3o esses \u00f3rg\u00e3os \u00e9 o primeiro passo para finalmente fazer a escolha certa. Confira logo abaixo!<\/p>\n\n\n\n<div class=\"container\" id=\"boxes\">\r\n  <div class=\"row\">\r\n\r\n    <div class=\"col-sm\">\r\n      <div class=\"banner-federais\" id=\"box-assinatura\">\r\n        <h2 class=\"titulo-assinatura\" style=\"text-align: left;\">Cursos para o CNU<\/h2>\r\n        <p class=\"subtitulo-assinatura\" style=\"text-align: left;\">Prepare-se para o &#8220;Enem dos Concursos&#8221;!<\/p>\r\n        <div class=\"box-botao\" style=\"text-align: left;\">\r\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/cursosPorConcurso\/concurso-nacional-unificado-cnu\/\" role=\"button\" rel=\"noopener noreferrer\">Confira os pacotes!<\/a>\r\n        <\/div>\r\n      <\/div><\/div><\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-quais-orgaos-do-cnu-2024-estarao-na-nova-edicao-em-2025\">Quais \u00f3rg\u00e3os do CNU 2024 estar\u00e3o na nova edi\u00e7\u00e3o em 2025?<\/h2>\n\n\n\n<p>Apesar de ter <strong>36 \u00f3rg\u00e3os federais<\/strong> na disputa, contemplando diversas oportunidades, pouqu\u00edssimos \u00f3rg\u00e3os, de fato, estiveram no \u00faltimo CNU e retornaram para um novo preenchimento. S\u00e3o eles:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Minist\u00e9rio da Gest\u00e3o e Inova\u00e7\u00e3o (MGI)<\/strong>: que ter\u00e1 <strong>1.672<\/strong> vagas nesta edi\u00e7\u00e3o e teve<strong> 1.620<\/strong> no \u00faltimo <strong>ENEM dos concursos;<\/strong>\n<ul class=\"wp-block-list\">\n<li><strong>Cargos:<\/strong> Analista T\u00e9cnico-Administrativo, Assistente Social, M\u00e9dico, Psic\u00f3logo, Analista T\u00e9cnico de Desenvolvimento Socioecon\u00f4mico e Analista T\u00e9cnico de Defesa e Justi\u00e7a.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>Ag\u00eancia Nacional de Sa\u00fade Suplementar\u00a0<em>(<a href=\"https:\/\/www.estrategiaconcursos.com.br\/cursosPorConcurso\/ans-agencia-nacional-de-saude-suplementar-140\/\" target=\"_blank\" rel=\"noreferrer noopener\">ANS<\/a>)<\/em>:<\/strong> respons\u00e1vel por 20 vagas este ano e 35 oportunidades no ano passado; e\n<ul class=\"wp-block-list\">\n<li><strong>Cargo: <\/strong>T\u00e9cnico em Regula\u00e7\u00e3o de Sa\u00fade Suplementar<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>Ag\u00eancia Nacional de Transportes Aquavi\u00e1rios (<a href=\"https:\/\/www.estrategiaconcursos.com.br\/cursosPorConcurso\/antaq-297\/\" target=\"_blank\" rel=\"noreferrer noopener\">Antaq<\/a>)<\/strong>: que possui 30 vagas no <strong>CNU 2025<\/strong> e tamb\u00e9m ofertou 30 vagas no \u00faltimo CPNU.\n<ul class=\"wp-block-list\">\n<li><strong>Cargos <\/strong>T\u00e9cnico em Regula\u00e7\u00e3o de Servi\u00e7os de Transportes Aquavi\u00e1rios.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-conheca-os-principais-salarios\">Conhe\u00e7a os principais sal\u00e1rios<\/h2>\n\n\n\n<p>Outra forma de escolher oficialmente aonde apostar as fichas \u00e9 sabendo os principais sal\u00e1rios do <strong>CPNU<\/strong>. Confira:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Carreiras de Ag\u00eancias Reguladoras,<\/strong>\n<ul class=\"wp-block-list\">\n<li>Todas as carreiras de ag\u00eancias reguladoras, especificamente para <strong>Especialista<\/strong>, ter\u00e3o sal\u00e1rios de <strong>R$ 17.726,42<\/strong>, os maiores desta edi\u00e7\u00e3o do <strong>ENEM dos concursos;<\/strong><\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>Carreiras de Pesquisador,<\/strong>\n<ul class=\"wp-block-list\">\n<li>Todos os futuros pesquisadores contar\u00e3o com a segunda maior remunera\u00e7\u00e3o do <strong>CPNU<\/strong>, com valores que alcan\u00e7am <strong>R$ 13.498,00<\/strong> ou <strong>R$ 11.124,13<\/strong>;<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>Carreiras militares<\/strong>\n<ul class=\"wp-block-list\">\n<li>Analistas e Engenheiros de Tecnologia garantir\u00e3o vencimentos-base de <strong>R$ 12.369,42<\/strong>;<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>Carreiras de Analista e Tecnologista<\/strong>,\n<ul class=\"wp-block-list\">\n<li>Os cargos que se relacionam ao campo mais cient\u00edfico, como de Analista e Tecnologista, tamb\u00e9m ter\u00e3o sal\u00e1rios iniciais interessantes, de at\u00e9 <strong>R$ 11.124,13;<\/strong><\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>Demais carreiras<\/strong>\n<ul class=\"wp-block-list\">\n<li>Ainda t\u00eam outras carreiras que s\u00e3o especiais por conta de suas \u00f3timas remunera\u00e7\u00f5es! Podemos falar, por exemplo, de Arquiteto, Engenheiro e Estat\u00edstico, que possuem valores de <strong>R$ 10.396,50<\/strong> inicialmente. <\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<p>Ademais, ser\u00e3o contempladas carreiras diversas no <strong>Concurso Nacional Unificado (CNU)<\/strong>, garantindo, tamb\u00e9m, flexibilidade e versatilidade para muitos interessados.<\/p>\n\n\n\n<p class=\"has-text-align-center\"><em>Para ficar por dentro de todas as informa\u00e7\u00f5es sobre o CNU <a href=\"https:\/\/www.gov.br\/gestao\/pt-br\" target=\"_blank\" rel=\"noreferrer noopener\">2025<\/a>, n\u00e3o deixe de conferir nosso artigo completo sobre a sele\u00e7\u00e3o:<\/em><\/p>\n\n\n\n<p class=\"has-text-align-center has-background\" style=\"background-color:#e1e4e6\"><strong>Mais informa\u00e7\u00f5es do <a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-nacional-unificado\/\" target=\"_blank\" rel=\"noreferrer noopener\">CNU<\/a><\/strong><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"cursos-assinatura\"><em>Quer estudar para o pr\u00f3ximo Concurso Nacional Unificado (CNU)? Confira nossas assinaturas:<\/em><\/h2>\n\n\n\n<div class=\"container\" id=\"boxes\">\r\n  <div class=\"row\">\r\n\r\n    <div class=\"col-sm\">\r\n      <div class=\"estrategia\" id=\"box-assinatura\">\r\n        <h3 class=\"titulo-assinatura\">Assinatura Concursos<\/h3>\r\n        <p class=\"subtitulo-assinatura\">Assinatura de 1 ano ou 2 anos<\/p>\r\n        <div class=\"box-botao\">\r\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/assinaturas\/\" role=\"button\" rel=\"noopener noreferrer\">ASSINE AGORA<\/a>\r\n        <\/div>\r\n      <\/div><\/div><\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"h-quer-saber-tudo-sobre-concursos-previstos-confira-os-nossos-artigos\">Quer saber tudo sobre concursos previstos?<br \/>Confira os nossos artigos!<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-agencias-reguladoras\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos Ag\u00eancias Reguladoras<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos Abertos<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-federais\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos Federais<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2025\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos 2025<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2026\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos 2026<\/a><\/li>\n<\/ul>\n\n\n\n<div class=\"schema-faq wp-block-yoast-faq-block\"><div class=\"schema-faq-section\" id=\"faq-question-1749560608754\"><strong class=\"schema-faq-question\">O que \u00e9 a nota ponderada no CNU?<\/strong> <p class=\"schema-faq-answer\">A nota ponderada no CNU \u00e9 o resultado final da sua prova objetiva, levando em considera\u00e7\u00e3o o peso espec\u00edfico de cada \u00e1rea de conhecimento exigida para o bloco tem\u00e1tico ao qual voc\u00ea concorre. Em outras palavras, n\u00e3o basta apenas somar os acertos, cada disciplina tem um peso diferente e isso influencia diretamente na sua pontua\u00e7\u00e3o final.<\/p> <\/div> <div class=\"schema-faq-section\" id=\"faq-question-1749560674744\"><strong class=\"schema-faq-question\">Como a nota do CNU \u00e9 calculada?<\/strong> <p class=\"schema-faq-answer\">A nota do CNU \u00e9 calculada da seguinte forma:<br \/>Primeiro, \u00e9 feita a contagem dos acertos em cada \u00e1rea de conhecimento;<br \/>Em seguida, essa pontua\u00e7\u00e3o \u00e9 multiplicada pelo peso correspondente de cada disciplina, conforme o edital do bloco escolhido;<br \/>Por fim, soma-se o resultado de todas as \u00e1reas, gerando a nota ponderada.<\/p> <\/div> <div class=\"schema-faq-section\" id=\"faq-question-1749561034079\"><strong class=\"schema-faq-question\">Qual nota \u00e9 boa no CNU?<\/strong> <p class=\"schema-faq-answer\">Ainda n\u00e3o h\u00e1 um par\u00e2metro definitivo, pois o que \u00e9 considerado &#8220;boa nota&#8221; depende da concorr\u00eancia, do bloco tem\u00e1tico, do \u00f3rg\u00e3o e do cargo. No entanto, de forma geral, uma nota ponderada acima de 70% costuma ser competitiva. Para cargos mais disputados, \u00e9 prov\u00e1vel que os aprovados apresentem notas acima de 80%.<\/p> <\/div> <\/div>\n","protected":false},"excerpt":{"rendered":"<p>Saiba quais \u00f3rg\u00e3os do edital de 2025 que tamb\u00e9m fizeram parte do \u00faltimo CNU O Concurso Nacional Unificado (CNU 2025) j\u00e1 tem sua banca definida e chega cada vez mais pr\u00f3ximo de finalmente ser seu novo edital publicado. Com a chegada iminente do edital, torna-se super relevante decidir qual carreira trilhar para a t\u00e3o sonhada [&hellip;]<\/p>\n","protected":false},"author":2692,"featured_media":1270513,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"news","footnotes":""},"categories":[214992,220219],"tags":[],"tax_estado":[219963],"class_list":["post-1593598","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-concursos-administrativos","category-noticias","tax_estado-concursos-federais"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>CNU 2025: quais \u00f3rg\u00e3os tamb\u00e9m estiveram na edi\u00e7\u00e3o anterior?<\/title>\n<meta name=\"description\" content=\"Quais s\u00e3o os \u00f3rg\u00e3os que retornaram para uma segunda edi\u00e7\u00e3o no Concurso Nacional Unificado (CNU) 2025? Veja todos os detalhes!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-orgaos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CNU 2025: quais \u00f3rg\u00e3os tamb\u00e9m estiveram na edi\u00e7\u00e3o anterior?\" \/>\n<meta property=\"og:description\" content=\"Quais s\u00e3o os \u00f3rg\u00e3os que retornaram para uma segunda edi\u00e7\u00e3o no Concurso Nacional Unificado (CNU) 2025? Veja todos os detalhes!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-orgaos\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-18T22:17:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-19T12:53:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/08\/29075651\/concurso-nacional-unificado.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"432\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ronaldo Scanavini Neto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ronaldo Scanavini Neto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-orgaos\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-orgaos\/\"},\"author\":{\"name\":\"Ronaldo Scanavini Neto\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/70c2ad4297aa24ff8815b08215b23a76\"},\"headline\":\"CNU 2025: quais \u00f3rg\u00e3os tamb\u00e9m estiveram na edi\u00e7\u00e3o anterior?\",\"datePublished\":\"2025-06-18T22:17:49+00:00\",\"dateModified\":\"2025-06-19T12:53:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-orgaos\/\"},\"wordCount\":714,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-orgaos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/08\/29075651\/concurso-nacional-unificado.jpg\",\"articleSection\":[\"Executivo (Administrativa)\",\"\u00daltimas not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-orgaos\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":[\"WebPage\",\"FAQPage\"],\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-orgaos\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-orgaos\/\",\"name\":\"CNU 2025: quais \u00f3rg\u00e3os tamb\u00e9m estiveram na edi\u00e7\u00e3o anterior?\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-orgaos\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-orgaos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/08\/29075651\/concurso-nacional-unificado.jpg\",\"datePublished\":\"2025-06-18T22:17:49+00:00\",\"dateModified\":\"2025-06-19T12:53:22+00:00\",\"description\":\"Quais s\u00e3o os \u00f3rg\u00e3os que retornaram para uma segunda edi\u00e7\u00e3o no Concurso Nacional Unificado (CNU) 2025? Veja todos os detalhes!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-orgaos\/#breadcrumb\"},\"mainEntity\":[{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-orgaos\/#faq-question-1749560608754\"},{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-orgaos\/#faq-question-1749560674744\"},{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-orgaos\/#faq-question-1749561034079\"}],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-orgaos\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-orgaos\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/08\/29075651\/concurso-nacional-unificado.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/08\/29075651\/concurso-nacional-unificado.jpg\",\"width\":768,\"height\":432,\"caption\":\"CNU 2: saiu convoca\u00e7\u00e3o para Fase 6; cronograma atualizado\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-orgaos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CNU 2025: quais \u00f3rg\u00e3os tamb\u00e9m estiveram na edi\u00e7\u00e3o anterior?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/70c2ad4297aa24ff8815b08215b23a76\",\"name\":\"Ronaldo Scanavini Neto\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/f93d8e56fe264596e94aee6b3feb737d98ad0fc5bac7eb0a245f04723c5c8f21?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f93d8e56fe264596e94aee6b3feb737d98ad0fc5bac7eb0a245f04723c5c8f21?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f93d8e56fe264596e94aee6b3feb737d98ad0fc5bac7eb0a245f04723c5c8f21?s=96&d=mm&r=g\",\"caption\":\"Ronaldo Scanavini Neto\"},\"description\":\"Graduando em Comunica\u00e7\u00e3o Social \u2013 Jornalismo pela Universidade Federal de Vi\u00e7osa (UFV). Integra a equipe de jornalismo do Estrat\u00e9gia Concursos desde 2023, atuando com \u00eanfase na cobertura da \u00e1rea fiscal. Tamb\u00e9m realiza a apura\u00e7\u00e3o e produ\u00e7\u00e3o de not\u00edcias sobre concursos federais, \u00f3rg\u00e3os participantes do CNU e das \u00e1reas de controle, gest\u00e3o, engenharia, Exame CFC, comunica\u00e7\u00e3o social TI e \u00e1rea de concursos administrativos.\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/ronaldo-netoestrategia-com\/\"},{\"@type\":\"Question\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-orgaos\/#faq-question-1749560608754\",\"position\":1,\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-orgaos\/#faq-question-1749560608754\",\"name\":\"O que \u00e9 a nota ponderada no CNU?\",\"answerCount\":1,\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"A nota ponderada no CNU \u00e9 o resultado final da sua prova objetiva, levando em considera\u00e7\u00e3o o peso espec\u00edfico de cada \u00e1rea de conhecimento exigida para o bloco tem\u00e1tico ao qual voc\u00ea concorre. Em outras palavras, n\u00e3o basta apenas somar os acertos, cada disciplina tem um peso diferente e isso influencia diretamente na sua pontua\u00e7\u00e3o final.\",\"inLanguage\":\"pt-BR\"},\"inLanguage\":\"pt-BR\"},{\"@type\":\"Question\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-orgaos\/#faq-question-1749560674744\",\"position\":2,\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-orgaos\/#faq-question-1749560674744\",\"name\":\"Como a nota do CNU \u00e9 calculada?\",\"answerCount\":1,\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"A nota do CNU \u00e9 calculada da seguinte forma:<br\/>Primeiro, \u00e9 feita a contagem dos acertos em cada \u00e1rea de conhecimento;<br\/>Em seguida, essa pontua\u00e7\u00e3o \u00e9 multiplicada pelo peso correspondente de cada disciplina, conforme o edital do bloco escolhido;<br\/>Por fim, soma-se o resultado de todas as \u00e1reas, gerando a nota ponderada.\",\"inLanguage\":\"pt-BR\"},\"inLanguage\":\"pt-BR\"},{\"@type\":\"Question\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-orgaos\/#faq-question-1749561034079\",\"position\":3,\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-orgaos\/#faq-question-1749561034079\",\"name\":\"Qual nota \u00e9 boa no CNU?\",\"answerCount\":1,\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Ainda n\u00e3o h\u00e1 um par\u00e2metro definitivo, pois o que \u00e9 considerado \\\"boa nota\\\" depende da concorr\u00eancia, do bloco tem\u00e1tico, do \u00f3rg\u00e3o e do cargo. No entanto, de forma geral, uma nota ponderada acima de 70% costuma ser competitiva. Para cargos mais disputados, \u00e9 prov\u00e1vel que os aprovados apresentem notas acima de 80%.\",\"inLanguage\":\"pt-BR\"},\"inLanguage\":\"pt-BR\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"CNU 2025: quais \u00f3rg\u00e3os tamb\u00e9m estiveram na edi\u00e7\u00e3o anterior?","description":"Quais s\u00e3o os \u00f3rg\u00e3os que retornaram para uma segunda edi\u00e7\u00e3o no Concurso Nacional Unificado (CNU) 2025? Veja todos os detalhes!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-orgaos\/","og_locale":"pt_BR","og_type":"article","og_title":"CNU 2025: quais \u00f3rg\u00e3os tamb\u00e9m estiveram na edi\u00e7\u00e3o anterior?","og_description":"Quais s\u00e3o os \u00f3rg\u00e3os que retornaram para uma segunda edi\u00e7\u00e3o no Concurso Nacional Unificado (CNU) 2025? Veja todos os detalhes!","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-orgaos\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2025-06-18T22:17:49+00:00","article_modified_time":"2025-06-19T12:53:22+00:00","og_image":[{"width":768,"height":432,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/08\/29075651\/concurso-nacional-unificado.jpg","type":"image\/jpeg"}],"author":"Ronaldo Scanavini Neto","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Ronaldo Scanavini Neto","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-orgaos\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-orgaos\/"},"author":{"name":"Ronaldo Scanavini Neto","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/70c2ad4297aa24ff8815b08215b23a76"},"headline":"CNU 2025: quais \u00f3rg\u00e3os tamb\u00e9m estiveram na edi\u00e7\u00e3o anterior?","datePublished":"2025-06-18T22:17:49+00:00","dateModified":"2025-06-19T12:53:22+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-orgaos\/"},"wordCount":714,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-orgaos\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/08\/29075651\/concurso-nacional-unificado.jpg","articleSection":["Executivo (Administrativa)","\u00daltimas not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-orgaos\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":["WebPage","FAQPage"],"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-orgaos\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-orgaos\/","name":"CNU 2025: quais \u00f3rg\u00e3os tamb\u00e9m estiveram na edi\u00e7\u00e3o anterior?","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-orgaos\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-orgaos\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/08\/29075651\/concurso-nacional-unificado.jpg","datePublished":"2025-06-18T22:17:49+00:00","dateModified":"2025-06-19T12:53:22+00:00","description":"Quais s\u00e3o os \u00f3rg\u00e3os que retornaram para uma segunda edi\u00e7\u00e3o no Concurso Nacional Unificado (CNU) 2025? Veja todos os detalhes!","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-orgaos\/#breadcrumb"},"mainEntity":[{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-orgaos\/#faq-question-1749560608754"},{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-orgaos\/#faq-question-1749560674744"},{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-orgaos\/#faq-question-1749561034079"}],"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-orgaos\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-orgaos\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/08\/29075651\/concurso-nacional-unificado.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/08\/29075651\/concurso-nacional-unificado.jpg","width":768,"height":432,"caption":"CNU 2: saiu convoca\u00e7\u00e3o para Fase 6; cronograma atualizado"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-orgaos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"CNU 2025: quais \u00f3rg\u00e3os tamb\u00e9m estiveram na edi\u00e7\u00e3o anterior?"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/70c2ad4297aa24ff8815b08215b23a76","name":"Ronaldo Scanavini Neto","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/f93d8e56fe264596e94aee6b3feb737d98ad0fc5bac7eb0a245f04723c5c8f21?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f93d8e56fe264596e94aee6b3feb737d98ad0fc5bac7eb0a245f04723c5c8f21?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f93d8e56fe264596e94aee6b3feb737d98ad0fc5bac7eb0a245f04723c5c8f21?s=96&d=mm&r=g","caption":"Ronaldo Scanavini Neto"},"description":"Graduando em Comunica\u00e7\u00e3o Social \u2013 Jornalismo pela Universidade Federal de Vi\u00e7osa (UFV). Integra a equipe de jornalismo do Estrat\u00e9gia Concursos desde 2023, atuando com \u00eanfase na cobertura da \u00e1rea fiscal. Tamb\u00e9m realiza a apura\u00e7\u00e3o e produ\u00e7\u00e3o de not\u00edcias sobre concursos federais, \u00f3rg\u00e3os participantes do CNU e das \u00e1reas de controle, gest\u00e3o, engenharia, Exame CFC, comunica\u00e7\u00e3o social TI e \u00e1rea de concursos administrativos.","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/ronaldo-netoestrategia-com\/"},{"@type":"Question","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-orgaos\/#faq-question-1749560608754","position":1,"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-orgaos\/#faq-question-1749560608754","name":"O que \u00e9 a nota ponderada no CNU?","answerCount":1,"acceptedAnswer":{"@type":"Answer","text":"A nota ponderada no CNU \u00e9 o resultado final da sua prova objetiva, levando em considera\u00e7\u00e3o o peso espec\u00edfico de cada \u00e1rea de conhecimento exigida para o bloco tem\u00e1tico ao qual voc\u00ea concorre. Em outras palavras, n\u00e3o basta apenas somar os acertos, cada disciplina tem um peso diferente e isso influencia diretamente na sua pontua\u00e7\u00e3o final.","inLanguage":"pt-BR"},"inLanguage":"pt-BR"},{"@type":"Question","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-orgaos\/#faq-question-1749560674744","position":2,"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-orgaos\/#faq-question-1749560674744","name":"Como a nota do CNU \u00e9 calculada?","answerCount":1,"acceptedAnswer":{"@type":"Answer","text":"A nota do CNU \u00e9 calculada da seguinte forma:<br\/>Primeiro, \u00e9 feita a contagem dos acertos em cada \u00e1rea de conhecimento;<br\/>Em seguida, essa pontua\u00e7\u00e3o \u00e9 multiplicada pelo peso correspondente de cada disciplina, conforme o edital do bloco escolhido;<br\/>Por fim, soma-se o resultado de todas as \u00e1reas, gerando a nota ponderada.","inLanguage":"pt-BR"},"inLanguage":"pt-BR"},{"@type":"Question","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-orgaos\/#faq-question-1749561034079","position":3,"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-orgaos\/#faq-question-1749561034079","name":"Qual nota \u00e9 boa no CNU?","answerCount":1,"acceptedAnswer":{"@type":"Answer","text":"Ainda n\u00e3o h\u00e1 um par\u00e2metro definitivo, pois o que \u00e9 considerado \"boa nota\" depende da concorr\u00eancia, do bloco tem\u00e1tico, do \u00f3rg\u00e3o e do cargo. No entanto, de forma geral, uma nota ponderada acima de 70% costuma ser competitiva. Para cargos mais disputados, \u00e9 prov\u00e1vel que os aprovados apresentem notas acima de 80%.","inLanguage":"pt-BR"},"inLanguage":"pt-BR"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1593598","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/2692"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1593598"}],"version-history":[{"count":3,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1593598\/revisions"}],"predecessor-version":[{"id":1593727,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1593598\/revisions\/1593727"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/1270513"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1593598"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1593598"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1593598"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1593598"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}