{"id":1577729,"date":"2025-05-19T23:26:29","date_gmt":"2025-05-20T02:26:29","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=1577729"},"modified":"2025-05-20T21:03:35","modified_gmt":"2025-05-21T00:03:35","slug":"concurso-sefaz-pr-recursos-auditor-fiscal","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-sefaz-pr-recursos-auditor-fiscal\/","title":{"rendered":"Concurso Sefaz PR: veja os recursos de Auditor Fiscal"},"content":{"rendered":"\n<p>O <strong>concurso Sefaz PR<\/strong>&nbsp;<strong>(<a href=\"https:\/\/www.estrategiaconcursos.com.br\/cursosPorConcurso\/secretaria-da-fazenda-do-estado-do-parana-sefaz-pr\/\" target=\"_blank\" rel=\"noreferrer noopener\">Secretaria de Fazenda do Paran\u00e1<\/a><\/strong>), para <strong>Auditor Fiscal<\/strong>, teve suas provas aplicadas no \u00faltimo domingo, 18. Inclusive, os gabaritos preliminares da etapa j\u00e1 foram divulgados.<\/p>\n\n\n\n<p>Com isso, o prazo para interposi\u00e7\u00e3o de recursos ficar\u00e1 aberto entre os dias 20 e 21 de maio, diretamente na \u00e1rea do candidato no site da <a href=\"https:\/\/conhecimento.fgv.br\/concursos\/seappr25?utm_source=google&amp;utm_medium=cpc&amp;utm_campaign=ec-ge-vd-gsh-semanacnu-semesp-140923\" target=\"_blank\" rel=\"noreferrer noopener\">FGV<\/a>.<\/p>\n\n\n\n<p>E para te ajudar, assim como na <a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-sefaz-pr-auditor\/\" target=\"_blank\" rel=\"noreferrer noopener\">corre\u00e7\u00e3o extraoficial<\/a>, nossos professores identificaram algumas possibilidades de recursos para as avalia\u00e7\u00f5es de <strong>Auditor Fiscal.<\/strong> Veja abaixo:<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-very-light-gray-to-cyan-bluish-gray-gradient-background has-background\" id=\"ingles\">Concurso Sefaz PR: recursos Auditor Fiscal (prova manh\u00e3)<\/h2>\n\n\n\n<p class=\"has-very-light-gray-to-cyan-bluish-gray-gradient-background has-background has-medium-font-size\"><strong>PROVA TIPO 2 (VERDE) &#8211; L\u00cdNGUA PORTUGUESA<\/strong><\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>QUEST\u00c3O 5<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"436\" height=\"388\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/05\/20122916\/image-196.png\" alt=\"Concurso Sefaz PR: veja os recursos de Auditor Fiscal\" class=\"wp-image-1578391\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/05\/20122916\/image-196.png 436w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/05\/20122916\/image-196-300x267.png 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/05\/20122916\/image-196-150x133.png 150w\" sizes=\"auto, (max-width: 436px) 100vw, 436px\" \/><\/figure>\n\n\n\n<p><strong>GABARITO PRELIMINAR DA BANCA: D<\/strong><\/p>\n\n\n\n<p><strong>GABARITO PRETENDIDO:&nbsp; A<\/strong><\/p>\n\n\n\n<p><strong>FUNDAMENTA\u00c7\u00c3O:&nbsp;<\/strong><\/p>\n\n\n\n<p>A quest\u00e3o de n\u00famero 5 teve gabarito preliminar a alternativa \u2018D\u2019. Contudo, com todo o respeito \u00e0 Banca, nota-se um equ\u00edvoco, conforme fundamenta\u00e7\u00e3o que se segue.<\/p>\n\n\n\n<p>A primeira assertiva \u00e9 verdadeira, pois o primeiro per\u00edodo do texto de fato \u201cmostra uma afirma\u00e7\u00e3o de car\u00e1ter universal, fruto da opini\u00e3o do enunciador\u201d. No fragmento textual que serve de base para a quest\u00e3o, l\u00ea-se no primeiro per\u00edodo: \u201cNingu\u00e9m ousa dizer adeus aos pr\u00f3prios h\u00e1bitos\u201d, frase que traz uma afirma\u00e7\u00e3o de car\u00e1ter universal \u2013 papel exercido pelo termo \u201cningu\u00e9m\u201d, originada da opini\u00e3o do autor. Trata-se da tese que, por sua vez, reflete a opini\u00e3o &#8211; um modalizador <em>per se<\/em> \u2013 do produtor do texto. Em \u00faltima inst\u00e2ncia, o primeiro per\u00edodo do referido texto retrata a tese do autor. Vale lembrar que entende-se por tese afirma\u00e7\u00e3o central e principal que o autor pretende defender ou explorar, isto \u00e9, a ideia n\u00facleo que guia o desenvolvimento do texto e que o autor pretende provar ou argumentar (GARCIA, 2004.)<\/p>\n\n\n\n<p>Igualmente \u00e9 verdadeira a segunda assertiva, na qual se l\u00ea: \u201co segundo per\u00edodo do texto desempenha a fun\u00e7\u00e3o de demonstra\u00e7\u00e3o do que foi afirmado antes.\u201d Sem d\u00favidas, esse \u00e9 o efeito de sentido causado pela passagem a seguir: \u201c<em>Muitos suicidas se detiveram no limiar da morte ao pensarem no caf\u00e9 aonde v\u00e3o jogar todas as noites sua partida de domin\u00f3.\u201d <\/em>Esta passagem faz parte da estrat\u00e9gia de argumenta\u00e7\u00e3o (GARCIA, 2004) em que ocorre a demonstra\u00e7\u00e3o do foi escrito anteriormente. Assim, o autor demonstra, por meio de exemplifica\u00e7\u00e3o, que \u201cningu\u00e9m ousa dizer adeus aos pr\u00f3prios h\u00e1bitos\u201d, haja vista que nem mesmo os \u201csuicidas se detiveram no limiar da morte\u201d de manterem seu h\u00e1bito de jogar domin\u00f3 todas as noites.<\/p>\n\n\n\n<p>Por fim, \u00e9 falsa a terceira assertiva, pois, &nbsp;contrariamente ao que nela se l\u00ea, \u201co pronome possessivo \u2018sua\u2019\u201d <strong>n\u00e3o<\/strong> \u201cmostra ideia de posse em rela\u00e7\u00e3o ao jogo de domin\u00f3.\u201d Na realidade, o pronome possessivo tem valor sem\u00e2ntico de h\u00e1bito, de algo rotineiro ou que se repete. Desse modo, na frase \u201cjogar todas as noites sua partida de domin\u00f3\u201d, o pronome possessivo \u201csua\u201d n\u00e3o traz a ideia de posse dos suicidas sobre a modalidade de jogo. Dito de outro modo, os \u201csuicidas\u201d de que fala o texto n\u00e3o \u2018possuem\u2019 ou \u2018s\u00e3o donos\u2019 das \u2018partidas de domin\u00f3\u2019, mas sim, t\u00eam o h\u00e1bito rotineiro de todas as noites jogar domin\u00f3 em um caf\u00e9.<\/p>\n\n\n\n<p>Portanto, reitere-se o valor sem\u00e2ntico do pronome possessivo \u201cseu\u201d relacionado a h\u00e1bito ou rotina, ao indicar uma a\u00e7\u00e3o repetida que pertence ao cotidiano do sujeito \u2013 no caso do trecho da quest\u00e3o 5, os suicidas pensam nos caf\u00e9s onde jogam partidas de domin\u00f3 todas as noites antes mesmo da morte, o que refor\u00e7a a tese defendida pelo autor no primeiro per\u00edodo do trecho: \u201cningu\u00e9m ousa dizer adeus aos pr\u00f3prios h\u00e1bitos.\u201d<\/p>\n\n\n\n<p><strong>Com base no exposto acima, solicita-se respeitosamente a mudan\u00e7a de gabarito.<\/strong><\/p>\n\n\n\n<p><strong>REFER\u00caNCIA:<\/strong><\/p>\n\n\n\n<p>GARCIA, Othon Moacir. <strong>Comunica\u00e7\u00e3o em prosa moderna<\/strong>: aprenda a escrever, aprendendo a pensar. 24. ed. Rio de Janeiro: FGV, 2004.<\/p>\n\n\n\n<p class=\"has-very-light-gray-to-cyan-bluish-gray-gradient-background has-background has-medium-font-size\"><strong>PROVA TIPO 2 (VERDE) &#8211; AN\u00c1LISE DE DADOS: CONCEITOS E APLICA\u00c7\u00d5ES<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"545\" height=\"545\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/05\/20143139\/image-199.png\" alt=\"\" class=\"wp-image-1578477\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/05\/20143139\/image-199.png 545w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/05\/20143139\/image-199-300x300.png 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/05\/20143139\/image-199-150x150.png 150w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/05\/20143139\/image-199-96x96.png 96w\" sizes=\"auto, (max-width: 545px) 100vw, 545px\" \/><\/figure>\n\n\n\n<p class=\"has-medium-font-size\"><strong>QUEST\u00c3O 36<\/strong><\/p>\n\n\n\n<p>Pedido: anula\u00e7\u00e3o<br \/>Justificativa: O gr\u00e1fico apresenta um erro grave: n\u00e3o \u00e9 sim\u00e9trico . Como sabemos, a correla\u00e7\u00e3o entre duas vari\u00e1veis \u00e9 comutativa, isto \u00e9, corre(V1;V2) = corre(V2;V1). <\/p>\n\n\n\n<p>Com isso, a matriz das correla\u00e7\u00f5es deve ser sim\u00e9trica. A an\u00e1lise portanto fica imposs\u00edvel com o erro crasso na matriz.<\/p>\n\n\n\n<p class=\"has-very-light-gray-to-cyan-bluish-gray-gradient-background has-background has-medium-font-size\"><strong>PROVA TIPO 2 VERDE &#8211; DIREITO CIVIL<\/strong><\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>QUEST\u00c3O 46<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"371\" height=\"559\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/05\/20123046\/image-197.png\" alt=\"Concurso Sefaz PR: veja os recursos de Auditor Fiscal\" class=\"wp-image-1578394\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/05\/20123046\/image-197.png 371w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/05\/20123046\/image-197-199x300.png 199w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/05\/20123046\/image-197-150x226.png 150w\" sizes=\"auto, (max-width: 371px) 100vw, 371px\" \/><\/figure>\n\n\n\n<p>O gabarito preliminar divulgado pela banca foi a <strong>letra D<\/strong>.<\/p>\n\n\n\n<p>Requer-se <strong>altera\u00e7\u00e3o do gabarito para letra A<\/strong>, ou subsidiariamente, a <strong>anula\u00e7\u00e3o<\/strong> da quest\u00e3o.<\/p>\n\n\n\n<p>A quest\u00e3o apresentou uma situa\u00e7\u00e3o pr\u00e1tica em que se constata o enquadramento de Joana no quesito legal da emancipa\u00e7\u00e3o.<\/p>\n\n\n\n<p>O examinador aponta que devem ser consideradas as disposi\u00e7\u00f5es do <strong>C\u00f3digo Civil<\/strong> e da <strong>jurisprud\u00eancia dominante<\/strong> sobre o tema.<\/p>\n\n\n\n<p>Os requisitos legais para o caso em tela encontram-se no<strong> inciso V, do par\u00e1grafo \u00fanico do art. 5\u00ba do C\u00f3digo Civil<\/strong>, abaixo reproduzido:<\/p>\n\n\n\n<p><em>Art. 5&nbsp;<u><sup>o<\/sup><\/u>(&#8230;)<\/em><\/p>\n\n\n\n<p><em>Par\u00e1grafo \u00fanico. Cessar\u00e1, para os menores, a incapacidade:<\/em><\/p>\n\n\n\n<p><em>(&#8230;)<\/em><\/p>\n\n\n\n<p><em>V &#8211; pelo estabelecimento civil ou comercial, ou pela exist\u00eancia de rela\u00e7\u00e3o de emprego, desde que, em fun\u00e7\u00e3o deles, o menor com dezesseis anos completos tenha economia pr\u00f3pria.<\/em><\/p>\n\n\n\n<p>Assim, Joana, para ser emancipada e poder praticar plenamente todos os atos da vida civil, precisa j\u00e1 ter <strong>completado 16 anos<\/strong>, possuir <strong>rela\u00e7\u00e3o de emprego<\/strong> e, com isso, usufruir <strong>de economia pr\u00f3pria<\/strong>.<\/p>\n\n\n\n<p>Repara-se que <strong>n\u00e3o h\u00e1 a exig\u00eancia legal do requisito da averba\u00e7\u00e3o<\/strong> no registro civil.<\/p>\n\n\n\n<p>O <strong>inciso II, do artigo 9\u00ba do C\u00f3digo Civil<\/strong> exige que a emancipa\u00e7\u00e3o seja registrada no registro p\u00fablico, por\u00e9m essa exig\u00eancia refere-se apenas \u00e0quela decorrente de outorga dos pais ou por senten\u00e7a do juiz, ou seja, a exig\u00eancia de registro contida nesse comando n\u00e3o se aplica ao caso da quest\u00e3o.<\/p>\n\n\n\n<p><em>Art. 9 o Ser\u00e3o registrados em registro p\u00fablico:<\/em><\/p>\n\n\n\n<p><em>I &#8211; os nascimentos, casamentos e \u00f3bitos;<\/em><\/p>\n\n\n\n<p><em>II &#8211; a emancipa\u00e7\u00e3o por outorga dos pais ou por senten\u00e7a do juiz;<\/em><\/p>\n\n\n\n<p>Caso o eminente examinador entenda que a averba\u00e7\u00e3o se faz necess\u00e1ria por previs\u00e3o contida em alguma outra norma legal diferente da prevista no C\u00f3digo Civil, mant\u00e9m-se o argumento de que a quest\u00e3o <strong>deve ser anulada<\/strong>, afinal, a quest\u00e3o foi n\u00edtida em afirmar que a resposta deveria ser dada \u00e0 luz da previs\u00e3o contida no C\u00f3digo Civil e n\u00e3o com base em outras legisla\u00e7\u00f5es.<\/p>\n\n\n\n<p>Com isso, entende-se que a <strong>exig\u00eancia contida na alternativa \u201cD\u201d<\/strong> de que a emancipa\u00e7\u00e3o deve ser formalizada com averba\u00e7\u00e3o no registro civil <strong>n\u00e3o se sustenta com base na escrita contida no C\u00f3digo Civil<\/strong>.<\/p>\n\n\n\n<p>N\u00e3o obstante a an\u00e1lise legal, a banca tamb\u00e9m citou que a quest\u00e3o deveria ser analisada tento como par\u00e2metro a <strong>jurisprud\u00eancia dominante<\/strong>.<\/p>\n\n\n\n<p>Ora, em an\u00e1lise mais precisa a respeito da jurisprud\u00eancia envolvendo o tema, t\u00eam-se no <strong>Informativo 687 de 08 de mar\u00e7o de 2021 do Superior Tribunal de Justi\u00e7a<\/strong>, no <a href=\"https:\/\/processo.stj.jus.br\/SCON\/jurisprudencia\/toc.jsp?livre=%28RESP.clas.+e+%40num%3D%221872102%22%29+ou+%28RESP+adj+%221872102%22%29.suce.\" target=\"_blank\" rel=\"noreferrer noopener\">REsp 1.872.102\/SP<\/a> de Relatoria do Ministro Marco Aur\u00e9lio Belizze, Terceira Turma, por unanimidade, julgado em 02\/03\/2021, a seguinte ementa:<\/p>\n\n\n\n<p>RECURSO ESPECIAL. CIVIL. CONTRATO DE GEST\u00c3O DE CARREIRA E DE AGENCIAMENTO DE JOGADOR PROFISSIONAL DE FUTEBOL. NEGATIVA DE PRESTA\u00c7\u00c3O JURISDICIONAL. N\u00c3O OCORR\u00caNCIA. HIP\u00d3TESE DE EMANCIPA\u00c7\u00c3O LEGAL CARACTERIZADA. RELA\u00c7\u00c3O EMPREGAT\u00cdCIA. ART. 5\u00ba, PAR\u00c1GRAFO \u00daNICO, V, DO CC. DESNECESSIDADE DE AUTORIZA\u00c7\u00c3O JUDICIAL. AFERI\u00c7\u00c3O DA VALIDADE DOS CONTRATOS \u00c0 LUZ DO ART. 1.691 DO CC. IMPOSSIBILIDADE. FILHO EMANCIPADO. APLICA\u00c7\u00c3O DA LEI PEL\u00c9. DESCABIMENTO. ATO JUR\u00cdDICO PERFEITO. CONTRATO DE GERENCIAMENTO DE CARREIRA. ATLETA PROFISSIONAL MENOR DE DEZOITO ANOS. VALIDADE. RECURSO ESPECIAL DE TRAFFIC TALENTOS E MARKETING ESPORTIVO LTDA. &#8211; EPP E FREDERICO AUGUSTO ANDRADE PENA PROVIDO E RECURSO ESPECIAL DE GR2 GEST\u00c3O E MARKETING LTDA. E GABRIEL MARTINEZ MASSA PARCIALMENTE PROVIDO.<br \/>1. O prop\u00f3sito recursal consiste em definir, al\u00e9m da negativa de presta\u00e7\u00e3o jurisdicional, se a autoriza\u00e7\u00e3o judicial \u00e9 pressuposto de validade de contratos de gest\u00e3o de carreira e de agenciamento de jogador profissional de futebol celebrados por atleta relativamente incapaz devidamente representado pelos pais ou respons\u00e1vel legal.<br \/>2. Verifica-se que o Tribunal de origem analisou todas as quest\u00f5es relevantes para a solu\u00e7\u00e3o da lide, de forma fundamentada, n\u00e3o havendo falar em negativa de presta\u00e7\u00e3o jurisdicional.<br \/><strong>3. A emancipa\u00e7\u00e3o legal proveniente de rela\u00e7\u00e3o empregat\u00edcia, prevista no art. 5\u00ba, par\u00e1grafo \u00fanico, V, parte final, do CC\/2002, pressup\u00f5e:<br \/>i) que o menor possua ao menos dezesseis anos completos; ii) a exist\u00eancia de v\u00ednculo empregat\u00edcio; e iii) que desse liame lhe sobrevenha economia pr\u00f3pria.<br \/>4. Por decorrer diretamente do texto da lei, essa esp\u00e9cie de emancipa\u00e7\u00e3o prescinde de autoriza\u00e7\u00e3o judicial, bem como dispensa o registro p\u00fablico respectivo para a validade dos atos civis praticados pelo emancipado, bastando apenas que se evidenciem os requisitos legais para a implementa\u00e7\u00e3o da capacidade civil plena, como na hip\u00f3tese.<\/strong><br \/>5. O regramento disposto no art. 1.691 do CC, que exige autoriza\u00e7\u00e3o judicial para a contra\u00e7\u00e3o de obriga\u00e7\u00f5es em nome do filho menor, n\u00e3o se aplica ao filho emancipado, porquanto dotado este de capacidade civil plena, podendo realizar os atos da vida civil, por si s\u00f3.<br \/>6. Celebrados os contratos dos presentes autos antes da entrada em vigor do inciso VI do art. 27-C da Lei n. 9.615\/1998 (Lei Pel\u00e9), mostra-se descabida a an\u00e1lise da sua higidez \u00e0 luz desse dispositivo legal, por se tratar de ato jur\u00eddico perfeito (art. 6\u00ba, \u00a7 1\u00ba, da LINDB).<br \/>7. A t\u00edtulo de refor\u00e7o argumentativo, \u00e9 nulo de pleno direito o contrato de gerenciamento de carreira pactuado pelo atleta em forma\u00e7\u00e3o menor de dezoito anos, afigurando-se v\u00e1lida, ao rev\u00e9s, a aven\u00e7a celebrada pelo atleta profissional menor de dezoito anos devidamente assistido, caso ainda n\u00e3o adquirida a capacidade civil plena, conforme a norma dos arts. 3\u00ba, \u00a7 1\u00ba, I, 27-C, VI, 28 e 29, \u00a7 4\u00ba, todos da Lei n. 9.615\/1998.<br \/>8. Recurso especial de Traffic Talentos Marketing Esportivo Ltda. &#8211; EPP e Frederico Augusto Andrade Pena provido e recurso especial de GR2 Gest\u00e3o e Marketing Ltda. e Gabriel Martinez Massa parcialmente provido.<\/p>\n\n\n\n<p>Repara-se que no <strong>item 3<\/strong>, o caso julgado refere-se \u00e0 mesma situa\u00e7\u00e3o descrita na quest\u00e3o, a respeito dos requisitos de emancipa\u00e7\u00e3o tratado no art. 5\u00ba, par\u00e1grafo \u00fanico, V, parte final, do CC\/2002. <strong>Nele consta expressamente os mesmos requisitos legais<\/strong>.<\/p>\n\n\n\n<p><strong>J\u00e1 o item 4 da citada EMENTA <\/strong>diz expressamente que essa esp\u00e9cie de emancipa\u00e7\u00e3o n\u00e3o precisa de autoriza\u00e7\u00e3o judicial e <strong>dispensa o registro p\u00fablico para a validade dos atos civis<\/strong> praticados pelo emancipado.<\/p>\n\n\n\n<p>Portanto, <strong>n\u00e3o h\u00e1 fundamento adequado para considerar correta a resposta apresentada na letra D da quest\u00e3o,<\/strong> tendo em vista que, nos termos do C\u00f3digo e da jurisprud\u00eancia, <strong>n\u00e3o se exige a formaliza\u00e7\u00e3o da averba\u00e7\u00e3o no registro civil como requisito para aquisi\u00e7\u00e3o<\/strong> da emancipa\u00e7\u00e3o legal.<\/p>\n\n\n\n<p>Entretanto, a alternativa <strong>proposta na letra A<\/strong> apresenta os requisitos de aquisi\u00e7\u00e3o da capacidade plena por emancipa\u00e7\u00e3o, mencionando a obten\u00e7\u00e3o de renda pr\u00f3pria e o fato de poder viver de forma independente, significando os mesmos requisitos da lei, diga-se, o de de possuir v\u00ednculo empregat\u00edcio que lhe proporcione economia pr\u00f3pria.<\/p>\n\n\n\n<p>A emancipa\u00e7\u00e3o do caso em tela \u00e9 mais conhecida como um tipo de emancipa\u00e7\u00e3o legal, o que tamb\u00e9m \u00e9 considerado pela doutrina <strong>emancipa\u00e7\u00e3o t\u00e1cita<\/strong>. E, consequentemente, todas os requisitos apontados na letra A est\u00e3o coerentes com o c\u00f3digo Civil e a jurisprud\u00eancia.<\/p>\n\n\n\n<p>Assim, com base nos argumentos e fundamentos apresentados, requer-se a altera\u00e7\u00e3o do gabarito preliminar da letra D para a letra A, ou, caso a banca n\u00e3o entenda a veracidade da letra A, que se anule a quest\u00e3o, por n\u00e3o haver resposta adequada, afinal, n\u00e3o resta d\u00favidas que a letra D n\u00e3o est\u00e1 correta.<\/p>\n\n\n\n<p class=\"has-very-light-gray-to-cyan-bluish-gray-gradient-background has-background has-medium-font-size\"><strong>PROVA TIPO 2 (VERDE) &#8211; DIREITO PENAL<\/strong><\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>QUEST\u00c3O 51<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"570\" height=\"295\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/05\/20210254\/image-214.png\" alt=\"\" class=\"wp-image-1578796\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/05\/20210254\/image-214.png 570w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/05\/20210254\/image-214-300x155.png 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/05\/20210254\/image-214-150x78.png 150w\" sizes=\"auto, (max-width: 570px) 100vw, 570px\" \/><\/figure>\n\n\n\n<p>O gabarito pela Banca traz a letra C como correta, com fundamento que a inser\u00e7\u00e3o de dados falsos em documento p\u00fablico configura o crime previsto no art.297 do C\u00f3digo Penal, denominado de falsifica\u00e7\u00e3o de documento p\u00fablico.<\/p>\n\n\n\n<p>Ocorre que a letra B tamb\u00e9m est\u00e1 correta, vez que a adultera\u00e7\u00e3o de testamento particular (documento p\u00fablico por equipara\u00e7\u00e3o) configura o crime de falsifica\u00e7\u00e3o de documento p\u00fablico, conforme o art.297, \u00a72\u00ba, do CP, abaixo:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Art. 297, \u00a7 2\u00ba, do CP- Para os efeitos penais, equiparam-se a documento p\u00fablico o emanado de entidade paraestatal, o t\u00edtulo ao portador ou transmiss\u00edvel por endosso, as a\u00e7\u00f5es de sociedade comercial, os livros mercantis e o testamento particular.<\/p>\n<\/blockquote>\n\n\n\n<p><strong>Pelo exposto, em sede de recurso \u00e0 quest\u00e3o, tendo em vista que existem duas alternativas corretas, requer o candidato que a Banca anule a quest\u00e3o supracitada.<\/strong><\/p>\n\n\n\n<p class=\"has-very-light-gray-to-cyan-bluish-gray-gradient-background has-background has-medium-font-size\"><strong>PROVA TIPO 2 (VERDE) &#8211; DIREITO TRIBUT\u00c1RIO<\/strong><\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>QUEST\u00c3O 71<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"588\" height=\"601\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/05\/19232412\/image-188.png\" alt=\"Concurso Sefaz PR: veja os recursos de Auditor Fiscal\" class=\"wp-image-1578111\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/05\/19232412\/image-188.png 588w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/05\/19232412\/image-188-294x300.png 294w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/05\/19232412\/image-188-150x153.png 150w\" sizes=\"auto, (max-width: 588px) 100vw, 588px\" \/><\/figure>\n\n\n\n<p>Ol\u00e1, pessoal. Tudo bem?<br \/>A quest\u00e3o 71 da prova Tipo 2, do per\u00edodo da manh\u00e3, apresenta o seguinte enunciado na assertiva III, a qual foi considerada como \u201ccorreta\u201d pelo gabarito preliminar informado pela Banca.<\/p>\n\n\n\n<p>\u201cIII. Quando as autoridades fiscais flagrarem a pr\u00e1tica de atos il\u00edcitos durante a sua execu\u00e7\u00e3o, como nas hip\u00f3teses de contrabando ou descaminho, n\u00e3o dever\u00e1 ocorrer a tributa\u00e7\u00e3o, mas a aplica\u00e7\u00e3o de penas administrativas, como o perdimento dos bens, sem preju\u00edzo das san\u00e7\u00f5es penais cab\u00edveis.\u201d<\/p>\n\n\n\n<p>Inicialmente acaba apresentar alguns conceitos b\u00e1sicos, como a defini\u00e7\u00e3o apresentada pelo C\u00f3digo Penal &#8211; Decreto-Lei no 2.848\/1940, sobre o \u201ccontrabando\u201d e \u201cdescaminho\u201d:<\/p>\n\n\n\n<p>Contrabando: Art. 334-A. Importar ou exportar mercadoria proibida<br \/>Descaminho: Art. 334. Iludir, no todo ou em parte, o pagamento de direito ou imposto devido pela entrada, pela sa\u00edda ou pelo consumo de mercadoria<\/p>\n\n\n\n<p>Ocorre que, diferentemente do que considerado pela Banca, o Regulamento Aduaneiro (Decreto n. 6.759\/2009) prev\u00ea que o descaminho, em oposi\u00e7\u00e3o ao contrabando, n\u00e3o leva necessariamente \u00e0 pena de \u201cperdimento\u201d da mercadoria, havendo previs\u00f5es de poss\u00edvel tributa\u00e7\u00e3o, conjuntamente com a incid\u00eancia de multa (por exemplo, em seus artigos 713 e 725).<\/p>\n\n\n\n<p>Inclusive h\u00e1 entendimento nesta linha pelo Supremo Tribunal Federal (HC 85.942\/SP), em Voto que o Ministro Luiz Fux afirma ser \u201cn\u00edtida a natureza tribut\u00e1ria do crime de descaminho, merc\u00ea de tutelar o er\u00e1rio p\u00fablico e a atividade arrecadadora do Estado\u201d.<\/p>\n\n\n\n<p>Desta forma vemos claramente que, diferentemente do crime de contrabando, no caso do descaminho, n\u00e3o h\u00e1 a necess\u00e1ria imposi\u00e7\u00e3o da pena de perdimento da mercadoria.<\/p>\n\n\n\n<p><strong>Assim, diante do exposto, propomos a altera\u00e7\u00e3o do gabarito da quest\u00e3o 71 para a alternativa \u201cB\u201d, em que apenas as assertivas I e II est\u00e3o corretas.<\/strong><\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>QUEST\u00c3O 72<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"552\" height=\"612\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/05\/19232434\/image-189.png\" alt=\"\" class=\"wp-image-1578112\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/05\/19232434\/image-189.png 552w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/05\/19232434\/image-189-271x300.png 271w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/05\/19232434\/image-189-150x166.png 150w\" sizes=\"auto, (max-width: 552px) 100vw, 552px\" \/><\/figure>\n\n\n\n<p>A quest\u00e3o 72 da prova Tipo 2, do per\u00edodo da manh\u00e3, apresenta o seguinte enunciado na assertiva I, a qual foi considerada como \u201ccorreta\u201d pelo gabarito preliminar informado pela Banca.<\/p>\n\n\n\n<p>\u201cI &#8211; Na aquisi\u00e7\u00e3o de filial em processo de recupera\u00e7\u00e3o judicial, o adquirente responde pelos tributos devidos pelo alienante at\u00e9 a data do neg\u00f3cio, mesmo que este prossiga na explora\u00e7\u00e3o da mesma atividade.\u201d<\/p>\n\n\n\n<p>Ocorre que, conforme prev\u00ea o Inciso II, Par\u00e1grafo 1o, do Art. 133 do CTN, combinado com o Par\u00e1grafo \u00danico do Art. 60 da Lei 11.101\/2005, a aquisi\u00e7\u00e3o de filial de empresa em processo de recupera\u00e7\u00e3o judicial (que somente pode ocorrer com autoriza\u00e7\u00e3o do juiz, sendo ent\u00e3o, necessariamente, uma aliena\u00e7\u00e3o judicial), n\u00e3o acarreta responsabilidade tribut\u00e1ria ao adquirente em rela\u00e7\u00e3o aos cr\u00e9ditos tribut\u00e1rios deixados pelo alienante, at\u00e9 a data do neg\u00f3cio. Vejamos:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>CTN. Art. 133. A pessoa natural ou jur\u00eddica de direito privado que adquirir de outra, por qualquer t\u00edtulo, fundo de com\u00e9rcio ou estabelecimento comercial, industrial ou profissional, e continuar a respectiva explora\u00e7\u00e3o, sob a mesma ou outra raz\u00e3o social ou sob firma ou nome individual, responde pelos tributos, relativos ao fundo ou estabelecimento adquirido, devidos at\u00e9 \u00e0 data do ato:<br \/>I &#8211; integralmente, se o alienante cessar a explora\u00e7\u00e3o do com\u00e9rcio, ind\u00fastria ou atividade;<br \/>II &#8211; subsidiariamente com o alienante, se este prosseguir na explora\u00e7\u00e3o ou iniciar dentro de seis meses a contar da data da aliena\u00e7\u00e3o, nova atividade no mesmo ou em outro ramo de com\u00e9rcio, ind\u00fastria ou profiss\u00e3o.<br \/>\u00a7 1o O disposto no caput deste artigo n\u00e3o se aplica na hip\u00f3tese de aliena\u00e7\u00e3o judicial:<br \/>I \u2013 em processo de fal\u00eancia;<br \/>II \u2013 de filial ou unidade produtiva isolada, em processo de recupera\u00e7\u00e3o judicial.<\/p>\n<\/blockquote>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Lei 11.101\/2005 Art. 60. Se o plano de recupera\u00e7\u00e3o judicial aprovado envolver aliena\u00e7\u00e3o judicial de filiais ou de unidades produtivas isoladas do devedor, o juiz ordenar\u00e1 a sua realiza\u00e7\u00e3o, observado o disposto no art. 142 desta Lei.<br \/>Par\u00e1grafo-\u00fanico. O objeto da aliena\u00e7\u00e3o estar\u00e1 livre de qualquer \u00f4nus e n\u00e3o haver\u00e1 sucess\u00e3o do arrematante nas obriga\u00e7\u00f5es do devedor de qualquer natureza, inclu\u00eddas, mas n\u00e3o exclusivamente, as de natureza ambiental, regulat\u00f3ria, administrativa, penal, anticorrup\u00e7\u00e3o, tribut\u00e1ria e trabalhista, observado o disposto no \u00a7 1o do art. 141 desta Lei.<\/p>\n<\/blockquote>\n\n\n\n<p>Desta forma vemos claramente que, no caso de uma aquisi\u00e7\u00e3o de filial em processo de recupera\u00e7\u00e3o judicial (que somente pode ocorrer por meio de uma \u201caliena\u00e7\u00e3o judicial\u201d), o adquirente n\u00e3o responde pelos tributos devidos pelo alienante at\u00e9 a data do neg\u00f3cio.<\/p>\n\n\n\n<p><strong>Assim, diante do exposto, propomos a altera\u00e7\u00e3o do gabarito da quest\u00e3o 72 para a alternativa \u201cA\u201d, em que apenas a assertiva II est\u00e1 correta.<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading has-very-light-gray-to-cyan-bluish-gray-gradient-background has-background\" id=\"ingles\">Concurso Sefaz PR: recursos Auditor Fiscal (prova tarde)<\/h2>\n\n\n\n<p class=\"has-very-light-gray-to-cyan-bluish-gray-gradient-background has-background has-medium-font-size\"><strong>PROVA TIPO 2 VERDE &#8211; FINAN\u00c7AS P\u00daBLICAS <\/strong><\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>QUEST\u00c3O 10<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"369\" height=\"420\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/05\/19235530\/image-190.png\" alt=\"\" class=\"wp-image-1578114\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/05\/19235530\/image-190.png 369w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/05\/19235530\/image-190-264x300.png 264w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/05\/19235530\/image-190-150x171.png 150w\" sizes=\"auto, (max-width: 369px) 100vw, 369px\" \/><\/figure>\n\n\n\n<p>O gabarito preliminar apontado para a quest\u00e3o 10 da prova tipo 1 (tarde) foi a letra A.<\/p>\n\n\n\n<p>Contudo, pugna-se pela <strong>ANULA\u00c7\u00c3O<\/strong> da quest\u00e3o com base nos seguintes fundamentos:<\/p>\n\n\n\n<p>As alternativas I, II e III est\u00e3o erradas, inexistindo gabarito.<\/p>\n\n\n\n<p>A alternativa I, considerada correta pela Banca FGV, est\u00e1 contr\u00e1ria ao disposto no art. 14 da Lei de Responsabilidade Fiscal. Isso porque assim disp\u00f5e o art. 14:<\/p>\n\n\n\n<p>Art. 14. A concess\u00e3o ou amplia\u00e7\u00e3o de incentivo ou benef\u00edcio de natureza tribut\u00e1ria da qual decorra ren\u00fancia de receita dever\u00e1 estar acompanhada de estimativa do impacto or\u00e7ament\u00e1rio-financeiro no exerc\u00edcio em que deva iniciar sua vig\u00eancia e nos dois seguintes, atender ao disposto na lei de diretrizes or\u00e7ament\u00e1rias <strong><u>e a pelo menos uma das seguintes condi\u00e7\u00f5es<\/u><\/strong>:&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p>I &#8211; demonstra\u00e7\u00e3o pelo proponente de que a ren\u00fancia foi considerada na estimativa de receita da lei or\u00e7ament\u00e1ria, na forma do art. 12, e de que n\u00e3o afetar\u00e1 as metas de resultados fiscais previstas no anexo pr\u00f3prio da lei de diretrizes or\u00e7ament\u00e1rias;<\/p>\n\n\n\n<p>II &#8211; estar acompanhada de <strong><u>medidas de compensa\u00e7\u00e3o<\/u><\/strong>, no per\u00edodo mencionado no caput, por meio do aumento de receita, proveniente da eleva\u00e7\u00e3o de al\u00edquotas, amplia\u00e7\u00e3o da base de c\u00e1lculo, majora\u00e7\u00e3o ou cria\u00e7\u00e3o de tributo ou contribui\u00e7\u00e3o.<\/p>\n\n\n\n<p>Dessa forma, o item I da quest\u00e3o, ao dispor que \u201cA concess\u00e3o de incentivos fiscais pode implicar em ren\u00fancia de receita p\u00fablica, fato que, por sua vez, <strong><u>dever\u00e1 estar acompanhado<\/u><\/strong> de estimativa do impacto or\u00e7ament\u00e1rio-financeiro e <strong><u>de medidas de compensa\u00e7\u00e3o<\/u><\/strong>\u201d, desconsidera por completo que o art. 14 da LRF n\u00e3o exige que a ren\u00fancia de receita venha, necessariamente, acompanhada de medidas de compensa\u00e7\u00e3o.<\/p>\n\n\n\n<p>Em verdade, o art. 14 traz dois requisitos sempre obrigat\u00f3rios: estimativa de impacto or\u00e7ament\u00e1rio-financeiro e atendimento ao disposto na Lei de Diretrizes Or\u00e7ament\u00e1rias. Por sua vez, o gestor, cumulativamente aos dois requisitos obrigat\u00f3rios previsto no <em>caput<\/em> do art. 14, deve atender a pelo menos uma das seguintes condi\u00e7\u00f5es: \u201cI &#8211; demonstra\u00e7\u00e3o pelo proponente de que a ren\u00fancia foi considerada na estimativa de receita da lei or\u00e7ament\u00e1ria, na forma do art. 12, e de que n\u00e3o afetar\u00e1 as metas de resultados fiscais previstas no anexo pr\u00f3prio da lei de diretrizes or\u00e7ament\u00e1rias\u201d <strong>ou<\/strong> \u201cII &#8211; estar acompanhada de medidas de compensa\u00e7\u00e3o, no per\u00edodo mencionado no caput, por meio do aumento de receita, proveniente da eleva\u00e7\u00e3o de al\u00edquotas, amplia\u00e7\u00e3o da base de c\u00e1lculo, majora\u00e7\u00e3o ou cria\u00e7\u00e3o de tributo ou contribui\u00e7\u00e3o\u201d.<\/p>\n\n\n\n<p>O texto da lei \u00e9 claro: \u201c<strong><u>pelo menos uma das seguintes condi\u00e7\u00f5es<\/u><\/strong>\u201d. Significa dizer que as medidas de compensa\u00e7\u00e3o <strong><u>podem ou n\u00e3o ser adotadas<\/u><\/strong>, visto que, se a ren\u00fancia de receita j\u00e1 foi considerada na estimativa da LOA e j\u00e1 houve comprova\u00e7\u00e3o de que os resultados fiscais n\u00e3o ser\u00e3o afetados (item I do art. 14), <strong><u>tal ren\u00fancia ser\u00e1 implementada sem medidas de compensa\u00e7\u00e3o<\/u><\/strong>.<\/p>\n\n\n\n<p>Dessa forma, inquestion\u00e1vel que o item I est\u00e1 errado, pois considera como obrigat\u00f3rio um requisito que a pr\u00f3pria Lei de Responsabilidade Fiscal expressamente prev\u00ea como alternativo.<\/p>\n\n\n\n<p>Tanto \u00e9 assim que a estimada Banca sempre realizou a cobran\u00e7a do art. 14 considerando o texto legal, ou seja, <strong>sempre tratou o requisito das \u201cmedidas de compensa\u00e7\u00e3o\u201d como <u>n\u00e3o obrigat\u00f3rio<\/u><\/strong>, conforme se observa das seguintes quest\u00f5es:<\/p>\n\n\n\n<p>FGV &#8211; 2025 &#8211; TCE-RR &#8211; Auditor Substituto de Conselheiro<\/p>\n\n\n\n<p>A Lei de Responsabilidade Fiscal (Lei Complementar n\u00ba 101\/2004) estabelece normas de finan\u00e7as p\u00fablicas voltadas para a responsabilidade na gest\u00e3o fiscal.<br \/>De acordo com essa lei, \u00e9 correto afirmar que<br \/>A) a concess\u00e3o ou amplia\u00e7\u00e3o de incentivo ou benef\u00edcio de natureza tribut\u00e1ria da qual decorra ren\u00fancia de receita dever\u00e1 estar acompanhada de estimativa do impacto or\u00e7ament\u00e1rio-financeiro, que compreenda o per\u00edodo legalmente previsto para a vig\u00eancia do incentivo ou benef\u00edcio.<br \/>B) a ren\u00fancia de receita deve ser sempre acompanhada da demonstra\u00e7\u00e3o de que foi considerada na estimativa de receita da lei or\u00e7ament\u00e1ria, bem como de medidas de compensa\u00e7\u00e3o.<br \/>C) a previs\u00e3o de parcelamentos, por impactar a previs\u00e3o de arrecada\u00e7\u00e3o, \u00e9 considerada, pela lei, ren\u00fancia de receitas.<br \/>D) o imposto incidente sobre opera\u00e7\u00e3o de c\u00e2mbio pode ter suas al\u00edquotas alteradas, na forma do Art. 150, \u00a71\u00ba, da Constitui\u00e7\u00e3o Federal de 1988, sem que haja a necessidade de estimativa de impacto or\u00e7ament\u00e1rio-financeiro, segundo a lei.<br \/>E) a concess\u00e3o de benef\u00edcio tribut\u00e1rio que esteja acompanhado de medida de compensa\u00e7\u00e3o, proveniente da eleva\u00e7\u00e3o de al\u00edquota de tributo sujeito ao princ\u00edpio da anterioridade, por expressa previs\u00e3o legal, entrar\u00e1 em vigor de imediato, desde que prevista a equival\u00eancia entre benef\u00edcio e compensa\u00e7\u00e3o.<\/p>\n\n\n\n<p>Na quest\u00e3o aplicada no TCE\/RR, neste ano, a estimada Banca considerou <strong><u>errada<\/u><\/strong> a alternativa B, que menciona que \u201ca ren\u00fancia de receita deve ser sempre acompanhada da demonstra\u00e7\u00e3o de que foi considerada na estimativa de receita da lei or\u00e7ament\u00e1ria, bem como de medidas de compensa\u00e7\u00e3o\u201d. O gabarito para a referida quest\u00e3o foi, corretamente, a letra D.<\/p>\n\n\n\n<p>O mesmo ocorre com a seguinte quest\u00e3o:<\/p>\n\n\n\n<p>FGV &#8211; 2024 &#8211; MF &#8211; Auditor Federal de Finan\u00e7as e Controle &#8211; \u00c1rea Econ\u00f4mico-Financeira &#8211; tarde<\/p>\n\n\n\n<p>Os Incentivos Fiscais s\u00e3o um instrumento de grande relev\u00e2ncia para o est\u00edmulo ao crescimento e \u00e0 redu\u00e7\u00e3o das desigualdades sociais, mas possuem impactos que podem comprometer o equil\u00edbrio or\u00e7ament\u00e1rio do setor p\u00fablico. Nesse contexto, \u00e9 correto afirmar que<\/p>\n\n\n\n<p>A) a LRF estabelece o regramento para gastos com pessoal e para a realiza\u00e7\u00e3o de opera\u00e7\u00f5es de cr\u00e9dito, bem como para as ren\u00fancias de receita, exceto se envolverem a cria\u00e7\u00e3o de tributo ou aumento de al\u00edquotas.<br \/>B) a LRF prev\u00ea, como compensa\u00e7\u00e3o de uma ren\u00fancia de receita, duas alternativas: aumento de al\u00edquota ou cria\u00e7\u00e3o de um novo tributo.<br \/>C) a LRF prev\u00ea uma an\u00e1lise de impacto de curto prazo, por um exerc\u00edcio, desde o in\u00edcio da vig\u00eancia do Incentivo Fiscal, para eventuais compensa\u00e7\u00f5es da ren\u00fancia de receita verificada.<br \/>D) o crescimento econ\u00f4mico \u00e9 um meio para a compensa\u00e7\u00e3o das ren\u00fancias fiscais realizadas pelo setor p\u00fablico, j\u00e1 que pode promover o incremento da arrecada\u00e7\u00e3o sem qualquer aumento de al\u00edquota ou cria\u00e7\u00e3o de imposto.<br \/>E) para cada Incentivo Fiscal concedido deve haver a medida de arrecada\u00e7\u00e3o incremental, aumento de al\u00edquota ou novo imposto correspondente, de forma a compensar eventuais perdas de receita p\u00fablica.<\/p>\n\n\n\n<p>A alternativa E, que disp\u00f5e que \u201cpara cada Incentivo Fiscal concedido deve haver a medida de arrecada\u00e7\u00e3o incremental, aumento de al\u00edquota ou novo imposto correspondente, de forma a compensar eventuais perdas de receita p\u00fablica\u201d foi considerada errada pela Banca, em aten\u00e7\u00e3o ao disposto no art. 14 da LRF.<\/p>\n\n\n\n<p>Dessa forma, voltando \u00e0 quest\u00e3o objeto do presente recurso, resta evidente que o requisito relativo \u00e0s medidas de compensa\u00e7\u00e3o n\u00e3o \u00e9 obrigat\u00f3rio, raz\u00e3o por que o item I est\u00e1 errado ao afirmar que \u201cA concess\u00e3o de incentivos fiscais pode implicar em ren\u00fancia de receita p\u00fablica, fato que, por sua vez, <strong><u>dever\u00e1 estar acompanhado<\/u><\/strong> de estimativa do impacto or\u00e7ament\u00e1rio-financeiro e <strong><u>de medidas de compensa\u00e7\u00e3o<\/u><\/strong>\u201d.<\/p>\n\n\n\n<p>Por sua vez, o item II trata sobre a redu\u00e7\u00e3o de al\u00edquota de ISS, o qual deve ser considerado como ren\u00fancia de receita, nos termos do art. 14 da LRF. Portanto, a afirma\u00e7\u00e3o de que essa redu\u00e7\u00e3o n\u00e3o \u00e9 considerada como ren\u00fancia de receita invalida o item.<\/p>\n\n\n\n<p>Da mesma forma, o item III est\u00e1 equivocado ao afirmar que a eleva\u00e7\u00e3o de al\u00edquotas \u00e9 a estrat\u00e9gia mais utilizada pelos governos municipais para tentar aumentar investimentos externos diretos. Isso porque n\u00e3o \u00e9 a eleva\u00e7\u00e3o de al\u00edquotas, mas a <strong>REDU\u00c7\u00c3O<\/strong> delas a estrat\u00e9gia mais utilizada pelos governos <strong>ESTADUAIS<\/strong> para atra\u00e7\u00e3o de investimentos externos.<\/p>\n\n\n\n<p><strong>Assim, uma vez que as alternativas I, II e III est\u00e3o erradas e tendo em vista que a alternativa I traz texto contr\u00e1rio ao previsto no art. 14, <em>caput<\/em> e incisos I e II, da LRF, pugna-se pela anula\u00e7\u00e3o da quest\u00e3o, devido \u00e0 inexist\u00eancia de gabarito.<\/strong><\/p>\n\n\n\n<p class=\"has-very-light-gray-to-cyan-bluish-gray-gradient-background has-background has-medium-font-size\"><strong>PROVA TIPO 2 VERDE &#8211; CONTABILIDADE GERAL, AVAN\u00c7ADA, CUSTOS E AUDITORIA FISCAL<\/strong><\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>QUEST\u00c3O 24<\/strong><\/p>\n\n\n\n<p>Uma loja de brincos s\u00f3 realiza vendas \u00e0 vista. Al\u00e9m disso, todas as despesas s\u00e3o pagas no momento de seu reconhecimento. Em 2024, a loja reconheceu receita de RS 400.000,00. No ano, 500 pares de brincos foram vendidos. Cada unidade de brinco tinha um custo vari\u00e1vel de R$ 100,00. Al\u00e9m disso, a loja reconheceu as seguintes despesas em 2024:<\/p>\n\n\n\n<p>Sal\u00e1rios: R$ 180.000,00.<br \/>Deprecia\u00e7\u00e3o dos ativos imobilizados: R$ 30.000,00.<br \/>Aluguel do escrit\u00f3rio: R$ 72.000,00.<br \/>Perda de recuperabilidade RS 15 15.000,00. no ano.<br \/>Constitui\u00e7\u00e3o de provis\u00e3o para conting\u00eancias: R$ 28.000,00.<\/p>\n\n\n\n<p>Assinale a op\u00e7\u00e3o que indica o ponto de equil\u00edbrio financeiro da loja<\/p>\n\n\n\n<p>A) 258 pares de brincos.<br \/>B) 360 pares de brincos.<br \/>C) 400 pares de brincos.<br \/>D) 420 pares de brincos.<br \/>E) 465 pares de brincos.<\/p>\n\n\n\n<p>O gabarito preliminar da banca foi a letra D = 420 pares de brincos.<\/p>\n\n\n\n<p>O c\u00e1lculo efetuado foi o seguinte:<\/p>\n\n\n\n<p>Pre\u00e7o de venda unit\u00e1rio = Receita total \/ quantidade<\/p>\n\n\n\n<p>Pre\u00e7o de venda (par de brincos) = $ 400.000 \/ 500 pares = $ 800<\/p>\n\n\n\n<p>O custo vari\u00e1vel \u00e9 de $100 para cada unidade de brinco, portanto o par ir\u00e1 apresentar custo vari\u00e1vel de $ 200<\/p>\n\n\n\n<p>Margem de contribui\u00e7\u00e3o = Pre\u00e7o de venda \u2013 custos vari\u00e1veis<\/p>\n\n\n\n<p>Margem de contribui\u00e7\u00e3o = $ 800 &#8211; $ 200 = $ 600<\/p>\n\n\n\n<p>Ponto de equil\u00edbrio financeiro = custos e despesas fixas desembols\u00e1veis \/ Margem de contribui\u00e7\u00e3o<\/p>\n\n\n\n<p>A banca considerou apenas sal\u00e1rio e aluguel do escrit\u00f3rio como custo e despesas fixas.<\/p>\n\n\n\n<p>Custo + despesas fixas = $ 180.000 + $ 72.000 = $ 252.000<\/p>\n\n\n\n<p>Ponto de equil\u00edbrio financeiro = $ 252.000 \/ $ 600 = 420 pares de brincos<\/p>\n\n\n\n<p>Ocorre que a constitui\u00e7\u00e3o de provis\u00e3o para conting\u00eancias tamb\u00e9m deveria ser considerada para o c\u00e1lculo do ponto de equil\u00edbrio financeiro.<\/p>\n\n\n\n<p>O ponto de equil\u00edbrio financeiro elimina as despesas que afetaram o lucro, mas n\u00e3o ser\u00e3o pagas a ningu\u00e9m. Ou seja, n\u00e3o resultar\u00e3o em desembolso. Assim, devem ser exclu\u00eddas a despesa de deprecia\u00e7\u00e3o, de amortiza\u00e7\u00e3o, de exaust\u00e3o e as perdas com recuperabilidade.<\/p>\n\n\n\n<p>Mas a provis\u00e3o para conting\u00eancias ir\u00e1 resultar em desembolso futuro. Nesse caso, o c\u00e1lculo correto \u00e9 o seguinte:<\/p>\n\n\n\n<p>Despesas:<\/p>\n\n\n\n<figure class=\"wp-block-table is-style-stripes\"><table class=\"has-fixed-layout\"><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\">Sal\u00e1rio<\/td><td class=\"has-text-align-center\" data-align=\"center\">180.000,00<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Aluguel<\/td><td class=\"has-text-align-center\" data-align=\"center\">72.000,00<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">constitui\u00e7\u00e3o de reserva para conting\u00eancias<\/td><td class=\"has-text-align-center\" data-align=\"center\">28.000,00<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Total<\/td><td class=\"has-text-align-center\" data-align=\"center\">280.000,00<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p>Ponto de equil\u00edbrio financeiro = $ 280.000 \/ $ 600 = 466,67 pares de brinco, ou 467 considerando o arredondamento.<\/p>\n\n\n\n<p>A quest\u00e3o n\u00e3o apresenta resposta correta. A que mais se aproxima (letra E = 465 pares) n\u00e3o corresponde ao ponto de equil\u00edbrio financeiro, que \u00e9 de 466,7.<\/p>\n\n\n\n<p>Se a banca considerou, na sua resposta, apenas as despesas que seriam desembolsadas no per\u00edodo, deve incluir tamb\u00e9m a&nbsp; despesa de constitui\u00e7\u00e3o de provis\u00e3o para conting\u00eancias. Afinal, a quest\u00e3o menciona claramente que todas as despesas s\u00e3o pagas no momento de seu reconhecimento.<\/p>\n\n\n\n<p>Ou seja, de acordo com os dados da quest\u00e3o, a empresa reconhece uma despesa com constitui\u00e7\u00e3o de provis\u00e3o para conting\u00eancias e efetua o pagamento, no momento do reconhecimento da despesa.<\/p>\n\n\n\n<p>Assim, solicitamos a <strong>ANULA\u00c7\u00c3O <\/strong>da quest\u00e3o por n\u00e3o apresentar alternativa correta.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>QUEST\u00c3O 32<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td><strong>32. A sociedade empres\u00e1ria Beta Ltda. adquiriu mercadorias pelo valor de R$ 7.000,00, e as revendeu pelo valor de R$ 10.000,00,. Considerando que nessas opera\u00e7\u00f5es incidiu ICMS de 15%, ap\u00f3s o registro cont\u00e1bil da compra e venda dessas mercadorias, assinale a op\u00e7\u00e3o que indica o cr\u00e9dito fiscal, em R$, que a sociedade empres\u00e1ria apresentar\u00e1.<\/strong> <strong>(A) 1.500,00.<\/strong> <strong>(B) 1.050,00.<\/strong> <strong>(C) 0.<\/strong> <strong>(D) 450,00.<\/strong> <strong>(E) 350,00.<\/strong><\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p><strong>Coment\u00e1rios:<\/strong><\/p>\n\n\n\n<p><strong>Gabarito da banca: C.<\/strong><\/p>\n\n\n\n<p>A quest\u00e3o quer saber o cr\u00e9dito fiscal, em R$, que a sociedade empres\u00e1ria apresentar\u00e1.<\/p>\n\n\n\n<p>Preliminarmente, vamos distinguir cr\u00e9dito de ICMS (cr\u00e9dito fiscal), saldo credor ou cr\u00e9dito acumulado de ICMS:<\/p>\n\n\n\n<p>O termo &#8220;cr\u00e9dito&#8221;, \u00e9 muitas vezes confundido com o termo &#8220;saldo credor de ICMS&#8221; ou com &#8220;cr\u00e9dito acumulado de ICMS&#8221;. \u00c9 necess\u00e1rio estabelecer que embora os tr\u00eas termos sejam muitas vezes utilizados para a mesma finalidade, a n\u00edvel t\u00e9cnico s\u00e3o de fato tr\u00eas situa\u00e7\u00f5es distintas.<\/p>\n\n\n\n<p><strong>1. Cr\u00e9dito de ICMS:<\/strong><\/p>\n\n\n\n<p>Denomina-se &#8220;cr\u00e9dito de ICMS&#8221; o valor individual do cr\u00e9dito, costumando ser este o valor destacado na nota fiscal de compra e que ser\u00e1 abatido do valor a pagar, mediante a escritura\u00e7\u00e3o.&nbsp; No entanto, n\u00e3o s\u00e3o todas as compras, mesmo que tenha o valor do ICMS destacado na nota fiscal, d\u00e1 ao contribuinte direito ao cr\u00e9dito para tal fim.<\/p>\n\n\n\n<p>O ICMS a pagar \u00e9 composto de lan\u00e7amentos a cr\u00e9dito (compras) e lan\u00e7amentos a d\u00e9bito (vendas). Os cr\u00e9ditos podem ser lan\u00e7ados de forma extempor\u00e2nea, (em at\u00e9 cinco anos), caso o contribuinte n\u00e3o tenha escriturado a nota de compra.&nbsp; (Diferentemente dos d\u00e9bitos, os quais se n\u00e3o lan\u00e7ados a tempo, devem ser lan\u00e7ados com multa e juros)<\/p>\n\n\n\n<p>As aquisi\u00e7\u00f5es do ativo imobilizado, apesar de ter o cr\u00e9dito destacado integralmente na nota fiscal.&nbsp; Devem ser lan\u00e7adas na escrita fiscal, para fins de c\u00e1lculo do imposto a pagar, em 48 parcelas, de acordo com as regras fixadas por cada estado.<\/p>\n\n\n\n<p>Existem ainda outros lan\u00e7amentos de cr\u00e9dito, como pagamentos efetuados indevidamente, ou cr\u00e9ditos relativos \u00e0 devolu\u00e7\u00e3o de vendas.<\/p>\n\n\n\n<p><strong>2. Saldo credor de ICMS:<\/strong><\/p>\n\n\n\n<p>A apura\u00e7\u00e3o do ICMS \u00e9 mensal, ocasi\u00e3o em que, da escritura\u00e7\u00e3o fiscal dos d\u00e9bitos e cr\u00e9ditos, resulta o saldo do imposto a recolher para os cofres p\u00fablicos. Em determinadas situa\u00e7\u00f5es as empresas efetuam as suas compras em determinados meses para realizarem a venda nos meses subsequentes.<\/p>\n\n\n\n<p>Vamos imaginar uma empresa que comercializa ch\u00e1s no inverno e que esta empresa realiza as suas compras nos meses de ver\u00e3o, para concentrar suas vendas no inverno.<\/p>\n\n\n\n<p>Lembrando que a apura\u00e7\u00e3o do imposto \u00e9 mensal e que neste exemplo as compras foram maiores do que as vendas, tendo a empresa escriturado um volume de cr\u00e9ditos superiores ao volume de d\u00e9bitos.<\/p>\n\n\n\n<p>Neste exemplo, por serem os cr\u00e9ditos maiores que os d\u00e9bitos, a empresa ir\u00e1 ficar com &#8220;saldo credor acumulado&#8221; do imposto a ser transportado para o m\u00eas ou meses seguintes. Temos aqui um saldo credor acumulado decorrente de estoques, o qual ser\u00e1 abatido o imposto a pagar quando este estoque for vendido.<\/p>\n\n\n\n<p>Portanto saldo credor de ICMS \u00e9 uma situa\u00e7\u00e3o transit\u00f3ria, onde logo este saldo \u00e9 compensado e se dilui, por ocasi\u00e3o das vendas.<\/p>\n\n\n\n<p><strong>3. Cr\u00e9dito acumulado de ICMS<\/strong><\/p>\n\n\n\n<p>Tecnicamente falando em termos de ICMS, saldo credor n\u00e3o \u00e9 o mesmo que &#8220;cr\u00e9dito acumulado&#8221;.&nbsp;<\/p>\n\n\n\n<p>&#8220;Saldo credor&#8221;, como vimos \u00e9 o resultado provis\u00f3rio da confronta\u00e7\u00e3o de d\u00e9bitos e cr\u00e9ditos.&nbsp; Saldo, este transportado para per\u00edodos subsequentes onde ir\u00e1 se diluir com os d\u00e9bitos, zerando o saldo credor e resultando em imposto a pagar.<\/p>\n\n\n\n<p>A sucessiva apura\u00e7\u00e3o de saldo credor, sendo transportado para o m\u00eas seguinte, onde apura-se novo &#8220;saldo credor&#8221;, e assim sucessivamente, \u00e9 o que denominados &#8220;saldo credor acumulado do imposto&#8221;, ou em algumas unidades da federa\u00e7\u00e3o de &#8220;cr\u00e9dito acumulado&#8221;.<\/p>\n\n\n\n<p>No Estado de S\u00e3o Paulo, denomina-se cr\u00e9dito acumulado o saldo credor acumulado ap\u00f3s ter passado pela aprova\u00e7\u00e3o pela Secretaria Estadual da Fazenda.<\/p>\n\n\n\n<p>Enquanto se encontra apenas na escrita fiscal, denomina-se &#8220;saldo credor acumulado&#8221;, depois que passa pela aprova\u00e7\u00e3o e passa a contar na conta corrente fiscal junto a SEFAZ, passa a se chamar &#8220;cr\u00e9dito acumulado do imposto&#8221;.<\/p>\n\n\n\n<p>Temos ent\u00e3o que o cr\u00e9dito acumulado nestes termos equivale a dinheiro e \u00e9 pass\u00edvel de transfer\u00eancia para outras empresas.&nbsp; Enquanto o saldo credor acumulado ainda n\u00e3o, pois depende da aprova\u00e7\u00e3o pr\u00e9via ou homologa\u00e7\u00e3o pela SEFAZ paulista.<\/p>\n\n\n\n<p>Fonte: <a href=\"https:\/\/www.migalhas.com.br\/depeso\/369849\/icms--o-problema-do-saldo-credor-acumulado\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.migalhas.com.br\/depeso\/369849\/icms&#8211;o-problema-do-saldo-credor-acumulado<\/a>. Acesso em 20 de maio de 2025.<\/p>\n\n\n\n<p>Assim, o cr\u00e9dito fiscal (cr\u00e9dito do ICMS) \u00e9 o direito que a empresa tem de se apropriar de determinados valores de tributos pagos ou destacados em suas opera\u00e7\u00f5es anteriores, principalmente em compras de mercadorias ou servi\u00e7os, para compensar com os tributos que ela deve recolher nas opera\u00e7\u00f5es seguintes.<\/p>\n\n\n\n<p>Quando a empresa compra mercadorias, ela gera um cr\u00e9dito de ICMS (direito de se abater do valor a pagar).<\/p>\n\n\n\n<p>Quando ela vende mercadorias, ela gera um d\u00e9bito de ICMS (valor que deve ser pago ao fisco).<\/p>\n\n\n\n<p>O valor a pagar ao fisco ser\u00e1: D\u00e9bito de ICMS da venda \u2013 Cr\u00e9dito de ICMS da compra.<\/p>\n\n\n\n<p>Frise-se que a quest\u00e3o quer saber apenas o cr\u00e9dito fiscal, ou seja, o ICMS da compra, n\u00e3o o saldo final a pagar.<\/p>\n\n\n\n<p>Vamos aos c\u00e1lculos:<\/p>\n\n\n\n<p><strong>2. C\u00e1lculo:<\/strong><\/p>\n\n\n\n<p>Compra:<\/p>\n\n\n\n<p>Valor: R$ 7.000,00<\/p>\n\n\n\n<p>Al\u00edquota de ICMS: 15%<\/p>\n\n\n\n<p><strong>Cr\u00e9dito fiscal (ICMS da compra): R$ 7.000,00 \u00d7 15% = R$ 1.050,00<\/strong><\/p>\n\n\n\n<p>Agora se fosse perguntado da seguinte forma \u2013 qual o saldo credor do per\u00edodo, ap\u00f3s o registro cont\u00e1bil da compra e venda dessas mercadorias, a resposta seria ZERO, porque o cr\u00e9dito foi todo absorvido pelo d\u00e9bito. Faltou a informa\u00e7\u00e3o, no enunciado da quest\u00e3o, que houve o confronto entre saldo devedor e credor no Livro Registro de Apura\u00e7\u00e3o (LRA) do ICMS previsto na legisla\u00e7\u00e3o.<\/p>\n\n\n\n<p>Ademais, o Art. 26, par 3\u00b0, VIII, do RICMS-PR, que fala expressamente em \u201ccr\u00e9dito fiscal\u201d e n\u00e3o o trata como resultado da apura\u00e7\u00e3o do imposto (como considerou a banca), mas como o direto de cr\u00e9dito para abater das subsequentes sa\u00eddas.<\/p>\n\n\n\n<p>Ante o exposto, pede-se a <strong>altera\u00e7\u00e3o de gabarito de C para B, <\/strong>uma vez que o conceito de cr\u00e9dito fiscal n\u00e3o se confunde com saldo credor do per\u00edodo. N\u00e3o sendo poss\u00edvel a altera\u00e7\u00e3o, pede-se a anula\u00e7\u00e3o da quest\u00e3o por apresentar mais de uma possibilidade de interpreta\u00e7\u00e3o.<\/p>\n\n\n\n<p class=\"has-text-align-center has-background\" style=\"background-color:#d6dce1\"><strong><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-sefaz-pr\/\" target=\"_blank\" rel=\"noreferrer noopener\">Mais informa\u00e7\u00f5es do concurso Sefaz Paran\u00e1<\/a><\/strong><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<div class=\"container\" id=\"boxes\">\n  <div class=\"row\">\n\n    <div class=\"col-sm\">\n      <div class=\"estrategia\" id=\"box-assinatura\">\n        <h3 class=\"titulo-assinatura\">Assinatura Concursos<\/h3>\n        <p class=\"subtitulo-assinatura\">Assinatura de 1 ano ou 2 anos<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/assinaturas\/\" role=\"button\" rel=\"noopener noreferrer\">ASSINE AGORA<\/a>\n        <\/div>\n      <\/div>\n     \n    <\/div><\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"quer-saber-tudo-sobre-concursos-previstos-confira-nossos-artigos\">Quer saber tudo sobre concursos previstos?<br \/>Confira nossos artigos!<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos Abertos<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-fiscais\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos Fiscais<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2025\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos 2025<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2026\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos 2026<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>O concurso Sefaz PR&nbsp;(Secretaria de Fazenda do Paran\u00e1), para Auditor Fiscal, teve suas provas aplicadas no \u00faltimo domingo, 18. Inclusive, os gabaritos preliminares da etapa j\u00e1 foram divulgados. Com isso, o prazo para interposi\u00e7\u00e3o de recursos ficar\u00e1 aberto entre os dias 20 e 21 de maio, diretamente na \u00e1rea do candidato no site da FGV. [&hellip;]<\/p>\n","protected":false},"author":2134,"featured_media":1557945,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"news","footnotes":""},"categories":[1983,220219],"tags":[867,8],"tax_estado":[219981],"class_list":["post-1577729","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fiscal-estadual","category-noticias","tag-prova-comentada","tag-recurso","tax_estado-pr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Concurso Sefaz PR: veja os recursos de Auditor Fiscal<\/title>\n<meta name=\"description\" content=\"Confira os poss\u00edveis recursos da prova de Auditor Fiscal do concurso Sefaz PR; prazo para interposi\u00e7\u00e3o de recursos em 20 e 21 de maio.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-sefaz-pr-recursos-auditor-fiscal\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Concurso Sefaz PR: veja os recursos de Auditor Fiscal\" \/>\n<meta property=\"og:description\" content=\"Confira os poss\u00edveis recursos da prova de Auditor Fiscal do concurso Sefaz PR; prazo para interposi\u00e7\u00e3o de recursos em 20 e 21 de maio.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-sefaz-pr-recursos-auditor-fiscal\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-20T02:26:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-21T00:03:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/04\/04122902\/concurso-sefaz-pr.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"536\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Rafaela Teixeira\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rafaela Teixeira\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"30 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-sefaz-pr-recursos-auditor-fiscal\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-sefaz-pr-recursos-auditor-fiscal\/\"},\"author\":{\"name\":\"Rafaela Teixeira\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/e75352021ea7f60781c599934f916eb1\"},\"headline\":\"Concurso Sefaz PR: veja os recursos de Auditor Fiscal\",\"datePublished\":\"2025-05-20T02:26:29+00:00\",\"dateModified\":\"2025-05-21T00:03:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-sefaz-pr-recursos-auditor-fiscal\/\"},\"wordCount\":5999,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-sefaz-pr-recursos-auditor-fiscal\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/04\/04122902\/concurso-sefaz-pr.jpg\",\"keywords\":[\"prova comentada\",\"Recurso\"],\"articleSection\":[\"Fiscal - Estadual (ICMS)\",\"\u00daltimas not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-sefaz-pr-recursos-auditor-fiscal\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-sefaz-pr-recursos-auditor-fiscal\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-sefaz-pr-recursos-auditor-fiscal\/\",\"name\":\"Concurso Sefaz PR: veja os recursos de Auditor Fiscal\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-sefaz-pr-recursos-auditor-fiscal\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-sefaz-pr-recursos-auditor-fiscal\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/04\/04122902\/concurso-sefaz-pr.jpg\",\"datePublished\":\"2025-05-20T02:26:29+00:00\",\"dateModified\":\"2025-05-21T00:03:35+00:00\",\"description\":\"Confira os poss\u00edveis recursos da prova de Auditor Fiscal do concurso Sefaz PR; prazo para interposi\u00e7\u00e3o de recursos em 20 e 21 de maio.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-sefaz-pr-recursos-auditor-fiscal\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-sefaz-pr-recursos-auditor-fiscal\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-sefaz-pr-recursos-auditor-fiscal\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/04\/04122902\/concurso-sefaz-pr.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/04\/04122902\/concurso-sefaz-pr.jpg\",\"width\":1024,\"height\":536,\"caption\":\"Sefaz PR resultado final\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-sefaz-pr-recursos-auditor-fiscal\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Concurso Sefaz PR: veja os recursos de Auditor Fiscal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/e75352021ea7f60781c599934f916eb1\",\"name\":\"Rafaela Teixeira\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/8a349a2b22039b1ee88fc06461487c950fd6aa411ea8af8633314b43334ae793?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8a349a2b22039b1ee88fc06461487c950fd6aa411ea8af8633314b43334ae793?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8a349a2b22039b1ee88fc06461487c950fd6aa411ea8af8633314b43334ae793?s=96&d=mm&r=g\",\"caption\":\"Rafaela Teixeira\"},\"description\":\"Rafaela Teixeira \u00e9 advogada conveniada \u00e0 Defensoria P\u00fablica de S\u00e3o Paulo pela OAB, com experi\u00eancia em reda\u00e7\u00e3o jur\u00eddica e atua\u00e7\u00e3o em institui\u00e7\u00f5es p\u00fablicas, incluindo est\u00e1gio no TRE-SP. Possui mais de 7 anos de experi\u00eancia na produ\u00e7\u00e3o de conte\u00fados voltados ao nicho de concursos p\u00fablicos, com foco em apura\u00e7\u00e3o jornal\u00edstica cont\u00ednua, an\u00e1lise de editais e obten\u00e7\u00e3o de informa\u00e7\u00f5es diretamente junto a \u00f3rg\u00e3os e fontes oficiais. No Blog do Estrat\u00e9gia Concursos, atua como Analista de Conte\u00fado S\u00eanior, respons\u00e1vel pelo jornalismo do per\u00edodo noturno e da madrugada, com atua\u00e7\u00e3o transversal na cobertura de concursos p\u00fablicos, garantindo a continuidade, fluidez e confiabilidade das publica\u00e7\u00f5es e dos bastidores dos certames.\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/rafaela-teixeira\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Concurso Sefaz PR: veja os recursos de Auditor Fiscal","description":"Confira os poss\u00edveis recursos da prova de Auditor Fiscal do concurso Sefaz PR; prazo para interposi\u00e7\u00e3o de recursos em 20 e 21 de maio.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-sefaz-pr-recursos-auditor-fiscal\/","og_locale":"pt_BR","og_type":"article","og_title":"Concurso Sefaz PR: veja os recursos de Auditor Fiscal","og_description":"Confira os poss\u00edveis recursos da prova de Auditor Fiscal do concurso Sefaz PR; prazo para interposi\u00e7\u00e3o de recursos em 20 e 21 de maio.","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-sefaz-pr-recursos-auditor-fiscal\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2025-05-20T02:26:29+00:00","article_modified_time":"2025-05-21T00:03:35+00:00","og_image":[{"width":1024,"height":536,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/04\/04122902\/concurso-sefaz-pr.jpg","type":"image\/jpeg"}],"author":"Rafaela Teixeira","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Rafaela Teixeira","Est. tempo de leitura":"30 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-sefaz-pr-recursos-auditor-fiscal\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-sefaz-pr-recursos-auditor-fiscal\/"},"author":{"name":"Rafaela Teixeira","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/e75352021ea7f60781c599934f916eb1"},"headline":"Concurso Sefaz PR: veja os recursos de Auditor Fiscal","datePublished":"2025-05-20T02:26:29+00:00","dateModified":"2025-05-21T00:03:35+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-sefaz-pr-recursos-auditor-fiscal\/"},"wordCount":5999,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-sefaz-pr-recursos-auditor-fiscal\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/04\/04122902\/concurso-sefaz-pr.jpg","keywords":["prova comentada","Recurso"],"articleSection":["Fiscal - Estadual (ICMS)","\u00daltimas not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-sefaz-pr-recursos-auditor-fiscal\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-sefaz-pr-recursos-auditor-fiscal\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-sefaz-pr-recursos-auditor-fiscal\/","name":"Concurso Sefaz PR: veja os recursos de Auditor Fiscal","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-sefaz-pr-recursos-auditor-fiscal\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-sefaz-pr-recursos-auditor-fiscal\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/04\/04122902\/concurso-sefaz-pr.jpg","datePublished":"2025-05-20T02:26:29+00:00","dateModified":"2025-05-21T00:03:35+00:00","description":"Confira os poss\u00edveis recursos da prova de Auditor Fiscal do concurso Sefaz PR; prazo para interposi\u00e7\u00e3o de recursos em 20 e 21 de maio.","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-sefaz-pr-recursos-auditor-fiscal\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-sefaz-pr-recursos-auditor-fiscal\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-sefaz-pr-recursos-auditor-fiscal\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/04\/04122902\/concurso-sefaz-pr.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/04\/04122902\/concurso-sefaz-pr.jpg","width":1024,"height":536,"caption":"Sefaz PR resultado final"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-sefaz-pr-recursos-auditor-fiscal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Concurso Sefaz PR: veja os recursos de Auditor Fiscal"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/e75352021ea7f60781c599934f916eb1","name":"Rafaela Teixeira","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/8a349a2b22039b1ee88fc06461487c950fd6aa411ea8af8633314b43334ae793?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8a349a2b22039b1ee88fc06461487c950fd6aa411ea8af8633314b43334ae793?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8a349a2b22039b1ee88fc06461487c950fd6aa411ea8af8633314b43334ae793?s=96&d=mm&r=g","caption":"Rafaela Teixeira"},"description":"Rafaela Teixeira \u00e9 advogada conveniada \u00e0 Defensoria P\u00fablica de S\u00e3o Paulo pela OAB, com experi\u00eancia em reda\u00e7\u00e3o jur\u00eddica e atua\u00e7\u00e3o em institui\u00e7\u00f5es p\u00fablicas, incluindo est\u00e1gio no TRE-SP. Possui mais de 7 anos de experi\u00eancia na produ\u00e7\u00e3o de conte\u00fados voltados ao nicho de concursos p\u00fablicos, com foco em apura\u00e7\u00e3o jornal\u00edstica cont\u00ednua, an\u00e1lise de editais e obten\u00e7\u00e3o de informa\u00e7\u00f5es diretamente junto a \u00f3rg\u00e3os e fontes oficiais. No Blog do Estrat\u00e9gia Concursos, atua como Analista de Conte\u00fado S\u00eanior, respons\u00e1vel pelo jornalismo do per\u00edodo noturno e da madrugada, com atua\u00e7\u00e3o transversal na cobertura de concursos p\u00fablicos, garantindo a continuidade, fluidez e confiabilidade das publica\u00e7\u00f5es e dos bastidores dos certames.","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/rafaela-teixeira\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1577729","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/2134"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1577729"}],"version-history":[{"count":19,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1577729\/revisions"}],"predecessor-version":[{"id":1578797,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1577729\/revisions\/1578797"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/1557945"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1577729"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1577729"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1577729"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1577729"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}