{"id":1577062,"date":"2025-05-16T15:30:45","date_gmt":"2025-05-16T18:30:45","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=1577062"},"modified":"2025-05-16T15:33:57","modified_gmt":"2025-05-16T18:33:57","slug":"concurso-tj-mg-orgao-especial-aprova-unificacao-na-carreira","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tj-mg-orgao-especial-aprova-unificacao-na-carreira\/","title":{"rendered":"Concurso TJ MG: \u00d3rg\u00e3o Especial aprova unifica\u00e7\u00e3o na carreira!"},"content":{"rendered":"\n<p>No dia 14 de maio, o \u00d3rg\u00e3o Especial do <a href=\"https:\/\/www.estrategiaconcursos.com.br\/cursosPorConcurso\/tj-mg\/\" target=\"_blank\" rel=\"noreferrer noopener\">Tribunal de Justi\u00e7a de Minas Gerais<\/a> , aprovou a resolu\u00e7\u00e3o que trata sobre a unifica\u00e7\u00e3o das especialidades do cargo <strong>Oficial Judici\u00e1rio, Oficial de Justi\u00e7a e Comiss\u00e1rio da Inf\u00e2ncia e da Juventude.<\/strong><\/p>\n\n\n\n<p>A ideia principal da mudan\u00e7a \u00e9 simplificar e flexibilizar a estrutura de cargos, ou seja, as especialidades de Oficial de Justi\u00e7a e Comiss\u00e1rio da Inf\u00e2ncia e Juventude deixam de existir como categorias separadas, e passam a integrar a especialidade \u00fanica de Oficial Judici\u00e1rio. As atividades dos cargos n\u00e3o ser\u00e3o alteradas.<\/p>\n\n\n\n<p>Segundo a resolu\u00e7\u00e3o, <em>\u201cAos servidores que ocupavam, na data da aprova\u00e7\u00e3o desta Resolu\u00e7\u00e3o, as especialidades de Comiss\u00e1rio da Inf\u00e2ncia e da Juventude ou de Oficial de Justi\u00e7a, do cargo de Oficial Judici\u00e1rio do Agrupamento \u201cPermanente\u201d do Quadro de Cargos de Provimento Efetivo do Poder Judici\u00e1rio ser\u00e3o designados para o exerc\u00edcio das atribui\u00e7\u00f5es previstas [&#8230;], fica resguardada a perman\u00eancia no exerc\u00edcio das atividades para as quais foram designados, salvo se houver interesse do servidor\u201d<\/em>.<\/p>\n\n\n\n<p>Para aqueles que demonstrarem interesse em trocar de atribui\u00e7\u00f5es, a altera\u00e7\u00e3o requerer\u00e1 de apresenta\u00e7\u00e3o de requerimento ao Presidente do TJMG, al\u00e9m de estar condicionada ao atendimento do interesse p\u00fablico.<\/p>\n\n\n\n<p>O Sindicato dos Servidores da justi\u00e7a de Minas Gerais afirmou que os servidores designados para atividades externas (como as dos Oficiais de Justi\u00e7a) continuam com os mesmos direitos: adicional de periculosidade, indeniza\u00e7\u00f5es por dilig\u00eancias e controle de frequ\u00eancia adequado \u00e0 fun\u00e7\u00e3o.\u00a0<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-concurso-tjmg-edital-em-breve\">Concurso TJMG: edital em breve<\/h2>\n\n\n\n<p>Vale lembrar que um novo edital estar\u00e1 em breve na pra\u00e7a e j\u00e1 tem banca definida.<\/p>\n\n\n\n<p>Com as principais informa\u00e7\u00f5es da sele\u00e7\u00e3o j\u00e1 divulgadas, o edital pode sair a qualquer momento. As vagas ser\u00e3o de n\u00edvel m\u00e9dio para:;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Oficial Judici\u00e1rio (agora carreira unificada)<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-atribuicoes\">Atribui\u00e7\u00f5es<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Oficial Judici\u00e1rio \u2013 Comiss\u00e3o da Inf\u00e2ncia e da Juventude<\/strong>\n<ul class=\"wp-block-list\">\n<li>Auxiliar no preparo de processos, promover medidas preliminares de instru\u00e7\u00e3o relativas a crian\u00e7as e adolescentes, determinadas pelo juiz;<\/li>\n\n\n\n<li>Lavrar auto de infra\u00e7\u00e3o, quando constatar viola\u00e7\u00e3o das normas de prote\u00e7\u00e3o \u00e0 crian\u00e7a e ao adolescente que tipifiquem infra\u00e7\u00f5es administrativas;<\/li>\n\n\n\n<li>Fiscalizar a execu\u00e7\u00e3o das normas de assist\u00eancia e prote\u00e7\u00e3o que digam respeito \u00e0 crian\u00e7a e ao adolescente;<\/li>\n\n\n\n<li>Cumprir determina\u00e7\u00e3o judicial, com o fim de esclarecer fatos ou circunst\u00e2ncias que possam comprometer a seguran\u00e7a f\u00edsica e moral de crian\u00e7as e adolescentes;<\/li>\n\n\n\n<li>Auxiliar a cria\u00e7\u00e3o e manuten\u00e7\u00e3o de cadastro contendo informa\u00e7\u00f5es sobre crian\u00e7as e adolescentes sob regime de acolhimento familiar e institucional;<\/li>\n\n\n\n<li>Substituir a chefia no seu impedimento ou afastamento, quando indicado pelo superior hier\u00e1rquico;<\/li>\n\n\n\n<li>Participar de comiss\u00f5es e grupos de trabalho, quando designado; e<\/li>\n\n\n\n<li>Executar outras atividades identificadas pelo superior hier\u00e1rquico, relacionadas com a atividade-fim, inclusive no que concerne ao processo judicial eletr\u00f4nico, em suas variadas formas.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>Oficial Judici\u00e1rio \u2013 Oficial Judici\u00e1rio<\/strong>\n<ul class=\"wp-block-list\">\n<li>Executar atividades de suporte nas \u00e1reas judici\u00e1ria e administrativa na Secretaria do Tribunal de Justi\u00e7a ou na Justi\u00e7a de Primeira Inst\u00e2ncia;<\/li>\n\n\n\n<li>Registrar, reunir e avaliar informa\u00e7\u00f5es relativas a processos judiciais e procedimentos administrativos;<\/li>\n\n\n\n<li>Auxiliar o magistrado nas audi\u00eancias ou sess\u00f5es de julgamento;<\/li>\n\n\n\n<li>Redigir e digitar mat\u00e9ria relacionada a sua \u00e1rea de atua\u00e7\u00e3o;<\/li>\n\n\n\n<li>Realizar atos para subsidiar a movimenta\u00e7\u00e3o do processo e demais servi\u00e7os administrativos;<\/li>\n\n\n\n<li>Redigir e digitar mat\u00e9ria relacionada a sua \u00e1rea de atua\u00e7\u00e3o;<\/li>\n\n\n\n<li>Substituir a chefia no seu impedimento ou afastamento, quando indicado pelo superior hier\u00e1rquico;<\/li>\n\n\n\n<li>Participar de comiss\u00f5es e grupos de trabalho;<\/li>\n\n\n\n<li>Executar outras atividades identificadas pelo superior hier\u00e1rquico, relacionadas com a atividade fim, inclusive no que concerne ao processo judicial eletr\u00f4nico em suas variadas formas.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong> Oficial de Justi\u00e7a<\/strong>\n<ul class=\"wp-block-list\">\n<li>realizar cita\u00e7\u00f5es, intima\u00e7\u00f5es, notifica\u00e7\u00f5es e demais dilig\u00eancias pr\u00f3prias de seu of\u00edcio, ordenadas em processos judiciais e lavrar termos e certid\u00f5es respectivas;<\/li>\n\n\n\n<li>executar atividades preparat\u00f3rias para a realiza\u00e7\u00e3o da sess\u00e3o de julgamento;<\/li>\n\n\n\n<li>dar suporte \u00e0s sess\u00f5es realizadas pelos \u00f3rg\u00e3os do Tribunal, executando os servi\u00e7os que lhe forem determinados;<\/li>\n\n\n\n<li>dar suporte \u00e0s audi\u00eancias ou sess\u00f5es do Tribunal do J\u00fari, quando necess\u00e1rio, e coadjuvar o juiz na manuten\u00e7\u00e3o da ordem;<\/li>\n\n\n\n<li>promover as avalia\u00e7\u00f5es judiciais nos casos indicados em lei;<\/li>\n\n\n\n<li>fazer hasta p\u00fablica, onde n\u00e3o houver leiloeiro p\u00fablico ou designado para esse fim;<\/li>\n\n\n\n<li>executar atividades de suporte nas \u00e1reas judici\u00e1rias da Secretaria do Tribunal de Justi\u00e7a e da Justi\u00e7a de Primeira Inst\u00e2ncia;<\/li>\n\n\n\n<li>substituir a chefia no seu impedimento ou afastamento, quando indicado pelo superior hier\u00e1rquico;<\/li>\n\n\n\n<li>participar de comiss\u00f5es e grupos de trabalho, quando designado;<\/li>\n\n\n\n<li>executar outras atividades identificadas pelo superior hier\u00e1rquico, relacionadas com a atividade-fim, inclusive no que concerne ao processo judicial eletr\u00f4nico, em suas variadas formas.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center has-light-green-cyan-background-color has-background has-medium-font-size\" id=\"h-saiba-mais-concurso-tjmg\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-black-color\">Saiba mais:<\/mark> <a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tjmg\/\" target=\"_blank\" rel=\"noreferrer noopener\">concurso TJMG<\/a><\/h2>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"cursos\">Quer saber tudo sobre concursos previstos?<br \/>Confira nossos artigos!<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos abertos<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2025\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos 2025<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2026\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos 2026<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-tribunais\/\">Concursos tribunais<\/a><\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"CURSOS-ASSUNATURA\">Agora que voc\u00ea conferiu sobre as vagas do concurso TJMG, que tal estudar para um novo certame?<\/h2>\n\n\n\n<div class=\"container\" id=\"boxes\">\n  <div class=\"row\">\n\n    <div class=\"col-sm\">\n      <div class=\"banner-tribunal\" id=\"box-assinatura\">\n        <h3 class=\"titulo-assinatura\">Curso TJ MG<\/h3>\n        <p class=\"subtitulo-assinatura\">Conhe\u00e7a os cursos<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/cursosPorConcurso\/tj-mg-oficial-de-apoio-judicial-e-judiciario\/\" role=\"button\" rel=\"noopener noreferrer\">Conhe\u00e7a mais<\/a>\n        <\/div>\n      <\/div>\n      <p class=\"texto-auxiliar\">Prepare-se com o melhor material e com quem mais aprova em Concursos P\u00fablicos em todo o pa\u00eds.<\/p>\n    <\/div>\n\n  <\/div>\n<\/div>\n\n\n\n<div class=\"container\" id=\"boxes\">\n  <div class=\"row\">\n\n    <div class=\"col-sm\">\n      <div class=\"estrategia\" id=\"box-assinatura\">\n        <h3 class=\"titulo-assinatura\">Assinatura Concursos<\/h3>\n        <p class=\"subtitulo-assinatura\">Assinatura de 1 ano ou 2 anos<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/assinaturas\/\" role=\"button\" rel=\"noopener noreferrer\">ASSINE AGORA<\/a>\n        <\/div>\n      <\/div>\n     \n    <\/div><\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/estrategia2013\/\"><\/a><br \/><\/h2>\n","protected":false},"excerpt":{"rendered":"<p>No dia 14 de maio, o \u00d3rg\u00e3o Especial do Tribunal de Justi\u00e7a de Minas Gerais , aprovou a resolu\u00e7\u00e3o que trata sobre a unifica\u00e7\u00e3o das especialidades do cargo Oficial Judici\u00e1rio, Oficial de Justi\u00e7a e Comiss\u00e1rio da Inf\u00e2ncia e da Juventude. A ideia principal da mudan\u00e7a \u00e9 simplificar e flexibilizar a estrutura de cargos, ou seja, [&hellip;]<\/p>\n","protected":false},"author":657,"featured_media":1126024,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"news","footnotes":""},"categories":[1984],"tags":[],"tax_estado":[219974],"class_list":["post-1577062","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tribunais","tax_estado-mg"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Concurso TJ MG: \u00d3rg\u00e3o Especial aprova unifica\u00e7\u00e3o na carreira!<\/title>\n<meta name=\"description\" content=\"Concurso TJ MG: \u00d3rg\u00e3o Especial aprova unifica\u00e7\u00e3o na carreira de Oficial Judici\u00e1rio! Confira o que muda e o que permanece!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tj-mg-orgao-especial-aprova-unificacao-na-carreira\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Concurso TJ MG: \u00d3rg\u00e3o Especial aprova unifica\u00e7\u00e3o na carreira!\" \/>\n<meta property=\"og:description\" content=\"Concurso TJ MG: \u00d3rg\u00e3o Especial aprova unifica\u00e7\u00e3o na carreira de Oficial Judici\u00e1rio! Confira o que muda e o que permanece!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tj-mg-orgao-especial-aprova-unificacao-na-carreira\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-16T18:30:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-16T18:33:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/11\/18104921\/tj-mg.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nat\u00e1lia Scarano\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nat\u00e1lia Scarano\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tj-mg-orgao-especial-aprova-unificacao-na-carreira\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tj-mg-orgao-especial-aprova-unificacao-na-carreira\/\"},\"author\":{\"name\":\"Nat\u00e1lia Scarano\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/751aedf909a9d10cb23ce6ac527ce0f2\"},\"headline\":\"Concurso TJ MG: \u00d3rg\u00e3o Especial aprova unifica\u00e7\u00e3o na carreira!\",\"datePublished\":\"2025-05-16T18:30:45+00:00\",\"dateModified\":\"2025-05-16T18:33:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tj-mg-orgao-especial-aprova-unificacao-na-carreira\/\"},\"wordCount\":914,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tj-mg-orgao-especial-aprova-unificacao-na-carreira\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/11\/18104921\/tj-mg.jpg\",\"articleSection\":[\"Tribunais\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tj-mg-orgao-especial-aprova-unificacao-na-carreira\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tj-mg-orgao-especial-aprova-unificacao-na-carreira\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tj-mg-orgao-especial-aprova-unificacao-na-carreira\/\",\"name\":\"Concurso TJ MG: \u00d3rg\u00e3o Especial aprova unifica\u00e7\u00e3o na carreira!\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tj-mg-orgao-especial-aprova-unificacao-na-carreira\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tj-mg-orgao-especial-aprova-unificacao-na-carreira\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/11\/18104921\/tj-mg.jpg\",\"datePublished\":\"2025-05-16T18:30:45+00:00\",\"dateModified\":\"2025-05-16T18:33:57+00:00\",\"description\":\"Concurso TJ MG: \u00d3rg\u00e3o Especial aprova unifica\u00e7\u00e3o na carreira de Oficial Judici\u00e1rio! Confira o que muda e o que permanece!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tj-mg-orgao-especial-aprova-unificacao-na-carreira\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tj-mg-orgao-especial-aprova-unificacao-na-carreira\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tj-mg-orgao-especial-aprova-unificacao-na-carreira\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/11\/18104921\/tj-mg.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/11\/18104921\/tj-mg.jpg\",\"width\":1200,\"height\":628,\"caption\":\"concurso tjmg 2011\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tj-mg-orgao-especial-aprova-unificacao-na-carreira\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Concurso TJ MG: \u00d3rg\u00e3o Especial aprova unifica\u00e7\u00e3o na carreira!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/751aedf909a9d10cb23ce6ac527ce0f2\",\"name\":\"Nat\u00e1lia Scarano\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/8a889b8db3dbd227a1a78627357ec8fe64f5e99189d1889a270127828ab372ac?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8a889b8db3dbd227a1a78627357ec8fe64f5e99189d1889a270127828ab372ac?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8a889b8db3dbd227a1a78627357ec8fe64f5e99189d1889a270127828ab372ac?s=96&d=mm&r=g\",\"caption\":\"Nat\u00e1lia Scarano\"},\"description\":\"Jornalista, formada e p\u00f3s graduada pelo IESB, faz parte do time de jornalistas do Estrat\u00e9gia desde 2017. Possui familiaridade com as \u00e1reas de Tribunais, Defensorias, Procuradorias, Minist\u00e9rios P\u00fablicos, Conselhos, Educa\u00e7\u00e3o, \u00c1rea de Seguran\u00e7a, concursos de Carreiras Jur\u00eddicas e OAB. Experi\u00eancia em marketing digital, assessoria de comunica\u00e7\u00e3o e institucional na \u00e1rea privada e p\u00fablica, com atua\u00e7\u00e3o em \u00f3rg\u00e3os como CGU, Cofen e CNM.\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/natalia-scaranoestrategiaconcursos-com-br\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Concurso TJ MG: \u00d3rg\u00e3o Especial aprova unifica\u00e7\u00e3o na carreira!","description":"Concurso TJ MG: \u00d3rg\u00e3o Especial aprova unifica\u00e7\u00e3o na carreira de Oficial Judici\u00e1rio! Confira o que muda e o que permanece!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tj-mg-orgao-especial-aprova-unificacao-na-carreira\/","og_locale":"pt_BR","og_type":"article","og_title":"Concurso TJ MG: \u00d3rg\u00e3o Especial aprova unifica\u00e7\u00e3o na carreira!","og_description":"Concurso TJ MG: \u00d3rg\u00e3o Especial aprova unifica\u00e7\u00e3o na carreira de Oficial Judici\u00e1rio! Confira o que muda e o que permanece!","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tj-mg-orgao-especial-aprova-unificacao-na-carreira\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2025-05-16T18:30:45+00:00","article_modified_time":"2025-05-16T18:33:57+00:00","og_image":[{"width":1200,"height":628,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/11\/18104921\/tj-mg.jpg","type":"image\/jpeg"}],"author":"Nat\u00e1lia Scarano","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Nat\u00e1lia Scarano","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tj-mg-orgao-especial-aprova-unificacao-na-carreira\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tj-mg-orgao-especial-aprova-unificacao-na-carreira\/"},"author":{"name":"Nat\u00e1lia Scarano","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/751aedf909a9d10cb23ce6ac527ce0f2"},"headline":"Concurso TJ MG: \u00d3rg\u00e3o Especial aprova unifica\u00e7\u00e3o na carreira!","datePublished":"2025-05-16T18:30:45+00:00","dateModified":"2025-05-16T18:33:57+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tj-mg-orgao-especial-aprova-unificacao-na-carreira\/"},"wordCount":914,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tj-mg-orgao-especial-aprova-unificacao-na-carreira\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/11\/18104921\/tj-mg.jpg","articleSection":["Tribunais"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tj-mg-orgao-especial-aprova-unificacao-na-carreira\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tj-mg-orgao-especial-aprova-unificacao-na-carreira\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tj-mg-orgao-especial-aprova-unificacao-na-carreira\/","name":"Concurso TJ MG: \u00d3rg\u00e3o Especial aprova unifica\u00e7\u00e3o na carreira!","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tj-mg-orgao-especial-aprova-unificacao-na-carreira\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tj-mg-orgao-especial-aprova-unificacao-na-carreira\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/11\/18104921\/tj-mg.jpg","datePublished":"2025-05-16T18:30:45+00:00","dateModified":"2025-05-16T18:33:57+00:00","description":"Concurso TJ MG: \u00d3rg\u00e3o Especial aprova unifica\u00e7\u00e3o na carreira de Oficial Judici\u00e1rio! Confira o que muda e o que permanece!","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tj-mg-orgao-especial-aprova-unificacao-na-carreira\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tj-mg-orgao-especial-aprova-unificacao-na-carreira\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tj-mg-orgao-especial-aprova-unificacao-na-carreira\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/11\/18104921\/tj-mg.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/11\/18104921\/tj-mg.jpg","width":1200,"height":628,"caption":"concurso tjmg 2011"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tj-mg-orgao-especial-aprova-unificacao-na-carreira\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Concurso TJ MG: \u00d3rg\u00e3o Especial aprova unifica\u00e7\u00e3o na carreira!"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/751aedf909a9d10cb23ce6ac527ce0f2","name":"Nat\u00e1lia Scarano","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/8a889b8db3dbd227a1a78627357ec8fe64f5e99189d1889a270127828ab372ac?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8a889b8db3dbd227a1a78627357ec8fe64f5e99189d1889a270127828ab372ac?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8a889b8db3dbd227a1a78627357ec8fe64f5e99189d1889a270127828ab372ac?s=96&d=mm&r=g","caption":"Nat\u00e1lia Scarano"},"description":"Jornalista, formada e p\u00f3s graduada pelo IESB, faz parte do time de jornalistas do Estrat\u00e9gia desde 2017. Possui familiaridade com as \u00e1reas de Tribunais, Defensorias, Procuradorias, Minist\u00e9rios P\u00fablicos, Conselhos, Educa\u00e7\u00e3o, \u00c1rea de Seguran\u00e7a, concursos de Carreiras Jur\u00eddicas e OAB. Experi\u00eancia em marketing digital, assessoria de comunica\u00e7\u00e3o e institucional na \u00e1rea privada e p\u00fablica, com atua\u00e7\u00e3o em \u00f3rg\u00e3os como CGU, Cofen e CNM.","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/natalia-scaranoestrategiaconcursos-com-br\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1577062","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/657"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1577062"}],"version-history":[{"count":4,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1577062\/revisions"}],"predecessor-version":[{"id":1577084,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1577062\/revisions\/1577084"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/1126024"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1577062"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1577062"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1577062"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1577062"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}