{"id":1575563,"date":"2025-05-18T07:45:00","date_gmt":"2025-05-18T10:45:00","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=1575563"},"modified":"2025-05-16T13:39:01","modified_gmt":"2025-05-16T16:39:01","slug":"simulado-especial-area-de-controle","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/simulado-especial-area-de-controle\/","title":{"rendered":"1\u00ba Simulado Especial \u00c1rea de Controle para FGV (pr\u00e9-edital)"},"content":{"rendered":"\n<p>A<strong> \u00e1rea de controle <\/strong>\u00e9 uma das mais abrangentes no mundo dos concursos p\u00fablicos, ofertando vagas tanto para forma\u00e7\u00e3o geral quanto para gradua\u00e7\u00f5es em \u00e1reas espec\u00edficas (Exs.: Direito, Engenharia, Ci\u00eancias Cont\u00e1beis&#8230;).<\/p>\n\n\n\n<p>Al\u00e9m disso, \u00e9 poss\u00edvel encontrar oportunidades em \u00e2mbito municipal, estadual e federal. Atualmente, os certames mais quentes s\u00e3o os do <strong>TCE PE<\/strong>, <strong>TCE RS<\/strong> e <strong>TCU<\/strong>.<\/p>\n\n\n\n<p>Se voc\u00ea se prepara para alguma sele\u00e7\u00e3o da \u00e1rea, preste bem aten\u00e7\u00e3o no que trouxemos para voc\u00ea! Vamos realizar neste domingo, 18 de maio, o <strong>1\u00ba<\/strong> <strong>Simulado Especial para \u00c1rea de Controle<\/strong>, com foco na banca <strong>FGV<\/strong>.<\/p>\n\n\n\n<p>Ser\u00e3o 4 horas para responder <strong>80 quest\u00f5es <\/strong>de m\u00faltipla escolha (cinco alternativas), al\u00e9m de uma parte discursiva. Ficou interessado? Confira os detalhes:<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-cronograma-de-aplicacao-do-simulado-especial-para-area-de-controle\">Cronograma de aplica\u00e7\u00e3o do Simulado Especial para \u00c1rea de Controle<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>In\u00edcio da prova:<\/strong>&nbsp;\u00e0s 8h<\/li>\n\n\n\n<li><strong>Fim da aplica\u00e7\u00e3o:<\/strong>&nbsp;\u00e0s 12h<\/li>\n\n\n\n<li><strong>Corre\u00e7\u00e3o AO VIVO:<\/strong>&nbsp;a partir das 14h<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-estrutura-das-questoes-do-simulado-especial-para-area-de-controle\">Estrutura das quest\u00f5es do Simulado Especial para \u00c1rea de Controle<\/h2>\n\n\n\n<figure class=\"wp-block-table is-style-stripes\"><table><thead><tr><th class=\"has-text-align-center\" data-align=\"center\">Disciplina<\/th><th class=\"has-text-align-center\" data-align=\"center\">N\u00famero de quest\u00f5es<\/th><th class=\"has-text-align-center\" data-align=\"center\">Respons\u00e1vel<\/th><\/tr><\/thead><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\" colspan=\"4\"><strong>Conhecimentos Gerais &#8211; 40<\/strong><\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Portugu\u00eas&nbsp;<\/td><td class=\"has-text-align-center\" data-align=\"center\">12<\/td><td class=\"has-text-align-center\" data-align=\"center\">Patricia Manzato<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Matem\u00e1tica Financeira<\/td><td class=\"has-text-align-center\" data-align=\"center\">5<\/td><td class=\"has-text-align-center\" data-align=\"center\">Eduardo Mocellin<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Estat\u00edstica<\/td><td class=\"has-text-align-center\" data-align=\"center\">5<\/td><td class=\"has-text-align-center\" data-align=\"center\">Carlos Henrique<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Racioc\u00ednio L\u00f3gico<\/td><td class=\"has-text-align-center\" data-align=\"center\">4<\/td><td class=\"has-text-align-center\" data-align=\"center\">Eduardo Mocellin<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Direito Constitucional<\/td><td class=\"has-text-align-center\" data-align=\"center\">7<\/td><td class=\"has-text-align-center\" data-align=\"center\">Adriane Fauth<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Direito Administrativo<\/td><td class=\"has-text-align-center\" data-align=\"center\">7<\/td><td class=\"has-text-align-center\" data-align=\"center\">Fabiano Pereira<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\" colspan=\"4\"><strong>Conhecimentos Espec\u00edficos &#8211; 50<\/strong><\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Administra\u00e7\u00e3o Financeira e Or\u00e7ament\u00e1ria&nbsp;<\/td><td class=\"has-text-align-center\" data-align=\"center\">6<\/td><td class=\"has-text-align-center\" data-align=\"center\">Leandro Ravyelle<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Administra\u00e7\u00e3o P\u00fablica<\/td><td class=\"has-text-align-center\" data-align=\"center\">6<\/td><td class=\"has-text-align-center\" data-align=\"center\">Stefan Fantini<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">An\u00e1lise de Dados<\/td><td class=\"has-text-align-center\" data-align=\"center\">6<\/td><td class=\"has-text-align-center\" data-align=\"center\">Emannuelle Gouveia<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Auditoria Governamental<\/td><td class=\"has-text-align-center\" data-align=\"center\">6<\/td><td class=\"has-text-align-center\" data-align=\"center\">Guilherme Santanna<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Contabilidade Aplicada ao Setor P\u00fablico<\/td><td class=\"has-text-align-center\" data-align=\"center\">6<\/td><td class=\"has-text-align-center\" data-align=\"center\">Gilmar Possati<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Controle Externo<\/td><td class=\"has-text-align-center\" data-align=\"center\">5<\/td><td class=\"has-text-align-center\" data-align=\"center\">Herbert Almeida<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Pol\u00edticas P\u00fablicas<\/td><td class=\"has-text-align-center\" data-align=\"center\">5<\/td><td class=\"has-text-align-center\" data-align=\"center\">Rodrigo Renn\u00f3<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Discursiva<\/td><td class=\"has-text-align-center\" data-align=\"center\">1<\/td><td class=\"has-text-align-center\" data-align=\"center\">Carlos Roberto<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-simulado-especial-para-area-de-controle-e-ranking-estrategico\">Simulado Especial para \u00c1rea de Controle e Ranking Estrat\u00e9gico<\/h2>\n\n\n\n<p class=\"has-text-align-center has-very-light-gray-background-color has-background\" style=\"font-size:clamp(14.642px, 0.915rem + ((1vw - 3.2px) * 0.721), 22px);px\"><strong><a href=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/05\/16133711\/sem_comentario_area_controle_18-05.pdf\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Baixe o PDF do Simulado<\/a><\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong><\/strong><strong><a href=\"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLSefwYhAz2Hm6wG0g765-AmlQZeorL5icG2mQ7bBGGks93Qv_g\/viewform?usp=send_form\" target=\"_blank\" rel=\"noreferrer noopener\">Conte-nos o que achou desse simulado!<\/a><\/strong><\/li>\n<\/ul>\n\n\n\n<p class=\"has-text-align-center has-very-light-gray-background-color has-background\" style=\"font-size:clamp(14.642px, 0.915rem + ((1vw - 3.2px) * 0.721), 22px);px\"><strong><a href=\"https:\/\/forms.gle\/TgVTDpUaKZK6zPYj9\" target=\"_blank\" rel=\"noreferrer noopener\">Preencha aqui seu gabarito<\/a><\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center has-very-light-gray-background-color has-background\" style=\"font-size:clamp(14.642px, 0.915rem + ((1vw - 3.2px) * 0.721), 22px);px\"><strong><a href=\"https:\/\/docs.google.com\/spreadsheets\/d\/1K3sNz6c3NGb8jNwA-LeI8PsxwqkeIgTfl8rebjMBJ2g\/edit?usp=sharing\" target=\"_blank\" rel=\"noreferrer noopener\">Ranking Estrat\u00e9gico<\/a><\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-correcao-ao-vivo-a-partir-das-14h\">Corre\u00e7\u00e3o AO VIVO \u2013 a partir das 14h<\/h2>\n\n\n\n<p>Para que voc\u00ea possa conferir seu desempenho, a partir das&nbsp;14h, nossos professores ir\u00e3o realizar a corre\u00e7\u00e3o das quest\u00f5es em transmiss\u00e3o ao vivo no canal do Estrat\u00e9gia no Youtube. <\/p>\n\n\n\n<p>Acompanhe nossa corre\u00e7\u00e3o e aproveite para tirar todas as suas d\u00favidas a respeito do simulado!<\/p>\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio lyte-align aligncenter\"><div class=\"lyte-wrapper\" style=\"width:853px;max-width:100%;margin:5px;\"><div class=\"lyMe\" id=\"WYL_EIMBE9oJU0s\"><div id=\"lyte_EIMBE9oJU0s\" data-src=\"\/\/i.ytimg.com\/vi\/EIMBE9oJU0s\/hqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\"><\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/EIMBE9oJU0s\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/EIMBE9oJU0s\/0.jpg\" alt=\"YouTube video thumbnail\" width=\"853\" height=\"460\" \/><br \/>Assista a este v\u00eddeo no YouTube<\/a><\/noscript><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:853px;margin:5px;\"><\/div><figcaption><\/figcaption><\/figure>\n\n\n<p class=\"has-luminous-vivid-amber-background-color has-background\"><strong>ATEN\u00c7\u00c3O!&nbsp;<\/strong>os&nbsp;<strong>gabaritos&nbsp;<\/strong>dos simulados ser\u00e3o divulgados junto com os respectivos cadernos de provas comentados, exclusivamente na \u00e1rea do aluno.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity\"\/>\n\n\n\n<p class=\"has-text-align-center has-very-light-gray-background-color has-background\" style=\"font-size:clamp(14.642px, 0.915rem + ((1vw - 3.2px) * 0.721), 22px);px\"><strong>Saiba mais:&nbsp;<a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-controle\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos Controle<\/a><\/strong><\/p>\n\n\n\n<div class=\"container\" id=\"boxes\">\n  <div class=\"row\">\n\n    <div class=\"col-sm\">\n      <div class=\"banner-controle-ec\" id=\"box-assinatura\">\n        <h2 class=\"titulo-assinatura\" style=\"text-align: left;\">Concursos Controle<\/h2>\n        <p class=\"subtitulo-assinatura\" style=\"text-align: left;\">Prepara\u00e7\u00e3o completa para os concursos<\/p>\n        <div class=\"box-botao\" style=\"text-align: left;\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/cursosPorConcurso\/cursos-para-concursos-da-area-de-controle\/\" role=\"button\" rel=\"noopener noreferrer\">VER CURSOS<\/a>\n        <\/div>\n      <\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"container\" id=\"boxes\">\r\n  <div class=\"row\">\r\n\r\n    <div class=\"col-sm\">\r\n      <div class=\"estrategia\" id=\"box-assinatura\">\r\n        <h3 class=\"titulo-assinatura\">Assinatura Concursos<\/h3>\r\n        <p class=\"subtitulo-assinatura\">Assinatura de 1 ano ou 2 anos<\/p>\r\n        <div class=\"box-botao\">\r\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/assinaturas\/\" role=\"button\" rel=\"noopener noreferrer\">ASSINE AGORA<\/a>\r\n        <\/div>\r\n      <\/div>\r\n     \r\n    <\/div><\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"h-quer-saber-tudo-sobre-concursos-previstos-confira-nossos-artigos\">Quer saber tudo sobre concursos previstos?<br \/>Confira nossos artigos!<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos Abertos<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2025\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos 2025<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2026\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos 2026<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>A \u00e1rea de controle \u00e9 uma das mais abrangentes no mundo dos concursos p\u00fablicos, ofertando vagas tanto para forma\u00e7\u00e3o geral quanto para gradua\u00e7\u00f5es em \u00e1reas espec\u00edficas (Exs.: Direito, Engenharia, Ci\u00eancias Cont\u00e1beis&#8230;). Al\u00e9m disso, \u00e9 poss\u00edvel encontrar oportunidades em \u00e2mbito municipal, estadual e federal. Atualmente, os certames mais quentes s\u00e3o os do TCE PE, TCE RS [&hellip;]<\/p>\n","protected":false},"author":659,"featured_media":1577001,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"news","footnotes":""},"categories":[220180,214710,220219],"tags":[],"tax_estado":[219963],"class_list":["post-1575563","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-controle-gestao","category-tribunais-de-contas","category-noticias","tax_estado-concursos-federais"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>1\u00ba Simulado Especial \u00c1rea de Controle para FGV (pr\u00e9-edital)<\/title>\n<meta name=\"description\" content=\"Participe gratuitamente do nosso 1\u00ba Simulado Especial para a \u00c1rea de Controle - banca FGV. \u00c9 hoje (18), a partir das 8h.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/simulado-especial-area-de-controle\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"1\u00ba Simulado Especial \u00c1rea de Controle para FGV (pr\u00e9-edital)\" \/>\n<meta property=\"og:description\" content=\"Participe gratuitamente do nosso 1\u00ba Simulado Especial para a \u00c1rea de Controle - banca FGV. \u00c9 hoje (18), a partir das 8h.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/simulado-especial-area-de-controle\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-18T10:45:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/05\/16133852\/capturar.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1324\" \/>\n\t<meta property=\"og:image:height\" content=\"689\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Camila Leite\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Camila Leite\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/simulado-especial-area-de-controle\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/simulado-especial-area-de-controle\/\"},\"author\":{\"name\":\"Camila Leite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/84ecdc6eb58d3cf1689bf76c5cd8fb38\"},\"headline\":\"1\u00ba Simulado Especial \u00c1rea de Controle para FGV (pr\u00e9-edital)\",\"datePublished\":\"2025-05-18T10:45:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/simulado-especial-area-de-controle\/\"},\"wordCount\":428,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/simulado-especial-area-de-controle\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/05\/16133852\/capturar.jpg\",\"articleSection\":[\"Controladorias\/Gest\u00e3o (CGU, CGE, STN, EPPGG)\",\"Tribunais de Contas (TCU, TCE, TCM)\",\"\u00daltimas not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/simulado-especial-area-de-controle\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/simulado-especial-area-de-controle\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/simulado-especial-area-de-controle\/\",\"name\":\"1\u00ba Simulado Especial \u00c1rea de Controle para FGV (pr\u00e9-edital)\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/simulado-especial-area-de-controle\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/simulado-especial-area-de-controle\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/05\/16133852\/capturar.jpg\",\"datePublished\":\"2025-05-18T10:45:00+00:00\",\"description\":\"Participe gratuitamente do nosso 1\u00ba Simulado Especial para a \u00c1rea de Controle - banca FGV. \u00c9 hoje (18), a partir das 8h.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/simulado-especial-area-de-controle\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/simulado-especial-area-de-controle\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/simulado-especial-area-de-controle\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/05\/16133852\/capturar.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/05\/16133852\/capturar.jpg\",\"width\":1324,\"height\":689},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/simulado-especial-area-de-controle\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"1\u00ba Simulado Especial \u00c1rea de Controle para FGV (pr\u00e9-edital)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/84ecdc6eb58d3cf1689bf76c5cd8fb38\",\"name\":\"Camila Leite\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/f2f8faef639c8a2bfb7fb909912a56917f4c3a0aed064500168e2fb8ea55cf61?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f2f8faef639c8a2bfb7fb909912a56917f4c3a0aed064500168e2fb8ea55cf61?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f2f8faef639c8a2bfb7fb909912a56917f4c3a0aed064500168e2fb8ea55cf61?s=96&d=mm&r=g\",\"caption\":\"Camila Leite\"},\"description\":\"Formada em Design Gr\u00e1fico e em Propaganda e Marketing pela UNIP, integra a equipe de jornalismo do Estrat\u00e9gia Concursos desde 2018. Ao longo dos anos, construiu uma s\u00f3lida experi\u00eancia na produ\u00e7\u00e3o de conte\u00fado informativo e relevante para concurseiros. Desde 2020, atua na cobertura das \u00e1reas Fiscal \u2014 com \u00eanfase nas Secretarias de Fazenda (Sefaz) das regi\u00f5es Sul e Sudeste \u2014, al\u00e9m da cobertura de concursos federais, como CNU, Petrobras, CGU, Receita Federal, ag\u00eancias reguladoras (Anvisa, ANAC, entre outras) e INSS. Mant\u00e9m contato direto com os principais \u00f3rg\u00e3os p\u00fablicos, acompanhando editais, atualiza\u00e7\u00f5es e movimenta\u00e7\u00f5es importantes para os candidatos.\",\"sameAs\":[\"https:\/\/www.linkedin.com\/in\/camila-pinheiro-leite-9ba135b6\/\"],\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/camila-leiteestrategiaconcursos-com-br\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"1\u00ba Simulado Especial \u00c1rea de Controle para FGV (pr\u00e9-edital)","description":"Participe gratuitamente do nosso 1\u00ba Simulado Especial para a \u00c1rea de Controle - banca FGV. \u00c9 hoje (18), a partir das 8h.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/simulado-especial-area-de-controle\/","og_locale":"pt_BR","og_type":"article","og_title":"1\u00ba Simulado Especial \u00c1rea de Controle para FGV (pr\u00e9-edital)","og_description":"Participe gratuitamente do nosso 1\u00ba Simulado Especial para a \u00c1rea de Controle - banca FGV. \u00c9 hoje (18), a partir das 8h.","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/simulado-especial-area-de-controle\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2025-05-18T10:45:00+00:00","og_image":[{"width":1324,"height":689,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/05\/16133852\/capturar.jpg","type":"image\/jpeg"}],"author":"Camila Leite","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Camila Leite","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/simulado-especial-area-de-controle\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/simulado-especial-area-de-controle\/"},"author":{"name":"Camila Leite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/84ecdc6eb58d3cf1689bf76c5cd8fb38"},"headline":"1\u00ba Simulado Especial \u00c1rea de Controle para FGV (pr\u00e9-edital)","datePublished":"2025-05-18T10:45:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/simulado-especial-area-de-controle\/"},"wordCount":428,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/simulado-especial-area-de-controle\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/05\/16133852\/capturar.jpg","articleSection":["Controladorias\/Gest\u00e3o (CGU, CGE, STN, EPPGG)","Tribunais de Contas (TCU, TCE, TCM)","\u00daltimas not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/simulado-especial-area-de-controle\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/simulado-especial-area-de-controle\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/simulado-especial-area-de-controle\/","name":"1\u00ba Simulado Especial \u00c1rea de Controle para FGV (pr\u00e9-edital)","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/simulado-especial-area-de-controle\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/simulado-especial-area-de-controle\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/05\/16133852\/capturar.jpg","datePublished":"2025-05-18T10:45:00+00:00","description":"Participe gratuitamente do nosso 1\u00ba Simulado Especial para a \u00c1rea de Controle - banca FGV. \u00c9 hoje (18), a partir das 8h.","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/simulado-especial-area-de-controle\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/simulado-especial-area-de-controle\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/simulado-especial-area-de-controle\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/05\/16133852\/capturar.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/05\/16133852\/capturar.jpg","width":1324,"height":689},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/simulado-especial-area-de-controle\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"1\u00ba Simulado Especial \u00c1rea de Controle para FGV (pr\u00e9-edital)"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/84ecdc6eb58d3cf1689bf76c5cd8fb38","name":"Camila Leite","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/f2f8faef639c8a2bfb7fb909912a56917f4c3a0aed064500168e2fb8ea55cf61?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f2f8faef639c8a2bfb7fb909912a56917f4c3a0aed064500168e2fb8ea55cf61?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f2f8faef639c8a2bfb7fb909912a56917f4c3a0aed064500168e2fb8ea55cf61?s=96&d=mm&r=g","caption":"Camila Leite"},"description":"Formada em Design Gr\u00e1fico e em Propaganda e Marketing pela UNIP, integra a equipe de jornalismo do Estrat\u00e9gia Concursos desde 2018. Ao longo dos anos, construiu uma s\u00f3lida experi\u00eancia na produ\u00e7\u00e3o de conte\u00fado informativo e relevante para concurseiros. Desde 2020, atua na cobertura das \u00e1reas Fiscal \u2014 com \u00eanfase nas Secretarias de Fazenda (Sefaz) das regi\u00f5es Sul e Sudeste \u2014, al\u00e9m da cobertura de concursos federais, como CNU, Petrobras, CGU, Receita Federal, ag\u00eancias reguladoras (Anvisa, ANAC, entre outras) e INSS. Mant\u00e9m contato direto com os principais \u00f3rg\u00e3os p\u00fablicos, acompanhando editais, atualiza\u00e7\u00f5es e movimenta\u00e7\u00f5es importantes para os candidatos.","sameAs":["https:\/\/www.linkedin.com\/in\/camila-pinheiro-leite-9ba135b6\/"],"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/camila-leiteestrategiaconcursos-com-br\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1575563","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/659"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1575563"}],"version-history":[{"count":7,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1575563\/revisions"}],"predecessor-version":[{"id":1577002,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1575563\/revisions\/1577002"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/1577001"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1575563"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1575563"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1575563"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1575563"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}