{"id":1572924,"date":"2025-06-09T18:02:00","date_gmt":"2025-06-09T21:02:00","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=1572924"},"modified":"2025-06-10T08:30:45","modified_gmt":"2025-06-10T11:30:45","slug":"cnu-2025-provas-confirmadas","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-provas-confirmadas\/","title":{"rendered":"CNU 2025 j\u00e1 tem etapas de provas confirmadas; confira!"},"content":{"rendered":"\n<p style=\"font-size:clamp(16.293px, 1.018rem + ((1vw - 3.2px) * 0.854), 25px);\"><em><strong>Provas do CNU 2025 ser\u00e3o divididas em duas fases<\/strong><\/em><\/p>\n\n\n\n<p>Com edital previsto para julho, muitos concurseiros querem se debru\u00e7ar nos estudos para as <strong>provas <\/strong>do <strong>CNU 2025<\/strong> quanto antes, mas, quais etapas foram confirmadas at\u00e9 o momento?<\/p>\n\n\n\n<p>A resposta deste questionamento \u00e9 primordial para que voc\u00ea elabore corretamente um plano de estudos, bem como usufruir da \u00faltima edi\u00e7\u00e3o de base para seus momentos a s\u00f3s com os livros.<\/p>\n\n\n\n<p>Dessa forma, \u00e9 primordial que voc\u00ea fique atento aos detalhes e, assim, alcance uma das <strong>3,6 mil vagas<\/strong> ofertadas no novo <strong>&#8220;ENEM dos concursos&#8221;!<\/strong><\/p>\n\n\n\n<div class=\"container\" id=\"boxes\">\r\n  <div class=\"row\">\r\n\r\n    <div class=\"col-sm\">\r\n      <div class=\"banner-federais\" id=\"box-assinatura\">\r\n        <h2 class=\"titulo-assinatura\" style=\"text-align: left;\">Cursos para o CNU<\/h2>\r\n        <p class=\"subtitulo-assinatura\" style=\"text-align: left;\">Prepare-se para o &#8220;Enem dos Concursos&#8221;!<\/p>\r\n        <div class=\"box-botao\" style=\"text-align: left;\">\r\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/cursosPorConcurso\/concurso-nacional-unificado-cnu\/\" role=\"button\" rel=\"noopener noreferrer\">Confira os pacotes!<\/a>\r\n        <\/div>\r\n      <\/div><\/div><\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-quais-sao-as-etapas-confirmadas-do-cnu-2025\">Quais s\u00e3o as etapas confirmadas do CNU 2025?<\/h2>\n\n\n\n<p>At\u00e9 o momento, sabe-se que o <strong>CNU 2025<\/strong> ter\u00e1 duas etapas de provas, sob organiza\u00e7\u00e3o da <a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/fgv-banca-cnu-2025\/\" target=\"_blank\" rel=\"noreferrer noopener\">banca<\/a> <strong>FGV<\/strong>: <\/p>\n\n\n\n<p><strong>I &#8211; primeira etapa, dividida nas seguintes fases:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Fase 1 <\/strong>&#8211; exame de habilidades e conhecimentos a serem aferidos por meio de aplica\u00e7\u00e3o de <strong>provas objetivas<\/strong>, de car\u00e1ter classificat\u00f3rio e eliminat\u00f3rio;<\/li>\n\n\n\n<li><strong>Fase 2 <\/strong>&#8211; exame de habilidades e conhecimentos a serem aferidos por meio da aplica\u00e7\u00e3o de <strong>provas discursivas<\/strong>, de car\u00e1ter classificat\u00f3rio e eliminat\u00f3rio;<\/li>\n\n\n\n<li><strong>Fase 3 &#8211; <\/strong>destinada a <strong>avalia\u00e7\u00e3o de t\u00edtulos<\/strong>, de car\u00e1ter classificat\u00f3rio;<\/li>\n\n\n\n<li><strong>Fase 4 &#8211;<\/strong> subdividida nos seguintes itens:\n<ul class=\"wp-block-list\">\n<li><strong>a) per\u00edcia m\u00e9dica<\/strong> dos candidatos que se declararem com defici\u00eancia, de car\u00e1ter unicamente eliminat\u00f3rio, para verificar se efetivamente se trata de pessoas com defici\u00eancia, bem como a compatibilidade entre as atribui\u00e7\u00f5es do cargo e a defici\u00eancia apresentada pelos candidatos; e<\/li>\n\n\n\n<li><strong>b) procedimento de verifica\u00e7\u00e3o <\/strong>da condi\u00e7\u00e3o declarada para concorrer \u00e0s vagas reservadas aos candidatos negros, de car\u00e1ter unicamente eliminat\u00f3rio, na forma das disposi\u00e7\u00f5es da Instru\u00e7\u00e3o Normativa MGI n\u00ba 23, de 25 de julho de 2023.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<p><strong>II &#8211; segunda etapa, para os cargos em que couber, destinada ao curso ou programa de forma\u00e7\u00e3o, de car\u00e1ter eliminat\u00f3rio.<\/strong><\/p>\n\n\n\n<p>A <strong>prova objetiva<\/strong> \u00e9 prevista para o dia <strong>05 de outubro<\/strong>. O exame ser\u00e1 composto por quest\u00f5es de m\u00faltipla escolha e cada um ter\u00e1 um total de <strong>cinco alternativas<\/strong>, sendo apenas uma a correta. <\/p>\n\n\n\n<p>J\u00e1 a <strong>prova discursiva<\/strong> \u00e9 prevista para <strong>07 de dezembro<\/strong>. Entretanto, um n\u00famero significativo de concurseiros aprovados na prova objetiva ser\u00e3o convocados para essa fase.<\/p>\n\n\n\n<p>O n\u00famero pode chegar at\u00e9 <strong>9 vezes <\/strong>o n\u00famero de vagas de cada cargo. Por exemplo, uma carreira com 100 vagas, at\u00e9 900 aprovados passar\u00e3o para esta fase e enfrentar\u00e3o a avalia\u00e7\u00e3o discursiva.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-enem-dos-concursos-tera-3-6-mil-vagas-e-salarios-de-ate-r-16-4-mil\">ENEM dos concursos ter\u00e1 3,6 mil vagas e sal\u00e1rios de at\u00e9 R$ 16,4 mil!<\/h2>\n\n\n\n<p>O <strong>Concurso Nacional Unificado (CNU)<\/strong> de <strong>2025 <\/strong>ofertar\u00e1 um total de <strong>3.652 vagas<\/strong> para <strong>36<\/strong> \u00f3rg\u00e3os federais. Este quantitativo se divide entre provimentos imediatos e de cadastro reserva.<\/p>\n\n\n\n<p>Ao todo, ser\u00e3o <strong>2.480 oportunidades<\/strong> contempladas de forma imediata, sendo 1.972 de n\u00edvel superior e 508 de n\u00edvel m\u00e9dio. Enquanto <strong>1.172 vagas<\/strong> ser\u00e3o exclusivas para forma\u00e7\u00e3o de cadastro reserva.<\/p>\n\n\n\n<p>J\u00e1 os sal\u00e1rios possuem valores pra l\u00e1 de surpreendentes, uma vez que alcan\u00e7am at\u00e9 <strong>R$ 16,4 mil<\/strong>, isso sem contar benef\u00edcios como aux\u00edlio-alimenta\u00e7\u00e3o (R$ 1 mil), aux\u00edlio-transporte, plano de sa\u00fade e aux\u00edlio-creche.<\/p>\n\n\n\n<p>Ademais, a previs\u00e3o \u00e9 de que o edital seja publicado em julho deste ano e as inscri\u00e7\u00f5es sejam abertas no mesmo m\u00eas.<\/p>\n\n\n\n<p class=\"has-text-align-center\"> <em>Para ficar por dentro de todas as informa\u00e7\u00f5es sobre o CNU <a href=\"https:\/\/www.gov.br\/gestao\/pt-br\/concursonacional\" target=\"_blank\" rel=\"noreferrer noopener\">2025<\/a>, al\u00e9m das provas confirmadas, n\u00e3o deixe de conferir nosso artigo completo sobre a sele\u00e7\u00e3o:<\/em><\/p>\n\n\n\n<p class=\"has-text-align-center has-background\" style=\"background-color:#e1e4e6\"><strong>Mais informa\u00e7\u00f5es do <a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-nacional-unificado\/\" target=\"_blank\" rel=\"noreferrer noopener\">CNU<\/a><\/strong><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"cursos-assinatura\"><em>Quer estudar para o pr\u00f3ximo Concurso Nacional Unificado (CNU)?<\/em><\/h2>\n\n\n\n<div class=\"container\" id=\"boxes\">\r\n  <div class=\"row\">\r\n\r\n    <div class=\"col-sm\">\r\n      <div class=\"estrategia\" id=\"box-assinatura\">\r\n        <h3 class=\"titulo-assinatura\">Assinatura Concursos<\/h3>\r\n        <p class=\"subtitulo-assinatura\">Assinatura de 1 ano ou 2 anos<\/p>\r\n        <div class=\"box-botao\">\r\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/assinaturas\/\" role=\"button\" rel=\"noopener noreferrer\">ASSINE AGORA<\/a>\r\n        <\/div>\r\n      <\/div><\/div><\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"h-quer-saber-tudo-sobre-concursos-previstos-confira-os-nossos-artigos\">Quer saber tudo sobre concursos previstos?<br \/>Confira os nossos artigos!<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos Abertos<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-federais\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos Federais<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2025\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos 2025<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2026\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos 2026<\/a><\/li>\n<\/ul>\n\n\n\n<div class=\"schema-faq wp-block-yoast-faq-block\"><div class=\"schema-faq-section\" id=\"faq-question-1749488353369\"><strong class=\"schema-faq-question\">Quando ser\u00e1 a prova do CNU 2025?<\/strong> <p class=\"schema-faq-answer\">A aplica\u00e7\u00e3o da prova objetiva do CNU 2025 est\u00e1 prevista para o dia 5 de outubro de 2025. J\u00e1 a prova discursiva, segunda fase do certame, deve ocorrer em 7 de dezembro de 2025.<\/p> <\/div> <div class=\"schema-faq-section\" id=\"faq-question-1749488517892\"><strong class=\"schema-faq-question\">Quando ser\u00e3o as inscri\u00e7\u00f5es para o CNU 2025?<\/strong> <p class=\"schema-faq-answer\">O per\u00edodo de inscri\u00e7\u00f5es para o CNU 2025 est\u00e1 previsto para o m\u00eas de julho. A data exata ainda n\u00e3o foi oficialmente confirmada, mas \u00e9 importante ficar atento \u00e0s atualiza\u00e7\u00f5es da banca organizadora, FGV.<\/p> <\/div> <div class=\"schema-faq-section\" id=\"faq-question-1749488540454\"><strong class=\"schema-faq-question\">Quando sai o resultado do CNU 2025?<\/strong> <p class=\"schema-faq-answer\">A divulga\u00e7\u00e3o dos resultados do novo ENEM dos Concursos est\u00e1 prevista para fevereiro de 2026.<\/p> <\/div> <\/div>\n","protected":false},"excerpt":{"rendered":"<p>Provas do CNU 2025 ser\u00e3o divididas em duas fases Com edital previsto para julho, muitos concurseiros querem se debru\u00e7ar nos estudos para as provas do CNU 2025 quanto antes, mas, quais etapas foram confirmadas at\u00e9 o momento? A resposta deste questionamento \u00e9 primordial para que voc\u00ea elabore corretamente um plano de estudos, bem como usufruir [&hellip;]<\/p>\n","protected":false},"author":2692,"featured_media":1270513,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"news","footnotes":""},"categories":[214992,220219],"tags":[],"tax_estado":[219963],"class_list":["post-1572924","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-concursos-administrativos","category-noticias","tax_estado-concursos-federais"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>CNU 2025 j\u00e1 tem etapas de provas confirmadas; confira!<\/title>\n<meta name=\"description\" content=\"O Concurso Nacional Unificado (CNU) de 2025 j\u00e1 tem algumas etapas de provas confirmadas. Saiba quais s\u00e3o aqui!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-provas-confirmadas\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CNU 2025 j\u00e1 tem etapas de provas confirmadas; confira!\" \/>\n<meta property=\"og:description\" content=\"O Concurso Nacional Unificado (CNU) de 2025 j\u00e1 tem algumas etapas de provas confirmadas. Saiba quais s\u00e3o aqui!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-provas-confirmadas\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-09T21:02:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-10T11:30:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/08\/29075651\/concurso-nacional-unificado.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"432\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ronaldo Scanavini Neto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ronaldo Scanavini Neto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-provas-confirmadas\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-provas-confirmadas\/\"},\"author\":{\"name\":\"Ronaldo Scanavini Neto\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/70c2ad4297aa24ff8815b08215b23a76\"},\"headline\":\"CNU 2025 j\u00e1 tem etapas de provas confirmadas; confira!\",\"datePublished\":\"2025-06-09T21:02:00+00:00\",\"dateModified\":\"2025-06-10T11:30:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-provas-confirmadas\/\"},\"wordCount\":725,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-provas-confirmadas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/08\/29075651\/concurso-nacional-unificado.jpg\",\"articleSection\":[\"Executivo (Administrativa)\",\"\u00daltimas not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-provas-confirmadas\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":[\"WebPage\",\"FAQPage\"],\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-provas-confirmadas\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-provas-confirmadas\/\",\"name\":\"CNU 2025 j\u00e1 tem etapas de provas confirmadas; confira!\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-provas-confirmadas\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-provas-confirmadas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/08\/29075651\/concurso-nacional-unificado.jpg\",\"datePublished\":\"2025-06-09T21:02:00+00:00\",\"dateModified\":\"2025-06-10T11:30:45+00:00\",\"description\":\"O Concurso Nacional Unificado (CNU) de 2025 j\u00e1 tem algumas etapas de provas confirmadas. Saiba quais s\u00e3o aqui!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-provas-confirmadas\/#breadcrumb\"},\"mainEntity\":[{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-provas-confirmadas\/#faq-question-1749488353369\"},{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-provas-confirmadas\/#faq-question-1749488517892\"},{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-provas-confirmadas\/#faq-question-1749488540454\"}],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-provas-confirmadas\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-provas-confirmadas\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/08\/29075651\/concurso-nacional-unificado.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/08\/29075651\/concurso-nacional-unificado.jpg\",\"width\":768,\"height\":432,\"caption\":\"CNU 2: saiu convoca\u00e7\u00e3o para Fase 6; cronograma atualizado\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-provas-confirmadas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CNU 2025 j\u00e1 tem etapas de provas confirmadas; confira!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/70c2ad4297aa24ff8815b08215b23a76\",\"name\":\"Ronaldo Scanavini Neto\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/f93d8e56fe264596e94aee6b3feb737d98ad0fc5bac7eb0a245f04723c5c8f21?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f93d8e56fe264596e94aee6b3feb737d98ad0fc5bac7eb0a245f04723c5c8f21?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f93d8e56fe264596e94aee6b3feb737d98ad0fc5bac7eb0a245f04723c5c8f21?s=96&d=mm&r=g\",\"caption\":\"Ronaldo Scanavini Neto\"},\"description\":\"Graduando em Comunica\u00e7\u00e3o Social \u2013 Jornalismo pela Universidade Federal de Vi\u00e7osa (UFV). Integra a equipe de jornalismo do Estrat\u00e9gia Concursos desde 2023, atuando com \u00eanfase na cobertura da \u00e1rea fiscal. Tamb\u00e9m realiza a apura\u00e7\u00e3o e produ\u00e7\u00e3o de not\u00edcias sobre concursos federais, \u00f3rg\u00e3os participantes do CNU e das \u00e1reas de controle, gest\u00e3o, engenharia, Exame CFC, comunica\u00e7\u00e3o social TI e \u00e1rea de concursos administrativos.\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/ronaldo-netoestrategia-com\/\"},{\"@type\":\"Question\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-provas-confirmadas\/#faq-question-1749488353369\",\"position\":1,\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-provas-confirmadas\/#faq-question-1749488353369\",\"name\":\"Quando ser\u00e1 a prova do CNU 2025?\",\"answerCount\":1,\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"A aplica\u00e7\u00e3o da prova objetiva do CNU 2025 est\u00e1 prevista para o dia 5 de outubro de 2025. J\u00e1 a prova discursiva, segunda fase do certame, deve ocorrer em 7 de dezembro de 2025.\",\"inLanguage\":\"pt-BR\"},\"inLanguage\":\"pt-BR\"},{\"@type\":\"Question\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-provas-confirmadas\/#faq-question-1749488517892\",\"position\":2,\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-provas-confirmadas\/#faq-question-1749488517892\",\"name\":\"Quando ser\u00e3o as inscri\u00e7\u00f5es para o CNU 2025?\",\"answerCount\":1,\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"O per\u00edodo de inscri\u00e7\u00f5es para o CNU 2025 est\u00e1 previsto para o m\u00eas de julho. A data exata ainda n\u00e3o foi oficialmente confirmada, mas \u00e9 importante ficar atento \u00e0s atualiza\u00e7\u00f5es da banca organizadora, FGV.\",\"inLanguage\":\"pt-BR\"},\"inLanguage\":\"pt-BR\"},{\"@type\":\"Question\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-provas-confirmadas\/#faq-question-1749488540454\",\"position\":3,\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-provas-confirmadas\/#faq-question-1749488540454\",\"name\":\"Quando sai o resultado do CNU 2025?\",\"answerCount\":1,\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"A divulga\u00e7\u00e3o dos resultados do novo ENEM dos Concursos est\u00e1 prevista para fevereiro de 2026.\",\"inLanguage\":\"pt-BR\"},\"inLanguage\":\"pt-BR\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"CNU 2025 j\u00e1 tem etapas de provas confirmadas; confira!","description":"O Concurso Nacional Unificado (CNU) de 2025 j\u00e1 tem algumas etapas de provas confirmadas. Saiba quais s\u00e3o aqui!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-provas-confirmadas\/","og_locale":"pt_BR","og_type":"article","og_title":"CNU 2025 j\u00e1 tem etapas de provas confirmadas; confira!","og_description":"O Concurso Nacional Unificado (CNU) de 2025 j\u00e1 tem algumas etapas de provas confirmadas. Saiba quais s\u00e3o aqui!","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-provas-confirmadas\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2025-06-09T21:02:00+00:00","article_modified_time":"2025-06-10T11:30:45+00:00","og_image":[{"width":768,"height":432,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/08\/29075651\/concurso-nacional-unificado.jpg","type":"image\/jpeg"}],"author":"Ronaldo Scanavini Neto","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Ronaldo Scanavini Neto","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-provas-confirmadas\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-provas-confirmadas\/"},"author":{"name":"Ronaldo Scanavini Neto","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/70c2ad4297aa24ff8815b08215b23a76"},"headline":"CNU 2025 j\u00e1 tem etapas de provas confirmadas; confira!","datePublished":"2025-06-09T21:02:00+00:00","dateModified":"2025-06-10T11:30:45+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-provas-confirmadas\/"},"wordCount":725,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-provas-confirmadas\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/08\/29075651\/concurso-nacional-unificado.jpg","articleSection":["Executivo (Administrativa)","\u00daltimas not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-provas-confirmadas\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":["WebPage","FAQPage"],"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-provas-confirmadas\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-provas-confirmadas\/","name":"CNU 2025 j\u00e1 tem etapas de provas confirmadas; confira!","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-provas-confirmadas\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-provas-confirmadas\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/08\/29075651\/concurso-nacional-unificado.jpg","datePublished":"2025-06-09T21:02:00+00:00","dateModified":"2025-06-10T11:30:45+00:00","description":"O Concurso Nacional Unificado (CNU) de 2025 j\u00e1 tem algumas etapas de provas confirmadas. Saiba quais s\u00e3o aqui!","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-provas-confirmadas\/#breadcrumb"},"mainEntity":[{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-provas-confirmadas\/#faq-question-1749488353369"},{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-provas-confirmadas\/#faq-question-1749488517892"},{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-provas-confirmadas\/#faq-question-1749488540454"}],"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-provas-confirmadas\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-provas-confirmadas\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/08\/29075651\/concurso-nacional-unificado.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/08\/29075651\/concurso-nacional-unificado.jpg","width":768,"height":432,"caption":"CNU 2: saiu convoca\u00e7\u00e3o para Fase 6; cronograma atualizado"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-provas-confirmadas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"CNU 2025 j\u00e1 tem etapas de provas confirmadas; confira!"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/70c2ad4297aa24ff8815b08215b23a76","name":"Ronaldo Scanavini Neto","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/f93d8e56fe264596e94aee6b3feb737d98ad0fc5bac7eb0a245f04723c5c8f21?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f93d8e56fe264596e94aee6b3feb737d98ad0fc5bac7eb0a245f04723c5c8f21?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f93d8e56fe264596e94aee6b3feb737d98ad0fc5bac7eb0a245f04723c5c8f21?s=96&d=mm&r=g","caption":"Ronaldo Scanavini Neto"},"description":"Graduando em Comunica\u00e7\u00e3o Social \u2013 Jornalismo pela Universidade Federal de Vi\u00e7osa (UFV). Integra a equipe de jornalismo do Estrat\u00e9gia Concursos desde 2023, atuando com \u00eanfase na cobertura da \u00e1rea fiscal. Tamb\u00e9m realiza a apura\u00e7\u00e3o e produ\u00e7\u00e3o de not\u00edcias sobre concursos federais, \u00f3rg\u00e3os participantes do CNU e das \u00e1reas de controle, gest\u00e3o, engenharia, Exame CFC, comunica\u00e7\u00e3o social TI e \u00e1rea de concursos administrativos.","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/ronaldo-netoestrategia-com\/"},{"@type":"Question","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-provas-confirmadas\/#faq-question-1749488353369","position":1,"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-provas-confirmadas\/#faq-question-1749488353369","name":"Quando ser\u00e1 a prova do CNU 2025?","answerCount":1,"acceptedAnswer":{"@type":"Answer","text":"A aplica\u00e7\u00e3o da prova objetiva do CNU 2025 est\u00e1 prevista para o dia 5 de outubro de 2025. J\u00e1 a prova discursiva, segunda fase do certame, deve ocorrer em 7 de dezembro de 2025.","inLanguage":"pt-BR"},"inLanguage":"pt-BR"},{"@type":"Question","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-provas-confirmadas\/#faq-question-1749488517892","position":2,"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-provas-confirmadas\/#faq-question-1749488517892","name":"Quando ser\u00e3o as inscri\u00e7\u00f5es para o CNU 2025?","answerCount":1,"acceptedAnswer":{"@type":"Answer","text":"O per\u00edodo de inscri\u00e7\u00f5es para o CNU 2025 est\u00e1 previsto para o m\u00eas de julho. A data exata ainda n\u00e3o foi oficialmente confirmada, mas \u00e9 importante ficar atento \u00e0s atualiza\u00e7\u00f5es da banca organizadora, FGV.","inLanguage":"pt-BR"},"inLanguage":"pt-BR"},{"@type":"Question","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-provas-confirmadas\/#faq-question-1749488540454","position":3,"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/cnu-2025-provas-confirmadas\/#faq-question-1749488540454","name":"Quando sai o resultado do CNU 2025?","answerCount":1,"acceptedAnswer":{"@type":"Answer","text":"A divulga\u00e7\u00e3o dos resultados do novo ENEM dos Concursos est\u00e1 prevista para fevereiro de 2026.","inLanguage":"pt-BR"},"inLanguage":"pt-BR"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1572924","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/2692"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1572924"}],"version-history":[{"count":10,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1572924\/revisions"}],"predecessor-version":[{"id":1588828,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1572924\/revisions\/1588828"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/1270513"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1572924"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1572924"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1572924"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1572924"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}