{"id":1571809,"date":"2025-05-07T08:48:00","date_gmt":"2025-05-07T11:48:00","guid":{"rendered":"https:\/\/blog-estrategia.mystagingwebsite.com\/blog\/?p=1571809"},"modified":"2025-05-07T11:17:31","modified_gmt":"2025-05-07T14:17:31","slug":"concurso-mpu-recursos-perito-engenharia","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-mpu-recursos-perito-engenharia\/","title":{"rendered":"Concurso MPU: recursos de Perito Engenharia!"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">O <strong>concurso MPU (Minist\u00e9rio P\u00fablico da Uni\u00e3o)<\/strong> teve suas provas aplicadas no \u00faltimo domingo, 06. Inclusive, os gabaritos preliminares da etapa j\u00e1 foram divulgados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Com isso, aos interessados, o prazo para interposi\u00e7\u00e3o de recursos ficar\u00e1 aberto entre os dias 07 e 08 de abril, diretamente na \u00e1rea do candidato no site da <a href=\"https:\/\/conhecimento.fgv.br\/concursos\/mpu2025\" target=\"_blank\" rel=\"noreferrer noopener\">FGV<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">E para te ajudar, assim como na corre\u00e7\u00e3o extraoficial, nossos professores identificaram algumas possibilidades de recursos para <strong><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-mpu-engenharia-eletrica\/\" target=\"_blank\" rel=\"noreferrer noopener\">Engenharia El\u00e9trica<\/a> e <a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-mpu-engenharia-mecanica\/\" target=\"_blank\" rel=\"noreferrer noopener\">Engenharia Mec\u00e2nica<\/a>.<\/strong> Veja abaixo:<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-very-light-gray-to-cyan-bluish-gray-gradient-background has-background\" id=\"ingles\">Concurso MPU &#8211; Recursos de Engenharia El\u00e9trica<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>DISCIPLINA: Conhecimentos Espec\u00edficos I<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Quest\u00e3o 55 &#8211; MPU<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">II- O somat\u00f3rio das correntes nas fases da carga sempre ser\u00e1 igual a zero<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Coment\u00e1rios:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O item est\u00e1 incorreto. O somat\u00f3rio das correntes de fase de uma carga ser\u00e1 nula apenas se o sistema for equilibrado, que n\u00e3o \u00e9 o caso descrito no enunciado da quest\u00e3o. &nbsp;Em um sistema desequilibrado, o somat\u00f3rio das correntes n\u00e3o ser\u00e1 nula, visto que as correntes de fase s\u00e3o diferentes em m\u00f3dulo e\/ou fase.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como a quest\u00e3o solicita a alternativa que apresenta apenas os itens corretos, o gabarito da quest\u00e3o se torna a alternativa A e n\u00e3o a alternativa D conforme a banca indicou como gabarito preliminar.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-dots\"\/>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>Quest\u00e3o a ser analisada: Quest\u00e3o 12 prova branca \u2013 Tipo 1<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Na frase \u201cInfelizmente, meu amigo se esqueceu de dar o aviso da entrevista para o pobre Marcelo\u201d, cruzam-se duas fun\u00e7\u00f5es de linguagem, que s\u00e3o:<\/em><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><em>(A) referencial e f\u00e1tica;<\/em><\/li>\n\n\n\n<li><em>(B) conativa e metalingu\u00edstica;<\/em><\/li>\n\n\n\n<li><em>(C) metalingu\u00edstica e referencial;<\/em><\/li>\n\n\n\n<li><em>(D) emotiva e conativa;<\/em><\/li>\n\n\n\n<li><em>(E) f\u00e1tica e emotiva.<\/em><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Solicita-se \u00e0 respeitosa banca revis\u00e3o do gabarito divulga sobre essa quest\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Na an\u00e1lise da frase <strong>\u201cInfelizmente, meu amigo se esqueceu de dar o aviso da entrevista para o pobre Marcelo\u201d<\/strong>, observa-se a conflu\u00eancia de duas fun\u00e7\u00f5es de linguagem: a <strong>fun\u00e7\u00e3o emotiva<\/strong> e a <strong>fun\u00e7\u00e3o referencial,<\/strong> op\u00e7\u00e3o que n\u00e3o est\u00e1 presente entre as alternativas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A <strong>fun\u00e7\u00e3o emotiva<\/strong>, tamb\u00e9m denominada expressiva, manifesta-se de forma evidente no adv\u00e9rbio modalizador \u201cinfelizmente\u201d, termo que n\u00e3o acrescenta informa\u00e7\u00e3o objetiva ao conte\u00fado da mensagem, mas que revela o posicionamento afetivo do enunciador diante da situa\u00e7\u00e3o narrada. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Essa fun\u00e7\u00e3o tem como foco o <strong>emissor<\/strong>, e caracteriza-se pela exterioriza\u00e7\u00e3o de seus sentimentos, atitudes, ju\u00edzos ou emo\u00e7\u00f5es. No caso em quest\u00e3o, o uso do adv\u00e9rbio denota um tom de lamento, sinalizando a desaprova\u00e7\u00e3o ou tristeza do falante quanto ao esquecimento cometido.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">J\u00e1 a <strong>fun\u00e7\u00e3o referencial<\/strong> \u2013 ou denotativa \u2013 tem por objetivo principal <strong>transmitir informa\u00e7\u00f5es de maneira objetiva<\/strong>, com foco no <strong>conte\u00fado da mensagem<\/strong> (ou contexto). Ela \u00e9 amplamente predominante na parte central do enunciado, em que se informa um fato concreto e verific\u00e1vel: o esquecimento do amigo quanto ao aviso da entrevista destinado a Marcelo. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Trata-se, portanto, de um discurso com alto grau de informatividade, caracter\u00edstico da fun\u00e7\u00e3o referencial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cumpre ainda mencionar, <strong>a t\u00edtulo de observa\u00e7\u00e3o interpretativa<\/strong>, a possibilidade de identifica\u00e7\u00e3o de um tra\u00e7o residual da <strong>fun\u00e7\u00e3o f\u00e1tica<\/strong>. Esta \u00faltima \u00e9 centrada no canal da comunica\u00e7\u00e3o e tem por finalidade garantir a manuten\u00e7\u00e3o do contato entre os interlocutores, sendo comumente marcada por express\u00f5es de verifica\u00e7\u00e3o ou apelo, tais como \u201cal\u00f4\u201d, \u201centendeu?\u201d, \u201ccerto?\u201d. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Embora tais marcas n\u00e3o estejam explicitamente presentes na frase, poder-se-ia entender o uso da express\u00e3o \u201cmeu amigo\u201d e o tom coloquial do enunciado como ind\u00edcios t\u00eanues de uma tentativa de aproxima\u00e7\u00e3o do interlocutor, o que remeteria, ainda que indiretamente, \u00e0 fun\u00e7\u00e3o f\u00e1tica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Em s\u00edntese, a estrutura da frase em an\u00e1lise evidencia, de modo predominante e inequ\u00edvoco, a articula\u00e7\u00e3o entre as fun\u00e7\u00f5es <strong>emotiva<\/strong> e <strong>referencial<\/strong>, sendo inadequada, portanto, a interpreta\u00e7\u00e3o que identifique nela elementos da fun\u00e7\u00e3o <strong>conativa<\/strong>, como sugerido na alternativa considerada correta no gabarito da quest\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Solicita-se anula\u00e7\u00e3o da supracitada quest\u00e3o.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-dots\"\/>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>Quest\u00e3o a ser analisada: Quest\u00e3o 5 prova branca \u2013 Tipo 1<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Em todas as frases abaixo, h\u00e1 <strong>termos de liga\u00e7\u00e3o<\/strong> sublinhados.<br \/>A frase em que esse termo se <strong>refere \u00e0 estrutura do texto<\/strong> e <strong>n\u00e3o a fatos reais<\/strong> \u00e9:<\/em><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong><em>(A)<\/em><\/strong><em> Cheguei atrasado ao trabalho e, <strong>por causa<\/strong> disso, fui multado em 10% dos meus vencimentos;<\/em><\/li>\n\n\n\n<li><em><strong>(B)<\/strong> <strong>\u00c0 propor\u00e7\u00e3o que<\/strong> leio o livro, mais me apaixono pela figura humana de Van Gogh;<\/em><\/li>\n\n\n\n<li><em><strong>(C)<\/strong> <strong>Logo ap\u00f3s<\/strong> o relato de sua doen\u00e7a, o personagem interrompeu a narrativa por v\u00e1rios dias;<\/em><\/li>\n\n\n\n<li><em><strong>(D)<\/strong> Os estudantes ficaram <strong>t\u00e3o<\/strong> chateados com os resultados da prova <strong>que<\/strong> decidiram fazer uma greve;<\/em><\/li>\n\n\n\n<li><em><strong>(E)<\/strong> Os alunos leram os livros encomendados pelo mestre, <strong>mas<\/strong> alguns deles n\u00e3o apreciaram a tarefa.<\/em><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Solicita-se anula\u00e7\u00e3o da presente quest\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A reda\u00e7\u00e3o do enunciado da quest\u00e3o 5 compromete a clareza exigida em concursos p\u00fablicos ao empregar os termos \u201cestrutura do texto\u201d e \u201cfatos reais\u201d de forma vaga e amb\u00edgua. N\u00e3o se define se \u201cfatos reais\u201d dizem respeito ao mundo emp\u00edrico, \u00e0 veracidade l\u00f3gica ou \u00e0 fic\u00e7\u00e3o narrativa, o que torna incerto o crit\u00e9rio de escolha.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O gabarito oficial aponta como correta a alternativa <strong>(C)<\/strong> \u2013 <em>\u201cLogo ap\u00f3s o relato de sua doen\u00e7a, o personagem interrompeu a narrativa por v\u00e1rios dias\u201d<\/em> \u2013 sob o pressuposto de que a locu\u00e7\u00e3o \u201clogo ap\u00f3s\u201d organiza a sequ\u00eancia interna da narrativa, estruturando temporalmente os eventos dentro do discurso. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No entanto, mesmo nesse exemplo, a locu\u00e7\u00e3o tamb\u00e9m <strong>pode ser interpretada como indicadora de um fato cronol\u00f3gico (uma doen\u00e7a foi relatada), <\/strong>o que mant\u00e9m a confus\u00e3o entre \u201cestrutura do texto\u201d e \u201cfatos narrados\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m disso, outras alternativas \u2014 como a <strong>(B)<\/strong>, por exemplo \u2014 apresentam estruturas em que o termo sublinhado (\u201c\u00c0 propor\u00e7\u00e3o que\u201d) claramente <strong>atua na progress\u00e3o textual<\/strong>, estabelecendo um paralelismo entre o ato de ler e a intensifica\u00e7\u00e3o do sentimento, podendo, portanto, ser interpretado como um <strong>marcador argumentativo ou organizador textual<\/strong>, e n\u00e3o exclusivamente como express\u00e3o de um fato observ\u00e1vel ou verific\u00e1vel.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A alternativa <strong>(A)<\/strong>, por sua vez, tamb\u00e9m n\u00e3o deve ser descartada com base apenas na oposi\u00e7\u00e3o proposta pelo enunciado, visto que express\u00f5es como <strong>\u201cpor causa disso\u201d<\/strong> tamb\u00e9m atuam em mecanismos de coes\u00e3o anaf\u00f3rica, referindo-se a segmentos anteriores e contribuindo para a coes\u00e3o textual \u2013 o que, por outro vi\u00e9s, tamb\u00e9m diz respeito \u00e0 estrutura textual.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Portanto, a aus\u00eancia de defini\u00e7\u00e3o precisa para \u201cfatos reais\u201d e a indefini\u00e7\u00e3o quanto ao que se entende por \u201cestrutura do texto\u201d tornam o enunciado <strong>inadequado<\/strong>, pois permitem m\u00faltiplas interpreta\u00e7\u00f5es razo\u00e1veis, ferindo o princ\u00edpio da <strong>objetividade e da univocidade<\/strong> que deve reger uma avalia\u00e7\u00e3o de car\u00e1ter seletivo. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Assim, solicita-se a <strong>anula\u00e7\u00e3o da quest\u00e3o<\/strong> ou, alternativamente, a <strong>reformula\u00e7\u00e3o do enunciado para uma nova aplica\u00e7\u00e3o<\/strong>, garantindo a precis\u00e3o terminol\u00f3gica e a justi\u00e7a avaliativa.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-dots\"\/>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Recurso para quest\u00e3o 63:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">N\u00e3o h\u00e1 nenhuma alternativa poss\u00edvel para fazer com que a sa\u00edda seja 0. O gabarito informa que seria letra C, por\u00e9m fazendo a resposta da C ir\u00e1 dar o resultado igual a 1, pois no \u00faltimo OR ser\u00e11 \u2013 0 \u2013 1 as entradas, resultando em 1.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para que o \u00faltimo OR seja 0 \u2013 0 \u2013 0 nas entradas (obrigat\u00f3rio para a sa\u00edda ser 0), precisamos que C seja 1 obrigatoriamente, pois faz parte de uma AND que depois \u00e9 negada para ser entrada da OR final. Essa AND deve ter sa\u00edda igual a 1 (para ao negar ficar 0), para a AND ser 1 as duas entradas devem ser 1, e uma delas \u00e9 C diretamente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">E vai direto na OR final que deve ter todas 0, portanto deve ser 0.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A AND com D e C deve retornar 0, pois sua sa\u00edda est\u00e1 ligada na OR final. Como C \u00e9 1, para a AND retornar 0 D deve ser 0.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Assim n\u00f3s temos que C = 1; D = 0; E = 0;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A e B s\u00e3o entradas de uma NAND que deve retornar 1. Para a NAND retornar 1 basta que uma das entradas, ou as duas, sejam 0. Ent\u00e3o para estes temos algumas op\u00e7\u00f5es poss\u00edveis.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por\u00e9m, n\u00e3o temos nenhuma op\u00e7\u00e3o que satisfa\u00e7a C=1, D=0 e E=0.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A quest\u00e3o deve ser anulada.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-dots\"\/>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Sugest\u00e3o para Recursos Direitos Humanos e Acessibilidade MPU<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Quest\u00e3o<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A Conven\u00e7\u00e3o Americana de Direitos Humanos, tamb\u00e9m denominada Pacto de S\u00e3o Jos\u00e9 da Costa Rica, \u00e9 o instrumento mais importante de efetiva\u00e7\u00e3o dos direitos humanos do sistema interamericano. O documento instituiu o denominado Sistema Interamericano de Direitos Humanos (SIDH), composto por dois \u00f3rg\u00e3os principais: a Comiss\u00e3o Interamericana de Direitos Humanos (CIDH) e a Corte Interamericana de Direitos Humanos (Corte IDH). Acerca dos mecanismos de implementa\u00e7\u00e3o do Pacto de S\u00e3o Jos\u00e9 da Costa Rica, \u00e9 correto afirmar que:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">(A) o Estado signat\u00e1rio do Pacto de S\u00e3o Jos\u00e9 da Costa Rica pode ratificar a Conven\u00e7\u00e3o Americana de Direitos Humanos e n\u00e3o reconhecer a jurisdi\u00e7\u00e3o contenciosa da Corte Internacional de Direitos Humanos, j\u00e1 que tal reconhecimento \u00e9 cl\u00e1usula facultativa da Conven\u00e7\u00e3o;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">(B) o Brasil \u00e9 Estado-Parte da Conven\u00e7\u00e3o desde 1992 e, em 2002, reconheceu a compet\u00eancia contenciosa da Corte Interamericana de Direitos Humanos;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">(C) o reconhecimento da jurisdi\u00e7\u00e3o contenciosa da Corte Internacional de Direitos Humanos \u00e9 obrigat\u00f3rio e feito por declara\u00e7\u00e3o espec\u00edfica para todo e qualquer caso, e n\u00e3o somente para determinado caso espec\u00edfico;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">(D) a Corte Interamericana de Direitos Humanos \u00e9 composta por nove ju\u00edzes, cuja escolha \u00e9 feita pelos Estados-Parte da Conven\u00e7\u00e3o, em sess\u00e3o da Assembleia Geral da OEA, de uma lista de candidatos propostos pelos mesmos Estados;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">(E) as v\u00edtimas, assim como os Estados-Parte, podem submeter casos diretamente \u00e0 Corte, sem que haja necessidade de apresentar suas alega\u00e7\u00f5es \u00e0 Comiss\u00e3o Interamericana de Direitos Humanos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Gabarito preliminar: A<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Fundamenta\u00e7\u00e3o:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O Brasil ratificou a <strong>Conven\u00e7\u00e3o Americana sobre Direitos Humanos<\/strong> em <strong>1992<\/strong> e reconheceu a compet\u00eancia jurisdicional contenciosa da <strong>Corte Interamericana de Direitos Humanos (Corte IDH)<\/strong> em <strong>1998<\/strong>, ato este promulgado pelo <strong>Decreto n\u00ba 4.463\/2002<\/strong>.<br \/>Quando o <strong>Congresso Nacional<\/strong>, por meio do <strong>Decreto Legislativo n\u00ba 89\/1998<\/strong>, reconheceu a compet\u00eancia obrigat\u00f3ria da Corte IDH, a <strong>Declara\u00e7\u00e3o de Aceita\u00e7\u00e3o<\/strong> foi devidamente depositada junto \u00e0 <strong>Secretaria-Geral da Organiza\u00e7\u00e3o dos Estados Americanos (OEA)<\/strong><strong> em <\/strong><strong>10 de dezembro de 1998<\/strong><strong>.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O gabarito preliminar traz a <strong>alternativa A como correta, por\u00e9m, na alternativa se<\/strong> utiliza incorretamente a express\u00e3o &#8220;<strong>Corte Internacional de Direitos Humanos<\/strong>&#8220;, quando o correto seria &#8220;<strong>Corte Interamericana de Direitos Humanos<\/strong>&#8220;, o que compromete a seguran\u00e7a necess\u00e1ria ao julgamento da quest\u00e3o por parte do candidato.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Portanto, a quest\u00e3o merece anula\u00e7\u00e3o, pois n\u00e3o existe alternativa correta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Quest\u00e3o<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por ser tema de leg\u00edtimo interesse internacional, a prote\u00e7\u00e3o dos direitos humanos n\u00e3o \u00e9 reduzida ao dom\u00ednio reservado do Estado, ou seja, n\u00e3o se restringe \u00e0 compet\u00eancia nacional exclusiva ou \u00e0 jurisdi\u00e7\u00e3o dom\u00e9stica exclusiva. Contudo, h\u00e1 especificidades no tratamento dos tratados internacionais de prote\u00e7\u00e3o dos direitos humanos no ordenamento jur\u00eddico brasileiro, que ocorrem de acordo com as regras previstas na Constitui\u00e7\u00e3o Federal de 1988. Sobre o tema, analise as afirmativas a seguir, \u00e0 luz da Constitui\u00e7\u00e3o Federal e da doutrina majorit\u00e1ria.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">I. Compete privativamente ao presidente da Rep\u00fablica promulgar um ato internacional, depois de devidamente ratificado, para que este seja incorporado \u00e0 legisla\u00e7\u00e3o interna. II. No Direito brasileiro vigora um sistema misto, pois, a partir da Emenda Constitucional n\u00ba 45\/2004, a Constitui\u00e7\u00e3o Federal passou a contar com um rito especial para aprova\u00e7\u00e3o dos tratados internacionais que versam sobre direitos humanos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">III. Os tratados internacionais sobre direitos humanos que forem aprovados por dois quintos dos votos dos membros de cada Casa do Congresso Nacional, em dois turnos de vota\u00e7\u00e3o, ser\u00e3o equivalentes \u00e0s emendas constitucionais.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">IV. Nas hip\u00f3teses de grave viola\u00e7\u00e3o de direitos humanos, o procurador-geral da Rep\u00fablica, com a finalidade de assegurar o cumprimento de obriga\u00e7\u00f5es decorrentes de tratados internacionais de direitos humanos dos quais o Brasil seja parte, poder\u00e1 suscitar, perante o Supremo Tribunal Federal, em qualquer fase do inqu\u00e9rito ou processo, incidente de deslocamento de compet\u00eancia para a Justi\u00e7a Federal. Est\u00e1 correto o que se afirma em:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">(A) I e IV, apenas;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">(B) III e IV, apenas;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">(C) I, II e III, apenas;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">(D) I, II e IV, apenas;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">(E) I, II, III e IV.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Gabarito Preliminar: D<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Fundamenta\u00e7\u00e3o:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As assertivas III e IV est\u00e3o incorretas, vejamos:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">III \u2013 O <strong>art. 5\u00ba, \u00a7 3\u00ba, da Constitui\u00e7\u00e3o Federal<\/strong> estabelece que os <strong>tratados e conven\u00e7\u00f5es internacionais sobre direitos humanos<\/strong>, aprovados em <strong>cada Casa do Congresso Nacional<\/strong>, em <strong>dois turnos<\/strong>, por <strong>tr\u00eas quintos dos votos<\/strong> dos respectivos membros, ser\u00e3o equivalentes \u00e0s <strong>emendas constitucionais<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">IV \u2013 O artigo 109, par\u00e1grafo quinto da Constitui\u00e7\u00e3o Federal determina que:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a7 5\u00ba Nas hip\u00f3teses de grave viola\u00e7\u00e3o de direitos humanos, o Procurador-Geral da Rep\u00fablica, com a finalidade de assegurar o cumprimento de obriga\u00e7\u00f5es decorrentes de tratados internacionais de direitos humanos dos quais o Brasil seja parte, poder\u00e1 suscitar, perante o <strong>Superior Tribunal de Justi\u00e7a<\/strong>, em qualquer fase do inqu\u00e9rito ou processo, incidente de deslocamento de compet\u00eancia para a Justi\u00e7a Federal.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Na assertiva aponta que o IDC deveria ser suscitado perante o Supremo Tribunal Federal, o que n\u00e3o encontra respaldo no texto constitucional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Diante da aus\u00eancia de alternativa correta, a quest\u00e3o deve ser anulada.<\/strong><strong><\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading has-very-light-gray-to-cyan-bluish-gray-gradient-background has-background\" id=\"ingles\">Concurso MPU &#8211; Recursos de Engenharia Mec\u00e2nica<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>DISCIPLINA:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Aguardando recursos.<\/em><\/p>\n\n\n\n<p class=\"has-text-align-center has-background has-medium-font-size wp-block-paragraph\" style=\"background-color:#abb7c229\"><strong>Saiba mais:&nbsp;<a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-mpu\" target=\"_blank\" rel=\"noreferrer noopener\">Concurso MPU<\/a><\/strong><\/p>\n\n\n\n<div class=\"container\" id=\"boxes\">\n  <div class=\"row\">\n\n    <div class=\"col-sm\">\n      <div class=\"banner-mpu-ec\" id=\"box-assinatura\">\n        <h2 class=\"titulo-assinatura\">Curso para o MPU<\/h2>\n        <p class=\"subtitulo-assinatura\">Prepare-se para o Concurso MPU com o Estrat\u00e9gia!<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/cursosPorConcurso\/mpu-ministerio-publico-da-uniao\/\" role=\"button\" rel=\"noopener noreferrer\">VER CURSOS<\/a>\n        <\/div>\n      <\/div>\n      <p class=\"texto-auxiliar\">Prepare-se com o melhor material e com quem mais aprova em Concursos P\u00fablicos em todo o pa\u00eds.<\/p>\n    <\/div>\n\n  <\/div>\n<\/div>\n\n\n\n<div class=\"container\" id=\"boxes\">\n  <div class=\"row\">\n\n    <div class=\"col-sm\">\n      <div class=\"estrategia\" id=\"box-assinatura\">\n        <h3 class=\"titulo-assinatura\"> Concursos P\u00fablicos\n        <p class=\"subtitulo-assinatura\">Assinatura de 1 ano ou 2 anos<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/assinaturas\/\" role=\"button\" rel=\"noopener noreferrer\">ASSINE AGORA<\/a>\n        <\/div>\n      <\/h3><\/div><\/div><\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"h-quer-saber-tudo-sobre-concursos-previstos-confira-nossos-artigos\">Quer saber tudo sobre concursos previstos?<br \/>Confira nossos artigos!<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos Abertos<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-federais\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos Federais<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2025\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos 2025<\/a><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O concurso MPU (Minist\u00e9rio P\u00fablico da Uni\u00e3o) teve suas provas aplicadas no \u00faltimo domingo, 06. Inclusive, os gabaritos preliminares da etapa j\u00e1 foram divulgados. Com isso, aos interessados, o prazo para interposi\u00e7\u00e3o de recursos ficar\u00e1 aberto entre os dias 07 e 08 de abril, diretamente na \u00e1rea do candidato no site da FGV. E para [&hellip;]<\/p>\n","protected":false},"author":2134,"featured_media":846824,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"post_tipo":"news","footnotes":""},"categories":[1984,220219],"tags":[],"tax_estado":[219963],"class_list":["post-1571809","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tribunais","category-noticias","tax_estado-concursos-federais"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Concurso MPU: recursos de Perito Engenharia!<\/title>\n<meta name=\"description\" content=\"Concurso MPU: confira neste artigo os poss\u00edveis recursos das provas de Engenharia El\u00e9trica e Mec\u00e2nica. Todos os detalhes est\u00e3o no blog!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-mpu-recursos-perito-engenharia\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Concurso MPU: recursos de Perito Engenharia!\" \/>\n<meta property=\"og:description\" content=\"Concurso MPU: confira neste artigo os poss\u00edveis recursos das provas de Engenharia El\u00e9trica e Mec\u00e2nica. Todos os detalhes est\u00e3o no blog!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-mpu-recursos-perito-engenharia\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-07T11:48:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-07T14:17:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/08\/27001830\/mpu.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"432\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Rafaela Teixeira\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rafaela Teixeira\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"12 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/concurso-mpu-recursos-perito-engenharia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/concurso-mpu-recursos-perito-engenharia\\\/\"},\"author\":{\"name\":\"Rafaela Teixeira\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/e75352021ea7f60781c599934f916eb1\"},\"headline\":\"Concurso MPU: recursos de Perito Engenharia!\",\"datePublished\":\"2025-05-07T11:48:00+00:00\",\"dateModified\":\"2025-05-07T14:17:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/concurso-mpu-recursos-perito-engenharia\\\/\"},\"wordCount\":2320,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/concurso-mpu-recursos-perito-engenharia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2021\\\/08\\\/27001830\\\/mpu.jpeg\",\"articleSection\":[\"Tribunais\",\"\u00daltimas not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/concurso-mpu-recursos-perito-engenharia\\\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/concurso-mpu-recursos-perito-engenharia\\\/\",\"url\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/concurso-mpu-recursos-perito-engenharia\\\/\",\"name\":\"Concurso MPU: recursos de Perito Engenharia!\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/concurso-mpu-recursos-perito-engenharia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/concurso-mpu-recursos-perito-engenharia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2021\\\/08\\\/27001830\\\/mpu.jpeg\",\"datePublished\":\"2025-05-07T11:48:00+00:00\",\"dateModified\":\"2025-05-07T14:17:31+00:00\",\"description\":\"Concurso MPU: confira neste artigo os poss\u00edveis recursos das provas de Engenharia El\u00e9trica e Mec\u00e2nica. Todos os detalhes est\u00e3o no blog!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/concurso-mpu-recursos-perito-engenharia\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/concurso-mpu-recursos-perito-engenharia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/concurso-mpu-recursos-perito-engenharia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2021\\\/08\\\/27001830\\\/mpu.jpeg\",\"contentUrl\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2021\\\/08\\\/27001830\\\/mpu.jpeg\",\"width\":768,\"height\":432,\"caption\":\"Concurso Analista do MPU - Direito\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/concurso-mpu-recursos-perito-engenharia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Concurso MPU: recursos de Perito Engenharia!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2025\\\/06\\\/03203428\\\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2025\\\/06\\\/03203428\\\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/e75352021ea7f60781c599934f916eb1\",\"name\":\"Rafaela Teixeira\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a349a2b22039b1ee88fc06461487c950fd6aa411ea8af8633314b43334ae793?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a349a2b22039b1ee88fc06461487c950fd6aa411ea8af8633314b43334ae793?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a349a2b22039b1ee88fc06461487c950fd6aa411ea8af8633314b43334ae793?s=96&d=mm&r=g\",\"caption\":\"Rafaela Teixeira\"},\"description\":\"Rafaela Teixeira \u00e9 advogada conveniada \u00e0 Defensoria P\u00fablica de S\u00e3o Paulo pela OAB, com experi\u00eancia em reda\u00e7\u00e3o jur\u00eddica e atua\u00e7\u00e3o em institui\u00e7\u00f5es p\u00fablicas, incluindo est\u00e1gio no TRE-SP. Possui mais de 7 anos de experi\u00eancia na produ\u00e7\u00e3o de conte\u00fados voltados ao nicho de concursos p\u00fablicos, com foco em apura\u00e7\u00e3o jornal\u00edstica cont\u00ednua, an\u00e1lise de editais e obten\u00e7\u00e3o de informa\u00e7\u00f5es diretamente junto a \u00f3rg\u00e3os e fontes oficiais. No Blog do Estrat\u00e9gia Concursos, atua como Analista de Conte\u00fado S\u00eanior, respons\u00e1vel pelo jornalismo do per\u00edodo noturno e da madrugada, com atua\u00e7\u00e3o transversal na cobertura de concursos p\u00fablicos, garantindo a continuidade, fluidez e confiabilidade das publica\u00e7\u00f5es e dos bastidores dos certames.\",\"url\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/author\\\/rafaela-teixeira\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Concurso MPU: recursos de Perito Engenharia!","description":"Concurso MPU: confira neste artigo os poss\u00edveis recursos das provas de Engenharia El\u00e9trica e Mec\u00e2nica. Todos os detalhes est\u00e3o no blog!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-mpu-recursos-perito-engenharia\/","og_locale":"pt_BR","og_type":"article","og_title":"Concurso MPU: recursos de Perito Engenharia!","og_description":"Concurso MPU: confira neste artigo os poss\u00edveis recursos das provas de Engenharia El\u00e9trica e Mec\u00e2nica. Todos os detalhes est\u00e3o no blog!","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-mpu-recursos-perito-engenharia\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2025-05-07T11:48:00+00:00","article_modified_time":"2025-05-07T14:17:31+00:00","og_image":[{"width":768,"height":432,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/08\/27001830\/mpu.jpeg","type":"image\/jpeg"}],"author":"Rafaela Teixeira","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Rafaela Teixeira","Est. tempo de leitura":"12 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-mpu-recursos-perito-engenharia\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-mpu-recursos-perito-engenharia\/"},"author":{"name":"Rafaela Teixeira","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/e75352021ea7f60781c599934f916eb1"},"headline":"Concurso MPU: recursos de Perito Engenharia!","datePublished":"2025-05-07T11:48:00+00:00","dateModified":"2025-05-07T14:17:31+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-mpu-recursos-perito-engenharia\/"},"wordCount":2320,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-mpu-recursos-perito-engenharia\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/08\/27001830\/mpu.jpeg","articleSection":["Tribunais","\u00daltimas not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-mpu-recursos-perito-engenharia\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-mpu-recursos-perito-engenharia\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-mpu-recursos-perito-engenharia\/","name":"Concurso MPU: recursos de Perito Engenharia!","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-mpu-recursos-perito-engenharia\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-mpu-recursos-perito-engenharia\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/08\/27001830\/mpu.jpeg","datePublished":"2025-05-07T11:48:00+00:00","dateModified":"2025-05-07T14:17:31+00:00","description":"Concurso MPU: confira neste artigo os poss\u00edveis recursos das provas de Engenharia El\u00e9trica e Mec\u00e2nica. Todos os detalhes est\u00e3o no blog!","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-mpu-recursos-perito-engenharia\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-mpu-recursos-perito-engenharia\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-mpu-recursos-perito-engenharia\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/08\/27001830\/mpu.jpeg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/08\/27001830\/mpu.jpeg","width":768,"height":432,"caption":"Concurso Analista do MPU - Direito"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-mpu-recursos-perito-engenharia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Concurso MPU: recursos de Perito Engenharia!"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/e75352021ea7f60781c599934f916eb1","name":"Rafaela Teixeira","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/8a349a2b22039b1ee88fc06461487c950fd6aa411ea8af8633314b43334ae793?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8a349a2b22039b1ee88fc06461487c950fd6aa411ea8af8633314b43334ae793?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8a349a2b22039b1ee88fc06461487c950fd6aa411ea8af8633314b43334ae793?s=96&d=mm&r=g","caption":"Rafaela Teixeira"},"description":"Rafaela Teixeira \u00e9 advogada conveniada \u00e0 Defensoria P\u00fablica de S\u00e3o Paulo pela OAB, com experi\u00eancia em reda\u00e7\u00e3o jur\u00eddica e atua\u00e7\u00e3o em institui\u00e7\u00f5es p\u00fablicas, incluindo est\u00e1gio no TRE-SP. Possui mais de 7 anos de experi\u00eancia na produ\u00e7\u00e3o de conte\u00fados voltados ao nicho de concursos p\u00fablicos, com foco em apura\u00e7\u00e3o jornal\u00edstica cont\u00ednua, an\u00e1lise de editais e obten\u00e7\u00e3o de informa\u00e7\u00f5es diretamente junto a \u00f3rg\u00e3os e fontes oficiais. No Blog do Estrat\u00e9gia Concursos, atua como Analista de Conte\u00fado S\u00eanior, respons\u00e1vel pelo jornalismo do per\u00edodo noturno e da madrugada, com atua\u00e7\u00e3o transversal na cobertura de concursos p\u00fablicos, garantindo a continuidade, fluidez e confiabilidade das publica\u00e7\u00f5es e dos bastidores dos certames.","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/rafaela-teixeira\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1571809","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/2134"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1571809"}],"version-history":[{"count":0,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1571809\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/846824"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1571809"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1571809"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1571809"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1571809"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}