{"id":1568564,"date":"2025-06-14T14:19:00","date_gmt":"2025-06-14T17:19:00","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=1568564"},"modified":"2025-05-16T14:44:46","modified_gmt":"2025-05-16T17:44:46","slug":"fato-gerador-ipva-sefaz-pi","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/fato-gerador-ipva-sefaz-pi\/","title":{"rendered":"Fato gerador do IPVA para SEFAZ\/PI"},"content":{"rendered":"\n<p>Ol\u00e1, tudo bem?!! Neste material de hoje vamos analisar um assunto muito importante para a prova de Auditor Fiscal do Piau\u00ed: fato gerador do IPVA para SEFAZ\/PI de acordo com a legisla\u00e7\u00e3o nacional e estadual.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"311\" height=\"162\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/04\/28142203\/image-381.png\" alt=\"Fato gerador do IPVA para SEFAZ\/PI\" class=\"wp-image-1568567\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/04\/28142203\/image-381.png 311w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/04\/28142203\/image-381-300x156.png 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/04\/28142203\/image-381-150x78.png 150w\" sizes=\"auto, (max-width: 311px) 100vw, 311px\" \/><figcaption class=\"wp-element-caption\">Fato gerador do IPVA para SEFAZ\/PI<\/figcaption><\/figure>\n\n\n\n<p>De forma direcionada, iremos passar pelos seguintes t\u00f3picos:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Conhecer disposi\u00e7\u00f5es normativas sobre fato gerador do IPVA para SEFAZ\/PI;\u00a0<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Entender observa\u00e7\u00f5es relevantes sobre o tema;\u00a0<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Encerrar com considera\u00e7\u00f5es finais.\u00a0<\/li>\n<\/ul>\n\n\n\n<p>Nesse sentido, tendo como refer\u00eancia a <a href=\"https:\/\/www.sefaz.pi.gov.br\/arquivos\/legislacao\/leis\/Lei4257.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Lei estadual n\u00ba 4.257\/1989, que trata do ICMS no Estado<\/a>, vamos agora estudar um pouco mais sobre fato gerador do IPVA para SEFAZ\/PI.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-fato-gerador-do-ipva-para-sefaz-pi-nbsp\"><strong>Fato gerador do IPVA para SEFAZ\/PI<\/strong>&nbsp;<\/h2>\n\n\n\n<p>Para os entes estaduais, \u00e9 essencial um controle efetivo sobre os tributos de suas compet\u00eancias, especialmente<strong> <\/strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-luminous-vivid-orange-color\"><strong>ICMS, IPVA e ITMCD.<\/strong>\u00a0<\/mark><\/p>\n\n\n\n<p>No tocante ao IPVA, especificamente, este incide sobre a propriedade de ve\u00edculos automotores registrados na jurisdi\u00e7\u00e3o daquele territ\u00f3rio, e s\u00e3o imprescind\u00edveis para manter a arrecada\u00e7\u00e3o do Estado a n\u00edveis satisfat\u00f3rios.&nbsp;<\/p>\n\n\n\n<p>Al\u00e9m disso, \u00e9 necess\u00e1rio estar<mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\"> <strong>atento ao que a legisla\u00e7\u00e3o aplic\u00e1vel imp\u00f5e,<\/strong><\/mark> tendo em vista que cada unidade estadual tem prerrogativa de estabelecer as regras espec\u00edficas pertinentes que devem vigorar naquela regi\u00e3o, desde que sejam observadas, tamb\u00e9m, as normas gerais no tocante ao tributo em quest\u00e3o.\u00a0<\/p>\n\n\n\n<p>Um ponto importante no que diz respeito ao IPVA, e que costuma cair em provas, \u00e9 um entendimento do <strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-green-cyan-color\">STF (Supremo Tribunal Federal) que rege que n\u00e3o incide IPVA sobre propriedade de aeronaves. <\/mark><\/strong>Ou seja, mesmo um avi\u00e3o sendo um ve\u00edculo motorizado, n\u00e3o h\u00e1 incid\u00eancia do IPVA neste caso, na interpreta\u00e7\u00e3o do STF. Logo, se alguma legisla\u00e7\u00e3o impuser essa tributa\u00e7\u00e3o (e muitas delas o fazem) estar\u00e1 indo na contram\u00e3o do que sumulou o Supremo. Essa \u00e9 uma discuss\u00e3o bem densa e que pode ser bastante explorada inclusive em provas discursivas. Destacamos inclusive isso aqui mais abaixo, no trecho da norma do Piau\u00ed que traz esse imbr\u00f3glio. Se liga!\u00a0<\/p>\n\n\n\n<p>Com isso, vamos ent\u00e3o entender o que diz a lei 4548\/1992 sobre fato gerador do IPVA para SEFAZ\/PI:&nbsp;<\/p>\n\n\n\n<p>Art. 1\u00ba Esta Lei institui o Imposto sobre a Propriedade de Ve\u00edculos Automotores &#8211; IPVA, de conformidade com o art. 155, inciso I, al\u00ednea c, da Constitui\u00e7\u00e3o federal, e disciplina sua cobran\u00e7a.&nbsp;<\/p>\n\n\n\n<p>Art. 2\u00ba <strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">O Imposto sobre a Propriedade de Ve\u00edculos Automotores &#8211; IPVA tem como fato gerador a propriedade de ve\u00edculos automotores terrestres, aqu\u00e1ticos e a\u00e9reos. <\/mark><\/strong><em>(aqui a legisla\u00e7\u00e3o piauiense contradiz aquele entendimento do STF que falamos acima sobre aeronaves)<\/em>\u00a0<\/p>\n\n\n\n<p>Art. 3\u00ba<mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\"> <strong>Considera-se ocorrido o fato gerador do IPVA para SEFAZ\/PI:<\/strong>\u00a0<\/mark><\/p>\n\n\n\n<p>I &#8211; no dia primeiro de janeiro de cada ano;&nbsp;<\/p>\n\n\n\n<p>II &#8211; em se tratando de ve\u00edculo novo, na data da sua aquisi\u00e7\u00e3o, por consumidor final, ou quando da incorpora\u00e7\u00e3o ao ativo permanente por empresa fabricante ou revendedora;&nbsp;<\/p>\n\n\n\n<p>III &#8211; <mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\"><strong>em se tratando de ve\u00edculo n\u00e3o registrado e n\u00e3o licenciado neste Estado<\/strong>,<\/mark> na data da aquisi\u00e7\u00e3o, quando n\u00e3o houver comprova\u00e7\u00e3o do pagamento do IPVA em outra Unidade da Federa\u00e7\u00e3o;\u00a0<\/p>\n\n\n\n<p>IV &#8211; em se tratando de ve\u00edculo de proced\u00eancia estrangeira, para efeito da primeira tributa\u00e7\u00e3o ocorre fato gerador do IPVA para SEFAZ\/PI:&nbsp;<\/p>\n\n\n\n<p>a) na data do desembara\u00e7o aduaneiro,<mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\"> <strong>quando importado por consumidor final;<\/strong>\u00a0<\/mark><\/p>\n\n\n\n<p>b) na data da aquisi\u00e7\u00e3o por consumidor final, quando importado por empresa revendedora;&nbsp;<\/p>\n\n\n\n<p>c) no momento da incorpora\u00e7\u00e3o ao ativo permanente da empresa importadora;&nbsp;<\/p>\n\n\n\n<p>V &#8211; no momento da perda da condi\u00e7\u00e3o que fundamentava a isen\u00e7\u00e3o, n\u00e3o incid\u00eancia ou imunidade.&nbsp;<\/p>\n\n\n\n<p>VI &#8211; relativamente a ve\u00edculo de propriedade de<strong> <\/strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\"><strong>empresa locadora:<\/strong>\u00a0<\/mark><\/p>\n\n\n\n<p>a) no dia 1\u00ba de janeiro de cada ano, em se tratando de ve\u00edculo usado j\u00e1 registrado ou licenciado neste Estado;&nbsp;<\/p>\n\n\n\n<p>b) na data em que vier a ser locado ou colocado \u00e0 disposi\u00e7\u00e3o para loca\u00e7\u00e3o no territ\u00f3rio deste Estado, em se tratando de ve\u00edculo usado registrado ou licenciado anteriormente em outro Estado;&nbsp;<\/p>\n\n\n\n<p>c) <mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\"><strong>na data de sua aquisi\u00e7\u00e3o para integrar a frota destinada \u00e0 loca\u00e7\u00e3o neste Estado, em se tratando de ve\u00edculo novo.<\/strong>\u00a0<\/mark><\/p>\n\n\n\n<p>\u00a7 1\u00ba Na hip\u00f3tese prevista na al\u00ednea &#8220;b&#8221; do inciso VI deste artigo, n\u00e3o se considera ocorrido o fato gerador do IPVA para SEFAZ\/PI quando se tratar de ve\u00edculo disponibilizado temporariamente para loca\u00e7\u00e3o no territ\u00f3rio deste Estado.&nbsp;<\/p>\n\n\n\n<p>\u00a7 2\u00ba Considera-se disponibilizado <strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\">temporariamente<\/mark> <\/strong>para loca\u00e7\u00e3o neste Estado o ve\u00edculo que seja objeto de, no m\u00e1ximo, um contrato de loca\u00e7\u00e3o que envolva a entrega desse ve\u00edculo ao locat\u00e1rio em territ\u00f3rio piauiense.\u00a0<\/p>\n\n\n\n<p>\u00a7 3\u00ba Na hip\u00f3tese das al\u00edneas &#8220;b&#8221; e &#8220;c&#8221; do inciso VI, o imposto ser\u00e1 cobrado proporcionalmente ao per\u00edodo que faltar para completar 12 (doze) meses do respectivo exerc\u00edcio.&nbsp;<\/p>\n\n\n\n<p>Passamos, portanto, pelo tema fato gerador do IPVA para SEFAZ\/PI, assunto fundamental para o concurso de auditor fiscal deste Estado.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-consideracoes-finais-nbsp\"><strong>Considera\u00e7\u00f5es Finais<\/strong>&nbsp;<\/h2>\n\n\n\n<p>Chegamos ao final do nosso breve artigo sobre fato gerador do IPVA para SEFAZ\/PI, e esperamos que seja muito \u00fatil para a sua prepara\u00e7\u00e3o e aprova\u00e7\u00e3o.&nbsp;<\/p>\n\n\n\n<p><em>Lembre-se que \u00e9 essencial a <\/em><a href=\"https:\/\/www.estrategiaconcursos.com.br\/\" target=\"_blank\" rel=\"noreferrer noopener\"><em>leitura dos PDF\u2019s e a revis\u00e3o frequente dos conte\u00fados, para que assim os seus estudos fiquem cada vez mais avan\u00e7ados.<\/em><\/a><em>&nbsp;<\/em>&nbsp;&nbsp;<\/p>\n\n\n\n<p>Um grande abra\u00e7o e at\u00e9 mais!&nbsp;<\/p>\n\n\n\n<p class=\"has-text-align-center\"><strong>Quer saber quais ser\u00e3o os pr\u00f3ximos concursos?<\/strong>&nbsp;<\/p>\n\n\n\n<p class=\"has-text-align-center\"><strong>Confira nossos artigos!<\/strong>&nbsp;<\/p>\n\n\n\n<p class=\"has-text-align-center has-luminous-vivid-amber-background-color has-background\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos abertos<\/a>&nbsp;<\/p>\n\n\n\n<p class=\"has-text-align-center has-luminous-vivid-amber-background-color has-background\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2025\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos 2025<\/a>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ol\u00e1, tudo bem?!! Neste material de hoje vamos analisar um assunto muito importante para a prova de Auditor Fiscal do Piau\u00ed: fato gerador do IPVA para SEFAZ\/PI de acordo com a legisla\u00e7\u00e3o nacional e estadual.&nbsp; De forma direcionada, iremos passar pelos seguintes t\u00f3picos:&nbsp; Nesse sentido, tendo como refer\u00eancia a Lei estadual n\u00ba 4.257\/1989, que trata [&hellip;]<\/p>\n","protected":false},"author":2887,"featured_media":1568567,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1983],"tags":[],"tax_estado":[219963,219980],"class_list":["post-1568564","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fiscal-estadual","tax_estado-concursos-federais","tax_estado-pi"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Fato gerador do IPVA para SEFAZ\/PI<\/title>\n<meta name=\"description\" content=\"Neste material vamos analisar um assunto muito importante para a prova de Auditor Fiscal do Piau\u00ed: fato gerador do IPVA para SEFAZ\/PI.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/fato-gerador-ipva-sefaz-pi\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fato gerador do IPVA para SEFAZ\/PI\" \/>\n<meta property=\"og:description\" content=\"Neste material vamos analisar um assunto muito importante para a prova de Auditor Fiscal do Piau\u00ed: fato gerador do IPVA para SEFAZ\/PI.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/fato-gerador-ipva-sefaz-pi\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-14T17:19:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/04\/28142203\/image-381.png\" \/>\n\t<meta property=\"og:image:width\" content=\"311\" \/>\n\t<meta property=\"og:image:height\" content=\"162\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"F\u00e1bio Prado dos Santos Santana\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"F\u00e1bio Prado dos Santos Santana\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/fato-gerador-ipva-sefaz-pi\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/fato-gerador-ipva-sefaz-pi\/\"},\"author\":{\"name\":\"F\u00e1bio Prado dos Santos Santana\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/b1af3515254fed0a6861d754def3f005\"},\"headline\":\"Fato gerador do IPVA para SEFAZ\/PI\",\"datePublished\":\"2025-06-14T17:19:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/fato-gerador-ipva-sefaz-pi\/\"},\"wordCount\":950,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/fato-gerador-ipva-sefaz-pi\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/04\/28142203\/image-381.png\",\"articleSection\":[\"Fiscal - Estadual (ICMS)\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/fato-gerador-ipva-sefaz-pi\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/fato-gerador-ipva-sefaz-pi\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/fato-gerador-ipva-sefaz-pi\/\",\"name\":\"Fato gerador do IPVA para SEFAZ\/PI\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/fato-gerador-ipva-sefaz-pi\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/fato-gerador-ipva-sefaz-pi\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/04\/28142203\/image-381.png\",\"datePublished\":\"2025-06-14T17:19:00+00:00\",\"description\":\"Neste material vamos analisar um assunto muito importante para a prova de Auditor Fiscal do Piau\u00ed: fato gerador do IPVA para SEFAZ\/PI.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/fato-gerador-ipva-sefaz-pi\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/fato-gerador-ipva-sefaz-pi\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/fato-gerador-ipva-sefaz-pi\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/04\/28142203\/image-381.png\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/04\/28142203\/image-381.png\",\"width\":311,\"height\":162,\"caption\":\"Fato gerador do IPVA para SEFAZ\/PI\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/fato-gerador-ipva-sefaz-pi\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fato gerador do IPVA para SEFAZ\/PI\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/b1af3515254fed0a6861d754def3f005\",\"name\":\"F\u00e1bio Prado dos Santos Santana\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/0e3399436850f804c1d7731313952ccf303887c14b1711595235048e3ec0299b?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0e3399436850f804c1d7731313952ccf303887c14b1711595235048e3ec0299b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0e3399436850f804c1d7731313952ccf303887c14b1711595235048e3ec0299b?s=96&d=mm&r=g\",\"caption\":\"F\u00e1bio Prado dos Santos Santana\"},\"description\":\"Principais Aprova\u00e7\u00f5es em Concursos: Auditor Fiscal Tribut\u00e1rio Municipal - ISS S\u00e3o Paulo (2024); Auditor Fiscal - Receita Federal do Brasil (2023); Professor Efetivo - Universidade Federal de Sergipe (2014).\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/fabioprado-ufsgmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Fato gerador do IPVA para SEFAZ\/PI","description":"Neste material vamos analisar um assunto muito importante para a prova de Auditor Fiscal do Piau\u00ed: fato gerador do IPVA para SEFAZ\/PI.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/fato-gerador-ipva-sefaz-pi\/","og_locale":"pt_BR","og_type":"article","og_title":"Fato gerador do IPVA para SEFAZ\/PI","og_description":"Neste material vamos analisar um assunto muito importante para a prova de Auditor Fiscal do Piau\u00ed: fato gerador do IPVA para SEFAZ\/PI.","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/fato-gerador-ipva-sefaz-pi\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2025-06-14T17:19:00+00:00","og_image":[{"width":311,"height":162,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/04\/28142203\/image-381.png","type":"image\/png"}],"author":"F\u00e1bio Prado dos Santos Santana","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"F\u00e1bio Prado dos Santos Santana","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/fato-gerador-ipva-sefaz-pi\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/fato-gerador-ipva-sefaz-pi\/"},"author":{"name":"F\u00e1bio Prado dos Santos Santana","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/b1af3515254fed0a6861d754def3f005"},"headline":"Fato gerador do IPVA para SEFAZ\/PI","datePublished":"2025-06-14T17:19:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/fato-gerador-ipva-sefaz-pi\/"},"wordCount":950,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/fato-gerador-ipva-sefaz-pi\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/04\/28142203\/image-381.png","articleSection":["Fiscal - Estadual (ICMS)"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/fato-gerador-ipva-sefaz-pi\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/fato-gerador-ipva-sefaz-pi\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/fato-gerador-ipva-sefaz-pi\/","name":"Fato gerador do IPVA para SEFAZ\/PI","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/fato-gerador-ipva-sefaz-pi\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/fato-gerador-ipva-sefaz-pi\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/04\/28142203\/image-381.png","datePublished":"2025-06-14T17:19:00+00:00","description":"Neste material vamos analisar um assunto muito importante para a prova de Auditor Fiscal do Piau\u00ed: fato gerador do IPVA para SEFAZ\/PI.","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/fato-gerador-ipva-sefaz-pi\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/fato-gerador-ipva-sefaz-pi\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/fato-gerador-ipva-sefaz-pi\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/04\/28142203\/image-381.png","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/04\/28142203\/image-381.png","width":311,"height":162,"caption":"Fato gerador do IPVA para SEFAZ\/PI"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/fato-gerador-ipva-sefaz-pi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Fato gerador do IPVA para SEFAZ\/PI"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/b1af3515254fed0a6861d754def3f005","name":"F\u00e1bio Prado dos Santos Santana","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/0e3399436850f804c1d7731313952ccf303887c14b1711595235048e3ec0299b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0e3399436850f804c1d7731313952ccf303887c14b1711595235048e3ec0299b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0e3399436850f804c1d7731313952ccf303887c14b1711595235048e3ec0299b?s=96&d=mm&r=g","caption":"F\u00e1bio Prado dos Santos Santana"},"description":"Principais Aprova\u00e7\u00f5es em Concursos: Auditor Fiscal Tribut\u00e1rio Municipal - ISS S\u00e3o Paulo (2024); Auditor Fiscal - Receita Federal do Brasil (2023); Professor Efetivo - Universidade Federal de Sergipe (2014).","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/fabioprado-ufsgmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1568564","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/2887"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1568564"}],"version-history":[{"count":1,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1568564\/revisions"}],"predecessor-version":[{"id":1568573,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1568564\/revisions\/1568573"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/1568567"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1568564"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1568564"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1568564"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1568564"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}