{"id":1560987,"date":"2025-06-21T14:32:00","date_gmt":"2025-06-21T17:32:00","guid":{"rendered":"https:\/\/blog-estrategia.mystagingwebsite.com\/blog\/?p=1560987"},"modified":"2025-05-16T15:00:41","modified_gmt":"2025-05-16T18:00:41","slug":"principios-dos-titulos-credito","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/principios-dos-titulos-credito\/","title":{"rendered":"Princ\u00edpios dos t\u00edtulos de cr\u00e9dito"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Ol\u00e1, estudantes do Direito! Preparados para mais uma sess\u00e3o de aprendizado? Neste artigo as estudaremos os princ\u00edpios dos t\u00edtulos de cr\u00e9dito.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para melhor compreens\u00e3o, o assunto foi dividido nos seguintes t\u00f3picos:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Introdu\u00e7\u00e3o<\/strong><\/li>\n\n\n\n<li><strong>Cartularidade<\/strong><\/li>\n\n\n\n<li><strong>Literalidade<\/strong><\/li>\n\n\n\n<li><strong>Autonomia<\/strong><\/li>\n\n\n\n<li><strong>Independ\u00eancia<\/strong><\/li>\n\n\n\n<li><strong>Tipicidade<\/strong><\/li>\n\n\n\n<li><strong>Considera\u00e7\u00f5es finais<\/strong><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Vamos l\u00e1!<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/04\/10160201\/chatgpt-image-apr-10-2025-04_08_48-pm.png\" alt=\"princ\u00edpios dos t\u00edtulos de cr\u00e9dito\" class=\"wp-image-1561146\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/04\/10160201\/chatgpt-image-apr-10-2025-04_08_48-pm.png 1024w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/04\/10160201\/chatgpt-image-apr-10-2025-04_08_48-pm-300x300.png 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/04\/10160201\/chatgpt-image-apr-10-2025-04_08_48-pm-150x150.png 150w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/04\/10160201\/chatgpt-image-apr-10-2025-04_08_48-pm-768x768.png 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/04\/10160201\/chatgpt-image-apr-10-2025-04_08_48-pm-96x96.png 96w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h1 class=\"wp-block-heading has-large-font-size\" id=\"h-introducao\">Introdu\u00e7\u00e3o<\/h1>\n\n\n\n<p class=\"wp-block-paragraph\">T\u00edtulos de cr\u00e9dito s\u00e3o documentos necess\u00e1rios para o exerc\u00edcio do direito literal e aut\u00f4nomo a que ele se refere. Ou seja, s\u00e3o documentos que representam obriga\u00e7\u00f5es de pagamento. Eles funcionam como <strong>instrumentos de circula\u00e7\u00e3o de riqueza r\u00e1pidos e seguros <\/strong>(Santa Cruz, 2023).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Essa rapidez e seguran\u00e7a \u00e9 garantida por meio da observa\u00e7\u00e3o de algumas formalidades. Essas formalidades s\u00e3o reguladas tanto por diplomas normativos nacionais como por diplomas normativos internacionais, como a Lei Uniforme de Genebra, aderida pelo ordenamento jur\u00eddico brasileiro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esse conceito de t\u00edtulo de cr\u00e9dito, junto das formalidades inerentes a eles, fazem com que assumam atributos especiais que os qualificam. Aos t\u00edtulos de cr\u00e9dito s\u00e3o atribu\u00eddos os princ\u00edpios: da cartularidade, da literalidade, da autonomia, da independ\u00eancia e da tipicidade. Esses dois \u00faltimos n\u00e3o s\u00e3o reconhecidos por toda a doutrina, mas ser\u00e3o igualmente estudados por precau\u00e7\u00e3o.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-large-font-size\" id=\"h-cartularidade\">Cartularidade<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">O primeiro dos princ\u00edpios dos t\u00edtulos de cr\u00e9dito a ser estudado \u00e9 o da <strong>cartularidade<\/strong>. Esse princ\u00edpio imp\u00f5e que qualquer direito relacionado ao t\u00edtulo de cr\u00e9dito dependa de sua posse leg\u00edtima.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Assim, o protesto do t\u00edtulo demanda sua apresenta\u00e7\u00e3o ao tabeli\u00e3o, o que viabiliza, inclusive, a restitui\u00e7\u00e3o da c\u00e1rtula ao devedor quando do pagamento da d\u00edvida (conforme arts. 8\u00ba, 12 e 13 da Lei 9.492\/1997).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tamb\u00e9m decorre desse princ\u00edpio a ideia de que a posse do t\u00edtulo pelo devedor presume o seu pagamento. Trata-se de presun\u00e7\u00e3o relativa, cuja positiva\u00e7\u00e3o foi feita no art. 324 do CC: A entrega do t\u00edtulo ao devedor firma a presun\u00e7\u00e3o do pagamento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ainda como decorr\u00eancia desse princ\u00edpio, tem-se que a execu\u00e7\u00e3o judicial do t\u00edtulo de cr\u00e9dito depende de sua apresenta\u00e7\u00e3o ao ju\u00edzo, conforme art. 798, I, &#8220;a&#8221;, do CPC: Ao propor a execu\u00e7\u00e3o, incumbe ao exequente: I &#8211; instruir a peti\u00e7\u00e3o inicial com: a) o t\u00edtulo executivo extrajudicial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">E, n\u00e3o menos importante, temos a circularidade como uma caracter\u00edstica desse princ\u00edpio. Os t\u00edtulos, como regra, podem circular na pra\u00e7a sem que isso comprometa sua validade. Salvo nos casos em que o tomador seja especificado, qualquer pessoa que tiver sua posse pode assumir a qualidade de credor\/tomador.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Em que pese a nomenclatura e as caracter\u00edsticas desses princ\u00edpio, \u00e9 importante ter em mente que atualmente se admite a figura dos t\u00edtulos de cr\u00e9dito eletr\u00f4nicos, o que enseja a mitiga\u00e7\u00e3o desse princ\u00edpio.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-large-font-size\" id=\"h-literalidade\">Literalidade<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">A<strong> literalidade<\/strong> \u00e9 o princ\u00edpio que imp\u00f5e a correspond\u00eancia da obriga\u00e7\u00e3o ao que est\u00e1 escrito no t\u00edtulo de cr\u00e9dito. A interpreta\u00e7\u00e3o da obriga\u00e7\u00e3o \u00e9 literal: n\u00e3o se deve e nem se pode cobrar nada a mai ou, nada a menos do que est\u00e1 escrito. Isso serve como uma garantia para o credor e o devedor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As anota\u00e7\u00f5es de quita\u00e7\u00e3o parcial, aval e endosso tamb\u00e9m devem ser lan\u00e7adas no t\u00edtulo. A quita\u00e7\u00e3o parcial feita em apartado pode ser questionada. J\u00e1 o aval e o endosso, se n\u00e3o forem feitos no t\u00edtulo, carecer\u00e3o de validade.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-large-font-size\" id=\"h-autonomia\">Autonomia<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Esse \u00e9 o princ\u00edpio dos t\u00edtulos de cr\u00e9dito mais controverso. Isso porque seus efeitos geram as principais discuss\u00f5es nos processos de execu\u00e7\u00e3o judicial, muitas vezes fundandas na exce\u00e7\u00e3o do contrato n\u00e3o cumprido.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A <strong>autonomia<\/strong> \u00e9 o princ\u00edpio que traduz a qualidade de <strong>direito novo<\/strong> ao t\u00edtulo de cr\u00e9dito. Esse direito novo \u00e9 desvinculado da rela\u00e7\u00e3o que lhe deu origem.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O princ\u00edpio da autonomia pode ser segregado em dois outros princ\u00edpios: o da abstra\u00e7\u00e3o e o da inoponibilidade das exce\u00e7\u00f5es.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O<strong> princ\u00edpio da abstra\u00e7\u00e3o<\/strong> faz com que a obriga\u00e7\u00e3o do t\u00edtulo seja abstra\u00edda quando este \u00e9 colocado em circula\u00e7\u00e3o. Ou seja, o exerc\u00edcio do direito escrito no t\u00edtulo independe das rela\u00e7\u00f5es anteriores \u00e0 posse do credo atual.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">J\u00e1 o <strong>princ\u00edpio da inoponibilidade das exce\u00e7\u00f5es<\/strong> decorre do princ\u00edpio da abstra\u00e7\u00e3o. Isso porque as exce\u00e7\u00f5es pessoais ou os v\u00edcios ocorridos nas rela\u00e7\u00f5es pret\u00e9ritas \u00e0 posse atual do t\u00edtulo n\u00e3o podem ser alegadas contra o atual possuidor. Por exemplo, caso a constitui\u00e7\u00e3o de um t\u00edtulo de cr\u00e9dito tenha sido motivada por um contrato de presta\u00e7\u00e3o de servi\u00e7os e esse t\u00edtulo tenha sido colocado em circula\u00e7\u00e3o, os direitos inerentes ao t\u00edtulo n\u00e3o ficaram vinculados \u00e0 efetiva\u00e7\u00e3o do servi\u00e7o contratado. O possuidor de boa-f\u00e9 n\u00e3o ficar\u00e1 sujeito \u00e0s exce\u00e7\u00f5es ou v\u00edcios das rela\u00e7\u00f5es anteriores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Muitos juristas sequer fazem men\u00e7\u00e3o a esses dois subprinc\u00edpios de maneira espec\u00edfica, pois s\u00e3o inerentes ao pr\u00f3prio princ\u00edpio da autonomia.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-large-font-size\" id=\"h-independencia\">Independ\u00eancia<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">O princ\u00edpio da independ\u00eancia n\u00e3o \u00e9 amplamente reconhecido pela doutrina como princ\u00edpio dos t\u00edtulos de cr\u00e9dito. Segundo esse princ\u00edpio, os t\u00edtulos independem de outros documentos para complet\u00e1-los. Sua validade depende somente dos requisitos a eles inerentes.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-large-font-size\" id=\"h-tipicidade\">Tipicidade<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">A tipicidade tamb\u00e9m n\u00e3o \u00e9 amplamente reconhecida como princ\u00edpio dos t\u00edtulos de cr\u00e9dito. Segundo esse princ\u00edpio, os t\u00edtulos dependem de reconhecimento legal para adquirirem essa qualidade. Ou seja, somente se pode considerar como t\u00edtulo de cr\u00e9dito aqueles documentos cujos requisitos e formalidades estejam estabelecidos por meio de lei.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gostou do texto? Deixe um coment\u00e1rio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.instagram.com\/gabrielssantos96\">https:\/\/www.instagram.com\/gabrielssantos96<\/a><\/p>\n\n\n\n<p class=\"has-text-align-center has-white-color has-vivid-cyan-blue-background-color has-text-color has-background has-link-color wp-elements-1 wp-block-paragraph\"><strong><a href=\"https:\/\/www.youtube.com\/@EstrategiaConcursosBrasil\">Canal do Estrat\u00e9gia Concursos no Youtube<\/a><\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center has-white-color has-vivid-cyan-blue-background-color has-text-color has-background has-link-color wp-elements-2 wp-block-paragraph\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\"><strong>Concursos Abertos<\/strong><\/a><\/p>\n\n\n\n<p class=\"has-text-align-center has-white-color has-vivid-cyan-blue-background-color has-text-color has-background has-link-color wp-elements-3 wp-block-paragraph\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2025\/\"><strong>Concursos 2025<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ol\u00e1, estudantes do Direito! Preparados para mais uma sess\u00e3o de aprendizado? Neste artigo as estudaremos os princ\u00edpios dos t\u00edtulos de cr\u00e9dito. Para melhor compreens\u00e3o, o assunto foi dividido nos seguintes t\u00f3picos: Vamos l\u00e1! Introdu\u00e7\u00e3o T\u00edtulos de cr\u00e9dito s\u00e3o documentos necess\u00e1rios para o exerc\u00edcio do direito literal e aut\u00f4nomo a que ele se refere. Ou seja, [&hellip;]<\/p>\n","protected":false},"author":3013,"featured_media":1561146,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"post_tipo":"article","footnotes":""},"categories":[1],"tags":[],"tax_estado":[219963],"class_list":["post-1560987","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cursos-e-concursos","tax_estado-concursos-federais"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.1 (Yoast SEO v28.1) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Princ\u00edpios dos t\u00edtulos de cr\u00e9dito<\/title>\n<meta name=\"description\" content=\"Veja as caracter\u00edsticas dos princ\u00edpios dos t\u00edtulos de cr\u00e9dito e como eles influenciam os atributos das c\u00e1rtulas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/principios-dos-titulos-credito\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Princ\u00edpios dos t\u00edtulos de cr\u00e9dito\" \/>\n<meta property=\"og:description\" content=\"Veja as caracter\u00edsticas dos princ\u00edpios dos t\u00edtulos de cr\u00e9dito e como eles influenciam os atributos das c\u00e1rtulas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/principios-dos-titulos-credito\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-21T17:32:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/04\/10160201\/chatgpt-image-apr-10-2025-04_08_48-pm.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Gabriel Souza Santos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gabriel Souza Santos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/principios-dos-titulos-credito\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/principios-dos-titulos-credito\\\/\"},\"author\":{\"name\":\"Gabriel Souza Santos\",\"@id\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/#\\\/schema\\\/person\\\/d948c69f6dd3bbd74ea6c9f7451a93c6\"},\"headline\":\"Princ\u00edpios dos t\u00edtulos de cr\u00e9dito\",\"datePublished\":\"2025-06-21T17:32:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/principios-dos-titulos-credito\\\/\"},\"wordCount\":1002,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/principios-dos-titulos-credito\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2025\\\/04\\\/10160201\\\/chatgpt-image-apr-10-2025-04_08_48-pm.png\",\"articleSection\":[\"Concursos P\u00fablicos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/principios-dos-titulos-credito\\\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/principios-dos-titulos-credito\\\/\",\"url\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/principios-dos-titulos-credito\\\/\",\"name\":\"Princ\u00edpios dos t\u00edtulos de cr\u00e9dito\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/principios-dos-titulos-credito\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/principios-dos-titulos-credito\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2025\\\/04\\\/10160201\\\/chatgpt-image-apr-10-2025-04_08_48-pm.png\",\"datePublished\":\"2025-06-21T17:32:00+00:00\",\"description\":\"Veja as caracter\u00edsticas dos princ\u00edpios dos t\u00edtulos de cr\u00e9dito e como eles influenciam os atributos das c\u00e1rtulas.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/principios-dos-titulos-credito\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/principios-dos-titulos-credito\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/principios-dos-titulos-credito\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2025\\\/04\\\/10160201\\\/chatgpt-image-apr-10-2025-04_08_48-pm.png\",\"contentUrl\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2025\\\/04\\\/10160201\\\/chatgpt-image-apr-10-2025-04_08_48-pm.png\",\"width\":1024,\"height\":1024,\"caption\":\"princ\u00edpios dos t\u00edtulos de cr\u00e9dito\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/principios-dos-titulos-credito\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Princ\u00edpios dos t\u00edtulos de cr\u00e9dito\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/#website\",\"url\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2025\\\/06\\\/03203428\\\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2025\\\/06\\\/03203428\\\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/#\\\/schema\\\/person\\\/d948c69f6dd3bbd74ea6c9f7451a93c6\",\"name\":\"Gabriel Souza Santos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fd1003725e80f9cbb3f5083f64f112beb33dbd3bcbc7d34e628143a7cdd6cb8a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fd1003725e80f9cbb3f5083f64f112beb33dbd3bcbc7d34e628143a7cdd6cb8a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fd1003725e80f9cbb3f5083f64f112beb33dbd3bcbc7d34e628143a7cdd6cb8a?s=96&d=mm&r=g\",\"caption\":\"Gabriel Souza Santos\"},\"url\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/author\\\/gabriel-s-96hotmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Princ\u00edpios dos t\u00edtulos de cr\u00e9dito","description":"Veja as caracter\u00edsticas dos princ\u00edpios dos t\u00edtulos de cr\u00e9dito e como eles influenciam os atributos das c\u00e1rtulas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/principios-dos-titulos-credito\/","og_locale":"pt_BR","og_type":"article","og_title":"Princ\u00edpios dos t\u00edtulos de cr\u00e9dito","og_description":"Veja as caracter\u00edsticas dos princ\u00edpios dos t\u00edtulos de cr\u00e9dito e como eles influenciam os atributos das c\u00e1rtulas.","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/principios-dos-titulos-credito\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2025-06-21T17:32:00+00:00","og_image":[{"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/04\/10160201\/chatgpt-image-apr-10-2025-04_08_48-pm.png","width":1024,"height":1024,"type":"image\/png"}],"author":"Gabriel Souza Santos","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Gabriel Souza Santos","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/principios-dos-titulos-credito\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/principios-dos-titulos-credito\/"},"author":{"name":"Gabriel Souza Santos","@id":"https:\/\/blog-estrategia.mystagingwebsite.com\/#\/schema\/person\/d948c69f6dd3bbd74ea6c9f7451a93c6"},"headline":"Princ\u00edpios dos t\u00edtulos de cr\u00e9dito","datePublished":"2025-06-21T17:32:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/principios-dos-titulos-credito\/"},"wordCount":1002,"commentCount":0,"publisher":{"@id":"https:\/\/blog-estrategia.mystagingwebsite.com\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/principios-dos-titulos-credito\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/04\/10160201\/chatgpt-image-apr-10-2025-04_08_48-pm.png","articleSection":["Concursos P\u00fablicos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/principios-dos-titulos-credito\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/principios-dos-titulos-credito\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/principios-dos-titulos-credito\/","name":"Princ\u00edpios dos t\u00edtulos de cr\u00e9dito","isPartOf":{"@id":"https:\/\/blog-estrategia.mystagingwebsite.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/principios-dos-titulos-credito\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/principios-dos-titulos-credito\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/04\/10160201\/chatgpt-image-apr-10-2025-04_08_48-pm.png","datePublished":"2025-06-21T17:32:00+00:00","description":"Veja as caracter\u00edsticas dos princ\u00edpios dos t\u00edtulos de cr\u00e9dito e como eles influenciam os atributos das c\u00e1rtulas.","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/principios-dos-titulos-credito\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/principios-dos-titulos-credito\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/principios-dos-titulos-credito\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/04\/10160201\/chatgpt-image-apr-10-2025-04_08_48-pm.png","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/04\/10160201\/chatgpt-image-apr-10-2025-04_08_48-pm.png","width":1024,"height":1024,"caption":"princ\u00edpios dos t\u00edtulos de cr\u00e9dito"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/principios-dos-titulos-credito\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/blog-estrategia.mystagingwebsite.com\/"},{"@type":"ListItem","position":2,"name":"Princ\u00edpios dos t\u00edtulos de cr\u00e9dito"}]},{"@type":"WebSite","@id":"https:\/\/blog-estrategia.mystagingwebsite.com\/#website","url":"https:\/\/blog-estrategia.mystagingwebsite.com\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/blog-estrategia.mystagingwebsite.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog-estrategia.mystagingwebsite.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/blog-estrategia.mystagingwebsite.com\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/blog-estrategia.mystagingwebsite.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/blog-estrategia.mystagingwebsite.com\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/blog-estrategia.mystagingwebsite.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/blog-estrategia.mystagingwebsite.com\/#\/schema\/person\/d948c69f6dd3bbd74ea6c9f7451a93c6","name":"Gabriel Souza Santos","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/fd1003725e80f9cbb3f5083f64f112beb33dbd3bcbc7d34e628143a7cdd6cb8a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fd1003725e80f9cbb3f5083f64f112beb33dbd3bcbc7d34e628143a7cdd6cb8a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fd1003725e80f9cbb3f5083f64f112beb33dbd3bcbc7d34e628143a7cdd6cb8a?s=96&d=mm&r=g","caption":"Gabriel Souza Santos"},"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/gabriel-s-96hotmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1560987","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/3013"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1560987"}],"version-history":[{"count":0,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1560987\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/1561146"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1560987"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1560987"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1560987"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1560987"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}