{"id":1559882,"date":"2025-04-09T11:13:00","date_gmt":"2025-04-09T14:13:00","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=1559882"},"modified":"2025-04-11T17:25:47","modified_gmt":"2025-04-11T20:25:47","slug":"concurso-ibama-cargo-2-tema-1-recursos","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ibama-cargo-2-tema-1-recursos\/","title":{"rendered":"Concurso IBAMA &#8211; Cargo 2 (Tema 1): recursos poss\u00edveis!"},"content":{"rendered":"\n<p><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/diogo-mendesestrategiaconcursos-com-br\/\"><\/a>Ap\u00f3s a aplica\u00e7\u00e3o das provas do\u00a0<strong>concurso<\/strong> <strong>IBAMA<\/strong> (<a href=\"https:\/\/www.estrategiaconcursos.com.br\/cursosPorConcurso\/ibama-analista-61\/\" target=\"_blank\" rel=\"noreferrer noopener\">Instituto Brasileiro do Meio Ambiente e dos Recursos Naturais Renov\u00e1veis<\/a>) no \u00faltimo domingo, 06 de abril, o <a href=\"https:\/\/www.cebraspe.org.br\/concursos\/ibama_25\" target=\"_blank\" rel=\"noreferrer noopener\">Cebraspe<\/a>, respons\u00e1vel pela condu\u00e7\u00e3o do certame, liberou o acesso aos\u00a0<a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ibama-2025-gabaritos-preliminares\/\" target=\"_blank\" rel=\"noreferrer noopener\">gabaritos provis\u00f3rios<\/a>\u00a0da etapa.<\/p>\n\n\n\n<p>Com isso, os interessados poder\u00e3o interpor recursos entre os dias 08 e 10 de abril. O Estrat\u00e9gia Concursos esteve presente durante toda a sua prepara\u00e7\u00e3o, inclusive realizando a&nbsp;<a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-ibama-analista-ambiental-cargo2\/\" target=\"_blank\" rel=\"noreferrer noopener\">corre\u00e7\u00e3o extraoficial<\/a>. Agora, vamos te ajudar em mais essa importante etapa!<\/p>\n\n\n\n<p>Nosso time de professores elaborou sugest\u00f5es de recursos contra o gabarito provis\u00f3rio da sele\u00e7\u00e3o. Veja a seguir!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-concurso-ibama-analista-ambiental-cargo-2-tema-1-recursos-possiveis\">Concurso IBAMA &#8211; Analista Ambiental (Cargo 2 &#8211; Tema 1): recursos poss\u00edveis<\/h2>\n\n\n\n<p class=\"has-very-light-gray-to-cyan-bluish-gray-gradient-background has-background\"><strong>PORTUGU\u00caS<\/strong> &#8211; <strong>PROF. ADRIANA FIGUEIREDO<\/strong><\/p>\n\n\n\n<p><strong>QUEST\u00c3O 4<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"709\" height=\"246\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/04\/08210348\/image.jpg\" alt=\"\" class=\"wp-image-1560001\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/04\/08210348\/image.jpg 709w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/04\/08210348\/image-300x104.jpg 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/04\/08210348\/image-150x52.jpg 150w\" sizes=\"auto, (max-width: 709px) 100vw, 709px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"708\" height=\"188\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/04\/08210348\/image.jpg\" alt=\"\" class=\"wp-image-1560002\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/04\/08210348\/image.jpg 708w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/04\/08210348\/image-300x80.jpg 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/04\/08210348\/image-150x40.jpg 150w\" sizes=\"auto, (max-width: 708px) 100vw, 708px\" \/><\/figure>\n\n\n\n<p><strong>GABARITO PRELIMINAR DA BANCA: E<\/strong><\/p>\n\n\n\n<p><strong>GABARITO PRETENDIDO:&nbsp; C<\/strong><\/p>\n\n\n\n<p><strong>FUNDAMENTA\u00c7\u00c3O:&nbsp;<\/strong><\/p>\n\n\n\n<p>A quest\u00e3o de n\u00famero 4 teve gabarito preliminar E (Errado). Contudo, nota-se um equ\u00edvoco, conforme fundamenta\u00e7\u00e3o que se segue.<\/p>\n\n\n\n<p>De acordo com Bechara (2006, p. 611), dentre quatro motivos, usam-se os dois-pontos para enumerar e explicar. Cunha e Cintra (2001, p. 655-656) tamb\u00e9m prescrevem o uso de dois-pontos para anunciar uma cita\u00e7\u00e3o, uma enumera\u00e7\u00e3o explicativa e um esclarecimento \u201cuma s\u00edntese ou uma consequ\u00eancia do que foi enunciado.\u201d Assim, o emprego desse sinal de pontua\u00e7\u00e3o no texto introduz uma explica\u00e7\u00e3o do que foi escrito anteriormente, sob a forma de par\u00e1frase com exemplos.<\/p>\n\n\n\n<p>No texto, l\u00ea-se: \u201cA linguagem n\u00e3o \u00e9 uma inven\u00e7\u00e3o cultural, assim como tampouco a postura ereta o \u00e9. N\u00e3o \u00e9 uma manifesta\u00e7\u00e3o geral da capacidade de usar s\u00edmbolos: uma crian\u00e7a de tr\u00eas anos \u00e9 um g\u00eanio gramatical, mas \u00e9 bastante incompetente em termos de artes visuais, iconografia religiosa, sinais de tr\u00e2nsito e outros itens b\u00e1sicos do curr\u00edculo de semi\u00f3tica.\u201d Depreende-se, portanto, que a explica\u00e7\u00e3o e os exemplos confirmam que a linguagem n\u00e3o \u00e9 mais uma dentre as capacidades de usar s\u00edmbolos. Destaque-se a ora\u00e7\u00e3o \u201cuma crian\u00e7a de tr\u00eas anos \u00e9 um g\u00eanio gramatical\u201d, em que o autor do texto comprova o argumento de que a linguagem n\u00e3o est\u00e1 relacionada \u00e0 compet\u00eancia semi\u00f3tica por meio de exemplifica\u00e7\u00e3o: aos tr\u00eas anos, uma crian\u00e7a j\u00e1 domina uma l\u00edngua (\u201cg\u00eanio gramatical\u201d.)<\/p>\n\n\n\n<p>Ainda de acordo com o trecho citado, percebe-se que a ideia de que a crian\u00e7a ser \u201cbastante incompetente\u201d em \u201coutros itens b\u00e1sicos do curr\u00edculo de semi\u00f3tica\u201d \u00e9 uma par\u00e1frase explicativa de \u201cmanifesta\u00e7\u00e3o geral da capacidade de usar s\u00edmbolos\u201d, ou seja, aquilo que a linguagem n\u00e3o \u00e9.<\/p>\n\n\n\n<p>Em retrospectiva, as par\u00e1frases explicam e exemplificam a afirma\u00e7\u00e3o que o texto faz antes dos dois-pontos.<\/p>\n\n\n\n<p>Com base no exposto acima, solicita-se a mudan\u00e7a de gabarito.<\/p>\n\n\n\n<p><strong>Refer\u00eancias bibliogr\u00e1ficas:<\/strong><\/p>\n\n\n\n<p>BECHARA, Evanildo. <strong>Moderna gram\u00e1tica portuguesa<\/strong>. 37. ed. rev. e ampl. Rio de Janeiro: Lucerna, 2006.<\/p>\n\n\n\n<p>CINTRA, Celso; CINTRA, Lindley. <strong>Nova gram\u00e1tica do portugu\u00eas contempor\u00e2neo<\/strong>. 3. ed. rev. Rio de Janeiro: Nova Fronteira, 2001.<\/p>\n\n\n\n<p class=\"has-very-light-gray-to-cyan-bluish-gray-gradient-background has-background\"><strong>\u00c9TICA NO SERVI\u00c7O P\u00daBLICO<\/strong> &#8211; <strong>PROF. TIAGO ZANOLLA<\/strong><\/p>\n\n\n\n<p><strong>QUEST\u00c3O 23<\/strong><\/p>\n\n\n\n<p><strong>Gabarito Preliminar:<\/strong> Errado<\/p>\n\n\n\n<p><strong>Gabarito Correto (Requerido):<\/strong> Certo<\/p>\n\n\n\n<p>A quest\u00e3o sob an\u00e1lise apresenta o seguinte enunciado:<\/p>\n\n\n\n<p><em>Os servidores do IBAMA ocupantes de cargos de natureza especial, a fim de adotar uma conduta \u00e9tica no exerc\u00edcio de suas fun\u00e7\u00f5es, devem-se ater \u00e0s normas contidas no C\u00f3digo de \u00c9tica do IBAMA, no C\u00f3digo de \u00c9tica Profissional do Servidor P\u00fablico Civil do Poder Executivo Federal e no C\u00f3digo de Conduta da Alta Administra\u00e7\u00e3o Federal.<\/em><\/p>\n\n\n\n<p>O gabarito preliminar considerou a afirma\u00e7\u00e3o <strong>errada<\/strong>, contudo, o conte\u00fado da quest\u00e3o est\u00e1 <strong>plenamente de acordo<\/strong> com a previs\u00e3o normativa expressa no <strong>art. 5\u00ba, \u00a7 4\u00ba do C\u00f3digo de \u00c9tica dos agentes p\u00fablicos do IBAMA<\/strong>, o qual disp\u00f5e:<\/p>\n\n\n\n<p><strong>Art. 5\u00ba, \u00a7 4\u00ba<\/strong> \u2013 <em>&#8220;O <strong>agente p\u00fablico<\/strong> nomeado para o cargo de Superintendente, Diretor, Assessor ou titulares de <strong>cargos de natureza especial<\/strong>, ou autoridades equivalentes ocupantes de cargo do Grupo-Dire\u00e7\u00e3o, Assessoramento Superiores e Chefias dever\u00e3o se comprometer \u00e0 observ\u00e2ncia do C\u00f3digo de \u00c9tica Profissional do Servidor P\u00fablico Civil do Poder Executivo Federal, pelo C\u00f3digo de Conduta da Alta Administra\u00e7\u00e3o Federal, pelas Resolu\u00e7\u00f5es expedidas pela Comiss\u00e3o de \u00c9tica P\u00fablica da Presid\u00eancia da Rep\u00fablica (CEP\/PR), al\u00e9m da obedi\u00eancia \u00e0s determina\u00e7\u00f5es deste C\u00f3digo, sem preju\u00edzo de outras leis ou normas de conduta \u00e9tica aplic\u00e1veis.&#8221;<\/em><\/p>\n\n\n\n<p>Conforme se extrai do dispositivo, os servidores que exercem <strong>cargos de natureza especial ou equivalentes<\/strong> no \u00e2mbito do IBAMA devem observar, de forma <strong>simult\u00e2nea e complementar<\/strong>:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>o <strong>Decreto n\u00ba 1.171\/1994<\/strong> (C\u00f3digo de \u00c9tica do Servidor P\u00fablico Civil do Poder Executivo Federal);<\/li>\n\n\n\n<li>o <strong>C\u00f3digo de Conduta da Alta Administra\u00e7\u00e3o Federal<\/strong>;<\/li>\n\n\n\n<li>o <strong>C\u00f3digo de \u00c9tica do IBAMA<\/strong>;<\/li>\n\n\n\n<li>e demais normas de conduta \u00e9tica aplic\u00e1veis.<\/li>\n<\/ul>\n\n\n\n<p>A assertiva reproduz <strong>de forma fiel e literal<\/strong> os elementos essenciais da norma. Ainda que n\u00e3o mencione as resolu\u00e7\u00f5es da Comiss\u00e3o de \u00c9tica P\u00fablica da Presid\u00eancia da Rep\u00fablica (CEP\/PR), sua omiss\u00e3o n\u00e3o compromete a corre\u00e7\u00e3o da afirmativa, pois o n\u00facleo da obriga\u00e7\u00e3o \u00e9tica mencionada permanece <strong>intato e correto<\/strong>.<\/p>\n\n\n\n<p><strong>PEDIDO<\/strong><\/p>\n\n\n\n<p>Diante do exposto, requer-se a <strong>altera\u00e7\u00e3o do gabarito da quest\u00e3o 25 de \u201cErrado\u201d para \u201cCerto\u201d<\/strong>, por estar <strong>em conformidade com o art. 5\u00ba, \u00a7 4\u00ba do C\u00f3digo de \u00c9tica dos agentes p\u00fablicos do IBAMA<\/strong>.<\/p>\n\n\n\n<p class=\"has-very-light-gray-to-cyan-bluish-gray-gradient-background has-background\"><strong>INC\u00caNDIOS FLORESTAIS<\/strong> &#8211; <strong>PROF. MONIK BEGNAME<\/strong><\/p>\n\n\n\n<p><strong>QUEST\u00c3O 79<\/strong><\/p>\n\n\n\n<p>Em rela\u00e7\u00e3o aos impactos do fogo nos ecossistemas, julgue os itens a seguir.<\/p>\n\n\n\n<p> A redu\u00e7\u00e3o dos n\u00edveis de auxinas desencadeada pela passagem do fogo em plantas adaptadas \u00e9 uma resposta hormonal para a sobreviv\u00eancia em savanas, pois estimula o crescimento de gemas laterais, evidenciado pela arquitetura tortuosa das \u00e1rvores.<\/p>\n\n\n\n<p><strong>GABARITO PRELIMINAR: E<\/strong><\/p>\n\n\n\n<p><strong>GABARITO SUGERIDO: C<\/strong><\/p>\n\n\n\n<p><strong>\u00c0 Banca Organizadora,<\/strong><\/p>\n\n\n\n<p>Venho interpor recurso contra o gabarito da seguinte quest\u00e3o, que trata dos impactos do fogo em ecossistemas de savana, como o Cerrado. A banca considerou a assertiva como <strong>incorreta<\/strong>, mas com base na literatura cient\u00edfica, \u00e9 poss\u00edvel afirmar que ela est\u00e1 <strong>correta<\/strong>.<\/p>\n\n\n\n<p><strong>Justificativa:<\/strong><\/p>\n\n\n\n<p>Fundamento t\u00e9cnico:<\/p>\n\n\n\n<ol start=\"1\" class=\"wp-block-list\">\n<li>Domin\u00e2ncia apical \u2013 A auxina \u00e9 produzida na gema apical e inibe o crescimento das gemas laterais. Sua redu\u00e7\u00e3o (como em casos de poda ou perturba\u00e7\u00f5es como o fogo) permite o crescimento dessas gemas laterais (TAIZ et al., 2017; MASON et al., 2014).<\/li>\n\n\n\n<li>Resposta ao fogo \u2013 Em ambientes de savana, onde o fogo \u00e9 recorrente, muitas plantas apresentam adapta\u00e7\u00f5es morfol\u00f3gicas e fisiol\u00f3gicas. A arquitetura tortuosa \u00e9 uma dessas respostas adaptativas, associada \u00e0 brota\u00e7\u00e3o de gemas laterais ap\u00f3s a destrui\u00e7\u00e3o da parte a\u00e9rea (ou supress\u00e3o da domin\u00e2ncia apical) por queimadas (BONILLA, 2011; Fagan et al., 2015).<\/li>\n<\/ol>\n\n\n\n<p>A literatura cient\u00edfica em fisiologia vegetal explica que a auxina, produzida na gema apical, regula a domin\u00e2ncia apical, inibindo o crescimento das gemas laterais. Quando h\u00e1 redu\u00e7\u00e3o dos n\u00edveis de auxina \u2013 como ap\u00f3s a passagem do fogo \u2013 ocorre est\u00edmulo ao crescimento de gemas laterais, processo bem descrito como uma adapta\u00e7\u00e3o em ambientes de savana, o que leva \u00e0 forma\u00e7\u00e3o de uma arquitetura a\u00e9rea tortuosa, t\u00edpica de plantas desses biomas.<\/p>\n\n\n\n<p>Tais mecanismos fisiol\u00f3gicos est\u00e3o amplamente descritos em obras de refer\u00eancia, como TAIZ et al. (2017), FAGAN et al. (2015), e em pesquisas como a de MASON et al. (2014), refor\u00e7ando que a quest\u00e3o possui embasamento t\u00e9cnico-cient\u00edfico.<\/p>\n\n\n\n<p><strong>Refer\u00eancias Bibliogr\u00e1ficas:<\/strong><\/p>\n\n\n\n<p>TAIZ, Lincoln et al. <strong>Fisiologia e Desenvolvimento Vegetal<\/strong>. 6. ed. Porto Alegre: Artmed, 2017.<\/p>\n\n\n\n<p>FAGAN, E. B. et al. <strong>Fisiologia Vegetal: Reguladores Vegetais<\/strong>. S\u00e3o Paulo: Andrei, 2015.<\/p>\n\n\n\n<p>BONILLA, G. A. E. Sele\u00e7\u00e3o de Bact\u00e9rias Diazotr\u00f3ficas Solubilizadoras de F\u00f3sforo e seu Efeito no Desenvolvimento de Plantas de Arroz. 2011. Disserta\u00e7\u00e3o (Mestrado) \u2013 Universidade Federal Rural do Rio de Janeiro.<\/p>\n\n\n\n<p>MASON, M. G. et al. <em>Sugar demand, not auxin, is the initial regulator of apical dominance. Proceedings of the National Academy of Sciences<\/em>, v. 111, n. 16, p. 6092\u20136097, 2014.<\/p>\n\n\n\n<p>Solicito, portanto, a altera\u00e7\u00e3o do gabarito de Errado para Certo ou, no m\u00ednimo, anula\u00e7\u00e3o da quest\u00e3o.<\/p>\n\n\n\n<p class=\"has-very-light-gray-to-cyan-bluish-gray-gradient-background has-background\"><strong>Gabriela Zavadinack &#8211; No\u00e7\u00f5es De Gest\u00e3o P\u00fablica &#8211; AFO<\/strong><\/p>\n\n\n\n<p><strong>Recurso para a quest\u00e3o 38 da prova tipo \u201cO moinho n\u00e3o m\u00f3i com \u00e1guas passadas\u201d \u2013 Cargo 2: Analista Ambiental &#8211; IBAMA<\/strong><\/p>\n\n\n\n<p><strong>Enunciado da quest\u00e3o:<\/strong><\/p>\n\n\n\n<p><em>A dimens\u00e3o t\u00e9cnica do PPA 2024-2027 materializa-se nos programas, que incluem aspectos como objetivos, metas, entregas e investimentos necess\u00e1rios para sua implementa\u00e7\u00e3o.<\/em><\/p>\n\n\n\n<p><strong>Fundamentos para altera\u00e7\u00e3o de gabarito:<\/strong><\/p>\n\n\n\n<p>O gabarito preliminar apontado para a quest\u00e3o foi \u201cCERTO\u201d.<\/p>\n\n\n\n<p>Contudo, pugna-se pela altera\u00e7\u00e3o de gabarito para \u201cERRADO\u201d.<\/p>\n\n\n\n<p>De acordo com o Manual T\u00e9cnico do PPA 2024\/2027<a href=\"#_ftn1\" id=\"_ftnref1\">[1]<\/a>, <em>\u201cO PPA 2024-2027 \u2013 na condi\u00e7\u00e3o de plano central do governo federal \u2013 apresenta tr\u00eas dimens\u00f5es principais: <strong>estrat\u00e9gica, t\u00e1tica e operacional<\/strong>\u201d.<\/em><\/p>\n\n\n\n<p>A dimens\u00e3o estrat\u00e9gica, segundo o documento, traduz as principais linhas estrat\u00e9gicas definidas pelo governo federal para a implementa\u00e7\u00e3o de pol\u00edticas p\u00fablicas, tendo como horizonte o per\u00edodo de quatro anos. Ainda, \u00e9 composta pela Vis\u00e3o de Futuro, pelos Valores, Diretrizes, Eixos Tem\u00e1ticos, Objetivos Estrat\u00e9gicos e Indicadores-chave Nacionais e respectivas Metas.<\/p>\n\n\n\n<p>Por sua vez, a dimens\u00e3o <strong><u>t\u00e1tica<\/u><\/strong>, de acordo com o MTPPA 2024\/2027<em>, \u201cconsiste nos programas, com seus objetivos, objetivos espec\u00edficos, indicadores, metas, entregas, investimentos plurianuais e medidas institucionais e normativas\u201d.<\/em><\/p>\n\n\n\n<p>J\u00e1 a dimens\u00e3o operacional <em>\u201ccompreende o conjunto de a\u00e7\u00f5es or\u00e7ament\u00e1rias inclu\u00eddas na Lei Or\u00e7ament\u00e1ria Anual (LOA), bem como a\u00e7\u00f5es n\u00e3o or\u00e7ament\u00e1rias presentes nos Programas Final\u00edsticos do PPA\u201d.<\/em><\/p>\n\n\n\n<p>A quest\u00e3o, por sua vez, afirma que a dimens\u00e3o \u201c<strong>t\u00e9cnica<\/strong>\u201d do PPA materializa-se nos programas, que incluem aspectos como objetivos, metas, entregas e investimentos necess\u00e1rios para sua implementa\u00e7\u00e3o, o que est\u00e1 plenamente equivocado.<\/p>\n\n\n\n<p>Os termos \u201ct\u00e1tica\u201d e \u201ct\u00e9cnica\u201d n\u00e3o s\u00e3o sin\u00f4nimos dentro do planejamento estrat\u00e9gico. Em verdade, o termo \u201ct\u00e9cnico\u201d diz respeito ao planejamento <strong>operacional<\/strong>, conforme preleciona Chiavenato:<\/p>\n\n\n\n<p><strong>N\u00edvel operacional<\/strong>: <strong><u>\u00e9 tamb\u00e9m denominado n\u00edvel t\u00e9cnico ou n\u00facleo t\u00e9cnico<\/u><\/strong>; est\u00e1 localizado nas \u00e1reas inferiores da empresa. Est\u00e1 relacionado com os problemas ligados \u00e0 <strong>execu\u00e7\u00e3o cotidiana e eficiente das tarefas e opera\u00e7\u00f5es<\/strong> da empresa e orientado quase que exclusivamente para as exig\u00eancias impostas pela natureza da tarefa t\u00e9cnica a ser executada, com os materiais a serem processados e com a coopera\u00e7\u00e3o de numerosos especialistas necess\u00e1rios ao andamento dos trabalhos. <strong>\u00c9 o n\u00edvel em que as tarefas s\u00e3o executadas e as opera\u00e7\u00f5es realizadas: envolve o trabalho b\u00e1sico relacionado diretamente com a produ\u00e7\u00e3o dos produtos ou servi\u00e7os da empresa<\/strong>.<a href=\"#_ftn2\" id=\"_ftnref2\">[2]<\/a><\/p>\n\n\n\n<p>Ou seja, trazendo o conceito para a Administra\u00e7\u00e3o P\u00fablica, a dimens\u00e3o t\u00e9cnica do PPA est\u00e1 ligada \u00e0 execu\u00e7\u00e3o, ou seja, \u00e0s a\u00e7\u00f5es or\u00e7ament\u00e1rias e n\u00e3o or\u00e7ament\u00e1rias, que constam da dimens\u00e3o operacional. Ela est\u00e1 relacionada \u00e0 implementa\u00e7\u00e3o das pol\u00edticas p\u00fablicas e n\u00e3o deve ser confundida com a dimens\u00e3o t\u00e1tica, que \u00e9 a respons\u00e1vel pela tradu\u00e7\u00e3o das diretrizes estrat\u00e9gicas do governo em programas, objetivos, metas etc. <strong>A dimens\u00e3o t\u00e9cnica envolve a gest\u00e3o operacional das pol\u00edticas p\u00fablicas, focando na execu\u00e7\u00e3o dos programas, o que inclui o detalhamento da execu\u00e7\u00e3o or\u00e7ament\u00e1ria e os aspectos de controle e monitoramento (a\u00e7\u00f5es or\u00e7ament\u00e1rias e n\u00e3o or\u00e7ament\u00e1rias).<\/strong><\/p>\n\n\n\n<p>Por outro lado, a <strong>dimens\u00e3o t\u00e1tica<\/strong> refere-se a um n\u00edvel intermedi\u00e1rio do planejamento, que <strong>traduz as diretrizes estrat\u00e9gicas em a\u00e7\u00f5es concretas<\/strong>, sendo respons\u00e1vel por definir os programas, objetivos, objetivos espec\u00edficos, indicadores, metas, entregas, investimentos plurianuais e medidas institucionais e normativas que orientar\u00e3o as a\u00e7\u00f5es de governo, <strong><u>e n\u00e3o pela gest\u00e3o operacional, como ocorre na dimens\u00e3o t\u00e9cnica<\/u><\/strong>.<\/p>\n\n\n\n<p>Portanto, \u00e9 incorreto afirmar que a <strong>dimens\u00e3o t\u00e9cnica<\/strong> do PPA se materializa nos programas. Na verdade, os programas est\u00e3o vinculados \u00e0 <strong>dimens\u00e3o t\u00e1tica<\/strong> do planejamento, que est\u00e1 diretamente associada \u00e0 implementa\u00e7\u00e3o concreta das pol\u00edticas p\u00fablicas por meio de metas, entregas e investimentos, conforme o ciclo de planejamento governamental.<\/p>\n\n\n\n<p>A confus\u00e3o entre as dimens\u00f5es t\u00e9cnica e t\u00e1tica reflete uma interpreta\u00e7\u00e3o equivocada do que cada uma representa no contexto do planejamento plurianual. A dimens\u00e3o t\u00e9cnica n\u00e3o deve ser entendida como a que engloba diretamente os <strong>programas<\/strong> do PPA, j\u00e1 que essa atribui\u00e7\u00e3o pertence \u00e0 dimens\u00e3o t\u00e1tica, respons\u00e1vel pela tradu\u00e7\u00e3o das estrat\u00e9gias em programas.<\/p>\n\n\n\n<p>Importante mencionar, tamb\u00e9m, que o MTPPA 2024\/2027 <strong>em nenhum momento<\/strong> se refere \u00e0 dimens\u00e3o t\u00e1tica como dimens\u00e3o t\u00e9cnica, o que denota o equ\u00edvoco da utiliza\u00e7\u00e3o do termo na quest\u00e3o objeto de recurso.<\/p>\n\n\n\n<p>Dessa forma, uma vez que os \u201c<em>programas, que incluem aspectos como objetivos, metas, entregas e investimentos necess\u00e1rios para sua implementa\u00e7\u00e3o\u201d <\/em>n\u00e3o est\u00e3o presentes na dimens\u00e3o t\u00e9cnica (operacional), mas sim na dimens\u00e3o t\u00e1tica, pugna-se, respeitosamente, pela <strong>altera\u00e7\u00e3o de gabarito para \u201cERRADO\u201d<\/strong>.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p>[1] https:\/\/www.gov.br\/planejamento\/pt-br\/assuntos\/planejamento\/plano-plurianual\/copy_of_arquivos\/manual-tecnico-do-plano-plurianual-2024-2027\/manual-do-ppa-2024-2027-1.pdf<\/p>\n\n\n\n<p>[2] Chiavenato, I. (2022). Administra\u00e7\u00e3o: Teoria, Processo e Pr\u00e1tica (6\u00aa ed.). S\u00e3o Paulo: Atlas. p. 42.<\/p>\n\n\n\n<p class=\"has-very-light-gray-to-cyan-bluish-gray-gradient-background has-background\"><strong>Professor Andr\u00e9 Rocha<\/strong><\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Quest\u00e3o 73 <\/strong>(No processo de regulariza\u00e7\u00e3o de uma&#8230;)<\/p>\n\n\n\n<p>Recurso: anula\u00e7\u00e3o da quest\u00e3o.<\/p>\n\n\n\n<p>Fundamenta\u00e7\u00e3o: exige conte\u00fado do Decreto n\u00ba 12.336\/2024, n\u00e3o previsto no edital.<\/p>\n\n\n\n<p><strong>Quest\u00e3o 101 <\/strong>(Entre os servi\u00e7os ambientais destinados&#8230;)<\/p>\n\n\n\n<p>Recurso: convers\u00e3o para gabarito \u201cerrado\u201d ou, subsidiariamente, anula\u00e7\u00e3o da quest\u00e3o.<\/p>\n\n\n\n<p>Fundamenta\u00e7\u00e3o: o plantio de \u00e1rvores n\u00e3o contribui para a redu\u00e7\u00e3o da emiss\u00e3o de CO<sub>2<\/sub>, mas sim para o sequestro\/remo\u00e7\u00e3o de CO<sub>2 <\/sub>da atmosfera. Evidentemente, num contexto de compensa\u00e7\u00e3o, o plantio pode auxiliar na redu\u00e7\u00e3o do saldo de emiss\u00f5es, ou mesmo o plantio poderia evitar emiss\u00f5es num contexto de recupera\u00e7\u00e3o de \u00e1reas degradadas, por exemplo, mas ter de chegar a esse tipo de conclus\u00e3o para responder \u00e0 quest\u00e3o \u00e9 extrapolar o que foi fornecido pelo enunciado da quest\u00e3o. Numa prova objetiva, as quest\u00f5es n\u00e3o podem ser pass\u00edveis de interpreta\u00e7\u00e3o\/subjetividades\/extrapola\u00e7\u00f5es, raz\u00e3o pela qual a quest\u00e3o deveria, no m\u00ednimo, ser anulada.<\/p>\n\n\n\n<p><strong>Quest\u00e3o 107 <\/strong>(A venda ou a revenda de merc\u00fario met\u00e1lico&#8230;)<\/p>\n\n\n\n<p>Recurso: anula\u00e7\u00e3o da quest\u00e3o.<\/p>\n\n\n\n<p>Fundamenta\u00e7\u00e3o: exige a literalidade do art. 36 da Instru\u00e7\u00e3o Normativa n\u00ba 26\/2024 do Ibama, conte\u00fado n\u00e3o previsto no edital.<\/p>\n\n\n\n<p><strong>Quest\u00e3o 108 <\/strong>(N\u00e3o se aplicam aos compostos de merc\u00fario&#8230;)<\/p>\n\n\n\n<p>Recurso: anula\u00e7\u00e3o da quest\u00e3o.<\/p>\n\n\n\n<p>Fundamenta\u00e7\u00e3o: exige a literalidade do art. 1\u00ba da Instru\u00e7\u00e3o Normativa n\u00ba 26\/2024 do Ibama, conte\u00fado n\u00e3o previsto no edital.<\/p>\n\n\n\n<p><strong>Quest\u00e3o 109 <\/strong>(O IBAMA poder\u00e1 realizar, no prazo de at\u00e9 trinta dias&#8230;)<\/p>\n\n\n\n<p>Recurso: anula\u00e7\u00e3o da quest\u00e3o.<\/p>\n\n\n\n<p>Fundamenta\u00e7\u00e3o: exige a literalidade do art. 55 da Instru\u00e7\u00e3o Normativa n\u00ba 26\/2024 do Ibama, conte\u00fado n\u00e3o previsto no edital.<\/p>\n\n\n\n<p class=\"has-text-align-center\"><em>Para mais informa\u00e7\u00f5es do concurso IBAMA, cujos recursos para o cargo 2 voc\u00ea confere neste artigo, acesse o link abaixo. Preparamos uma p\u00e1gina completa para voc\u00ea!<\/em><\/p>\n\n\n\n<p class=\"has-text-align-center has-cyan-bluish-gray-background-color has-background has-medium-font-size\"><strong>Saiba mais: <a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ibama\/\" target=\"_blank\" rel=\"noreferrer noopener\">concurso IBAMA<\/a><\/strong><\/p>\n\n\n\n<div class=\"container\" id=\"boxes\">\n  <div class=\"row\">\n\n    <div class=\"col-sm\">\n      <div class=\"banner-federais\" id=\"box-assinatura\">\n        <h2 class=\"titulo-assinatura\" style=\"text-align: left;\">Cursos para o IBAMA<\/h2>\n        <p class=\"subtitulo-assinatura\" style=\"text-align: left;\">Prepare-se com o Estrat\u00e9gia!<\/p>\n        <div class=\"box-botao\" style=\"text-align: left;\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/cursosPorConcurso\/ibama-analista-61\/\" role=\"button\" rel=\"noopener noreferrer\">Confira os pacotes!<\/a>\n        <\/div>\n      <\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"container\" id=\"boxes\">\n  <div class=\"row\">\n\n    <div class=\"col-sm\">\n      <div class=\"estrategia\" id=\"box-assinatura\">\n        <h3 class=\"titulo-assinatura\">Assinatura Concursos<\/h3>\n        <p class=\"subtitulo-assinatura\">Assinatura de 1 ano ou 2 anos<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/assinaturas\/\" role=\"button\" rel=\"noopener noreferrer\">ASSINE AGORA<\/a>\n        <\/div>\n      <\/div><\/div><\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"quer-saber-tudo-sobre-concursos-previstos-confira-nossos-artigos\">Quer saber tudo sobre concursos previstos?<br \/>Confira nossos artigos!<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos Abertos<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-federais\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos Federais<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2025\/\">Concursos 2025<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Ap\u00f3s a aplica\u00e7\u00e3o das provas do\u00a0concurso IBAMA (Instituto Brasileiro do Meio Ambiente e dos Recursos Naturais Renov\u00e1veis) no \u00faltimo domingo, 06 de abril, o Cebraspe, respons\u00e1vel pela condu\u00e7\u00e3o do certame, liberou o acesso aos\u00a0gabaritos provis\u00f3rios\u00a0da etapa. Com isso, os interessados poder\u00e3o interpor recursos entre os dias 08 e 10 de abril. O Estrat\u00e9gia Concursos esteve [&hellip;]<\/p>\n","protected":false},"author":1483,"featured_media":951975,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"news","footnotes":""},"categories":[1],"tags":[],"tax_estado":[],"class_list":["post-1559882","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cursos-e-concursos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Concurso IBAMA - Cargo 2 (Tema 1): recursos poss\u00edveis!<\/title>\n<meta name=\"description\" content=\"Veja quais s\u00e3o as quest\u00f5es e recursos poss\u00edveis contra os gabaritos do concurso IBAMA para o cargo 2, no site da coruja!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ibama-cargo-2-tema-1-recursos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Concurso IBAMA - Cargo 2 (Tema 1): recursos poss\u00edveis!\" \/>\n<meta property=\"og:description\" content=\"Veja quais s\u00e3o as quest\u00f5es e recursos poss\u00edveis contra os gabaritos do concurso IBAMA para o cargo 2, no site da coruja!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ibama-cargo-2-tema-1-recursos\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-09T14:13:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-11T20:25:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/01\/21150137\/ibama-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"168\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Diogo Mendes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Diogo Mendes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"13 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ibama-cargo-2-tema-1-recursos\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ibama-cargo-2-tema-1-recursos\/\"},\"author\":{\"name\":\"Diogo Mendes\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/cc9e76173880338ce9f656c88664a1f6\"},\"headline\":\"Concurso IBAMA &#8211; Cargo 2 (Tema 1): recursos poss\u00edveis!\",\"datePublished\":\"2025-04-09T14:13:00+00:00\",\"dateModified\":\"2025-04-11T20:25:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ibama-cargo-2-tema-1-recursos\/\"},\"wordCount\":2582,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ibama-cargo-2-tema-1-recursos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/01\/21150137\/ibama-1.jpg\",\"articleSection\":[\"Concursos P\u00fablicos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ibama-cargo-2-tema-1-recursos\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ibama-cargo-2-tema-1-recursos\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ibama-cargo-2-tema-1-recursos\/\",\"name\":\"Concurso IBAMA - Cargo 2 (Tema 1): recursos poss\u00edveis!\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ibama-cargo-2-tema-1-recursos\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ibama-cargo-2-tema-1-recursos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/01\/21150137\/ibama-1.jpg\",\"datePublished\":\"2025-04-09T14:13:00+00:00\",\"dateModified\":\"2025-04-11T20:25:47+00:00\",\"description\":\"Veja quais s\u00e3o as quest\u00f5es e recursos poss\u00edveis contra os gabaritos do concurso IBAMA para o cargo 2, no site da coruja!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ibama-cargo-2-tema-1-recursos\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ibama-cargo-2-tema-1-recursos\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ibama-cargo-2-tema-1-recursos\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/01\/21150137\/ibama-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/01\/21150137\/ibama-1.jpg\",\"width\":300,\"height\":168,\"caption\":\"IBAMA nomea\u00e7\u00f5es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ibama-cargo-2-tema-1-recursos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Concurso IBAMA &#8211; Cargo 2 (Tema 1): recursos poss\u00edveis!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/cc9e76173880338ce9f656c88664a1f6\",\"name\":\"Diogo Mendes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/9754d6777d460a45ef4067b586b94c32005cc2345a0404b8d96adc620cf63806?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9754d6777d460a45ef4067b586b94c32005cc2345a0404b8d96adc620cf63806?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9754d6777d460a45ef4067b586b94c32005cc2345a0404b8d96adc620cf63806?s=96&d=mm&r=g\",\"caption\":\"Diogo Mendes\"},\"description\":\"Diogo Mendes \u00e9 jornalista formado pela Universidade Paulista, com experi\u00eancia em reda\u00e7\u00f5es de diversos ve\u00edculos e na produ\u00e7\u00e3o de conte\u00fados especializados em concursos p\u00fablicos. Desde 2019, atua no Estrat\u00e9gia Concursos como Jornalista e Analista de Conte\u00fado, com foco na apura\u00e7\u00e3o de informa\u00e7\u00f5es junto a \u00f3rg\u00e3os e fontes oficiais. Dedica-se especialmente \u00e0 produ\u00e7\u00e3o de not\u00edcias e reportagens sobre Concursos Legislativos, al\u00e9m de acompanhar diariamente os concursos policiais, banc\u00e1rios e da \u00e1rea da sa\u00fade.\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/diogo-mendesestrategiaconcursos-com-br\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Concurso IBAMA - Cargo 2 (Tema 1): recursos poss\u00edveis!","description":"Veja quais s\u00e3o as quest\u00f5es e recursos poss\u00edveis contra os gabaritos do concurso IBAMA para o cargo 2, no site da coruja!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ibama-cargo-2-tema-1-recursos\/","og_locale":"pt_BR","og_type":"article","og_title":"Concurso IBAMA - Cargo 2 (Tema 1): recursos poss\u00edveis!","og_description":"Veja quais s\u00e3o as quest\u00f5es e recursos poss\u00edveis contra os gabaritos do concurso IBAMA para o cargo 2, no site da coruja!","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ibama-cargo-2-tema-1-recursos\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2025-04-09T14:13:00+00:00","article_modified_time":"2025-04-11T20:25:47+00:00","og_image":[{"width":300,"height":168,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/01\/21150137\/ibama-1.jpg","type":"image\/jpeg"}],"author":"Diogo Mendes","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Diogo Mendes","Est. tempo de leitura":"13 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ibama-cargo-2-tema-1-recursos\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ibama-cargo-2-tema-1-recursos\/"},"author":{"name":"Diogo Mendes","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/cc9e76173880338ce9f656c88664a1f6"},"headline":"Concurso IBAMA &#8211; Cargo 2 (Tema 1): recursos poss\u00edveis!","datePublished":"2025-04-09T14:13:00+00:00","dateModified":"2025-04-11T20:25:47+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ibama-cargo-2-tema-1-recursos\/"},"wordCount":2582,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ibama-cargo-2-tema-1-recursos\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/01\/21150137\/ibama-1.jpg","articleSection":["Concursos P\u00fablicos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ibama-cargo-2-tema-1-recursos\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ibama-cargo-2-tema-1-recursos\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ibama-cargo-2-tema-1-recursos\/","name":"Concurso IBAMA - Cargo 2 (Tema 1): recursos poss\u00edveis!","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ibama-cargo-2-tema-1-recursos\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ibama-cargo-2-tema-1-recursos\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/01\/21150137\/ibama-1.jpg","datePublished":"2025-04-09T14:13:00+00:00","dateModified":"2025-04-11T20:25:47+00:00","description":"Veja quais s\u00e3o as quest\u00f5es e recursos poss\u00edveis contra os gabaritos do concurso IBAMA para o cargo 2, no site da coruja!","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ibama-cargo-2-tema-1-recursos\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ibama-cargo-2-tema-1-recursos\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ibama-cargo-2-tema-1-recursos\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/01\/21150137\/ibama-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/01\/21150137\/ibama-1.jpg","width":300,"height":168,"caption":"IBAMA nomea\u00e7\u00f5es"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ibama-cargo-2-tema-1-recursos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Concurso IBAMA &#8211; Cargo 2 (Tema 1): recursos poss\u00edveis!"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/cc9e76173880338ce9f656c88664a1f6","name":"Diogo Mendes","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/9754d6777d460a45ef4067b586b94c32005cc2345a0404b8d96adc620cf63806?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9754d6777d460a45ef4067b586b94c32005cc2345a0404b8d96adc620cf63806?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9754d6777d460a45ef4067b586b94c32005cc2345a0404b8d96adc620cf63806?s=96&d=mm&r=g","caption":"Diogo Mendes"},"description":"Diogo Mendes \u00e9 jornalista formado pela Universidade Paulista, com experi\u00eancia em reda\u00e7\u00f5es de diversos ve\u00edculos e na produ\u00e7\u00e3o de conte\u00fados especializados em concursos p\u00fablicos. Desde 2019, atua no Estrat\u00e9gia Concursos como Jornalista e Analista de Conte\u00fado, com foco na apura\u00e7\u00e3o de informa\u00e7\u00f5es junto a \u00f3rg\u00e3os e fontes oficiais. Dedica-se especialmente \u00e0 produ\u00e7\u00e3o de not\u00edcias e reportagens sobre Concursos Legislativos, al\u00e9m de acompanhar diariamente os concursos policiais, banc\u00e1rios e da \u00e1rea da sa\u00fade.","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/diogo-mendesestrategiaconcursos-com-br\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1559882","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/1483"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1559882"}],"version-history":[{"count":12,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1559882\/revisions"}],"predecessor-version":[{"id":1561880,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1559882\/revisions\/1561880"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/951975"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1559882"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1559882"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1559882"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1559882"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}