{"id":1554549,"date":"2025-04-30T14:36:00","date_gmt":"2025-04-30T17:36:00","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=1554549"},"modified":"2025-04-22T17:50:03","modified_gmt":"2025-04-22T20:50:03","slug":"oxitona-paroxitona-proparoxitona","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/oxitona-paroxitona-proparoxitona\/","title":{"rendered":"Ox\u00edtona, parox\u00edtona e proparox\u00edtona: O que \u00e9?"},"content":{"rendered":"\n<p>Ol\u00e1, pessoal. Hoje falaremos sobre uma forma muito importante de classifica\u00e7\u00e3o de palavras: <strong>Ox\u00edtona, parox\u00edtona e proparox\u00edtona.<\/strong> Essa forma de classifica\u00e7\u00e3o <em>leva em conta a posi\u00e7\u00e3o da s\u00edlaba mais forte da palavra<\/em> e tem muita import\u00e2ncia em diversos outros assuntos, como a acentua\u00e7\u00e3o e a separa\u00e7\u00e3o de palavras.<\/p>\n\n\n<figure class=\"wp-block-post-featured-image\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1920\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/05\/04120352\/aprova%C3%A7%C3%A3o2_wordcloud-scaled.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"ox\u00edtona, parox\u00edtona e proparox\u00edtona\" style=\"object-fit:cover;\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/05\/04120352\/aprova%C3%A7%C3%A3o2_wordcloud-scaled.jpg 2560w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/05\/04120352\/aprova%C3%A7%C3%A3o2_wordcloud-300x225.jpg 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/05\/04120352\/aprova%C3%A7%C3%A3o2_wordcloud-1024x768.jpg 1024w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/05\/04120352\/aprova%C3%A7%C3%A3o2_wordcloud-768x576.jpg 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/05\/04120352\/aprova%C3%A7%C3%A3o2_wordcloud-1536x1152.jpg 1536w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/05\/04120352\/aprova%C3%A7%C3%A3o2_wordcloud-2048x1536.jpg 2048w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/05\/04120352\/aprova%C3%A7%C3%A3o2_wordcloud-610x458.jpg 610w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/figure>\n\n\n<h2 class=\"wp-block-heading\" id=\"h-oxitonas-e-monossilabos-tonicos-ultima-silaba\">OX\u00cdTONAS E MONOSS\u00cdLABOS T\u00d4NICOS &#8211; \u00daLTIMA S\u00cdLABA<\/h2>\n\n\n\n<p>Ox\u00edtonas s\u00e3o aquelas palavras em que a s\u00edlaba t\u00f4nica(aquele que pronunciamos com mais for\u00e7a) se encontra na \u00faltima s\u00edlaba.<\/p>\n\n\n\n<p>Exemplos: tam<strong><em>b\u00e9m<\/em><\/strong>, a<em><strong>mor<\/strong><\/em>, televi<strong><em>s\u00e3o<\/em><\/strong>.<\/p>\n\n\n\n<p>Vamos separar as palavras para facilitarmos a visualiza\u00e7\u00e3o:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>tam-<strong>b\u00e9m<\/strong>. Vejam que a s\u00edlaba mais forte \u00e9 a parte final(<em>-b\u00e9m<\/em>)<\/li>\n\n\n\n<li>a-<strong>mor<\/strong>. Vejam que a s\u00edlaba mais forte \u00e9 a parte final(<em>-mor<\/em>).<\/li>\n\n\n\n<li>te-le-vi-<strong>s\u00e3o<\/strong>. Vejam que a s\u00edlaba mais forte \u00e9 a parte final(<em>-s\u00e3o<\/em>)<\/li>\n<\/ul>\n\n\n\n<p>Tamb\u00e9m possuem a s\u00edlaba forte na parte final os monoss\u00edlabos t\u00f4nicos. <\/p>\n\n\n\n<p>Os monoss\u00edlabos s\u00e3o, como o pr\u00f3prio nome diz, aquelas palavras que s\u00f3 possuem uma s\u00edlaba(sem possibilidade de separa\u00e7\u00e3o sil\u00e1bica). Ex: P\u00e1, p\u00e9, que.<\/p>\n\n\n\n<p>Dentro dos monoss\u00edlabos, temos os <strong>\u00e1tonos <\/strong>e os <strong>t\u00f4nicos<\/strong>. <\/p>\n\n\n\n<p>Os \u00e1tonos s\u00e3o aqueles que pronunci\u00e1mos de maneira pouco enf\u00e1tica, n\u00e3o possuem acento e n\u00e3o possuem um sentido completo sem estarem em um contexto. Ex. que, se, um, uns etc.<\/p>\n\n\n\n<p>Por sua vez, os monoss\u00edlabos t\u00f4nicos s\u00e3o aqueles quem pronunciamos com mais for\u00e7a, possuem sentido pr\u00f3prio e podem ser acentuadas, se atendidas as regras de acentua\u00e7\u00e3o. Ex. p\u00e1, p\u00e9, c\u00e9u e r\u00e9u.<\/p>\n\n\n\n<p>Apenas como complemento, os <strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-green-cyan-color\">monoss\u00edlabos t\u00f4nicos&nbsp;s\u00e3o acentuados quando terminam em a\/as, e\/es, o\/os, \u00e9u(s), \u00e9i(s), \u00f3i(s)<\/mark><\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-paroxitona-penultima-silaba\">PAROX\u00cdTONA &#8211; PEN\u00daLTIMA S\u00cdLABA<\/h2>\n\n\n\n<p>As parox\u00edtonas s\u00e3o palavras em que a s\u00edlaba t\u00f4nica(aquela que pronunciamos com mais for\u00e7a) se encontra na <strong>pen\u00faltima s\u00edlaba<\/strong>.<\/p>\n\n\n\n<p>Vamos a alguns exemplos:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Maravilha(Ma &#8211; ra &#8211; <strong>VI <\/strong>-lha);<\/li>\n\n\n\n<li>Indigente(In &#8211; di &#8211; <strong>GEN <\/strong>&#8211; te);<\/li>\n\n\n\n<li>V\u00edrus (<strong>V\u00cd <\/strong>&#8211; rus).<\/li>\n<\/ul>\n\n\n\n<p>Da mesma forma que as ox\u00edtonas e os monoss\u00edlabos t\u00f4nicos, as parox\u00edtonas possuem diversas regras de acentua\u00e7\u00e3o que s\u00e3o muito importantes para qualquer tipo de concurso p\u00fablico\/vestibular.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-proparoxitonas-antepenultima-silaba\">PROPAROX\u00cdTONAS &#8211; ANTEPEN\u00daLTIMA S\u00cdLABA<\/h2>\n\n\n\n<p>Pessoal, as proparox\u00edtonas s\u00e3o aquelas em que a s\u00edlaba forte se encontra na <strong>antepen\u00faltima <\/strong>parte.<\/p>\n\n\n\n<p>Vamos a exemplos:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Pr\u00f3ximo: <strong>PR\u00d3<\/strong> &#8211; XI &#8211; MO;<\/li>\n\n\n\n<li>L\u00facido: <strong>L\u00da <\/strong>&#8211; CI &#8211; DO;<\/li>\n\n\n\n<li>\u00c9poca: <strong>\u00c9 <\/strong>&#8211; PO &#8211; CA.<\/li>\n<\/ul>\n\n\n\n<p>Em que pese n\u00e3o ser o objetivo desse artigo, j\u00e1 gravem que <strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">TODAS as proparox\u00edtonas s\u00e3o acentuadas.<\/mark><\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-proparoxitona-eventual\">PROPAROX\u00cdTONA EVENTUAL<\/h3>\n\n\n\n<p>Ainda no \u00e2mbito das proparox\u00edtonas, h\u00e1 um tema pouco explorado que gostar\u00edamos de comentar: <strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\">proparox\u00edtonas eventuais.<\/mark><\/strong><\/p>\n\n\n\n<p>Provavelmente voc\u00eas j\u00e1 se depararam com essas palavras e nem perceberam que havia essa celeuma por tr\u00e1s. Vamos a um exemplo para demonstrar. Separemos a palavra SECRET\u00c1RIA:<\/p>\n\n\n\n<p><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-luminous-vivid-orange-color\">SECRET\u00c1RIA = SE &#8211; CRE &#8211; T\u00c1 &#8211; RIA ou SE &#8211; CRE -T\u00c1 &#8211; RI &#8211; A?<\/mark><\/strong><\/p>\n\n\n\n<p>Ou seja, a s\u00edlaba forte est\u00e1 na pen\u00faltima s\u00edlaba ou na antepen\u00faltima s\u00edlaba? <\/p>\n\n\n\n<p>Pessoal, n\u00e3o temos um consenso entre os gram\u00e1ticos. <\/p>\n\n\n\n<p>O que prevalece \u00e9 que ambas as divis\u00f5es sil\u00e1bicas est\u00e3o corretas.<\/p>\n\n\n\n<p><strong>Aprofundando&#8230;<\/strong><\/p>\n\n\n\n<p>As vogais (a, e, i, o, u) podem ser classificadas como vogais(quando possuem a maior carga sonora de uma s\u00edlaba) ou semivogais(quando s\u00e3o pronunciadas de maneira pouco enf\u00e1tica ou nem s\u00e3o pronunciadas). Quando uma vogal e uma semivogal se encontram, temos o chamado DITONGO.<\/p>\n\n\n\n<p>Eles podem ser <strong>DITONGOS CRESCENTES (semivogal + vogal)<\/strong> ou <strong>DITONGOS DECRESCENTES (vogal + semivogal).<\/strong><\/p>\n\n\n\n<p><strong>Exemplo<\/strong>: Pai.<\/p>\n\n\n\n<p>Vejam que tempo duas vogais. O &#8220;<strong>a<\/strong>&#8221; possui maior carga sonora. J\u00e1 o &#8220;<strong>i<\/strong>&#8221; \u00e9 pouco pronunciado(sai quase como um sussurro). Neste caso, temos uma vogal + semivogal, logo \u00e9 um <strong>DITONGO DECRESCENTE<\/strong>.<\/p>\n\n\n\n<p>A discuss\u00e3o das proparox\u00edtonas eventuais recai nos DITONGOS CRESCENTES. Isso porque<mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-purple-color\"> <strong>toda s\u00edlaba precisa ter uma vogal(nunca esque\u00e7am essa regra)<\/strong><\/mark><strong>.<\/strong> Assim, voltando ao exemplo origin\u00e1rio, vejam que <strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-luminous-vivid-orange-color\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-luminous-vivid-orange-color\">SE &#8211; CRE &#8211; T\u00c1 &#8211; RIA<\/mark><\/strong><\/mark><\/strong> possuem um DITONGO CRESCENTE(<strong>IA<\/strong>). Por\u00e9m, como o &#8220;A&#8221; \u00c9 SEMPRE VOGAL, ela poderia figurar sozinha (RI &#8211; A), o que passaria a ser um HIATO(encontro de duas vogais) e n\u00e3o um DITONGO (vogal + semivogal e vice-versa).<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-questao-sobre-proparoxitona-eventual\">Quest\u00e3o sobre proparox\u00edtona eventual<\/h3>\n\n\n\n<p>O CEBRASPE cobrou uma quest\u00e3o que explorou esse tema. Vejamos:<\/p>\n\n\n\n<p><a href=\"http:\/\/www.cespe.unb.br\/concursos\/stf_13\/arquivos\/STF13_008_17.pdf\">2013 &#8211; CEBRASPE &#8211; ANALISTA JUDICI\u00c1RIO STF<\/a><\/p>\n\n\n\n<p><em>&#8220;Quest\u00e3o 54. O emprego do acento gr\u00e1fico em \u201c<strong>rem\u00e9dios<\/strong>\u201d pode ser justificado com base em duas regras distintas de acentua\u00e7\u00e3o&#8221;. CERTO\/ERRADO<\/em><\/p>\n\n\n\n<p><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\">Coment\u00e1rios<\/mark><\/strong>: Observem que o final da palavra \u00e9 um ditongo crescente. Pronuncie mentalmente a palavra e veja que o &#8220;o&#8221; \u00e9 pronunciado com mais \u00eanfase que o pr\u00f3prio &#8220;i&#8221;.<\/p>\n\n\n\n<p>Ent\u00e3o, poder\u00edamos ter a seguinte separa\u00e7\u00e3o: RE &#8211; M\u00c9 &#8211; DIOS. Aqui, acentuar\u00edamos por ser uma parox\u00edtona terminada em ditongo.<\/p>\n\n\n\n<p>Por\u00e9m, poder\u00edamos separar assim: RE &#8211; M\u00c9 &#8211; D<strong>I<\/strong> &#8211; OS. Aqui, acentuar\u00edamos por ser uma proparox\u00edtona e, ao inv\u00e9s de haver um DITONGO, haveria um HIATO(encontro de duas vogais). Ou seja, o &#8220;<strong>I<\/strong>&#8221; seria vogal tamb\u00e9m.<\/p>\n\n\n\n<p>Ambas as formas s\u00e3o defendidas como corretas por importantes estudiosos, como Evanildo Bechara &#8211; <em>vide Moderna Gram\u00e1tica Portuguesa, 39\u00aa edi\u00e7\u00e3o (2019)<\/em>.<\/p>\n\n\n\n<p>Logo, podemos aplicar duas regras. <strong>Gabarito: CERTO<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-palavras-que-causam-duvidas\">PALAVRAS QUE CAUSAM D\u00daVIDAS<\/h2>\n\n\n\n<p>Nobres, a pr\u00e1tica de estudos nos mostra que h\u00e1 diversas palavras que comumente pronunciamos errado e por conseguinte classificaremos errado em ox\u00edtona, parox\u00edtona e proparox\u00edtona.<\/p>\n\n\n\n<p>As principais e mais cobradas em concursos s\u00e3o:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>ru<strong>BRI<\/strong>ca &#8211; A s\u00edlaba forte \u00e9 BRI ent\u00e3o leva acento. Portanto, <strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\"><em>R\u00da<\/em>BRICA <\/mark><\/strong>est\u00e1 <strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\">ERRADO<\/mark><\/strong>.<\/li>\n\n\n\n<li><strong>\u00cdbero<\/strong>:\u00a0A pron\u00fancia correta \u00e9 &#8220;i-<strong>be<\/strong>-ro&#8221;, e n\u00e3o &#8220;\u00ed-be-ro&#8221;.\u00a0<\/li>\n\n\n\n<li><strong>Gratuito<\/strong>:\u00a0A pron\u00fancia correta \u00e9 &#8220;gra-<strong>tu<\/strong>i-to&#8221;, e n\u00e3o &#8220;gra-tu-\u00ed-to&#8221;.\u00a0<\/li>\n\n\n\n<li><strong>Car\u00e1teres<\/strong>:\u00a0A pron\u00fancia correta \u00e9 &#8220;ca-rac-<strong>te<\/strong>-res&#8221;, e n\u00e3o &#8220;ca-r\u00e1c-te-res&#8221;.\u00a0<\/li>\n\n\n\n<li><strong>\u00cdnterim<\/strong>:\u00a0A pron\u00fancia correta \u00e9 &#8220;<strong>\u00edn<\/strong>terim&#8221;, e n\u00e3o &#8220;interim&#8221;.\u00a0<\/li>\n\n\n\n<li><strong>L\u00eavedo<\/strong>:\u00a0A pron\u00fancia correta \u00e9 &#8220;<strong>l\u00ea<\/strong>vedo&#8221;, e n\u00e3o &#8220;levedo&#8221;.\u00a0<\/li>\n\n\n\n<li><strong>Leuc\u00f3cito<\/strong>:\u00a0A pron\u00fancia correta \u00e9 &#8220;leu<strong>c\u00f3<\/strong>cito&#8221;, e n\u00e3o &#8220;leucocito&#8221;.\u00a0<\/li>\n\n\n\n<li><strong>Prot\u00f3tipo<\/strong>:\u00a0A pron\u00fancia correta \u00e9 &#8220;pro<strong>t\u00f3<\/strong>tipo&#8221;, e n\u00e3o &#8220;prototipo&#8221;.<\/li>\n\n\n\n<li><strong>Cateter<\/strong>: A pron\u00fancia correta \u00e9 &#8220;cate<strong>TER<\/strong>&#8220;, e n\u00e3o &#8220;cat\u00e9ter&#8221;.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-conclusao\">CONCLUS\u00c3O<\/h2>\n\n\n\n<p>Finalizamos, pessoal, mais um artigo. O tema relacionada \u00e0 ox\u00edtona, parox\u00edtona e proparox\u00edtona \u00e9 de grande relev\u00e2ncia ao estudo da l\u00edngua portuguesa e est\u00e1 totalmente integrado com outros temais tais como separa\u00e7\u00e3o sil\u00e1bica e acentua\u00e7\u00e3o. De forma que sugerimos o estudo conjunto desses temas.<\/p>\n\n\n\n<p>Bons Estudos!<\/p>\n\n\n\n<p class=\"has-text-align-left\"><strong>Quer estar antenado aos pr\u00f3ximos concursos previstos? Confira nossos artigos!<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center has-black-color has-vivid-cyan-blue-background-color has-text-color has-background has-link-color wp-elements-9603f785c0eec09bc6030dcf96ae9ff9\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-black-color\">Concursos Abertos<\/mark><\/strong><\/a><\/p>\n\n\n\n<p class=\"has-text-align-center has-black-color has-vivid-cyan-blue-background-color has-text-color has-background has-link-color wp-elements-84cb1561c24d33e0c6315ae1f6005bde\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2025\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-black-color\">Concursos 2025<\/mark><\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ol\u00e1, pessoal. Hoje falaremos sobre uma forma muito importante de classifica\u00e7\u00e3o de palavras: Ox\u00edtona, parox\u00edtona e proparox\u00edtona. Essa forma de classifica\u00e7\u00e3o leva em conta a posi\u00e7\u00e3o da s\u00edlaba mais forte da palavra e tem muita import\u00e2ncia em diversos outros assuntos, como a acentua\u00e7\u00e3o e a separa\u00e7\u00e3o de palavras. OX\u00cdTONAS E MONOSS\u00cdLABOS T\u00d4NICOS &#8211; \u00daLTIMA S\u00cdLABA [&hellip;]<\/p>\n","protected":false},"author":2891,"featured_media":510065,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1],"tags":[],"tax_estado":[219963],"class_list":["post-1554549","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cursos-e-concursos","tax_estado-concursos-federais"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ox\u00edtona, parox\u00edtona e proparox\u00edtona<\/title>\n<meta name=\"description\" content=\"Falaremos sobre a classifica\u00e7\u00e3o das palavras em ox\u00edtona, parox\u00edtona e proparox\u00edtona e sua rela\u00e7\u00e3o com a separa\u00e7\u00e3o de palavras e acentua\u00e7\u00e3o.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/oxitona-paroxitona-proparoxitona\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ox\u00edtona, parox\u00edtona e proparox\u00edtona: O que \u00e9?\" \/>\n<meta property=\"og:description\" content=\"Falaremos sobre a classifica\u00e7\u00e3o das palavras em ox\u00edtona, parox\u00edtona e proparox\u00edtona e sua rela\u00e7\u00e3o com a separa\u00e7\u00e3o de palavras e acentua\u00e7\u00e3o.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/oxitona-paroxitona-proparoxitona\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-30T17:36:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/05\/04120352\/aprova%C3%A7%C3%A3o2_wordcloud-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Julian Silva da Costa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Julian Silva da Costa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/oxitona-paroxitona-proparoxitona\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/oxitona-paroxitona-proparoxitona\/\"},\"author\":{\"name\":\"Julian Silva da Costa\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/a5ec86ed99d8fd925bce05c446c24029\"},\"headline\":\"Ox\u00edtona, parox\u00edtona e proparox\u00edtona: O que \u00e9?\",\"datePublished\":\"2025-04-30T17:36:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/oxitona-paroxitona-proparoxitona\/\"},\"wordCount\":1160,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/oxitona-paroxitona-proparoxitona\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/05\/04120352\/aprova%C3%A7%C3%A3o2_wordcloud-scaled.jpg\",\"articleSection\":[\"Concursos P\u00fablicos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/oxitona-paroxitona-proparoxitona\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/oxitona-paroxitona-proparoxitona\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/oxitona-paroxitona-proparoxitona\/\",\"name\":\"Ox\u00edtona, parox\u00edtona e proparox\u00edtona\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/oxitona-paroxitona-proparoxitona\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/oxitona-paroxitona-proparoxitona\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/05\/04120352\/aprova%C3%A7%C3%A3o2_wordcloud-scaled.jpg\",\"datePublished\":\"2025-04-30T17:36:00+00:00\",\"description\":\"Falaremos sobre a classifica\u00e7\u00e3o das palavras em ox\u00edtona, parox\u00edtona e proparox\u00edtona e sua rela\u00e7\u00e3o com a separa\u00e7\u00e3o de palavras e acentua\u00e7\u00e3o.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/oxitona-paroxitona-proparoxitona\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/oxitona-paroxitona-proparoxitona\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/oxitona-paroxitona-proparoxitona\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/05\/04120352\/aprova%C3%A7%C3%A3o2_wordcloud-scaled.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/05\/04120352\/aprova%C3%A7%C3%A3o2_wordcloud-scaled.jpg\",\"width\":2560,\"height\":1920,\"caption\":\"ox\u00edtona, parox\u00edtona e proparox\u00edtona\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/oxitona-paroxitona-proparoxitona\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ox\u00edtona, parox\u00edtona e proparox\u00edtona: O que \u00e9?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/a5ec86ed99d8fd925bce05c446c24029\",\"name\":\"Julian Silva da Costa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/bdd6b68c7c5a37063a734a0fb5b7547b717c3909fd8740b8e2e6ecf1df91f3f0?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/bdd6b68c7c5a37063a734a0fb5b7547b717c3909fd8740b8e2e6ecf1df91f3f0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/bdd6b68c7c5a37063a734a0fb5b7547b717c3909fd8740b8e2e6ecf1df91f3f0?s=96&d=mm&r=g\",\"caption\":\"Julian Silva da Costa\"},\"description\":\"Principais aprova\u00e7\u00f5es: Escola Preparat\u00f3ria de Cadetes do Ar(2006-2007); Escola de Sargento das Armas-EsSA(2008); T\u00e9cnico em Seguran\u00e7a do Banco Central do Brasil(2013); Analista em Planejamento e Finan\u00e7as - SEPOG RO(2017); Fiscal de Tributos Estaduais - SEFAZ MT(2023); Auditor Fiscal Tribut\u00e1rio Municipal - ISS\/SP(2023)\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/julian_aracatihotmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ox\u00edtona, parox\u00edtona e proparox\u00edtona","description":"Falaremos sobre a classifica\u00e7\u00e3o das palavras em ox\u00edtona, parox\u00edtona e proparox\u00edtona e sua rela\u00e7\u00e3o com a separa\u00e7\u00e3o de palavras e acentua\u00e7\u00e3o.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/oxitona-paroxitona-proparoxitona\/","og_locale":"pt_BR","og_type":"article","og_title":"Ox\u00edtona, parox\u00edtona e proparox\u00edtona: O que \u00e9?","og_description":"Falaremos sobre a classifica\u00e7\u00e3o das palavras em ox\u00edtona, parox\u00edtona e proparox\u00edtona e sua rela\u00e7\u00e3o com a separa\u00e7\u00e3o de palavras e acentua\u00e7\u00e3o.","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/oxitona-paroxitona-proparoxitona\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2025-04-30T17:36:00+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/05\/04120352\/aprova%C3%A7%C3%A3o2_wordcloud-scaled.jpg","type":"image\/jpeg"}],"author":"Julian Silva da Costa","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Julian Silva da Costa","Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/oxitona-paroxitona-proparoxitona\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/oxitona-paroxitona-proparoxitona\/"},"author":{"name":"Julian Silva da Costa","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/a5ec86ed99d8fd925bce05c446c24029"},"headline":"Ox\u00edtona, parox\u00edtona e proparox\u00edtona: O que \u00e9?","datePublished":"2025-04-30T17:36:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/oxitona-paroxitona-proparoxitona\/"},"wordCount":1160,"commentCount":1,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/oxitona-paroxitona-proparoxitona\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/05\/04120352\/aprova%C3%A7%C3%A3o2_wordcloud-scaled.jpg","articleSection":["Concursos P\u00fablicos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/oxitona-paroxitona-proparoxitona\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/oxitona-paroxitona-proparoxitona\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/oxitona-paroxitona-proparoxitona\/","name":"Ox\u00edtona, parox\u00edtona e proparox\u00edtona","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/oxitona-paroxitona-proparoxitona\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/oxitona-paroxitona-proparoxitona\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/05\/04120352\/aprova%C3%A7%C3%A3o2_wordcloud-scaled.jpg","datePublished":"2025-04-30T17:36:00+00:00","description":"Falaremos sobre a classifica\u00e7\u00e3o das palavras em ox\u00edtona, parox\u00edtona e proparox\u00edtona e sua rela\u00e7\u00e3o com a separa\u00e7\u00e3o de palavras e acentua\u00e7\u00e3o.","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/oxitona-paroxitona-proparoxitona\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/oxitona-paroxitona-proparoxitona\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/oxitona-paroxitona-proparoxitona\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/05\/04120352\/aprova%C3%A7%C3%A3o2_wordcloud-scaled.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/05\/04120352\/aprova%C3%A7%C3%A3o2_wordcloud-scaled.jpg","width":2560,"height":1920,"caption":"ox\u00edtona, parox\u00edtona e proparox\u00edtona"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/oxitona-paroxitona-proparoxitona\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Ox\u00edtona, parox\u00edtona e proparox\u00edtona: O que \u00e9?"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/a5ec86ed99d8fd925bce05c446c24029","name":"Julian Silva da Costa","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/bdd6b68c7c5a37063a734a0fb5b7547b717c3909fd8740b8e2e6ecf1df91f3f0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bdd6b68c7c5a37063a734a0fb5b7547b717c3909fd8740b8e2e6ecf1df91f3f0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bdd6b68c7c5a37063a734a0fb5b7547b717c3909fd8740b8e2e6ecf1df91f3f0?s=96&d=mm&r=g","caption":"Julian Silva da Costa"},"description":"Principais aprova\u00e7\u00f5es: Escola Preparat\u00f3ria de Cadetes do Ar(2006-2007); Escola de Sargento das Armas-EsSA(2008); T\u00e9cnico em Seguran\u00e7a do Banco Central do Brasil(2013); Analista em Planejamento e Finan\u00e7as - SEPOG RO(2017); Fiscal de Tributos Estaduais - SEFAZ MT(2023); Auditor Fiscal Tribut\u00e1rio Municipal - ISS\/SP(2023)","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/julian_aracatihotmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1554549","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/2891"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1554549"}],"version-history":[{"count":34,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1554549\/revisions"}],"predecessor-version":[{"id":1657513,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1554549\/revisions\/1657513"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/510065"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1554549"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1554549"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1554549"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1554549"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}