{"id":1550237,"date":"2025-04-26T08:14:00","date_gmt":"2025-04-26T11:14:00","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=1550237"},"modified":"2025-04-22T15:15:40","modified_gmt":"2025-04-22T18:15:40","slug":"trabalho-remoto","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/trabalho-remoto\/","title":{"rendered":"Trabalho remoto"},"content":{"rendered":"\n<p>Ol\u00e1, estudantes do Direito! Preparados para mais uma sess\u00e3o de aprendizado? Neste artigo estudaremos as normas relativas ao trabalho remoto e analisaremos sua cobran\u00e7a em concursos.<\/p>\n\n\n\n<p>Para melhor compreens\u00e3o, o assunto foi dividido nos seguintes t\u00f3picos:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Introdu\u00e7\u00e3o<\/strong><\/li>\n\n\n\n<li><strong>Conceito de trabalho remoto: Lei 14.442\/2022<\/strong><\/li>\n\n\n\n<li><strong>Quest\u00f5es de concurso<\/strong><\/li>\n\n\n\n<li><strong>Considera\u00e7\u00f5es finais<\/strong><\/li>\n<\/ul>\n\n\n\n<p>Vamos l\u00e1!<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"727\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/03\/22195831\/image-3.jpg\" alt=\"trabalho remoto\" class=\"wp-image-1550240\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/03\/22195831\/image-3.jpg 1024w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/03\/22195831\/image-3-300x213.jpg 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/03\/22195831\/image-3-768x545.jpg 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/03\/22195831\/image-3-150x106.jpg 150w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h1 class=\"wp-block-heading\" id=\"h-introducao\">Introdu\u00e7\u00e3o<\/h1>\n\n\n\n<p>A regula\u00e7\u00e3o do trabalho remoto atendeu a uma necessidade que h\u00e1 muito tempo j\u00e1 se manifestava no setor.<\/p>\n\n\n\n<p>Os avan\u00e7os tecnol\u00f3gicos facilitaram a troca de informa\u00e7\u00f5es de maneira mais r\u00e1pida e confi\u00e1vel, al\u00e9m de ampliar proporcionar novas maneiras mais eficazes de se fazer determinadas tarefas. No mundo inteiro trabalhos vinham sendo exercidos de maneira remota, mas no Brasil essa realidade se limitava somente a algumas profiss\u00f5es e em nichos.<\/p>\n\n\n\n<p>Profissionais aut\u00f4nomos foram os que mais se beneficiaram das comodidades dos trabalhos n\u00e3o presenciais. Alguns prestadores de servi\u00e7o tamb\u00e9m usufru\u00edam das utilidades proporcionadas pela tecnologia, mas de maneira prec\u00e1ria. Em rela\u00e7\u00e3o aos trabalhos que demandavam v\u00ednculo constante e regularidade legal, careciam normas que regulassem sua execu\u00e7\u00e3o.<\/p>\n\n\n\n<p>Com a dissemina\u00e7\u00e3o da covid-19 e a aplica\u00e7\u00e3o de pol\u00edticas extremamente restritivas de locomo\u00e7\u00e3o, tornou-se urgente a regula\u00e7\u00e3o do trabalho remoto.<\/p>\n\n\n\n<p>Uma MPj\u00e1  havia sido publicada em 2020 para regular o tema, mas perdeu sua efic\u00e1cia sem vota\u00e7\u00e3o no Congresso. Finalmente, em 2022, a MP 1.108\/2022 foi convertida na Lei 14.442\/2022.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-large-font-size\" id=\"h-conceito-de-trabalho-remoto-lei-14-442-2022\">Conceito de trabalho remoto: Lei 14.442\/2022<\/h2>\n\n\n\n<p>O conceito de trabalho remoto foi introduzido na CLT por meio da Lei 14.442\/2022:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Art. 75-B. Considera-se teletrabalho ou trabalho remoto a presta\u00e7\u00e3o de servi\u00e7os fora das depend\u00eancias do empregador, de maneira preponderante ou n\u00e3o, com a utiliza\u00e7\u00e3o de tecnologias de informa\u00e7\u00e3o e de comunica\u00e7\u00e3o, que, por sua natureza, n\u00e3o configure trabalho externo.<\/p>\n<\/blockquote>\n\n\n\n<p>Compreender esse conceito \u00e9 extremamente importante, uma vez que as quest\u00f5es de concursos p\u00fablicos costumam cobrar a literalidade do art. 75-B da CLT.<\/p>\n\n\n\n<p>Para compreender esse artigo completamente, \u00e9 necess\u00e1rio, ainda, entender do que se trata o trabalho externo e o trabalho em domic\u00edlio.<\/p>\n\n\n\n<p>O <strong>trabalho externo<\/strong> se refere \u00e0 presta\u00e7\u00e3o de servi\u00e7os realizada fora das depend\u00eancias da empresa ou do empregador, seja em locais determinados ou itinerantes, como no caso de atua\u00e7\u00e3o em campo, visita\u00e7\u00e3o de clientes, realiza\u00e7\u00e3o de entregas ou desempenho de atividades em diferentes endere\u00e7os.<\/p>\n\n\n\n<p>O trabalho remoto seria uma modalidade qualificada do <strong>trabalho em domic\u00edlio.<\/strong> Este n\u00e3o se realiza com o uso predominante das tecnologias de informa\u00e7\u00e3o e comunica\u00e7\u00e3o, mas sim com a realiza\u00e7\u00e3o de um trabalho convencional no domic\u00edlio do empregado.<\/p>\n\n\n\n<p>Filipe Garcia (2023) costuma diferenciar o<strong> trabalho remoto<\/strong> das outras modalidades de trabalho em raz\u00e3o do <strong>uso predominante de recursos eletr\u00f4nicos e de inform\u00e1tica, como computador, internet e outros meios de comunica\u00e7\u00e3o<\/strong>.<\/p>\n\n\n\n<p>As normas dos par\u00e1grafos do artigo 75-B tamb\u00e9m costumar ser bastante cobradas. A an\u00e1lise de quest\u00f5es que tratam desse tema \u00e9 feita a seguir.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-large-font-size\" id=\"h-questoes-de-concurso\">Quest\u00f5es de concurso<\/h2>\n\n\n\n<p>Desde 2022, quando a MP 1.108 foi convertida em lei, as bancas organizadores de concursos p\u00fablicos intensificaram a cobran\u00e7a do trabalho remoto, do trabalho externo e do trabalho em domic\u00edlio. \u00c9 verdade que o foco das cobran\u00e7as \u00e9 o trabalho remoto, mas esporadicamente as bancas misturam os demais conceitos para avaliar a profundidade do conhecimento do candidato sobre a mat\u00e9ria.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><strong>(FUNDATEC &#8211; GHC &#8211; ADMINISTRADOR &#8211; 2024) QUEST\u00c3O 21 \u2013 Em 2022, foram introduzidas altera\u00e7\u00f5es na Consolida\u00e7\u00e3o das Leis do Trabalho (CLT) que regulamentaram o teletrabalho. Nesse sentido, analise as assertivas abaixo, relacionadas ao teletrabalho, assinalando C, se corretas, ou I, se incorretas.<\/strong><\/p>\n\n\n\n<p>( ) Considera-se teletrabalho ou trabalho remoto a presta\u00e7\u00e3o de servi\u00e7os fora das depend\u00eancias do empregador, de maneira preponderante ou n\u00e3o, com a utiliza\u00e7\u00e3o de tecnologias de informa\u00e7\u00e3o e de comunica\u00e7\u00e3o, que, por sua natureza, n\u00e3o configure trabalho externo.<\/p>\n\n\n\n<p>( ) Fica permitida a ado\u00e7\u00e3o do regime de teletrabalho ou trabalho remoto para estagi\u00e1rios e aprendizes. [art. 75-B, \u00a7 6\u00ba, da CLT]<\/p>\n\n\n\n<p>( ) O empregado submetido ao regime de teletrabalho ou trabalho remoto poder\u00e1 prestar servi\u00e7os por jornada ou por produ\u00e7\u00e3o ou tarefa.<\/p>\n\n\n\n<p>( ) O regime de teletrabalho ou trabalho remoto se equipara \u00e0 ocupa\u00e7\u00e3o de operador<\/p>\n\n\n\n<p>de telemarketing ou de teleatendimento. A ordem correta de preenchimento dos par\u00eanteses, de cima para baixo, \u00e9:<\/p>\n\n\n\n<p>A) C \u2013 I \u2013 I \u2013 C.<\/p>\n\n\n\n<p>B) C \u2013 I \u2013 C \u2013 I.<\/p>\n\n\n\n<p><strong>C) C \u2013 C \u2013 C \u2013 I.<\/strong><\/p>\n\n\n\n<p>D) I \u2013 C \u2013 C \u2013 C.<\/p>\n\n\n\n<p>E) I \u2013 C \u2013 I \u2013 C.<\/p>\n<\/blockquote>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><strong>(MPT &#8211; MPT &#8211; PROCURADOR DO TRABALHO &#8211; 2022) Acerca do teletrabalho ou trabalho remoto, assinale a alternativa INCORRETA:<\/strong><\/p>\n\n\n\n<p>(A) Os empregadores dever\u00e3o dar prioridade aos empregados com defici\u00eancia e aos empregados com filhos ou crian\u00e7a sob guarda judicial at\u00e9 quatro anos de idade na aloca\u00e7\u00e3o em vagas para atividades que possam ser efetuadas por meio do teletrabalho ou trabalho remoto.<\/p>\n\n\n\n<p><strong>(B) Em raz\u00e3o da natureza do trabalho desenvolvido por estagi\u00e1rios e aprendizes, n\u00e3o lhes \u00e9 permitida a ado\u00e7\u00e3o do regime de teletrabalho ou trabalho remoto. [art. 75-B, \u00a7 6\u00ba, da CLT]<\/strong><\/p>\n\n\n\n<p>(C) Aos empregados em regime de teletrabalho aplicam-se as disposi\u00e7\u00f5es previstas na legisla\u00e7\u00e3o local e nas conven\u00e7\u00f5es e nos acordos coletivos de trabalho relativas \u00e0 base territorial do estabelecimento de lota\u00e7\u00e3o do empregado.<\/p>\n\n\n\n<p>(D) O tempo de uso de equipamentos tecnol\u00f3gicos e de infraestrutura necess\u00e1ria, bem como de softwares, de ferramentas digitais ou de aplica\u00e7\u00f5es de internet utilizados para o teletrabalho, fora da jornada de trabalho normal do empregado n\u00e3o constitui tempo \u00e0 disposi\u00e7\u00e3o ou regime de prontid\u00e3o ou de sobreaviso exceto se houver previs\u00e3o em acordo individual ou em acordo ou conven\u00e7\u00e3o coletiva de trabalho.<\/p>\n\n\n\n<p>(E) N\u00e3o respondida.<\/p>\n<\/blockquote>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><strong>(CESPE &#8211; MPS &#8211; PERITO M\u00c9DICO FEDERAL &#8211; 2024)<\/strong><strong>Os empregados com defici\u00eancia ter\u00e3o prefer\u00eancia na aloca\u00e7\u00e3o em vagas para atividades a serem efetuadas por meio do teletrabalho ou trabalho remoto, desde que comprovem, mediante relat\u00f3rio de per\u00edcia m\u00e9dica, a real necessidade de sua aloca\u00e7\u00e3o nessa modalidade de trabalho<\/strong>. [<strong>Errado<\/strong>. N\u00e3o demanda per\u00edcia nem demonstra\u00e7\u00e3o de necessidade de aloca\u00e7\u00e3o]<\/p>\n<\/blockquote>\n\n\n\n<h2 class=\"wp-block-heading has-large-font-size\" id=\"h-consideracoes-finais\">Considera\u00e7\u00f5es finais<\/h2>\n\n\n\n<p>O conte\u00fado sobre trabalho remoto \u00e9 enxuto. Cobram-se nas provas de concursos as normas do art. 75-B a 75-F. Uma leitura de menos de 15 minutos \u00e9 suficiente para exaurir o conte\u00fado dessas normas. Contudo, \u00e9 importante praticar a resolu\u00e7\u00e3o de quest\u00f5es para entender o modo como esse assunto \u00e9 exigido nas quest\u00f5es.<\/p>\n\n\n\n<p>Procure por provas antigas e utilize a plataforma de quest\u00f5es do Estrat\u00e9gia Concursos para facilitar o estudo.<\/p>\n\n\n\n<p>Gostou do texto? Deixe um coment\u00e1rio abaixo.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.instagram.com\/gabrielssantos96\">https:\/\/www.instagram.com\/gabrielssantos96<\/a><\/p>\n\n\n\n<p class=\"has-text-align-center has-white-color has-vivid-cyan-blue-background-color has-text-color has-background has-link-color wp-elements-934bee992b67b6144e8b666952a903fb\"><strong><a href=\"https:\/\/www.youtube.com\/@EstrategiaConcursosBrasil\">Canal do Estrat\u00e9gia Concursos no Youtube<\/a><\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center has-white-color has-vivid-cyan-blue-background-color has-text-color has-background has-link-color wp-elements-4ee3858d78f8e73e6a059835bfd98e6f\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\"><strong>Concursos Abertos<\/strong><\/a><\/p>\n\n\n\n<p class=\"has-text-align-center has-white-color has-vivid-cyan-blue-background-color has-text-color has-background has-link-color wp-elements-1aca1c51fe870dad71059b988ff0425d\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2025\/\"><strong>Concursos 2025<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ol\u00e1, estudantes do Direito! Preparados para mais uma sess\u00e3o de aprendizado? Neste artigo estudaremos as normas relativas ao trabalho remoto e analisaremos sua cobran\u00e7a em concursos. Para melhor compreens\u00e3o, o assunto foi dividido nos seguintes t\u00f3picos: Vamos l\u00e1! Introdu\u00e7\u00e3o A regula\u00e7\u00e3o do trabalho remoto atendeu a uma necessidade que h\u00e1 muito tempo j\u00e1 se manifestava [&hellip;]<\/p>\n","protected":false},"author":3013,"featured_media":1550240,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1],"tags":[],"tax_estado":[219963],"class_list":["post-1550237","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cursos-e-concursos","tax_estado-concursos-federais"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Trabalho remoto<\/title>\n<meta name=\"description\" content=\"Veja o conceito de trabalho remoto e aprenda como as bancas organizadoras cobram esse assunto nos concursos p\u00fablicos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/trabalho-remoto\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trabalho remoto\" \/>\n<meta property=\"og:description\" content=\"Veja o conceito de trabalho remoto e aprenda como as bancas organizadoras cobram esse assunto nos concursos p\u00fablicos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/trabalho-remoto\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-26T11:14:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/03\/22195831\/image-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"727\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gabriel Souza Santos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gabriel Souza Santos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/trabalho-remoto\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/trabalho-remoto\/\"},\"author\":{\"name\":\"Gabriel Souza Santos\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/d948c69f6dd3bbd74ea6c9f7451a93c6\"},\"headline\":\"Trabalho remoto\",\"datePublished\":\"2025-04-26T11:14:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/trabalho-remoto\/\"},\"wordCount\":1138,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/trabalho-remoto\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/03\/22195831\/image-3.jpg\",\"articleSection\":[\"Concursos P\u00fablicos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/trabalho-remoto\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/trabalho-remoto\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/trabalho-remoto\/\",\"name\":\"Trabalho remoto\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/trabalho-remoto\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/trabalho-remoto\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/03\/22195831\/image-3.jpg\",\"datePublished\":\"2025-04-26T11:14:00+00:00\",\"description\":\"Veja o conceito de trabalho remoto e aprenda como as bancas organizadoras cobram esse assunto nos concursos p\u00fablicos.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/trabalho-remoto\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/trabalho-remoto\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/trabalho-remoto\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/03\/22195831\/image-3.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/03\/22195831\/image-3.jpg\",\"width\":1024,\"height\":727,\"caption\":\"trabalho remoto\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/trabalho-remoto\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trabalho remoto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/d948c69f6dd3bbd74ea6c9f7451a93c6\",\"name\":\"Gabriel Souza Santos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/fd1003725e80f9cbb3f5083f64f112beb33dbd3bcbc7d34e628143a7cdd6cb8a?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/fd1003725e80f9cbb3f5083f64f112beb33dbd3bcbc7d34e628143a7cdd6cb8a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/fd1003725e80f9cbb3f5083f64f112beb33dbd3bcbc7d34e628143a7cdd6cb8a?s=96&d=mm&r=g\",\"caption\":\"Gabriel Souza Santos\"},\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/gabriel-s-96hotmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Trabalho remoto","description":"Veja o conceito de trabalho remoto e aprenda como as bancas organizadoras cobram esse assunto nos concursos p\u00fablicos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/trabalho-remoto\/","og_locale":"pt_BR","og_type":"article","og_title":"Trabalho remoto","og_description":"Veja o conceito de trabalho remoto e aprenda como as bancas organizadoras cobram esse assunto nos concursos p\u00fablicos.","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/trabalho-remoto\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2025-04-26T11:14:00+00:00","og_image":[{"width":1024,"height":727,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/03\/22195831\/image-3.jpg","type":"image\/jpeg"}],"author":"Gabriel Souza Santos","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Gabriel Souza Santos","Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/trabalho-remoto\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/trabalho-remoto\/"},"author":{"name":"Gabriel Souza Santos","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/d948c69f6dd3bbd74ea6c9f7451a93c6"},"headline":"Trabalho remoto","datePublished":"2025-04-26T11:14:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/trabalho-remoto\/"},"wordCount":1138,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/trabalho-remoto\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/03\/22195831\/image-3.jpg","articleSection":["Concursos P\u00fablicos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/trabalho-remoto\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/trabalho-remoto\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/trabalho-remoto\/","name":"Trabalho remoto","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/trabalho-remoto\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/trabalho-remoto\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/03\/22195831\/image-3.jpg","datePublished":"2025-04-26T11:14:00+00:00","description":"Veja o conceito de trabalho remoto e aprenda como as bancas organizadoras cobram esse assunto nos concursos p\u00fablicos.","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/trabalho-remoto\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/trabalho-remoto\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/trabalho-remoto\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/03\/22195831\/image-3.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/03\/22195831\/image-3.jpg","width":1024,"height":727,"caption":"trabalho remoto"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/trabalho-remoto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Trabalho remoto"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/d948c69f6dd3bbd74ea6c9f7451a93c6","name":"Gabriel Souza Santos","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/fd1003725e80f9cbb3f5083f64f112beb33dbd3bcbc7d34e628143a7cdd6cb8a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fd1003725e80f9cbb3f5083f64f112beb33dbd3bcbc7d34e628143a7cdd6cb8a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fd1003725e80f9cbb3f5083f64f112beb33dbd3bcbc7d34e628143a7cdd6cb8a?s=96&d=mm&r=g","caption":"Gabriel Souza Santos"},"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/gabriel-s-96hotmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1550237","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/3013"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1550237"}],"version-history":[{"count":7,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1550237\/revisions"}],"predecessor-version":[{"id":1551228,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1550237\/revisions\/1551228"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/1550240"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1550237"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1550237"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1550237"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1550237"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}