{"id":1539803,"date":"2025-04-02T14:10:00","date_gmt":"2025-04-02T17:10:00","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=1539803"},"modified":"2025-03-17T17:05:00","modified_gmt":"2025-03-17T20:05:00","slug":"teoria-erc-mpu","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/teoria-erc-mpu\/","title":{"rendered":"Teoria ERC: motiva\u00e7\u00e3o para o concurso do MPU"},"content":{"rendered":"\n<p>Neste artigo voc\u00ea encontrar\u00e1 um resumo da Teoria ERC de Alderfer, uma das principais teorias de conte\u00fado, para o concurso do Minist\u00e9rio P\u00fablico da Uni\u00e3o.<\/p>\n\n\n\n<p>Ol\u00e1, concurseiro! Tudo bem com voc\u00ea? O t\u00e3o esperado edital do concurso do <a href=\"https:\/\/www.mpu.mp.br\/\" target=\"_blank\" rel=\"noreferrer noopener\">Minist\u00e9rio P\u00fablico da Uni\u00e3o<\/a> foi finalmente publicado e chegou a hora de darmos uma acelerada nos estudos, afinal, o dia da prova est\u00e1 chegando.<\/p>\n\n\n\n<p>Desse modo, para auxiliar voc\u00ea na prepara\u00e7\u00e3o para esse concurso, elaboramos um resumo acerca Teoria ERC de Alderfer, do t\u00f3pico <strong>Motiva\u00e7\u00e3o.<\/strong><\/p>\n\n\n\n<p>Ent\u00e3o, pegue o seu marca-texto e vamos aos conceitos mais importantes e relevantes para voc\u00ea gabaritar esse assunto.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-consideracoes-iniciais\">Considera\u00e7\u00f5es Iniciais<\/h2>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"258\" height=\"180\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/03\/02111820\/tome-nota.png\" alt=\"\" class=\"wp-image-1539810\" style=\"width:212px;height:auto\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/03\/02111820\/tome-nota.png 258w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/03\/02111820\/tome-nota-150x105.png 150w\" sizes=\"auto, (max-width: 258px) 100vw, 258px\" \/><\/figure>\n\n\n\n<p>Primeiramente, \u00e9 importante trazermos a voc\u00ea alguns conceitos de <strong>motiva\u00e7\u00e3o <\/strong>que costumam cair em provas de concurso.<\/p>\n\n\n\n<p>De acordo com Robbins, <strong>motiva\u00e7\u00e3o \u00e9 a vontade de fazer algo, condicionada pela capacidade que essa a\u00e7\u00e3o tem de satisfazer alguma necessidade individual.<\/strong><\/p>\n\n\n\n<p>J\u00e1, conforme preceitua Gregory, a <strong>motiva\u00e7\u00e3o representa um conjunto de for\u00e7as que leva as pessoas a se engajarem em algum tipo de comportamento mais do que qualquer outro comportamento alternativo.<\/strong><\/p>\n\n\n\n<p>Chiavenato, por sua vez, postula que a <strong>motiva\u00e7\u00e3o funciona como o resultado da intera\u00e7\u00e3o entre o indiv\u00edduo e a situa\u00e7\u00e3o que o envolve. <\/strong>Conforme esse autor, a <strong>motiva\u00e7\u00e3o <\/strong>est\u00e1 relacionada a tr\u00eas aspectos b\u00e1sicos:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Dire\u00e7\u00e3o: <\/strong>\u00e9 a dire\u00e7\u00e3o do comportamento (do esfor\u00e7o), no sentido de atingir determinado <strong>objetivo<\/strong>. O esfor\u00e7o deve ser direcionado para o alcance de algum objetivo. Ou seja, refere-se ao objetivo que se quer alcan\u00e7ar. Indica onde focar o comportamento (esfor\u00e7o).<\/li>\n\n\n\n<li><strong>Intensidade: <\/strong>refere-se \u00e0 <strong>for\u00e7a <\/strong>e \u00e0 <strong>intensidade <\/strong>do comportamento (do esfor\u00e7o). Isto \u00e9, representa o <strong>tamanho do esfor\u00e7o<\/strong> que a pessoa emprega para o alcance do objetivo.<\/li>\n\n\n\n<li><strong>Persist\u00eancia: <\/strong>\u00e9 a <strong>dura\u00e7\u00e3o <\/strong>e <strong>persist\u00eancia <\/strong>(ou <strong>perman\u00eancia) <\/strong>do comportamento (do esfor\u00e7o). Trata-se da dura\u00e7\u00e3o de tempo que a pessoa mant\u00e9m seu esfor\u00e7o em dire\u00e7\u00e3o ao objetivo proposto. Ou seja, significa <strong>por quanto tempo a pessoa consegue manter seu esfor\u00e7o<\/strong>.<\/li>\n<\/ul>\n\n\n\n<p>Veja a imagem abaixo retirada do PDF do <a href=\"https:\/\/www.estrategiaconcursos.com.br\/\" target=\"_blank\" rel=\"noreferrer noopener\">Estrat\u00e9gia Concursos<\/a>.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"474\" height=\"399\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/03\/02110932\/motivacao.png\" alt=\"Motiva\u00e7\u00e3o\" class=\"wp-image-1539805\" style=\"width:388px;height:auto\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/03\/02110932\/motivacao.png 474w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/03\/02110932\/motivacao-300x253.png 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/03\/02110932\/motivacao-150x126.png 150w\" sizes=\"auto, (max-width: 474px) 100vw, 474px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-teorias-da-motivacao\">Teorias da motiva\u00e7\u00e3o<\/h2>\n\n\n\n<p>Primeiramente, vale ressaltar que diversos autores e estudiosos buscaram explicar como a motiva\u00e7\u00e3o ocorre. Desse modo, surgiram diversas teorias motivacionais.<\/p>\n\n\n\n<p>Ademais, \u00e9 necess\u00e1rio enfatizar que as teorias da motiva\u00e7\u00e3o se dividem em <strong>teorias de conte\u00fado <\/strong>e <strong>teorias de processo.<\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-teorias-de-conteudo\">Teorias de conte\u00fado<\/h3>\n\n\n\n<p>Conforme a literatura, as <strong>teorias de conte\u00fado<\/strong> buscam explicar \u201c<strong>o que\u201d <\/strong>motiva o indiv\u00edduo. Ou seja, essas teorias partem do princ\u00edpio de que os indiv\u00edduos agem para satisfazer seus <strong>interesses <\/strong>e <strong>necessidades. <\/strong>Portanto, as teorias de conte\u00fado se preocupam com <strong>necessidades espec\u00edficas<\/strong> que <strong>motivam<\/strong> e <strong>impulsionam<\/strong> os indiv\u00edduos a agirem.<\/p>\n\n\n\n<p>As teorias de conte\u00fado s\u00e3o as seguintes:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Teoria da Hierarquia das Necessidades (Maslow);<\/li>\n\n\n\n<li><strong>Teoria ERC (ou ERG) de Alderfer;<\/strong><\/li>\n\n\n\n<li>Teoria dos Dois fatores ou bifatorial de Herzberg;<\/li>\n\n\n\n<li>Teoria das Necessidades Adquiridas de McClelland;<\/li>\n\n\n\n<li>Teoria X e Y de Mc Gregor.<\/li>\n<\/ul>\n\n\n\n<p>Falaremos aqui da <strong>Teoria ERC (ou ERG) de Alderfer.<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-teoria-erc-de-alderfer\">Teoria ERC de Alderfer<\/h2>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"268\" height=\"183\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/03\/02111908\/se-liga.png\" alt=\"\" class=\"wp-image-1539811\" style=\"width:236px;height:auto\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/03\/02111908\/se-liga.png 268w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/03\/02111908\/se-liga-150x102.png 150w\" sizes=\"auto, (max-width: 268px) 100vw, 268px\" \/><\/figure>\n\n\n\n<p>A teoria ERC (<strong>Exist\u00eancia-Relacionamento-Crescimento)<\/strong>, desenvolvida por Alderfer, pode ser considerada uma <strong>adapta\u00e7\u00e3o da Teoria da Hierarquia das Necessidades de Maslow<\/strong>.<\/p>\n\n\n\n<p>&nbsp;A primeira diferen\u00e7a \u00e9 que Alderfer \u201ccondensou\u201d as necessidades (os n\u00edveis hier\u00e1rquicos) em 3 categorias:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Necessidades de <strong>E<\/strong>xist\u00eancia;<\/li>\n\n\n\n<li>Necessidades de <strong>R<\/strong>elacionamento;<\/li>\n\n\n\n<li>Necessidades de <strong>C<\/strong>rescimento.<\/li>\n<\/ol>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-as-necessidades-conforme-alderfer\">As necessidades conforme Alderfer<\/h3>\n\n\n\n<p>Vejamos cada uma das necessidades, conforme preceitua Alderfer:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Necessidades de exist\u00eancia: <\/strong>correspondem aos <strong>2 primeiros n\u00edveis da Hierarquia de Maslow<\/strong>. Trata-se das necessidades de <strong>sobreviv\u00eancia<\/strong>, <strong>exist\u00eancia<\/strong>, <strong>preserva\u00e7\u00e3o<\/strong> e <strong>bem-estar f\u00edsico<\/strong>.<\/li>\n\n\n\n<li><strong>Necessidades de Relacionamento:<\/strong> correspondem \u00e0s <strong>necessidades sociais de Maslow<\/strong> e aos <strong>fatores externos das necessidades de estima de Maslow<\/strong>. Trata-se das <strong>rela\u00e7\u00f5es interpessoais<\/strong>, da <strong>sociabilidade<\/strong>, etc.<\/li>\n\n\n\n<li><strong>Necessidades de Crescimento:<\/strong> correspondem \u00e0s <strong>necessidades de autorrealiza\u00e7\u00e3o de Maslow<\/strong> e aos <strong>fatores internos das necessidades de estima<\/strong>. Trata-se das <strong>necessidades de desenvolvimento<\/strong> e do <strong>desejo de crescimento do ser humano<\/strong>.<\/li>\n<\/ul>\n\n\n\n<p>Veja a imagem abaixo retirada do PDF do <a href=\"https:\/\/www.estrategiaconcursos.com.br\/\" target=\"_blank\" rel=\"noreferrer noopener\">Estrat\u00e9gia Concursos<\/a>.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"452\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/03\/02113557\/teoria-erc-1024x452.png\" alt=\"Teoria ERC\" class=\"wp-image-1539812\" style=\"width:759px;height:auto\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/03\/02113557\/teoria-erc-1024x452.png 1024w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/03\/02113557\/teoria-erc-300x132.png 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/03\/02113557\/teoria-erc-768x339.png 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/03\/02113557\/teoria-erc-150x66.png 150w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/03\/02113557\/teoria-erc.png 1101w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Outra diferen\u00e7a importante da Teoria de Maslow \u00e9 que, para Alderfer, as necessidades podem ser buscadas simultaneamente. Ou seja, as necessidades podem ser \u201cativadas\u201d ao mesmo tempo. Desse modo, n\u00e3o \u00e9 necess\u00e1rio que uma necessidade de um n\u00edvel anterior seja satisfeita para que se busque uma necessidade de um n\u00edvel posterior.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-principio-de-frustracao-regressao\">Princ\u00edpio de \u201cFrustra\u00e7\u00e3o-Regress\u00e3o\u201d<\/h3>\n\n\n\n<p>Conforme a <strong>Teoria ERC<\/strong>, uma outra diferen\u00e7a importante entre esta e a teoria da Hierarquia das Necessidades de Maslow \u00e9 que, para Maslow, o progresso de um indiv\u00edduo na hierarquia \u00e9 o resultado da satisfa\u00e7\u00e3o de alguma necessidade menos elevada (ou seja, a satisfa\u00e7\u00e3o de uma necessidade referente a um n\u00edvel imediatamente anterior).<\/p>\n\n\n\n<p>Para Alderfer, entretanto, a Teoria ERC adota o princ\u00edpio da <strong>\u201cfrustra\u00e7\u00e3o-regress\u00e3o\u201d<\/strong>, segundo o qual <strong>uma necessidade menos elevada pode ser ativada quando uma necessidade mais elevada n\u00e3o pode ser satisfeita.<\/strong><\/p>\n\n\n\n<p>Desse modo, a Teoria ERC postula que, <strong>se uma necessidade de n\u00edvel mais elevado for reprimida (ou seja, n\u00e3o for satisfeita), a vontade do indiv\u00edduo em satisfazer uma necessidade de n\u00edvel menos elevado tende a aumentar.<\/strong><\/p>\n\n\n\n<p>Veja abaixo a figura retirada do PDF do <a href=\"https:\/\/www.estrategiaconcursos.com.br\/cursosPorConcurso\/sistema-de-questoes\/\" target=\"_blank\" rel=\"noreferrer noopener\">Estrat\u00e9gia Concursos<\/a> que ilustra o Princ\u00edpio de Frustra\u00e7\u00e3o-Regress\u00e3o proposto por Alderfer e a Teoria ERC.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"432\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/03\/02113808\/frustracao-regressao-1-1024x432.png\" alt=\"Princ\u00edpio da Frustra\u00e7\u00e3o Regress\u00e3o\" class=\"wp-image-1539813\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/03\/02113808\/frustracao-regressao-1-1024x432.png 1024w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/03\/02113808\/frustracao-regressao-1-300x126.png 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/03\/02113808\/frustracao-regressao-1-768x324.png 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/03\/02113808\/frustracao-regressao-1-150x63.png 150w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/03\/02113808\/frustracao-regressao-1.png 1117w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-para-finalizar\">Para finalizar<\/h2>\n\n\n\n<p>Por fim, saiba que o objetivo deste artigo foi trazer para voc\u00ea pontos importantes acerca do tema <strong>Motiva\u00e7\u00e3o <\/strong>para o concurso do Minist\u00e9rio P\u00fablico da Uni\u00e3o. No entanto, para al\u00e9m desse certame, esse tema \u00e9 extremamente relevante para provas de concurso em geral.&nbsp;<\/p>\n\n\n\n<p>Outrossim, este resumo n\u00e3o abrange toda a complexidade do tema Motiva\u00e7\u00e3o, mas, certamente, nele voc\u00ea encontrar\u00e1 aspectos importantes que ajudar\u00e3o voc\u00ea a gabaritar quest\u00f5es sobre esse assunto.&nbsp;<\/p>\n\n\n\n<p>Al\u00e9m disso, para a sua prepara\u00e7\u00e3o, n\u00e3o deixe de responder muitas quest\u00f5es. Para auxiliar voc\u00ea nessa miss\u00e3o, o <a href=\"https:\/\/www.estrategiaconcursos.com.br\/\" target=\"_blank\" rel=\"noreferrer noopener\">Estrat\u00e9gia Concursos<\/a> oferece um sistema de quest\u00f5es bastante completo que certamente ajudar\u00e1 voc\u00ea na conquista da t\u00e3o sonhada vaga no servi\u00e7o p\u00fablico.\u00a0<\/p>\n\n\n\n<p>Finalmente, n\u00e3o deixe de acompanhar e ficar por dentro do que acontece no mundo dos concursos.&nbsp;<\/p>\n\n\n\n<p>Bons estudos e at\u00e9 mais!&nbsp;<\/p>\n\n\n\n<p class=\"has-text-align-center has-pale-cyan-blue-background-color has-background\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos abertos<\/a>&nbsp;<\/p>\n\n\n\n<p class=\"has-text-align-center has-pale-cyan-blue-background-color has-background\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2025\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos 2025<\/a>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Neste artigo voc\u00ea encontrar\u00e1 um resumo da Teoria ERC de Alderfer, uma das principais teorias de conte\u00fado, para o concurso do Minist\u00e9rio P\u00fablico da Uni\u00e3o. Ol\u00e1, concurseiro! Tudo bem com voc\u00ea? O t\u00e3o esperado edital do concurso do Minist\u00e9rio P\u00fablico da Uni\u00e3o foi finalmente publicado e chegou a hora de darmos uma acelerada nos estudos, [&hellip;]<\/p>\n","protected":false},"author":2982,"featured_media":1513821,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1],"tags":[],"tax_estado":[219963],"class_list":["post-1539803","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cursos-e-concursos","tax_estado-concursos-federais"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Teoria ERC: motiva\u00e7\u00e3o para o concurso do MPU<\/title>\n<meta name=\"description\" content=\"Resumo da Teoria ERC de Alderfer, uma das principais teorias de conte\u00fado, para o concurso do Minist\u00e9rio P\u00fablico da Uni\u00e3o.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/teoria-erc-mpu\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Teoria ERC: motiva\u00e7\u00e3o para o concurso do MPU\" \/>\n<meta property=\"og:description\" content=\"Resumo da Teoria ERC de Alderfer, uma das principais teorias de conte\u00fado, para o concurso do Minist\u00e9rio P\u00fablico da Uni\u00e3o.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/teoria-erc-mpu\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-02T17:10:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/01\/08091451\/mpu.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"990\" \/>\n\t<meta property=\"og:image:height\" content=\"774\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Caroline Martins da Costa Leite\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Caroline Martins da Costa Leite\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/teoria-erc-mpu\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/teoria-erc-mpu\/\"},\"author\":{\"name\":\"Caroline Martins da Costa Leite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/1c7ac186f04b04e87eeba66c2467cf6a\"},\"headline\":\"Teoria ERC: motiva\u00e7\u00e3o para o concurso do MPU\",\"datePublished\":\"2025-04-02T17:10:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/teoria-erc-mpu\/\"},\"wordCount\":1069,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/teoria-erc-mpu\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/01\/08091451\/mpu.jpg\",\"articleSection\":[\"Concursos P\u00fablicos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/teoria-erc-mpu\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/teoria-erc-mpu\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/teoria-erc-mpu\/\",\"name\":\"Teoria ERC: motiva\u00e7\u00e3o para o concurso do MPU\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/teoria-erc-mpu\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/teoria-erc-mpu\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/01\/08091451\/mpu.jpg\",\"datePublished\":\"2025-04-02T17:10:00+00:00\",\"description\":\"Resumo da Teoria ERC de Alderfer, uma das principais teorias de conte\u00fado, para o concurso do Minist\u00e9rio P\u00fablico da Uni\u00e3o.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/teoria-erc-mpu\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/teoria-erc-mpu\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/teoria-erc-mpu\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/01\/08091451\/mpu.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/01\/08091451\/mpu.jpg\",\"width\":990,\"height\":774,\"caption\":\"aten\u00e7\u00e3o\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/teoria-erc-mpu\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Teoria ERC: motiva\u00e7\u00e3o para o concurso do MPU\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/1c7ac186f04b04e87eeba66c2467cf6a\",\"name\":\"Caroline Martins da Costa Leite\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/061997e69e4fd91b5e3d45dff736c5f05b3c02a4283b46708faf52b75701224e?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/061997e69e4fd91b5e3d45dff736c5f05b3c02a4283b46708faf52b75701224e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/061997e69e4fd91b5e3d45dff736c5f05b3c02a4283b46708faf52b75701224e?s=96&d=mm&r=g\",\"caption\":\"Caroline Martins da Costa Leite\"},\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/carol_leite1706hotmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Teoria ERC: motiva\u00e7\u00e3o para o concurso do MPU","description":"Resumo da Teoria ERC de Alderfer, uma das principais teorias de conte\u00fado, para o concurso do Minist\u00e9rio P\u00fablico da Uni\u00e3o.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/teoria-erc-mpu\/","og_locale":"pt_BR","og_type":"article","og_title":"Teoria ERC: motiva\u00e7\u00e3o para o concurso do MPU","og_description":"Resumo da Teoria ERC de Alderfer, uma das principais teorias de conte\u00fado, para o concurso do Minist\u00e9rio P\u00fablico da Uni\u00e3o.","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/teoria-erc-mpu\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2025-04-02T17:10:00+00:00","og_image":[{"width":990,"height":774,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/01\/08091451\/mpu.jpg","type":"image\/jpeg"}],"author":"Caroline Martins da Costa Leite","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Caroline Martins da Costa Leite","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/teoria-erc-mpu\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/teoria-erc-mpu\/"},"author":{"name":"Caroline Martins da Costa Leite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/1c7ac186f04b04e87eeba66c2467cf6a"},"headline":"Teoria ERC: motiva\u00e7\u00e3o para o concurso do MPU","datePublished":"2025-04-02T17:10:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/teoria-erc-mpu\/"},"wordCount":1069,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/teoria-erc-mpu\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/01\/08091451\/mpu.jpg","articleSection":["Concursos P\u00fablicos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/teoria-erc-mpu\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/teoria-erc-mpu\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/teoria-erc-mpu\/","name":"Teoria ERC: motiva\u00e7\u00e3o para o concurso do MPU","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/teoria-erc-mpu\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/teoria-erc-mpu\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/01\/08091451\/mpu.jpg","datePublished":"2025-04-02T17:10:00+00:00","description":"Resumo da Teoria ERC de Alderfer, uma das principais teorias de conte\u00fado, para o concurso do Minist\u00e9rio P\u00fablico da Uni\u00e3o.","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/teoria-erc-mpu\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/teoria-erc-mpu\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/teoria-erc-mpu\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/01\/08091451\/mpu.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/01\/08091451\/mpu.jpg","width":990,"height":774,"caption":"aten\u00e7\u00e3o"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/teoria-erc-mpu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Teoria ERC: motiva\u00e7\u00e3o para o concurso do MPU"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/1c7ac186f04b04e87eeba66c2467cf6a","name":"Caroline Martins da Costa Leite","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/061997e69e4fd91b5e3d45dff736c5f05b3c02a4283b46708faf52b75701224e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/061997e69e4fd91b5e3d45dff736c5f05b3c02a4283b46708faf52b75701224e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/061997e69e4fd91b5e3d45dff736c5f05b3c02a4283b46708faf52b75701224e?s=96&d=mm&r=g","caption":"Caroline Martins da Costa Leite"},"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/carol_leite1706hotmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1539803","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/2982"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1539803"}],"version-history":[{"count":4,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1539803\/revisions"}],"predecessor-version":[{"id":1539814,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1539803\/revisions\/1539814"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/1513821"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1539803"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1539803"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1539803"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1539803"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}