{"id":1536963,"date":"2025-04-16T15:03:42","date_gmt":"2025-04-16T18:03:42","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=1536963"},"modified":"2025-04-16T18:48:32","modified_gmt":"2025-04-16T21:48:32","slug":"cadernos-de-questoes-ineditas-do-concurso-mpu","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/cadernos-de-questoes-ineditas-do-concurso-mpu\/","title":{"rendered":"Cadernos de quest\u00f5es in\u00e9ditas do concurso MPU"},"content":{"rendered":"<a id=\"cta-icon\" href=\"https:\/\/www.redirectmais.com\/wpp\/mpu-grupo\" target=\"blank\" style=\"background:rgb(41,166,26)\">\n            <img decoding=\"async\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/01\/03154041\/whatsapp_13851.png\" alt=\"\" alt=\"whatsapp_13851\"><span > Acesse agora o Grupo de Estudos para o Concurso MPU<\/span><\/a>\n\n\n\n<p class=\"has-luminous-vivid-amber-background-color has-background\"><em><strong>Cadernos de Quest\u00f5es para o concurso MPU &#8211; Minist\u00e9rio P\u00fablico da Uni\u00e3o:<\/strong>&nbsp;resolva quest\u00f5es sobre o conte\u00fado do edital do MPU e eleve sua prepara\u00e7\u00e3o a outro patamar.<\/em><\/p>\n\n\n\n<p>Ol\u00e1, Estrategista!<\/p>\n\n\n\n<p>S\u00e3o ofertadas<strong>&nbsp;172&nbsp;vagas<\/strong>&nbsp;para os cargos de&nbsp;<strong>t\u00e9cnico e analisa<\/strong>, ambos de n\u00edvel superior. As oportunidades oferecem iniciais que variam de&nbsp;<strong>R$ 8.529,67 a R$ 13.994,80*, al\u00e9m de benef\u00edcios.<\/strong><\/p>\n\n\n\n<p>Cabe destacar que j\u00e1 est\u00e3o em vigor as novas remunera\u00e7\u00f5es iniciais&nbsp;do <a href=\"https:\/\/www.estrategiaconcursos.com.br\/cursosPorConcurso\/mpu-ministerio-publico-da-uniao\/\" target=\"_blank\" rel=\"noreferrer noopener\">Minist\u00e9rio P\u00fablico da Uni\u00e3o<\/a>, que variam de&nbsp;<strong>R$ 9.052,54 at\u00e9 R$ 14.852,98,&nbsp;<\/strong>al\u00e9m de benef\u00edcios que possibilitam uma remunera\u00e7\u00e3o de at\u00e9 R$ 17 mil.<\/p>\n\n\n\n<p><strong><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-mpu\/\">Veja aqui todos os detalhes do concurso!<\/a><\/strong><\/p>\n\n\n\n<p>Para se destacar da concorr\u00eancia, \u00e9 preciso ter foco total. J\u00e1 sabemos que a&nbsp;<strong>resolu\u00e7\u00e3o de quest\u00f5es \u00e9 de extrema import\u00e2ncia durante a prepara\u00e7\u00e3o<\/strong>&nbsp;para uma prova, facilitando o estudo das disciplinas e otimizando a memoriza\u00e7\u00e3o dos principais pontos pass\u00edveis de serem cobrados pelas bancas examinadoras.<\/p>\n\n\n\n<p>Pensando nisso, a equipe do Sistema de Quest\u00f5es do Estrat\u00e9gia Concursos preparou diversas quest\u00f5es para te auxiliar no estudo e fixa\u00e7\u00e3o do conte\u00fado do concurso MPU.<\/p>\n\n\n\n<p>Teremos quest\u00f5es in\u00e9ditas acerca da Legisla\u00e7\u00e3o cobrada no certame.&nbsp;<em>Confira abaixo os cadernos dispon\u00edveis e turbine sua prepara\u00e7\u00e3o!<\/em><\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center has-background\" id=\"h-cadernos-de-questoes-ineditas-do-concurso-mpu\" style=\"background-color:#abb7c285\">Cadernos de quest\u00f5es in\u00e9ditas do concurso MPU<\/h2>\n\n\n\n<p><strong>Conhecimentos b\u00e1sicos:<\/strong><\/p>\n\n\n\n<p><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/db0145c1-20e7-4a8d-ab14-5dfe6835be0d\/\">Pol\u00edtica Nacional sobre Mudan\u00e7as do Clima (Lei n\u00ba 12.187\/2009)<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/65c427b9-f2dc-47c6-b8ef-7cfa4c782869\/\">Pol\u00edtica Nacional de Res\u00edduos S\u00f3lidos (Lei n\u00ba 12.305\/2010 e suas altera\u00e7\u00f5es e Decreto n\u00ba 10.936\/2022)<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/d0fa4c6a-e941-476c-8f44-d4627f4ad116?page=3\">Lei de Crimes Ambientais (Lei n\u00ba 9.605\/1998 e suas altera\u00e7\u00f5es)<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/0894e873-1b0d-4a17-9a11-d09a176ef890\/\">Sistema Nacional de Unidades de Conserva\u00e7\u00e3o da Natureza (Lei n\u00ba 9.985\/2000 e suas altera\u00e7\u00f5es)<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/53586248-2121-471b-973e-5c8787b9756c\">Estatuto de igualdade racial (Lei n\u00ba 12.288\/2010 e suas altera\u00e7\u00f5es)<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/91fb4627-a41d-4b1e-86ed-4abd4d4146b7\/?page=1&amp;per_page=undefined\">Lei Brasileira de Inclus\u00e3o da Pessoa com Defici\u00eancia \u2013 Estatuto da Pessoa com Defici\u00eancia (Lei n\u00ba 13.146\/2015 e suas altera\u00e7\u00f5es)<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/9aefdb8d-a065-496c-ad6a-e8856d9501b5\/?page=1&amp;per_page=undefined\">Normas gerais e crit\u00e9rios b\u00e1sicos para a promo\u00e7\u00e3o da acessibilidade das pessoas com defici\u00eancia ou com mobilidade reduzida (Lei n\u00ba 10.098\/2000 e suas altera\u00e7\u00f5es)<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/1f4e0f9e-ba5b-4a97-91a6-7660b3b7a240\/?page=1&amp;per_page=undefined\">Prioridade de atendimento \u00e0s pessoas com defici\u00eancia (Lei n\u00ba 10.048\/2000 e suas altera\u00e7\u00f5es)<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/0737458c-d8b5-4cca-9a0a-0fa47ef8572c\">Lei n\u00ba 12.527\/2011 e suas altera\u00e7\u00f5es (Lei de Acesso \u00e0 Informa\u00e7\u00e3o)<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/320a88c7-0dee-4058-8490-f4ddc5b77993\">Lei n\u00ba 13.709\/2018 e suas altera\u00e7\u00f5es (Lei Geral de Prote\u00e7\u00e3o de Dados Pessoais \u2013 LGPD)<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/d18b53b6-3908-46aa-91a7-070edf1e9a42?page=1&amp;per_page=undefined&amp;sort=key_pedagogical_order&amp;order=ASC\">Resolu\u00e7\u00e3o CNMP n\u00ba 276\/2023 \u2013 Disp\u00f5e sobre a Pol\u00edtica Nacional do Minist\u00e9rio P\u00fablico Digital \u2013 MP Digital:<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/7bc25739-7bef-4d63-a80c-7be1756d6829?page=1&amp;per_page=undefined&amp;sort=key_pedagogical_order&amp;order=ASC\">Lei n\u00ba 13.316\/2016 e suas altera\u00e7\u00f5es:<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/4dca985c-1176-4c7c-bdd5-8f15bf311e62?page=1&amp;per_page=undefined&amp;sort=key_pedagogical_order&amp;order=ASC\">Portaria PGR\/MPU n\u00ba 247\/2023 (Programa de Integridade do Minist\u00e9rio P\u00fablico da Uni\u00e3o):<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/041ca43a-ea40-4523-acbb-93883731f3b2?page=1&amp;per_page=undefined&amp;sort=key_pedagogical_order&amp;order=ASC\">Pacto de S\u00e3o Jos\u00e9 da Costa Rica e Decreto n\u00ba 678\/1992 (Conven\u00e7\u00e3o Americana sobre Direitos Humanos):<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/d18b53b6-3908-46aa-91a7-070edf1e9a42?page=1&amp;per_page=undefined&amp;sort=key_pedagogical_order&amp;order=ASC\">Resolu\u00e7\u00e3o CNMP n\u00ba 276\/2023 \u2013 Disp\u00f5e sobre a Pol\u00edtica Nacional do Minist\u00e9rio P\u00fablico Digital \u2013 MP Digital:<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/c14481d4-cddf-461b-a638-ab4db1185471?page=1&amp;per_page=undefined&amp;order=ASC&amp;sort=order_index\">Lei Complementar n\u00ba 75\/1993:<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/7bc25739-7bef-4d63-a80c-7be1756d6829?page=1&amp;per_page=undefined&amp;sort=key_pedagogical_order&amp;order=ASC\">Lei n\u00ba 13.316\/2016 e suas altera\u00e7\u00f5es:<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/d74f6a2f-15c6-44dd-8703-8522c7f4af53?page=1&amp;per_page=undefined&amp;sort=key_pedagogical_order&amp;order=ASC\">Portaria PGR\/MPU n\u00ba 98\/2017 (C\u00f3digo de \u00c9tica e de Conduta do MPU e da ESMPU):<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/4dca985c-1176-4c7c-bdd5-8f15bf311e62?page=1&amp;per_page=undefined&amp;sort=key_pedagogical_order&amp;order=ASC\">Portaria PGR\/MPU n\u00ba 247\/2023 (Programa de Integridade do Minist\u00e9rio P\u00fablico da Uni\u00e3o):<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-torne-se-assinante-do-estrategia\">Torne-se assinante do Estrat\u00e9gia!<\/h2>\n\n\n\n<p><strong>Resolva muitas quest\u00f5es in\u00e9ditas e saia na frente do seu concorrente<\/strong>. N\u00c3O PERCA MAIS TEMPO!<\/p>\n\n\n\n<p><em>Confira abaixo os nossos planos:<\/em><\/p>\n\n\n\n<p class=\"has-text-align-center has-light-green-cyan-background-color has-background\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/cursosPorConcurso\/sistema-de-questoes\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Assinatura do Sistema de Quest\u00f5es<\/strong><\/a><\/p>\n\n\n\n<p class=\"has-text-align-center has-pale-cyan-blue-background-color has-background\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/assinaturas\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Assinaturas do Estrat\u00e9gia Concursos<\/strong><\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"h-quer-saber-tudo-sobre-concursos-previstos-confira-nossos-artigos\">Quer saber tudo sobre concursos previstos?<br \/>Confira nossos artigos!<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos abertos<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-tribunais\/\">Concursos tribunais<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2025\/\">Concursos 2025<\/a><\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"assinatura-e-cursos\">Cursos para o concurso MPU<\/h2>\n\n\n\n<p class=\"has-text-align-left\">Gostou desta oportunidade e deseja come\u00e7ar se preparar agora mesmo? Ent\u00e3o, confira os nossos cursos e <strong>comece agora a estudar para o MPU<\/strong>:<\/p>\n\n\n\n<div class=\"container\" id=\"boxes\">\n  <div class=\"row\">\n\n    <div class=\"col-sm\">\n      <div class=\"banner-mpu-ec\" id=\"box-assinatura\">\n        <h2 class=\"titulo-assinatura\">Curso para o MPU<\/h2>\n        <p class=\"subtitulo-assinatura\">Prepare-se para o Concurso MPU com o Estrat\u00e9gia!<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/cursosPorConcurso\/mpu-ministerio-publico-da-uniao\/\" role=\"button\" rel=\"noopener noreferrer\">VER CURSOS<\/a>\n        <\/div>\n      <\/div>\n      <p class=\"texto-auxiliar\">Prepare-se com o melhor material e com quem mais aprova em Concursos P\u00fablicos em todo o pa\u00eds.<\/p>\n    <\/div>\n\n  <\/div>\n<\/div>\n\n\n\n<div class=\"container\" id=\"boxes\">\n  <div class=\"row\">\n\n    <div class=\"col-sm\">\n      <div class=\"estrategia\" id=\"box-assinatura\">\n        <h3 class=\"titulo-assinatura\">Assinatura Concursos<\/h3>\n        <p class=\"subtitulo-assinatura\">Assinatura de 1 ano ou 2 anos<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/assinaturas\/\" role=\"button\" rel=\"noopener noreferrer\">ASSINE AGORA<\/a>\n        <\/div>\n      <\/div>\n     \n    <\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Cadernos de Quest\u00f5es para o concurso MPU &#8211; Minist\u00e9rio P\u00fablico da Uni\u00e3o:&nbsp;resolva quest\u00f5es sobre o conte\u00fado do edital do MPU e eleve sua prepara\u00e7\u00e3o a outro patamar. Ol\u00e1, Estrategista! S\u00e3o ofertadas&nbsp;172&nbsp;vagas&nbsp;para os cargos de&nbsp;t\u00e9cnico e analisa, ambos de n\u00edvel superior. As oportunidades oferecem iniciais que variam de&nbsp;R$ 8.529,67 a R$ 13.994,80*, al\u00e9m de benef\u00edcios. Cabe [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":846824,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"news_page","footnotes":""},"categories":[1984,220737],"tags":[],"tax_estado":[219963],"class_list":["post-1536963","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tribunais","category-tribunais-tribunais","tax_estado-concursos-federais"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Cadernos de quest\u00f5es in\u00e9ditas do concurso MPU<\/title>\n<meta name=\"description\" content=\"Cadernos de Quest\u00f5es para o concurso MPU:\u00a0resolva quest\u00f5es sobre o conte\u00fado do edital e saia na frente. Confira!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/cadernos-de-questoes-ineditas-do-concurso-mpu\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cadernos de quest\u00f5es in\u00e9ditas do concurso MPU\" \/>\n<meta property=\"og:description\" content=\"Cadernos de Quest\u00f5es para o concurso MPU:\u00a0resolva quest\u00f5es sobre o conte\u00fado do edital e saia na frente. Confira!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/cadernos-de-questoes-ineditas-do-concurso-mpu\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/EstrategiaConcursos\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-16T18:03:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-16T21:48:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/08\/27001830\/mpu.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"432\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Coordena\u00e7\u00e3o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Coordena\u00e7\u00e3o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/cadernos-de-questoes-ineditas-do-concurso-mpu\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/cadernos-de-questoes-ineditas-do-concurso-mpu\/\"},\"author\":{\"name\":\"Coordena\u00e7\u00e3o\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/b4a388c97673c5f483d72185668afa1f\"},\"headline\":\"Cadernos de quest\u00f5es in\u00e9ditas do concurso MPU\",\"datePublished\":\"2025-04-16T18:03:42+00:00\",\"dateModified\":\"2025-04-16T21:48:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/cadernos-de-questoes-ineditas-do-concurso-mpu\/\"},\"wordCount\":652,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/cadernos-de-questoes-ineditas-do-concurso-mpu\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/08\/27001830\/mpu.jpeg\",\"articleSection\":[\"Tribunais\",\"Tribunais\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/cadernos-de-questoes-ineditas-do-concurso-mpu\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/cadernos-de-questoes-ineditas-do-concurso-mpu\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/cadernos-de-questoes-ineditas-do-concurso-mpu\/\",\"name\":\"Cadernos de quest\u00f5es in\u00e9ditas do concurso MPU\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/cadernos-de-questoes-ineditas-do-concurso-mpu\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/cadernos-de-questoes-ineditas-do-concurso-mpu\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/08\/27001830\/mpu.jpeg\",\"datePublished\":\"2025-04-16T18:03:42+00:00\",\"dateModified\":\"2025-04-16T21:48:32+00:00\",\"description\":\"Cadernos de Quest\u00f5es para o concurso MPU:\u00a0resolva quest\u00f5es sobre o conte\u00fado do edital e saia na frente. Confira!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/cadernos-de-questoes-ineditas-do-concurso-mpu\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/cadernos-de-questoes-ineditas-do-concurso-mpu\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/cadernos-de-questoes-ineditas-do-concurso-mpu\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/08\/27001830\/mpu.jpeg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/08\/27001830\/mpu.jpeg\",\"width\":768,\"height\":432,\"caption\":\"Concurso Analista do MPU - Direito\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/cadernos-de-questoes-ineditas-do-concurso-mpu\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cadernos de quest\u00f5es in\u00e9ditas do concurso MPU\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/b4a388c97673c5f483d72185668afa1f\",\"name\":\"Coordena\u00e7\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g\",\"caption\":\"Coordena\u00e7\u00e3o\"},\"sameAs\":[\"https:\/\/www.facebook.com\/EstrategiaConcursos\",\"https:\/\/x.com\/EstratConcursos\"],\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/estrategia2013\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Cadernos de quest\u00f5es in\u00e9ditas do concurso MPU","description":"Cadernos de Quest\u00f5es para o concurso MPU:\u00a0resolva quest\u00f5es sobre o conte\u00fado do edital e saia na frente. Confira!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/cadernos-de-questoes-ineditas-do-concurso-mpu\/","og_locale":"pt_BR","og_type":"article","og_title":"Cadernos de quest\u00f5es in\u00e9ditas do concurso MPU","og_description":"Cadernos de Quest\u00f5es para o concurso MPU:\u00a0resolva quest\u00f5es sobre o conte\u00fado do edital e saia na frente. Confira!","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/cadernos-de-questoes-ineditas-do-concurso-mpu\/","og_site_name":"Estrat\u00e9gia Concursos","article_author":"https:\/\/www.facebook.com\/EstrategiaConcursos","article_published_time":"2025-04-16T18:03:42+00:00","article_modified_time":"2025-04-16T21:48:32+00:00","og_image":[{"width":768,"height":432,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/08\/27001830\/mpu.jpeg","type":"image\/jpeg"}],"author":"Coordena\u00e7\u00e3o","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Coordena\u00e7\u00e3o","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/cadernos-de-questoes-ineditas-do-concurso-mpu\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/cadernos-de-questoes-ineditas-do-concurso-mpu\/"},"author":{"name":"Coordena\u00e7\u00e3o","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/b4a388c97673c5f483d72185668afa1f"},"headline":"Cadernos de quest\u00f5es in\u00e9ditas do concurso MPU","datePublished":"2025-04-16T18:03:42+00:00","dateModified":"2025-04-16T21:48:32+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/cadernos-de-questoes-ineditas-do-concurso-mpu\/"},"wordCount":652,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/cadernos-de-questoes-ineditas-do-concurso-mpu\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/08\/27001830\/mpu.jpeg","articleSection":["Tribunais","Tribunais"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/cadernos-de-questoes-ineditas-do-concurso-mpu\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/cadernos-de-questoes-ineditas-do-concurso-mpu\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/cadernos-de-questoes-ineditas-do-concurso-mpu\/","name":"Cadernos de quest\u00f5es in\u00e9ditas do concurso MPU","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/cadernos-de-questoes-ineditas-do-concurso-mpu\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/cadernos-de-questoes-ineditas-do-concurso-mpu\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/08\/27001830\/mpu.jpeg","datePublished":"2025-04-16T18:03:42+00:00","dateModified":"2025-04-16T21:48:32+00:00","description":"Cadernos de Quest\u00f5es para o concurso MPU:\u00a0resolva quest\u00f5es sobre o conte\u00fado do edital e saia na frente. Confira!","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/cadernos-de-questoes-ineditas-do-concurso-mpu\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/cadernos-de-questoes-ineditas-do-concurso-mpu\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/cadernos-de-questoes-ineditas-do-concurso-mpu\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/08\/27001830\/mpu.jpeg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/08\/27001830\/mpu.jpeg","width":768,"height":432,"caption":"Concurso Analista do MPU - Direito"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/cadernos-de-questoes-ineditas-do-concurso-mpu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Cadernos de quest\u00f5es in\u00e9ditas do concurso MPU"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/b4a388c97673c5f483d72185668afa1f","name":"Coordena\u00e7\u00e3o","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g","caption":"Coordena\u00e7\u00e3o"},"sameAs":["https:\/\/www.facebook.com\/EstrategiaConcursos","https:\/\/x.com\/EstratConcursos"],"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/estrategia2013\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1536963","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1536963"}],"version-history":[{"count":5,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1536963\/revisions"}],"predecessor-version":[{"id":1564397,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1536963\/revisions\/1564397"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/846824"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1536963"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1536963"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1536963"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1536963"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}