{"id":1533081,"date":"2025-02-16T22:42:40","date_gmt":"2025-02-17T01:42:40","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=1533081"},"modified":"2025-02-17T21:21:46","modified_gmt":"2025-02-18T00:21:46","slug":"informativo-stj-extraordinario-23-comentado-parte-1","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-extraordinario-23-comentado-parte-1\/","title":{"rendered":"Informativo STJ Extraordin\u00e1rio 23 Comentado Parte 1"},"content":{"rendered":"\n<p><\/p><p><\/p><p><span data-darkreader-inline-color=\"\" style=\"font-size: revert;color: initial;, sans-serif;--darkreader-inline-color: initial\">Informativo n\u00ba Extraordin\u00e1rio 23 (Parte 1) do STJ&nbsp;<\/span><strong style=\"font-size: revert;color: initial;, sans-serif;--darkreader-inline-color: initial\" data-darkreader-inline-color=\"\">COMENTADO<\/strong><span data-darkreader-inline-color=\"\" style=\"font-size: revert;color: initial;, sans-serif;--darkreader-inline-color: initial\">.<\/span><\/p><p class=\"has-text-align-center\"><a href=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/02\/16224152\/stj-extraordiario-23-pt1.pdf\" rel=\"sponsored nofollow\">DOWNLOAD do PDF AQUI!<\/a><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"lyte-wrapper\" style=\"width:853px;max-width:100%;margin:5px;\"><div class=\"lyMe\" id=\"WYL_jJtaEvHlUzk\"><div id=\"lyte_jJtaEvHlUzk\" data-src=\"\/\/i.ytimg.com\/vi\/jJtaEvHlUzk\/hqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\"><\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/jJtaEvHlUzk\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/jJtaEvHlUzk\/0.jpg\" alt=\"YouTube video thumbnail\" width=\"853\" height=\"460\" \/><br \/>Assista a este v\u00eddeo no YouTube<\/a><\/noscript><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:853px;margin:5px;\"><\/div>\n<\/div><\/figure>\n\n\n\n<h1 class=\"wp-block-heading\" id=\"h-direito-constitucional\"><a>DIREITO CONSTITUCIONAL<\/a><\/h1>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-1-nbsp-nbsp-nbsp-nbsp-embargos-de-divergencia-acordao-paradigma-oriundo-de-acoes-de-garantia-constitucional\"><a>1.&nbsp;&nbsp;&nbsp;&nbsp; Embargos de diverg\u00eancia. Ac\u00f3rd\u00e3o paradigma oriundo de a\u00e7\u00f5es de garantia constitucional<\/a><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-1-1-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-dos-fatos\"><a>1.1.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Dos FATOS.<\/a><\/h3>\n\n\n\n<p>Dr. Creison, um advogado experiente, ajuizou embargos de diverg\u00eancia no STJ tentando utilizar um ac\u00f3rd\u00e3o proferido em mandado de seguran\u00e7a como paradigma para seu caso. No entanto, ao recorrer, viu sua peti\u00e7\u00e3o ser indeferida liminarmente, pois a jurisprud\u00eancia consolidada do STJ impede o uso de decis\u00f5es em a\u00e7\u00f5es de garantia constitucional como paradigmas em embargos de diverg\u00eancia. A quest\u00e3o a ser analisada envolve a possibilidade de confrontar entendimentos de a\u00e7\u00f5es constitucionais com recursos especiais.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-1-2-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-analise-estrategica\"><a>1.2.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; An\u00e1lise ESTRAT\u00c9GICA.<\/a><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-1-2-1-do-direito\">1.2.1. Do DIREITO.<\/h4>\n\n\n\n<p>C\u00f3digo de Processo Civil (CPC), art. 1.043, \u00a7 1\u00ba<\/p>\n\n\n\n<p>Regimento Interno do STJ, art. 21-E, inciso V e art. 266-C<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-1-2-2-dos-fundamentos\">1.2.2. Dos FUNDAMENTOS.<\/h4>\n\n\n\n<p>N\u00e3o h\u00e1 possibilidade de se confrontar, em embargos de diverg\u00eancia, mesmo ap\u00f3s a entrada em vigor do Novo C\u00f3digo de Processo Civil, teses jur\u00eddicas decididas em sede de recurso especial com aquelas apreciadas em a\u00e7\u00f5es constitucionais.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; A Corte Especial do STJ no julgamento do EREsp 1.805.591-DF, de relatoria da ministra Nancy Andrighi, assentou que: &#8220;o \u00a7 1\u00ba do art. 1.043 do CPC restringe os julgados que podem ser objetos de compara\u00e7\u00e3o, em sede de embargos de diverg\u00eancia, a recursos e a\u00e7\u00f5es de compet\u00eancia origin\u00e1ria, N\u00c3O podendo, portanto, funcionar como paradigma ac\u00f3rd\u00e3os proferidos em a\u00e7\u00f5es que t\u00eam natureza jur\u00eddica de garantia constitucional, como os <strong>habeas corpus, mandado de seguran\u00e7a, habeas data e mandado de injun\u00e7\u00e3o<\/strong>. O mesmo racioc\u00ednio vale para enunciados de s\u00famula de tribunais&#8221;.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; No caso ora analisado, os embargos de diverg\u00eancia foram indeferidos liminarmente, no \u00e2mbito da Presid\u00eancia do STJ, a teor do contido no art. 21-E, inciso V, do Regimento Interno do Superior Tribunal de Justi\u00e7a, c\/c o art. 266-C do mesmo diploma legal, posto que n\u00e3o se admite como paradigma ac\u00f3rd\u00e3o proferido em a\u00e7\u00f5es que possuem natureza de garantia constitucional como o mandado de seguran\u00e7a.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Os embargos de diverg\u00eancia t\u00eam por finalidade pacificar a jurisprud\u00eancia no \u00e2mbito do Tribunal conferindo seguran\u00e7a jur\u00eddica ao jurisdicionado. Assim, cab\u00edvel contra ac\u00f3rd\u00e3o proferido em recurso especial e em agravo em recurso especial, que s\u00e3o recursos destinados a dar a melhor interpreta\u00e7\u00e3o \u00e0 legisla\u00e7\u00e3o federal.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; A fun\u00e7\u00e3o de uniformizar a interpreta\u00e7\u00e3o da legisla\u00e7\u00e3o federal se d\u00e1 na via do recurso especial. E, para tanto, \u00e9 conveniente que o aresto paradigma tenha sido proferido em julgamento com mesmo grau de cogni\u00e7\u00e3o.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Por fim, no mesmo sentido, o Supremo Tribunal Federal tamb\u00e9m ostenta firme jurisprud\u00eancia no sentido da inviabilidade de utiliza\u00e7\u00e3o de paradigmas em sede de habeas corpus para comprova\u00e7\u00e3o de diss\u00eddio em embargos de diverg\u00eancia. (ARE 1.402.115 AgR-Ed-EDv-AgR, Relator Min. Luiz Fux, Tribunal Pleno, julgado em 22\/5\/2023, DJe 7\/6\/2023).<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-1-3-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-da-decisao\"><a>1.3.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Da DECIS\u00c3O.<\/a><\/h3>\n\n\n\n<p>N\u00e3o se admite como paradigma, em sede de embargos de diverg\u00eancia, os julgados proferidos em a\u00e7\u00f5es com natureza jur\u00eddica de garantia constitucional (habeas corpus, habeas data, mandado de seguran\u00e7a e mandado de injun\u00e7\u00e3o).<\/p>\n\n\n\n<p>AgInt nos EAREsp 2.143.376-SP, Rel. Ministro Raul Ara\u00fajo, Rel. para ac\u00f3rd\u00e3o Ministra Maria Thereza de Assis Moura, Corte Especial, por maioria, julgado em 6\/11\/2024, DJEN 23\/12\/2024 (Info Extraordin\u00e1rio 23)<\/p>\n\n\n\n<h1 class=\"wp-block-heading\" id=\"h-direito-do-consumidor\"><a><\/a><a>DIREITO<\/a> DO CONSUMIDOR<\/h1>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-2-nbsp-nbsp-nbsp-nbsp-plano-de-saude-medicamento-antineoplasico-tratamento-para-o-enfrentamento-do-cancer-recusa-de-cobertura\"><a>2.&nbsp;&nbsp;&nbsp;&nbsp; Plano de sa\u00fade. Medicamento antineopl\u00e1sico. Tratamento para o enfrentamento do c\u00e2ncer. Recusa de cobertura.<\/a><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-2-1-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-dos-fatos\"><a><\/a><a>2.1.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Dos FATOS.<\/a><\/h3>\n\n\n\n<p>Dona Matilde, aposentada, descobriu um c\u00e2ncer e recebeu do m\u00e9dico a prescri\u00e7\u00e3o de um medicamento de alto custo. A esperan\u00e7a virou frustra\u00e7\u00e3o quando o plano de sa\u00fade bateu o p\u00e9 e negou a cobertura, alegando que o rem\u00e9dio n\u00e3o constava no rol da ANS. Indignada, Matilde insistiu que o tratamento era essencial e que a recusa contrariava a boa-f\u00e9 contratual. O plano, por sua vez, defendeu que sua obriga\u00e7\u00e3o se limitava \u00e0s coberturas expressamente previstas. E assim est\u00e1 formado o impasse: o plano de sa\u00fade pode negar o tratamento essencial s\u00f3 porque ele n\u00e3o est\u00e1 listado na ANS?<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-2-2-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-analise-estrategica\"><a><\/a><a>2.2.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; An\u00e1lise ESTRAT\u00c9GICA.<\/a><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-2-2-1-dos-fundamentos\">2.2.1. Dos FUNDAMENTOS.<\/h4>\n\n\n\n<p>Segundo a jurisprud\u00eancia do Superior Tribunal de Justi\u00e7a, independentemente da discuss\u00e3o a respeito da <strong>natureza do rol da ANS<\/strong> (se taxativo ou exemplificativo), <strong>imp\u00f5e-se ao plano de sa\u00fade a cobertura de tratamento contra o C\u00c2NCER<\/strong>, inclusive o fornecimento do medicamento denominado antineopl\u00e1sico a ser ministrado via oral.<\/p>\n\n\n\n<p>No caso, a operadora de plano de sa\u00fade recusou a cobertura do medicamento, denominado Abemaciclibe 150 mg, prescrito pelo m\u00e9dico para o enfrentamento da grave doen\u00e7a da paciente, deixando-a padecendo \u00e0 pr\u00f3pria sorte no tratamento da referida enfermidade (neoplasia de mama bilateral), circunst\u00e2ncia que evidencia abusividade e descumprimento da fun\u00e7\u00e3o social do contrato.<\/p>\n\n\n\n<p>A teor da orienta\u00e7\u00e3o jurisprudencial desta Corte Superior, considera-se abusiva a negativa, pela operadora de plano de sa\u00fade, de cobertura de medicamento antineopl\u00e1sico oral indicado por m\u00e9dico assistente para o tratamento contra o c\u00e2ncer (neoplasia de mama bilateral).<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-2-3-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-da-decisao\"><a>2.3.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Da DECIS\u00c3O.<\/a><\/h3>\n\n\n\n<p>Considera-se abusiva a negativa, pela operadora de plano de sa\u00fade, de cobertura de medicamento antineopl\u00e1sico oral indicado para o tratamento contra o c\u00e2ncer.<\/p>\n\n\n\n<p>Processo em segredo de justi\u00e7a, Rel. Ministro Marco Buzzi, Segunda Se\u00e7\u00e3o, por unanimidade, julgado em 11\/12\/2024, DJEN 17\/12\/2024 (Info Extraordin\u00e1rio 23)<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-3-nbsp-nbsp-nbsp-nbsp-inscricao-irregular-em-cadastro-de-protecao-ao-credito-existencia-de-inscricao-regular-anterior\"><a>3.&nbsp;&nbsp;&nbsp;&nbsp; Inscri\u00e7\u00e3o irregular em cadastro de prote\u00e7\u00e3o ao cr\u00e9dito. Exist\u00eancia de inscri\u00e7\u00e3o regular anterior.<\/a><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-3-1-nbsp-dos-fatos\"><a>3.1.&nbsp; Dos FATOS.<\/a><\/h3>\n\n\n\n<p>Creisson teve seu nome inscrito no cadastro de inadimplentes por engano. Dias depois, uma d\u00edvida leg\u00edtima apareceu em seu nome. O banco argumentou que, como Jo\u00e3o j\u00e1 estava negativado, n\u00e3o havia mais dano moral. Jo\u00e3o, por sua vez, dizia que a primeira inscri\u00e7\u00e3o j\u00e1 tinha sujado sua reputa\u00e7\u00e3o. A d\u00favida est\u00e1 lan\u00e7ada: a exist\u00eancia de uma d\u00edvida leg\u00edtima (posterior) pode apagar o erro da inscri\u00e7\u00e3o indevida (anterior)?<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-3-2-nbsp-analise-estrategica\"><a>3.2.&nbsp; An\u00e1lise ESTRAT\u00c9GICA.<\/a><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-3-2-1-nbsp-nbsp-nbsp-do-direito\">3.2.1.&nbsp;&nbsp;&nbsp; Do DIREITO.<\/h4>\n\n\n\n<p>S\u00famula n. 385\/STJ<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-3-2-2-nbsp-nbsp-nbsp-dos-fundamentos\">3.2.2.&nbsp;&nbsp;&nbsp; Dos FUNDAMENTOS.<\/h4>\n\n\n\n<p>O prop\u00f3sito recursal consiste em definir se caracteriza dano moral a irregular anota\u00e7\u00e3o em cadastro de prote\u00e7\u00e3o ao cr\u00e9dito quando existente leg\u00edtima inscri\u00e7\u00e3o posterior.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; O Direito do Consumidor, como ramo especial do Direito, possui autonomia e l\u00f3gica de funcionamento pr\u00f3prias, notadamente por regular rela\u00e7\u00f5es jur\u00eddicas especiais compostas por um sujeito em situa\u00e7\u00e3o de vulnerabilidade. Toda legisla\u00e7\u00e3o dedicada \u00e0 tutela do consumidor tem a mesma finalidade: reequilibrar a rela\u00e7\u00e3o entre consumidores e fornecedores, refor\u00e7ando a posi\u00e7\u00e3o da parte vulner\u00e1vel e, quando necess\u00e1rio, impondo restri\u00e7\u00f5es a certas pr\u00e1ticas comerciais.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Esta Corte Superior perfilha o entendimento de que a inscri\u00e7\u00e3o indevida do nome do consumidor em cadastro de prote\u00e7\u00e3o ao cr\u00e9dito caracteriza dano moral <em>in re ipsa<\/em>, salvo quando preexistente leg\u00edtima inscri\u00e7\u00e3o.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Na esp\u00e9cie, examina-se hip\u00f3tese em que <em>a inscri\u00e7\u00e3o leg\u00edtima n\u00e3o \u00e9 preexistente, mas sim posterior<\/em> \u00e0 anota\u00e7\u00e3o irregular de que se est\u00e1 a tratar, o que afasta a incid\u00eancia da S\u00famula 385\/STJ.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Deve-se examinar a situa\u00e7\u00e3o do consumidor no exato momento da inscri\u00e7\u00e3o irregular. Se, neste instante, j\u00e1 havia anota\u00e7\u00e3o leg\u00edtima anterior, n\u00e3o pode o consumidor alegar que teve sua dignidade, honra e respeito violados, pois devedor j\u00e1 era. Por outro lado, se, no momento da inscri\u00e7\u00e3o irregular, n\u00e3o havia qualquer anota\u00e7\u00e3o leg\u00edtima anterior, inquestionavelmente estar\u00e1 caracterizado o dano moral in re ipsa, nos termos da jurisprud\u00eancia desta Corte, sendo irrelevante o fato de existirem anota\u00e7\u00f5es leg\u00edtimas em momento posterior. Logo, a irregular anota\u00e7\u00e3o em cadastro de prote\u00e7\u00e3o ao cr\u00e9dito quando existente leg\u00edtima inscri\u00e7\u00e3o posterior caracteriza dano moral <em>in re ipsa<\/em>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-3-3-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-da-decisao\"><a>3.3.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Da DECIS\u00c3O.<\/a><\/h3>\n\n\n\n<p>A anota\u00e7\u00e3o irregular em cadastro de prote\u00e7\u00e3o ao cr\u00e9dito que antecede a inscri\u00e7\u00e3o leg\u00edtima caracteriza dano moral in re ipsa.<\/p>\n\n\n\n<p>REsp 2.160.941-SP, Rel. Ministra Nancy Andrighi, Terceira Turma, por unanimidade, julgado em 5\/11\/2024, DJe 8\/11\/2024 (Info Extraordin\u00e1rio 23)<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-4-nbsp-nbsp-nbsp-nbsp-bem-de-consumo-duravel-ainda-em-comercializacao-peca-de-reposicao-nao-disponibilizada-ao-consumidor-configuracao-de-vicio-do-produto\"><a>4.&nbsp;&nbsp;&nbsp;&nbsp; Bem de consumo dur\u00e1vel ainda em comercializa\u00e7\u00e3o. Pe\u00e7a de reposi\u00e7\u00e3o n\u00e3o disponibilizada ao consumidor. Configura\u00e7\u00e3o de v\u00edcio do produto.<\/a><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-4-1-nbsp-dos-fatos\"><a>4.1.&nbsp; Dos FATOS.<\/a><\/h3>\n\n\n\n<p>Carlinhos comprou um carro zero, mas, quando precisou trocar uma pe\u00e7a, descobriu que ela simplesmente n\u00e3o existia no mercado. A montadora alegava que o carro estava em perfeitas condi\u00e7\u00f5es e que a reposi\u00e7\u00e3o de pe\u00e7as dependia da demanda. Carlos insistia que, sem a pe\u00e7a, o carro era in\u00fatil, gerando a possibilidade de desfazimento do contrato, com a devolu\u00e7\u00e3o do possante.<\/p>\n\n\n\n<p>A falta de pe\u00e7as de reposi\u00e7\u00e3o para carro do ano pode ser considerada um defeito do produto?<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-4-2-nbsp-analise-estrategica\"><a>4.2.&nbsp; An\u00e1lise ESTRAT\u00c9GICA.<\/a><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-4-2-1-nbsp-nbsp-nbsp-do-direito\">4.2.1.&nbsp;&nbsp;&nbsp; Do DIREITO.<\/h4>\n\n\n\n<p>C\u00f3digo de Defesa do Consumidor (CDC), art. 18 e art. 32<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-4-2-2-nbsp-nbsp-nbsp-dos-fundamentos\">4.2.2.&nbsp;&nbsp;&nbsp; Dos FUNDAMENTOS.<\/h4>\n\n\n\n<p>Cinge-se a controv\u00e9rsia quanto \u00e0 possibilidade de desfazimento do contrato de compra e venda de ve\u00edculo zero quil\u00f4metro pelo fato de o fabricante n\u00e3o ter disponibilizado pe\u00e7as necess\u00e1rias ao reparo do bem durante longo per\u00edodo.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Nos termos do art. 18 do CDC, ser\u00e1 poss\u00edvel falar em v\u00edcio do produto sempre que verificada alguma desconformidade de qualidade ou quantidade capaz de tornar o bem impr\u00f3prio ou inadequado para o fim a que se destina.<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td>O regime da responsabilidade dos fornecedores por v\u00edcios de produtos decorre da viola\u00e7\u00e3o a um dever de adequa\u00e7\u00e3o, assim entendida como a aptid\u00e3o do produto (ou do servi\u00e7o) para servir, para ser \u00fatil ao <em>uso que legitimamente dele se espera<\/em>. Referida inadequa\u00e7\u00e3o ou v\u00edcio de qualidade, surge de ordin\u00e1rio com o pr\u00f3prio bem. Decorre, normalmente, de uma falha de projeto, de fabrica\u00e7\u00e3o ou de montagem. N\u00e3o se afasta, por\u00e9m, a <strong>possibilidade de que essa inadequa\u00e7\u00e3o surja apenas momento <u>posterior<\/u><\/strong>, depois da comercializa\u00e7\u00e3o do bem, na fase de p\u00f3s-venda.<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Isso se mostra claro no mercado de autom\u00f3veis, em que os fornecedores t\u00eam o dever de viabilizar o funcionamento do bem mesmo ap\u00f3s a sua comercializa\u00e7\u00e3o, garantido pe\u00e7as de reposi\u00e7\u00e3o. Ainda que o autom\u00f3vel adquirido n\u00e3o contivesse nenhum v\u00edcio de projeto ou fabrica\u00e7\u00e3o, apresentando a qualidade adequada no momento da venda ao consumidor, deve ser considerado viciado se n\u00e3o dispuser de pe\u00e7as de reposi\u00e7\u00e3o para eventual reparo em caso de avaria. Isso porque a falta de pe\u00e7as para reposi\u00e7\u00e3o impede o seu uso regular e frustra a expectativa leg\u00edtima de utiliza\u00e7\u00e3o do bem.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; <strong>O consumidor que adquire ve\u00edculo zero quil\u00f4metro, lan\u00e7ado h\u00e1 pouco tempo no mercado nacional, tem a leg\u00edtima expectativa de encontrar pe\u00e7as para reposi\u00e7\u00e3o capazes de garantir o conserto em caso de avaria<\/strong>. Ningu\u00e9m compra um carro para us\u00e1-lo apenas at\u00e9 que apresente algum defeito. Ao contr\u00e1rio, \u00e9 pr\u00e1tica consagrada no mercado de consumo, que esse tipo de bem possa ser reparado v\u00e1rias e v\u00e1rias vezes, sempre que necess\u00e1rio, durante um tempo razo\u00e1vel.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; O art. 32 do CDC, ali\u00e1s, anuncia, expressamente que o oferecimento de pe\u00e7as de reposi\u00e7\u00e3o integra a pr\u00f3pria qualidade do produto oferecido no mercado de consumo. Assim, a falta de pe\u00e7as de reposi\u00e7\u00e3o no seguimento de ve\u00edculos automotores caracteriza, por isso, verdadeiro v\u00edcio do produto, ensejando para o consumidor as op\u00e7\u00f5es de substitui\u00e7\u00e3o do produto, restitui\u00e7\u00e3o da quantia paga ou abatimento proporcional do pre\u00e7o, nos termos do art. 18, \u00a7 1\u00ba, do CDC<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-4-3-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-da-decisao\"><a>4.3.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Da DECIS\u00c3O.<\/a><\/h3>\n\n\n\n<p>A falta de pe\u00e7as de reposi\u00e7\u00e3o de ve\u00edculo adquirido zero quil\u00f4metro, lan\u00e7ado h\u00e1 pouco tempo no mercado nacional, caracteriza v\u00edcio do produto, ensejando para o consumidor as op\u00e7\u00f5es de substitui\u00e7\u00e3o do produto, restitui\u00e7\u00e3o da quantia paga ou abatimento proporcional do pre\u00e7o<\/p>\n\n\n\n<p>REsp 2.149.058-SP, Rel. Ministro Moura Ribeiro, Terceira Turma, por unanimidade, julgado em 10\/12\/2024, DJEN 18\/12\/2024 (Info Info Extraordin\u00e1rio 23<\/p>\n\n\n\n<h1 class=\"wp-block-heading\" id=\"h-direito-processual-civil\"><a><\/a><a><\/a><a>DIREITO<\/a> PROCESSUAL CIVIL<\/h1>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-5-nbsp-nbsp-nbsp-nbsp-modificacao-do-polo-passivo-da-execucao-reapreciacao-da-materia-em-impugnacao-ao-cumprimento-de-sentenca\"><a>5.&nbsp;&nbsp;&nbsp;&nbsp; Modifica\u00e7\u00e3o do polo passivo da execu\u00e7\u00e3o. Reaprecia\u00e7\u00e3o da mat\u00e9ria em impugna\u00e7\u00e3o ao cumprimento de senten\u00e7a.<\/a><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-5-1-nbsp-dos-fatos\"><a><\/a><a><\/a><a>5.1.&nbsp; Dos FATOS.<\/a><\/h3>\n\n\n\n<p>Geremias, devedor, faleceu enquanto a a\u00e7\u00e3o de cobran\u00e7a seguia seu rumo. Ap\u00f3s a morte de Geremias, j\u00e1 na fase de execu\u00e7\u00e3o, seu filho e herdeiro, Creitinho, assumiu a posi\u00e7\u00e3o no polo passivo.<\/p>\n\n\n\n<p>Ap\u00f3s algum tempo, Creitinho tentou questionar a sua legitimidade passiva, alegando que a sucess\u00e3o da d\u00edvida deveria ser reavaliada. A parte exequente, no entanto, afirma que a sucess\u00e3o j\u00e1 havia sido reconhecida anteriormente e que o herdeiro n\u00e3o pode rediscutir a quest\u00e3o.<\/p>\n\n\n\n<p>Pronto! Est\u00e1 aberta a controv\u00e9rsia sobre a possibilidade de rean\u00e1lise de quest\u00f5es processuais j\u00e1 decididas no curso da execu\u00e7\u00e3o.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-5-2-nbsp-analise-estrategica\"><a><\/a><a><\/a><a>5.2.&nbsp; An\u00e1lise ESTRAT\u00c9GICA.<\/a><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-5-2-1-nbsp-nbsp-nbsp-do-direito\">5.2.1.&nbsp;&nbsp;&nbsp; Do DIREITO.<\/h4>\n\n\n\n<p>C\u00f3digo de Processo Civil (CPC\/1973), art. 267, \u00a7 3\u00ba, art. 471 e art. 473;<\/p>\n\n\n\n<p>C\u00f3digo de Processo Civil (CPC\/2015), art. 485, \u00a7 3\u00ba, art. 505 e art. 507.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-5-2-2-nbsp-nbsp-nbsp-dos-fundamentos\">5.2.2.&nbsp;&nbsp;&nbsp; Dos FUNDAMENTOS.<\/h4>\n\n\n\n<p>A respeito da preclus\u00e3o, o art. 471 do CPC\/1973, vigente \u00e0 \u00e9poca em que proferidos os julgados pelas inst\u00e2ncias ordin\u00e1rias (atual art. 505 do CPC\/2015), dispunha que &#8220;nenhum juiz decidir\u00e1 novamente as quest\u00f5es j\u00e1 decididas, relativas \u00e0 mesma lide, salvo: I &#8211; se, tratando-se de rela\u00e7\u00e3o jur\u00eddica continuativa, sobreveio modifica\u00e7\u00e3o no estado de fato ou de direito; caso em que poder\u00e1 a parte pedir a revis\u00e3o do que foi estatu\u00eddo na senten\u00e7a; II &#8211; nos demais casos prescritos em lei&#8221;.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Al\u00e9m disso, o art. 473 do CPC\/1973 (art. 507 do CPC\/2015) disciplinava que &#8220;\u00e9 defeso \u00e0 parte discutir, no curso do processo, as quest\u00f5es j\u00e1 decididas, a cujo respeito se operou a preclus\u00e3o&#8221;.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; N\u00e3o se desconhece que a jurisprud\u00eancia do Superior Tribunal de Justi\u00e7a, por consider\u00e1vel lapso temporal, admitia a rediscuss\u00e3o das mat\u00e9rias de ordem p\u00fablica, que, por serem suscet\u00edveis de delibera\u00e7\u00e3o judicial de of\u00edcio, a qualquer tempo e grau de jurisdi\u00e7\u00e3o, n\u00e3o se sujeitavam \u00e0 preclus\u00e3o para o juiz, al\u00e9m do fato de que a preclus\u00e3o \u00e9 san\u00e7\u00e3o imposta somente \u00e0s partes, e n\u00e3o ao julgador.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; N\u00e3o obstante, tal entendimento tem sido mitigado na jurisprud\u00eancia do STJ, atrav\u00e9s da compreens\u00e3o de que, havendo decis\u00e3o judicial anterior acerca de determinada mat\u00e9ria, ainda que de ordem p\u00fablica, ocorre a sua preclus\u00e3o consumativa, a inviabilizar o seu reexame pelo juiz (preclus\u00e3o pro judicato).<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; De fato, a preclus\u00e3o \u00e9 uma san\u00e7\u00e3o imposta \u00e0 parte, tal como extra\u00eddo do disposto no art. 473 do CPC\/1973 (art. 507 do CPC\/2015). Por\u00e9m, a isso n\u00e3o se limita, pois o seu espectro de incid\u00eancia \u00e9 mais amplo, impedindo a rediscuss\u00e3o de uma mat\u00e9ria no \u00e2mbito da mesma lide, <em>quando n\u00e3o impugnada oportunamente (preclus\u00e3o temporal) ou j\u00e1 decidida em momento pret\u00e9rito<\/em> (preclus\u00e3o consumativa), transcendendo as partes essa segunda hip\u00f3tese para alcan\u00e7ar tamb\u00e9m o juiz (preclus\u00e3o pro judicato), nos termos do art. 471 do CPC\/1973 (art. 505 do CPC\/2015).<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; <strong>Nem mesmo as mat\u00e9rias de ordem p\u00fablica<\/strong> arroladas no enunciado do art. 267, \u00a7 3\u00ba, do CPC\/1973 (art. 485, \u00a7 3\u00ba, do CPC\/2015) &#8211; o qual permite ao juiz delas conhecer de of\u00edcio, em qualquer tempo e grau de jurisdi\u00e7\u00e3o, tais como os pressupostos processuais e as condi\u00e7\u00f5es da a\u00e7\u00e3o -, <strong>est\u00e3o imunes \u00e0 preclus\u00e3o consumativa<\/strong>.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Ao referido dispositivo de lei deve-se dar a devida interpreta\u00e7\u00e3o, pois a possibilidade de conhecimento da mat\u00e9ria de ordem p\u00fablica pelo juiz, em qualquer tempo e grau de jurisdi\u00e7\u00e3o ordin\u00e1ria (na esteira da jurisprud\u00eancia do STJ), <strong>N\u00c3O se confunde com a possibilidade de seu reexame<\/strong>, tendo em vista a inexist\u00eancia de refer\u00eancia legal acerca da preclus\u00e3o das referidas quest\u00f5es de ordem p\u00fablica j\u00e1 decididas. Trata-se de coisas distintas, pois a possibilidade de <em>conhecimento de of\u00edcio das quest\u00f5es de ordem p\u00fablica n\u00e3o se confunde com a preclus\u00e3o<\/em>.<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td><strong>CONHECIMENTO DE OF\u00cdCIO<\/strong><strong><\/strong><\/td><td><strong>PRECLUS\u00c3O CONSUMATIVA<\/strong><strong><\/strong><\/td><\/tr><tr><td>Flexibiliza\u00e7\u00e3o do princ\u00edpio dispositivo (da demanda ou da in\u00e9rcia de jurisdi\u00e7\u00e3o), permitindo que o juiz conhe\u00e7a e delibere, excepcionalmente, sobre temas n\u00e3o levantados pelas partes.<\/td><td>Impossibilidade de se refazer determinado ato processual e impossibilidade de reexame de mat\u00e9ria j\u00e1 decidida.<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Compilando a jurisprud\u00eancia do Superior Tribunal de Justi\u00e7a, tem-se que a possibilidade de conhecimento e an\u00e1lise, de of\u00edcio, pelo juiz das mat\u00e9rias de ordem p\u00fablica encontra limite na preclus\u00e3o consumativa, sendo insuscet\u00edveis de nova delibera\u00e7\u00e3o pelo juiz (preclus\u00e3o pro judicato).<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Al\u00e9m disso, &#8220;o instituto da preclus\u00e3o pro judicato tem por objetivo preservar a ordem p\u00fablica e a seguran\u00e7a jur\u00eddica, atingindo, assim, o exerc\u00edcio da fun\u00e7\u00e3o jurisdicional&#8221; (HC n. 416.454\/TO, Rel. Ministro Ribeiro Dantas, Quinta Turma, julgado em 28\/11\/2017, DJe de 1\u00ba\/12\/2017).<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Na mesma perspectiva, j\u00e1 assentou a Primeira Turma do STJ que, &#8220;o instituto da preclus\u00e3o pro judicato atinge diretamente o exerc\u00edcio da fun\u00e7\u00e3o jurisdicional, sendo imperioso o seu reconhecimento pelo magistrado, independentemente da provoca\u00e7\u00e3o das partes, para a preserva\u00e7\u00e3o da ordem p\u00fablica e da seguran\u00e7a jur\u00eddica&#8221; (EDcl no REsp n. 1.513.017\/MA, Rel. Ministro Gurgel de Faria, Primeira Turma, julgado em 13\/6\/2017, DJe de 14\/9\/2017).<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Portanto, conclui-se que as mat\u00e9rias de ordem p\u00fablica, embora pass\u00edveis de conhecimento pelo juiz de of\u00edcio, quando ainda n\u00e3o decididas, s\u00e3o insuscet\u00edveis de nova delibera\u00e7\u00e3o judicial, ante a preclus\u00e3o pro judicato, que \u00e9 esp\u00e9cie de preclus\u00e3o consumativa.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-5-3-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-da-decisao\"><a><\/a><a>5.3.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Da DECIS\u00c3O.<\/a><\/h3>\n\n\n\n<p>As mat\u00e9rias de ordem p\u00fablica, embora pass\u00edveis de conhecimento pelo juiz de of\u00edcio, s\u00e3o insuscet\u00edveis de nova delibera\u00e7\u00e3o judicial, ante a preclus\u00e3o pro judicato, que \u00e9 esp\u00e9cie de preclus\u00e3o consumativa.<\/p>\n\n\n\n<p>EREsp 1.488.048-MT, Rel. Ministro Marco Aur\u00e9lio Bellizze, Segunda Se\u00e7\u00e3o, por unanimidade, julgado em 13\/11\/2024, DJe 22\/11\/2024 (Info Extraordin\u00e1rio 23)<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-6-nbsp-nbsp-nbsp-nbsp-bem-de-familia-imovel-indivisivel-totalidade-do-bem\"><a>6.&nbsp;&nbsp;&nbsp;&nbsp; Bem de fam\u00edlia. Im\u00f3vel indivis\u00edvel. Totalidade do bem<\/a><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-6-1-nbsp-dos-fatos\"><a><\/a><a>6.1.&nbsp; Dos FATOS.<\/a><\/h3>\n\n\n\n<p>Em um processo de div\u00f3rcio consensual, Creiton doou o im\u00f3vel comum para os filhos e a ex-esposa. Passado algum tempo, Crementina quase caiu de costas ao saber que ao tempo dessa doa\u00e7\u00e3o, Creiton estava enterrado em d\u00edvidas at\u00e9 o pesco\u00e7o. O credor de uma dessas cobran\u00e7as buscava a penhorada do im\u00f3vel.<\/p>\n\n\n\n<p>O banco credor argumenta que a doa\u00e7\u00e3o do bem ocorreu quando a d\u00edvida j\u00e1 existia, de modo que haveria fraude. Subsidiariamente, entende que poderia executar a parcela do im\u00f3vel que pertencia ao devedor. Crementina, desesperada, argumenta que o bem de fam\u00edlia dever ser protegido integralmente.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-6-2-nbsp-analise-estrategica\"><a><\/a><a>6.2.&nbsp; An\u00e1lise ESTRAT\u00c9GICA.<\/a><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-6-2-1-nbsp-nbsp-nbsp-dos-fundamentos\">6.2.1.&nbsp;&nbsp;&nbsp; Dos FUNDAMENTOS.<\/h4>\n\n\n\n<p>Discute-se se o bem de fam\u00edlia perde a sua impenhorabilidade no caso de ter sido doado aos filhos do executado e da meeira, tendo permanecido como resid\u00eancia da fam\u00edlia.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Conforme a jurisprud\u00eancia do STJ, n\u00e3o h\u00e1 falar em fraude ao credor apta a destituir a prote\u00e7\u00e3o do bem doado pela embargada, pois <em>n\u00e3o houve altera\u00e7\u00e3o na destina\u00e7\u00e3o original do im\u00f3vel<\/em>, qual seja, a moradia da fam\u00edlia. Nesse sentido, REsp n. 1.926.646\/SP, Rel. Ministra Nancy Andrighi, Terceira Turma, julgado em 15\/2\/2022, DJe de 18\/2\/2022.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Na hip\u00f3tese, uma vez que foi constatado que o im\u00f3vel \u00e9 utilizado como resid\u00eancia da meeira e do executado de forma cont\u00ednua, h\u00e1 que se manter a impenhorabilidade do bem de fam\u00edlia.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Dessa forma, reconhecida a prote\u00e7\u00e3o do bem de fam\u00edlia em rela\u00e7\u00e3o \u00e0 mea\u00e7\u00e3o da esposa, que sequer \u00e9 devedora na a\u00e7\u00e3o principal, tal prote\u00e7\u00e3o se estende \u00e0 totalidade do bem, visto que objetiva resguardar a fam\u00edlia contra o desabrigo e n\u00e3o apenas prevenir o perdimento de bens da meeira.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-6-3-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-da-decisao\"><a><\/a><a>6.3.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Da DECIS\u00c3O.<\/a><\/h3>\n\n\n\n<p>O reconhecimento da prote\u00e7\u00e3o do bem de fam\u00edlia em rela\u00e7\u00e3o \u00e0 mea\u00e7\u00e3o da esposa, que sequer \u00e9 devedora na a\u00e7\u00e3o principal, se estende \u00e0 totalidade do bem, visto que objetiva resguardar a fam\u00edlia contra o desabrigo e n\u00e3o apenas prevenir o perdimento de bens da meeira.<\/p>\n\n\n\n<p>EDcl no AgInt no AREsp 2.244.832-SP, Rel. Ministro Humberto Martins, Terceira Turma, por unanimidade, julgado em 23\/9\/2024, DJe 1\u00ba\/10\/2024 &nbsp;(Info Extraordin\u00e1rio 23)<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-7-nbsp-nbsp-nbsp-nbsp-acao-de-reconhecimento-de-uniao-estavel-pos-morte\"><a>7.&nbsp;&nbsp;&nbsp;&nbsp; A\u00e7\u00e3o de reconhecimento de uni\u00e3o est\u00e1vel p\u00f3s-morte<\/a><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-7-1-nbsp-dos-fatos\"><a><\/a><a>7.1.&nbsp; Dos FATOS.<\/a><\/h3>\n\n\n\n<p>Gertrudes e Creosvaldo viveram juntos por anos, mas nunca formalizaram a rela\u00e7\u00e3o. Ap\u00f3s a morte de Creosvaldo, Gertrudes entrou na Justi\u00e7a pretendendo o reconhecimento da uni\u00e3o est\u00e1vel. Os herdeiros do falecido n\u00e3o gostaram nada da ideia e afirmaram que os dois eram apenas bons amigos.<\/p>\n\n\n\n<p>A situa\u00e7\u00e3o era t\u00e3o conflituosa que as partes n\u00e3o se entendiam nem no ju\u00edzo que deveria processar a demanda&#8230;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-7-2-nbsp-analise-estrategica\"><a><\/a><a>7.2.&nbsp; An\u00e1lise ESTRAT\u00c9GICA.<\/a><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-7-2-1-nbsp-nbsp-nbsp-do-direito\">7.2.1.&nbsp;&nbsp;&nbsp; Do DIREITO.<\/h4>\n\n\n\n<p>C\u00f3digo de Processo Civil (CPC\/1973), art. 100, I<\/p>\n\n\n\n<p>C\u00f3digo de Processo Civil (CPC\/2015), art. 53, I, b<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-7-2-2-nbsp-nbsp-nbsp-dos-fundamentos\">7.2.2.&nbsp;&nbsp;&nbsp; Dos FUNDAMENTOS.<\/h4>\n\n\n\n<p>A controv\u00e9rsia consiste em definir qual o ju\u00edzo competente para processar e julgar a\u00e7\u00e3o de reconhecimento de uni\u00e3o est\u00e1vel ajuizada contra esp\u00f3lio e sucessor do convivente falecido quando ausente filho incapaz.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Na vig\u00eancia do <strong>CPC de 1973<\/strong>, a jurisprud\u00eancia do STJ firmou-se no sentido da incid\u00eancia, por analogia, da regra prevista no art. 100, inciso I, do CPC de 1973, tendo em vista a aus\u00eancia de regulamenta\u00e7\u00e3o espec\u00edfica para as a\u00e7\u00f5es referentes \u00e0 uni\u00e3o est\u00e1vel, bem como diante da similitude da mat\u00e9ria com aquelas trazidas em a\u00e7\u00f5es de div\u00f3rcio e anula\u00e7\u00e3o de casamento. &nbsp;Em raz\u00e3o da aplica\u00e7\u00e3o da referida norma, consagrou-se o domic\u00edlio da mulher como o competente para julgamento de a\u00e7\u00e3o de reconhecimento e dissolu\u00e7\u00e3o de uni\u00e3o est\u00e1vel, inclusive nas hip\u00f3teses nas quais a demanda era proposta ap\u00f3s o falecimento do companheiro contra seu esp\u00f3lio e sucessores.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Com a vig\u00eancia do CPC de 2015, a quest\u00e3o passou a ser regulamentada de maneira diversa pelo art. 53, inciso I. A compet\u00eancia para as a\u00e7\u00f5es concernentes \u00e0 uni\u00e3o est\u00e1vel, que estava anteriormente diretamente vinculada ao domic\u00edlio da mulher, atualmente \u00e9 regida por par\u00e2metro diverso, reconhecendo-se a necessidade de privilegiar, primeiramente, os interesses de eventual filho incapaz das partes e, ausente tal hip\u00f3tese, o \u00faltimo domic\u00edlio do casal.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; A hip\u00f3tese prevista na al\u00ednea b do inciso I do art. 53 do CPC\/2015, a toda evid\u00eancia, pretende <strong>garantir IGUALDADE de tratamento processual entre os conviventes e facilitar a produ\u00e7\u00e3o de <u>provas<\/u> necess\u00e1ria \u00e0 instru\u00e7\u00e3o da demanda<\/strong>. De fato, as provas capazes de demonstrar as pretens\u00f5es defendidas nos conflitos levados \u00e0 justi\u00e7a na seara de fam\u00edlia, em sua maioria, encontram-se no domic\u00edlio no qual as partes residiam, a exemplo dos bens im\u00f3veis que comp\u00f5em eventual patrim\u00f4nio comum e das testemunhas que conviveram com as partes e s\u00e3o capazes de atestar as quest\u00f5es controvertidas.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Por fim, ressalta-se que o fato de a a\u00e7\u00e3o ser movida contra o esp\u00f3lio e sucessora n\u00e3o afasta a natureza da a\u00e7\u00e3o de reconhecimento de uni\u00e3o est\u00e1vel e, consequentemente, a norma espec\u00edfica quanto \u00e0 compet\u00eancia. Tal interpreta\u00e7\u00e3o foi adotada pelo STJ tamb\u00e9m na vig\u00eancia do diploma processual de 1973<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-7-3-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-da-decisao\"><a><\/a><a>7.3.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Da DECIS\u00c3O.<\/a><\/h3>\n\n\n\n<p>Na aus\u00eancia de filhos incapazes, a compet\u00eancia para processar e julgar a\u00e7\u00f5es de reconhecimento de uni\u00e3o est\u00e1vel, inclusive quando proposta ap\u00f3s o falecimento do convivente, \u00e9 do ju\u00edzo correspondente ao \u00faltimo domic\u00edlio do casal.<\/p>\n\n\n\n<p>Processo sem segredo de justi\u00e7a, Rel. Ministro Ricardo Villas B\u00f4as Cueva, Terceira Turma, por unanimidade, julgado em 3\/12\/2024, DJEN 6\/12\/2024 (Info Extraordin\u00e1rio 23)<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-8-nbsp-nbsp-nbsp-nbsp-inventario-e-limites-da-jurisdicao-brasileira-bens-situados-no-exterior\"><a>8.&nbsp;&nbsp;&nbsp;&nbsp; Invent\u00e1rio e Limites da jurisdi\u00e7\u00e3o brasileira. Bens situados no exterior.<\/a><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-8-1-nbsp-dos-fatos\"><a><\/a><a>8.1.&nbsp; Dos FATOS.<\/a><\/h3>\n\n\n\n<p>Quando Nostradamus faleceu, deixou bens tanto no Brasil quanto nos Estados Unidos. Seus filhos brasileiros queriam incluir tudo no invent\u00e1rio brasileiro, alegando que a sucess\u00e3o deveria seguir a lei do pa\u00eds onde ele morava. J\u00e1 os herdeiros colaterais americanos defendiam que os bens estrangeiros deveriam ser tratados conforme as leis locais. E agora?! A sucess\u00e3o de bens no exterior pode ser resolvida no Brasil ou deve ser julgada no pa\u00eds onde os bens est\u00e3o localizados?<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-8-2-nbsp-analise-estrategica\"><a><\/a><a>8.2.&nbsp; An\u00e1lise ESTRAT\u00c9GICA.<\/a><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-8-2-1-nbsp-nbsp-nbsp-do-direito\">8.2.1.&nbsp;&nbsp;&nbsp; Do DIREITO.<\/h4>\n\n\n\n<p>C\u00f3digo de Processo Civil (CPC\/15), art. 23, II;&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p>Lei de Introdu\u00e7\u00e3o \u00e0s Normas de Direito Brasileiro (LINDB), art. 7\u00ba e art. 10.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-8-2-2-nbsp-nbsp-nbsp-dos-fundamentos\">8.2.2.&nbsp;&nbsp;&nbsp; Dos FUNDAMENTOS.<\/h4>\n\n\n\n<p>Cinge-se a controv\u00e9rsia a discutir a compet\u00eancia para processar invent\u00e1rio de falecido residente no Brasil, mas que possu\u00eda bens no exterior.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Nos termos do art. 23, II, do CPC\/15, \u00e9 de compet\u00eancia exclusiva da autoridade brasileira, com exclus\u00e3o de qualquer outra, em mat\u00e9ria de sucess\u00e3o heredit\u00e1ria, proceder ao invent\u00e1rio de bens situados no Brasil, ainda que o autor da heran\u00e7a seja de nacionalidade estrangeira ou tenha domic\u00edlio fora do territ\u00f3rio nacional.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; A Lei de Introdu\u00e7\u00e3o \u00e0s Normas de Direito Brasileiro (LINDB) elegeu o domic\u00edlio como relevante regra de conex\u00e3o para solver conflitos decorrentes de situa\u00e7\u00f5es jur\u00eddicas relacionadas a mais de um sistema legal (conflitos de leis interespaciais), porquanto consistente na pr\u00f3pria sede jur\u00eddica do indiv\u00edduo.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Assim, a lei do pa\u00eds em que for domiciliada a pessoa determina as regras sobre o come\u00e7o e o fim da personalidade, o direito ao nome, a capacidade jur\u00eddica e dos direitos de fam\u00edlia (art. 7\u00ba). Por sua vez, a lei do domic\u00edlio do autor da heran\u00e7a regular\u00e1 a correlata sucess\u00e3o, nos termos do art. 10 da lei sob comento.<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td>Em que pese a preval\u00eancia da lei do domic\u00edlio do indiv\u00edduo para regular as suas rela\u00e7\u00f5es jur\u00eddicas pessoais, conforme preceitua a LINDB, esta regra de conex\u00e3o N\u00c3O \u00e9 absoluta.<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Consoante a doutrina, outros elementos de conectividade podem, a depender da situa\u00e7\u00e3o sob an\u00e1lise, revelarem-se preponderantes e, por conseguinte, excepcionar a aludida regra, tais como a situa\u00e7\u00e3o da coisa, a faculdade concedida \u00e0 vontade individual na escolha da lei aplic\u00e1vel, quando isto for poss\u00edvel, ou por imposi\u00e7\u00f5es de ordem p\u00fablica.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Dessa maneira, em uma interpreta\u00e7\u00e3o SISTEM\u00c1TICA das disposi\u00e7\u00f5es contidas na LINDB e no CPC\/2015, depreende-se que o <em>legislador inviabilizou a unidade da sucess\u00e3o<\/em>, amparada no princ\u00edpio da universalidade sucess\u00f3ria e determina que a transmiss\u00e3o do conjunto de bens deve ser governada por uma lei \u00fanica, pois pela lei se transmite uma universalidade, um patrim\u00f4nio, ou seja, o conjunto de direitos reais e obrigacionais, ativos e passivos pertencentes a uma pessoa.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Diante disso, a jurisprud\u00eancia do STJ segue a orienta\u00e7\u00e3o de que o Brasil adota o princ\u00edpio da pluralidade dos ju\u00edzos sucess\u00f3rios, pois, ainda que o art. 10 da LINDB preceitue a preval\u00eancia da lei do domic\u00edlio do indiv\u00edduo para regular as suas rela\u00e7\u00f5es jur\u00eddicas, esta regra n\u00e3o \u00e9 absoluta, devendo o invent\u00e1rio e a partilha ser processados no lugar da situa\u00e7\u00e3o dos bens deixados pelo falecido, n\u00e3o podendo o ju\u00edzo do invent\u00e1rio no Brasil decidir sobre bens sitos no estrangeiro.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; O entendimento que tem prevalecido nesta Corte Superior \u00e9 o de que a lei brasileira n\u00e3o tem aplica\u00e7\u00e3o em rela\u00e7\u00e3o \u00e0 sucess\u00e3o dos bens no exterior, inclusive para fins de eventual compensa\u00e7\u00e3o de leg\u00edtimas.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Portanto, o ordenamento jur\u00eddico p\u00e1trio adotou a pluralidade sucess\u00f3ria, a qual prestigia a legisla\u00e7\u00e3o do local em que situados os bens (<em>lex rei sitae<\/em>) para regular a sucess\u00e3o heredit\u00e1ria, impedindo que o Poder Judici\u00e1rio brasileiro conhe\u00e7a de bens situados no exterior.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-8-3-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-da-decisao\"><a><\/a><a>8.3.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Da DECIS\u00c3O.<\/a><\/h3>\n\n\n\n<p>A lei brasileira n\u00e3o tem aplica\u00e7\u00e3o em rela\u00e7\u00e3o \u00e0 sucess\u00e3o dos bens no exterior, inclusive para fins de eventual compensa\u00e7\u00e3o de leg\u00edtimas<\/p>\n\n\n\n<p>Processo em segredo de justi\u00e7a, Rel. Ministro Marco Aur\u00e9lio Bellizze, Terceira Turma, por unanimidade, julgado em 27\/8\/2024, DJe 29\/8\/2024 (Info Extraordin\u00e1rio 23)<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-9-nbsp-nbsp-nbsp-nbsp-investigacao-de-paternidade-pos-morte-cumulada-com-peticao-de-heranca-estrangeiro-domiciliado-temporariamente-no-brasil\"><a>9.&nbsp;&nbsp;&nbsp;&nbsp; Investiga\u00e7\u00e3o de paternidade p\u00f3s-morte cumulada com peti\u00e7\u00e3o de heran\u00e7a. Estrangeiro domiciliado temporariamente no Brasil.<\/a><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-9-1-nbsp-dos-fatos\"><a><\/a><a>9.1.&nbsp; Dos FATOS.<\/a><\/h3>\n\n\n\n<p>Pierre, franc\u00eas de nascimento, descobriu que poderia ser filho de um brasileiro falecido. Ele decidiu tirar umas f\u00e9rias prolongadas em terras tupiniquins e aproveitar para demandar na Justi\u00e7a brasileira. A ideia \u00e9 anular seus documentos de paternidade franceses, fazer o reconhecimento de paternidade <em>brasuca<\/em> e, de quebra, garantir uma parte da heran\u00e7a.<\/p>\n\n\n\n<p>Os herdeiros brasileiros, indignados, alegaram que o caso deveria ser julgado na Fran\u00e7a, onde Pierre tinha seu registro civil. Agora, a quest\u00e3o \u00e9 saber at\u00e9 onde vai a jurisdi\u00e7\u00e3o brasileira para alterar registros de nascimento feitos no exterior.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-9-2-nbsp-analise-estrategica\"><a><\/a><a>9.2.&nbsp; An\u00e1lise ESTRAT\u00c9GICA.<\/a><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-9-2-1-nbsp-nbsp-nbsp-do-direito\">9.2.1.&nbsp;&nbsp;&nbsp; Do DIREITO.<\/h4>\n\n\n\n<p>C\u00f3digo de Processo Civil (CPC\/2015), art. 23, II<\/p>\n\n\n\n<p>Decreto-lei n. 4.657\/1942. (Lei de Introdu\u00e7\u00e3o \u00e0s Normas de Direito Brasileiro &#8211; LINDB), art. 8\u00ba, caput, art. 10 e 12, \u00a7 1\u00ba<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-9-2-2-nbsp-nbsp-nbsp-dos-fundamentos\">9.2.2.&nbsp;&nbsp;&nbsp; Dos FUNDAMENTOS.<\/h4>\n\n\n\n<p>A controv\u00e9rsia consiste em definir se a justi\u00e7a brasileira \u00e9 competente para apreciar pedido que <strong>altera registro de nascimento de estrangeiro domiciliado temporariamente no Brasil<\/strong>.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; A Lei de Introdu\u00e7\u00e3o \u00e0s Normas de Direito Brasileiro (LINDB), que deve ser interpretada \u00e0 luz das normas de compet\u00eancia previstas no diploma processual civil, inegavelmente elegeu o domic\u00edlio como relevante regra de conex\u00e3o para solver conflitos decorrentes de situa\u00e7\u00f5es jur\u00eddicas relacionadas a mais de um sistema legal (conflitos de leis INTERESPACIAIS), porquanto consistente na pr\u00f3pria sede jur\u00eddica do indiv\u00edduo. Assim, a lei do pa\u00eds em que for domiciliada a pessoa determina as regras sobre o come\u00e7o e o fim da personalidade, o direito ao nome, a capacidade jur\u00eddica e dos direitos de fam\u00edlia (art. 7\u00ba da LINDB).<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Por sua vez, a lei do domic\u00edlio do autor da heran\u00e7a regular\u00e1 a correlata sucess\u00e3o, nos termos do art. 10 da mesma lei. Portanto, o elemento de conex\u00e3o, no conflito de leis no espa\u00e7o, estipulado pelo ordenamento jur\u00eddico p\u00e1trio \u00e9 o domic\u00edlio da pessoa, de maneira que, mesmo quando a concep\u00e7\u00e3o, o nascimento e o registro da pessoa natural tenham ocorrido no exterior, ser\u00e1 aplicada a norma brasileira quando o domic\u00edlio do postulante for no Brasil.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Diante disso, deve-se perquirir qual o crit\u00e9rio para se reconhecer o domic\u00edlio da pessoa para fins de se estabelecer os limites da jurisdi\u00e7\u00e3o brasileira, tanto em rela\u00e7\u00e3o \u00e0 investiga\u00e7\u00e3o de paternidade como \u00e0 peti\u00e7\u00e3o de heran\u00e7a.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; No caso de origem, o autor declarou ser <em>temporariamente<\/em> residente e domiciliado em endere\u00e7o localizado no Brasil, postulando o reconhecimento da paternidade, a fim de que conste o nome de seu pai em sua certid\u00e3o de nascimento (emitida por governo estrangeiro) e lhe seja assegurado o direito de heran\u00e7a. Ocorre que, diante do quadro f\u00e1tico delineado pelo Tribunal de origem, percebe-se que o autor n\u00e3o possui domic\u00edlio no Brasil!<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td>A <em>mera declara\u00e7\u00e3o<\/em> de domic\u00edlio tempor\u00e1rio, sem outros elementos que demonstrem sua inten\u00e7\u00e3o de estabelecer no Pa\u00eds o centro de suas rela\u00e7\u00f5es jur\u00eddicas, <strong>N\u00c3O \u00e9 capaz de transformar uma mera <em>moradia<\/em> em <em>domic\u00edlio civil<\/em><\/strong>.<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; De outro lado, n\u00e3o se pode olvidar que, nos termos do art. 10 da LINDB, a sucess\u00e3o por morte ou por aus\u00eancia obedece \u00e0 lei do pa\u00eds em que domiciliado o falecido, qualquer que seja a natureza e a situa\u00e7\u00e3o dos bens, devendo, contudo, tal regra ser analisada e interpretada sistematicamente, em conjunto com as demais normas internas que regulam o tema, em especial o arts. 8\u00ba, caput, e 12, \u00a7 1\u00ba, da LINDB.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Al\u00e9m disso, o art. 23, II, do CPC\/2015 prev\u00ea a compet\u00eancia exclusiva da autoridade brasileira em mat\u00e9ria de sucess\u00e3o heredit\u00e1ria, cabendo a ela proceder \u00e0 confirma\u00e7\u00e3o de testamento particular e ao invent\u00e1rio e \u00e0 partilha de bens situados no Brasil, ainda que o autor da heran\u00e7a seja de nacionalidade estrangeira ou tenha domic\u00edlio fora do territ\u00f3rio nacional.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Observa-se que, na hip\u00f3tese de haver bens im\u00f3veis a inventariar situados, simultaneamente, aqui e no exterior, o Brasil adota o princ\u00edpio da PLURALIDADE dos ju\u00edzos sucess\u00f3rios; no entanto, compete \u00e0 autoridade judici\u00e1ria brasileira, com exclus\u00e3o de qualquer outra, conhecer e julgar a\u00e7\u00f5es relativas a bens aqui situados.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Assim, o STJ entende que &#8220;apenas no que diz respeito aos bens im\u00f3veis situados no Brasil, invi\u00e1vel a homologa\u00e7\u00e3o da partilha efetuada pela autoridade estrangeira, pois, nos termos do art. 89, I, do CPC\/73, em vigor quando da prola\u00e7\u00e3o da senten\u00e7a estrangeira, a partilha dos bens im\u00f3veis situados no Brasil apenas pode ser feita pela autoridade judici\u00e1ria brasileira, com a exclus\u00e3o de qualquer outra&#8221; (HDE n. 176\/EX, Rel. Min. Benedito Gon\u00e7alves, Corte Especial, julgado em 15\/8\/2018, DJe 21\/8\/2018).<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Dessa maneira, a partilha de eventuais bens situados no Pa\u00eds \u00e9 de compet\u00eancia exclusiva da autoridade judicial brasileira, ou seja, o pleito de peti\u00e7\u00e3o de heran\u00e7a em rela\u00e7\u00e3o aos bens situados no Brasil est\u00e1 dentro dos limites da jurisdi\u00e7\u00e3o nacional.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Por conseguinte, verifica-se a necessidade de se DIFERENCIAR os pedidos autorais, reconhecendo-se a jurisdi\u00e7\u00e3o brasileira para o pleito de peti\u00e7\u00e3o de heran\u00e7a, mas afast\u00e1-la quanto ao pedido de investiga\u00e7\u00e3o de paternidade.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Isso porque, mesmo diante da aus\u00eancia de jurisdi\u00e7\u00e3o brasileira sobre o pedido de investiga\u00e7\u00e3o de paternidade, \u00e9 poss\u00edvel o processamento e o julgamento do pleito de peti\u00e7\u00e3o de heran\u00e7a pela autoridade judici\u00e1ria nacional, discutindo-se, na causa de pedir, a efetiva paternidade do falecido e a viola\u00e7\u00e3o do direito heredit\u00e1rio.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Em face disso, torna-se imperioso o reconhecimento de que o pleito de declara\u00e7\u00e3o da paternidade se encontra fora dos limites da jurisdi\u00e7\u00e3o nacional, o que implica &#8211; quanto a esse pedido &#8211; a extin\u00e7\u00e3o do processo, sem resolu\u00e7\u00e3o do m\u00e9rito, nos termos do art. 485, IV, do CPC\/2015, cabendo, todavia, \u00e0 autoridade judicial brasileira processar e julgar a peti\u00e7\u00e3o de heran\u00e7a sobre os bens aqui situados.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-9-3-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-da-decisao\"><a><\/a><a>9.3.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Da DECIS\u00c3O.<\/a><\/h3>\n\n\n\n<p>O pedido de investiga\u00e7\u00e3o de paternidade feito por estrangeiro n\u00e3o domiciliado no Brasil encontra-se fora dos limites da jurisdi\u00e7\u00e3o nacional, contudo \u00e9 poss\u00edvel o julgamento de peti\u00e7\u00e3o de heran\u00e7a pela autoridade judici\u00e1ria brasileira, discutindo-se, na causa de pedir, a efetiva paternidade do falecido e a viola\u00e7\u00e3o do direito heredit\u00e1rio.<\/p>\n\n\n\n<p>Processo em segredo de justi\u00e7a, Rel. Ministro Marco Aur\u00e9lio Bellizze, Terceira Turma, por unanimidade, julgado em 20\/8\/2024, DJe 23\/8\/2024 (Info Extraordin\u00e1rio 23)<\/p>\n\n\n\n<h1 class=\"wp-block-heading\" id=\"h-direito-civil\"><a><\/a><a>DIREITO<\/a> CIVIL<\/h1>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-10-nbsp-contratos-de-cessao-de-direitos-autorais-patrimoniais-utilizacao-das-obras-musicais-em-formato-digital-streaming\"><a>10.&nbsp; Contratos de cess\u00e3o de direitos autorais patrimoniais. Utiliza\u00e7\u00e3o das obras musicais em formato digital. Streaming.<\/a><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-10-1-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-dos-fatos\"><a><\/a><a>10.1.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Dos FATOS.<\/a><\/h3>\n\n\n\n<p>Nos anos 80, a banda de rock \u201cOs Esquecidos\u201d assinou um contrato de cess\u00e3o de direitos autorais sem imaginar que, d\u00e9cadas depois, suas m\u00fasicas estariam bombando no streaming. Agora, os m\u00fasicos queriam impedir que suas can\u00e7\u00f5es sejam exploradas sem nova autoriza\u00e7\u00e3o, alegando que o contrato n\u00e3o previa esse tipo de uso.<\/p>\n\n\n\n<p>A gravadora, por outro lado, argumenta que a cess\u00e3o era ampla e que a evolu\u00e7\u00e3o tecnol\u00f3gica n\u00e3o limitava a explora\u00e7\u00e3o comercial das obras.<\/p>\n\n\n\n<p>A <strong><em>x<\/em><\/strong> da quest\u00e3o \u00e9: contratos antigos podem restringir a explora\u00e7\u00e3o de novas tecnologias que sequer existiam na \u00e9poca?<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-10-2-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-analise-estrategica\"><a><\/a><a>10.2.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; An\u00e1lise ESTRAT\u00c9GICA.<\/a><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-10-2-1-do-direito\">10.2.1. Do DIREITO.<\/h4>\n\n\n\n<p>Lei n. 9.610\/1998, art. 29, VII, VIII, i, IX e X e art. 49, V<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-10-2-2-dos-fundamentos\">10.2.2. Dos FUNDAMENTOS.<\/h4>\n\n\n\n<p>Cinge-se a controv\u00e9rsia a verificar a necessidade ou n\u00e3o de autoriza\u00e7\u00e3o espec\u00edfica para explora\u00e7\u00e3o econ\u00f4mica de obras musicais via streaming.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Os contratos usualmente celebrados por titulares de direitos autorais s\u00e3o os de cess\u00e3o e os de edi\u00e7\u00e3o. Enquanto os primeiros se caracterizam por implicar a transfer\u00eancia dos direitos patrimoniais do autor (definitiva ou tempor\u00e1ria, total ou parcial), os segundos s\u00e3o aqueles pelos quais o contratante (editor) assume a obriga\u00e7\u00e3o de publicar ou fazer publicar obra art\u00edstica, tendo como principal caracter\u00edstica a sua dura\u00e7\u00e3o limitada (seja quanto ao tempo de vig\u00eancia seja quanto ao n\u00famero de edi\u00e7\u00f5es que ser\u00e3o objeto de publica\u00e7\u00e3o).<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; A diferen\u00e7a fundamental entre contratos de cess\u00e3o e de edi\u00e7\u00e3o, portanto, \u00e9 que, &#8220;Na cess\u00e3o, os direitos patrimoniais do autor s\u00e3o transferidos com poucas reservas, na edi\u00e7\u00e3o, o autor autoriza o editor a publicar a obra com tiragem de exemplares e tempo definidos no contrato&#8221; (REsp 2.148.396\/RJ, DJe 6\/9\/2024).<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; A jurisprud\u00eancia do STJ se firmou no sentido de que a tecnologia streaming enquadra-se nas disposi\u00e7\u00f5es normativas do art. 29, VII, VIII, i, IX e X, da Lei n. 9.610\/1998, configurando, portanto, modalidade de explora\u00e7\u00e3o econ\u00f4mica das obras musicais a demandar autoriza\u00e7\u00e3o pr\u00e9via e expressa pelos titulares dos direitos autorais.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Desse modo, tal forma de utiliza\u00e7\u00e3o das obras musicais, em princ\u00edpio, necessitariam de sua autoriza\u00e7\u00e3o espec\u00edfica.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Ademais, conforme previsto no <strong>art. 49, V, da atual Lei de Direitos Autorais<\/strong>, a cess\u00e3o a terceiros &#8220;s\u00f3 se operar\u00e1 para modalidades de utiliza\u00e7\u00e3o j\u00e1 existentes \u00e0 data do contrato&#8221;.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Ocorre que a prote\u00e7\u00e3o espec\u00edfica conferida pelo art. 49, V, da Lei n. 9.610\/1998, n\u00e3o estava presente no ordenamento jur\u00eddico anteriormente \u00e0 edi\u00e7\u00e3o desse diploma legal, de modo que, em raz\u00e3o do princ\u00edpio da irretroatividade da lei, afigura-se <em>invi\u00e1vel a aplica\u00e7\u00e3o de suas disposi\u00e7\u00f5es a contratos celebrados antes de sua vig\u00eancia<\/em>.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Assim &#8211; e em conformidade com o quanto decidido no julgamento do REsp 2.148.396\/RJ -, &#8220;inexistindo nos diplomas legais vigentes \u00e0 \u00e9poca da celebra\u00e7\u00e3o dos instrumentos disposi\u00e7\u00f5es legais com conte\u00fado normativo assemelhado ao previsto no art. 49, V, da Lei n. 9.610\/1998 e ausentes outras restri\u00e7\u00f5es \u00e0 liberdade dos contratantes de dispor sobre direitos no momento da celebra\u00e7\u00e3o dos contratos, poss\u00edvel a explora\u00e7\u00e3o das obras cedidas pela modalidade de utiliza\u00e7\u00e3o streaming pela cession\u00e1ria&#8221;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-10-3-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-da-decisao\"><a><\/a><a>10.3.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Da DECIS\u00c3O.<\/a><\/h3>\n\n\n\n<p>A prote\u00e7\u00e3o conferida pelo art. 49, V, da Lei n. 9.610\/1998, no sentido de que &#8220;a cess\u00e3o s\u00f3 se operar\u00e1 para modalidades de utiliza\u00e7\u00e3o j\u00e1 existentes \u00e0 data do contrato&#8221;, n\u00e3o se aplica a contratos celebrados antes de sua vig\u00eancia.<\/p>\n\n\n\n<p>REsp 2.029.976-SP, Rel. Ministra Nancy Andrighi, Terceira Turma, por unanimidade, julgado em 12\/11\/2024, DJe 14\/11\/2024 (Info Extraordin\u00e1rio 23)<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-11-nbsp-divida-de-fies-destinacao-a-familia-ou-ao-patrimonio-comum-reversao-a-familia-apenas-futura-indireta-e-hipotetica\"><a>11.&nbsp; D\u00edvida de FIES. Destina\u00e7\u00e3o \u00e0 fam\u00edlia ou ao patrim\u00f4nio comum. Revers\u00e3o \u00e0 fam\u00edlia apenas futura, indireta e hipot\u00e9tica.<\/a><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-11-1-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-dos-fatos\"><a><\/a><a>11.1.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Dos FATOS.<\/a><\/h3>\n\n\n\n<p>Depois de anos de namoro e um breve casamento, Creitinho e Gertrudes decidiram seguir caminhos separados. Na partilha dos bens, Gertrudes exigia que a d\u00edvida do FIES de sua faculdade fosse dividida entre os dois, alegando que o benef\u00edcio da forma\u00e7\u00e3o dela era comum \u00e0 \u00e9poca.<\/p>\n\n\n\n<p>Creitinho retrucou dizendo que o diploma n\u00e3o era um bem compartilh\u00e1vel e que a d\u00edvida do financiamento estudantil era exclusivamente dela.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-11-2-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-analise-estrategica\"><a><\/a><a>11.2.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; An\u00e1lise ESTRAT\u00c9GICA.<\/a><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-11-2-1-dos-fundamentos\">11.2.1. Dos FUNDAMENTOS.<\/h4>\n\n\n\n<p>Cinge-se a controv\u00e9rsia em definir se seria comunic\u00e1vel e partilh\u00e1vel a d\u00edvida originada do FIES &#8211; Fundo de Financiamento Estudantil.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; O financiamento estudantil contra\u00eddo por um dos c\u00f4njuges, como o FIES, possui natureza personal\u00edssima e N\u00c3O deve ser objeto de partilha por ocasi\u00e3o da dissolu\u00e7\u00e3o do v\u00ednculo conjugal ou convivencial, na medida em que o investimento em educa\u00e7\u00e3o realizado apenas por um dos c\u00f4njuges ou conviventes (e a respectiva d\u00edvida) apenas gera a perspectiva futura e eventual de que esse investimento poderia ser diretamente revertido em benef\u00edcio da entidade familiar.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; O financiamento estudantil \u00e9 um meio para a obten\u00e7\u00e3o de melhoria na vida de quem dele usufrui sob as \u00f3ticas profissional, pessoal, social e cultural, de modo que o benefici\u00e1rio do conhecimento adquirido na atividade de ensino financiada ser\u00e1 exclusivamente o c\u00f4njuge ou <em>convivente que efetivamente realizou a atividade educacional, que inclusive levar\u00e1 consigo o conhecimento adquirido<\/em> ap\u00f3s a dissolu\u00e7\u00e3o do v\u00ednculo conjugal ou convivencial.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; O benef\u00edcio apenas mediato e hipot\u00e9tico causado pela atividade estudantil financiada, por n\u00e3o implicar em benef\u00edcio direto e concreto \u00e0 entidade familiar, n\u00e3o deve ser partilhado por ocasi\u00e3o do div\u00f3rcio ou dissolu\u00e7\u00e3o da uni\u00e3o est\u00e1vel.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-11-3-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-da-decisao\"><a><\/a><a>11.3.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Da DECIS\u00c3O.<\/a><\/h3>\n\n\n\n<p>A d\u00edvida oriunda do FIES &#8211; Fundo de Financiamento Estudantil, possui natureza personal\u00edssima e n\u00e3o deve ser objeto de partilha por ocasi\u00e3o da dissolu\u00e7\u00e3o do v\u00ednculo conjugal ou convivencial.<\/p>\n\n\n\n<p>Processo em segredo de justi\u00e7a, Rel. Ministra Nancy Andrighi, Terceira Turma, por unanimidade, julgado em 5\/11\/2024, DJe 8\/11\/2024 (Info Extraordin\u00e1rio 23)<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-12-nbsp-hipoteca-imovel-residencial-nao-adquirido-com-recursos-oriundos-do-sfh-sumula-308-do-stj\"><a>12.&nbsp; Hipoteca. Im\u00f3vel residencial n\u00e3o adquirido com recursos oriundos do SFH. S\u00famula 308 do STJ<\/a><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-12-1-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-dos-fatos\"><a><\/a><a>12.1.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Dos FATOS.<\/a><\/h3>\n\n\n\n<p>Genov\u00e9vio comprou um apartamento e estava feliz da vida at\u00e9 descobrir que o im\u00f3vel estava hipotecado por uma d\u00edvida da construtora com o banco. O banco queria cobrar a d\u00edvida, afirmando que a garantia hipotec\u00e1ria era v\u00e1lida independentemente da venda. Genov\u00e9vio, por sua vez, sustentava que, como comprador de boa-f\u00e9, n\u00e3o deveria ser prejudicado por um neg\u00f3cio entre terceiros. Pode um comprador pode ser for\u00e7ado a assumir uma d\u00edvida hipotec\u00e1ria que n\u00e3o foi dele?<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-12-2-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-analise-estrategica\"><a><\/a><a>12.2.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; An\u00e1lise ESTRAT\u00c9GICA.<\/a><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-12-2-1-do-direito\">12.2.1. Do DIREITO.<\/h4>\n\n\n\n<p>S\u00famula n. 308 do STJ.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-12-2-2-dos-fundamentos\">12.2.2. Dos FUNDAMENTOS.<\/h4>\n\n\n\n<p>Cinge-se a controv\u00e9rsia em saber se, nos termos da S\u00famula n. 308 do STJ, a hipoteca firmada entre a construtora e o agente financeiro, anterior ou posterior \u00e0 celebra\u00e7\u00e3o do contrato de promessa de compra e venda, teria efic\u00e1cia perante os adquirentes de im\u00f3vel n\u00e3o inserido no Sistema Financeiro de Habita\u00e7\u00e3o &#8211; SFH.<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td>&nbsp;&nbsp;&nbsp;&nbsp; Conforme entendimento do Superior Tribunal de Justi\u00e7a, consolidado na S\u00famula 308, a hipoteca firmada entre a construtora e o agente financeiro N\u00c3O tem efic\u00e1cia perante os adquirentes do im\u00f3vel. Nesse contexto, importa ressaltar que a jurisprud\u00eancia n\u00e3o diferencia a hip\u00f3tese, se anterior ou posterior \u00e0 celebra\u00e7\u00e3o do contrato, para considerar o gravame ineficaz.<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Observa-se, ainda, que, de acordo com a atual jurisprud\u00eancia, <strong>o &#8220;fato de o compromisso de compra e venda de im\u00f3vel residencial n\u00e3o ser regulado pelas normas do Sistema Financeiro da Habita\u00e7\u00e3o n\u00e3o afasta a incid\u00eancia da S\u00famula 308\/STJ<\/strong>&#8221; (AgInt no REsp n. 2.119.978\/SE, relator Ministro Marco Aur\u00e9lio Bellizze, Terceira Turma, julgado em 12\/8\/2024, DJe de 15\/8\/2024).<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Assim, o entendimento do STJ \u00e9 no sentido de &#8220;n\u00e3o admitir que o financiamento banc\u00e1rio com garantia de hipoteca, sob qualquer forma de contrata\u00e7\u00e3o, impe\u00e7a que o adquirente da unidade imobili\u00e1ria quitada tenha acesso \u00e0 escritura p\u00fablica do im\u00f3vel, \u00e0 transfer\u00eancia do bem para seu nome e \u00e0 baixa da hipoteca&#8221; (AgInt no REsp n. 1.935.088\/PB, relator Ministro Luis Felipe Salom\u00e3o, Quarta Turma, julgado em 14\/12\/2021, DJe de 22\/4\/2022).<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-12-3-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-da-decisao\"><a><\/a><a>12.3.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Da DECIS\u00c3O.<\/a><\/h3>\n\n\n\n<p>O fato de o compromisso de compra e venda de im\u00f3vel residencial n\u00e3o ser regulado pelas normas do Sistema Financeiro da Habita\u00e7\u00e3o (SFH) n\u00e3o afasta a incid\u00eancia da S\u00famula 308 do STJ.<\/p>\n\n\n\n<p>AgInt nos EDcl no REsp 1.992.417-AL, Rel. Ministro Humberto Martins, Terceira Turma, por unanimidade, julgado em 21\/10\/2024, DJe 25\/10\/2024 (Info Extraordin\u00e1rio 23)<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-13-nbsp-pedido-de-divorcio-morte-superveniente-do-autor-da-acao\"><a>13.&nbsp; Pedido de div\u00f3rcio. Morte superveniente do autor da a\u00e7\u00e3o<\/a><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-13-1-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-dos-fatos\"><a><\/a><a>13.1.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Dos FATOS.<\/a><\/h3>\n\n\n\n<p>Clara entrou com pedido de div\u00f3rcio, mas faleceu antes que o processo fosse conclu\u00eddo. O ex-marido, sustentava que, sem a senten\u00e7a, o casamento continuava v\u00e1lido para fins sucess\u00f3rios.<\/p>\n\n\n\n<p>Os filhos e herdeiros alegavam, por outro lado, que a vontade de Clara j\u00e1 era clara: ela queria o div\u00f3rcio, e a morte n\u00e3o deveria mudar isso. E assim surge a quest\u00e3o: o div\u00f3rcio precisa de uma senten\u00e7a formal para valer, ou basta a vontade da parte?<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-13-2-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-analise-estrategica\"><a><\/a><a>13.2.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; An\u00e1lise ESTRAT\u00c9GICA.<\/a><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-13-2-1-do-direito\">13.2.1. Do DIREITO.<\/h4>\n\n\n\n<p>Constitui\u00e7\u00e3o Federal (CF), art. 226, \u00a7 6\u00ba<\/p>\n\n\n\n<p>C\u00f3digo Civil (CC), art. 1.571, \u00a7 1\u00ba<\/p>\n\n\n\n<p>C\u00f3digo de Processo Civil (CPC) art. 355 e art. 356<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-13-2-2-dos-fundamentos\">13.2.2. Dos FUNDAMENTOS.<\/h4>\n\n\n\n<p>O \u00a7 1\u00ba do art. 1.571 do C\u00f3digo Civil disp\u00f5e que &#8220;o casamento v\u00e1lido s\u00f3 se dissolve pela morte de um dos c\u00f4njuges ou pelo div\u00f3rcio (&#8230;)&#8221;. Assim, a ocorr\u00eancia de qualquer um desses fatos &#8211; morte ou div\u00f3rcio &#8211; p\u00f5e fim ao casamento. Contudo, a quest\u00e3o deixa de ser t\u00e3o simples quando os dois eventos &#8211; morte e div\u00f3rcio &#8211; apresentam-se.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; No caso de origem, o Tribunal local concluiu que, a despeito do div\u00f3rcio antecipadamente reconhecido, a causa de extin\u00e7\u00e3o do casamento foi, ao final, a morte do c\u00f4njuge autor da a\u00e7\u00e3o, revogando a liminar anteriormente concedida.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Entretanto, as consequ\u00eancias jur\u00eddicas dessa op\u00e7\u00e3o, a prevalecer uma ou outra forma de extin\u00e7\u00e3o do casamento, s\u00e3o t\u00e3o distintas &#8211; notadamente nos campos previdenci\u00e1rio e sucess\u00f3rio &#8211; que o tema exige um exame acurado e, sobretudo, um tratamento jurisprudencial uniforme.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; A posi\u00e7\u00e3o adotada pela Corte local segue o entendimento que predominou por muito tempo na doutrina e na jurisprud\u00eancia. Contudo, o advento da Emenda Constitucional n. 66\/2010, que alterou a reda\u00e7\u00e3o do \u00a7 6\u00ba do art. 226 da Constitui\u00e7\u00e3o Federal, trazendo o que a doutrina chama de uma &#8220;completa mudan\u00e7a de paradigma&#8221;.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; A aludida altera\u00e7\u00e3o constitucional dispensou qualquer requisito pr\u00e9vio para a extin\u00e7\u00e3o do casamento, al\u00e9m da vontade da pessoa casada de p\u00f4r fim \u00e0 rela\u00e7\u00e3o, posicionando o instituto na categoria dos chamados &#8220;direitos potestativos&#8221;. Portanto, a dissolu\u00e7\u00e3o do casamento passou a depender, unicamente, da v\u00e1lida manifesta\u00e7\u00e3o da vontade de um dos c\u00f4njuges de n\u00e3o mais permanecer casado. Nesse contexto, <strong>n\u00e3o h\u00e1 mais raz\u00e3o para que os efeitos da manifesta\u00e7\u00e3o de vontade da parte de dissolver o v\u00ednculo fiquem atrelados \u00e0 senten\u00e7a definitiva<\/strong>.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Dessa forma, ainda que n\u00e3o haja consenso entre as partes no que se refere \u00e0s consequ\u00eancias do fim da rela\u00e7\u00e3o, e o div\u00f3rcio seja caracterizado como &#8220;litigioso&#8221;, <em>fato \u00e9 que o lit\u00edgio n\u00e3o recai sobre o div\u00f3rcio em si, mas sobre as demais quest\u00f5es dele decorrentes<\/em>, como as de cunho patrimonial (partilha, alimentos) e as de organiza\u00e7\u00e3o da filia\u00e7\u00e3o (guarda, regime de visitas etc.).<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; N\u00e3o havendo, portanto, possibilidade de &#8220;lit\u00edgio&#8221; (controv\u00e9rsia) em torno da extin\u00e7\u00e3o do v\u00ednculo em si, o div\u00f3rcio pode (e deve) ser reconhecido imediatamente, com fundamento nos arts. 355 ou 356 do CPC (a depender de haver ou n\u00e3o necessidade de prosseguimento do feito para decidir outras quest\u00f5es), mediante decis\u00e3o de m\u00e9rito, de cogni\u00e7\u00e3o exauriente, cujos efeitos passam a surtir desde logo.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Nessas situa\u00e7\u00f5es, portanto, caso o autor venha a falecer no curso do processo, o seu estado civil j\u00e1 ter\u00e1 sido alterado para divorciado, n\u00e3o cabendo mais cogitar de eventual viuvez. Mas, se, eventualmente, nenhuma dessas provid\u00eancias tenha sido tomada, e o autor da a\u00e7\u00e3o de div\u00f3rcio venha a falecer antes de qualquer decis\u00e3o acerca do seu pedido, ainda assim o div\u00f3rcio poder\u00e1 ser reconhecido, pois a manifesta\u00e7\u00e3o de vontade \u00e9 o que basta para tanto.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Assim, \u00e9 poss\u00edvel afirmar que n\u00e3o se mostra adequada a extin\u00e7\u00e3o da a\u00e7\u00e3o de div\u00f3rcio pela morte do autor sem antes se apreciar o pleito de dissolu\u00e7\u00e3o do v\u00ednculo, conforme a vontade por ele expressada. Nessa linha, o enunciado n\u00ba 45 do IBDFAM: &#8220;A a\u00e7\u00e3o de div\u00f3rcio j\u00e1 ajuizada n\u00e3o dever\u00e1 ser extinta sem resolu\u00e7\u00e3o de m\u00e9rito, em caso do falecimento de uma das partes&#8221;.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Ademais, a possibilidade de reconhecimento do div\u00f3rcio ap\u00f3s a morte tamb\u00e9m foi incorporada na proposta de Reforma do C\u00f3digo Civil apresentada por comiss\u00e3o de juristas ao Senado Federal, em abril de 2024. Segundo o relat\u00f3rio, o \u00a7 4\u00ba do art. 1.571 do C\u00f3digo Civil passaria a ter a seguinte reda\u00e7\u00e3o: &#8220;O falecimento de um dos c\u00f4njuges ou conviventes, depois da propositura da a\u00e7\u00e3o de div\u00f3rcio ou de dissolu\u00e7\u00e3o da uni\u00e3o est\u00e1vel, n\u00e3o enseja a extin\u00e7\u00e3o do processo, podendo os herdeiros prosseguir com a demanda, retroagindo os efeitos da senten\u00e7a \u00e0 data estabelecida na senten\u00e7a como aquela do final do conv\u00edvio&#8221;.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Sendo assim, conclui-se que, ainda que n\u00e3o haja, por ora, legisla\u00e7\u00e3o espec\u00edfica a respeito, a natureza do direito material posto em ju\u00edzo implica a preval\u00eancia da vontade livremente manifestada em vida sobre a morte na defini\u00e7\u00e3o da causa da dissolu\u00e7\u00e3o do casamento.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-13-3-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-da-decisao\"><a><\/a><a>13.3.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Da DECIS\u00c3O.<\/a><\/h3>\n\n\n\n<p>Se o pedido de div\u00f3rcio n\u00e3o for apreciado e a parte autora falecer durante o processo, o reconhecimento da dissolu\u00e7\u00e3o do v\u00ednculo poder\u00e1 ser realizado postumamente.<\/p>\n\n\n\n<p>Processo em segredo de justi\u00e7a, Rel. Ministro Ricardo Villas B\u00f4as Cueva, Terceira Turma, por unanimidade, julgado em 27\/8\/2024, DJe 30\/8\/2024 (Info Extraordin\u00e1rio 23)<\/p>\n\n\n\n<h1 class=\"wp-block-heading\" id=\"h-direito-da-crianca-e-do-adolescente\"><a>DIREITO DA CRIAN\u00c7A E DO ADOLESCENTE<\/a><\/h1>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-14-nbsp-habeas-corpus-em-acao-de-destituicao-de-poder-familiar-nao-configuracao-de-violacao-a-direito-de-locomocao-nem-sequer-por-via-reflexa-inadequacao-da-via\"><a>14.&nbsp; Habeas corpus em a\u00e7\u00e3o de destitui\u00e7\u00e3o de poder familiar. N\u00e3o configura\u00e7\u00e3o de viola\u00e7\u00e3o a direito de locomo\u00e7\u00e3o, nem sequer por via reflexa. Inadequa\u00e7\u00e3o da via.<\/a><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-14-1-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-dos-fatos\"><a>14.1.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Dos FATOS.<\/a><\/h3>\n\n\n\n<p>Belinha, crian\u00e7a em tenra idade, foi retirada dos pais por alegada neglig\u00eancia e colocada em fam\u00edlia substituta. Algum tempo depois, uma prima da m\u00e3e biol\u00f3gica apareceu, pedindo a guarda e alegando la\u00e7os familiares. N\u00e3o logrando \u00eaxito em suas intentadas por outras vias e vendo o processo de ado\u00e7\u00e3o andar em seu desfavor, a prima impetrou <em>habeas corpus<\/em> para tentar reverter a situa\u00e7\u00e3o. Mas pode o <em>habeas corpus<\/em> ser usado para questionar uma decis\u00e3o de guarda e ado\u00e7\u00e3o?<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-14-2-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-analise-estrategica\"><a>14.2.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; An\u00e1lise ESTRAT\u00c9GICA.<\/a><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-14-2-1-dos-fundamentos\">14.2.1. Dos FUNDAMENTOS.<\/h4>\n\n\n\n<p>Na origem, o Minist\u00e9rio P\u00fablico estadual ajuizou a\u00e7\u00e3o de destitui\u00e7\u00e3o de poder familiar contra os genitores da crian\u00e7a, visando a prote\u00e7\u00e3o integral da filha, que estava em situa\u00e7\u00e3o de risco sob os cuidados deles. Ap\u00f3s a instru\u00e7\u00e3o do feito, foi julgado procedente o pedido do Minist\u00e9rio P\u00fablico estadual de destitui\u00e7\u00e3o do poder familiar dos genitores da infante, com determina\u00e7\u00e3o de deflagra\u00e7\u00e3o de procedimento de ado\u00e7\u00e3o.<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td>O habeas corpus N\u00c3O \u00e9 a via adequada para impugnar ac\u00f3rd\u00e3o que indeferiu pedido de convers\u00e3o de julgamento de apela\u00e7\u00e3o em dilig\u00eancia para fins de aferi\u00e7\u00e3o da capacidade de terceira interessada (prima da genitora) de cuidar da infante, pois tal ato judicial n\u00e3o repercute, nem sequer indiretamente, no seu direito de ir e vir.<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p>&nbsp;&nbsp; N\u00e3o \u00e9 do melhor interesse da infante que estava em situa\u00e7\u00e3o de risco sob os cuidados da genitora, que se acha inserida num cen\u00e1rio de uso de drogas il\u00edcitas e de ingest\u00e3o de bebidas alco\u00f3licas, de instabilidade emocional\/ps\u00edquica e que n\u00e3o adere aos tratamentos j\u00e1 disponibilizados pela rede de assist\u00eancia, o retardamento no julgamento da apela\u00e7\u00e3o contra senten\u00e7a de destitui\u00e7\u00e3o de poder familiar, com a convers\u00e3o do julgamento em dilig\u00eancia, para aferir se parente de sua genitora, que se mostrou indecisa quanto a pretens\u00e3o de criar da crian\u00e7a, tem capacidade e condi\u00e7\u00f5es para dela cuidar.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; A not\u00f3ria inviabilidade de manuten\u00e7\u00e3o do poder familiar reclama que, pelo menos, sejam tomadas provid\u00eancias para o in\u00edcio de coloca\u00e7\u00e3o da crian\u00e7a em fam\u00edlia substituta, ainda que n\u00e3o tenha havido o tr\u00e2nsito em julgado da senten\u00e7a.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; O pr\u00f3prio art. 163 do ECA disp\u00f5e que o <em>procedimento para a perda e suspens\u00e3o do poder familiar dever\u00e1 ser conclu\u00eddo no prazo m\u00e1ximo de 120 <\/em>dias, e que caber\u00e1 ao Juiz, no caso de not\u00f3ria inviabilidade de manuten\u00e7\u00e3o do poder familiar, dirigir esfor\u00e7os para preparar a crian\u00e7a com vistas \u00e0 coloca\u00e7\u00e3o em fam\u00edlia substituta.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Ademais, a Resolu\u00e7\u00e3o do Conselho Nacional de Justi\u00e7a &#8211; CNJ n. 289, de 14\/8\/2019, que disp\u00f5e sobre a implanta\u00e7\u00e3o e funcionamento do Sistema Nacional de Ado\u00e7\u00e3o e Acolhimento &#8211; SNA, no seu anexo I, que disp\u00f5e sobre a regulamenta\u00e7\u00e3o t\u00e9cnica, prev\u00ea nos seus arts. 3\u00ba e 4\u00ba que: &#8220;A coloca\u00e7\u00e3o de crian\u00e7a ou do adolescente na situa\u00e7\u00e3o &#8216;apta para ado\u00e7\u00e3o&#8217; dever\u00e1 ocorrer ap\u00f3s o tr\u00e2nsito em julgado do processo de destitui\u00e7\u00e3o ou extin\u00e7\u00e3o do poder familiar, ou ainda quando a crian\u00e7a ou o adolescente for \u00f3rf\u00e3o ou tiver ambos os genitores desconhecidos.&#8221;, sendo que &#8220;O juiz poder\u00e1, no melhor interesse da crian\u00e7a ou do adolescente, determinar a inclus\u00e3o cautelar na situa\u00e7\u00e3o &#8216;apta para ado\u00e7\u00e3o&#8217; antes do tr\u00e2nsito em julgado da decis\u00e3o que destitui ou extingue o poder familiar, hip\u00f3tese em que o pretendente dever\u00e1 ser informado sobre o risco jur\u00eddico.&#8221;.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Como foi dito no julgamento no Habeas Corpus n. 775.298\/MG pela Terceira Turma do Superior Tribunal de Justi\u00e7a- STJ, o tempo das crian\u00e7as \u00e9 diferente do tempo do processo, n\u00e3o podendo a situa\u00e7\u00e3o da crian\u00e7a de tenra idade ficar submetida \u00e0 indecis\u00e3o de parente da genitora que ora quer e ora n\u00e3o quer sua guarda e nem se deu ao trabalho de ajuizar a\u00e7\u00e3o com este escopo.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; H\u00e1 entendimento jurisprudencial no \u00e2mbito da Terceira Turma do STJ, no sentido de que <strong>o princ\u00edpio da prioridade da fam\u00edlia natural sofre flexibiliza\u00e7\u00e3o a depender do caso concreto<\/strong>, devendo ser observado sempre o melhor interesse da crian\u00e7a ou do adolescente, havendo uma relativa prioridade da fam\u00edlia natural ou extensa.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Al\u00e9m disso, a jurisprud\u00eancia do STJ firmou o entendimento de que, em se tratando de quest\u00f5es atinentes a guarda e direito de visita\u00e7\u00e3o de filhos menores, ou seja, temas pr\u00f3prios de Direito de Fam\u00edlia, \u00e9 inadequada a utiliza\u00e7\u00e3o do habeas corpus para a defesa de tais interesses, sobretudo nessa via estreita que \u00e9 invi\u00e1vel a incurs\u00e3o aprofundada nos elementos probat\u00f3rios, entendimento que se aplica tamb\u00e9m na hip\u00f3tese de destitui\u00e7\u00e3o de poder familiar.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Nesse cen\u00e1rio, crian\u00e7a desabrigada ap\u00f3s razo\u00e1vel tempo e acolhida pela fam\u00edlia substituta h\u00e1 pelo menos 6 (seis) meses, n\u00e3o merece os transtornos de nova modifica\u00e7\u00e3o de sua guarda f\u00e1tica.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Por isso, ocorrendo o desabrigamento institucional da crian\u00e7a e iniciado o processo de conviv\u00eancia com a fam\u00edlia substituta, o habeas corpus n\u00e3o deve ser utilizado como suced\u00e2neo de recurso pr\u00f3prio, sob pena de desvirtuar a finalidade de sua garantia constitucional, n\u00e3o podendo ser manejado quando inexiste ato judicial capaz de causar ofensa ou amea\u00e7a, ainda que indireta, \u00e0 liberdade de locomo\u00e7\u00e3o.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-14-3-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-da-decisao\"><a>14.3.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Da DECIS\u00c3O.<\/a><\/h3>\n\n\n\n<p>O habeas corpus n\u00e3o \u00e9 a via adequada para impugnar ac\u00f3rd\u00e3o que indeferiu pedido de convers\u00e3o de julgamento em dilig\u00eancia para fins de realiza\u00e7\u00e3o de estudo psicossocial, objetivando aferir a aptid\u00e3o de terceiro interessado para o exerc\u00edcio de guarda, tendo em vista que crian\u00e7a desabrigada ap\u00f3s razo\u00e1vel tempo e acolhida em fam\u00edlia substituta n\u00e3o merece os transtornos de nova modifica\u00e7\u00e3o de sua guarda f\u00e1tica.<\/p>\n\n\n\n<p>Processo em segredo de justi\u00e7a, Rel. Ministro Moura Ribeiro, Terceira Turma, por unanimidade, julgado em 12\/11\/2024, DJe 19\/11\/2024 (Info Extraordin\u00e1rio 23)<\/p>\n\n\n\n<h1 class=\"wp-block-heading\" id=\"h-direito-empresarial\"><a>DIREITO EMPRESARIAL<\/a><\/h1>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-15-nbsp-cessao-fiduciaria-de-credito-recebiveis-garantias-de-credito-referencia-feita-no-contrato-como-aquelas-que-genericamente-aparecem-no-bordero-inexistencia-de-qualquer-grau-de-determinacao-necessidade-de-indicacao-do-credito\"><a>15.&nbsp; Cess\u00e3o fiduci\u00e1ria de cr\u00e9dito receb\u00edveis. Garantias de cr\u00e9dito Refer\u00eancia feita no contrato como aquelas que genericamente aparecem no &#8220;border\u00f4&#8221;. Inexist\u00eancia de qualquer grau de determina\u00e7\u00e3o. Necessidade de indica\u00e7\u00e3o do cr\u00e9dito<\/a><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-15-1-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-dos-fatos\"><a>15.1.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Dos FATOS.<\/a><\/h3>\n\n\n\n<p>A empresa de transportes Expresso Seca Velha tomou um empr\u00e9stimo alto e deu como garantia receb\u00edveis de cart\u00f5es de cr\u00e9dito. O banco credor, quando a empresa entrou em dificuldades, tentou executar os valores que estavam em um \u201cborder\u00f4\u201d gen\u00e9rico. O problema? O documento n\u00e3o especificava quais bens eram objetos da garantia. A Expresso Seca Velha alega que essa generalidade torna sem efeito a aliena\u00e7\u00e3o fiduci\u00e1ria.<\/p>\n\n\n\n<p>O banco, por outro lado, diz que \u00e9 pr\u00e1tica do mercado incluir cr\u00e9ditos futuros de forma ampla. A pergunta: um \u201cborder\u00f4\u201d gen\u00e9rico pode servir como instrumento v\u00e1lido para garantir a cess\u00e3o fiduci\u00e1ria.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-15-2-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-analise-estrategica\"><a>15.2.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; An\u00e1lise ESTRAT\u00c9GICA.<\/a><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-15-2-1-do-direito\">15.2.1. Do DIREITO.<\/h4>\n\n\n\n<p>Lei n. 11.101\/2005, art. 49, \u00a7 3\u00ba<\/p>\n\n\n\n<p>C\u00f3digo Civil (CC\/2002), art. 104, II<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-15-2-2-dos-fundamentos\">15.2.2. Dos FUNDAMENTOS.<\/h4>\n\n\n\n<p>A controv\u00e9rsia consiste em definir se, na cess\u00e3o fiduci\u00e1ria de cr\u00e9ditos receb\u00edveis, a mera men\u00e7\u00e3o \u00e0queles cr\u00e9ditos que constarem em &#8220;border\u00f4&#8221; j\u00e1 satisfaz os pressupostos da garantia fiduci\u00e1ria ou se, diante de tamanho grau de indetermina\u00e7\u00e3o, estar\u00e3o submetidos \u00e0 recupera\u00e7\u00e3o judicial como quirograf\u00e1rios.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; No caso em exame, o Administrador Judicial concluiu que os direitos credit\u00f3rios objetos da controv\u00e9rsia &#8220;n\u00e3o foram especificados de maneira clara, pois seu objeto se refere aos descritos no border\u00f4 eletr\u00f4nico conforme cl\u00e1usulas 5 e 5.1 do contrato celebrado, que n\u00e3o informam a esp\u00e9cie de direito credit\u00f3rio em concreto, bem como n\u00e3o foi apresentado instrumento de cess\u00e3o fiduci\u00e1ria devidamente registrado no domic\u00edlio do devedor&#8221;.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; O ac\u00f3rd\u00e3o recorrido destacou que, <strong>n\u00e3o h\u00e1 se falar na necessidade de discrimina\u00e7\u00e3o individualizada de todos os t\u00edtulos representativos do cr\u00e9dito para perfectibilizar o neg\u00f3cio fiduci\u00e1rio, mas de sua determina\u00e7\u00e3o, ao menos em esp\u00e9cie enquanto receb\u00edveis em garantia<\/strong> (duplicata, cheque p\u00f3s-datado, cart\u00e3o de cr\u00e9dito etc).<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Para os fins do art. 49, \u00a7 3\u00ba da Lei n. 11.101\/2005, \u00e9 necess\u00e1rio um crit\u00e9rio m\u00ednimo de determina\u00e7\u00e3o dos cr\u00e9ditos garantidos, at\u00e9 porque o &#8220;border\u00f4&#8221; poder\u00e1 espelhar realiza\u00e7\u00f5es de ativos n\u00e3o necessariamente relacionados \u00e0 atividade produtiva da empresa (aliena\u00e7\u00e3o de bens n\u00e3o garantidos, p.ex.), sobre os quais terceiros (demais credores da recuperanda) ter\u00e3o interesse em acompanhar.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Conclui-se que o contrato de cess\u00e3o fiduci\u00e1ria de receb\u00edveis n\u00e3o poder\u00e1 versar sobre bem indeterminado, mas poder\u00e1 recair sobre objeto DETERMIN\u00c1VEL (CC, art. 104, II). E, nesse sentido, a identifica\u00e7\u00e3o dos bens dever\u00e1 ser a mais espec\u00edfica, dentro do poss\u00edvel.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-15-3-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-da-decisao\"><a>15.3.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Da DECIS\u00c3O.<\/a><\/h3>\n\n\n\n<p>Para fins de n\u00e3o sujei\u00e7\u00e3o do cr\u00e9dito \u00e0 recupera\u00e7\u00e3o judicial, nos termos do art. 49, \u00a7 3\u00ba da Lei n. 11.101\/2005, na cess\u00e3o fiduci\u00e1ria de cr\u00e9ditos receb\u00edveis, a mera men\u00e7\u00e3o aos cr\u00e9ditos que constarem em &#8220;border\u00f4&#8221; n\u00e3o \u00e9 suficiente para satisfazer os pressupostos da garantia fiduci\u00e1ria por n\u00e3o revelar qualquer grau de determina\u00e7\u00e3o.<\/p>\n\n\n\n<p>AgInt no REsp 2.042.014-RJ, Rel. Ministro Moura Ribeiro, Terceira Turma, por unanimidade, julgado em 30\/9\/2024, DJe 2\/10\/2024 &nbsp;(Info Extraordin\u00e1rio 23)<\/p>\n\n\n\n<h1 class=\"wp-block-heading\" id=\"h-direito\"><a>DIREITO<\/a><\/h1>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-16-nbsp-acao-de-execucao-de-titulo-extrajudicial-penhora-de-bens-imoveis-deposito-judicial-de-valor-superior-a-divida-satisfacao-do-credito-remicao-da-execucao-ausencia-de-prejuizo\"><a>16.&nbsp; A\u00e7\u00e3o de execu\u00e7\u00e3o de t\u00edtulo extrajudicial. Penhora de bens im\u00f3veis. Dep\u00f3sito judicial de valor superior \u00e0 d\u00edvida. Satisfa\u00e7\u00e3o do cr\u00e9dito. Remi\u00e7\u00e3o da execu\u00e7\u00e3o. Aus\u00eancia de preju\u00edzo<\/a><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-16-1-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-dos-fatos\"><a>16.1.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Dos FATOS.<\/a><\/h3>\n\n\n\n<p>Joselito, pequeno empres\u00e1rio, teve um im\u00f3vel penhorado em um processo de execu\u00e7\u00e3o. Desesperado para n\u00e3o perder o patrim\u00f4nio, conseguiu vender um outro bem e, com o dinheiro na m\u00e3o, fez o dep\u00f3sito judicial da quantia integral da d\u00edvida. S\u00f3 que o credor, louco para p\u00f4r as m\u00e3os no im\u00f3vel (porventura avaliado em valor inferior ao de mercado) n\u00e3o quis aceitar o dinheiro e insistiu que preferia adjudicar o im\u00f3vel. Joselito argumenta que a execu\u00e7\u00e3o deveria ser extinta, j\u00e1 que a d\u00edvida estava paga. O credor, por sua vez, sustenta que tinha o direito de escolher como queria receber.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-16-2-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-analise-estrategica\"><a>16.2.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; An\u00e1lise ESTRAT\u00c9GICA.<\/a><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-16-2-1-do-direito\">16.2.1. Do DIREITO.<\/h4>\n\n\n\n<p>C\u00f3digo de Processo Civil (CPC), arts. 826, 835, 848, I, e 924, II<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-16-2-2-dos-fundamentos\">16.2.2. Dos FUNDAMENTOS.<\/h4>\n\n\n\n<p>Cuida-se, na origem, de execu\u00e7\u00e3o de t\u00edtulo extrajudicial fundada em contrato de loca\u00e7\u00e3o em que houve a penhora dos im\u00f3veis do executado com posterior dep\u00f3sito em conta judicial de valor superior ao valor executado proveniente da promessa de compra e venda a terceiros dos im\u00f3veis penhorados. Insurge-se o credor\/exequente alegando o seu direito de adjudica\u00e7\u00e3o.<\/p>\n\n\n\n<p><strong>&nbsp;&nbsp;&nbsp;&nbsp; O art. 826 do CPC d\u00e1 ao executado a faculdade de evitar a adjudica\u00e7\u00e3o ou a aliena\u00e7\u00e3o dos seus bens atrav\u00e9s do pagamento da d\u00edvida<\/strong>. Ademais, o artigo 848, I, do CPC disciplina que as partes podem requerer a substitui\u00e7\u00e3o da penhora se ela n\u00e3o obedecer \u00e0 ordem legal prevista no artigo 835 do CPC, que estabelece o dinheiro como primeira op\u00e7\u00e3o.<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td>Na esp\u00e9cie, a pretens\u00e3o de adjudica\u00e7\u00e3o dos im\u00f3veis N\u00c3O se mostra a medida mais adequada de recebimento do cr\u00e9dito diante do dep\u00f3sito de valor que supera o cr\u00e9dito exequendo.<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; A decreta\u00e7\u00e3o de nulidade de atos processuais depende de efetiva demonstra\u00e7\u00e3o de preju\u00edzo da parte interessada (pas de nullit\u00e9 sans grief), por preval\u00eancia do princ\u00edpio da instrumentalidade das formas, o que n\u00e3o ocorreu no caso.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; A remi\u00e7\u00e3o da execu\u00e7\u00e3o corresponde \u00e0 satisfa\u00e7\u00e3o integral do d\u00e9bito executado no curso do processo, podendo ser exercida at\u00e9 a assinatura do auto de arremata\u00e7\u00e3o, importando na extin\u00e7\u00e3o da execu\u00e7\u00e3o, na forma do art. 924, II, do CPC, bastando apenas que o executado deposite em ju\u00edzo a import\u00e2ncia suficiente ao pagamento da d\u00edvida reclamada mais os encargos adicionais.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-16-3-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-da-decisao\"><a>16.3.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Da DECIS\u00c3O.<\/a><\/h3>\n\n\n\n<p>A pretens\u00e3o de adjudica\u00e7\u00e3o dos im\u00f3veis n\u00e3o se mostra a medida mais adequada de recebimento do cr\u00e9dito diante do dep\u00f3sito em conta judicial de valor monet\u00e1rio que supera o cr\u00e9dito exequendo.<\/p>\n\n\n\n<p>REsp 2.123.788-MG, Rel. Ministro Humberto Martins, Terceira Turma, por unanimidade, julgado em 24\/9\/2024, DJe 1\u00ba\/10\/2024 (Info Extraordin\u00e1rio 23)<\/p>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object aria-label=\"Incorporar PDF\" data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden><\/object><a id=\"wp-block-file--media-965cd440-244c-489e-886c-6933759f8738\" href=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/02\/16224152\/stj-extraordiario-23-pt1.pdf\">STJ &#8211; Extraordia\u0301rio 23 Pt1<\/a><a href=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/02\/16224152\/stj-extraordiario-23-pt1.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-965cd440-244c-489e-886c-6933759f8738\">Baixar<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Informativo n\u00ba Extraordin\u00e1rio 23 (Parte 1) do STJ&nbsp;COMENTADO. DOWNLOAD do PDF AQUI! DIREITO CONSTITUCIONAL 1.&nbsp;&nbsp;&nbsp;&nbsp; Embargos de diverg\u00eancia. Ac\u00f3rd\u00e3o paradigma oriundo de a\u00e7\u00f5es de garantia constitucional 1.1.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Dos FATOS. Dr. Creison, um advogado experiente, ajuizou embargos de diverg\u00eancia no STJ tentando utilizar um ac\u00f3rd\u00e3o proferido em mandado de seguran\u00e7a como paradigma para seu caso. No [&hellip;]<\/p>\n","protected":false},"author":833,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1],"tags":[],"tax_estado":[],"class_list":["post-1533081","post","type-post","status-publish","format-standard","hentry","category-cursos-e-concursos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Informativo STJ Extraordin\u00e1rio 23 Comentado Parte 1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-extraordinario-23-comentado-parte-1\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Informativo STJ Extraordin\u00e1rio 23 Comentado Parte 1\" \/>\n<meta property=\"og:description\" content=\"Informativo n\u00ba Extraordin\u00e1rio 23 (Parte 1) do STJ&nbsp;COMENTADO. DOWNLOAD do PDF AQUI! DIREITO CONSTITUCIONAL 1.&nbsp;&nbsp;&nbsp;&nbsp; Embargos de diverg\u00eancia. Ac\u00f3rd\u00e3o paradigma oriundo de a\u00e7\u00f5es de garantia constitucional 1.1.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Dos FATOS. Dr. Creison, um advogado experiente, ajuizou embargos de diverg\u00eancia no STJ tentando utilizar um ac\u00f3rd\u00e3o proferido em mandado de seguran\u00e7a como paradigma para seu caso. No [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-extraordinario-23-comentado-parte-1\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-17T01:42:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-18T00:21:46+00:00\" \/>\n<meta name=\"author\" content=\"Jean Vilbert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jean Vilbert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"56 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-extraordinario-23-comentado-parte-1\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-extraordinario-23-comentado-parte-1\/\"},\"author\":{\"name\":\"Jean Vilbert\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/475a0922f10cff0d1bc8bfecde05f999\"},\"headline\":\"Informativo STJ Extraordin\u00e1rio 23 Comentado Parte 1\",\"datePublished\":\"2025-02-17T01:42:40+00:00\",\"dateModified\":\"2025-02-18T00:21:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-extraordinario-23-comentado-parte-1\/\"},\"wordCount\":11300,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"articleSection\":[\"Concursos P\u00fablicos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-extraordinario-23-comentado-parte-1\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-extraordinario-23-comentado-parte-1\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-extraordinario-23-comentado-parte-1\/\",\"name\":\"Informativo STJ Extraordin\u00e1rio 23 Comentado Parte 1\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"datePublished\":\"2025-02-17T01:42:40+00:00\",\"dateModified\":\"2025-02-18T00:21:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-extraordinario-23-comentado-parte-1\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-extraordinario-23-comentado-parte-1\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-extraordinario-23-comentado-parte-1\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Informativo STJ Extraordin\u00e1rio 23 Comentado Parte 1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/475a0922f10cff0d1bc8bfecde05f999\",\"name\":\"Jean Vilbert\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/1667694e4ebdd32feeac9ea2794de3f0470b5c55c6198181ab0b0c333b121921?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1667694e4ebdd32feeac9ea2794de3f0470b5c55c6198181ab0b0c333b121921?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1667694e4ebdd32feeac9ea2794de3f0470b5c55c6198181ab0b0c333b121921?s=96&d=mm&r=g\",\"caption\":\"Jean Vilbert\"},\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/jeanvilbertgmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Informativo STJ Extraordin\u00e1rio 23 Comentado Parte 1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-extraordinario-23-comentado-parte-1\/","og_locale":"pt_BR","og_type":"article","og_title":"Informativo STJ Extraordin\u00e1rio 23 Comentado Parte 1","og_description":"Informativo n\u00ba Extraordin\u00e1rio 23 (Parte 1) do STJ&nbsp;COMENTADO. DOWNLOAD do PDF AQUI! DIREITO CONSTITUCIONAL 1.&nbsp;&nbsp;&nbsp;&nbsp; Embargos de diverg\u00eancia. Ac\u00f3rd\u00e3o paradigma oriundo de a\u00e7\u00f5es de garantia constitucional 1.1.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Dos FATOS. Dr. Creison, um advogado experiente, ajuizou embargos de diverg\u00eancia no STJ tentando utilizar um ac\u00f3rd\u00e3o proferido em mandado de seguran\u00e7a como paradigma para seu caso. No [&hellip;]","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-extraordinario-23-comentado-parte-1\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2025-02-17T01:42:40+00:00","article_modified_time":"2025-02-18T00:21:46+00:00","author":"Jean Vilbert","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Jean Vilbert","Est. tempo de leitura":"56 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-extraordinario-23-comentado-parte-1\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-extraordinario-23-comentado-parte-1\/"},"author":{"name":"Jean Vilbert","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/475a0922f10cff0d1bc8bfecde05f999"},"headline":"Informativo STJ Extraordin\u00e1rio 23 Comentado Parte 1","datePublished":"2025-02-17T01:42:40+00:00","dateModified":"2025-02-18T00:21:46+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-extraordinario-23-comentado-parte-1\/"},"wordCount":11300,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"articleSection":["Concursos P\u00fablicos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-extraordinario-23-comentado-parte-1\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-extraordinario-23-comentado-parte-1\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-extraordinario-23-comentado-parte-1\/","name":"Informativo STJ Extraordin\u00e1rio 23 Comentado Parte 1","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"datePublished":"2025-02-17T01:42:40+00:00","dateModified":"2025-02-18T00:21:46+00:00","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-extraordinario-23-comentado-parte-1\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-extraordinario-23-comentado-parte-1\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-extraordinario-23-comentado-parte-1\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Informativo STJ Extraordin\u00e1rio 23 Comentado Parte 1"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/475a0922f10cff0d1bc8bfecde05f999","name":"Jean Vilbert","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/1667694e4ebdd32feeac9ea2794de3f0470b5c55c6198181ab0b0c333b121921?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1667694e4ebdd32feeac9ea2794de3f0470b5c55c6198181ab0b0c333b121921?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1667694e4ebdd32feeac9ea2794de3f0470b5c55c6198181ab0b0c333b121921?s=96&d=mm&r=g","caption":"Jean Vilbert"},"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/jeanvilbertgmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1533081","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/833"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1533081"}],"version-history":[{"count":3,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1533081\/revisions"}],"predecessor-version":[{"id":1533750,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1533081\/revisions\/1533750"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1533081"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1533081"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1533081"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1533081"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}