{"id":1518064,"date":"2025-01-16T21:28:24","date_gmt":"2025-01-17T00:28:24","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=1518064"},"modified":"2025-01-17T09:25:10","modified_gmt":"2025-01-17T12:25:10","slug":"concurso-mpu-disciplinas-exigidas","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-mpu-disciplinas-exigidas\/","title":{"rendered":"Quais as disciplinas exigidas na prova objetiva do edital MPU 2025?"},"content":{"rendered":"\n<p>O concurso do\u00a0<a href=\"https:\/\/www.estrategiaconcursos.com.br\/cursosPorConcurso\/mpu-ministerio-publico-da-uniao\/\" target=\"_blank\" rel=\"noreferrer noopener\">Minist\u00e9rio P\u00fablico da Uni\u00e3o<\/a>\u00a0(<strong>MPU<\/strong>) est\u00e1 com as <strong>inscri\u00e7\u00f5es abertas<\/strong> e oferta <strong>172 vagas imediatas,<\/strong>\u00a0e n\u00f3s preparamos este artigo com as principais disciplinas exigidas no edital!<\/p>\n\n\n\n<p>As vagas dispon\u00edveis exigem <strong>n\u00edvel superior de escolaridade,<\/strong> com sal\u00e1rios<strong> iniciais que variam de R$ 8.529,67 a R$ 13.994,80, <\/strong>al\u00e9m de benef\u00edcios. <\/p>\n\n\n\n<p>Os interessados podem se<strong> inscrever no site da FGV at\u00e9 27 de fevereiro de 2025<\/strong>. A <strong>avalia\u00e7\u00e3o <\/strong>dos candidatos est\u00e1 prevista para o dia<strong> 4 de maio de 2025.<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-etapas-concurso-mpu-2025\">Etapas concurso MPU 2025:<\/h2>\n\n\n\n<p>Os candidatos inscritos no edital ser\u00e3o avaliados por meio da aplica\u00e7\u00e3o das seguintes etapas:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Prova Objetiva<\/strong>&nbsp;\u2013 eliminat\u00f3rio e classificat\u00f3rio;<\/li>\n\n\n\n<li><strong>Prova Discursiva<\/strong>&nbsp;\u2013 eliminat\u00f3rio e classificat\u00f3rio; e<\/li>\n\n\n\n<li><strong>Teste de Aptid\u00e3o F\u00edsica (TAF)<\/strong>&nbsp;\u2013 eliminat\u00f3rio.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"objetiva\">Provas Objetivas<\/h3>\n\n\n\n<p>As provas para o cargo de <strong>Analista <\/strong>ser\u00e3o aplicadas no <strong>per\u00edodo da manh\u00e3<\/strong>. Enquanto as provas para o cargo de <strong>T\u00e9cnico<\/strong> ser\u00e3o aplicadas no mesmo dia, no <strong>per\u00edodo da tarde.<\/strong><\/p>\n\n\n\n<p>A etapa \u00e9 composta de <strong>80 quest\u00f5es para todos os cargos,<\/strong> divididas em:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>T\u00c9CNICO DO MPU \/ ADMINISTRA\u00c7\u00c3O<\/strong>\n<ul class=\"wp-block-list\">\n<li>L\u00edngua Portuguesa 20 quest\u00f5es;<\/li>\n\n\n\n<li>No\u00e7\u00f5es de Sustentabilidade 05 quest\u00f5es;<\/li>\n\n\n\n<li>No\u00e7\u00f5es de Direitos Humanos e Fundamentais e de Acessibilidade 05 quest\u00f5es;<\/li>\n\n\n\n<li>Legisla\u00e7\u00e3o Institucional 05 quest\u00f5es;<\/li>\n\n\n\n<li>Conhecimentos Espec\u00edficos 45 quest\u00f5es;<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>T\u00c9CNICO DO MPU \/ DEMAIS ESPECIALIDADES<\/strong>\n<ul class=\"wp-block-list\">\n<li>L\u00edngua Portuguesa 15 quest\u00f5es;<\/li>\n\n\n\n<li>No\u00e7\u00f5es de Sustentabilidade 05 quest\u00f5es;<\/li>\n\n\n\n<li>No\u00e7\u00f5es de Direitos Humanos e Fundamentais e de Acessibilidade 05 quest\u00f5es;<\/li>\n\n\n\n<li>No\u00e7\u00f5es de Administra\u00e7\u00e3o P\u00fablica 05 quest\u00f5es;<\/li>\n\n\n\n<li>Legisla\u00e7\u00e3o Institucional 05 quest\u00f5es;<\/li>\n\n\n\n<li>No\u00e7\u00f5es de Direito Administrativo 05 quest\u00f5es;<\/li>\n\n\n\n<li>Conhecimentos Espec\u00edficos 40 quest\u00f5es;<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>ANALISTA DO MPU \/ DIREITO<\/strong>\n<ul class=\"wp-block-list\">\n<li>L\u00edngua Portuguesa 15 quest\u00f5es;<\/li>\n\n\n\n<li>No\u00e7\u00f5es de Sustentabilidade 05 quest\u00f5es;<\/li>\n\n\n\n<li>No\u00e7\u00f5es de Direitos Humanos e Fundamentais e de Legisla\u00e7\u00e3o Institucional 05 quest\u00f5es;<\/li>\n\n\n\n<li>Conhecimentos Espec\u00edficos 45 quest\u00f5es;<\/li>\n\n\n\n<li>No\u00e7\u00f5es de Administra\u00e7\u00e3o P\u00fablica 05 quest\u00f5es;<\/li>\n\n\n\n<li>Acessibilidade 05 quest\u00f5es;<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>ANALISTA DO MPU \/ DEMAIS ESPECIALIDADES (EXCETO CARGOS DE PERITO)<\/strong>\n<ul class=\"wp-block-list\">\n<li>L\u00edngua Portuguesa 15 quest\u00f5es;<\/li>\n\n\n\n<li>No\u00e7\u00f5es de Sustentabilidade 05 quest\u00f5es;<\/li>\n\n\n\n<li>No\u00e7\u00f5es de Direitos Humanos e Fundamentais e de No\u00e7\u00f5es de Administra\u00e7\u00e3o P\u00fablica 05 quest\u00f5es;<\/li>\n\n\n\n<li>Legisla\u00e7\u00e3o Institucional 05 quest\u00f5es;<\/li>\n\n\n\n<li>No\u00e7\u00f5es de Direito Administrativo 05 quest\u00f5es;<\/li>\n\n\n\n<li>Conhecimentos Espec\u00edficos 40 quest\u00f5es;<\/li>\n\n\n\n<li>Acessibilidade 05<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>ANALISTA DO MPU \/ PERITO (TODAS AS ESPECIALIDADES)<\/strong>\n<ul class=\"wp-block-list\">\n<li>L\u00edngua Portuguesa 15 quest\u00f5es;<\/li>\n\n\n\n<li>No\u00e7\u00f5es de Sustentabilidade 05 quest\u00f5es;<\/li>\n\n\n\n<li>No\u00e7\u00f5es de Direitos Humanos e Fundamentais e de Acessibilidade 05 quest\u00f5es;<\/li>\n\n\n\n<li>No\u00e7\u00f5es de Administra\u00e7\u00e3o P\u00fablica 05 quest\u00f5es;<\/li>\n\n\n\n<li>Legisla\u00e7\u00e3o Institucional 05 quest\u00f5es;<\/li>\n\n\n\n<li>No\u00e7\u00f5es de Direito Administrativo 05 quest\u00f5es;<\/li>\n\n\n\n<li>No\u00e7\u00f5es de Per\u00edcia em Processo Civil 05 quest\u00f5es;<\/li>\n\n\n\n<li>Conhecimentos Espec\u00edficos 35 quest\u00f5es.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-disciplinas-exigidas-concurso-mpu-2025\">Disciplinas exigidas concurso MPU 2025:<\/h2>\n\n\n\n<p>O conte\u00fado program\u00e1tico contempla<strong> legisla\u00e7\u00e3o, jurisprud\u00eancia e doutrina pertinentes aos temas.<\/strong> Confira abaixo um resumo preparado pela equipe do Estrat\u00e9gia:<\/p>\n\n\n\n<p><strong>L\u00edngua Portuguesa (para todos os cargos):<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Interpreta\u00e7\u00e3o e compreens\u00e3o de texto.<\/li>\n\n\n\n<li>Organiza\u00e7\u00e3o estrutural dos textos: coes\u00e3o, coer\u00eancia e intertextualidade.<\/li>\n\n\n\n<li>Modos de organiza\u00e7\u00e3o discursiva: descri\u00e7\u00e3o, narra\u00e7\u00e3o, exposi\u00e7\u00e3o, argumenta\u00e7\u00e3o e injun\u00e7\u00e3o.<\/li>\n\n\n\n<li>Tipos textuais: informativo, publicit\u00e1rio, propagand\u00edstico, normativo, did\u00e1tico, divinat\u00f3rio.<\/li>\n\n\n\n<li>Textos liter\u00e1rios e n\u00e3o liter\u00e1rios.<\/li>\n\n\n\n<li>Tipologia e estrutura da frase portuguesa: deslocamento, substitui\u00e7\u00e3o, modifica\u00e7\u00e3o e corre\u00e7\u00e3o.<\/li>\n\n\n\n<li>Norma padr\u00e3o, pontua\u00e7\u00e3o, sinais gr\u00e1ficos e estrutura sint\u00e1tica.<\/li>\n\n\n\n<li>Fun\u00e7\u00f5es da linguagem e atos de comunica\u00e7\u00e3o.<\/li>\n\n\n\n<li>Estrutura e forma\u00e7\u00e3o de palavras, classes gramaticais.<\/li>\n\n\n\n<li>Sem\u00e2ntica: sentido pr\u00f3prio e figurado, ant\u00f4nimos, sin\u00f4nimos, polissemia e ambiguidade.<\/li>\n\n\n\n<li>Uso de dicion\u00e1rios e vocabul\u00e1rio: neologismos, arca\u00edsmos, estrangeirismos e latinismos.<\/li>\n\n\n\n<li>Ortografia, acentua\u00e7\u00e3o gr\u00e1fica e crase.<\/li>\n<\/ul>\n\n\n\n<p><strong>No\u00e7\u00f5es de Sustentabilidade (para todos os cargos):<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Meio Ambiente: Constitui\u00e7\u00e3o Federal de 1988 (Art. 225).<\/li>\n\n\n\n<li>Desenvolvimento Sustent\u00e1vel: Relat\u00f3rio Brundtland.<\/li>\n\n\n\n<li>Agenda Ambiental da Administra\u00e7\u00e3o P\u00fablica (A3P).<\/li>\n\n\n\n<li>Pol\u00edticas p\u00fablicas ambientais: mudan\u00e7as clim\u00e1ticas, res\u00edduos s\u00f3lidos, crimes ambientais.<\/li>\n\n\n\n<li>Sistema Nacional de Unidades de Conserva\u00e7\u00e3o.<\/li>\n\n\n\n<li>Lei da Coopera\u00e7\u00e3o Federativa em mat\u00e9ria ambiental (Lei Complementar n\u00ba 140\/2011).<\/li>\n<\/ul>\n\n\n\n<p><strong>No\u00e7\u00f5es de Direitos Humanos e Fundamentais e de Acessibilidade (para todos os cargos):<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Teoria e legisla\u00e7\u00e3o sobre direitos fundamentais e humanos.<\/li>\n\n\n\n<li>Declara\u00e7\u00e3o Universal dos Direitos Humanos e tratados internacionais.<\/li>\n\n\n\n<li>Agenda 2030 da ONU e Pol\u00edtica Nacional de Direitos Humanos.<\/li>\n\n\n\n<li>Equidade de g\u00eanero e estatuto da igualdade racial.<\/li>\n\n\n\n<li>Lei Brasileira de Inclus\u00e3o da Pessoa com Defici\u00eancia (Lei n\u00ba 13.146\/2015).<\/li>\n\n\n\n<li>Normas de acessibilidade e prioridade no atendimento a pessoas com defici\u00eancia.<\/li>\n<\/ul>\n\n\n\n<p><strong>No\u00e7\u00f5es de Administra\u00e7\u00e3o P\u00fablica (para todos os cargos, exceto T01 &#8211; T\u00e9cnico do MPU\/Administra\u00e7\u00e3o):<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Conceitos b\u00e1sicos de administra\u00e7\u00e3o: efici\u00eancia, efic\u00e1cia, qualidade.<\/li>\n\n\n\n<li>Estrutura organizacional: princ\u00edpios, tipos e departamentaliza\u00e7\u00e3o.<\/li>\n\n\n\n<li>Fun\u00e7\u00f5es da administra\u00e7\u00e3o: planejamento, organiza\u00e7\u00e3o, dire\u00e7\u00e3o e controle.<\/li>\n\n\n\n<li>Planejamento estrat\u00e9gico, t\u00e1tico e operacional.<\/li>\n\n\n\n<li>Gest\u00e3o de processos e compet\u00eancias organizacionais.<\/li>\n\n\n\n<li>Comportamento organizacional: lideran\u00e7a, motiva\u00e7\u00e3o e trabalho em equipe.<\/li>\n\n\n\n<li>Evolu\u00e7\u00e3o dos modelos de administra\u00e7\u00e3o p\u00fablica (patrimonialista, burocr\u00e1tica e gerencial).<\/li>\n\n\n\n<li>Transforma\u00e7\u00e3o digital e uso de tecnologias no setor p\u00fablico: IA, Blockchain, automa\u00e7\u00e3o.<\/li>\n\n\n\n<li>Resolu\u00e7\u00e3o CNMP n\u00ba 276\/2023 sobre MP Digital.<\/li>\n<\/ul>\n\n\n\n<p><strong>Legisla\u00e7\u00e3o Institucional (para todos os cargos):<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Lei Complementar n\u00ba 75\/1993.<\/li>\n\n\n\n<li>Lei n\u00ba 13.316\/2016 e suas altera\u00e7\u00f5es.<\/li>\n\n\n\n<li>Portaria PGR\/MPU n\u00ba 98\/2017 (C\u00f3digo de \u00c9tica e de Conduta do MPU e da ESMPU).<\/li>\n\n\n\n<li>Portaria PGR\/MPU n\u00ba 247\/2023 (Programa de Integridade do Minist\u00e9rio P\u00fablico da Uni\u00e3o).<\/li>\n<\/ul>\n\n\n\n<p><strong>No\u00e7\u00f5es de Direito Administrativo (para todos os cargos, exceto T01 &#8211; T\u00e9cnico do MPU\/Administra\u00e7\u00e3o e A07 &#8211; Analista do MPU\/Direito):<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Princ\u00edpios do Direito Administrativo.<\/li>\n\n\n\n<li>Atos administrativos e poderes administrativos.<\/li>\n\n\n\n<li>Uso e abuso do poder.<\/li>\n\n\n\n<li>Organiza\u00e7\u00e3o administrativa: Administra\u00e7\u00e3o Direta e Indireta.<\/li>\n\n\n\n<li>Contratos administrativos, licita\u00e7\u00f5es e Lei n\u00ba 14.133\/2021.<\/li>\n\n\n\n<li>Processo administrativo: Lei n\u00ba 9.784\/1999.<\/li>\n\n\n\n<li>Seguran\u00e7a jur\u00eddica e efici\u00eancia no Direito P\u00fablico (LINDB, Lei n\u00ba 13.655\/2018).<\/li>\n\n\n\n<li>Agentes p\u00fablicos e servidores: Lei n\u00ba 8.112\/1990 e suas altera\u00e7\u00f5es.<\/li>\n\n\n\n<li>Regime jur\u00eddico dos servidores p\u00fablicos federais.<\/li>\n\n\n\n<li>Servi\u00e7os p\u00fablicos e responsabilidade civil do Estado.<\/li>\n\n\n\n<li>Controle da Administra\u00e7\u00e3o P\u00fablica: Conselho Nacional do Minist\u00e9rio P\u00fablico e Tribunais de Contas.<\/li>\n\n\n\n<li>Improbidade Administrativa.<\/li>\n\n\n\n<li>Lei n\u00ba 12.527\/2011 (Lei de Acesso \u00e0 Informa\u00e7\u00e3o) e Lei n\u00ba 13.709\/2018 (Lei Geral de Prote\u00e7\u00e3o de Dados Pessoais \u2013 LGPD).<\/li>\n\n\n\n<li>S\u00famulas e jurisprud\u00eancia dos tribunais superiores.<\/li>\n<\/ul>\n\n\n\n<p class=\"has-text-align-center has-light-green-cyan-background-color has-background\"><a href=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/01\/16211825\/disciplinas-mpu.pdf\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Confira aqui a lista completa de disciplinas exigidas do concurso MPU 2025!<\/strong><\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-disciplinas-exigidas-no-ultimo-edital-do-concurso-mpu\">Disciplinas exigidas no \u00faltimo edital do concurso MPU:<\/h2>\n\n\n\n<p>O<strong>&nbsp;\u00faltimo concurso do MPU ocorreu em 2018<\/strong>&nbsp;com oferta de<strong>&nbsp;47 vagas imediatas<\/strong>, seu resultado foi&nbsp;<strong>homologado em dezembro de 2018<\/strong>&nbsp;e teve a vig\u00eancia encerrada em setembro de 2024.<\/p>\n\n\n\n<p>Os candidatos inscritos para o cargo de <strong>Analista do MPU foram avaliados por 120 quest\u00f5es objetivas e uma prova discursiva,<\/strong> de car\u00e1ter eliminat\u00f3rio e classificat\u00f3rio, com dura\u00e7\u00e3o de 4 horas e 30 minutos, realizadas no turno da manh\u00e3.<\/p>\n\n\n\n<p>Para o cargo de <strong>T\u00e9cnico do MPU, <\/strong>os candidatos foram avaliados exclusivamente por <strong>provas objetivas,<\/strong> de car\u00e1ter eliminat\u00f3rio e classificat\u00f3rio, com dura\u00e7\u00e3o de 3 horas e 30 minutos, aplicadas no turno da tarde.<\/p>\n\n\n\n<p>As provas objetivas, de car\u00e1ter eliminat\u00f3rio e classificat\u00f3rio, valendo <strong>120,00 ponto<\/strong>s foi constitu\u00edda de itens para julgamento de <strong>CERTO<\/strong> ou <strong>ERRADO<\/strong>.<\/p>\n\n\n\n<p>Nas provas, foram avaliados, al\u00e9m de habilidades, conhecimentos conforme descritos a seguir:<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-conhecimentos-basicos-para-todos-os-cargos-50-questoes\">Conhecimentos B\u00e1sicos para Todos os Cargos: 50 quest\u00f5es<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>L\u00edngua Portuguesa:<\/strong>\n<ul class=\"wp-block-list\">\n<li>Compreens\u00e3o e interpreta\u00e7\u00e3o de textos de g\u00eaneros variados.<\/li>\n\n\n\n<li>Reconhecimento de tipos e g\u00eaneros textuais.<\/li>\n\n\n\n<li>Dom\u00ednio da ortografia oficial.<\/li>\n\n\n\n<li>Dom\u00ednio dos mecanismos de coes\u00e3o textual:\n<ul class=\"wp-block-list\">\n<li>Emprego de elementos de referencia\u00e7\u00e3o, substitui\u00e7\u00e3o e repeti\u00e7\u00e3o.<\/li>\n\n\n\n<li>Uso de conectores e outros elementos de sequencia\u00e7\u00e3o textual.<\/li>\n\n\n\n<li>Emprego de tempos e modos verbais.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>Dom\u00ednio da estrutura morfossint\u00e1tica do per\u00edodo:\n<ul class=\"wp-block-list\">\n<li>Emprego das classes de palavras.<\/li>\n\n\n\n<li>Rela\u00e7\u00f5es de coordena\u00e7\u00e3o e subordina\u00e7\u00e3o entre ora\u00e7\u00f5es e termos da ora\u00e7\u00e3o.<\/li>\n\n\n\n<li>Emprego dos sinais de pontua\u00e7\u00e3o.<\/li>\n\n\n\n<li>Concord\u00e2ncia verbal e nominal.<\/li>\n\n\n\n<li>Reg\u00eancia verbal e nominal.<\/li>\n\n\n\n<li>Emprego do sinal indicativo de crase.<\/li>\n\n\n\n<li>Coloca\u00e7\u00e3o dos pronomes \u00e1tonos.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>Reescrita de frases e par\u00e1grafos do texto:\n<ul class=\"wp-block-list\">\n<li>Significa\u00e7\u00e3o das palavras.<\/li>\n\n\n\n<li>Substitui\u00e7\u00e3o de palavras ou trechos de texto.<\/li>\n\n\n\n<li>Reorganiza\u00e7\u00e3o da estrutura de ora\u00e7\u00f5es e per\u00edodos.<\/li>\n\n\n\n<li>Reescrita de textos de diferentes g\u00eaneros e n\u00edveis de formalidade.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>Acessibilidade:<\/strong>\n<ul class=\"wp-block-list\">\n<li>Lei n\u00ba 13.146\/2015 e suas altera\u00e7\u00f5es (Lei Brasileira de Inclus\u00e3o da Pessoa com Defici\u00eancia).<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>\u00c9tica no Servi\u00e7o P\u00fablico:<\/strong>\n<ul class=\"wp-block-list\">\n<li>\u00c9tica e moral.<\/li>\n\n\n\n<li>\u00c9tica, princ\u00edpios e valores.<\/li>\n\n\n\n<li>\u00c9tica e democracia: exerc\u00edcio da cidadania.<\/li>\n\n\n\n<li>\u00c9tica e fun\u00e7\u00e3o p\u00fablica.<\/li>\n\n\n\n<li>\u00c9tica no Setor P\u00fablico:\n<ul class=\"wp-block-list\">\n<li>Decreto n\u00ba 1.171\/1994 e suas altera\u00e7\u00f5es (C\u00f3digo de \u00c9tica Profissional do Servi\u00e7o P\u00fablico).<\/li>\n\n\n\n<li>Lei n\u00ba 8.112\/1990 e suas altera\u00e7\u00f5es: regime disciplinar (deveres e proibi\u00e7\u00f5es, acumula\u00e7\u00e3o, responsabilidades, penalidades).<\/li>\n\n\n\n<li>Lei n\u00ba 8.429\/1992 e suas altera\u00e7\u00f5es: disposi\u00e7\u00f5es gerais e atos de improbidade administrativa.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>Portaria PGR\/MPU n\u00ba 98\/2017 (C\u00f3digo de \u00c9tica e de Conduta do Minist\u00e9rio P\u00fablico da Uni\u00e3o e da Escola Superior do Minist\u00e9rio P\u00fablico da Uni\u00e3o).<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>Legisla\u00e7\u00e3o Aplicada ao MPU e ao CNMP:<\/strong>\n<ul class=\"wp-block-list\">\n<li>Minist\u00e9rio P\u00fablico da Uni\u00e3o:\n<ul class=\"wp-block-list\">\n<li>Lei Complementar n\u00ba 75\/1993 (Lei Org\u00e2nica do Minist\u00e9rio P\u00fablico da Uni\u00e3o).<\/li>\n\n\n\n<li>Perfil constitucional do Minist\u00e9rio P\u00fablico e suas fun\u00e7\u00f5es institucionais.<\/li>\n\n\n\n<li>Conceito, princ\u00edpios institucionais, autonomia funcional e administrativa.<\/li>\n\n\n\n<li>Iniciativa legislativa e elabora\u00e7\u00e3o da proposta or\u00e7ament\u00e1ria.<\/li>\n\n\n\n<li>Os v\u00e1rios Minist\u00e9rios P\u00fablicos.<\/li>\n\n\n\n<li>O Procurador-Geral da Rep\u00fablica: requisitos para a investidura e procedimento de destitui\u00e7\u00e3o.<\/li>\n\n\n\n<li>Os demais Procuradores-Gerais, ingresso na carreira, promo\u00e7\u00e3o, aposentadoria, garantias, prerrogativas e veda\u00e7\u00f5es.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>Conselho Nacional do Minist\u00e9rio P\u00fablico (CNMP):\n<ul class=\"wp-block-list\">\n<li>Composi\u00e7\u00e3o e atribui\u00e7\u00f5es constitucionais.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-conhecimentos-especificos-70-questoes\">Conhecimentos Espec\u00edficos: 70 quest\u00f5es<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-cargo-1-analista-do-mpu-especialidade-direito\">Cargo 1: Analista do MPU \u2013 Especialidade: Direito<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Direito Administrativo:<\/strong>\n<ul class=\"wp-block-list\">\n<li>Estado, governo e administra\u00e7\u00e3o p\u00fablica: conceitos, elementos, poderes, natureza, fins e princ\u00edpios.<\/li>\n\n\n\n<li>Direito administrativo: conceito, fontes e princ\u00edpios.<\/li>\n\n\n\n<li>Ato administrativo: conceito, requisitos, atributos, classifica\u00e7\u00e3o e esp\u00e9cies.<\/li>\n\n\n\n<li>Invalida\u00e7\u00e3o, anula\u00e7\u00e3o e revoga\u00e7\u00e3o de atos administrativos.<\/li>\n\n\n\n<li>Prescri\u00e7\u00e3o.<\/li>\n\n\n\n<li>Lei n\u00ba 8.112\/1990 e suas altera\u00e7\u00f5es.<\/li>\n\n\n\n<li>Poderes da administra\u00e7\u00e3o: vinculado, discricion\u00e1rio, hier\u00e1rquico, disciplinar e regulamentar.<\/li>\n\n\n\n<li>Servi\u00e7os p\u00fablicos: conceito, classifica\u00e7\u00e3o, regulamenta\u00e7\u00e3o e formas de presta\u00e7\u00e3o.<\/li>\n\n\n\n<li>Organiza\u00e7\u00e3o administrativa: administra\u00e7\u00e3o direta e indireta, centralizada e descentralizada.<\/li>\n\n\n\n<li>Controle e responsabiliza\u00e7\u00e3o da administra\u00e7\u00e3o: controle administrativo, judicial, legislativo e responsabilidade civil do Estado.<\/li>\n\n\n\n<li>Lei n\u00ba 8.666\/1993 e suas altera\u00e7\u00f5es.<\/li>\n\n\n\n<li>Lei n\u00ba 10.520\/2002 e suas altera\u00e7\u00f5es e Decreto n\u00ba 5.450\/2005 e suas altera\u00e7\u00f5es.<\/li>\n\n\n\n<li>Decreto n\u00ba 7.892\/2013 e suas altera\u00e7\u00f5es.<\/li>\n\n\n\n<li>Jurisprud\u00eancia dos tribunais superiores.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>Direito Constitucional:<\/strong>\n<ul class=\"wp-block-list\">\n<li>Constitui\u00e7\u00e3o da Rep\u00fablica Federativa do Brasil de 1988.<\/li>\n\n\n\n<li>Princ\u00edpios fundamentais e aplicabilidade das normas constitucionais.<\/li>\n\n\n\n<li>Direitos e garantias fundamentais, direitos e deveres individuais e coletivos, direitos sociais, de nacionalidade, direitos pol\u00edticos e partidos pol\u00edticos.<\/li>\n\n\n\n<li>Organiza\u00e7\u00e3o pol\u00edtico-administrativa do Estado: Uni\u00e3o, estados, Distrito Federal, munic\u00edpios e territ\u00f3rios.<\/li>\n\n\n\n<li>Administra\u00e7\u00e3o p\u00fablica, servidores p\u00fablicos, Poder Executivo, Legislativo e Judici\u00e1rio, e suas atribui\u00e7\u00f5es.<\/li>\n\n\n\n<li>Fun\u00e7\u00f5es essenciais \u00e0 justi\u00e7a: Minist\u00e9rio P\u00fablico, Advocacia P\u00fablica e Defensoria P\u00fablica.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>Direito do Trabalho:<\/strong>\n<ul class=\"wp-block-list\">\n<li>Princ\u00edpios e fontes do direito do trabalho.<\/li>\n\n\n\n<li>Direitos constitucionais dos trabalhadores (art. 7\u00ba da Constitui\u00e7\u00e3o Federal).<\/li>\n\n\n\n<li>Rela\u00e7\u00e3o de trabalho e rela\u00e7\u00e3o de emprego.<\/li>\n\n\n\n<li>Sujeitos do contrato de trabalho, altera\u00e7\u00f5es e modalidades.<\/li>\n\n\n\n<li>Suspens\u00e3o e rescis\u00e3o do contrato de trabalho.<\/li>\n\n\n\n<li>Aviso pr\u00e9vio, jornada de trabalho, descanso e intervalos.<\/li>\n\n\n\n<li>Sal\u00e1rio m\u00ednimo, f\u00e9rias, remunera\u00e7\u00e3o e 13\u00ba sal\u00e1rio.<\/li>\n\n\n\n<li>Prescri\u00e7\u00e3o e decad\u00eancia.<\/li>\n\n\n\n<li>Seguran\u00e7a e medicina no trabalho, prote\u00e7\u00e3o ao trabalho do menor e da mulher.<\/li>\n\n\n\n<li>Direito coletivo do trabalho e comiss\u00f5es de concilia\u00e7\u00e3o pr\u00e9via.<\/li>\n\n\n\n<li>Jurisprud\u00eancia dos tribunais superiores.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>Direito Processual do Trabalho:<\/strong>\n<ul class=\"wp-block-list\">\n<li>Procedimentos nos diss\u00eddios individuais e recursos no processo do trabalho.<\/li>\n\n\n\n<li>Processos de execu\u00e7\u00e3o, prescri\u00e7\u00e3o e decad\u00eancia no processo do trabalho.<\/li>\n\n\n\n<li>Compet\u00eancia da justi\u00e7a do trabalho e rito sumar\u00edssimo.<\/li>\n\n\n\n<li>A\u00e7\u00e3o rescis\u00f3ria, mandado de seguran\u00e7a e diss\u00eddios coletivos.<\/li>\n\n\n\n<li>Jurisprud\u00eancia dos tribunais superiores, tribunais de contas e tribunais regionais do trabalho.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>Direito Civil:<\/strong>\n<ul class=\"wp-block-list\">\n<li>Lei de Introdu\u00e7\u00e3o \u00e0s Normas do Direito Brasileiro, vig\u00eancia, aplica\u00e7\u00e3o, interpreta\u00e7\u00e3o e integra\u00e7\u00e3o das leis.<\/li>\n\n\n\n<li>Pessoas naturais e jur\u00eddicas, bens p\u00fablicos, neg\u00f3cios jur\u00eddicos e contratos.<\/li>\n\n\n\n<li>Responsabilidade civil e prescri\u00e7\u00e3o.<\/li>\n\n\n\n<li>Jurisprud\u00eancia dos tribunais superiores.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>Direito Processual Civil:<\/strong>\n<ul class=\"wp-block-list\">\n<li>C\u00f3digo de Processo Civil e suas disposi\u00e7\u00f5es gerais.<\/li>\n\n\n\n<li>A\u00e7\u00e3o, pressupostos processuais, litiscons\u00f3rcio e interven\u00e7\u00e3o de terceiros.<\/li>\n\n\n\n<li>Atos processuais, poder e deveres do juiz, Minist\u00e9rio P\u00fablico e Defensoria P\u00fablica.<\/li>\n\n\n\n<li>Tutela provis\u00f3ria, forma\u00e7\u00e3o, suspens\u00e3o e extin\u00e7\u00e3o do processo.<\/li>\n\n\n\n<li>Processo de conhecimento e cumprimento de senten\u00e7a.<\/li>\n\n\n\n<li>Procedimentos especiais, mandado de seguran\u00e7a, a\u00e7\u00e3o popular e a\u00e7\u00e3o de improbidade administrativa.<\/li>\n\n\n\n<li>Jurisprud\u00eancia dos tribunais superiores.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>Direito Penal:<\/strong>\n<ul class=\"wp-block-list\">\n<li>Princ\u00edpios da legalidade e da anterioridade, aplica\u00e7\u00e3o da lei penal no tempo e no espa\u00e7o.<\/li>\n\n\n\n<li>Fato t\u00edpico, ilicitude, culpabilidade e imputabilidade penal.<\/li>\n\n\n\n<li>Crimes contra a pessoa, patrim\u00f4nio, f\u00e9 p\u00fablica e administra\u00e7\u00e3o p\u00fablica.<\/li>\n\n\n\n<li>Disposi\u00e7\u00f5es constitucionais aplic\u00e1veis ao direito penal.<\/li>\n\n\n\n<li>Jurisprud\u00eancia dos tribunais superiores.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>Direito Processual Penal:<\/strong>\n<ul class=\"wp-block-list\">\n<li>C\u00f3digo de Processo Penal e suas disposi\u00e7\u00f5es preliminares.<\/li>\n\n\n\n<li>Inqu\u00e9rito policial, a\u00e7\u00e3o penal, compet\u00eancia e provas.<\/li>\n\n\n\n<li>Pris\u00e3o e liberdade provis\u00f3ria, processo e julgamento dos crimes de responsabilidade.<\/li>\n\n\n\n<li>Habeas corpus e jurisprud\u00eancia dos tribunais superiores.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>Direito Penal Militar:<\/strong>\n<ul class=\"wp-block-list\">\n<li>Aplica\u00e7\u00e3o da lei penal militar, imputabilidade, concurso de agentes e penas.<\/li>\n\n\n\n<li>Crimes militares em tempo de paz e sua tipifica\u00e7\u00e3o.<\/li>\n\n\n\n<li>Jurisprud\u00eancia dos tribunais superiores.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>Direito Processual Penal Militar:<\/strong>\n<ul class=\"wp-block-list\">\n<li>Processo penal militar, pol\u00edcia judici\u00e1ria militar, inqu\u00e9rito policial militar e a\u00e7\u00e3o penal militar.<\/li>\n\n\n\n<li>Jurisprud\u00eancia dos tribunais superiores.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-cargo-2-tecnico-do-mpu-especialidade-administracao\">Cargo 2: T\u00e9cnico do MPU \u2013 Especialidade: Administra\u00e7\u00e3o<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>No\u00e7\u00f5es de Direito Administrativo:<\/strong>\n<ul class=\"wp-block-list\">\n<li>Organiza\u00e7\u00e3o administrativa, ato administrativo, processo administrativo, agentes p\u00fablicos, poderes administrativos, controle e responsabilidade da administra\u00e7\u00e3o.<\/li>\n\n\n\n<li>Lei n\u00ba 8.112\/1990 e suas altera\u00e7\u00f5es, Lei n\u00ba 8.666\/1993 e suas altera\u00e7\u00f5es.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>No\u00e7\u00f5es de Direito Constitucional:<\/strong>\n<ul class=\"wp-block-list\">\n<li>Constitui\u00e7\u00e3o de 1988, princ\u00edpios fundamentais, direitos e garantias fundamentais, organiza\u00e7\u00e3o do Estado e administra\u00e7\u00e3o p\u00fablica.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>No\u00e7\u00f5es de Administra\u00e7\u00e3o:<\/strong>\n<ul class=\"wp-block-list\">\n<li>Abordagens cl\u00e1ssica, burocr\u00e1tica e sist\u00eamica da administra\u00e7\u00e3o, evolu\u00e7\u00e3o da administra\u00e7\u00e3o p\u00fablica no Brasil, gest\u00e3o p\u00fablica e privada.<\/li>\n\n\n\n<li>Gest\u00e3o de pessoas e gest\u00e3o organizacional: planejamento estrat\u00e9gico, indicadores de desempenho e ferramentas de an\u00e1lise de cen\u00e1rio.<\/li>\n\n\n\n<li>Gest\u00e3o de projetos e solu\u00e7\u00e3o de problemas.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>No\u00e7\u00f5es de Arquivologia:<\/strong>\n<ul class=\"wp-block-list\">\n<li>Arquiv\u00edstica: princ\u00edpios, conceitos, gest\u00e3o de documentos, protocolos, classifica\u00e7\u00e3o e ordena\u00e7\u00e3o de documentos.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>No\u00e7\u00f5es de Administra\u00e7\u00e3o Or\u00e7ament\u00e1ria, Financeira e Or\u00e7amento P\u00fablico:<\/strong>\n<ul class=\"wp-block-list\">\n<li>Or\u00e7amento p\u00fablico, ciclos or\u00e7ament\u00e1rio, receita e despesa p\u00fablica, Lei de Responsabilidade Fiscal.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<p class=\"has-text-align-center\"><em>Confira mais detalhes do concurso <a href=\"https:\/\/www.mpu.mp.br\/\" target=\"_blank\" rel=\"noreferrer noopener\">MPU<\/a>, al\u00e9m das disciplinas exigidas no edital, atrav\u00e9s do link abaixo:<\/em><\/p>\n\n\n\n<h3 class=\"wp-block-heading has-text-align-center has-light-green-cyan-to-vivid-green-cyan-gradient-background has-background has-medium-font-size\">Saiba mais: <a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-mpu\/\" target=\"_blank\" rel=\"noreferrer noopener\">concurso MPU<\/a><\/h3>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"h-quer-saber-tudo-sobre-concursos-previstos-confira-nossos-artigos\">Quer saber tudo sobre concursos previstos?<br \/>Confira nossos artigos!<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos abertos<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2025\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Concursos 2025<\/a><\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"assinatura-e-cursos\">Que tal estudar para o concurso MPU?<\/h2>\n\n\n\n<div class=\"container\" id=\"boxes\">\n  <div class=\"row\">\n\n    <div class=\"col-sm\">\n      <div class=\"banner-tribunal\" id=\"box-assinatura\">\n        <h3 class=\"titulo-assinatura\">Curso MPU<\/h3>\n        <p class=\"subtitulo-assinatura\">Conhe\u00e7a os cursos<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/cursosPorConcurso\/mpu-ministerio-publico-da-uniao\/\" role=\"button\" rel=\"noopener noreferrer\">Conhe\u00e7a mais<\/a>\n        <\/div>\n      <\/div>\n      <p class=\"texto-auxiliar\">Prepare-se com o melhor material e com quem mais aprova em Concursos P\u00fablicos em todo o pa\u00eds.<\/p>\n    <\/div>\n\n  <\/div>\n<\/div>\n\n\n\n<div class=\"container\" id=\"boxes\">\n  <div class=\"row\">\n\n    <div class=\"col-sm\">\n      <div class=\"estrategia\" id=\"box-assinatura\">\n        <h3 class=\"titulo-assinatura\">Assinatura Concursos<\/h3>\n        <p class=\"subtitulo-assinatura\">Assinatura de 1 Ano ou 2 Anos<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/assinaturas\/\" role=\"button\" rel=\"noopener noreferrer\">ASSINE AGORA<\/a>\n        <\/div>\n      <\/div>\n     \n    <\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>O concurso do\u00a0Minist\u00e9rio P\u00fablico da Uni\u00e3o\u00a0(MPU) est\u00e1 com as inscri\u00e7\u00f5es abertas e oferta 172 vagas imediatas,\u00a0e n\u00f3s preparamos este artigo com as principais disciplinas exigidas no edital! As vagas dispon\u00edveis exigem n\u00edvel superior de escolaridade, com sal\u00e1rios iniciais que variam de R$ 8.529,67 a R$ 13.994,80, al\u00e9m de benef\u00edcios. Os interessados podem se inscrever no [&hellip;]<\/p>\n","protected":false},"author":2988,"featured_media":832731,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"news","footnotes":""},"categories":[1984,220219],"tags":[],"tax_estado":[219964,219965,219966,219967,219968,219969,219963,219970,219971,219972,219973,219974,219975,219976,219977,219978,219979,219980,219981,219982,219983,219984,219985,219986,219987,219988,219989,219990],"class_list":["post-1518064","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tribunais","category-noticias","tax_estado-ac","tax_estado-al","tax_estado-am","tax_estado-ap","tax_estado-ba","tax_estado-ce","tax_estado-concursos-federais","tax_estado-df","tax_estado-es","tax_estado-go","tax_estado-ma","tax_estado-mg","tax_estado-ms","tax_estado-mt","tax_estado-pa","tax_estado-pb","tax_estado-pe","tax_estado-pi","tax_estado-pr","tax_estado-rj","tax_estado-rn","tax_estado-ro","tax_estado-rr","tax_estado-rs","tax_estado-sc","tax_estado-se","tax_estado-sp","tax_estado-to"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Quais as disciplinas exigidas na prova objetiva do edital MPU 2025?<\/title>\n<meta name=\"description\" content=\"O Concurso MPU est\u00e1 com as inscri\u00e7\u00f5es abertas, prepare-se para o certame conferindo quais as disciplinas exigidas no edital!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-mpu-disciplinas-exigidas\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quais as disciplinas exigidas na prova objetiva do edital MPU 2025?\" \/>\n<meta property=\"og:description\" content=\"O Concurso MPU est\u00e1 com as inscri\u00e7\u00f5es abertas, prepare-se para o certame conferindo quais as disciplinas exigidas no edital!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-mpu-disciplinas-exigidas\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-17T00:28:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-17T12:25:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/05\/10170827\/mpu.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"432\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Priscila Bonomi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Priscila Bonomi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"13 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-mpu-disciplinas-exigidas\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-mpu-disciplinas-exigidas\/\"},\"author\":{\"name\":\"Priscila Bonomi\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/873d732f347f1d3c1ca596f53fbf3daf\"},\"headline\":\"Quais as disciplinas exigidas na prova objetiva do edital MPU 2025?\",\"datePublished\":\"2025-01-17T00:28:24+00:00\",\"dateModified\":\"2025-01-17T12:25:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-mpu-disciplinas-exigidas\/\"},\"wordCount\":2565,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-mpu-disciplinas-exigidas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/05\/10170827\/mpu.jpeg\",\"articleSection\":[\"Tribunais\",\"\u00daltimas not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-mpu-disciplinas-exigidas\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-mpu-disciplinas-exigidas\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-mpu-disciplinas-exigidas\/\",\"name\":\"Quais as disciplinas exigidas na prova objetiva do edital MPU 2025?\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-mpu-disciplinas-exigidas\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-mpu-disciplinas-exigidas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/05\/10170827\/mpu.jpeg\",\"datePublished\":\"2025-01-17T00:28:24+00:00\",\"dateModified\":\"2025-01-17T12:25:10+00:00\",\"description\":\"O Concurso MPU est\u00e1 com as inscri\u00e7\u00f5es abertas, prepare-se para o certame conferindo quais as disciplinas exigidas no edital!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-mpu-disciplinas-exigidas\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-mpu-disciplinas-exigidas\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-mpu-disciplinas-exigidas\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/05\/10170827\/mpu.jpeg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/05\/10170827\/mpu.jpeg\",\"width\":768,\"height\":432,\"caption\":\"teletrabalho servidores MPU\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-mpu-disciplinas-exigidas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Quais as disciplinas exigidas na prova objetiva do edital MPU 2025?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/873d732f347f1d3c1ca596f53fbf3daf\",\"name\":\"Priscila Bonomi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/aecb998f4787e93c4b9adc7c1376c42f00e7b0946d7a7dc1f4ea738ab2665187?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/aecb998f4787e93c4b9adc7c1376c42f00e7b0946d7a7dc1f4ea738ab2665187?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/aecb998f4787e93c4b9adc7c1376c42f00e7b0946d7a7dc1f4ea738ab2665187?s=96&d=mm&r=g\",\"caption\":\"Priscila Bonomi\"},\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/priscila-bonomiestrategia-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Quais as disciplinas exigidas na prova objetiva do edital MPU 2025?","description":"O Concurso MPU est\u00e1 com as inscri\u00e7\u00f5es abertas, prepare-se para o certame conferindo quais as disciplinas exigidas no edital!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-mpu-disciplinas-exigidas\/","og_locale":"pt_BR","og_type":"article","og_title":"Quais as disciplinas exigidas na prova objetiva do edital MPU 2025?","og_description":"O Concurso MPU est\u00e1 com as inscri\u00e7\u00f5es abertas, prepare-se para o certame conferindo quais as disciplinas exigidas no edital!","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-mpu-disciplinas-exigidas\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2025-01-17T00:28:24+00:00","article_modified_time":"2025-01-17T12:25:10+00:00","og_image":[{"width":768,"height":432,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/05\/10170827\/mpu.jpeg","type":"image\/jpeg"}],"author":"Priscila Bonomi","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Priscila Bonomi","Est. tempo de leitura":"13 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-mpu-disciplinas-exigidas\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-mpu-disciplinas-exigidas\/"},"author":{"name":"Priscila Bonomi","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/873d732f347f1d3c1ca596f53fbf3daf"},"headline":"Quais as disciplinas exigidas na prova objetiva do edital MPU 2025?","datePublished":"2025-01-17T00:28:24+00:00","dateModified":"2025-01-17T12:25:10+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-mpu-disciplinas-exigidas\/"},"wordCount":2565,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-mpu-disciplinas-exigidas\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/05\/10170827\/mpu.jpeg","articleSection":["Tribunais","\u00daltimas not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-mpu-disciplinas-exigidas\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-mpu-disciplinas-exigidas\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-mpu-disciplinas-exigidas\/","name":"Quais as disciplinas exigidas na prova objetiva do edital MPU 2025?","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-mpu-disciplinas-exigidas\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-mpu-disciplinas-exigidas\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/05\/10170827\/mpu.jpeg","datePublished":"2025-01-17T00:28:24+00:00","dateModified":"2025-01-17T12:25:10+00:00","description":"O Concurso MPU est\u00e1 com as inscri\u00e7\u00f5es abertas, prepare-se para o certame conferindo quais as disciplinas exigidas no edital!","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-mpu-disciplinas-exigidas\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-mpu-disciplinas-exigidas\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-mpu-disciplinas-exigidas\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/05\/10170827\/mpu.jpeg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/05\/10170827\/mpu.jpeg","width":768,"height":432,"caption":"teletrabalho servidores MPU"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-mpu-disciplinas-exigidas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Quais as disciplinas exigidas na prova objetiva do edital MPU 2025?"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/873d732f347f1d3c1ca596f53fbf3daf","name":"Priscila Bonomi","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/aecb998f4787e93c4b9adc7c1376c42f00e7b0946d7a7dc1f4ea738ab2665187?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/aecb998f4787e93c4b9adc7c1376c42f00e7b0946d7a7dc1f4ea738ab2665187?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/aecb998f4787e93c4b9adc7c1376c42f00e7b0946d7a7dc1f4ea738ab2665187?s=96&d=mm&r=g","caption":"Priscila Bonomi"},"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/priscila-bonomiestrategia-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1518064","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/2988"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1518064"}],"version-history":[{"count":34,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1518064\/revisions"}],"predecessor-version":[{"id":1518291,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1518064\/revisions\/1518291"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/832731"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1518064"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1518064"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1518064"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1518064"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}