{"id":1515720,"date":"2025-02-08T08:38:00","date_gmt":"2025-02-08T11:38:00","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=1515720"},"modified":"2025-01-12T07:51:26","modified_gmt":"2025-01-12T10:51:26","slug":"agentes-publicos-concurso-trt-10","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/agentes-publicos-concurso-trt-10\/","title":{"rendered":"Agentes P\u00fablicos para o TRT 10"},"content":{"rendered":"\n<p>Ol\u00e1, pessoal, tudo bem? Hoje, convidamos voc\u00ea para uma revis\u00e3o sobre os <strong>agentes p\u00fablicos<\/strong>.<\/p>\n\n\n\n<p>Existe boa probabilidade de cair pelo menos uma quest\u00e3o desse assunto na prova do <strong><a href=\"https:\/\/www.cebraspe.org.br\/tribunal-regional-do-trabalho-da-10a-regiao-abre-oportunidades-para-analista-e-tecnico-judiciario\/\" target=\"_blank\" rel=\"noreferrer noopener\">TRT 10<\/a> <\/strong>e, por isso, vale a pena dedicar alguns minutos para revisitar o tema.<\/p>\n\n\n\n<p>Vamos l\u00e1!<\/p>\n\n\n\n<p>Agente p\u00fablico \u00e9 o indiv\u00edduo que <strong>realiza alguma atividade p\u00fablica<\/strong>, a qualquer t\u00edtulo, ainda que temporariamente e sem remunera\u00e7\u00e3o.<\/p>\n\n\n\n<p>Segundo a <a href=\"https:\/\/www.planalto.gov.br\/ccivil_03\/leis\/L8429compilada.htm\" target=\"_blank\" rel=\"noreferrer noopener\">Lei n\u00ba 8.429\/1992<\/a>, consideram-se agente p\u00fablico o agente pol\u00edtico, o servidor p\u00fablico e todo aquele que exerce, <strong>ainda que transitoriamente<\/strong> <strong>ou sem remunera\u00e7\u00e3o<\/strong>, por elei\u00e7\u00e3o, nomea\u00e7\u00e3o, designa\u00e7\u00e3o, contrata\u00e7\u00e3o ou qualquer outra forma de investidura ou v\u00ednculo, mandato, cargo, emprego ou fun\u00e7\u00e3o na administra\u00e7\u00e3o p\u00fablica.<\/p>\n\n\n\n<p>Nesse sentido, vejamos os seguintes ensinamentos:<\/p>\n\n\n\n<p class=\"has-pale-cyan-blue-background-color has-background\"><em>&#8220;Assim, podemos dizer que <\/em><strong><em>s\u00e3o agentes p\u00fablicos as pessoas f\u00edsicas que exercem atribui\u00e7\u00f5es pol\u00edticas,<\/em><\/strong><em> como o Presidente da Rep\u00fablica e os parlamentares; <\/em><strong><em>as pessoas f\u00edsicas que exercem as atribui\u00e7\u00f5es administrativas<\/em><\/strong><em> no seu dia a dia, como atividade profissional, a exemplo dos servidores efetivos e comissionados, dos empregados p\u00fablicos, dos agentes tempor\u00e1rios e dos militares. Tamb\u00e9m se inserem nesse conceito amplo<\/em><strong><em> as pessoas que atuam em entidades privadas, mas que prestam servi\u00e7os mediante delega\u00e7\u00e3o do Estado<\/em><\/strong><em>, como um motorista de uma concession\u00e1ria de servi\u00e7o p\u00fablico, enquanto presta o servi\u00e7o de transporte \u00e0 popula\u00e7\u00e3o.&#8221; (ALMEIDA, Herbert. TCDF (Auditor de Controle Externo) Direito Administrativo &#8211; 2023 (Pr\u00e9-Edital). Estrat\u00e9gia Concursos, aula 14, p. 3)<\/em><\/p>\n\n\n\n<p>Resumindo, s\u00e3o considerados agentes p\u00fablicos quaisquer pessoas f\u00edsicas que exer\u00e7am alguma atividade estatal, <strong>independentemente <\/strong>do seu v\u00ednculo com o poder p\u00fablico.<\/p>\n\n\n\n<p>A doutrina classifica os agentes p\u00fablicos em:<\/p>\n\n\n\n<p>&#8211; <strong>Agentes pol\u00edticos<\/strong>: S\u00e3o aqueles que exercem atribui\u00e7\u00f5es do alto escal\u00e3o da Administra\u00e7\u00e3o P\u00fablica, como Chefes de Poder, Ministros e Secret\u00e1rios de Estado, Ju\u00edzes e membros do Minist\u00e9rio P\u00fablico etc.<\/p>\n\n\n\n<p>&#8211; <strong>Agentes administrativos<\/strong>: S\u00e3o os servidores, os empregados p\u00fablicos e os agentes tempor\u00e1rios, os quais exercem atividades administrativas remuneradas de car\u00e1ter profissional.&nbsp;<\/p>\n\n\n\n<p>Esses agentes est\u00e3o sujeitos a hierarquia funcional bem como a um regime jur\u00eddico pr\u00f3prio.<\/p>\n\n\n\n<p>&#8211; <strong>Agentes honor\u00edficos<\/strong>: S\u00e3o indiv\u00edduos sem v\u00ednculo empregat\u00edcio com a Administra\u00e7\u00e3o P\u00fablica, os quais exercem suas atribui\u00e7\u00f5es de forma tempor\u00e1ria e sem remunera\u00e7\u00e3o, a exemplo dos mes\u00e1rios nas elei\u00e7\u00f5es.<\/p>\n\n\n\n<p>&#8211; <strong>Agentes delegados<\/strong>: S\u00e3o agentes que recebem delega\u00e7\u00e3o da Administra\u00e7\u00e3o P\u00fablica para o desempenho de atribui\u00e7\u00f5es de interesse p\u00fablico (servi\u00e7os p\u00fablicos).&nbsp;<\/p>\n\n\n\n<p>Ex.: Agentes de concession\u00e1rias e permission\u00e1rias de servi\u00e7os p\u00fablicos.<\/p>\n\n\n\n<p>&#8211; <strong>Agentes credenciados<\/strong>: S\u00e3o aqueles que recebem a incumb\u00eancia de representar o poder p\u00fablico em eventos ou cerim\u00f4nias, mediante remunera\u00e7\u00e3o.&nbsp;<\/p>\n\n\n\n<p>Ex.: Atletas ol\u00edmpicos.<\/p>\n\n\n\n<p>&#8211; <strong>Agentes de fato<\/strong>: S\u00e3o particulares sem v\u00ednculo formal ou leg\u00edtimo com a Administra\u00e7\u00e3o P\u00fablica, que desempenham alguma fun\u00e7\u00e3o p\u00fablica, em situa\u00e7\u00f5es especiais.&nbsp;<\/p>\n\n\n\n<p>Eles s\u00e3o classificados como <strong>agentes necess\u00e1rios e agentes putativos<\/strong>.<\/p>\n\n\n\n<p>Os <strong>agentes necess\u00e1rios<\/strong> correspondem aos particulares que acabam colaborando de forma volunt\u00e1ria em casos de desastres naturais e na presta\u00e7\u00e3o de socorro.&nbsp;<\/p>\n\n\n\n<p>Ex.: Moradores que atuam no resgate de pessoas inundadas em um bairro afetado por enchentes.<\/p>\n\n\n\n<p>J\u00e1 os <strong>agentes putativos<\/strong> s\u00e3o pessoas que executam atividades p\u00fablicas sem terem sido investidos legalmente nos respectivos cargos.&nbsp;<\/p>\n\n\n\n<p>Como exemplos, podemos citar um servidor que pratica um ato fora da esfera de suas compet\u00eancias, ou agentes contratados indevidamente.<\/p>\n\n\n\n<p>Importa ressaltar que os atos praticados pelos agentes putativos <strong>produzem efeitos externos<\/strong> em rela\u00e7\u00e3o a terceiros de boa-f\u00e9.<\/p>\n\n\n\n<p>Esse caso espec\u00edfico traduz o que a doutrina chama de <strong>teoria da apar\u00eancia<\/strong>, uma vez que a investidura dos agentes que praticam os atos da administra\u00e7\u00e3o p\u00fablica \u00e9<strong> presumida<\/strong> pelos administrados.<\/p>\n\n\n\n<p>Al\u00e9m disso, a despeito do seu v\u00ednculo irregular com o poder p\u00fablico, tais agentes <strong>fazem jus a remunera\u00e7\u00e3o<\/strong>, cuja devolu\u00e7\u00e3o n\u00e3o se pode exigir, sob pena de enriquecimento il\u00edcito do Estado.<\/p>\n\n\n\n<p>&#8211; <strong>Militares<\/strong>: S\u00e3o agentes integrantes das For\u00e7as Armadas (Marinha, Ex\u00e9rcito ou Aeron\u00e1utica) e t\u00eam por miss\u00e3o assegurar a defesa nacional.<\/p>\n\n\n\n<p>As For\u00e7as Armadas s\u00e3o institui\u00e7\u00f5es permanentes subordinadas ao Presidente da Rep\u00fablica e t\u00eam como <strong>princ\u00edpios b\u00e1sicos a hierarquia e a disciplina<\/strong>.<\/p>\n\n\n\n<p>Sobre o assunto, vale acrescentar uma contribui\u00e7\u00e3o de Pedro Lenza:<\/p>\n\n\n\n<p class=\"has-pale-cyan-blue-background-color has-background\"><em>&#8220;As For\u00e7as Armadas<\/em><strong><em> organizam-se com base na hierarquia e na disciplina, sob a autoridade e comando supremos do Presidente da Rep\u00fablica<\/em><\/strong><em>, que tem por atribui\u00e7\u00f5es nomear os comandantes da Marinha, do Ex\u00e9rcito e da Aeron\u00e1utica, promover seus oficiais-generais e nome\u00e1-los para os cargos que lhes s\u00e3o privativos&#8221; (LENZA, Pedro. Direito constitucional\/Pedro Lenza. \u2013 25. ed. \u2013 S\u00e3o Paulo: Saraiva Educa\u00e7\u00e3o, 2021. (Cole\u00e7\u00e3o Esquematizado\u00ae), p. 1544)<\/em><\/p>\n\n\n\n<p>Um ponto bastante explorado em provas \u00e9 que <strong>os agentes militares n\u00e3o possuem direito de greve<\/strong> e n\u00e3o podem se filiar a partidos pol\u00edticos enquanto estiverem no servi\u00e7o ativo.\u00a0<\/p>\n\n\n\n<p>Ficamos por aqui\u2026<\/p>\n\n\n\n<p>Para se aprofundar no assunto, estude com nossos <a href=\"https:\/\/www.estrategiaconcursos.com.br\/cursos\/concurso\/\">materiais em pdf e em v\u00eddeo aulas<\/a>, e aumente as suas chances de aprova\u00e7\u00e3o.<\/p>\n\n\n\n<p>Bons estudos e at\u00e9 a pr\u00f3xima!<\/p>\n\n\n\n<p>Nilson Assis<\/p>\n\n\n\n<p>Analista Legislativo do Senado Federal<\/p>\n\n\n\n<p>@nsassis.concursos<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2025\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos 2025<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-federais-2023\/\">Concursos federais<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/cj.estrategia.com\/portal\/concursos-abertos-carreiras-juridicas\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos abertos Carreiras Jur\u00eddicas<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\">Concursos abertos<\/a><\/li>\n<\/ul>\n\n\n\n<p><strong>Refer\u00eancias bibliogr\u00e1ficas<\/strong><\/p>\n\n\n\n<p>ALMEIDA, Herbert. <strong>TCDF (Auditor de Controle Externo) Direito Administrativo &#8211; 2023 (Pr\u00e9-Edital)<\/strong>. Estrat\u00e9gia Concursos, aula 14.<\/p>\n\n\n\n<p>BRASIL. [Constitui\u00e7\u00e3o (1988)]. <strong>Constitui\u00e7\u00e3o da Rep\u00fablica Federativa do Brasil de 1988<\/strong>. Bras\u00edlia, DF: Presid\u00eancia da Rep\u00fablica. Dispon\u00edvel em:&nbsp;<\/p>\n\n\n\n<p><a href=\"https:\/\/www.planalto.gov.br\/ccivil_03\/constituicao\/constituicaocompilado.htm\">https:\/\/www.planalto.gov.br\/ccivil_03\/constituicao\/constituicaocompilado.htm<\/a>. Acesso em: 04 Jan. 2025.<\/p>\n\n\n\n<p>BRASIL. Lei n\u00ba 8.429, de 02 de junho de 1992. <strong>Disp\u00f5e sobre as san\u00e7\u00f5es aplic\u00e1veis em virtude da pr\u00e1tica de atos de improbidade administrativa, de que trata o \u00a7 4\u00ba do art. 37 da Constitui\u00e7\u00e3o Federal; e d\u00e1 outras provid\u00eancias<\/strong>.\u00a0Dispon\u00edvel em: https:\/\/www.planalto.gov.br\/ccivil_03\/leis\/L8429compilada.htm. Acesso em: 11 Jan. 2025.<\/p>\n\n\n\n<p>LENZA, Pedro.<strong> Direito constitucional\/Pedro Lenza<\/strong>. \u2013 25. ed. \u2013 S\u00e3o Paulo: Saraiva Educa\u00e7\u00e3o, 2021. (Cole\u00e7\u00e3o Esquematizado\u00ae)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ol\u00e1, pessoal, tudo bem? Hoje, convidamos voc\u00ea para uma revis\u00e3o sobre os agentes p\u00fablicos. Existe boa probabilidade de cair pelo menos uma quest\u00e3o desse assunto na prova do TRT 10 e, por isso, vale a pena dedicar alguns minutos para revisitar o tema. Vamos l\u00e1! Agente p\u00fablico \u00e9 o indiv\u00edduo que realiza alguma atividade p\u00fablica, [&hellip;]<\/p>\n","protected":false},"author":2894,"featured_media":1515725,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1],"tags":[],"tax_estado":[219963],"class_list":["post-1515720","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cursos-e-concursos","tax_estado-concursos-federais"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Agentes P\u00fablicos para o TRT 10<\/title>\n<meta name=\"description\" content=\"Ol\u00e1, pessoal, tudo bem? Hoje, convidamos voc\u00ea para uma revis\u00e3o sobre os agentes p\u00fablicos. Vale a pena dedicar alguns minutos com esse tema.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/agentes-publicos-concurso-trt-10\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Agentes P\u00fablicos para o TRT 10\" \/>\n<meta property=\"og:description\" content=\"Ol\u00e1, pessoal, tudo bem? Hoje, convidamos voc\u00ea para uma revis\u00e3o sobre os agentes p\u00fablicos. Vale a pena dedicar alguns minutos com esse tema.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/agentes-publicos-concurso-trt-10\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-08T11:38:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/01\/11154534\/agentes.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"169\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nilson Silva de Assis\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nilson Silva de Assis\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/agentes-publicos-concurso-trt-10\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/agentes-publicos-concurso-trt-10\/\"},\"author\":{\"name\":\"Nilson Silva de Assis\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/2602628e49ec93d5f782b149f91603ab\"},\"headline\":\"Agentes P\u00fablicos para o TRT 10\",\"datePublished\":\"2025-02-08T11:38:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/agentes-publicos-concurso-trt-10\/\"},\"wordCount\":1064,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/agentes-publicos-concurso-trt-10\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/01\/11154534\/agentes.jpg\",\"articleSection\":[\"Concursos P\u00fablicos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/agentes-publicos-concurso-trt-10\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/agentes-publicos-concurso-trt-10\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/agentes-publicos-concurso-trt-10\/\",\"name\":\"Agentes P\u00fablicos para o TRT 10\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/agentes-publicos-concurso-trt-10\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/agentes-publicos-concurso-trt-10\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/01\/11154534\/agentes.jpg\",\"datePublished\":\"2025-02-08T11:38:00+00:00\",\"description\":\"Ol\u00e1, pessoal, tudo bem? Hoje, convidamos voc\u00ea para uma revis\u00e3o sobre os agentes p\u00fablicos. Vale a pena dedicar alguns minutos com esse tema.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/agentes-publicos-concurso-trt-10\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/agentes-publicos-concurso-trt-10\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/agentes-publicos-concurso-trt-10\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/01\/11154534\/agentes.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/01\/11154534\/agentes.jpg\",\"width\":300,\"height\":169,\"caption\":\"agentes\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/agentes-publicos-concurso-trt-10\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Agentes P\u00fablicos para o TRT 10\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/2602628e49ec93d5f782b149f91603ab\",\"name\":\"Nilson Silva de Assis\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/cdec26ae7042f64d4ddcb70bcf78a4fcbc02661bfa30a7ce3d8bf515b625a75a?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cdec26ae7042f64d4ddcb70bcf78a4fcbc02661bfa30a7ce3d8bf515b625a75a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cdec26ae7042f64d4ddcb70bcf78a4fcbc02661bfa30a7ce3d8bf515b625a75a?s=96&d=mm&r=g\",\"caption\":\"Nilson Silva de Assis\"},\"description\":\"Atualmente \u00e9 Analista Legislativo do Senado Federal e Professor do Estrat\u00e9gia Concursos. Suas principais aprova\u00e7\u00f5es: Analista Legislativo do Senado Federal; Auditor Federal de Finan\u00e7as e Controle da CGU; Auditor-Fiscal da Receita Estadual da SEFAZ ES; T\u00e9cnico Fazend\u00e1rio do ISS Manaus; Assistente Executivo em Metrologia e Qualidade do Inmetro; Agente Fazend\u00e1rio do ISS Niter\u00f3i\/RJ; Assistente Administrativo da Prefeitura do Rio (RioSa\u00fade); Assistente Administrativo da Secretaria de Administra\u00e7\u00e3o do Munic\u00edpio do RJ.\",\"sameAs\":[\"https:\/\/www.instagram.com\/nilsonassis.concursos\/\",\"kedin.com\/in\/nilson-assis-954132295\/\"],\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/nilson-sdeassisgmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Agentes P\u00fablicos para o TRT 10","description":"Ol\u00e1, pessoal, tudo bem? Hoje, convidamos voc\u00ea para uma revis\u00e3o sobre os agentes p\u00fablicos. Vale a pena dedicar alguns minutos com esse tema.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/agentes-publicos-concurso-trt-10\/","og_locale":"pt_BR","og_type":"article","og_title":"Agentes P\u00fablicos para o TRT 10","og_description":"Ol\u00e1, pessoal, tudo bem? Hoje, convidamos voc\u00ea para uma revis\u00e3o sobre os agentes p\u00fablicos. Vale a pena dedicar alguns minutos com esse tema.","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/agentes-publicos-concurso-trt-10\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2025-02-08T11:38:00+00:00","og_image":[{"width":300,"height":169,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/01\/11154534\/agentes.jpg","type":"image\/jpeg"}],"author":"Nilson Silva de Assis","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Nilson Silva de Assis","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/agentes-publicos-concurso-trt-10\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/agentes-publicos-concurso-trt-10\/"},"author":{"name":"Nilson Silva de Assis","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/2602628e49ec93d5f782b149f91603ab"},"headline":"Agentes P\u00fablicos para o TRT 10","datePublished":"2025-02-08T11:38:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/agentes-publicos-concurso-trt-10\/"},"wordCount":1064,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/agentes-publicos-concurso-trt-10\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/01\/11154534\/agentes.jpg","articleSection":["Concursos P\u00fablicos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/agentes-publicos-concurso-trt-10\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/agentes-publicos-concurso-trt-10\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/agentes-publicos-concurso-trt-10\/","name":"Agentes P\u00fablicos para o TRT 10","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/agentes-publicos-concurso-trt-10\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/agentes-publicos-concurso-trt-10\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/01\/11154534\/agentes.jpg","datePublished":"2025-02-08T11:38:00+00:00","description":"Ol\u00e1, pessoal, tudo bem? Hoje, convidamos voc\u00ea para uma revis\u00e3o sobre os agentes p\u00fablicos. Vale a pena dedicar alguns minutos com esse tema.","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/agentes-publicos-concurso-trt-10\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/agentes-publicos-concurso-trt-10\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/agentes-publicos-concurso-trt-10\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/01\/11154534\/agentes.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/01\/11154534\/agentes.jpg","width":300,"height":169,"caption":"agentes"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/agentes-publicos-concurso-trt-10\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Agentes P\u00fablicos para o TRT 10"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/2602628e49ec93d5f782b149f91603ab","name":"Nilson Silva de Assis","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/cdec26ae7042f64d4ddcb70bcf78a4fcbc02661bfa30a7ce3d8bf515b625a75a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cdec26ae7042f64d4ddcb70bcf78a4fcbc02661bfa30a7ce3d8bf515b625a75a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cdec26ae7042f64d4ddcb70bcf78a4fcbc02661bfa30a7ce3d8bf515b625a75a?s=96&d=mm&r=g","caption":"Nilson Silva de Assis"},"description":"Atualmente \u00e9 Analista Legislativo do Senado Federal e Professor do Estrat\u00e9gia Concursos. Suas principais aprova\u00e7\u00f5es: Analista Legislativo do Senado Federal; Auditor Federal de Finan\u00e7as e Controle da CGU; Auditor-Fiscal da Receita Estadual da SEFAZ ES; T\u00e9cnico Fazend\u00e1rio do ISS Manaus; Assistente Executivo em Metrologia e Qualidade do Inmetro; Agente Fazend\u00e1rio do ISS Niter\u00f3i\/RJ; Assistente Administrativo da Prefeitura do Rio (RioSa\u00fade); Assistente Administrativo da Secretaria de Administra\u00e7\u00e3o do Munic\u00edpio do RJ.","sameAs":["https:\/\/www.instagram.com\/nilsonassis.concursos\/","kedin.com\/in\/nilson-assis-954132295\/"],"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/nilson-sdeassisgmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1515720","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/2894"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1515720"}],"version-history":[{"count":2,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1515720\/revisions"}],"predecessor-version":[{"id":1515728,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1515720\/revisions\/1515728"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/1515725"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1515720"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1515720"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1515720"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1515720"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}